{"id":50157,"count":1,"description":"","link":"https:\/\/exaudi.org\/it\/tag\/appello-al-disarmo\/","name":"appello al disarmo","slug":"appello-al-disarmo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>appello al disarmo &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/tag\/appello-al-disarmo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"appello al disarmo &#8211; Exaudi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/tag\/appello-al-disarmo\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/tag\\\/appello-al-disarmo\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/tag\\\/appello-al-disarmo\\\/\",\"name\":\"appello al disarmo &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/tag\\\/appello-al-disarmo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/tag\\\/appello-al-disarmo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"appello al disarmo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"appello al disarmo &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/tag\/appello-al-disarmo\/","og_locale":"it_IT","og_type":"article","og_title":"appello al disarmo &#8211; Exaudi","og_url":"https:\/\/exaudi.org\/it\/tag\/appello-al-disarmo\/","og_site_name":"Exaudi","twitter_card":"summary_large_image","twitter_site":"@Exaudi_News","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/exaudi.org\/it\/tag\/appello-al-disarmo\/","url":"https:\/\/exaudi.org\/it\/tag\/appello-al-disarmo\/","name":"appello al disarmo &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/tag\/appello-al-disarmo\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/tag\/appello-al-disarmo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"appello al disarmo"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags\/50157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts?tags=50157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}