{"id":9190,"date":"2021-04-01T10:50:58","date_gmt":"2021-04-01T08:50:58","guid":{"rendered":"https:\/\/exaudi.org\/?p=9190"},"modified":"2021-04-01T13:38:15","modified_gmt":"2021-04-01T11:38:15","slug":"lannuncio-del-vangelo-e-sempre-legato-alla-croce","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/","title":{"rendered":"L&#8217;annuncio del Vangelo \u00e8 sempre legato alla Croce"},"content":{"rendered":"<p>Quest\u2019anno la pandemia non ha impedito al Papa, contrariamente al 2020, di celebrare la Santa Messa Crismale nella Basilica Vaticana, anche se la partecipazione \u00e8 stata limitata ad alcuni Cardinali e Vescovi, ai Superiori della Segreteria di Stato e ai membri del Consiglio presbiteriale della Diocesi di Roma, che hanno concelebrato con il S. Padre. Nella liturgia della Messa Crismale che si celebra in questo giorno in tutte le chiese cattedrali (o in alcuni casi viene anticipata per convenienza alla sera del mercoled\u00ec), i sacerdoti rinnovano le promesse fatte al momento della Sacra ordinazione; quindi ha luogo la benedizione dell\u2019olio degli infermi, dell\u2019olio dei catecumeni e del crisma. Nella sua omelia il S. Padre ha fatto riferimento alla presenza della Croce nella vita di Ges\u00f9 e in quella dei sacerdoti chiamati ad annunciare il Vangelo. Ecco il testo diffuso dalla Sala Stampa vaticana:<\/p>\n<figure id=\"attachment_9212\" aria-describedby=\"caption-attachment-9212\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9212\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1-300x200.jpg\" alt=\"Misa Crismal Jueves Santo Homil\u00eda Papa\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1-300x200.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1-1024x683.jpg 1024w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1-768x512.jpg 768w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1-1536x1024.jpg 1536w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1-150x100.jpg 150w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1-696x464.jpg 696w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1-1068x712.jpg 1068w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1-630x420.jpg 630w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/010421-_1.jpg 1737w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-9212\" class=\"wp-caption-text\">\u00a9 Vatican Media<\/figcaption><\/figure>\n<p>Il Vangelo ci presenta un cambiamento di sentimenti nelle persone che ascoltano il Signore. Il cambiamento \u00e8 drammatico e ci mostra quanto la persecuzione e la Croce sono legate all\u2019annuncio del Vangelo. L\u2019ammirazione suscitata dalle parole di grazia che uscivano dalla bocca di Ges\u00f9 dur\u00f2 poco nell\u2019animo della gente di Nazaret. Una frase che qualcuno mormor\u00f2 a bassa voce si \u201cviralizz\u00f2\u201d insidiosamente: \u00abNon \u00e8 costui il figlio di Giuseppe?\u00bb.<\/p>\n<figure id=\"attachment_9225\" aria-describedby=\"caption-attachment-9225\" style=\"width: 200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9225\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-200x300.jpg 200w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-681x1024.jpg 681w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-768x1154.jpg 768w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-1022x1536.jpg 1022w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-150x225.jpg 150w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-300x451.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-696x1046.jpg 696w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-1068x1605.jpg 1068w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1-279x420.jpg 279w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-1.jpg 1179w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><figcaption id=\"caption-attachment-9225\" class=\"wp-caption-text\">\u00a9 Vatican Media<\/figcaption><\/figure>\n<p>Si tratta di una di quelle frasi ambigue che si lasciano cadere di passaggio. Uno la pu\u00f2 usare per esprimere con gioia: \u201cChe meraviglia che uno di origini cos\u00ec umili parli con questa autorit\u00e0!\u201d. E un altro pu\u00f2 usarla per dire con disprezzo: \u201cE questo da dove \u00e8 uscito? Chi crede di essere?\u201d. Se ci facciamo caso, la frase si ripete quando gli Apostoli, nel giorno di Pentecoste, pieni di Spirito Santo cominciano a predicare il Vangelo. Qualcuno disse: \u00abTutti costoro che parlano non sono forse Galilei?\u00bb. E mentre alcuni accolsero la Parola, altri li presero per ubriachi.<\/p>\n<h4>Germe di violenza<\/h4>\n<p>Formalmente sembrerebbe che si lasciasse aperta una scelta ma, se consideriamo gli effetti, in quel contesto concreto, queste parole contenevano un germe di violenza che si \u00e8 scatenata contro Ges\u00f9. Si tratta di una \u201cfrase trainante\u201d, come quando uno dice: \u201cQuesto \u00e8 troppo!\u201d e aggredisce l\u2019altro oppure se ne va. Il Signore, che a volte faceva silenzio o se ne andava all\u2019altra riva, questa volta non rinunci\u00f2 a commentare, ma smascher\u00f2 la logica maligna che si nascondeva sotto l\u2019apparenza di un semplice pettegolezzo di paese. \u00abVoi mi citerete questo proverbio: \u201cMedico, cura te stesso. Quanto abbiamo udito che accadde a Cafarnao, fallo anche qui, nella tua patria!\u00bb. \u201cCura te stesso\u2026\u201d. \u201cChe salvi se stesso\u201d. Qui sta il veleno! \u00c8 la stessa frase che seguir\u00e0 il Signore fino alla Croce: \u00abHa salvato altri! Salvi se stesso\u00bb; \u201ce salvi anche noi\u201d, aggiunger\u00e0 uno dei due ladroni.<\/p>\n<h4>Segno di contraddizione<\/h4>\n<p>Il Signore, come sempre, non dialoga con lo spirito maligno, risponde soltanto con la Scrittura. Nemmeno i profeti Elia ed Eliseo furono accettati dai loro compatrioti e invece lo furono da parte di una vedova fenicia e di un siro malato di lebbra: due stranieri, due persone di altra religione. I fatti colpiscono nel segno e provocano l\u2019effetto che aveva profetizzato Simeone, quell\u2019anziano carismatico: che Ges\u00f9 sarebbe stato \u00absegno di contraddizione\u00bb (semeion antilegomenon).<\/p>\n<p>La parola di Ges\u00f9 ha il potere di far uscire alla luce ci\u00f2 che uno porta nel cuore, che di solito \u00e8 un miscuglio, come il grano e la zizzania. E questo provoca combattimento spirituale. Vedendo i gesti di misericordia sovrabbondante del Signore e ascoltando le sue beatitudini e i \u201cguai a voi!\u201d del Vangelo, ci si trova obbligati a discernere e a scegliere.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9205\" style=\"text-align: center\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/cq5dam.thumbnail.cropped.1000.563-34-300x169.jpeg\" alt=\"Pope's Holy Thursday Chrism Mass - Copyright: Vatican Media\" width=\"300\" height=\"169\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/cq5dam.thumbnail.cropped.1000.563-34-300x169.jpeg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/cq5dam.thumbnail.cropped.1000.563-34-768x432.jpeg 768w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/cq5dam.thumbnail.cropped.1000.563-34-150x84.jpeg 150w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/cq5dam.thumbnail.cropped.1000.563-34-696x392.jpeg 696w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/cq5dam.thumbnail.cropped.1000.563-34-746x420.jpeg 746w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/cq5dam.thumbnail.cropped.1000.563-34.jpeg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>In questo caso la sua parola non fu accolta e questo fece s\u00ec che la folla, accesa d\u2019ira, tentasse di togliergli la vita. Ma non era ancora \u201cl\u2019ora\u201d e il Signore, ci dice il Vangelo, \u00abpassando in mezzo a loro, si mise in cammino\u00bb. Non era l\u2019ora, ma la velocit\u00e0 con cui si scatenarono la furia e la ferocia dell\u2019accanimento, capace di uccidere il Signore in quello stesso momento, ci mostra che sempre \u00e8 l\u2019ora. E questo \u00e8 ci\u00f2 che desidero condividere oggi con voi, cari sacerdoti: che l\u2019ora dell\u2019annuncio gioioso e l\u2019ora della persecuzione e della Croce vanno insieme.<\/p>\n<h4>Una Croce concreta<\/h4>\n<p>L\u2019annuncio del Vangelo \u00e8 sempre legato all\u2019abbraccio di una Croce concreta. La luce mite della Parola genera chiarezza nei cuori ben disposti e confusione e rifiuto in quelli che non lo sono. Questo lo vediamo costantemente nel Vangelo. Il seme buono seminato nel campo porta frutto \u2013 il cento, il sessanta, il trenta per uno \u2013, ma risveglia anche l\u2019invidia del nemico che ossessivamente si mette a seminare zizzania durante la notte. La tenerezza del padre misericordioso attrae irresistibilmente il figlio prodigo perch\u00e9 ritorni a casa, ma suscita anche l\u2019indignazione e il risentimento del figlio maggiore.<\/p>\n<h4>Gli esempi del Vangelo<\/h4>\n<p>La generosit\u00e0 del padrone della vigna \u00e8 motivo di gratitudine per gli operai dell\u2019ultima ora, ma \u00e8 anche motivo di aspri commenti per i primi, che si sentono offesi perch\u00e9 il loro padrone \u00e8 buono. La vicinanza di Ges\u00f9 che va a mangiare con i peccatori guadagna cuori come quello di Zaccheo, quello di Matteo, quello della Samaritana\u2026, ma provoca anche sentimenti di disprezzo in coloro che si credono giusti. La magnanimit\u00e0 di quell\u2019uomo che manda il suo figlio pensando che sar\u00e0 rispettato dai vignaioli, scatena tuttavia in essi una ferocia fuori da ogni misura: siamo di fronte al mistero dell\u2019iniquit\u00e0, che porta a uccidere il Giusto. Tutto questo, cari fratelli sacerdoti, ci fa vedere che l\u2019annuncio della Buona Notizia \u00e8 legato misteriosamente alla persecuzione e alla Croce.<\/p>\n<figure id=\"attachment_9228\" aria-describedby=\"caption-attachment-9228\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9228\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3-300x200.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3-1024x683.jpg 1024w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3-768x512.jpg 768w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3-1536x1024.jpg 1536w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3-150x100.jpg 150w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3-696x464.jpg 696w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3-1068x712.jpg 1068w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3-630x420.jpg 630w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-3.jpg 1737w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-9228\" class=\"wp-caption-text\">\u00a9 Vatican Media<\/figcaption><\/figure>\n<p>Sant\u2019Ignazio di Loyola, nella contemplazione della Nativit\u00e0 &#8211; scusatemi questa pubblicit\u00e0 di famiglia &#8211; in quella contemplazione della Nativit\u00e0 esprime questa verit\u00e0 evangelica quando ci fa osservare e considerare quello che fanno San Giuseppe e la Madonna: \u00abPer esempio, camminano e si danno da fare perch\u00e9 il Signore nasca in un\u2019estrema povert\u00e0 e, dopo aver tanto sofferto fame e sete, caldo e freddo, ingiurie e oltraggi, muoia in croce. E tutto questo per me. Poi \u2013 aggiunge Ignazio \u2013, riflettendo, ricavare qualche frutto spirituale\u00bb. La gioia della nascita del Signore, il dolore della Croce, la persecuzione.<\/p>\n<h4>La presenza costante della Croce<\/h4>\n<p>Che riflessione possiamo fare per trarre profitto per la nostra vita sacerdotale contemplando questa precoce presenza della Croce \u2013 dell\u2019incomprensione, del rifiuto, della persecuzione \u2013 all\u2019inizio e nel cuore stesso della predicazione evangelica? Mi vengono in mente due riflessioni. La prima: non meraviglia constatare che la Croce \u00e8 presente nella vita del Signore all\u2019inizio del suo ministero e perfino prima della sua nascita. \u00c8 presente gi\u00e0 nel primo turbamento di Maria davanti all\u2019annuncio dell\u2019Angelo; \u00e8 presente nell\u2019insonnia di Giuseppe al sentirsi obbligato ad abbandonare la sua promessa sposa; \u00e8 presente nella persecuzione di Erode e nei disagi che patisce la Santa Famiglia, uguali a quelle di tante famiglie che devono andare in esilio dalla propria patria.<\/p>\n<h4>La Croce non si negozia<\/h4>\n<p>Questa realt\u00e0 ci apre al mistero della Croce vissuta \u201cda prima\u201d. Ci fa comprendere che la Croce non \u00e8 un fatto a posteriori, occasionale, prodotto da una congiuntura nella vita del Signore. \u00c8 vero che tutti i crocifissori della storia fanno apparire la Croce come se fosse un danno collaterale, ma non \u00e8 cos\u00ec: la Croce non dipende dalle circostanze. Le grandi croci dell\u2019umanit\u00e0 e le piccole \u2013 diciamo cos\u00ec \u2013 croci nostre, di ognuno di noi non dipendono dalle circostanze. Perch\u00e9 il Signore ha abbracciato la Croce in tutta la sua integrit\u00e0? Perch\u00e9 Ges\u00f9 ha abbracciato la passione intera? Ha abbracciato il tradimento e l\u2019abbandono dei suoi amici gi\u00e0 dall\u2019ultima cena, ha accettato la detenzione illegale, il giudizio sommario, la sentenza sproporzionata, la cattiveria senza motivo degli schiaffi e degli sputi gratuiti\u2026<\/p>\n<p>Se le circostanze determinassero il potere salvifico della Croce, il Signore non avrebbe abbracciato tutto. Ma quando \u00e8 stata la sua ora, Egli ha abbracciato la Croce intera. Perch\u00e9 nella Croce non c\u2019\u00e8 ambiguit\u00e0! La Croce non si negozia.<\/p>\n<h4>Il veleno del maligno<\/h4>\n<p>La seconda riflessione \u00e8 la seguente. \u00c8 vero che c\u2019\u00e8 qualcosa della Croce che \u00e8 parte integrante della nostra condizione umana, del limite e della fragilit\u00e0. Per\u00f2 \u00e8 anche vero che c\u2019\u00e8 qualcosa di ci\u00f2 che accade nella Croce che non \u00e8 inerente alla nostra fragilit\u00e0, bens\u00ec \u00e8 il morso del serpente, il quale, vedendo il crocifisso inerme, lo morde e tenta di avvelenare e screditare tutta la sua opera. Morso che cerca di scandalizzare &#8211; questa \u00e8 un\u2019epoca degli scandali-, morso che cerca di immobilizzare e rendere sterile e insignificante ogni servizio e sacrificio d\u2019amore per gli altri. \u00c8 il veleno del maligno che continua a insistere: salva te stesso. E in questo morso, crudele e doloroso, che pretende di essere mortale, appare alla fine il trionfo di Dio.<\/p>\n<p>San Massimo il Confessore ci ha fatto vedere che con Ges\u00f9 crocifisso le cose si sono invertite: mordendo la carne del Signore, il demonio non lo ha avvelenato \u2013 in Lui ha trovato solo mansuetudine infinita e obbedienza alla volont\u00e0 del Padre \u2013 ma, al contrario, unita all\u2019amo della Croce ha inghiottito la Carne del Signore, che \u00e8 stata veleno per lui ed \u00e8 diventata per noi l\u2019antidoto che neutralizza il potere del maligno.<\/p>\n<h4>Abbracciare la Croce con Ges\u00f9<\/h4>\n<p>Queste sono le riflessioni. Chiediamo al Signore la grazia di trarre profitto da questi insegnamenti: c\u2019\u00e8 Croce nell\u2019annuncio del Vangelo, \u00e8 vero, ma \u00e8 una Croce che salva. Pacificata con il Sangue di Ges\u00f9, \u00e8 una Croce con la forza della vittoria di Cristo che sconfigge il male, che ci libera dal Maligno. Abbracciarla con Ges\u00f9 e come Lui, gi\u00e0 \u201cda prima\u201d di andare a predicare, ci permette di discernere e respingere il veleno dello scandalo con cui il demonio cercher\u00e0 di avvelenarci quando inaspettatamente sopraggiunger\u00e0 una croce nella nostra vita.<\/p>\n<h4>Non scandalizzarsi<\/h4>\n<p>\u00abNoi per\u00f2 non siamo di quelli che cedono (hypostoles)\u00bb dice l&#8217;autore della lettera agli Ebrei. \u00abNoi per\u00f2 non siamo di quelli che cedono\u00bb, \u00e8 il consiglio che ci d\u00e0: noi non ci scandalizziamo, perch\u00e9 non si \u00e8 scandalizzato Ges\u00f9 vedendo che il suo lieto annuncio di salvezza ai poveri non risuonava puro, ma in mezzo alle urla e alle minacce di quelli che non volevano udire la sua Parola o volevano ridurla a legalismi (moralisti, clericalisti&#8230;). Noi non ci scandalizziamo perch\u00e9 non si \u00e8 scandalizzato Ges\u00f9 dovendo guarire malati e liberare prigionieri in mezzo alle discussioni e alle controversie moralistiche, legalistiche, clericali che suscitava ogni volta che faceva il bene.<\/p>\n<figure id=\"attachment_9232\" aria-describedby=\"caption-attachment-9232\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9232\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4-300x200.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4-1024x682.jpg 1024w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4-768x511.jpg 768w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4-1536x1023.jpg 1536w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4-150x100.jpg 150w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4-696x463.jpg 696w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4-1068x711.jpg 1068w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4-631x420.jpg 631w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-4.jpg 1843w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-9232\" class=\"wp-caption-text\">\u00a9 Vatican Media<\/figcaption><\/figure>\n<p>Noi non ci scandalizziamo perch\u00e9 non si \u00e8 scandalizzato Ges\u00f9 dovendo dare la vista ai ciechi in mezzo a gente che chiudeva gli occhi per non vedere o guardava dall\u2019altra parte. Noi non ci scandalizziamo perch\u00e9 non si \u00e8 scandalizzato Ges\u00f9 del fatto che la sua predicazione dell\u2019anno di grazia del Signore \u2013 un anno che \u00e8 la storia intera \u2013 abbia provocato uno scandalo pubblico in ci\u00f2 che oggi occuperebbe appena la terza pagina di un giornale di provincia.<\/p>\n<p>E non ci scandalizziamo perch\u00e9 l\u2019annuncio del Vangelo non riceve la sua efficacia dalle nostre parole eloquenti, ma dalla forza della Croce. Dal modo in cui abbracciamo la Croce annunciando il Vangelo \u2013 con le opere e, se necessario, con le parole \u2013 si manifestano due cose: che le sofferenze procurateci dal Vangelo non sono nostre, ma \u00able sofferenze di Cristo in noi\u00bb e che \u00abnon annunciamo noi stessi, ma Cristo Ges\u00f9 Signore\u00bb e noi siamo \u00abservitori a causa di Ges\u00f9\u00bb.<\/p>\n<h4>Il ricordo dell\u2019aiuto divino<\/h4>\n<p>Desidero concludere con un ricordo. Una volta, in un momento molto buio della mia vita, chiedevo una grazia al Signore, che mi liberasse da una situazione dura e difficile. Un momento buio. Sono andato a predicare gli Esercizi spirituali ad alcune religiose e l\u2019ultimo giorno, com\u2019era abituale in quel tempo, si sono confessate. \u00c8 venuta una suora molto anziana, con gli occhi chiari, proprio luminosi. Era una donna di Dio.<\/p>\n<p>Allora ho sentito il desiderio di chiederle per me e le ho detto: \u201cSuora, come penitenza preghi per me, perch\u00e9 ho bisogno di una grazia. Se Lei la chiede al Signore, me la dar\u00e0 di sicuro\u201d. Lei ha fatto silenzio, ha aspettato un bel po\u2019, come se pregasse, e poi mi ha guardato e mi ha detto: \u201cCertamente il Signore Le dar\u00e0 la grazia, ma non si sbagli: la dar\u00e0 con il suo modo divino\u201d. Questo mi ha fatto tanto bene: sentire che il Signore ci d\u00e0 sempre quello che chiediamo, ma lo fa nel suo modo divino. Questo modo implica la croce. Non per masochismo, ma per amore, per amore sino alla fine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Papa Francesco ha celebrato la S. Messa Crismale a San Pietro<\/p>\n","protected":false},"author":17,"featured_media":9221,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[58,67,536,297],"tags":[1064,1369,1378,251,1302,706],"class_list":["post-9190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured-news","category-leone-xiv","category-special-it","category-ultime-notizie","tag-croce","tag-giovedi-santo","tag-messa-crismale","tag-papa-francesco","tag-sacerdoti","tag-vangelo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;annuncio del Vangelo \u00e8 sempre legato alla Croce &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"L&#039;annuncio del Vangelo legato alla Croce \u00e8 stato al centro dell&#039;omelia pronunciata da Papa Francesco durante la Messa Crismale a San Pietro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;annuncio del Vangelo \u00e8 sempre legato alla Croce &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"L&#039;annuncio del Vangelo legato alla Croce \u00e8 stato al centro dell&#039;omelia pronunciata da Papa Francesco durante la Messa Crismale a San Pietro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-01T08:50:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-01T11:38:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1701\" \/>\n\t<meta property=\"og:image:height\" content=\"1132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"L&#8217;annuncio del Vangelo \u00e8 sempre legato alla Croce\",\"datePublished\":\"2021-04-01T08:50:58+00:00\",\"dateModified\":\"2021-04-01T11:38:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/\"},\"wordCount\":2123,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Messa-crismale-2.jpg\",\"keywords\":[\"croce\",\"gioved\u00ec santo\",\"Messa crismale\",\"Papa Francesco\",\"sacerdoti\",\"Vangelo\"],\"articleSection\":[\"Featured News\",\"Leone XIV\",\"Special\",\"Ultime Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/\",\"name\":\"L'annuncio del Vangelo \u00e8 sempre legato alla Croce &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Messa-crismale-2.jpg\",\"datePublished\":\"2021-04-01T08:50:58+00:00\",\"dateModified\":\"2021-04-01T11:38:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"description\":\"L'annuncio del Vangelo legato alla Croce \u00e8 stato al centro dell'omelia pronunciata da Papa Francesco durante la Messa Crismale a San Pietro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Messa-crismale-2.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Messa-crismale-2.jpg\",\"width\":1701,\"height\":1132,\"caption\":\"La Messa Crismale celebrata dal S. Padre \u00a9 Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;annuncio del Vangelo \u00e8 sempre legato alla Croce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'annuncio del Vangelo \u00e8 sempre legato alla Croce &#8211; Exaudi","description":"L'annuncio del Vangelo legato alla Croce \u00e8 stato al centro dell'omelia pronunciata da Papa Francesco durante la Messa Crismale a San Pietro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/","og_locale":"it_IT","og_type":"article","og_title":"L'annuncio del Vangelo \u00e8 sempre legato alla Croce &#8211; Exaudi","og_description":"L'annuncio del Vangelo legato alla Croce \u00e8 stato al centro dell'omelia pronunciata da Papa Francesco durante la Messa Crismale a San Pietro","og_url":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2021-04-01T08:50:58+00:00","article_modified_time":"2021-04-01T11:38:15+00:00","og_image":[{"width":1701,"height":1132,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-2.jpg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"L&#8217;annuncio del Vangelo \u00e8 sempre legato alla Croce","datePublished":"2021-04-01T08:50:58+00:00","dateModified":"2021-04-01T11:38:15+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/"},"wordCount":2123,"image":{"@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-2.jpg","keywords":["croce","gioved\u00ec santo","Messa crismale","Papa Francesco","sacerdoti","Vangelo"],"articleSection":["Featured News","Leone XIV","Special","Ultime Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/","url":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/","name":"L'annuncio del Vangelo \u00e8 sempre legato alla Croce &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-2.jpg","datePublished":"2021-04-01T08:50:58+00:00","dateModified":"2021-04-01T11:38:15+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"description":"L'annuncio del Vangelo legato alla Croce \u00e8 stato al centro dell'omelia pronunciata da Papa Francesco durante la Messa Crismale a San Pietro","breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-2.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-2.jpg","width":1701,"height":1132,"caption":"La Messa Crismale celebrata dal S. Padre \u00a9 Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/lannuncio-del-vangelo-e-sempre-legato-alla-croce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;annuncio del Vangelo \u00e8 sempre legato alla Croce"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Messa-crismale-2.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-2oe","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/9190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=9190"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/9190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/9221"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=9190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=9190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=9190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}