{"id":86750,"date":"2023-10-29T17:45:47","date_gmt":"2023-10-29T16:45:47","guid":{"rendered":"https:\/\/exaudi.org\/?p=86750"},"modified":"2023-10-29T17:45:47","modified_gmt":"2023-10-29T16:45:47","slug":"amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/","title":{"rendered":"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3"},"content":{"rendered":"<p>Padre Jorge Mir\u00f3 condivide con i lettori di Exaudi il suo commento al Vangelo di oggi, 29 ottobre 2023, intitolato &#8220;<em>Amerai il Signore, tuo Dio, e il tuo prossimo come te stesso&#8221;<\/em>.<\/p>\n<p>***<\/p>\n<p>Nel Vangelo vediamo come i farisei chiedano a Ges\u00f9 <em>quale sia il comandamento principale della legge<\/em>.<\/p>\n<p>La risposta di Ges\u00f9 mostra che la cosa decisiva non \u00e8 sapere quale sia il comandamento pi\u00f9 importante, ma cercare l&#8217;origine di tutti: l&#8217;amore \u00e8 il centro e il compendio della legge di Dio. L&#8217;uomo \u00e8 creato a immagine di Dio e Dio \u00e8 amore. Pertanto, la vocazione all&#8217;amore \u00e8 ci\u00f2 che rende l&#8217;uomo l&#8217;autentica immagine di Dio: egli \u00e8 come Dio nella misura in cui ama (Benedetto XVI).<\/p>\n<p>Cio\u00e8, l&#8217;uomo si realizza come persona nella misura in cui ama con un amore come quello di Dio: gratuito, fedele, generoso, totale. Nella misura in cui esce da se stesso e sa donarsi.<\/p>\n<p>Essere cristiano \u00e8 aver scoperto che Dio ti ama gratuitamente; \u00e8 essere innamorato di Ges\u00f9 Cristo, \u00e8 cominciare a rispondere all&#8217;amore di Dio, fino a poterlo amare un giorno con tutto il cuore&#8230; \u00c8 vivere la vita nuova che lo Spirito Santo sta facendo in te. \u00c8 vivere la vita come una storia d&#8217;amore con il Signore.<\/p>\n<p>Quando siete toccati dall&#8217;amore di Dio, la vostra vita comincia a cambiare. Iniziate ad amare con lo stesso amore: liberamente, fedelmente, generosamente, generosamente, arrendevolmente, totalmente?<\/p>\n<p>Ecco perch\u00e9 essere cristiani non \u00e8 un moralismo, non \u00e8 semplicemente &#8220;adempiere&#8221; a una serie di comandamenti o regole.<\/p>\n<p>Essere cristiani \u00e8 seguire Ges\u00f9 Cristo, riconoscerlo come unico Maestro e confessarlo come unico Signore, lasciandolo essere il Signore della propria vita.<\/p>\n<p>Questa Parola ci invita a una <em>conversione<\/em> molto profonda: mettere Dio al centro della tua vita, lasciare che Ges\u00f9 Cristo sia il tuo Signore, e ascoltare ogni giorno lo Spirito Santo che, in mezzo alle lotte e alle tribolazioni, ti riempie il cuore di gioia, perch\u00e9 ti certifica nel cuore che Dio ti ama; che \u00e8 con te l\u00ec, sulla tua croce, nella tua storia concreta; che non c&#8217;\u00e8 niente e nessuno che possa separarti da questo Amore.<\/p>\n<p>E allora lo Spirito si occuper\u00e0 di ordinare la vostra vita, tenendo conto della vostra debolezza. Far\u00e0 nascere in voi l&#8217;amore per il prossimo, che nasce dall&#8217;ascolto docile e dall&#8217;accoglienza fiduciosa della Parola di Dio.<\/p>\n<p>Chi ama Dio, infatti, non vive nell&#8217;idolatria, non invoca il suo nome e cerca di santificare le feste, perch\u00e9 ha scoperto che il Signore sta facendo grandi opere nella sua vita e ha bisogno di celebrarle con i suoi fratelli e sorelle.<\/p>\n<p>Chi ama Dio, vede come la fede fa dell&#8217;<em>altro<\/em> un <em>fratello<\/em>, un figlio dello stesso Padre, anche il povero, lo straniero, la vedova e l&#8217;orfano. E chi riconosce l&#8217;<em>altro<\/em> come <em>fratello<\/em>, lo ama: rispetta e aiuta la sua famiglia, non \u00e8 violento verso il <em>fratello<\/em> e non lo uccide; lo rispetta perch\u00e9 riconosce che sia lui che il <em>fratello<\/em> sono templi dello Spirito Santo; non ruba al <em>fratello<\/em>, non gli mente, non pensa e non augura il male a nessuno e non invidia e non brama il <em>fratello<\/em>, proprio perch\u00e9 l&#8217;<em>altro<\/em> non \u00e8 un rivale contro cui lottare, n\u00e9 un oggetto da usare e da scartare, ma la fede fa dell&#8217;<em>altro<\/em> un <em>fratello<\/em> da amare e servire, un <em>dono<\/em> da accogliere.<\/p>\n<p>Vieni, Spirito Santo! (cfr. Lc 11,13).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 29 ottobre 2023<\/p>\n","protected":false},"author":17,"featured_media":86714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[73],"tags":[10008,10007,4952],"class_list":["post-86750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa-e-mondo","tag-commento-al-vangelo","tag-jorge-miro-2","tag-trending-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3 &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3 &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Domenica 29 ottobre 2023\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-29T16:45:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/10\/Juan-Gomez-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3\",\"datePublished\":\"2023-10-29T16:45:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/\"},\"wordCount\":569,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Juan-Gomez-scaled.jpg\",\"keywords\":[\"Commento al Vangelo\",\"Jorge Mir\u00f3\",\"Trending\"],\"articleSection\":[\"Chiesa e Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/\",\"name\":\"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3 &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Juan-Gomez-scaled.jpg\",\"datePublished\":\"2023-10-29T16:45:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Juan-Gomez-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Juan-Gomez-scaled.jpg\",\"width\":2560,\"height\":1710,\"caption\":\"Cathopic\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3 &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/","og_locale":"it_IT","og_type":"article","og_title":"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3 &#8211; Exaudi","og_description":"Domenica 29 ottobre 2023","og_url":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2023-10-29T16:45:47+00:00","og_image":[{"width":2560,"height":1710,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/10\/Juan-Gomez-scaled.jpg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3","datePublished":"2023-10-29T16:45:47+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/"},"wordCount":569,"image":{"@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/10\/Juan-Gomez-scaled.jpg","keywords":["Commento al Vangelo","Jorge Mir\u00f3","Trending"],"articleSection":["Chiesa e Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/","url":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/","name":"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3 &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/10\/Juan-Gomez-scaled.jpg","datePublished":"2023-10-29T16:45:47+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/10\/Juan-Gomez-scaled.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/10\/Juan-Gomez-scaled.jpg","width":2560,"height":1710,"caption":"Cathopic"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/amerai-il-signore-tuo-dio-e-il-tuo-prossimo-come-te-stesso-p-jorge-miro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Amerai il Signore tuo Dio e il tuo prossimo come te stesso: P. Jorge Mir\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/10\/Juan-Gomez-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-mzc","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/86750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=86750"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/86750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/86714"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=86750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=86750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=86750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}