{"id":68922,"date":"2023-01-21T18:04:41","date_gmt":"2023-01-21T17:04:41","guid":{"rendered":"https:\/\/exaudi.org\/?p=68922"},"modified":"2023-01-21T18:04:41","modified_gmt":"2023-01-21T17:04:41","slug":"udienza-di-papa-francesco-al-presidente-dellecuador","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/","title":{"rendered":"Udienza di Papa Francesco al Presidente dell&#8217;Ecuador"},"content":{"rendered":"<p>Nella mattina di oggi, sabato 21 gennaio 2023, il Santo Padre Francesco ha ricevuto in Udienza, nel Palazzo Apostolico Vaticano, il Presidente della Repubblica dell\u2019Ecuador, S.E. il Sig. Guillermo Lasso Mendoza, il quale, successivamente, ha incontrato Sua Eminenza Rev.ma il Sig. Cardinale Pietro Parolin, Segretario di Stato, accompagnato dall\u2019Ecc.mo Mons. Paul Richard Gallagher, Segretario per i Rapporti con gli Stati e le Organizzazioni Internazionali.<\/p>\n<p>Nel corso dei cordiali colloqui in Segreteria di Stato \u00e8 stato espresso apprezzamento per il contributo che la Chiesa offre nell\u2019ambito dell\u2019educazione, della salute, della promozione dei valori umani e spirituali e nel campo delle attivit\u00e0 caritative, sottolineando l\u2019importanza di un dialogo sincero e permanente tra la Chiesa e lo Stato per affrontare le sfide fondamentali della societ\u00e0.<\/p>\n<p>Inoltre, c\u2019\u00e8 stato un fruttuoso scambio di vedute sulla situazione politica e sociale della Regione, con attenzione agli sforzi miranti a favorire lo sviluppo e a promuovere la pace e ci si \u00e8 soffermati su alcuni temi di comune interesse quali la tutela della vita, la cura dell\u2019infanzia, la riforma del sistema penitenziario, il rispetto delle popolazioni indigene e della loro cultura, nonch\u00e9 la protezione dell\u2019ambiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rapporto della Sala Stampa della Santa Sede<\/p>\n","protected":false},"author":17,"featured_media":68923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[67],"tags":[4393,8215,251,4952,1843],"class_list":["post-68922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leone-xiv","tag-ecuador-it","tag-guillermo-lasso-mendoza","tag-papa-francesco","tag-trending-it","tag-udienza"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Udienza di Papa Francesco al Presidente dell&#039;Ecuador &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Udienza di Papa Francesco al Presidente dell&#039;Ecuador &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Rapporto della Sala Stampa della Santa Sede\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-21T17:04:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/01\/cq5dam.thumbnail.cropped.750.422-15.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"Udienza di Papa Francesco al Presidente dell&#8217;Ecuador\",\"datePublished\":\"2023-01-21T17:04:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/\"},\"wordCount\":202,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cq5dam.thumbnail.cropped.750.422-15.jpeg?fit=750%2C422&ssl=1\",\"keywords\":[\"ecuador\",\"Guillermo Lasso Mendoza\",\"Papa Francesco\",\"Trending\",\"udienza\"],\"articleSection\":[\"Leone XIV\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/\",\"name\":\"Udienza di Papa Francesco al Presidente dell'Ecuador &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cq5dam.thumbnail.cropped.750.422-15.jpeg?fit=750%2C422&ssl=1\",\"datePublished\":\"2023-01-21T17:04:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cq5dam.thumbnail.cropped.750.422-15.jpeg?fit=750%2C422&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cq5dam.thumbnail.cropped.750.422-15.jpeg?fit=750%2C422&ssl=1\",\"width\":750,\"height\":422,\"caption\":\"Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/udienza-di-papa-francesco-al-presidente-dellecuador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Udienza di Papa Francesco al Presidente dell&#8217;Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Udienza di Papa Francesco al Presidente dell'Ecuador &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/","og_locale":"it_IT","og_type":"article","og_title":"Udienza di Papa Francesco al Presidente dell'Ecuador &#8211; Exaudi","og_description":"Rapporto della Sala Stampa della Santa Sede","og_url":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2023-01-21T17:04:41+00:00","og_image":[{"width":750,"height":422,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/01\/cq5dam.thumbnail.cropped.750.422-15.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"Udienza di Papa Francesco al Presidente dell&#8217;Ecuador","datePublished":"2023-01-21T17:04:41+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/"},"wordCount":202,"image":{"@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2023\/01\/cq5dam.thumbnail.cropped.750.422-15.jpeg?fit=750%2C422&ssl=1","keywords":["ecuador","Guillermo Lasso Mendoza","Papa Francesco","Trending","udienza"],"articleSection":["Leone XIV"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/","url":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/","name":"Udienza di Papa Francesco al Presidente dell'Ecuador &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2023\/01\/cq5dam.thumbnail.cropped.750.422-15.jpeg?fit=750%2C422&ssl=1","datePublished":"2023-01-21T17:04:41+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2023\/01\/cq5dam.thumbnail.cropped.750.422-15.jpeg?fit=750%2C422&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2023\/01\/cq5dam.thumbnail.cropped.750.422-15.jpeg?fit=750%2C422&ssl=1","width":750,"height":422,"caption":"Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/udienza-di-papa-francesco-al-presidente-dellecuador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Udienza di Papa Francesco al Presidente dell&#8217;Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2023\/01\/cq5dam.thumbnail.cropped.750.422-15.jpeg?fit=750%2C422&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-hVE","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/68922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=68922"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/68922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/68923"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=68922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=68922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=68922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}