{"id":67580,"date":"2022-12-25T16:55:01","date_gmt":"2022-12-25T15:55:01","guid":{"rendered":"https:\/\/exaudi.org\/?p=67580"},"modified":"2022-12-25T16:55:01","modified_gmt":"2022-12-25T15:55:01","slug":"il-signore-gesu-vi-porti-tutto-lamore-di-dio","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/","title":{"rendered":"&#8220;Il Signore Ges\u00f9 vi porti tutto l&#8217;amore di Dio&#8221;"},"content":{"rendered":"<p>Alle ore 12 di oggi, Solennit\u00e0 del Natale del Signore, dalla Loggia Centrale della Basilica Vaticana, il Santo Padre Francesco, prima d&#8217;impartire la Benedizione \u201cUrbi et Orbi\u201d, ha rivolto il tradizionale Messaggio natalizio ai fedeli presenti in Piazza San Pietro e a quanti lo ascoltavano attraverso la radio, la televisione e gli altri mezzi di comunicazione.<\/p>\n<p>Questo il testo del Messaggio del Santo Padre per il Natale 2022:<\/p>\n<p><strong>Messaggio natalizio del Santo Padre<\/strong><\/p>\n<p><i>Cari fratelli e sorelle di Roma e del mondo intero, buon Natale!<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-67585 alignleft\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-300x200.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-1024x682.jpg 1024w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-770x513.jpg 770w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-360x240.jpg?crop=1 360w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-500x333.jpg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-1155x770.jpg 1155w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-370x247.jpg 370w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-293x195.jpg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-120x80.jpg 120w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-240x160.jpg 240w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280-390x260.jpg 390w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6280.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Il Signore Ges\u00f9, nato dalla Vergine Maria, porti a tutti voi l\u2019amore di Dio, sorgente di fiducia e di speranza; e porti insieme il dono della pace, che gli angeli annunciarono ai pastori di Betlemme: \u00abGloria a Dio nel pi\u00f9 alto dei cieli e sulla terra pace agli uomini, che egli ama\u00bb (<i>Lc<\/i>\u00a02,14).<\/p>\n<p>In questo giorno di festa volgiamo lo sguardo a Betlemme. Il Signore viene al mondo in una grotta ed \u00e8 adagiato in una mangiatoia per gli animali, perch\u00e9 i suoi genitori non hanno potuto trovare un alloggio, malgrado per Maria fosse ormai giunta l\u2019ora del parto. Viene tra noi nel silenzio e nell\u2019oscurit\u00e0 della notte, perch\u00e9 il Verbo di Dio non ha bisogno di riflettori, n\u00e9 del clamore delle voci umane. Egli stesso \u00e8 la Parola che d\u00e0 senso all\u2019esistenza, Lui \u00e8 la luce che rischiara il cammino. \u00abVeniva nel mondo la luce vera \u2013 dice il Vangelo \u2013, quella che illumina ogni uomo\u00bb (<i>Gv<\/i>\u00a01,9).<\/p>\n<p>Ges\u00f9 nasce in mezzo a noi, \u00e8\u00a0<i>Dio-con-noi<\/i>. Viene per accompagnare il nostro vivere quotidiano, per condividere tutto con noi, gioie e dolori, speranze e inquietudini. Viene come bambino inerme. Nasce al freddo, povero tra i poveri. Bisognoso di tutto, bussa alla porta del nostro cuore per trovare calore e riparo.<\/p>\n<p>Come i pastori di Betlemme, lasciamoci avvolgere dalla luce e andiamo a vedere il segno che Dio ci ha dato. Vinciamo il torpore del sonno spirituale e le false immagini della festa che fanno dimenticare chi \u00e8 il festeggiato. Usciamo dal frastuono che anestetizza il cuore e ci induce a preparare addobbi e regali pi\u00f9 che a contemplare l\u2019Avvenimento: il Figlio di Dio nato per noi.<\/p>\n<p>Fratelli, sorelle, volgiamoci a Betlemme, dove risuona il primo vagito del Principe della pace. S\u00ec, perch\u00e9 Lui stesso, Ges\u00f9,\u00a0<i>Lui<\/i>\u00a0<i>\u00e8 la nostra pace<\/i>: quella pace che il mondo non pu\u00f2 dare e che Dio Padre ha donato all\u2019umanit\u00e0 mandando nel mondo il suo Figlio. San Leone Magno ha un\u2019espressione che, nella concisione della lingua latina, riassume il messaggio di questo giorno: \u00ab<i>Natalis Domini, Natalis est pacis<\/i>\u00bb, \u00abil Natale del Signore \u00e8 il Natale della pace\u00bb (<i>Sermone<\/i>\u00a026,5).<\/p>\n<p>Ges\u00f9 Cristo \u00e8 anche\u00a0<i>la via della pace<\/i>. Egli, con la sua incarnazione, passione, morte e risurrezione, ha aperto il passaggio da un mondo chiuso, oppresso dalle tenebre dell\u2019inimicizia e della guerra, a un mondo aperto, libero di vivere nella fraternit\u00e0 e nella pace. Fratelli e sorelle, seguiamo questa strada! Ma per poterlo fare, per essere in grado di camminare dietro a Ges\u00f9, dobbiamo spogliarci dei pesi che ci intralciano e ci tengono bloccati.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-67588 alignright\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-300x200.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-1024x682.jpg 1024w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-770x513.jpg 770w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-360x240.jpg?crop=1 360w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-500x333.jpg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-1155x770.jpg 1155w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-370x247.jpg 370w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-293x195.jpg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-120x80.jpg 120w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-240x160.jpg 240w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276-390x260.jpg 390w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC8276.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>E quali sono questi pesi? Che cos\u2019\u00e8 questa \u201czavorra\u201d? Sono le stesse passioni negative che impedirono al re Erode e alla sua corte di riconoscere e accogliere la nascita di Ges\u00f9: cio\u00e8, l\u2019attaccamento al potere e al denaro, la superbia, l\u2019ipocrisia, la menzogna. Questi pesi impediscono di andare a Betlemme, escludono dalla grazia del Natale e chiudono l\u2019accesso alla via della pace. E in effetti, dobbiamo constatare con dolore che, mentre ci viene donato il Principe della pace, venti di guerra continuano a soffiare gelidi sull\u2019umanit\u00e0.<\/p>\n<p>Se vogliamo che sia Natale, il Natale di Ges\u00f9 e della pace, guardiamo a Betlemme e fissiamo lo sguardo sul volto del Bambino che \u00e8 nato per noi! E in quel piccolo viso innocente, riconosciamo quello dei bambini che in ogni parte del mondo anelano alla pace.<\/p>\n<p>Il nostro sguardo si riempia dei volti dei fratelli e delle sorelle ucraini, che vivono questo Natale al buio, al freddo o lontano dalle proprie case, a causa della distruzione causata da dieci mesi di guerra. Il Signore ci renda pronti a gesti concreti di solidariet\u00e0 per aiutare quanti stanno soffrendo, e illumini le menti di chi ha il potere di far tacere le armi e porre fine subito a questa guerra insensata! Purtroppo, si preferisce ascoltare altre ragioni, dettate dalle logiche del mondo. Ma la voce del Bambino, chi l\u2019ascolta?<\/p>\n<p>Il nostro tempo sta vivendo una grave\u00a0<i>carestia di pace<\/i>\u00a0anche in altre regioni, in altri teatri di questa terza guerra mondiale. Pensiamo alla Siria, ancora martoriata da un conflitto che \u00e8 passato in secondo piano ma non \u00e8 finito; e pensiamo alla Terra Santa, dove nei mesi scorsi sono aumentate le violenze e gli scontri, con morti e feriti. Imploriamo il Signore perch\u00e9 l\u00e0, nella terra che lo ha visto nascere, riprendano il dialogo e la ricerca della fiducia reciproca tra Palestinesi e Israeliani. Ges\u00f9 Bambino sostenga le comunit\u00e0 cristiane che vivono in tutto il Medio Oriente, perch\u00e9 in ciascuno di quei Paesi si possa vivere la bellezza della convivenza fraterna tra persone appartenenti a diverse fedi. Aiuti in particolare il Libano, perch\u00e9 possa finalmente risollevarsi, con il sostegno della Comunit\u00e0 internazionale e con la forza della fratellanza e della solidariet\u00e0. La luce di Cristo illumini la regione del Sahel, dove la pacifica convivenza tra popoli e tradizioni \u00e8 sconvolta da scontri e violenze. Orienti verso una tregua duratura nello Yemen e verso la riconciliazione nel Myanmar e in Iran, perch\u00e9 cessi ogni spargimento di sangue. Ispiri le autorit\u00e0 politiche e tutte le persone di buona volont\u00e0 nel continente americano, ad adoperarsi per pacificare le tensioni politiche e sociali che interessano vari Paesi; penso in particolare alla popolazione haitiana che sta soffrendo da tanto tempo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-67591 alignleft\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-300x200.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-1024x682.jpg 1024w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-770x513.jpg 770w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-360x240.jpg?crop=1 360w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-500x333.jpg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-1155x770.jpg 1155w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-370x247.jpg 370w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-293x195.jpg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-120x80.jpg 120w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-240x160.jpg 240w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073-390x260.jpg 390w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__MTC0073.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>In questo giorno, nel quale \u00e8 bello ritrovarsi attorno alla tavola imbandita, non distogliamo lo sguardo da Betlemme, che significa \u201ccasa del pane\u201d, e pensiamo alle persone che patiscono la fame, soprattutto bambini, mentre ogni giorno grandi quantit\u00e0 di alimenti vengono sprecate e si spendono risorse per le armi. La guerra in Ucraina ha ulteriormente aggravato la situazione, lasciando intere popolazioni a rischio di carestia, specialmente in Afghanistan e nei Paesi del Corno d\u2019Africa. Ogni guerra \u2013 lo sappiamo \u2013 provoca fame e sfrutta il cibo stesso come arma, impedendone la distribuzione a popolazioni gi\u00e0 sofferenti. In questo giorno, imparando dal Principe della pace, impegniamoci tutti, per primi quanti hanno responsabilit\u00e0 politiche, perch\u00e9 il cibo sia solo strumento di pace. Mentre gustiamo la gioia di ritrovarci con i nostri, pensiamo alle famiglie che sono pi\u00f9 ferite dalla vita, e a quelle che, in questo tempo di crisi economica, fanno fatica a causa della disoccupazione e mancano del necessario per vivere.<\/p>\n<p>Cari fratelli e sorelle, oggi come allora, Ges\u00f9, la luce vera, viene in un mondo malato d&#8217;indifferenza \u2013 brutta malattia! \u2013 che non lo accoglie (cfr <i>Gv<\/i>\u00a01,11), anzi lo respinge, come accade a molti stranieri, o lo ignora, come troppo spesso facciamo noi con i poveri. Non dimentichiamoci oggi dei tanti profughi e rifugiati che bussano alle nostre porte in cerca di conforto, calore e cibo. Non dimentichiamoci degli emarginati, delle persone sole, degli orfani e degli anziani \u2013 saggezza di un popolo \u2013 che rischiano di finire scartati, dei carcerati che guardiamo solo per i loro errori e non come esseri umani.<\/p>\n<p>Fratelli e sorelle, Betlemme ci mostra la semplicit\u00e0 di Dio, che si rivela non ai sapienti e ai dotti, ma ai piccoli, a chi ha il cuore puro e aperto (cfr\u00a0<i>Mt<\/i>\u00a011,25). Come i pastori, andiamo anche noi senza indugio e lasciamoci stupire dall\u2019evento impensabile di Dio che si fa uomo per la nostra salvezza. Colui che \u00e8 fonte di ogni bene si fa povero\u00a0<a class=\" cleaner\" href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/messages\/urbi\/documents\/20221225-urbi-et-orbi-natale.html#_ftn1\" name=\"_ftnref1\">[1]<\/a>\u00a0e chiede in elemosina la nostra povera umanit\u00e0. Lasciamoci commuovere dall\u2019amore di Dio, e seguiamo Ges\u00f9, che si \u00e8 spogliato della sua gloria per farci partecipi della sua pienezza\u00a0<a class=\" cleaner\" href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/messages\/urbi\/documents\/20221225-urbi-et-orbi-natale.html#_ftn2\" name=\"_ftnref2\">[2]<\/a>. Buon Natale a tutti!<\/p>\n<p>______________________________________________________<\/p>\n<p><a class=\" cleaner\" href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/messages\/urbi\/documents\/20221225-urbi-et-orbi-natale.html#_ftnref1\" name=\"_ftn1\">[1]<\/a>\u00a0Cfr S. Gregorio Nazianzeno,\u00a0<i>Discorso 45<\/i>.<\/p>\n<p><a class=\" cleaner\" href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/messages\/urbi\/documents\/20221225-urbi-et-orbi-natale.html#_ftnref2\" name=\"_ftn2\">[2]<\/a>\u00a0Cfr\u00a0<i>ibid<\/i>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Messaggio natalizio del Santo Padre e la Benedizione &#8220;Urbi et Orbi&#8221;<\/p>\n","protected":false},"author":17,"featured_media":67581,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[67,117],"tags":[8015,251,4952],"class_list":["post-67580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leone-xiv","category-messaggi","tag-benedizione-urbi-et-orbi-2022","tag-papa-francesco","tag-trending-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Il Signore Ges\u00f9 vi porti tutto l&#039;amore di Dio&quot; &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Il Signore Ges\u00f9 vi porti tutto l&#039;amore di Dio&quot; &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Messaggio natalizio del Santo Padre e la Benedizione &quot;Urbi et Orbi&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-25T15:55:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6302.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"&#8220;Il Signore Ges\u00f9 vi porti tutto l&#8217;amore di Dio&#8221;\",\"datePublished\":\"2022-12-25T15:55:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/\"},\"wordCount\":1332,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/thumbnail__DSC6302.jpg\",\"keywords\":[\"Benedizione \u201cUrbi et Orbi\u201d 2022\",\"Papa Francesco\",\"Trending\"],\"articleSection\":[\"Leone XIV\",\"Messaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/\",\"name\":\"\\\"Il Signore Ges\u00f9 vi porti tutto l'amore di Dio\\\" &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/thumbnail__DSC6302.jpg\",\"datePublished\":\"2022-12-25T15:55:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/thumbnail__DSC6302.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/thumbnail__DSC6302.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Il Signore Ges\u00f9 vi porti tutto l&#8217;amore di Dio&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Il Signore Ges\u00f9 vi porti tutto l'amore di Dio\" &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/","og_locale":"it_IT","og_type":"article","og_title":"\"Il Signore Ges\u00f9 vi porti tutto l'amore di Dio\" &#8211; Exaudi","og_description":"Messaggio natalizio del Santo Padre e la Benedizione \"Urbi et Orbi\"","og_url":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2022-12-25T15:55:01+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6302.jpg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"&#8220;Il Signore Ges\u00f9 vi porti tutto l&#8217;amore di Dio&#8221;","datePublished":"2022-12-25T15:55:01+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/"},"wordCount":1332,"image":{"@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6302.jpg","keywords":["Benedizione \u201cUrbi et Orbi\u201d 2022","Papa Francesco","Trending"],"articleSection":["Leone XIV","Messaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/","url":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/","name":"\"Il Signore Ges\u00f9 vi porti tutto l'amore di Dio\" &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6302.jpg","datePublished":"2022-12-25T15:55:01+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6302.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6302.jpg","width":1280,"height":853,"caption":"Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/il-signore-gesu-vi-porti-tutto-lamore-di-dio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"&#8220;Il Signore Ges\u00f9 vi porti tutto l&#8217;amore di Dio&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/12\/thumbnail__DSC6302.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-hA0","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/67580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=67580"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/67580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/67581"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=67580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=67580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=67580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}