{"id":61730,"date":"2022-09-08T17:24:23","date_gmt":"2022-09-08T15:24:23","guid":{"rendered":"https:\/\/exaudi.org\/?p=61730"},"modified":"2022-09-08T17:24:23","modified_gmt":"2022-09-08T15:24:23","slug":"avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/","title":{"rendered":"&#8220;Avete portato ai popoli e alle Chiese la vicinanza del Papa&#8221;"},"content":{"rendered":"<p>Questa mattina, nel Palazzo Apostolico Vaticano, il Santo Padre ha ricevuto in Udienza i partecipanti all\u2019Incontro triennale dei Rappresentanti Pontifici, in corso in Vaticano dal 7 al 10 settembre 2022.<\/p>\n<p>Pubblichiamo di seguito il saluto che il Papa ha rivolto ai presenti:<\/p>\n<p><strong>Saluto del Santo Padre<\/strong><\/p>\n<p>Cari fratelli!<\/p>\n<p>Do il benvenuto a tutti voi e ringrazio ciascuno di essere venuto, affrontando anche non poche difficolt\u00e0.<\/p>\n<p>Sono passati tre anni dal nostro scorso incontro. La tempesta della pandemia da Covid-19 ci ha costretti a varie limitazioni della vita quotidiana e delle nostre attivit\u00e0 pastorali. Ora sembra che il peggio sia passato, e grazie a Dio possiamo ritrovarci. Ma purtroppo l\u2019Europa e il mondo intero sono sconvolti da una guerra di speciale gravit\u00e0, sia per la violazione del diritto internazionale, sia per i rischi di\u00a0<i>escalation<\/i>\u00a0nucleare, sia per le pesanti conseguenze economiche e sociali. \u00c8 una terza guerra mondiale \u201ca pezzi\u201d, di cui voi siete testimoni nei luoghi in cui state svolgendo la vostra missione.<\/p>\n<p>Vi ringrazio per tutto quello che le Rappresentanze Pontificie hanno fatto e stanno facendo in queste situazioni di sofferenza. Avete portato ai popoli e alle Chiese la vicinanza del Papa; siete stati punti di riferimento nei momenti di maggiore smarrimento e turbolenza.<\/p>\n<p>E in tale contesto desidero ricordare insieme con voi i Nunzi Apostolici Mons. Joseph Chennoth e Mons. Aldo Giordano, che da poco ci hanno lasciato durante il loro servizio; come pure quelli defunti gi\u00e0 in quiescenza negli ultimi tre anni. Questi nostri cari fratelli ci hanno preceduto nel cammino e ci invitano a guardare avanti e in alto.<\/p>\n<p>Con questo sguardo andiamo avanti nel nostro lavoro, nell\u2019oggi della Chiesa e del mondo, confidando nella grazia del Signore. Come Chiesa siamo impegnati in un percorso sinodale che vorrebbe far crescere nel popolo di Dio proprio questa dimensione di sinodalit\u00e0. Anche voi siete stati coinvolti nella consultazione. E poi abbiamo all\u2019orizzonte il Giubileo del 2025, di cui \u00e8 stata avviata la preparazione. Come Curia Romana stiamo iniziando ad applicare la Costituzione apostolica\u00a0<i><a href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/apost_constitutions\/documents\/20220319-costituzione-ap-praedicate-evangelium.html\">Praedicate Evangelium<\/a><\/i>: nata attraverso un processo di quasi nove anni, essa richieder\u00e0 del tempo anche per entrare, per cos\u00ec dire, a pieno regime.<\/p>\n<p>Affidiamo la nostra riunione e tutte le intenzioni che abbiamo nel cuore all\u2019intercessione della Vergine Maria, nella festa della sua Nativit\u00e0.<\/p>\n<p>E ora lascio a voi la parola per le domande e i suggerimenti che vorrete condividere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incontro triennale dei Rappresentanti Pontifici<\/p>\n","protected":false},"author":17,"featured_media":61721,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[115,67],"tags":[4952,6917],"class_list":["post-61730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-incontri","category-leone-xiv","tag-trending-it","tag-triennale-rappresentanti-pontifici"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Avete portato ai popoli e alle Chiese la vicinanza del Papa&quot; &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Avete portato ai popoli e alle Chiese la vicinanza del Papa&quot; &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Incontro triennale dei Rappresentanti Pontifici\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-08T15:24:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Encuentro-Trienal.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"&#8220;Avete portato ai popoli e alle Chiese la vicinanza del Papa&#8221;\",\"datePublished\":\"2022-09-08T15:24:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/\"},\"wordCount\":406,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Encuentro-Trienal.jpeg\",\"keywords\":[\"Trending\",\"Triennale Rappresentanti Pontifici\"],\"articleSection\":[\"Incontri\",\"Leone XIV\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/\",\"name\":\"\\\"Avete portato ai popoli e alle Chiese la vicinanza del Papa\\\" &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Encuentro-Trienal.jpeg\",\"datePublished\":\"2022-09-08T15:24:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Encuentro-Trienal.jpeg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Encuentro-Trienal.jpeg\",\"width\":800,\"height\":533,\"caption\":\"\u00a9 Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Avete portato ai popoli e alle Chiese la vicinanza del Papa&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Avete portato ai popoli e alle Chiese la vicinanza del Papa\" &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/","og_locale":"it_IT","og_type":"article","og_title":"\"Avete portato ai popoli e alle Chiese la vicinanza del Papa\" &#8211; Exaudi","og_description":"Incontro triennale dei Rappresentanti Pontifici","og_url":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2022-09-08T15:24:23+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Encuentro-Trienal.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"&#8220;Avete portato ai popoli e alle Chiese la vicinanza del Papa&#8221;","datePublished":"2022-09-08T15:24:23+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/"},"wordCount":406,"image":{"@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Encuentro-Trienal.jpeg","keywords":["Trending","Triennale Rappresentanti Pontifici"],"articleSection":["Incontri","Leone XIV"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/","url":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/","name":"\"Avete portato ai popoli e alle Chiese la vicinanza del Papa\" &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Encuentro-Trienal.jpeg","datePublished":"2022-09-08T15:24:23+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Encuentro-Trienal.jpeg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Encuentro-Trienal.jpeg","width":800,"height":533,"caption":"\u00a9 Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/avete-portato-ai-popoli-e-alle-chiese-la-vicinanza-del-papa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"&#8220;Avete portato ai popoli e alle Chiese la vicinanza del Papa&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Encuentro-Trienal.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-g3E","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/61730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=61730"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/61730\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/61721"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=61730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=61730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=61730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}