{"id":48767,"date":"2022-01-11T13:02:48","date_gmt":"2022-01-11T12:02:48","guid":{"rendered":"https:\/\/exaudi.org\/?p=48767"},"modified":"2022-01-11T13:02:48","modified_gmt":"2022-01-11T12:02:48","slug":"portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/","title":{"rendered":"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo"},"content":{"rendered":"<p>Portare efficacemente la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo. \u00c8 l\u2019esortazione che Papa Francesco ha rivolto all\u2019arcivescovo di Cracovia, mons. Marek J\u0119draszewski, Gran Cancelliere della Pontificia Universit\u00e0 Giovanni Paolo II, in occasione del 625\u00b0 anniversario dell\u2019ateneo. Di seguito la traduzione del messaggio diffusa dalla Sala Stampa della S. Sede:<\/p>\n<h2>Una storia lunga sei secoli<\/h2>\n<p>L\u201911 gennaio 1397, su richiesta della Regina Santa Edwige e di suo marito Ladislao, Papa Bonifacio IX, con la Bolla \u201cEximiae devotionis affectus\u201d, eresse la Facolt\u00e0 di Teologia dell\u2019allora Accademia di Cracovia, poi Universit\u00e0 Jagellonica. La sua continuazione \u00e8 l\u2019attuale Facolt\u00e0 di Teologia della Pontificia Universit\u00e0 Giovanni Paolo II. Sono dunque passati 625 anni da questo evento epocale, che segna l\u2019inizio della storia del vostro relativamente giovane Ateneo.<\/p>\n<p>Insieme a voi ringrazio Dio per questa tradizione di pi\u00f9 di sei secoli, con tutte le sue conquiste scientifiche e didattiche, cos\u00ec come la propria spiritualit\u00e0 creata dai suoi santi fondatori, professori e studenti. La storia su cui state costruendo il presente \u00e8 notevole e importante, ma allo stesso tempo impegnativa. I tempi odierni richiedono a tutti noi di non dimenticare la tradizione, ma allo stesso tempo di guardare con speranza al futuro e di creare il futuro.<\/p>\n<h2>Far conoscere la verit\u00e0 del Vangelo<\/h2>\n<p>Il motto della vostra Universit\u00e0 \u00e8 la chiamata \u201cAndate e fate discepoli\u201d, e il documento sulla sua missione afferma che l\u2019attivit\u00e0 consiste nella riflessione scientifica sul contenuto della Rivelazione, utilizzando metodi di ricerca classici e contemporanei. San Giovanni Paolo II ha sottolineato la necessit\u00e0 di un tale \u201cministero del pensiero\u201d, attraverso il quale gli ambienti universitari si uniscono alla missione della Chiesa di diffondere il messaggio di Cristo nel mondo.<\/p>\n<p>Perci\u00f2, fedeli a secoli di tradizione, leggete i segni dei tempi, raccogliete con coraggio nuove sfide per portare efficacemente la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo. Che la vostra Universit\u00e0 sia un luogo di formazione di nuove generazioni di cristiani, non solo attraverso lo studio scientifico e la ricerca della verit\u00e0, ma anche attraverso la testimonianza sociale di vivere la fede. Che sia una comunit\u00e0 in cui l\u2019acquisizione della conoscenza si combini con la promozione del rispetto di ogni uomo, per l\u2019amor di Dio che lo ha creato, e con la cura della formazione dei cuori, aprendoli a ci\u00f2 che \u00e8 pi\u00f9 importante, ci\u00f2 che \u00e8 durevole e non passa.<\/p>\n<h2>Fedeli alla missione<\/h2>\n<p>I giovani hanno i loro sogni e le loro mete, e un\u2019Universit\u00e0 cattolica dovrebbe aiutarli a realizzarli sulla base della verit\u00e0, del bene e della bellezza che hanno la loro fonte in Dio. Il suo ministero del pensiero e di ricerca della verit\u00e0 \u00e8 necessario oggi alla Chiesa in Polonia e nel mondo. Portatelo avanti con un senso di responsabilit\u00e0 per essere fedeli alla vostra missione: andate e fate discepoli! Nella preghiera affido a Dio Te, Caro Fratello, il Rettore e i Professori, gli studenti e il personale dell\u2019Universit\u00e0, invocando l\u2019intercessione di Santa Edvige la Regina, fondatrice della Facolt\u00e0, e di San Giovanni Paolo II, e imparto di cuore la Benedizione Apostolica su tutti voi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Messaggio del S. Padre per i 625 anni della Pontificia Universit\u00e0 Giovanni Paolo II di Cracovia<\/p>\n","protected":false},"author":17,"featured_media":48768,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[67],"tags":[251,4952],"class_list":["post-48767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leone-xiv","tag-papa-francesco","tag-trending-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo: messaggio del Papa per i 625 anni dell&#039;ateneo Giovanni Paolo II di Cracovia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo: messaggio del Papa per i 625 anni dell&#039;ateneo Giovanni Paolo II di Cracovia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-11T12:02:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/01\/Giovanni-Paolo-II.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo\",\"datePublished\":\"2022-01-11T12:02:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/\"},\"wordCount\":524,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Giovanni-Paolo-II.jpeg\",\"keywords\":[\"Papa Francesco\",\"Trending\"],\"articleSection\":[\"Leone XIV\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/\",\"name\":\"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Giovanni-Paolo-II.jpeg\",\"datePublished\":\"2022-01-11T12:02:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"description\":\"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo: messaggio del Papa per i 625 anni dell'ateneo Giovanni Paolo II di Cracovia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Giovanni-Paolo-II.jpeg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Giovanni-Paolo-II.jpeg\",\"width\":1280,\"height\":844,\"caption\":\"San Giovanni Paolo II (C) Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo &#8211; Exaudi","description":"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo: messaggio del Papa per i 625 anni dell'ateneo Giovanni Paolo II di Cracovia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/","og_locale":"it_IT","og_type":"article","og_title":"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo &#8211; Exaudi","og_description":"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo: messaggio del Papa per i 625 anni dell'ateneo Giovanni Paolo II di Cracovia","og_url":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2022-01-11T12:02:48+00:00","og_image":[{"width":1280,"height":844,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/01\/Giovanni-Paolo-II.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo","datePublished":"2022-01-11T12:02:48+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/"},"wordCount":524,"image":{"@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/01\/Giovanni-Paolo-II.jpeg","keywords":["Papa Francesco","Trending"],"articleSection":["Leone XIV"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/","url":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/","name":"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/01\/Giovanni-Paolo-II.jpeg","datePublished":"2022-01-11T12:02:48+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"description":"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo: messaggio del Papa per i 625 anni dell'ateneo Giovanni Paolo II di Cracovia","breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/01\/Giovanni-Paolo-II.jpeg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/01\/Giovanni-Paolo-II.jpeg","width":1280,"height":844,"caption":"San Giovanni Paolo II (C) Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/portare-la-verita-del-vangelo-alluomo-contemporaneo-e-al-mondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Portare la verit\u00e0 del Vangelo all\u2019uomo contemporaneo e al mondo"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/01\/Giovanni-Paolo-II.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-cGz","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/48767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=48767"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/48767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/48768"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=48767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=48767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=48767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}