{"id":34770,"date":"2021-09-27T17:43:00","date_gmt":"2021-09-27T15:43:00","guid":{"rendered":"https:\/\/exaudi.wpengine.com\/?p=34770"},"modified":"2021-09-27T17:43:00","modified_gmt":"2021-09-27T15:43:00","slug":"salute-il-monito-del-papa-non-ce-solo-il-covid","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/","title":{"rendered":"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid"},"content":{"rendered":"<p>Questa mattina il Santo Padre ha ricevuto in Udienza i partecipanti all\u2019Assemblea Plenaria della <a href=\"http:\/\/www.academyforlife.va\/content\/pav\/it.html\">Pontificia Accademia per la Vita,<\/a> che si svolge da oggi al 29 settembre sul tema \u201cSalute pubblica in prospettiva globale. Pandemia, Bioetica, Futuro-Public Health in Global Perspective. Pandemic, Bioethics, Future\u201d. Ecco il discorso che il Papa ha rivolto ai presenti<\/p>\n<p>Care sorelle e cari fratelli, sono lieto di potervi incontrare in occasione della vostra Assemblea Generale e ringrazio Mons. Paglia per le sue parole. Rivolgo un saluto anche ai molti Accademici collegati. Il tema che avete scelto per questi giorni di lavoro \u00e8 particolarmente attuale: quello della salute pubblica nell\u2019orizzonte della globalizzazione. In effetti, la crisi pandemica ha fatto risuonare ancora pi\u00f9 fortemente \u00abtanto il grido della terra quanto il grido dei poveri\u00bb. Non possiamo essere sordi a questo duplice grido, dobbiamo ascoltarlo bene! Ed \u00e8 quello che voi vi proponete di fare.<\/p>\n<p>L\u2019esame delle numerose e gravi questioni emerse in questi ultimi due anni non \u00e8 un compito facile. Da una parte siamo logorati dalla pandemia di Covid-19 e dall\u2019inflazione di discorsi che sono stati suscitati: quasi non vogliamo pi\u00f9 sentirne parlare e abbiamo fretta di passare ad altri argomenti. Ma d\u2019altra parte \u00e8 indispensabile riflettere con calma per esaminare in profondit\u00e0 quanto \u00e8 accaduto e intravedere la strada verso un futuro migliore per tutti.<\/p>\n<h4>Non sprecare la crisi<\/h4>\n<p>Davvero, \u00abpeggio di questa crisi c\u2019\u00e8 solo il dramma di sprecarla\u00bb. E da una crisi sappiamo che non si esce uguali: o usciremo migliori, o usciremo peggiori. Ma uguali no. La scelta \u00e8 nelle nostre mani. E, ripeto, peggio di questa crisi c\u2019\u00e8 solo il dramma di sprecarla. Vi incoraggio in questo impegno; e trovo saggia e opportuna la dinamica di discernimento secondo cui si svolge il vostro incontro: anzitutto ascoltare attentamente la situazione, per poter favorire una vera e propria conversione e arrivare a precisare decisioni concrete per uscire dalla crisi migliori.<\/p>\n<h4>Interdipendenza<\/h4>\n<p>La riflessione che avete intrapreso negli ultimi anni sulla bioetica globale si sta mostrando preziosa. Vi avevo incoraggiato in questa prospettiva con la lettera Humana communitas, in occasione del XXV anniversario della vostra Accademia. L\u2019orizzonte della salute pubblica consente infatti di mettere a fuoco aspetti importanti per la convivenza della famiglia umana e per il rafforzamento di un tessuto di amicizia sociale. Sono tematiche centrali nell\u2019Enciclica Fratelli tutti. La crisi pandemica ha messo in luce quanto \u00e8 profonda l\u2019interdipendenza sia tra di noi sia tra la famiglia umana e la casa comune. Le nostre societ\u00e0, soprattutto in Occidente, hanno avuto tendenza a dimenticare questa interconnessione. E le amare conseguenze sono sotto i nostri occhi.<\/p>\n<p>In questo passaggio d\u2019epoca \u00e8 dunque urgente invertire tale tendenza nociva, ed \u00e8 possibile farlo mediante la sinergia tra diverse discipline. Occorrono conoscenze di biologia e di igiene, di medicina e di epidemiologia, ma anche di economia e sociologia, antropologia ed ecologia. Si tratta, oltre che di comprendere i fenomeni, anche di individuare criteri di azione tecnologici, politici ed etici riguardo ai sistemi sanitari, alla famiglia, al lavoro e all\u2019ambiente. Tale impostazione \u00e8 particolarmente importante nel campo della sanit\u00e0, perch\u00e9 la salute e la malattia sono determinate non solo dai processi della natura ma anche dalla vita sociale. Inoltre, non basta che un problema sia grave perch\u00e9 si imponga all\u2019attenzione e venga cos\u00ec affrontato: tanti problemi molto gravi sono ignorati per una mancanza di impegno adeguato.<\/p>\n<h4>Non c\u2019\u00e8 solo il Covid<\/h4>\n<p>Pensiamo all\u2019impatto devastante di certe malattie come la malaria e la tubercolosi: la precariet\u00e0 delle condizioni igienicosanitarie procura nel mondo ogni anno milioni di morti evitabili. Se compariamo questa realt\u00e0 con la preoccupazione che la pandemia di Covid-19 ha provocato, vediamo come la percezione della gravit\u00e0 del problema e la corrispondente mobilitazione di energie e di risorse sia molto diversa. Certo, facciamo bene a prendere tutte le misure per arginare e sconfiggere il Covid-19 sul piano globale, ma questa congiuntura storica in cui veniamo minacciati da vicino nella nostra salute dovrebbe farci attenti a ci\u00f2 che significa essere vulnerabili e vivere quotidianamente nella precariet\u00e0.<\/p>\n<h4>Igiene e baraccopoli<\/h4>\n<p>Potremo cos\u00ec renderci responsabili anche di quelle gravi condizioni in cui vivono altri e di cui finora ci siamo poco o per nulla interessati. Impareremo cos\u00ec a non proiettare le nostre priorit\u00e0 su popolazioni che abitano in altri continenti, dove altre necessit\u00e0 risultano pi\u00f9 urgenti; dove, ad esempio, mancano non solo i vaccini, ma l\u2019acqua potabile e il pane quotidiano. Fa non so se ridere o piangere, a volte piangere, quando sentiamo governanti o responsabili di comunit\u00e0 che consigliano agli abitanti delle baraccopoli di igienizzarsi parecchie volte al giorno con acqua e sapone. Ma, caro, tu non sei stato mai in una baraccopoli: l\u00ec non c\u2019\u00e8 l\u2019acqua, non conoscono il sapone. \u201cNo, non uscire di casa!\u201d: ma l\u00ec la casa \u00e8 il quartiere tutto, perch\u00e9 vivono\u2026 Per favore, prendiamoci cura di queste realt\u00e0, anche quando riflettiamo della salute.<\/p>\n<h4>L\u2019impatto delle scelte politiche<\/h4>\n<p>Ben venga, dunque, l\u2019impegno per un\u2019equa e universale distribuzione dei vaccini \u2013 questo \u00e8 importante \u2013, ma tenendo conto del campo pi\u00f9 vasto in cui si esigono gli stessi criteri di giustizia, per i bisogni di salute e promozione della vita. Considerare la salute nelle sue molteplici dimensioni e a livello globale aiuta a comprendere e assumere responsabilmente l\u2019interconnessione tra i fenomeni. E cos\u00ec si osserva meglio come anche le condizioni di vita, che sono frutto di scelte politiche, sociali e ambientali, producono un impatto sulla salute degli esseri umani. Se esaminiamo, in diversi Paesi e in diversi gruppi sociali, la speranza di vita \u2013 e di vita in salute \u2013 scopriamo forti disuguaglianze. Esse dipendono da variabili come il livello di retribuzione, il titolo di studio, il quartiere di residenza pur nella stessa citt\u00e0.<\/p>\n<p>Noi affermiamo che la vita e la salute sono valori ugualmente fondamentali per tutti, basati sull\u2019inalienabile dignit\u00e0 della persona umana. Ma, se a questa affermazione non segue l\u2019impegno adeguato per superare le diseguaglianze, noi di fatto accettiamo la dolorosa realt\u00e0 che non tutte le vite sono uguali e la salute non \u00e8 tutelata per tutti nello stesso modo. E qui vorrei ripetere la mia inquietudine [preoccupazione], perch\u00e9 ci sia sempre un sistema sanitario gratuito: non lo perdano i Paesi che l\u2019hanno, per esempio l\u2019Italia e altri, che hanno un bel sistema sanitario gratuito; non perderlo, perch\u00e9 altrimenti si arriverebbe a che, nella popolazione, avranno diritto alla cura della salute soltanto coloro che possono pagarla, gli altri no. E questa \u00e8 una sfida molto grande. Questo aiuta a superare le disuguaglianze.<\/p>\n<h4>Regole internazionali chiare<\/h4>\n<p>Pertanto, sono da sostenere le iniziative internazionali \u2013 penso ad esempio a quelle recentemente promosse dal G20 \u2013 volte a creare una governance globale per la salute di tutti gli abitanti del pianeta, vale a dire un insieme di regole chiare e concertate a livello internazionale, rispettose della dignit\u00e0 umana. Infatti, il rischio di nuove pandemie continuer\u00e0 a essere una minaccia anche per il futuro.<\/p>\n<h4>Il ruolo della PAV<\/h4>\n<p>Anche la Pontificia Accademia per la Vita pu\u00f2 offrire un prezioso contributo in tal senso, sentendosi compagna di strada di altre organizzazioni internazionali impegnate per questa stessa finalit\u00e0. Al riguardo, \u00e8 importante partecipare a iniziative comuni e, nelle modalit\u00e0 adeguate, al dibattito pubblico. Questo richiede naturalmente che, senza \u201cannacquare\u201d i contenuti, si cerchi di comunicarli con un linguaggio idoneo e argomentazioni comprensibili nell\u2019attuale contesto sociale; cos\u00ec che la proposta antropologica cristiana, ispirata dalla Rivelazione, possa aiutare anche gli uomini e le donne di oggi a riscoprire \u00abcome primario il diritto alla vita dal concepimento al suo termine naturale\u00bb.<\/p>\n<h4>Aborto e cultura dello scarto<\/h4>\n<figure id=\"attachment_34774\" aria-describedby=\"caption-attachment-34774\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34774\" src=\"https:\/\/exaudi.wpengine.com\/wp-content\/uploads\/2021\/09\/PAV-2-300x200.jpg\" alt=\"salute\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-300x200.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-1024x683.jpg 1024w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-768x512.jpg 768w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-1536x1024.jpg 1536w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-2048x1365.jpg 2048w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-150x100.jpg 150w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-696x464.jpg 696w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-1068x712.jpg 1068w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-1920x1280.jpg 1920w, https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-2-630x420.jpg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-34774\" class=\"wp-caption-text\">Il Papa con mons. Paglia \u00a9 Vatican Media<\/figcaption><\/figure>\n<p>Anche qui vorrei accennare che noi siamo vittime di una cultura dello scarto. Mons. Paglia, nella presentazione, ha accennato a qualcosa, ma c\u2019\u00e8 lo scarto dei bambini che non vogliamo accogliere, con quella legge dell\u2019aborto che li manda al mittente e li uccide direttamente. E oggi questo \u00e8 diventato un modo \u201cnormale\u201d, un\u2019abitudine che \u00e8 bruttissima, \u00e8 proprio un omicidio, e per capirlo bene forse ci aiuta fare una doppia domanda: \u00e8 giusto eliminare, fare fuori una vita umana per risolvere un problema? \u00c8 giusto affittare un sicario per risolvere un problema? Questo \u00e8 l\u2019aborto.<\/p>\n<h4>L\u2019eutanasia nascosta<\/h4>\n<p>E poi, dall\u2019altra parte, gli anziani: gli anziani che pure sono un po\u2019 \u201cmateriale di scarto\u201d, perch\u00e9 non servono\u2026 Ma sono la saggezza, sono le radici di saggezza della nostra civilt\u00e0, e questa civilt\u00e0 li scarta! S\u00ec, in tante parti c\u2019\u00e8 anche la legge dell\u2019eutanasia \u201cnascosta\u201d, come la chiamo io: \u00e8 quella che fa dire: \u201cle medicine sono care, se ne d\u00e0 la met\u00e0 soltanto\u201d; e questo significa accorciare la vita degli anziani. Con questo noi rinneghiamo la speranza: la speranza dei bimbi che ci portano la vita che ci fa andare avanti, e la speranza che \u00e8 nelle radici che ci danno gli anziani. Scartiamo ambedue. E poi, quello scarto di tutti i giorni, che la vita \u00e8 scartata.<\/p>\n<p>Stiamo attenti a questa cultura dello scarto: non \u00e8 un problema di una legge o dell\u2019altra, \u00e8 un problema dello scarto. E su questo punto [in questa direzione] voi accademici, le universit\u00e0 cattoliche e anche gli ospedali cattolici, non possono permettersi di andare. Questa \u00e8 una strada su cui noi non possiamo andare: la strada dello scarto. Perci\u00f2 va guardato con favore lo studio che la vostra Accademia ha compiuto in questi ultimi anni sul tema dell\u2019impatto delle nuove tecnologie sulla vita umana e, pi\u00f9 specificamente, sull\u2019\u201calgoretica\u201d, in maniera tale che \u00abla scienza sia veramente al servizio dell\u2019uomo, e non l\u2019uomo al servizio della scienza\u00bb.<\/p>\n<h4>renAIssance<\/h4>\n<p>Incoraggio, a questo proposito, il lavoro della neonata Fondazione renAIssance, per la diffusione e l\u2019approfondimento della Rome Call for AI Ethics, che spero vivamente possa ricevere l\u2019adesione da parte di molti. Desidero infine ringraziarvi per l\u2019impegno e il contributo che l\u2019Accademia ha fornito partecipando attivamente alla Commissione Covid del Vaticano. Grazie per questo. \u00c8 bello vedere la cooperazione che si realizza all\u2019interno della Curia Romana nella realizzazione di un progetto condiviso. Dobbiamo sviluppare sempre pi\u00f9 questi processi portati avanti insieme, ai quali so che molti di voi hanno partecipato, sollecitando una maggiore attenzione alle persone pi\u00f9 vulnerabili, come gli anziani, i disabili e i pi\u00f9 giovani.<\/p>\n<p>on questi sentimenti di gratitudine, affido alla Vergine Maria i lavori di questa Assemblea e anche l\u2019insieme della vostra attivit\u00e0 come Accademia per la difesa e la promozione dalla vita. Benedico di cuore ciascuno di voi e i vostri cari. E vi chiedo, per favore, di pregare per me, perch\u00e9 ne ho bisogno. Grazie!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scelte politiche, sociali e ambientali producono un impatto sulla salute dell\u2019uomo. Nuovo intervento contro aborto e eutanasia<\/p>\n","protected":false},"author":17,"featured_media":34771,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[67,2157,297],"tags":[3195,288,3194,2487,251,1464,574],"class_list":["post-34770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leone-xiv","category-top-ultime-notizie","category-ultime-notizie","tag-aborto-it","tag-covid","tag-eutanasia-it","tag-featured-3","tag-papa-francesco","tag-salute","tag-vita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"Discorso del Papa alla Pontificia Accademia per la Vita: le scelte politiche e ambientali influiscono sulla salute di tutti. No ad aborto ed eutanasia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Discorso del Papa alla Pontificia Accademia per la Vita: le scelte politiche e ambientali influiscono sulla salute di tutti. No ad aborto ed eutanasia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-27T15:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid\",\"datePublished\":\"2021-09-27T15:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/\"},\"wordCount\":1764,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/PAV-1-scaled.jpg\",\"keywords\":[\"Aborto\",\"Covid\",\"Eutanasia\",\"Featured\",\"Papa Francesco\",\"salute\",\"vita\"],\"articleSection\":[\"Leone XIV\",\"Top Ultime Notizie\",\"Ultime Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/\",\"name\":\"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/PAV-1-scaled.jpg\",\"datePublished\":\"2021-09-27T15:43:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"description\":\"Discorso del Papa alla Pontificia Accademia per la Vita: le scelte politiche e ambientali influiscono sulla salute di tutti. No ad aborto ed eutanasia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/PAV-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/PAV-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"L'udienza alla PAV \u00a9 Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/salute-il-monito-del-papa-non-ce-solo-il-covid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid &#8211; Exaudi","description":"Discorso del Papa alla Pontificia Accademia per la Vita: le scelte politiche e ambientali influiscono sulla salute di tutti. No ad aborto ed eutanasia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/","og_locale":"it_IT","og_type":"article","og_title":"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid &#8211; Exaudi","og_description":"Discorso del Papa alla Pontificia Accademia per la Vita: le scelte politiche e ambientali influiscono sulla salute di tutti. No ad aborto ed eutanasia","og_url":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2021-09-27T15:43:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-1-scaled.jpg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid","datePublished":"2021-09-27T15:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/"},"wordCount":1764,"image":{"@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-1-scaled.jpg","keywords":["Aborto","Covid","Eutanasia","Featured","Papa Francesco","salute","vita"],"articleSection":["Leone XIV","Top Ultime Notizie","Ultime Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/","url":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/","name":"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-1-scaled.jpg","datePublished":"2021-09-27T15:43:00+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"description":"Discorso del Papa alla Pontificia Accademia per la Vita: le scelte politiche e ambientali influiscono sulla salute di tutti. No ad aborto ed eutanasia","breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-1-scaled.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-1-scaled.jpg","width":2560,"height":1707,"caption":"L'udienza alla PAV \u00a9 Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/salute-il-monito-del-papa-non-ce-solo-il-covid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Salute, il monito del Papa: non c\u2019\u00e8 solo il Covid"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/09\/PAV-1-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-92O","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/34770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=34770"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/34770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/34771"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=34770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=34770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=34770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}