{"id":27384,"date":"2021-07-19T07:30:44","date_gmt":"2021-07-19T05:30:44","guid":{"rendered":"https:\/\/exaudi.org\/?p=27384"},"modified":"2021-07-23T14:46:51","modified_gmt":"2021-07-23T12:46:51","slug":"l-etica-delle-relazioni-migliora-i-risultati-dimpresa","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/","title":{"rendered":"L\u2019etica delle relazioni migliora i risultati d\u2019impresa?"},"content":{"rendered":"<p>In un precedente articolo ho analizzato la necessit\u00e0 di inglobare la dimensione etica nella formazione strategica del leader d&#8217;impresa. Riconoscere di lavorare per le persone e con le persone amplia la visione dei criteri e delle alternative al momento di decidere. E questo facilita la sostenibilit\u00e0 e la permanenza dell&#8217;impresa.<\/p>\n<h4>Non solo profitti<\/h4>\n<p>In molti paesi \u00e8 ancora in vigore un approccio aziendale basato sulla massimizzazione del profitto per gli azionisti. Questo approccio parte da una concettualizzazione meccanicistica della persona umana, considerandola solo come un mero consumatore. In questa prospettiva, l&#8217;obiettivo di ogni interazione economica si completa con la soddisfazione di un bisogno: materiale, fisico, cognitivo o affettivo. Tuttavia, la nostra esperienza quotidiana ci permette di scoprire che negli scambi di beni materiali vengono veicolati anche beni immateriali. Cos\u00ec, ad esempio, nella vendita di un utensile, detto utensile non viene solo scambiato con una somma di denaro. Infatti, questo utensile \u00e8 accompagnato da altri beni, o in mancanza, dalla loro assenza, come la collaborazione, la gratitudine, l&#8217;onest\u00e0, la conoscenza o il desiderio di servizio.<\/p>\n<h4>Relazioni umane<\/h4>\n<p>Questa realt\u00e0 \u00e8 quanto contempla il documento della Congregazione per la dottrina della fede \u201c<a href=\"https:\/\/www.vatican.va\/roman_curia\/congregations\/cfaith\/documents\/rc_con_cfaith_doc_20180106_oeconomicae-et-pecuniariae_it.html\">Considerazioni per un discernimento etico dell&#8217;attuale sistema economico e finanziario<\/a>\u201d per affermare che la persona umana \u00e8 un essere di relazioni, e che, quindi, non pu\u00f2 essere ridotta a una concezione meccanicistica o individualistica. Fin dal momento della nostra nascita, siamo inseriti in un amalgama di relazioni: siamo nipoti di nonni e abbiamo zii, nipoti, fratelli e cugini. Come commenta il prof. Sell\u00e9s, ogni essere umano \u00e8 un bambino.<\/p>\n<p>Quindi, quando si tratta dello scambio di beni economici che caratterizza l&#8217;attivit\u00e0 d&#8217;impresa, la qualit\u00e0 dell&#8217;impresa non pu\u00f2 essere valutata senza tenere conto anche dei beni immateriali che vengono convogliati in detto scambio. Misurare il risultato solo dal vantaggio economico significa ridurre l&#8217;ambito dell&#8217;attivit\u00e0 aziendale. O come commenta il Prof. Rivera: la gestione aziendale pu\u00f2 essere considerata umana solo quando i suoi decisori prestano attenzione all&#8217;impatto che le loro decisioni aziendali hanno sulla loro stessa qualit\u00e0 come persone (2019).<\/p>\n<h4>Impatto etico<\/h4>\n<p>Per fare un esempio, un&#8217;attivit\u00e0 economica caratterizzata da un&#8217;asimmetria svantaggiosa delle informazioni della controparte \u00e8 un&#8217;azione non etica. Tale azione costituisce una violazione dell&#8217;onest\u00e0 relazionale del decisore. L&#8217;impatto sulla qualit\u00e0 relazionale diventa cos\u00ec la misura per valutare la qualit\u00e0 etica dell&#8217;agire economico.<\/p>\n<p>Partendo da questo presupposto concettuale della persona umana, il citato documento della Congregazione offre una definizione di moralit\u00e0 estremamente utile e illuminante per il contesto economico e finanziario: \u201cTutte le dotazioni ed i mezzi di cui si avvalgono i mercati per potenziare la loro capacit\u00e0 allocativa, purch\u00e9 non rivolti contro la dignit\u00e0 della persona e non indifferenti al bene comune sono moralmente ammissibili\u201d (n. 13). La cura della qualit\u00e0 relazionale \u00e8 specificata dall&#8217;impatto della decisione sul bene comune. Cio\u00e8, l&#8217;impatto sull&#8217;insieme delle condizioni che consentono alla persona di essere pi\u00f9 persona umana. Condizioni che solitamente sono formulate da aspetti esterni come l&#8217;economia, la sicurezza, l&#8217;educazione, l&#8217;accesso al lavoro, la ricerca spirituale, ma che hanno sempre la caratteristica di essere un bene umano con una dimensione comunitaria: \u00e8 il bene di ciascuno in particolare (Alla ricerca di un&#8217;etica universale, n\u00ba 4.1).<\/p>\n<h4>Azioni non etiche<\/h4>\n<p>In questo senso, e a titolo esemplificativo, quelle che generano un beneficio economico, ma allo stesso tempo producono forti disuguaglianze, non potrebbero essere classificate come azioni etiche; i benefici prodotti da scambi economici che sfruttano un&#8217;asimmetria informativa; quelli che generano degrado ambientale; quelli che creano insicurezza sociale; o quelli che sono il prodotto di frode.<\/p>\n<h4>Il ruolo del decisore<\/h4>\n<p>L&#8217;attenzione alla qualit\u00e0 relazionale del decisore consente di valutare, in modo pi\u00f9 oggettivo e agevole, la qualit\u00e0 etica dell&#8217;attivit\u00e0 d&#8217;impresa. Il progresso economico deve, quindi, essere misurato dalla quantit\u00e0 e dall&#8217;efficacia dei benefici, dalla qualit\u00e0 della vita che produce e dall&#8217;estensione sociale del benessere che diffonde: e benessere che non pu\u00f2 essere ridotto agli aspetti materiali (n. .11).<\/p>\n<p>Bibliografia<\/p>\n<p>Considerazioni per un discernimento etico dell&#8217;attuale sistema economico e finanziario (2018). Congregazione per la Dottrina della Fede e Dicastero per il servizio dello sviluppo umano integrale.<\/p>\n<p>Alla ricerca di un&#8217;etica universale: una nuova prospettiva sul diritto naturale (2012). Commissione Teologica Internazionale.<\/p>\n<p>Rivera, C.A. (2019). Come possiamo potenziare una nuova generazione di leader aziendali attraverso l&#8217;educazione alla gestione etica? Journal of Character Education, 15 (1), 39-52.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;importanza degli aspetti morali nelle decisioni da assumere in un&#8217;azienda<\/p>\n","protected":false},"author":57,"featured_media":27318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[297,129],"tags":[2053,3371,2656,2654,3370],"class_list":["post-27384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultime-notizie","category-voci","tag-bene-comune","tag-etica-it","tag-impresa","tag-morale","tag-profitto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019etica delle relazioni migliora i risultati d\u2019impresa? &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"Un&#039;analisi dell&#039;importanza etica delle azioni in un&#039;impresa e delle relazioni che comporta nel contribuire a migliorare il bene comune\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019etica delle relazioni migliora i risultati d\u2019impresa? &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Un&#039;analisi dell&#039;importanza etica delle azioni in un&#039;impresa e delle relazioni che comporta nel contribuire a migliorare il bene comune\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-19T05:30:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T12:46:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/07\/12c312c3-1-768x509-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"509\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alejandro Fontana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alejandro Fontana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/\"},\"author\":{\"name\":\"Alejandro Fontana\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/036aa1cfc8cb49829af5d777f3965ad7\"},\"headline\":\"L\u2019etica delle relazioni migliora i risultati d\u2019impresa?\",\"datePublished\":\"2021-07-19T05:30:44+00:00\",\"dateModified\":\"2021-07-23T12:46:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/\"},\"wordCount\":735,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/12c312c3-1-768x509-1.jpg?fit=768%2C509&ssl=1\",\"keywords\":[\"bene comune\",\"\u00c9tica\",\"impresa\",\"Morale\",\"profitto\"],\"articleSection\":[\"Ultime Notizie\",\"Voci\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/\",\"name\":\"L\u2019etica delle relazioni migliora i risultati d\u2019impresa? &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/12c312c3-1-768x509-1.jpg?fit=768%2C509&ssl=1\",\"datePublished\":\"2021-07-19T05:30:44+00:00\",\"dateModified\":\"2021-07-23T12:46:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/036aa1cfc8cb49829af5d777f3965ad7\"},\"description\":\"Un'analisi dell'importanza etica delle azioni in un'impresa e delle relazioni che comporta nel contribuire a migliorare il bene comune\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/12c312c3-1-768x509-1.jpg?fit=768%2C509&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/12c312c3-1-768x509-1.jpg?fit=768%2C509&ssl=1\",\"width\":768,\"height\":509,\"caption\":\"\u00a9 Pxhere\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019etica delle relazioni migliora i risultati d\u2019impresa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/036aa1cfc8cb49829af5d777f3965ad7\",\"name\":\"Alejandro Fontana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g\",\"caption\":\"Alejandro Fontana\"},\"description\":\"Profesor de Direcci\u00f3n General y Control Directivo. Consultor en Direcci\u00f3n General para empresas y organizaciones c\u00edvicas. Doctorado en Planificaci\u00f3n y Desarrollo; M\u00e1ster en Organizaciones y Comportamiento Humano; M.B.A. y M.E. en Ingenier\u00eda Civil. Miembro del grupo de investigaci\u00f3n GESPLAN de la Universidad Polit\u00e9cnica de Madrid. \u00c1reas de inter\u00e9s: cooperaci\u00f3n horizontal; relaci\u00f3n empresa-sociedad civil; negocios internacionales y an\u00e1lisis de estrategias empresariales.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/alejandrofontana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019etica delle relazioni migliora i risultati d\u2019impresa? &#8211; Exaudi","description":"Un'analisi dell'importanza etica delle azioni in un'impresa e delle relazioni che comporta nel contribuire a migliorare il bene comune","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019etica delle relazioni migliora i risultati d\u2019impresa? &#8211; Exaudi","og_description":"Un'analisi dell'importanza etica delle azioni in un'impresa e delle relazioni che comporta nel contribuire a migliorare il bene comune","og_url":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2021-07-19T05:30:44+00:00","article_modified_time":"2021-07-23T12:46:51+00:00","og_image":[{"width":768,"height":509,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/07\/12c312c3-1-768x509-1.jpg","type":"image\/jpeg"}],"author":"Alejandro Fontana","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Alejandro Fontana","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/"},"author":{"name":"Alejandro Fontana","@id":"https:\/\/exaudi.org\/#\/schema\/person\/036aa1cfc8cb49829af5d777f3965ad7"},"headline":"L\u2019etica delle relazioni migliora i risultati d\u2019impresa?","datePublished":"2021-07-19T05:30:44+00:00","dateModified":"2021-07-23T12:46:51+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/"},"wordCount":735,"image":{"@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/07\/12c312c3-1-768x509-1.jpg?fit=768%2C509&ssl=1","keywords":["bene comune","\u00c9tica","impresa","Morale","profitto"],"articleSection":["Ultime Notizie","Voci"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/","url":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/","name":"L\u2019etica delle relazioni migliora i risultati d\u2019impresa? &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/07\/12c312c3-1-768x509-1.jpg?fit=768%2C509&ssl=1","datePublished":"2021-07-19T05:30:44+00:00","dateModified":"2021-07-23T12:46:51+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/036aa1cfc8cb49829af5d777f3965ad7"},"description":"Un'analisi dell'importanza etica delle azioni in un'impresa e delle relazioni che comporta nel contribuire a migliorare il bene comune","breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/07\/12c312c3-1-768x509-1.jpg?fit=768%2C509&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/07\/12c312c3-1-768x509-1.jpg?fit=768%2C509&ssl=1","width":768,"height":509,"caption":"\u00a9 Pxhere"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/l-etica-delle-relazioni-migliora-i-risultati-dimpresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"L\u2019etica delle relazioni migliora i risultati d\u2019impresa?"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/036aa1cfc8cb49829af5d777f3965ad7","name":"Alejandro Fontana","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g","caption":"Alejandro Fontana"},"description":"Profesor de Direcci\u00f3n General y Control Directivo. Consultor en Direcci\u00f3n General para empresas y organizaciones c\u00edvicas. Doctorado en Planificaci\u00f3n y Desarrollo; M\u00e1ster en Organizaciones y Comportamiento Humano; M.B.A. y M.E. en Ingenier\u00eda Civil. Miembro del grupo de investigaci\u00f3n GESPLAN de la Universidad Polit\u00e9cnica de Madrid. \u00c1reas de inter\u00e9s: cooperaci\u00f3n horizontal; relaci\u00f3n empresa-sociedad civil; negocios internacionales y an\u00e1lisis de estrategias empresariales.","url":"https:\/\/exaudi.org\/it\/author\/alejandrofontana\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/07\/12c312c3-1-768x509-1.jpg?fit=768%2C509&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-77G","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/27384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=27384"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/27384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/27318"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=27384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=27384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=27384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}