{"id":23327,"date":"2021-06-22T15:56:16","date_gmt":"2021-06-22T13:56:16","guid":{"rendered":"https:\/\/exaudi.org\/?p=17977"},"modified":"2021-06-24T23:23:13","modified_gmt":"2021-06-24T21:23:13","slug":"mettere-al-centro-i-nonni-e-gli-anziani","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/","title":{"rendered":"&#8220;Mettere al centro i nonni e gli anziani&#8221;"},"content":{"rendered":"<p>\u201cLa Giornata Mondiale dei Nonni e degli Anziani \u00e8 una festa. Ne sentivamo il bisogno: dopo un anno cos\u00ec difficile c\u2019\u00e8 davvero bisogno di fare festa, nonni e nipoti, giovani ed anziani\u201d. Lo ha detto il cardinale Kevin Farrell, Prefetto del Dicastero per i Laici, la Famiglia e la Vita, presentando il <a href=\"https:\/\/exaudi.org\/it\/giornata-degli-anziani-il-messaggio-del-s-padre\/\">messaggio<\/a> del S. Padre per la Giornata che si celebrer\u00e0 il 25 luglio, la domenica pi\u00f9 vicina alla memoria liturgica (il 26) dei santi Gioacchino e Anna, genitori della Vergine Maria e nonni di Ges\u00f9. Un messaggio che \u201c\u00e8 allo stesso tempo affettuoso ed esigente verso i nonni e gli anziani. Il Santo Padre si rivolge loro con parole affettuose, ma annunciando loro anche una chiamata ad \u201cuna vocazione rinnovata in un momento cruciale della storia\u201d.<\/p>\n<h4>Nonni e anziani al posto d\u2019onore<\/h4>\n<p>\u201cNella Chiesa, con Papa Francesco, i nonni e gli anziani hanno un posto d\u2019onore e la Giornata che celebriamo intende ribadirlo \u2013 ha spiegato il cardinale &#8211; Nella pastorale, ciascuna delle nostre comunit\u00e0 \u00e8 invitata a non considerare gli anziani come clienti dei nostri servizi sociali, ma a considerare anch\u2019essi protagonisti dei nostri programmi e a valorizzarne la spiritualit\u00e0. Mettere al centro i nonni e gli anziani, cogliere il valore della loro presenza \u00e8, inoltre, l\u2019unica vera alternativa alla cultura dello scarto\u201d.<\/p>\n<h4>Tenerezza<\/h4>\n<figure id=\"attachment_17963\" aria-describedby=\"caption-attachment-17963\" style=\"width: 300px\" class=\"wp-caption alignright\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-17963\" src=\"https:\/\/i0.wp.com\/34.121.236.21\/wp-content\/uploads\/2021\/06\/E4eidN8XEAEkau8-1-300x200.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" \/><figcaption id=\"caption-attachment-17963\" class=\"wp-caption-text\">Il cardinal Farrell<\/figcaption><\/figure>\n<p>Il prefetto si \u00e8 soffermato sulla parola tenerezza: \u201cNei confronti degli anziani perch\u00e9, come ricorda il Santo Padre nel messaggio, a loro il Coronavirus \u201cha riservato un trattamento pi\u00f9 duro\u201d. La \u201ctenerezza dei nonni nei confronti dei nipoti, della guida sicura che possono essere gli anziani per tanti ragazzi spaesati\u201d. Tenerezza che ha \u201cun valore sociale, che la celebrazione della Giornata vuole affermare. \u00c8 un balsamo di cui tutti abbiamo bisogno e i nostri nonni possono esserne dispensatori. Nella societ\u00e0 sfilacciata ed indurita che esce dalla pandemia, non c\u2019\u00e8 solo bisogno di vaccini e di ripresa economica (pur fondamentali), ma di reimparare l\u2019arte delle relazioni. In questo, i nonni e gli anziani possono essere nostri maestri\u201d.<\/p>\n<h4>Saggezza<\/h4>\n<p>C\u2019\u00e8 poi il tema della saggezza: \u201cGli anziani sono, in questa prospettiva, una grande risorsa per uscire dalla crisi, migliori e non peggiori \u2013 ha detto Farrell &#8211; Soprattutto per aiutarci comprendere che quella che viviamo non \u00e8 la prima crisi, n\u00e9 sar\u00e0 l\u2019ultima e che la vicenda degli uomini \u00e8 collocata in una storia che li trascende. L\u2019esperienza degli anziani pu\u00f2 aiutare i giovani a leggere la propria vita in maniera pi\u00f9 distaccata e realistica, con quella prudenza necessaria a fare delle scelte buone\u201d.<\/p>\n<figure id=\"attachment_17969\" aria-describedby=\"caption-attachment-17969\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-medium wp-image-17969\" src=\"https:\/\/i0.wp.com\/34.121.236.21\/wp-content\/uploads\/2021\/06\/E4emEp3X0AEzmue-1-1-300x200.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" \/><figcaption id=\"caption-attachment-17969\" class=\"wp-caption-text\">Maria Sofia Soli<\/figcaption><\/figure>\n<p>Un messaggio che si basa su tre pilastri: sogni, memoria e preghiera, come ha ricordato durante la presentazione Maria Sofia Soli, volontaria della Comunit\u00e0 di S. Egidio di 88 anni, che si tiene in contatto telefonico con oltre 200 anziani di Testaccio e si preoccupa delle loro necessit\u00e0, di alleviare la loro solitudine. \u201cGli anziani non hanno lo sguardo rivolto solo verso il passato. La stanchezza o la fragilit\u00e0 non ci impediscono di sognare, per i nostri nipoti, per le generazioni che verranno. Non c\u2019\u00e8 mai un momento in cui tirare i remi in barca o pensare solo a s\u00e9 stessi. Ogni et\u00e0 ha bisogno di esprimere una vita per gli altri. Ogni et\u00e0 ha la sua vocazione\u201d ha detto nella sua testimonianza.<\/p>\n<h4>Indulgenza plenaria<\/h4>\n<p>In occasione della Giornata sar\u00e0 possibile lucrare l\u2019indulgenza plenaria, concessa alle solite condizioni. Lo prevede un decreto della Penitenzieria apostolica. Potranno ottenere l\u2019indulgenza quanti parteciperanno alla Messa del Papa o a una delle celebrazioni previste in tutto il mondo, i fedeli che dedicheranno del tempo adeguato a visitare in presenza o virtualmente i fratelli anziani bisognosi o in difficolt\u00e0 (come i malati, gli abbandonati, i disabili e simili), gli anziani malati e tutti coloro che, impossibilitati a uscire da casa, si uniranno spiritualmente alle funzioni sacre della Giornata.<\/p>\n<h4>Le iniziative<\/h4>\n<p>Diverse le iniziative in programma, come ha spiegato Vittorio Scelzo, Incaricato per la pastorale degli anziani del Dicastero. Che ha sottolineato l\u2019importanza di visitare gli anziani: \u201cE\u2019 un modo per riappropriarci di un minimo di normalit\u00e0 e per resistere all\u2019idea che la solitudine sia un destino. La Giornata sar\u00e0 un&#8217;occasione per vivere la Chiesa in uscita. Immaginiamo che i nipoti consegnino il messaggio del Santo Padre ai propri nonni e che i ragazzi delle nostre parrocchie e delle nostre comunit\u00e0 ecclesiali escano e vadano a cercare gli anziani soli del proprio quartiere per dir loro \u201cIo sono con te ogni giorno\u201d. Non \u00e8 un caso che il messaggio sia stato firmato dal Santo Padre il giorno della Visitazione\u201d.<\/p>\n<figure id=\"attachment_17966\" aria-describedby=\"caption-attachment-17966\" style=\"width: 300px\" class=\"wp-caption alignright\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-medium wp-image-17966\" src=\"https:\/\/i0.wp.com\/34.121.236.21\/wp-content\/uploads\/2021\/06\/E4ekI80WYAUDN2r-1-300x200.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" \/><figcaption id=\"caption-attachment-17966\" class=\"wp-caption-text\">Vittorio Scelzo<\/figcaption><\/figure>\n<p>Visite che, ovviamente, dovranno avvenire nel rispetto delle norme sanitarie vigenti. \u201cDurante la visita dei nipoti ai propri nonni e dei giovani agli anziani soli, si possono consegnare il messaggio del Papa o pu\u00f2 ascoltare il video, si pu\u00f2 pregare con la preghiera preparata per la Giornata e si pu\u00f2 regalare un fiore o fare un piccolo dono\u201d.<\/p>\n<h4>Un video con il vescovo pi\u00f9 anziano del mondo<\/h4>\n<p>\u201cIl 25 luglio alle 10 \u2013 ha continuato Scelzo &#8211; il Santo Padre celebrer\u00e0 una messa con i nonni e gli anziani\u201d, con un numero ristretto di persone. Inoltre \u201cun suggerimento che ci sentiamo di dare \u00e8 quello di dedicare una memoria particolare agli anziani che sono morti a causa del Coronavirus\u201d. Infine, \u201cfra qualche giorno pubblicheremo il video della preghiera recitata dal Santo Padre insieme ad anziani di ogni parte del mondo\u201d. Tra loro, \u201cil vescovo pi\u00f9 anziano del mondo, un canadese di 101 anni. In questi giorni lanceremo una campagna social ed invitiamo tutti \u2013 in particolare i pi\u00f9 giovani \u2013 a raccontare le visite e le iniziative che nasceranno utilizzando l\u2019hashtag #IamWithYouAlways\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il prefetto del Dicastero per i laici, la famiglia e la vita ha presentato il messaggio del Papa per la Giornata mondiale<\/p>\n","protected":false},"author":16,"featured_media":24136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[73,58,2157,297],"tags":[1820,323,758,992,1821,251,1303,574],"class_list":["post-23327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa-e-mondo","category-featured-news","category-top-ultime-notizie","category-ultime-notizie","tag-anziani","tag-comunita-di-s-egidio","tag-famiglia","tag-laici","tag-nonni","tag-papa-francesco","tag-tenerezza","tag-vita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Mettere al centro i nonni e gli anziani&quot; &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"Mettere al centro nonni e anziani: cos\u00ec il prefetto del Dicastero per i laici, la famiglia e la vita, Farrell, presentando il messaggio del Papa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Mettere al centro i nonni e gli anziani&quot; &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Mettere al centro nonni e anziani: cos\u00ec il prefetto del Dicastero per i laici, la famiglia e la vita, Farrell, presentando il messaggio del Papa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T13:56:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-24T21:23:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/06\/papa-con-anziani-768x480-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Acali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Acali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/\"},\"author\":{\"name\":\"Andrea Acali\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/b8e8ff2fce804e1cda53a9d7b1559b58\"},\"headline\":\"&#8220;Mettere al centro i nonni e gli anziani&#8221;\",\"datePublished\":\"2021-06-22T13:56:16+00:00\",\"dateModified\":\"2021-06-24T21:23:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/\"},\"wordCount\":962,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/papa-con-anziani-768x480-1.jpeg?fit=768%2C480&ssl=1\",\"keywords\":[\"Anziani\",\"Comunit\u00e0 di S. Egidio\",\"famiglia\",\"laici\",\"nonni\",\"Papa Francesco\",\"tenerezza\",\"vita\"],\"articleSection\":[\"Chiesa e Mondo\",\"Featured News\",\"Top Ultime Notizie\",\"Ultime Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/\",\"name\":\"\\\"Mettere al centro i nonni e gli anziani\\\" &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/papa-con-anziani-768x480-1.jpeg?fit=768%2C480&ssl=1\",\"datePublished\":\"2021-06-22T13:56:16+00:00\",\"dateModified\":\"2021-06-24T21:23:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/b8e8ff2fce804e1cda53a9d7b1559b58\"},\"description\":\"Mettere al centro nonni e anziani: cos\u00ec il prefetto del Dicastero per i laici, la famiglia e la vita, Farrell, presentando il messaggio del Papa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/papa-con-anziani-768x480-1.jpeg?fit=768%2C480&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/papa-con-anziani-768x480-1.jpeg?fit=768%2C480&ssl=1\",\"width\":768,\"height\":480,\"caption\":\"\u00a9 Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/mettere-al-centro-i-nonni-e-gli-anziani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Mettere al centro i nonni e gli anziani&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/b8e8ff2fce804e1cda53a9d7b1559b58\",\"name\":\"Andrea Acali\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4ea222b8a5a507f1fb0e11ae86fdca2e5aa45c01e90d0bf7b168dbb9cba667d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4ea222b8a5a507f1fb0e11ae86fdca2e5aa45c01e90d0bf7b168dbb9cba667d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4ea222b8a5a507f1fb0e11ae86fdca2e5aa45c01e90d0bf7b168dbb9cba667d?s=96&d=mm&r=g\",\"caption\":\"Andrea Acali\"},\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dli-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Mettere al centro i nonni e gli anziani\" &#8211; Exaudi","description":"Mettere al centro nonni e anziani: cos\u00ec il prefetto del Dicastero per i laici, la famiglia e la vita, Farrell, presentando il messaggio del Papa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/","og_locale":"it_IT","og_type":"article","og_title":"\"Mettere al centro i nonni e gli anziani\" &#8211; Exaudi","og_description":"Mettere al centro nonni e anziani: cos\u00ec il prefetto del Dicastero per i laici, la famiglia e la vita, Farrell, presentando il messaggio del Papa","og_url":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2021-06-22T13:56:16+00:00","article_modified_time":"2021-06-24T21:23:13+00:00","og_image":[{"width":768,"height":480,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/06\/papa-con-anziani-768x480-1.jpeg","type":"image\/jpeg"}],"author":"Andrea Acali","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Andrea Acali","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/"},"author":{"name":"Andrea Acali","@id":"https:\/\/exaudi.org\/#\/schema\/person\/b8e8ff2fce804e1cda53a9d7b1559b58"},"headline":"&#8220;Mettere al centro i nonni e gli anziani&#8221;","datePublished":"2021-06-22T13:56:16+00:00","dateModified":"2021-06-24T21:23:13+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/"},"wordCount":962,"image":{"@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/papa-con-anziani-768x480-1.jpeg?fit=768%2C480&ssl=1","keywords":["Anziani","Comunit\u00e0 di S. Egidio","famiglia","laici","nonni","Papa Francesco","tenerezza","vita"],"articleSection":["Chiesa e Mondo","Featured News","Top Ultime Notizie","Ultime Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/","url":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/","name":"\"Mettere al centro i nonni e gli anziani\" &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/papa-con-anziani-768x480-1.jpeg?fit=768%2C480&ssl=1","datePublished":"2021-06-22T13:56:16+00:00","dateModified":"2021-06-24T21:23:13+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/b8e8ff2fce804e1cda53a9d7b1559b58"},"description":"Mettere al centro nonni e anziani: cos\u00ec il prefetto del Dicastero per i laici, la famiglia e la vita, Farrell, presentando il messaggio del Papa","breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/papa-con-anziani-768x480-1.jpeg?fit=768%2C480&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/papa-con-anziani-768x480-1.jpeg?fit=768%2C480&ssl=1","width":768,"height":480,"caption":"\u00a9 Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/mettere-al-centro-i-nonni-e-gli-anziani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"&#8220;Mettere al centro i nonni e gli anziani&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/b8e8ff2fce804e1cda53a9d7b1559b58","name":"Andrea Acali","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d4ea222b8a5a507f1fb0e11ae86fdca2e5aa45c01e90d0bf7b168dbb9cba667d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4ea222b8a5a507f1fb0e11ae86fdca2e5aa45c01e90d0bf7b168dbb9cba667d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4ea222b8a5a507f1fb0e11ae86fdca2e5aa45c01e90d0bf7b168dbb9cba667d?s=96&d=mm&r=g","caption":"Andrea Acali"},"url":"https:\/\/exaudi.org\/it\/author\/dli-org\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-64f","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/papa-con-anziani-768x480-1.jpeg?fit=768%2C480&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/23327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=23327"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/23327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/24136"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=23327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=23327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=23327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}