{"id":176845,"date":"2026-06-25T18:29:28","date_gmt":"2026-06-25T16:29:28","guid":{"rendered":"https:\/\/exaudi.org\/?p=176845"},"modified":"2026-06-25T18:29:28","modified_gmt":"2026-06-25T16:29:28","slug":"santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/","title":{"rendered":"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">A 28 anni, quando molti giovani sognano di consolidare una carriera professionale, raggiungere la stabilit\u00e0 economica o avanzare nel proprio lavoro,\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Santiago Valderrama Henao<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0ha preso una decisione radicale: abbandonare una promettente carriera da avvocato per rispondere a una chiamata che risuonava silenziosamente dentro di lui da anni, quella di diventare sacerdote.<\/span><\/span><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il cammino per diventare sacerdote<\/span><\/span><\/strong><\/p>\n<div class=\"wp-block-embed__wrapper\">\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Santiago appartiene alla\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">diocesi di El Espinal, in Colombia<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> , e risiede presso il\u00a0 <\/span><\/span><a href=\"https:\/\/seminariobidasoa.org\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/seminariobidasoa.org\/\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Seminario Internazionale Bidasoa<\/span><\/span><\/a><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> di Pamplona, \u200b\u200bdove sta completando il\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">primo anno di formazione sacerdotale<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0e gli studi di filosofia presso le Facolt\u00e0 Ecclesiastiche dell&#8217;Universit\u00e0 di Navarra.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La sua storia non nasce da una crisi personale, da un fallimento professionale o dalla disillusione nei confronti del mondo. Tutt&#8217;altro. &#8221; <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ero completamente soddisfatto della mia carriera,\u00a0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> della mia professione e della vita che conducevo&#8221;, afferma. Ed \u00e8 proprio per questo che la sua testimonianza ha un peso cos\u00ec grande: perch\u00e9 dimostra che\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">la\u00a0 <\/span><\/span><a href=\"https:\/\/fundacioncarf.org\/sacerdocio\/vocacion-sacerdotal\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/sacerdocio\/vocacion-sacerdotal\/\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">vocazione al sacerdozio<\/span><\/span><\/a><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0non \u00e8 una fuga,<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0ma una libera risposta all&#8217;invito di Dio.<\/span><\/span><\/p>\n<h3 class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Per lui tutto \u00e8 nuovo.<\/span><\/span><\/strong><\/h3>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Quando il suo vescovo, un ex allievo di Bidasoa, gli propose la possibilit\u00e0 di recarsi a Pamplona per la sua formazione, Santiago prov\u00f2 una gioia immensa. &#8221; <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ero entusiasta all&#8217;idea di potermi formare in un luogo con un programma strutturato<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> , un&#8217;atmosfera di studio intenso e una solida vita spirituale, cos\u00ec utile per le vocazioni sacerdotali e, soprattutto, per crescere nella santit\u00e0&#8221;.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Per lui \u00e8 tutto nuovo.<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0Il primo anno a Bidasoa. Il primo anno di seminario. Il primo anno di filosofia. Ma anche l&#8217;inizio di una vita completamente diversa.<\/span><\/span><\/p>\n<h3 class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Una brillante carriera da avvocato<\/span><\/span><\/strong><\/h3>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Prima di arrivare a Pamplona, \u200b\u200bSantiago aveva costruito una brillante carriera in ambito legale. Nel 2020 si \u00e8 laureato in Giurisprudenza e successivamente ha conseguito due\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">specializzazioni\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> , una in Diritto Finanziario e l&#8217;altra in Diritto Commerciale. Per quasi cinque anni ha lavorato prima in una banca e poi in uno studio legale.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Tuttavia, sotto quell&#8217;apparente tranquillit\u00e0, continuava a covare un&#8217;inquietudine ben pi\u00f9 profonda. &#8220;Fin da giovanissimo, ho sentito\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">in me un desiderio particolare per il sacerdozio<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> &#8220;, ricorda.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Durante gli anni universitari e i primi anni della mia carriera professionale, quella vocazione si \u00e8 fatta pi\u00f9 sfumata, forse oscurata dal ritmo frenetico della vita quotidiana, dagli obiettivi professionali e dai progetti personali. Ma Dio era ancora in attesa.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il momento decisivo arriv\u00f2 nel 2023, durante il Cammino di Santiago<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> . Mentre meditava sulla vita dell&#8217;apostolo, una domanda gli trafisse il cuore: &#8220;Se lui ha dato tutta la sua vita per Dio, cosa sto facendo io?&#8221;.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Quella domanda non scomparve. Pi\u00f9 tardi,\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">mentre si trovava a Siviglia, ebbe un&#8217;esperienza interiore che avrebbe segnato definitivamente la sua vita<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> . &#8220;Ho percepito che Dio mi invitava a fare quel passo e, in un certo senso, ho sentito che Lui, nel pieno rispetto della mia libert\u00e0, mi stava facendo capire che quello era il momento.&#8221;<\/span><\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-176668 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Obispo-768x1024-1.jpg?resize=768%2C1024&amp;ssl=1\" alt=\"\" width=\"768\" height=\"1024\" data-recalc-dims=\"1\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Obispo-768x1024-1.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Obispo-768x1024-1.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Obispo-768x1024-1.jpg?resize=500%2C667&amp;ssl=1 500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/p>\n<h3 class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Una vita professionale dedicata a Dio<\/span><\/span><\/strong><\/h3>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Decise quindi di rivolgersi alla Chiesa per iniziare un\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">serio percorso di discernimento.<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0E trov\u00f2 qualcosa che ora interpreta come provvidenziale: un&#8217;accoglienza che conferm\u00f2 ci\u00f2 che sentiva da tempo dentro di s\u00e9.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Lungi dal rinnegare il suo passato, Santiago guarda con gratitudine agli anni della sua attivit\u00e0 professionale.\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">&#8220;La mia vita professionale, che ora affido con gratitudine a Dio, mi ha insegnato moltissimo.<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0Mi ha aiutato a strutturare un modo di pensare, un linguaggio e un modo concreto di relazionarmi con le persone e con la realt\u00e0.&#8221;<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La sua storia sfata anche un altro stereotipo: quello secondo cui le vocazioni sacerdotali nascono necessariamente in contesti di dolore o sofferenza. Egli insiste sul fatto di\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">non aver abbandonato la carriera legale per frustrazione<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> . &#8220;\u00c8 stato semplicemente un invito di Dio che ho deciso di accettare&#8221;.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Proviene da una famiglia cattolica<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0e la radice della sua vocazione \u00e8 profondamente legata alla sua famiglia, dove la fede ha sempre occupato un posto di rilievo. I suoi genitori, Luis Gabriel e Luz Amparo, insieme ai nonni,\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">le hanno trasmesso una solida educazione cristiana.<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0Ha due sorelle maggiori e una nipote, e riconosce di aver imparato in famiglia &#8220;il valore dell&#8217;impegno, del lavoro ben fatto e delle intenzioni rette&#8221;.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Tra tutti i ricordi della sua infanzia, ce n&#8217;\u00e8 uno che non ha mai dimenticato.<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0&#8220;Una volta, quando ero molto piccolo, mia nonna Georgina mi chiese di recitare il Padre Nostro. Iniziai con sicurezza, ma a un certo punto non riuscii a continuare perch\u00e9 non lo ricordavo bene. Mi sentii molto imbarazzato e anche molto triste.&#8221;<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nel corso degli anni, comprese che quella scena apparentemente semplice aveva lasciato un segno profondo nella sua anima. &#8220;Ho capito, fin da bambino,\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">che la fede non poteva essere ridotta a qualcosa di superficiale,<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0ma doveva essere veramente radicata nel cuore&#8221;.\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Oggi, questa convinzione sostiene tutta la sua vocazione.<\/span><\/span><\/strong><\/p>\n<\/div>\n<div class=\"wp-block-embed__wrapper\">\n<h3 id=\"colombia-una-compleja-pluralidad-espiritual\" class=\"wp-block-heading\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Colombia, una pluralit\u00e0 complessa<\/span><\/span><\/strong><\/h3>\n<p class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La sua visione della Colombia \u00e8 intrisa di realismo, ma anche di speranza.\u00a0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> Parla con affetto della sua diocesi di El Espinal, situata nel dipartimento di Tolima, una Chiesa molto vicina alla realt\u00e0 della gente e segnata da enormi sfide pastorali.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il testo descrive una\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">grande diocesi caratterizzata da alti livelli di povert\u00e0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0e difficolt\u00e0 di comunicazione dovute alle pessime condizioni delle strade di accesso. In questo contesto, la secolarizzazione si manifesta non tanto come indifferenza religiosa, quanto piuttosto come\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">un complesso pluralismo spirituale.<\/span><\/span><\/strong><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abEsiste una presenza significativa di comunit\u00e0 evangeliche che svolgono un&#8217;intensa attivit\u00e0 pastorale\u00bb, spiega. \u00abMa ci sono anche fenomeni pi\u00f9 informali, gruppi privi di una struttura ecclesiale sufficiente, e persino pratiche legate\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">all&#8217;esoterismo o alla Santer\u00eda\u00bb.<\/span><\/span><\/strong><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">A tutto ci\u00f2 si aggiungono i problemi strutturali della Colombia:\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">la violenza in alcune regioni,<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0la normalizzazione delle attivit\u00e0 illegali e la crescente tensione politica. Santiago ritiene che il Paese stia attraversando un periodo di ridotta stabilit\u00e0 istituzionale e di mancanza di chiarezza strategica nella pubblica amministrazione, una situazione che incide direttamente sulla vita quotidiana della popolazione.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">&#8220;Tutto ci\u00f2 ha ripercussioni sulla convivenza sociale, sulle speranze delle persone<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0e sulla possibilit\u00e0 di costruire una societ\u00e0 pi\u00f9 stabile.&#8221;<\/span><\/span><\/p>\n<h3 id=\"el-papel-esencial-de-la-iglesia-y-la-falta-de-sacerdotes\" class=\"wp-block-heading\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il ruolo della Chiesa e la carenza di sacerdoti<\/span><\/span><\/strong><\/h3>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">In questo contesto, la Chiesa cattolica svolge un ruolo essenziale. &#8220;Accompagna le persone nella loro vita spirituale, sostiene la vita sacramentale ed\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00e8 presente anche in molti ambiti del servizio pubblico&#8221;.<\/span><\/span><\/strong><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">In molti luoghi, rimane un&#8217;istituzione profondamente rispettata per la sua vicinanza nei momenti difficili e per la sua capacit\u00e0 di agire con moderazione e discernimento durante le crisi sociali e nei periodi in cui la pace e la tranquillit\u00e0 vengono meno in altre parti del paese.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ma c&#8217;\u00e8 una realt\u00e0 che preoccupa particolarmente Santiago: la carenza di sacerdoti.\u00a0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> &#8220;Il numero di sacerdoti non \u00e8 sufficiente a soddisfare adeguatamente tutte le esigenze pastorali&#8221;. Nella sua diocesi, si registra un notevole\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">squilibrio tra il numero di parrocchie e il numero di sacerdoti disponibili.<\/span><\/span><\/strong><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Un altro punto di potenziale tensione per il futuro \u00e8 l&#8217;\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">et\u00e0 media del clero,<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0che si avvicina ai sessant&#8217;anni, e il numero di seminaristi non \u00e8 ancora sufficiente a garantire il ricambio generazionale.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Tuttavia, lungi dal parlare con un atteggiamento disfattista, egli parla con una serenit\u00e0, una pace e una fede che ispirano la preghiera per le vocazioni sacerdotali in Colombia e in tutto il mondo. &#8220;Una vocazione \u00e8 un dono di Dio e\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">la Chiesa non si sostiene in base a criteri statistici&#8221;.<\/span><\/span><\/strong><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-176665 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Diocesis.jpg?resize=1000%2C667&amp;ssl=1\" alt=\"\" width=\"1000\" height=\"667\" data-recalc-dims=\"1\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Diocesis.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Diocesis.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Diocesis.jpg?resize=770%2C514&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Diocesis.jpg?resize=360%2C240&amp;ssl=1 360w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago-Valderrama-Diocesis.jpg?resize=500%2C334&amp;ssl=1 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h3 id=\"el-reto-pastoral-de-su-diocesis\" class=\"wp-block-heading\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La sfida pastorale della sua diocesi El Espinal<\/span><\/span><\/strong><\/h3>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La grande sfida pastorale di El Espinal \u00e8 immensa: servire una diocesi di quasi 14.000 chilometri quadrati e\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">quasi un milione di abitanti, con numerose aree rurali, tutte molto disperse.\u00a0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> Tutti i sacerdoti si impegnano a rafforzare la formazione cristiana e ad accompagnare in particolare i giovani e coloro che sono in cerca di vocazione.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">I giovani sono al centro delle sue riflessioni<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .\u00a0 <\/span><span dir=\"auto\" style=\"vertical-align: inherit\">Santiago Valderrama Henao riconosce che\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">le chiese evangeliche e protestanti sono cresciute significativamente<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0negli ultimi anni in Colombia, anche in aree tradizionalmente cattoliche dove ora rappresentano una minoranza. Ritiene che parte di questa espansione sia dovuta alla\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">scarsa formazione religiosa di molti fedeli e alla difficolt\u00e0 della Chiesa di raggiungere tutte le regioni<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<h3 class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Annunciare il Vangelo <\/span><\/span><\/strong>\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">con vicinanza<\/span><\/span><\/strong><\/h3>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Egli per\u00f2 evita qualsiasi tono aggressivo o conflittuale. Al contrario, insiste sul fatto che la risposta debba essere la vicinanza e l&#8217;autentica proclamazione del Vangelo. \u00ab <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La Chiesa rinnova la sua missione apostolica annunciando il Vangelo con vicinanza.\u00a0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> Seguendo l&#8217;esempio del Signore con la donna samaritana: conoscendo la persona, comprendendola e accompagnandola\u00bb.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Si rammarica inoltre del fatto che in alcuni gruppi religiosi le persone possano subire rifiuto o maltrattamenti quando abbandonano tali comunit\u00e0. &#8220;Queste situazioni, inutile dirlo, non corrispondono alla logica cristiana dell&#8217;amore e della carit\u00e0&#8221;.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Per lui, l&#8217;evangelizzazione non pu\u00f2 basarsi unicamente su discorsi o strategie.\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Deve scaturire dalla testimonianza e dall&#8217;incontro personale con Cristo.<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0&#8220;\u00c8 la testimonianza di vicinanza e la proposta positiva di fede che permettono alla verit\u00e0 del Vangelo di maturare nel cuore di ciascuno&#8221;.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">E aggiunge una riflessione profondamente spirituale, evocando Sant&#8217;Agostino e il suo incontro con Sant&#8217;Ambrogio: &#8220;Non \u00e8 tanto una conquista fatta unicamente per iniziativa propria, quanto Cristo stesso che viene incontro alla persona&#8221;.<\/span><\/span><\/p>\n<h3 id=\"el-fenomeno-de-la-secularizacion-europea\" class=\"wp-block-heading\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">secolarizzazione europea<\/span><\/span><\/strong><\/h3>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Da quando \u00e8 arrivato in Spagna per studiare, Santiago ha anche osservato attentamente il fenomeno della secolarizzazione nella vecchia Europa.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00c8 particolarmente colpito dalla\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">&#8220;scarsa presenza di bambini e giovani nelle chiese<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> &#8220;, nonch\u00e9 dalla differenza di partecipazione\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">tra uomini e donne alla vita ecclesiale<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> , con una maggiore presenza di queste ultime.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Tuttavia, egli sottolinea anche il ruolo fondamentale svolto da molti\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">immigrati latinoamericani<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0nelle parrocchie spagnole. &#8220;In molti casi, contribuiscono in modo visibile al sostentamento delle comunit\u00e0 parrocchiali&#8221;.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Eppure, non si lascia sopraffare dal pessimismo. Al contrario. Durante esperienze come le\u00a0 Javieradas, il Giubileo dell&#8217;Anno della Misericordia, o <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">la vita<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> universitaria \u00a0e parrocchiale in Navarra, ha scoperto &#8220;una Chiesa gioiosa, impegnata e sincera&#8221;.<\/span><\/span><\/p>\n<h3 class=\"wp-block-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La santit\u00e0, la chiave per il sacerdote del XXI secolo.<\/span><\/span><\/strong><\/h3>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Quando parla del sacerdote del XXI secolo, la sua risposta \u00e8 chiara e incisiva. Non parla innanzitutto di abilit\u00e0 sociali, capacit\u00e0 gestionali o tecnologia: parla di santit\u00e0.\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abUn sacerdote del XXI secolo, proprio come uno del V, XII o XXV secolo,<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0deve essere, prima di tutto, un uomo concentrato sulla sua\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">santit\u00e0.<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0Cio\u00e8, un uomo che sia un profondo amico di Dio\u00bb.<\/span><\/span><\/p>\n<p class=\"wp-block-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Forse \u00e8 proprio qui che risiede il cuore di tutta la sua storia. La storia di un giovane avvocato colombiano che avrebbe potuto condurre una vita agiata e di successo, ma che un giorno si \u00e8 lasciato interpellare da una domanda semplice e radicale: &#8220;Cosa sto facendo?&#8221;. E che ha deciso di rispondere affidandosi completamente a Dio.<\/span><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santiago Valderrama, avvocato colombiano, ha abbandonato la sua brillante carriera professionale per prepararsi al sacerdozio e intraprendere il percorso di studi in seminario a Pamplona, \u200b\u200brispondendo con gratitudine e libert\u00e0 alla chiamata di Dio<\/p>\n","protected":false},"author":119,"featured_media":176676,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[73,97],"tags":[117307,117310,2458,117308,117309,11577,18381,3356,1370,117311,117312,44990,16301,64787,13555,1596,15444],"class_list":["post-176845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa-e-mondo","category-testimoni","tag-avvocato-colombiano","tag-chiesa-cattolica-in-colombia","tag-colombia-it","tag-da-avvocato-a-sacerdote","tag-diocesi-di-el-espinal","tag-fondazione-carf","tag-pamplona-2","tag-sacerdote-it","tag-sacerdozio","tag-santiago-valderrama-henao-2","tag-seminario-bidasoa-2","tag-seminario-internazionale-bidasoa","tag-testimonianza-vocazionale","tag-trending-it-236","tag-universita-di-navarra","tag-vocazione","tag-vocazione-sacerdotale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Santiago Valderrama, avvocato colombiano, ha abbandonato la sua brillante carriera professionale per prepararsi al sacerdozio e intraprendere il percorso di studi in seminario a Pamplona, \u200b\u200brispondendo con gratitudine e libert\u00e0 alla chiamata di Dio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/fundacioncarf\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T16:29:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1376\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fundaci\u00f3n CARF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/fundacioncarf\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fundaci\u00f3n CARF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/\"},\"author\":{\"name\":\"Fundaci\u00f3n CARF\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/fab8261a088ccf38cb54b3c50baa7baf\"},\"headline\":\"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote\",\"datePublished\":\"2026-06-25T16:29:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/\"},\"wordCount\":1744,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Santiago.jpg?fit=1376%2C768&ssl=1\",\"keywords\":[\"Avvocato colombiano\",\"Chiesa Cattolica in Colombia\",\"Colombia\",\"Da avvocato a sacerdote\",\"Diocesi di El Espinal\",\"FONDAZIONE CARF\",\"PAMPLONA\",\"Sacerdote\",\"sacerdozio\",\"Santiago Valderrama Henao\",\"Seminario Bidasoa\",\"Seminario Internazionale Bidasoa\",\"TESTIMONIANZA VOCAZIONALE\",\"Trending\",\"UNIVERSIT\u00c0 DI NAVARRA\",\"vocazione\",\"VOCAZIONE SACERDOTALE\"],\"articleSection\":[\"Chiesa e Mondo\",\"Testimoni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/\",\"name\":\"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Santiago.jpg?fit=1376%2C768&ssl=1\",\"datePublished\":\"2026-06-25T16:29:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/fab8261a088ccf38cb54b3c50baa7baf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Santiago.jpg?fit=1376%2C768&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Santiago.jpg?fit=1376%2C768&ssl=1\",\"width\":1376,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/fab8261a088ccf38cb54b3c50baa7baf\",\"name\":\"Fundaci\u00f3n CARF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab292d3529973c0d1cf4cda9208c6a8a7ee52923f0a291c39104715fa46aae4b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab292d3529973c0d1cf4cda9208c6a8a7ee52923f0a291c39104715fa46aae4b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab292d3529973c0d1cf4cda9208c6a8a7ee52923f0a291c39104715fa46aae4b?s=96&d=mm&r=g\",\"caption\":\"Fundaci\u00f3n CARF\"},\"description\":\"Trabajamos para llevar la sonrisa de Dios a todos los rincones del mundo a trav\u00e9s de los sacerdotes y ayudando a su formaci\u00f3n. Gracias a nuestros benefactores, ayudamos a la formaci\u00f3n de los sacerdotes, difundimos su buen nombre y rezamos por su fidelidad y las vocaciones. Trabajamos para servir a la Iglesia y que ninguna vocaci\u00f3n se pierda y luego ellos puedan transmitir en su labor pastoral toda la luz, ciencia y doctrina recibida. Acad\u00e9mico Las licenciaturas, programas de especializacio\u0301n o doctorados, otorgan a cada candidato una formaci\u00f3n espec\u00edfica en Teologi\u0301a, Filosofi\u0301a, Derecho Cano\u0301nico o Comunicacio\u0301n Social Institucional. Espiritual Los seminaristas y sacerdotes complementan su formacio\u0301n acade\u0301mica y humana con la espiritual, ya que deben estar preparados para seguir su vocaci\u00f3n y prestar su cuerpo y su espi\u0301ritu al Sen\u0303or. Humano A trave\u0301s del ambiente de familia y de preparaci\u00f3n, se consigue el desarrollo de actitudes, capacidades y valores que impactan en el crecimiento personal y social de los sacerdotes.\",\"sameAs\":[\"https:\\\/\\\/fundacioncarf.org\\\/\",\"https:\\\/\\\/www.facebook.com\\\/fundacioncarf\\\/\",\"https:\\\/\\\/www.instagram.com\\\/fundacioncarf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacioncarf\\\/posts\\\/?feedView=all\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/fundacioncarf\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/fundacioncarf\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/carf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/","og_locale":"it_IT","og_type":"article","og_title":"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote &#8211; Exaudi","og_description":"Santiago Valderrama, avvocato colombiano, ha abbandonato la sua brillante carriera professionale per prepararsi al sacerdozio e intraprendere il percorso di studi in seminario a Pamplona, \u200b\u200brispondendo con gratitudine e libert\u00e0 alla chiamata di Dio","og_url":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/fundacioncarf\/","article_published_time":"2026-06-25T16:29:28+00:00","og_image":[{"width":1376,"height":768,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago.jpg","type":"image\/jpeg"}],"author":"Fundaci\u00f3n CARF","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/fundacioncarf","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Fundaci\u00f3n CARF","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/"},"author":{"name":"Fundaci\u00f3n CARF","@id":"https:\/\/exaudi.org\/#\/schema\/person\/fab8261a088ccf38cb54b3c50baa7baf"},"headline":"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote","datePublished":"2026-06-25T16:29:28+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/"},"wordCount":1744,"image":{"@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago.jpg?fit=1376%2C768&ssl=1","keywords":["Avvocato colombiano","Chiesa Cattolica in Colombia","Colombia","Da avvocato a sacerdote","Diocesi di El Espinal","FONDAZIONE CARF","PAMPLONA","Sacerdote","sacerdozio","Santiago Valderrama Henao","Seminario Bidasoa","Seminario Internazionale Bidasoa","TESTIMONIANZA VOCAZIONALE","Trending","UNIVERSIT\u00c0 DI NAVARRA","vocazione","VOCAZIONE SACERDOTALE"],"articleSection":["Chiesa e Mondo","Testimoni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/","url":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/","name":"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago.jpg?fit=1376%2C768&ssl=1","datePublished":"2026-06-25T16:29:28+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/fab8261a088ccf38cb54b3c50baa7baf"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago.jpg?fit=1376%2C768&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago.jpg?fit=1376%2C768&ssl=1","width":1376,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/santiago-colombiano-ha-lasciato-una-brillante-carriera-per-diventare-sacerdote\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Santiago, colombiano, ha lasciato una brillante carriera per diventare sacerdote"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/fab8261a088ccf38cb54b3c50baa7baf","name":"Fundaci\u00f3n CARF","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ab292d3529973c0d1cf4cda9208c6a8a7ee52923f0a291c39104715fa46aae4b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ab292d3529973c0d1cf4cda9208c6a8a7ee52923f0a291c39104715fa46aae4b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab292d3529973c0d1cf4cda9208c6a8a7ee52923f0a291c39104715fa46aae4b?s=96&d=mm&r=g","caption":"Fundaci\u00f3n CARF"},"description":"Trabajamos para llevar la sonrisa de Dios a todos los rincones del mundo a trav\u00e9s de los sacerdotes y ayudando a su formaci\u00f3n. Gracias a nuestros benefactores, ayudamos a la formaci\u00f3n de los sacerdotes, difundimos su buen nombre y rezamos por su fidelidad y las vocaciones. Trabajamos para servir a la Iglesia y que ninguna vocaci\u00f3n se pierda y luego ellos puedan transmitir en su labor pastoral toda la luz, ciencia y doctrina recibida. Acad\u00e9mico Las licenciaturas, programas de especializacio\u0301n o doctorados, otorgan a cada candidato una formaci\u00f3n espec\u00edfica en Teologi\u0301a, Filosofi\u0301a, Derecho Cano\u0301nico o Comunicacio\u0301n Social Institucional. Espiritual Los seminaristas y sacerdotes complementan su formacio\u0301n acade\u0301mica y humana con la espiritual, ya que deben estar preparados para seguir su vocaci\u00f3n y prestar su cuerpo y su espi\u0301ritu al Sen\u0303or. Humano A trave\u0301s del ambiente de familia y de preparaci\u00f3n, se consigue el desarrollo de actitudes, capacidades y valores que impactan en el crecimiento personal y social de los sacerdotes.","sameAs":["https:\/\/fundacioncarf.org\/","https:\/\/www.facebook.com\/fundacioncarf\/","https:\/\/www.instagram.com\/fundacioncarf\/","https:\/\/www.linkedin.com\/company\/fundacioncarf\/posts\/?feedView=all","https:\/\/x.com\/https:\/\/x.com\/fundacioncarf","https:\/\/www.youtube.com\/c\/fundacioncarf"],"url":"https:\/\/exaudi.org\/it\/author\/carf\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-K0l","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Santiago.jpg?fit=1376%2C768&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/176845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/119"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=176845"}],"version-history":[{"count":3,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/176845\/revisions"}],"predecessor-version":[{"id":176848,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/176845\/revisions\/176848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/176676"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=176845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=176845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=176845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}