{"id":174042,"date":"2026-06-05T18:15:11","date_gmt":"2026-06-05T16:15:11","guid":{"rendered":"https:\/\/exaudi.org\/?p=174042"},"modified":"2026-06-05T18:15:11","modified_gmt":"2026-06-05T16:15:11","slug":"il-sollievo-dalla-sofferenza","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/","title":{"rendered":"Il sollievo dalla sofferenza"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Le cure palliative, che dovrebbero essere utilizzate quando non \u00e8 possibile guarire il paziente ma alleviarne la sofferenza e accompagnarlo nel percorso della malattia in modo multidisciplinare, non dovrebbero essere rivolte solo all&#8217;et\u00e0 adulta, ma a ogni fase della vita umana.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Affrontare il dolore e la sofferenza nelle <\/span><\/span><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">primissime fasi della vita umana rappresenta una delle maggiori sfide cliniche ed etiche del nostro tempo. Tradizionalmente, l&#8217;assistenza sanitaria ha teso ad estrapolare i modelli di trattamento per adulti alla popolazione pediatrica, un errore fondamentale che la bioetica moderna e gli specialisti in cure palliative pediatriche si sforzano di correggere.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il Comitato Nazionale di Bioetica (CNB), nel suo\u00a0 <\/span><\/span><a href=\"https:\/\/bioetica.governo.it\/media\/fqspzou0\/p155_2025-linee-guida-e-relazione-di-cura.pdf?utm_source=chatgpt.com\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">parere sulle cure palliative pediatriche<\/span><\/span><\/strong><\/a><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0pubblicato nel giugno 2025, insiste sulla necessit\u00e0 di sviluppare l&#8217;assistenza ai bambini attraverso strategie specifiche in ambito clinico, etico e organizzativo. Gli esperti mettono inoltre in guardia dalla necessit\u00e0 di adattare i servizi sanitari alle peculiarit\u00e0 dei pazienti pediatrici, al fine di offrire un&#8217;assistenza completa e di alta qualit\u00e0 sia ai bambini che alle loro famiglie.<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">A che et\u00e0 pu\u00f2 iniziare la sofferenza? Riconoscere il dolore fetale e neonatale<\/span><\/span><\/strong><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Per lungo tempo, l&#8217;assenza di un linguaggio verbale strutturato ha generato dubbi nella comunit\u00e0 scientifica sulla capacit\u00e0 dei feti e dei neonati di\u00a0 <\/span><\/span><a href=\"https:\/\/www.observatoriobioetica.org\/2023\/01\/en-que-semana-comienzan-los-fetos-a-sentir-dolor\/40807\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">percepire il dolore<\/span><\/span><\/strong><\/a><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> . Tuttavia, le attuali evidenze scientifiche sono conclusive: tra la 20a e la 22a settimana di gestazione, la risposta del feto a stimoli potenzialmente dolorosi \u00e8 simile a quella di un adulto a livello comportamentale, biochimico ed elettrofisiologico.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Questa scoperta ha profonde implicazioni bioetiche. L&#8217;uso di analgesici nella prima infanzia dovrebbe essere considerato non solo per alleviare le conseguenze fisiche del dolore, ma anche come un imperativo etico per prevenire la sofferenza in situazioni in cui \u00e8 altamente probabile che si verifichi. Ignorare questo fatto viola il diritto fondamentale di ogni essere umano a essere libero da sofferenze inutili.<\/span><\/span><\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-173870 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-scaled-e1780561969580-scaled.jpg?resize=2560%2C554&#038;ssl=1\" alt=\"\" width=\"2560\" height=\"554\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-scaled-e1780561969580-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-scaled-e1780561969580-scaled.jpg?resize=300%2C65&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-scaled-e1780561969580-scaled.jpg?resize=1024%2C222&amp;ssl=1 1024w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-scaled-e1780561969580-scaled.jpg?resize=770%2C167&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-scaled-e1780561969580-scaled.jpg?resize=1536%2C333&amp;ssl=1 1536w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-scaled-e1780561969580-scaled.jpg?resize=2048%2C444&amp;ssl=1 2048w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-scaled-e1780561969580-scaled.jpg?resize=500%2C108&amp;ssl=1 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Sfatare i miti sulle cure palliative<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> pediatriche<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nonostante <\/span><\/span><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">sia un diritto universalmente riconosciuto, si stima che, a livello globale, solo il 10% circa dei bambini che necessitano di cure palliative le riceva. Come affermano gli esperti dell&#8217;Istituto\u00a0 <\/span><\/span><strong><a href=\"https:\/\/www.observatoriobioetica.org\/wp-content\/uploads\/2026\/06\/Atencion-paliativa-menores-Digital-v1.pdf\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">per una Migliore Assistenza presso l&#8217;Ospedale San Juan de Dios<\/span><\/span><\/a>\u00a0<\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> di Vizcaya, &#8220;questa allarmante disparit\u00e0 \u00e8 dovuta in gran parte alla mancanza di risorse e alla diffusa ignoranza che stigmatizza questo tipo di assistenza&#8221;.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00c8 imperativo sfatare le false credenze che si configurano come barriere insormontabili. Le cure palliative non sono riservate esclusivamente agli ultimi momenti di vita, n\u00e9 equivalgono al preludio alla morte; il loro obiettivo \u00e8 infatti quello di garantire la migliore qualit\u00e0 di vita possibile al paziente fin dal momento stesso della diagnosi di una malattia debilitante. Non sono neanche una risorsa esclusiva per i malati di cancro: nella pratica clinica, il 70% dei bambini trattati in queste unit\u00e0 soffre di malattie genetiche, metaboliche o neurodegenerative, rispetto al 30% affetto da tumore.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Le cure palliative pediatriche rappresentano la cura attiva e completa del corpo, della mente e dello spirito del bambino, estendendo sempre una rete di supporto alla sua famiglia.<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La dimensione perinatale e l&#8217;alleanza terapeutica<\/span><\/span><\/strong><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La necessit\u00e0 di alleviare il dolore e sostenere chi soffre inizia ancor prima della nascita. Quando vengono diagnosticate gravi anomalie fetali con un&#8217;aspettativa di vita limitata, il sistema sanitario deve offrire una strategia coordinata che dia priorit\u00e0 alla qualit\u00e0 della vita sia della donna in gravidanza che del neonato. La gestione clinica di queste gravidanze richiede una rigorosa collaborazione interdisciplinare, che integri ginecologi, neonatologi, genetisti, psicologi e bioeticisti, per evitare che le famiglie affrontino questo difficile percorso da sole.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La recente\u00a0 <\/span><\/span><a href=\"https:\/\/www.dire.it\/28-05-2026\/1243876-salute-nasce-la-carta-di-roma-2026-al-via-alleanza-per-cure-palliative-pediatriche\/?utm_source=chatgpt.com\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u201cCarta di Roma 2026\u201d<\/span><\/span><\/strong><\/a><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0cristallizza questa visione etica attraverso dieci principi fondamentali, ribadendo che le cure palliative sono un diritto civile e sociale imprescindibile. Tra i suoi principi cardine vi sono l&#8217;obbligo di garantire che nessun bambino soffra inutilmente, l&#8217;importanza di non abbandonare le famiglie, la priorit\u00e0 di mantenere i bambini nelle proprie case ogniqualvolta sia possibile, e il dovere di ascoltare il bambino come parte integrante della sua cura.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">I bambini, anche i pi\u00f9 piccoli, hanno bisogno di avere la certezza di non essere abbandonati o ingannati. Hanno il diritto di ricevere informazioni oneste e adeguate alla loro et\u00e0 sulla loro malattia, il che \u00e8 fondamentale per placare le loro paure.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">In definitiva, garantire sollievo dal dolore e dalla sofferenza e l&#8217;accesso alle cure palliative fin dalla pi\u00f9 tenera et\u00e0, persino in epoca prenatale, non \u00e8 semplicemente un atto di compassione medica, ma un imperativo bioetico e una questione di giustizia sociale. Tutelare la dignit\u00e0 in situazioni di estrema vulnerabilit\u00e0 \u00e8 il vero indicatore dell&#8217;umanit\u00e0 del nostro sistema sanitario.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">A differenza del modello italiano, la scandalosa mancanza di attuazione in Spagna di politiche volte a fornire cure palliative di qualit\u00e0 sufficiente a chi ne ha bisogno, in qualsiasi fase della vita, costituisce una grave violazione del dovere di cura quando non \u00e8 possibile guarire.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Le proposte di eutanasia, che tendono a estendersi nel tempo anche all&#8217;et\u00e0 pediatrica, costituiscono la proposta inaccettabile per i pazienti che soffrono e chiedono di morire senza poter accedere all&#8217;alternativa delle cure palliative, che rappresentano il vero aiuto a vivere \u2013 non a morire \u2013 che la dignit\u00e0 umana merita.<\/span><\/span><\/p>\n<p><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Giulio Tudela. Cristina Castello. Osservatorio di Bioetica. Universit\u00e0 Cattolica di Valencia<\/span><\/span><\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un diritto inalienabile fin dall&#8217;inizio della vita<\/p>\n","protected":false},"author":87,"featured_media":173863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[71],"tags":[6083,115337,115338,93730,115339,64538,102264,115342,115343,115344,115346,115345,85244,115340,115341,115336,33192,64787,14154],"class_list":["post-174042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisi","tag-bioetica-it","tag-carta-di-roma-2026","tag-comitato-nazionale-italiano-di-bioetica","tag-cure-palliative-pediatriche","tag-cure-palliative-perinatali","tag-dignita-umana-it-3","tag-diritto-fondamentale","tag-dolore-fetale","tag-dolore-neonatale","tag-eutanasia-pediatrica-2","tag-istituto-per-una-migliore-assistenza","tag-ospedale-san-juan-de-dios-di-vizcaya","tag-osservatorio-di-bioetica-dellucv","tag-sfide-cliniche","tag-sfide-etiche","tag-sollievo-dalla-sofferenza","tag-sostegno-familiare","tag-trending-it-236","tag-universita-cattolica-di-valencia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il sollievo dalla sofferenza &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il sollievo dalla sofferenza &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Un diritto inalienabile fin dall&#039;inizio della vita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/observatoriodebioetica\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-05T16:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-2-scaled.png-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"994\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Observatorio de Bio\u00e9tica UCV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@obioetica\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Observatorio de Bio\u00e9tica UCV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/\"},\"author\":{\"name\":\"Observatorio de Bio\u00e9tica UCV\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/05d1c06e56ecb5490e9bff0d27026595\"},\"headline\":\"Il sollievo dalla sofferenza\",\"datePublished\":\"2026-06-05T16:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/\"},\"wordCount\":860,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/paliativos-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1\",\"keywords\":[\"Bio\u00e9tica\",\"Carta di Roma 2026\",\"Comitato Nazionale Italiano di Bioetica\",\"cure palliative pediatriche\",\"Cure palliative perinatali\",\"Dignit\u00e0 umana\",\"diritto fondamentale\",\"Dolore fetale\",\"Dolore neonatale\",\"Eutanasia pediatrica\",\"Istituto per una migliore assistenza\",\"Ospedale San Juan de Dios di Vizcaya\",\"Osservatorio di bioetica dell'UCV\",\"Sfide cliniche\",\"Sfide etiche\",\"Sollievo dalla sofferenza\",\"sostegno familiare\",\"Trending\",\"UNIVERSIT\u00c0 CATTOLICA DI VALENCIA\"],\"articleSection\":[\"Analisi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/\",\"name\":\"Il sollievo dalla sofferenza &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/paliativos-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1\",\"datePublished\":\"2026-06-05T16:15:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/05d1c06e56ecb5490e9bff0d27026595\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/paliativos-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/paliativos-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1\",\"width\":2560,\"height\":994},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-sollievo-dalla-sofferenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il sollievo dalla sofferenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/05d1c06e56ecb5490e9bff0d27026595\",\"name\":\"Observatorio de Bio\u00e9tica UCV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g\",\"caption\":\"Observatorio de Bio\u00e9tica UCV\"},\"description\":\"El Observatorio de Bio\u00e9tica se encuentra dentro del Instituto Ciencias de la vida de la Universidad Cat\u00f3lica de Valencia \u201cSan Vicente M\u00e1rtir\u201d . En el trasfondo de sus publicaciones, se defiende la vida humana desde la fecundaci\u00f3n a la muerte natural y la dignidad de la persona, teniendo como objetivo aunar esfuerzos para difundir la cultura de la vida como la define la Evangelium Vitae.\",\"sameAs\":[\"https:\\\/\\\/www.observatoriobioetica.org\\\/\",\"https:\\\/\\\/www.facebook.com\\\/observatoriodebioetica\\\/\",\"https:\\\/\\\/x.com\\\/obioetica\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC_Tr4WS5-TXoNo5e1MdQc7w\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/observatoriodebioeticaucv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il sollievo dalla sofferenza &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/","og_locale":"it_IT","og_type":"article","og_title":"Il sollievo dalla sofferenza &#8211; Exaudi","og_description":"Un diritto inalienabile fin dall'inizio della vita","og_url":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/observatoriodebioetica\/","article_published_time":"2026-06-05T16:15:11+00:00","og_image":[{"width":2560,"height":994,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-2-scaled.png-scaled.jpg","type":"image\/jpeg"}],"author":"Observatorio de Bio\u00e9tica UCV","twitter_card":"summary_large_image","twitter_creator":"@obioetica","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Observatorio de Bio\u00e9tica UCV","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/"},"author":{"name":"Observatorio de Bio\u00e9tica UCV","@id":"https:\/\/exaudi.org\/#\/schema\/person\/05d1c06e56ecb5490e9bff0d27026595"},"headline":"Il sollievo dalla sofferenza","datePublished":"2026-06-05T16:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/"},"wordCount":860,"image":{"@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","keywords":["Bio\u00e9tica","Carta di Roma 2026","Comitato Nazionale Italiano di Bioetica","cure palliative pediatriche","Cure palliative perinatali","Dignit\u00e0 umana","diritto fondamentale","Dolore fetale","Dolore neonatale","Eutanasia pediatrica","Istituto per una migliore assistenza","Ospedale San Juan de Dios di Vizcaya","Osservatorio di bioetica dell'UCV","Sfide cliniche","Sfide etiche","Sollievo dalla sofferenza","sostegno familiare","Trending","UNIVERSIT\u00c0 CATTOLICA DI VALENCIA"],"articleSection":["Analisi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/","url":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/","name":"Il sollievo dalla sofferenza &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","datePublished":"2026-06-05T16:15:11+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/05d1c06e56ecb5490e9bff0d27026595"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","width":2560,"height":994},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/il-sollievo-dalla-sofferenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Il sollievo dalla sofferenza"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/05d1c06e56ecb5490e9bff0d27026595","name":"Observatorio de Bio\u00e9tica UCV","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g","caption":"Observatorio de Bio\u00e9tica UCV"},"description":"El Observatorio de Bio\u00e9tica se encuentra dentro del Instituto Ciencias de la vida de la Universidad Cat\u00f3lica de Valencia \u201cSan Vicente M\u00e1rtir\u201d . En el trasfondo de sus publicaciones, se defiende la vida humana desde la fecundaci\u00f3n a la muerte natural y la dignidad de la persona, teniendo como objetivo aunar esfuerzos para difundir la cultura de la vida como la define la Evangelium Vitae.","sameAs":["https:\/\/www.observatoriobioetica.org\/","https:\/\/www.facebook.com\/observatoriodebioetica\/","https:\/\/x.com\/obioetica","https:\/\/www.youtube.com\/channel\/UC_Tr4WS5-TXoNo5e1MdQc7w"],"url":"https:\/\/exaudi.org\/it\/author\/observatoriodebioeticaucv\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-Jh8","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/paliativos-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/174042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=174042"}],"version-history":[{"count":6,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/174042\/revisions"}],"predecessor-version":[{"id":174049,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/174042\/revisions\/174049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/173863"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=174042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=174042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=174042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}