{"id":170890,"date":"2026-05-14T19:26:21","date_gmt":"2026-05-14T17:26:21","guid":{"rendered":"https:\/\/exaudi.org\/?p=170890"},"modified":"2026-05-14T19:26:21","modified_gmt":"2026-05-14T17:26:21","slug":"riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/","title":{"rendered":"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi"},"content":{"rendered":"<p><span dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Monsignor Enrique D\u00edaz D\u00edaz condivide con i lettori di Exaudi la sua riflessione sul Vangelo di questo gioved\u00ec 14 maggio 2026, festa di San Mattia,\u00a0 <\/span><\/span><\/span><span dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">dal titolo:\u00a0 <\/span><\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">&#8220;Non voi avete scelto me, ma io ho scelto voi <\/span><\/span><\/em><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">&#8220;.<\/span><\/span><\/em><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">***<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Atti 1:15-17, 20-26:\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abTirarono a sorte e la sorte cadde su Mattia; cos\u00ec fu aggiunto agli undici apostoli\u00bb.<\/span><\/span><\/em><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Salmo 112:\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abIl Signore lo ha posto tra i capi del suo popolo. Alleluia!\u00bb<\/span><\/span><\/em><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Giovanni 15:9-17:\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abNon voi avete scelto me, ma io ho scelto voi\u00bb.<\/span><\/span><\/em><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Celebrare oggi la festa di San Mattia, scelto come apostolo per sostituire Giuda dopo il suo tradimento, ci offre l&#8217;opportunit\u00e0 di sottolineare le caratteristiche essenziali di ogni discepolo. Quando si cerca il candidato ideale tra i discepoli, si pongono le seguenti condizioni: a) Che conosca Ges\u00f9 fin dal battesimo di Giovanni. b) Che abbia accompagnato Ges\u00f9 nel suo ministero pubblico. c) Che diventi testimone della risurrezione. Questa \u00e8 la via per ogni discepolo: avere un contatto diretto con Ges\u00f9, un incontro che metta a confronto la nostra vita con la proposta che Egli ci rivolge. Questo incontro avviene nella vita ordinaria: ascoltando la sua Parola, conoscendolo attraverso le sue azioni nei Vangeli, pregando, riconoscendolo nei nostri fratelli e sorelle e amandolo nei pi\u00f9 poveri tra noi. \u00c8 un incontro personale con Ges\u00f9; altrimenti, non possiamo definirci discepoli. Ma oltre a conoscerlo, dobbiamo rimanere fedeli alla sua Parola. Molti conobbero Ges\u00f9 e ascoltarono le sue parole, ma nei momenti di difficolt\u00e0 scelsero di allontanarsi da lui. Lo stesso pu\u00f2 accadere anche a noi: possiamo conoscere Ges\u00f9, possiamo apprezzare le sue parole, ma nei momenti decisivi potremmo non seguire il suo esempio e preferire invece le nostre zone di comfort. La fedelt\u00e0 \u00e8 la seconda condizione per essere discepoli. La terza condizione \u00e8 la disponibilit\u00e0 a diventare testimoni della risurrezione. Molti di noi conoscono la morte di Ges\u00f9 e provano compassione per lui. Ma il vero testimone porta al mondo il messaggio della risurrezione di Ges\u00f9: un messaggio di speranza e di vita. Il brano del Vangelo di oggi completa il profilo del discepolo: scelto per amare. Tutto ci\u00f2 che il discepolo fa \u00e8 fondato sull&#8217;amore che Dio Padre ha per noi e che ci ha rivelato in suo Figlio Ges\u00f9. Per questo il discepolo \u00e8 in grado di portare speranza e gioia. Per questo \u00e8 in grado di amare nello stile di Ges\u00f9. Il comandamento che Ges\u00f9 d\u00e0 loro \u00e8 di amarsi gli uni gli altri costantemente e per tutta la vita, come ha fatto lui, dimostrandolo dando la sua vita per loro. Essere discepoli significa amare Ges\u00f9 e amare il prossimo, e l&#8217;amore del discepolo per i suoi fratelli deve essere cos\u00ec grande da essere disposto a dare la propria vita.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>14 maggio, San Mattia Apostolo<\/p>\n","protected":false},"author":25,"featured_media":170773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[73,95],"tags":[102348,10963,112904,64787,706],"class_list":["post-170890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa-e-mondo","category-spiritualita","tag-commentario","tag-enrique-diaz-2","tag-san-mattia-apostolo","tag-trending-it-236","tag-vangelo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"14 maggio, San Mattia Apostolo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-14T17:26:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/05\/san-Matias.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Enrique D\u00edaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enrique D\u00edaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/\"},\"author\":{\"name\":\"Enrique D\u00edaz\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c02ffbd10830fa375f6882f7dcf1844d\"},\"headline\":\"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi\",\"datePublished\":\"2026-05-14T17:26:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/\"},\"wordCount\":462,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/san-Matias.png?fit=1280%2C1280&ssl=1\",\"keywords\":[\"Commentario\",\"ENRIQUE D\u00cdAZ\",\"San Mattia Apostolo\",\"Trending\",\"Vangelo\"],\"articleSection\":[\"Chiesa e Mondo\",\"Spiritualit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/\",\"name\":\"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/san-Matias.png?fit=1280%2C1280&ssl=1\",\"datePublished\":\"2026-05-14T17:26:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c02ffbd10830fa375f6882f7dcf1844d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/san-Matias.png?fit=1280%2C1280&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/san-Matias.png?fit=1280%2C1280&ssl=1\",\"width\":1280,\"height\":1280,\"caption\":\"San Mattia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c02ffbd10830fa375f6882f7dcf1844d\",\"name\":\"Enrique D\u00edaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g\",\"caption\":\"Enrique D\u00edaz\"},\"description\":\"Naci\u00f3 en Huandacareo, Michoac\u00e1n, M\u00e9xico, en 1952. Realiz\u00f3 sus estudios de Filosof\u00eda y Teolog\u00eda en el Seminario de Morelia. Ordenado di\u00e1cono el 22 de mayo de 1977, y presb\u00edtero el 23 de octubre del mismo a\u00f1o. Obtuvo la Licenciatura en Sagrada Escritura en el Pontificio Instituto B\u00edblico en Roma. Ha desarrollado m\u00faltiples encargos pastorales como el de capell\u00e1n de la rector\u00eda de las Tres Aves Mar\u00edas; responsable de la Pastoral B\u00edblica Diocesana y director de la Escuela B\u00edblica en Morelia; maestro de Biblia en el Seminario Conciliar de Morelia, p\u00e1rroco de la Parroquia de Nuestra Se\u00f1ora de Guadalupe, Col. Guadalupe, Morelia; o vicario episcopal para la Zona de Nuestra Se\u00f1ora de la Luz, P\u00e1tzcuaro. Ordenado obispo auxiliar de san Crist\u00f3bal de las Casas en 2003. En la Conferencia Episcopal form\u00f3 parte de las Comisiones de Biblia, Diaconado y Ministerios Laicales. Fue responsable de las Dimensiones de Ministerios Laicales, de Educaci\u00f3n y Cultura. Ha participado en encuentros latinoamericanos y mundiales sobre el Diaconado Permanente. Actualmente es el responsable de la Dimensi\u00f3n de Pastoral de la Cultura. Particip\u00f3 como Miembro del S\u00ednodo de Obispos sobre la Palabra de Dios en la Vida y Misi\u00f3n de la Iglesia en Roma, en 2008. Recibi\u00f3 el nombramiento de obispo coadjutor de San Crist\u00f3bal de las Casas en 2014. Nombrado II obispo de Irapuato el d\u00eda 11 de marzo, tom\u00f3 posesi\u00f3n el 19 de Mayo. Colabora en varias revistas y publicaciones sobre todo con la reflexi\u00f3n diaria y dominical tanto en audio como escrita.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/enriquediaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/","og_locale":"it_IT","og_type":"article","og_title":"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi &#8211; Exaudi","og_description":"14 maggio, San Mattia Apostolo","og_url":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2026-05-14T17:26:21+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/05\/san-Matias.png","type":"image\/png"}],"author":"Enrique D\u00edaz","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Enrique D\u00edaz","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/"},"author":{"name":"Enrique D\u00edaz","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c02ffbd10830fa375f6882f7dcf1844d"},"headline":"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi","datePublished":"2026-05-14T17:26:21+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/"},"wordCount":462,"image":{"@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/san-Matias.png?fit=1280%2C1280&ssl=1","keywords":["Commentario","ENRIQUE D\u00cdAZ","San Mattia Apostolo","Trending","Vangelo"],"articleSection":["Chiesa e Mondo","Spiritualit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/","url":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/","name":"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/san-Matias.png?fit=1280%2C1280&ssl=1","datePublished":"2026-05-14T17:26:21+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/c02ffbd10830fa375f6882f7dcf1844d"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/san-Matias.png?fit=1280%2C1280&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/san-Matias.png?fit=1280%2C1280&ssl=1","width":1280,"height":1280,"caption":"San Mattia"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/riflessione-del-vescovo-enrique-diaz-non-voi-avete-scelto-me-ma-io-ho-scelto-voi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Riflessione del Vescovo Enrique D\u00edaz: Non voi avete scelto me, ma io ho scelto voi"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c02ffbd10830fa375f6882f7dcf1844d","name":"Enrique D\u00edaz","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g","caption":"Enrique D\u00edaz"},"description":"Naci\u00f3 en Huandacareo, Michoac\u00e1n, M\u00e9xico, en 1952. Realiz\u00f3 sus estudios de Filosof\u00eda y Teolog\u00eda en el Seminario de Morelia. Ordenado di\u00e1cono el 22 de mayo de 1977, y presb\u00edtero el 23 de octubre del mismo a\u00f1o. Obtuvo la Licenciatura en Sagrada Escritura en el Pontificio Instituto B\u00edblico en Roma. Ha desarrollado m\u00faltiples encargos pastorales como el de capell\u00e1n de la rector\u00eda de las Tres Aves Mar\u00edas; responsable de la Pastoral B\u00edblica Diocesana y director de la Escuela B\u00edblica en Morelia; maestro de Biblia en el Seminario Conciliar de Morelia, p\u00e1rroco de la Parroquia de Nuestra Se\u00f1ora de Guadalupe, Col. Guadalupe, Morelia; o vicario episcopal para la Zona de Nuestra Se\u00f1ora de la Luz, P\u00e1tzcuaro. Ordenado obispo auxiliar de san Crist\u00f3bal de las Casas en 2003. En la Conferencia Episcopal form\u00f3 parte de las Comisiones de Biblia, Diaconado y Ministerios Laicales. Fue responsable de las Dimensiones de Ministerios Laicales, de Educaci\u00f3n y Cultura. Ha participado en encuentros latinoamericanos y mundiales sobre el Diaconado Permanente. Actualmente es el responsable de la Dimensi\u00f3n de Pastoral de la Cultura. Particip\u00f3 como Miembro del S\u00ednodo de Obispos sobre la Palabra de Dios en la Vida y Misi\u00f3n de la Iglesia en Roma, en 2008. Recibi\u00f3 el nombramiento de obispo coadjutor de San Crist\u00f3bal de las Casas en 2014. Nombrado II obispo de Irapuato el d\u00eda 11 de marzo, tom\u00f3 posesi\u00f3n el 19 de Mayo. Colabora en varias revistas y publicaciones sobre todo con la reflexi\u00f3n diaria y dominical tanto en audio como escrita.","url":"https:\/\/exaudi.org\/it\/author\/enriquediaz\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-Isi","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/san-Matias.png?fit=1280%2C1280&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/170890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=170890"}],"version-history":[{"count":3,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/170890\/revisions"}],"predecessor-version":[{"id":170893,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/170890\/revisions\/170893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/170773"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=170890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=170890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=170890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}