{"id":166474,"date":"2026-04-16T21:45:26","date_gmt":"2026-04-16T19:45:26","guid":{"rendered":"https:\/\/exaudi.org\/?p=166474"},"modified":"2026-04-16T23:40:17","modified_gmt":"2026-04-16T21:40:17","slug":"roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/","title":{"rendered":"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte"},"content":{"rendered":"<p>Il prossimo 21 aprile ricorre il primo anniversario della scomparsa di Papa Francesco e per ricordare il pontefice argentino, l&#8217;organizzazione internazionale Scholas Occurrentes, nata proprio su impulso di Bergoglio per promuovere la &#8220;cultura dell&#8217;incontro&#8221;, ha organizzato a Roma una giornata-evento con diversi appuntamenti. L&#8217;obiettivo \u00e8 custodire e rilanciare la sua eredit\u00e0 culturale, spirituale e educativa.<\/p>\n<p>La giornata si aprir\u00e0 alle 11 nella Casina Pio IV, con il seminario \u201cL\u2019eredit\u00e0 viva di Papa Francesco\u201d, con un focus sugli aspetti educativi. Saranno presentati alcuni dei principali progetti che Scholas sta sviluppando nei campi dell\u2019arte (con particolare riferimento al cinema), dello sport e dell\u2019educazione.<\/p>\n<p>Il seminario includer\u00e0 testimonianze di giovani protagonisti dei progetti, insieme agli interventi di referenti e personalit\u00e0 istituzionali, tra cui il viceministro del Lavoro e delle Politiche Sociali, on. Maria Teresa Bellucci; la segretaria della Pontificia Commissione per l\u2019America Latina, Emilce Cuda; il segretario del Dicastero per i Laici, la Famiglia e la Vita, Gleison de Paula Souza; i fondatori di Scholas Occurrentes, Jos\u00e9 Mar\u00eda del Corral ed Enrique Palmeyro; lo storico Alberto Melloni; l\u2019artista Mauro Pallotta in arte Maupal; e l\u2019attrice Happy Salma.<\/p>\n<p>Il cuore della giornata sar\u00e0 probabilmente nel pomeriggio. Alle 16, nella Filmoteca Vaticana, si terr\u00e0 la proiezione del documentario inedito \u201c<em>Aldeas: The Final Dream of Pope Francis\u201d<\/em>, progetto profondamente voluto da Papa Francesco e affidato personalmente al regista Martin Scorsese. Il film racconta <em>Aldeas<\/em>, un progetto di cinema comunitario nato per preservare e promuovere la diversit\u00e0 culturale oggi in pericolo, dando voce a comunit\u00e0 di diverse parti del mondo.\u00a0Ma, secondo indiscrezioni, la notizia principale consiste nelle parole pronunciate nel film dallo stesso Bergoglio che sentiva molto vicina la fine della sua avventura terrena: una sorta di premonizione della sua morte imminente che rappresenterebbe una testimonianza particolarmente toccante.<\/p>\n<p>Infine, a partire dalle 20, nell\u2019Auditorium della Conciliazione, si terr\u00e0 l\u2019evento omaggio \u201cTributo a Papa Francesco\u201d, un concerto arricchito da una selezione di video dedicati al pontificato di Bergoglio. Con la conduzione di Francesca Ceci si alterneranno sul palco Arisa, Jakarta Concert Orchestra, Batavia Madrigal Singers e la testimonianza di Happy Salma. Prevista anche un\u2019esposizione di pittura e design, con la partecipazione di artisti internazionali e un intervento artistico partecipativo guidato da giovani di Scholas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scholas Occurrentes promuove seminari, la proiezione del documentario inedito affidato a Martin Scorsese e un concerto-tributo per rilanciare il suo messaggio culturale ed educativo<\/p>\n","protected":false},"author":18,"featured_media":166479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[131],"tags":[108486,108481,108495,37271,108497,108484,108506,108491,15663,108487,108502,108501,108483,108489,108485,108498,108493,108503,108494,108496,108500,108504,108488,108499,64788,108482,664,108492,64787,108490,108505],"class_list":["post-166474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vaticano","tag-aldeas-the-final-dream-of-pope-francis","tag-anniversario-morte-papa-francesco","tag-arisa-concerto-roma","tag-auditorium-della-conciliazione-2","tag-batavia-madrigal-singers","tag-casina-pio-iv","tag-commemorazione-papa-francesco-roma","tag-concerto-papa-francesco-roma","tag-cultura-dellincontro","tag-documentario-papa-francesco","tag-emilce-cuda-2","tag-enrique-palmeyro","tag-eredita-papa-francesco","tag-evento-21-aprile-roma","tag-filmoteca-vaticana-2","tag-francesca-ceci","tag-giovani-scholas","tag-gleison-de-paula-souza","tag-happy-salma","tag-jakarta-concert-orchestra","tag-jose-maria-del-corral","tag-maria-teresa-bellucci","tag-martin-scorsese-papa-francesco","tag-mauro-pallotta-maupal","tag-papa-francesco-it-5","tag-roma-evento-papa-francesco","tag-scholas-occurrentes-it","tag-scholas-occurrentes-roma","tag-trending-it-236","tag-tributo-papa-francesco","tag-vaticano-evento-papa-francesco"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Scholas Occurrentes promuove seminari, la proiezione del documentario inedito affidato a Martin Scorsese e un concerto-tributo per rilanciare il suo messaggio culturale ed educativo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-16T19:45:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T21:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.1500.844-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Acali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Acali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/\"},\"author\":{\"name\":\"Andrea Acali\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/127735be832481a6d3c410c5837bb61a\"},\"headline\":\"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte\",\"datePublished\":\"2026-04-16T19:45:26+00:00\",\"dateModified\":\"2026-04-16T21:40:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/\"},\"wordCount\":392,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cq5dam.thumbnail.cropped.1500.844-3.jpeg\",\"keywords\":[\"Aldeas The Final Dream of Pope Francis\",\"anniversario morte Papa Francesco\",\"Arisa concerto Roma\",\"Auditorium della Conciliazione\",\"Batavia Madrigal Singers\",\"Casina Pio IV\",\"commemorazione Papa Francesco Roma\",\"concerto Papa Francesco Roma\",\"CULTURA DELL'INCONTRO\",\"documentario Papa Francesco\",\"Emilce Cuda\",\"Enrique Palmeyro\",\"eredit\u00e0 Papa Francesco\",\"evento 21 aprile Roma\",\"Filmoteca Vaticana\",\"Francesca Ceci\",\"giovani Scholas\",\"Gleison de Paula Souza\",\"Happy Salma\",\"Jakarta Concert Orchestra\",\"Jos\u00e9 Mar\u00eda del Corral\",\"Maria Teresa Bellucci\",\"Martin Scorsese Papa Francesco\",\"Mauro Pallotta Maupal\",\"Papa Francesco\",\"Roma evento Papa Francesco\",\"Scholas Occurrentes\",\"Scholas Occurrentes Roma\",\"Trending\",\"tributo Papa Francesco\",\"Vaticano evento Papa Francesco\"],\"articleSection\":[\"Vaticano\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/\",\"name\":\"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cq5dam.thumbnail.cropped.1500.844-3.jpeg\",\"datePublished\":\"2026-04-16T19:45:26+00:00\",\"dateModified\":\"2026-04-16T21:40:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/127735be832481a6d3c410c5837bb61a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cq5dam.thumbnail.cropped.1500.844-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cq5dam.thumbnail.cropped.1500.844-3.jpeg\",\"width\":1500,\"height\":844},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/127735be832481a6d3c410c5837bb61a\",\"name\":\"Andrea Acali\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g\",\"caption\":\"Andrea Acali\"},\"description\":\"Andrea Acali es un periodista y comunicador italiano con una larga trayectoria en el \u00e1mbito de la informaci\u00f3n religiosa, social y deportiva. Durante casi treinta a\u00f1os trabaj\u00f3 en el diario Il Tempo como vaticanista y jefe de secci\u00f3n, especializ\u00e1ndose en la cobertura de la actualidad del Vaticano y de la Iglesia cat\u00f3lica. Desde 2016 colabora como periodista web en RomaSette y tambi\u00e9n escribe para el peri\u00f3dico Avvenire. Desde 2019 ejerce como comunicador en la Delegazione della Generalitat de Catalunya in Italia, con sede en Roma, donde combina su experiencia period\u00edstica con la comunicaci\u00f3n institucional\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/andrea-acali-505567125\\\/?originalSubdomain=it\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/aacaliexaudi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/","og_locale":"it_IT","og_type":"article","og_title":"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte &#8211; Exaudi","og_description":"Scholas Occurrentes promuove seminari, la proiezione del documentario inedito affidato a Martin Scorsese e un concerto-tributo per rilanciare il suo messaggio culturale ed educativo","og_url":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2026-04-16T19:45:26+00:00","article_modified_time":"2026-04-16T21:40:17+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.1500.844-3.jpeg","type":"image\/jpeg"}],"author":"Andrea Acali","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Andrea Acali","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/"},"author":{"name":"Andrea Acali","@id":"https:\/\/exaudi.org\/#\/schema\/person\/127735be832481a6d3c410c5837bb61a"},"headline":"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte","datePublished":"2026-04-16T19:45:26+00:00","dateModified":"2026-04-16T21:40:17+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/"},"wordCount":392,"image":{"@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.1500.844-3.jpeg","keywords":["Aldeas The Final Dream of Pope Francis","anniversario morte Papa Francesco","Arisa concerto Roma","Auditorium della Conciliazione","Batavia Madrigal Singers","Casina Pio IV","commemorazione Papa Francesco Roma","concerto Papa Francesco Roma","CULTURA DELL'INCONTRO","documentario Papa Francesco","Emilce Cuda","Enrique Palmeyro","eredit\u00e0 Papa Francesco","evento 21 aprile Roma","Filmoteca Vaticana","Francesca Ceci","giovani Scholas","Gleison de Paula Souza","Happy Salma","Jakarta Concert Orchestra","Jos\u00e9 Mar\u00eda del Corral","Maria Teresa Bellucci","Martin Scorsese Papa Francesco","Mauro Pallotta Maupal","Papa Francesco","Roma evento Papa Francesco","Scholas Occurrentes","Scholas Occurrentes Roma","Trending","tributo Papa Francesco","Vaticano evento Papa Francesco"],"articleSection":["Vaticano"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/","url":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/","name":"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.1500.844-3.jpeg","datePublished":"2026-04-16T19:45:26+00:00","dateModified":"2026-04-16T21:40:17+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/127735be832481a6d3c410c5837bb61a"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.1500.844-3.jpeg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.1500.844-3.jpeg","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/roma-ricorda-papa-francesco-a-un-anno-dalla-scomparsa-in-un-film-inedito-parla-della-sua-morte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Roma ricorda Papa Francesco a un anno dalla scomparsa. In un film inedito parla della sua morte"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/127735be832481a6d3c410c5837bb61a","name":"Andrea Acali","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g","caption":"Andrea Acali"},"description":"Andrea Acali es un periodista y comunicador italiano con una larga trayectoria en el \u00e1mbito de la informaci\u00f3n religiosa, social y deportiva. Durante casi treinta a\u00f1os trabaj\u00f3 en el diario Il Tempo como vaticanista y jefe de secci\u00f3n, especializ\u00e1ndose en la cobertura de la actualidad del Vaticano y de la Iglesia cat\u00f3lica. Desde 2016 colabora como periodista web en RomaSette y tambi\u00e9n escribe para el peri\u00f3dico Avvenire. Desde 2019 ejerce como comunicador en la Delegazione della Generalitat de Catalunya in Italia, con sede en Roma, donde combina su experiencia period\u00edstica con la comunicaci\u00f3n institucional","sameAs":["https:\/\/www.linkedin.com\/in\/andrea-acali-505567125\/?originalSubdomain=it"],"url":"https:\/\/exaudi.org\/it\/author\/aacaliexaudi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.1500.844-3.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-Hj4","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/166474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=166474"}],"version-history":[{"count":3,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/166474\/revisions"}],"predecessor-version":[{"id":166505,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/166474\/revisions\/166505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/166479"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=166474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=166474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=166474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}