{"id":161833,"date":"2026-03-13T17:30:32","date_gmt":"2026-03-13T16:30:32","guid":{"rendered":"https:\/\/exaudi.org\/?p=161833"},"modified":"2026-03-13T17:37:25","modified_gmt":"2026-03-13T16:37:25","slug":"imparare-a-vedere-la-passione-con-gli-occhi-del-cuore","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/","title":{"rendered":"Imparare a vedere la Passione con gli occhi del cuore"},"content":{"rendered":"<p data-start=\"189\" data-end=\"577\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Esiste un modo superficiale di vivere\u00a0 <\/span><\/span><strong data-start=\"227\" data-end=\"243\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">la Settimana Santa<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> : considerarla una tradizione culturale, un&#8217;usanza familiare o una successione di celebrazioni liturgiche. Ma la Chiesa ha sempre insegnato qualcosa di molto pi\u00f9 profondo:\u00a0 <\/span><\/span><strong data-start=\"411\" data-end=\"423\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">la Quaresima<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0\u00e8 una scuola spirituale che prepara il cuore a comprendere il pi\u00f9 grande mistero del Cristianesimo, la Passione, morte e risurrezione di Ges\u00f9 Cristo.<\/span><\/span><\/p>\n<p data-start=\"579\" data-end=\"719\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Se vuoi aiutare un amico a superare questo momento, non basta spiegargli regole o usanze. Devi invitarlo a\u00a0 <\/span><\/span><strong data-start=\"693\" data-end=\"718\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">entrare nel mistero<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<p data-start=\"721\" data-end=\"797\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Perch\u00e9 la croce non si comprende solo con la ragione: si comprende con il cuore.<\/span><\/span><\/p>\n<p data-start=\"801\" data-end=\"878\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abLa croce \u00e8 la scuola dell&#8217;amore\u00bb. <\/span><\/span><\/strong><\/em><br data-start=\"834\" data-end=\"837\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Giovanni Paolo II<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<h3 data-section-id=\"x6hccw\" data-start=\"885\" data-end=\"946\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">1. La Quaresima \u00e8 un invito alla conversione<\/span><\/span><\/strong><\/h3>\n<p data-start=\"948\" data-end=\"1118\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La Chiesa stabilisce quaranta giorni di preparazione prima di Pasqua, ricordando i\u00a0 <\/span><\/span><strong data-start=\"1033\" data-end=\"1081\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">quaranta giorni che Cristo trascorse nel deserto<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0prima di iniziare la sua missione pubblica.<\/span><\/span><\/p>\n<p data-start=\"1120\" data-end=\"1225\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nella Bibbia, il deserto \u00e8 il luogo in cui le distrazioni scompaiono e l&#8217;anima si abbandona alla presenza di Dio.<\/span><\/span><\/p>\n<p data-start=\"1227\" data-end=\"1286\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">L\u00ec, l&#8217;uomo scopre ci\u00f2 che si cela veramente nel suo cuore.<\/span><\/span><\/p>\n<p data-start=\"1290\" data-end=\"1375\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abConosci te stesso e conoscerai Dio.\u00bb <\/span><\/span><\/strong><\/em><br data-start=\"1331\" data-end=\"1334\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Agostino d&#8217;Ippona<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<p data-start=\"1377\" data-end=\"1548\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ecco perch\u00e9 la Quaresima non \u00e8 un periodo triste. \u00c8 un tempo\u00a0 <\/span><\/span><strong data-start=\"1434\" data-end=\"1445\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">di sincera riflessione<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> . \u00c8 un tempo per guardare alla propria vita con onest\u00e0 e chiedersi: che posto ha Dio nella mia vita?<\/span><\/span><\/p>\n<p data-start=\"1550\" data-end=\"1615\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La Chiesa propone questo tempo come un invito a ritornare a Lui.<\/span><\/span><\/p>\n<p data-start=\"1619\" data-end=\"1750\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abDio non si stanca mai di perdonare; siamo noi che ci stanchiamo di chiedere perdono.\u00bb <\/span><\/span><\/strong><\/em><br data-start=\"1706\" data-end=\"1709\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Francesco<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<h3 data-section-id=\"187njcl\" data-start=\"1757\" data-end=\"1809\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">2. Il linguaggio spirituale della Quaresima<\/span><\/span><\/strong><\/h3>\n<p data-start=\"1811\" data-end=\"1919\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Fin dai primi secoli, la tradizione cristiana ha indicato tre vie specifiche per vivere la Quaresima:<\/span><\/span><\/p>\n<ul>\n<li data-start=\"1923\" data-end=\"1932\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">preghiera<\/span><\/span><\/li>\n<li data-start=\"1935\" data-end=\"1942\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">veloce<\/span><\/span><\/li>\n<li data-start=\"1945\" data-end=\"1964\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">elemosina o beneficenza<\/span><\/span><\/li>\n<\/ul>\n<p data-start=\"1966\" data-end=\"2035\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Non si tratta di semplici pratiche ascetiche. Sono tre movimenti del cuore.<\/span><\/span><\/p>\n<p data-start=\"2037\" data-end=\"2151\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La preghiera\u00a0 <\/span><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0ci conduce a Dio. <\/span><span dir=\"auto\" style=\"vertical-align: inherit\">Il digiuno\u00a0 <\/span><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0ci libera dall&#8217;egoismo. <\/span><strong data-start=\"2080\" data-end=\"2089\"><span dir=\"auto\" style=\"vertical-align: inherit\">La carit\u00e0<\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"> ci apre\u00a0 <\/span><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0al <\/span><\/span><strong data-start=\"2040\" data-end=\"2051\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">prossimo <\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><strong data-start=\"2119\" data-end=\"2130\"><span dir=\"auto\" style=\"vertical-align: inherit\">.<\/span><\/strong><\/span><br data-start=\"2074\" data-end=\"2077\" \/><br data-start=\"2113\" data-end=\"2116\" \/><\/p>\n<p data-start=\"2155\" data-end=\"2270\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abLa preghiera dilata il cuore fino a renderlo capace di ricevere Dio.\u00bb <\/span><\/span><\/strong><\/em><br data-start=\"2226\" data-end=\"2229\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madre Teresa<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<p data-start=\"2272\" data-end=\"2391\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il digiuno, ad esempio, non \u00e8 una dieta spirituale. \u00c8 un promemoria del fatto che gli esseri umani non vivono di sole cose materiali.<\/span><\/span><\/p>\n<p data-start=\"2395\" data-end=\"2483\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abCi \u200b\u200basteniamo dal cibo per appagare l&#8217;anima.\u00bb <\/span><\/span><\/strong><\/em><br data-start=\"2439\" data-end=\"2442\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Giovanni Crisostomo<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<p data-start=\"2485\" data-end=\"2620\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Quando qualcuno scopre il profondo significato di queste pratiche, comprende che la Quaresima non \u00e8 privazione, ma\u00a0 <\/span><\/span><strong data-start=\"2596\" data-end=\"2619\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">liberazione interiore<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<h3 data-section-id=\"1evejl2\" data-start=\"2627\" data-end=\"2664\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">3. Contempla la Passione<\/span><\/span><\/strong><\/h3>\n<p data-start=\"2666\" data-end=\"2819\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La\u00a0 <\/span><\/span><strong data-start=\"2669\" data-end=\"2689\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Passione di Cristo<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0\u00e8 il fulcro della fede cristiana. Non \u00e8 solo la storia di un uomo ingiustamente condannato, ma la rivelazione dell&#8217;amore di Dio.<\/span><\/span><\/p>\n<p data-start=\"2821\" data-end=\"2890\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ogni momento della narrazione evangelica rivela qualcosa del cuore di Cristo.<\/span><\/span><\/p>\n<p data-start=\"2892\" data-end=\"3004\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nel\u00a0 <\/span><\/span><strong data-start=\"2895\" data-end=\"2908\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Getsemani<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> vediamo la sua lotta interiore. <\/span><\/span><br data-start=\"2934\" data-end=\"2937\" \/><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nel\u00a0 <\/span><\/span><strong data-start=\"2943\" data-end=\"2961\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">processo ingiusto<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> , il suo silenzio. <\/span><\/span><br data-start=\"2975\" data-end=\"2978\" \/><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Sulla\u00a0 <\/span><\/span><strong data-start=\"2984\" data-end=\"2992\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">croce<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> , il suo perdono.<\/span><\/span><\/p>\n<p data-start=\"3008\" data-end=\"3099\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abGuardate il Crocifisso e vedrete quanto Dio vi ama\u00bb. <\/span><\/span><\/strong><\/em><br data-start=\"3055\" data-end=\"3058\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Francesco d&#8217;Assisi<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<p data-start=\"3101\" data-end=\"3203\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La croce \u00e8 scandalosa per la logica umana. Ma \u00e8 proprio l\u00ec che si rivela l&#8217;amore radicale di Dio.<\/span><\/span><\/p>\n<p data-start=\"3207\" data-end=\"3291\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abLa misura dell&#8217;amore \u00e8 amare senza misura.\u00bb <\/span><\/span><\/strong><\/em><br data-start=\"3247\" data-end=\"3250\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Bernardo di Chiaravalle<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<p data-start=\"3293\" data-end=\"3373\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cristo non risponde all&#8217;odio con l&#8217;odio. <\/span><\/span><br data-start=\"3329\" data-end=\"3332\" \/><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Non risponde alla violenza con la violenza.<\/span><\/span><\/p>\n<p data-start=\"3375\" data-end=\"3393\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Rispondi con amore.<\/span><\/span><\/p>\n<h3 data-section-id=\"ixs588\" data-start=\"3400\" data-end=\"3440\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">4. Vivere il Triduo Pasquale<\/span><\/span><\/strong><\/h3>\n<p data-start=\"3442\" data-end=\"3554\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il cuore della\u00a0 <\/span><\/span><strong data-start=\"3459\" data-end=\"3475\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Settimana Santa<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0\u00e8 il\u00a0 <\/span><\/span><strong data-start=\"3482\" data-end=\"3500\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Triduo Pasquale<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> , che inizia il Gioved\u00ec Santo e culmina a Pasqua.<\/span><\/span><\/p>\n<p data-start=\"3556\" data-end=\"3610\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Questi tre giorni racchiudono l&#8217;essenza del cristianesimo.<\/span><\/span><\/p>\n<p data-section-id=\"t8l1ur\" data-start=\"3612\" data-end=\"3647\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Gioved\u00ec Santo: l&#8217;amore che serve<\/span><\/span><\/strong><\/p>\n<p data-start=\"3649\" data-end=\"3736\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Durante l&#8217;\u00a0 <\/span><\/span><strong data-start=\"3655\" data-end=\"3670\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ultima Cena<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> , Cristo istitu\u00ec l&#8217;Eucaristia e lav\u00f2 i piedi ai suoi discepoli.<\/span><\/span><\/p>\n<p data-start=\"3738\" data-end=\"3771\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Dio si inginocchia davanti all&#8217;uomo.<\/span><\/span><\/p>\n<p data-start=\"3775\" data-end=\"3904\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abEssere cristiani non significa essere un&#8217;idea, ma un incontro con una Persona\u00bb. <\/span><\/span><\/strong><\/em><br data-start=\"3860\" data-end=\"3863\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Benedetto XVI<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<p data-section-id=\"oqmm16\" data-start=\"3906\" data-end=\"3947\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Venerd\u00ec Santo: l&#8217;amore che viene donato<\/span><\/span><\/strong><\/p>\n<p data-start=\"3949\" data-end=\"4030\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La croce non \u00e8 un evento casuale nella vita di Cristo, ma il culmine del suo dono di s\u00e9.<\/span><\/span><\/p>\n<p data-start=\"4034\" data-end=\"4137\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u201cQuando guardi il Crocifisso, capisci quanto Ges\u00f9 ti ama.\u201d <\/span><\/span><\/strong><\/em><br data-start=\"4093\" data-end=\"4096\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Josemar\u00eda Escriv\u00e1<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<p data-start=\"4139\" data-end=\"4191\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">L\u00ec Cristo perdona persino coloro che lo crocifiggono.<\/span><\/span><\/p>\n<p data-start=\"4195\" data-end=\"4215\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abPadre, perdona loro.\u00bb<\/span><\/span><\/strong><\/em><\/p>\n<p data-start=\"4217\" data-end=\"4259\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00c8 il momento in cui l&#8217;amore trionfa sull&#8217;odio.<\/span><\/span><\/p>\n<p data-section-id=\"1k9f0bk\" data-start=\"4261\" data-end=\"4298\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Sabato Santo: il silenzio di Dio<\/span><\/span><\/strong><\/p>\n<p data-start=\"4300\" data-end=\"4367\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il Sabato Santo \u00e8 uno dei giorni pi\u00f9 profondi dell&#8217;anno liturgico.<\/span><\/span><\/p>\n<p data-start=\"4369\" data-end=\"4421\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cristo giace nella tomba. <\/span><\/span><br data-start=\"4396\" data-end=\"4399\" \/><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Tutto sembra finito.<\/span><\/span><\/p>\n<p data-start=\"4423\" data-end=\"4482\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ma il silenzio di Dio non \u00e8 mai assenza. \u00c8 preparazione.<\/span><\/span><\/p>\n<blockquote data-start=\"4484\" data-end=\"4567\">\n<p data-start=\"4486\" data-end=\"4567\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abDio parla nel silenzio dell&#8217;anima.\u00bb <\/span><\/span><br data-start=\"4523\" data-end=\"4526\" \/><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madre Teresa<\/span><\/span><\/span><\/span><\/p>\n<\/blockquote>\n<p data-section-id=\"1vti4x9\" data-start=\"4569\" data-end=\"4612\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Domenica di Pasqua: la vittoria dell&#8217;amore<\/span><\/span><\/strong><\/p>\n<p data-start=\"4614\" data-end=\"4668\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La Risurrezione rivela il significato di tutto ci\u00f2 che \u00e8 accaduto.<\/span><\/span><\/p>\n<p data-start=\"4670\" data-end=\"4709\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La croce non era la fine. Era il cammino.<\/span><\/span><\/p>\n<p data-start=\"4713\" data-end=\"4795\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abCristo \u00e8 risorto: tutto cambia\u00bb. <\/span><\/span><\/strong><\/em><br data-start=\"4749\" data-end=\"4752\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Giovanni Paolo II<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<h3 data-section-id=\"1upeijb\" data-start=\"4802\" data-end=\"4857\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">5. La croce spiega anche la nostra vita<\/span><\/span><\/strong><\/h3>\n<p data-start=\"4859\" data-end=\"4951\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La Passione non \u00e8 solo una storia del passato. \u00c8 anche uno specchio dell&#8217;esperienza umana.<\/span><\/span><\/p>\n<p data-start=\"4953\" data-end=\"5025\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Tutti conosciamo la sofferenza, l&#8217;ingiustizia, il tradimento o la solitudine.<\/span><\/span><\/p>\n<p data-start=\"5027\" data-end=\"5057\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cristo ha attraversato tutto questo.<\/span><\/span><\/p>\n<p data-start=\"5061\" data-end=\"5166\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abLa sofferenza passa; la sofferenza per amore rimane.\u00bb <\/span><\/span><\/strong><\/em><br data-start=\"5120\" data-end=\"5123\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madre Teresa<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<p data-start=\"5168\" data-end=\"5257\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ecco perch\u00e9 il cristianesimo non promette una vita senza la croce. Ma promette qualcosa di molto pi\u00f9 grande:<\/span><\/span><\/p>\n<p data-start=\"5259\" data-end=\"5319\"><strong data-start=\"5259\" data-end=\"5319\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">che nessuna croce \u00e8 inutile quando \u00e8 unita a quella di Cristo.<\/span><\/span><\/strong><\/p>\n<p data-start=\"5323\" data-end=\"5424\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abNella sera della vita saremo giudicati in base all&#8217;amore.\u00bb <\/span><\/span><\/strong><\/em><br data-start=\"5378\" data-end=\"5381\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Giovanni della Croce<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<h3 data-section-id=\"u60837\" data-start=\"5431\" data-end=\"5470\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Insegnare come seguire Cristo<\/span><\/span><\/strong><\/h3>\n<p data-start=\"5472\" data-end=\"5559\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Se dovessi insegnare una sola cosa a un amico durante la Quaresima, forse sarebbe questa:<\/span><\/span><\/p>\n<p data-start=\"5561\" data-end=\"5649\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La fede cristiana non consiste nell&#8217;ammirare Cristo da lontano, <\/span><\/span><br data-start=\"5621\" data-end=\"5624\" \/><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">ma nel\u00a0 <\/span><\/span><strong data-start=\"5636\" data-end=\"5648\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">seguirlo<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<p data-start=\"5651\" data-end=\"5722\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Seguitelo nel perdono. <\/span><\/span><br data-start=\"5673\" data-end=\"5676\" \/><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Seguitelo nella resa. <\/span><\/span><br data-start=\"5699\" data-end=\"5702\" \/><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Seguitelo nell&#8217;amore.<\/span><\/span><\/p>\n<p data-start=\"5726\" data-end=\"5822\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abChi non vive per servire, non merita di vivere.\u00bb <\/span><\/span><\/strong><\/em><br data-start=\"5776\" data-end=\"5779\" \/><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2014\u00a0 <\/span><\/span><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madre Teresa<\/span><\/span><\/span><\/span><\/strong><\/em><\/p>\n<p data-start=\"5824\" data-end=\"5876\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La Quaresima \u00e8 il cammino che conduce a quella decisione.<\/span><\/span><\/p>\n<p data-start=\"5878\" data-end=\"5983\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Perch\u00e9 quando qualcuno comprende veramente la\u00a0 <\/span><\/span><strong data-start=\"5923\" data-end=\"5943\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Passione di Cristo<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> , scopre qualcosa che gli cambia la vita intera:<\/span><\/span><\/p>\n<p data-start=\"5985\" data-end=\"6040\"><strong data-start=\"5985\" data-end=\"6040\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Dio non ci ha amato solo in teoria. <\/span><\/span><br data-start=\"6013\" data-end=\"6016\" \/><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ci ha amato fino al punto di morire sulla croce.<\/span><\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Quaresima non \u00e8 un ricordo del passato, ma una scuola per imparare a vivere come Cristo<\/p>\n","protected":false},"author":151,"featured_media":161665,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[71],"tags":[102205,102206,102207,102208,102209,102217,102215,102211,102212,102204,35936,578,48105,102220,95521,102221,102222,102225,102223,102224,102226,102227,102216,102229,54807,102210,102228,102219,102218,102213,102214,64787,102230,102231],"class_list":["post-161833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisi","tag-articolo-cattolico-sulla-quaresima","tag-cammino-spirituale-quaresimale","tag-catechesi-sulla-passione-di-cristo","tag-come-vivere-la-quaresima","tag-conversione-cristiana-durante-la-quaresima","tag-digiuno-ed-elemosina-quaresimali","tag-evangelizzazione-durante-la-settimana-santa","tag-insegnamento-cristiano-sulla-croce","tag-insegnamento-della-chiesa-sulla-passione","tag-lamore-di-dio-sulla-croce","tag-patricia-jimenez-ramirez-2","tag-preghiera","tag-preparazione-alla-pasqua","tag-preparazione-spirituale-alla-pasqua","tag-quaresima-2026","tag-riflessione-cattolica-sulla-settimana-santa","tag-riflessione-profonda-sulla-settimana-santa","tag-riflessione-sul-sabato-santo","tag-riflessione-sulla-croce-di-cristo","tag-risurrezione-di-cristo-significato-di-gesu-cristo","tag-settimana-santa-cristiana","tag-significato-cristiano-della-sofferenza","tag-significato-del-giovedi-santo","tag-significato-del-triduo-pasquale","tag-significato-del-venerdi-santo","tag-significato-della-quaresima","tag-significato-della-settimana-santa","tag-spiegazione-cristiana-della-passione-di-gesu","tag-spiegazione-della-passione-di-cristo","tag-spiritualita-cattolica-durante-la-quaresima","tag-spiritualita-quaresimale","tag-trending-it-236","tag-vivere-la-fede-in-quaresima","tag-vivere-la-settimana-santa-in-modo-cristiano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imparare a vedere la Passione con gli occhi del cuore &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imparare a vedere la Passione con gli occhi del cuore &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"La Quaresima non \u00e8 un ricordo del passato, ma una scuola per imparare a vivere come Cristo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-13T16:30:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T16:37:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/03\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1360\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patricia Jim\u00e9nez Ram\u00edrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patricia Jim\u00e9nez Ram\u00edrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/\"},\"author\":{\"name\":\"Patricia Jim\u00e9nez Ram\u00edrez\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e7ff749045cafab5d7b926bb4edeaa51\"},\"headline\":\"Imparare a vedere la Passione con gli occhi del cuore\",\"datePublished\":\"2026-03-13T16:30:32+00:00\",\"dateModified\":\"2026-03-13T16:37:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/\"},\"wordCount\":866,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg?fit=1360%2C768&ssl=1\",\"keywords\":[\"Articolo cattolico sulla Quaresima\",\"Cammino spirituale quaresimale\",\"Catechesi sulla Passione di Cristo\",\"Come vivere la Quaresima\",\"Conversione cristiana durante la Quaresima\",\"digiuno ed elemosina quaresimali\",\"Evangelizzazione durante la Settimana Santa\",\"Insegnamento cristiano sulla croce\",\"Insegnamento della Chiesa sulla Passione\",\"L'amore di Dio sulla croce\",\"Patricia Jim\u00e9nez Ram\u00edrez\",\"preghiera\",\"preparazione alla Pasqua\",\"Preparazione spirituale alla Pasqua\",\"Quaresima 2026\",\"Riflessione cattolica sulla Settimana Santa\",\"Riflessione profonda sulla Settimana Santa\",\"Riflessione sul Sabato Santo\",\"Riflessione sulla Croce di Cristo\",\"Risurrezione di Cristo Significato di Ges\u00f9 Cristo\",\"Settimana Santa cristiana\",\"Significato cristiano della sofferenza\",\"Significato del Gioved\u00ec Santo\",\"Significato del Triduo Pasquale\",\"significato del Venerd\u00ec Santo\",\"Significato della Quaresima\",\"Significato della Settimana Santa\",\"Spiegazione cristiana della Passione di Ges\u00f9\",\"Spiegazione della Passione di Cristo\",\"Spiritualit\u00e0 cattolica durante la Quaresima\",\"Spiritualit\u00e0 quaresimale\",\"Trending\",\"Vivere la fede in Quaresima\",\"Vivere la Settimana Santa in modo cristiano\"],\"articleSection\":[\"Analisi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/\",\"name\":\"Imparare a vedere la Passione con gli occhi del cuore &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg?fit=1360%2C768&ssl=1\",\"datePublished\":\"2026-03-13T16:30:32+00:00\",\"dateModified\":\"2026-03-13T16:37:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e7ff749045cafab5d7b926bb4edeaa51\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg?fit=1360%2C768&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg?fit=1360%2C768&ssl=1\",\"width\":1360,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imparare a vedere la Passione con gli occhi del cuore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e7ff749045cafab5d7b926bb4edeaa51\",\"name\":\"Patricia Jim\u00e9nez Ram\u00edrez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1f016f3010698237250f552cc424d09fd3f545baa3b0e2f5008eae3181ed438?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1f016f3010698237250f552cc424d09fd3f545baa3b0e2f5008eae3181ed438?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1f016f3010698237250f552cc424d09fd3f545baa3b0e2f5008eae3181ed438?s=96&d=mm&r=g\",\"caption\":\"Patricia Jim\u00e9nez Ram\u00edrez\"},\"description\":\"Soy una mujer comprometida con mi familia, con una s\u00f3lida experiencia empresarial y una profunda dedicaci\u00f3n al hogar. Durante a\u00f1os trabaj\u00e9 en diversos entornos empresariales, liderando equipos y gestionando proyectos de impacto. Sin embargo, en los \u00faltimos a\u00f1os he tomado la decisi\u00f3n de centrarme en mi hogar y dedicar m\u00e1s tiempo a mi marido e hijos, quienes son mi mayor prioridad. Mi experiencia en el \u00e1mbito empresarial me ha brindado valiosas habilidades en gesti\u00f3n del tiempo, organizaci\u00f3n, liderazgo y resoluci\u00f3n de problemas, que ahora aplico en mi vida familiar para fomentar un ambiente armonioso y saludable para todos\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/patricia-jimenez-ramirez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imparare a vedere la Passione con gli occhi del cuore &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/","og_locale":"it_IT","og_type":"article","og_title":"Imparare a vedere la Passione con gli occhi del cuore &#8211; Exaudi","og_description":"La Quaresima non \u00e8 un ricordo del passato, ma una scuola per imparare a vivere come Cristo","og_url":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2026-03-13T16:30:32+00:00","article_modified_time":"2026-03-13T16:37:25+00:00","og_image":[{"width":1360,"height":768,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/03\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg","type":"image\/jpeg"}],"author":"Patricia Jim\u00e9nez Ram\u00edrez","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Patricia Jim\u00e9nez Ram\u00edrez","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/"},"author":{"name":"Patricia Jim\u00e9nez Ram\u00edrez","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e7ff749045cafab5d7b926bb4edeaa51"},"headline":"Imparare a vedere la Passione con gli occhi del cuore","datePublished":"2026-03-13T16:30:32+00:00","dateModified":"2026-03-13T16:37:25+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/"},"wordCount":866,"image":{"@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/03\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg?fit=1360%2C768&ssl=1","keywords":["Articolo cattolico sulla Quaresima","Cammino spirituale quaresimale","Catechesi sulla Passione di Cristo","Come vivere la Quaresima","Conversione cristiana durante la Quaresima","digiuno ed elemosina quaresimali","Evangelizzazione durante la Settimana Santa","Insegnamento cristiano sulla croce","Insegnamento della Chiesa sulla Passione","L'amore di Dio sulla croce","Patricia Jim\u00e9nez Ram\u00edrez","preghiera","preparazione alla Pasqua","Preparazione spirituale alla Pasqua","Quaresima 2026","Riflessione cattolica sulla Settimana Santa","Riflessione profonda sulla Settimana Santa","Riflessione sul Sabato Santo","Riflessione sulla Croce di Cristo","Risurrezione di Cristo Significato di Ges\u00f9 Cristo","Settimana Santa cristiana","Significato cristiano della sofferenza","Significato del Gioved\u00ec Santo","Significato del Triduo Pasquale","significato del Venerd\u00ec Santo","Significato della Quaresima","Significato della Settimana Santa","Spiegazione cristiana della Passione di Ges\u00f9","Spiegazione della Passione di Cristo","Spiritualit\u00e0 cattolica durante la Quaresima","Spiritualit\u00e0 quaresimale","Trending","Vivere la fede in Quaresima","Vivere la Settimana Santa in modo cristiano"],"articleSection":["Analisi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/","url":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/","name":"Imparare a vedere la Passione con gli occhi del cuore &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/03\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg?fit=1360%2C768&ssl=1","datePublished":"2026-03-13T16:30:32+00:00","dateModified":"2026-03-13T16:37:25+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e7ff749045cafab5d7b926bb4edeaa51"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/03\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg?fit=1360%2C768&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/03\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg?fit=1360%2C768&ssl=1","width":1360,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/imparare-a-vedere-la-passione-con-gli-occhi-del-cuore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Imparare a vedere la Passione con gli occhi del cuore"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e7ff749045cafab5d7b926bb4edeaa51","name":"Patricia Jim\u00e9nez Ram\u00edrez","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c1f016f3010698237250f552cc424d09fd3f545baa3b0e2f5008eae3181ed438?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c1f016f3010698237250f552cc424d09fd3f545baa3b0e2f5008eae3181ed438?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1f016f3010698237250f552cc424d09fd3f545baa3b0e2f5008eae3181ed438?s=96&d=mm&r=g","caption":"Patricia Jim\u00e9nez Ram\u00edrez"},"description":"Soy una mujer comprometida con mi familia, con una s\u00f3lida experiencia empresarial y una profunda dedicaci\u00f3n al hogar. Durante a\u00f1os trabaj\u00e9 en diversos entornos empresariales, liderando equipos y gestionando proyectos de impacto. Sin embargo, en los \u00faltimos a\u00f1os he tomado la decisi\u00f3n de centrarme en mi hogar y dedicar m\u00e1s tiempo a mi marido e hijos, quienes son mi mayor prioridad. Mi experiencia en el \u00e1mbito empresarial me ha brindado valiosas habilidades en gesti\u00f3n del tiempo, organizaci\u00f3n, liderazgo y resoluci\u00f3n de problemas, que ahora aplico en mi vida familiar para fomentar un ambiente armonioso y saludable para todos","url":"https:\/\/exaudi.org\/it\/author\/patricia-jimenez-ramirez\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-G6d","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/03\/grok-image-e52fe6d4-0bb6-4166-88ff-0134b9709b58.jpg?fit=1360%2C768&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/161833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/151"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=161833"}],"version-history":[{"count":3,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/161833\/revisions"}],"predecessor-version":[{"id":161841,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/161833\/revisions\/161841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/161665"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=161833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=161833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=161833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}