{"id":161266,"date":"2026-03-09T16:17:41","date_gmt":"2026-03-09T15:17:41","guid":{"rendered":"https:\/\/exaudi.org\/?p=161266"},"modified":"2026-03-09T16:17:41","modified_gmt":"2026-03-09T15:17:41","slug":"la-parola-e-il-volto-visibile-del-silenzio","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/","title":{"rendered":"La Parola \u00e8 il volto visibile del silenzio"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nell&#8217;ultimo articolo, &#8220;Anche Dio tace&#8221;, abbiamo esaminato il silenzio di Dio.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">come un vuoto doloroso,<\/span><\/span><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Oggi\u00a0 <\/span><\/span><\/strong><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">prendiamo il volo.<\/span><\/span><\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Abbiamo scoperto che il silenzio non \u00e8 vuoto.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00c8 gestazione.<\/span><\/span><\/strong><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">&#8220;In principio era il Verbo\u2026<\/span><\/span><\/em><\/p>\n<p style=\"text-align: center\"><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">e il Verbo era Dio\u00bb (Gv 1,1).<\/span><\/span><\/em><\/p>\n<p style=\"text-align: center\"><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">E quella Parola<\/span><\/span><\/em><\/p>\n<p style=\"text-align: center\"><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">&#8220;Si fece carne e venne ad abitare in mezzo a noi&#8221;<\/span><\/span><\/em><\/p>\n<p style=\"text-align: center\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">(Gv 1,14).<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Viveva con un\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">volto <\/span><\/span><\/strong>\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">specifico<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Mani che guariscono.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">I loro occhi che ci cercano.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">In esso,<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">il silenzio cessa di essere un&#8217;ombra<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">e diventa\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">una luce che si lascia guardare<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nel cuore del Padre<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il Figlio ha sempre riposato:<\/span><\/span><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Non c&#8217;\u00e8 rumore<\/span><\/span><\/strong><strong>\u00a0<\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Solo\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">la comunione perfetta<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Un silenzio cos\u00ec pieno d&#8217;amore che non ha bisogno di parole per essere completo.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Voi,<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">intrappolati nel turbine delle ore, che non bastano mai, invasi da<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La vibrazione delle notifiche continue.<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">scadenze strette,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">schermi che richiedono una risposta &#8221; <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">ieri<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> &#8220;<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Quanto tempo \u00e8 passato dall&#8217;ultima volta che hai alzato lo sguardo da terra?<\/span><\/span><\/p>\n<p><strong><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Dio si \u00e8 fatto uomo per mostrare all&#8217;uomo chi \u00e8.<\/span><\/span><\/em><\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Quel Dio silenzioso non ti ignora.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ti\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">abbraccia\u00a0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> dalla sua eternit\u00e0.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Lui ti ha sognato fin dall&#8217;inizio dei tempi.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La sua Parola non nasce dall&#8217;urgenza del mondo,<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">ma da quel\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">silenzio fecondo.<\/span><\/span><\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il silenzio del Padre diventa visibile, pu\u00f2 essere udito in un corpo ferito.<\/span><\/span><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Alza gli occhi, fissa lo sguardo<\/span><\/span><\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">L\u00ec, in mezzo alla routine,<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Qualcosa bolle in pentola per te.<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">A quel Pietro a cui Ges\u00f9 dice: \u00abTu sei Pietro e su questa pietra edificher\u00f2 la mia Chiesa\u00bb e al quale dice anche \u00abPrima che il gallo canti, mi rinnegherai tre volte\u00bb.<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Gli affida il presente e il futuro. Si fida di lui.<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il suo perdono\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">non \u00e8 un discorso<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0sul pentimento, sul &#8220;dovere&#8221;<\/span><\/span><\/li>\n<li><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00c8 uno sguardo<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0al momento esatto della sua negazione.<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abIl Verbo si fece carne\u00bb, e il silenzio dal volto umano ci guarda. Ed \u00e8 uno sguardo d&#8217;amore.<\/span><\/span><\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Queste non sono solo parole, questo non \u00e8 un &#8220;modulo di reclamo&#8221;&#8230;<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Non \u00e8 un trasportatore di dopamina a lunga durata d&#8217;azione.<\/span><\/span><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">L&#8217;invisibile diventa visibile in ogni gesto che abbandona l&#8217;anonimato.\u00a0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00c8 una meraviglia che non cessa mai.<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">il sudore del falegname a Nazareth,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">polvere delle strade della Galilea,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">lacrime durante l&#8217;Ultima Cena.<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ges\u00f9 non irrompe con la forza.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cristo, Dio e uomo, \u00e8 il presente continuo,\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">EGLI VIVE<\/span><\/span><\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">E oggi, proprio come ieri.<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Guarda l&#8217;adultera senza lapidarla.<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Tocca i lebbrosi.<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Piange sulla tomba di Lazzaro.<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Mangiare con i pubblicani.<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cristo svuot\u00f2 se stesso.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Si \u00e8 umiliato per esaltarci. Si \u00e8 fatto uomo affinch\u00e9 potessimo vivere la vita divina. La natura superiore assume quella inferiore. Il miracolo eucaristico in azione.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Quella\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">desolazione<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0\u00e8 il suo volto sofferente.<\/span><\/span><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Dio ha reso vulnerabile<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> la nostra vulnerabilit\u00e0<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Guarda quella faccia.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Non richiede alcun &#8220;Mi piace&#8221; o prestazione da parte tua.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Basta guardarlo.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Perch\u00e9 tu possa vedere in Lui\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">il silenzio \u201cabitato\u201d del Padre<\/span><\/span><\/strong><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">che \u00e8 entrato nella tua argilla e nella mia<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">entro i nostri limiti,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">nella nostra vera storia.<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Niente pi\u00f9 rumore: un silenzio che sussurra senza strani echi.<\/span><\/span><\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Emerge nel rumore\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">che\u00a0 <\/span><\/span><\/strong><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">non <\/span><\/span><\/strong><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0ci sommerge<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0se\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">lo<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> guardiamo \u00a0:<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ges\u00f9 non aggiunge volume al caos.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ci invita nella sua casa, nel suo silenzio \u201cabitato\u201d<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il silenzio di Nazareth (30 anni di lavoro con il legno).<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il silenzio del Getsemani (sudore di sangue).<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il silenzio della Croce: \u00abPadre, nelle tue mani\u00bb. \u00abPadre, perdonali, perch\u00e9 non sanno quello che fanno\u00bb.<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Dove fallisce la nostra speranza:<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nelle crisi professionali<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">In quel matrimonio fallito,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">In quel dolore e nella paura di un futuro senza figli,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">In quella solitudine tra la gente<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il suo sguardo continua a sussurrarci:<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Vali pi\u00f9 dei tuoi post.<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Pi\u00f9 della tua produttivit\u00e0.<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Molto pi\u00f9 della tua immagine online.<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Sollevate lo sguardo dal terreno dell&#8217;immediatezza.<\/span><\/span><\/strong><strong>\u00a0<\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Per sentire quella voce,<\/span><\/span><\/p>\n<ul>\n<li><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Spegni il tuo cellulare<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Pregate per 10 minuti in silenzio.<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">abita il tuo io interiore.<\/span><\/span><\/li>\n<\/ul>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La nostra missione inizia quando lasciamo che\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cristo si faccia carico della nostra cecit\u00e0, del nostro dolore<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0nella piccola vita di ogni giorno.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Solo allora le nostre parole, che Lui fa sue, guariscono veramente.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Non puoi competere con il rumore del mondo.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Lo attraversi con uno\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">sguardo trasformato.<\/span><\/span><\/strong><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Prima di partire,<\/span><\/span><\/strong><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Rileggilo tutte le volte che vuoi.<\/span><\/span><\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Non limitarti a passare oltre.<\/span><\/span><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Dio ha assunto <\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\">un volto umano e<\/span><\/strong><\/span><strong>\u00a0<\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">quella faccia<\/span><\/span><\/p>\n<ul>\n<li><strong><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ha il nostro nome<\/span><\/span><\/em><\/strong>\u00a0<em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> inciso <\/span><\/span><\/em><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0negli occhi.<\/span><\/span><\/em><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Oggi,<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Ora,<\/span><\/span><\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">alza gli occhi<\/span><\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2013 Lasciami guardarti.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u2013 Questo cambia il modo in cui vedi le cose<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">il mondo,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">agli altri,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">a te stesso.<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Siate voi stessi, siate tutti noi quel\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">volto visibile di Cristo<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0per coloro che stanno annegando.<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">sul tuo cellulare,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">nella sua fretta,<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">nel suo vuoto.<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La rivoluzione <\/span><\/span><\/strong>\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">inizia con uno sguardo<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<p><strong><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">IL TUO. <\/span><\/span><\/em><\/strong><strong><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">E IL MIO\u2026<\/span><\/span><\/em><\/strong><\/p>\n<p><strong><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 DAL SUO\u2026<\/span><\/span><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":164,"featured_media":161017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[129],"tags":[1064,101023,23274,101022,26939,101021,63863,101024,101027,101025,98959,54225,101029,101020,64787,101026,101028,101030],"class_list":["post-161266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voci","tag-croce","tag-gestalt-in-silenzio","tag-getsemani-2","tag-miracolo-delleucaristia","tag-nazareth-2","tag-prega-in-silenzio","tag-rosa-montenegro-2","tag-sguardo-amorevole-di-cristo","tag-sguardo-rivoluzionario","tag-sguardo-trasformante","tag-silenzio-abitato","tag-silenzio-di-dio","tag-silenzio-fecondo","tag-spegni-il-telefono","tag-trending-it-236","tag-verbo-fatto-carne","tag-volto-visibile-del-silenzio","tag-vulnerabilita-di-dio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Parola \u00e8 il volto visibile del silenzio &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Parola \u00e8 il volto visibile del silenzio &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/metaforasenrosa\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-09T15:17:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"1613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosa Montenegro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@coachingalicia\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosa Montenegro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/\"},\"author\":{\"name\":\"Rosa Montenegro\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/85388ea135d433877a2634f921d5567c\"},\"headline\":\"La Parola \u00e8 il volto visibile del silenzio\",\"datePublished\":\"2026-03-09T15:17:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/\"},\"wordCount\":784,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg\",\"keywords\":[\"croce\",\"Gestalt in silenzio\",\"Getsemani\",\"Miracolo dell'Eucaristia\",\"Nazareth\",\"prega in silenzio\",\"Rosa Montenegro\",\"Sguardo amorevole di Cristo\",\"Sguardo rivoluzionario\",\"Sguardo trasformante\",\"silenzio abitato\",\"silenzio di Dio\",\"Silenzio fecondo\",\"Spegni il telefono\",\"Trending\",\"Verbo fatto carne\",\"Volto visibile del silenzio\",\"Vulnerabilit\u00e0 di Dio\"],\"articleSection\":[\"Voci\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/\",\"name\":\"La Parola \u00e8 il volto visibile del silenzio &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg\",\"datePublished\":\"2026-03-09T15:17:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/85388ea135d433877a2634f921d5567c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg\",\"width\":1170,\"height\":1613},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-parola-e-il-volto-visibile-del-silenzio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Parola \u00e8 il volto visibile del silenzio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/85388ea135d433877a2634f921d5567c\",\"name\":\"Rosa Montenegro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fc49e154ba2f960002488bc6c90128a74660ddaabe7e2096076c8659f3d49fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fc49e154ba2f960002488bc6c90128a74660ddaabe7e2096076c8659f3d49fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fc49e154ba2f960002488bc6c90128a74660ddaabe7e2096076c8659f3d49fa?s=96&d=mm&r=g\",\"caption\":\"Rosa Montenegro\"},\"description\":\"Pedagoga, orientadora familiar (UNAV) y autora del libro \u201cEl yo y sus met\u00e1foras\u201d libro de antropolog\u00eda para gente sencilla. Con una extensa experiencia internacional en asesoramiento, formaci\u00f3n y coaching, acompa\u00f1a procesos de reconstrucci\u00f3n personal y promueve el fortalecimiento de la identidad desde un enfoque humanista y transformador.\",\"sameAs\":[\"https:\\\/\\\/metaforasenrosa.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/metaforasenrosa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/metaforasenrosa\\\/\",\"https:\\\/\\\/x.com\\\/coachingalicia\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/rosa-montenegro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Parola \u00e8 il volto visibile del silenzio &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/","og_locale":"it_IT","og_type":"article","og_title":"La Parola \u00e8 il volto visibile del silenzio &#8211; Exaudi","og_description":"...","og_url":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/metaforasenrosa\/","article_published_time":"2026-03-09T15:17:41+00:00","og_image":[{"width":1170,"height":1613,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg","type":"image\/jpeg"}],"author":"Rosa Montenegro","twitter_card":"summary_large_image","twitter_creator":"@coachingalicia","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Rosa Montenegro","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/"},"author":{"name":"Rosa Montenegro","@id":"https:\/\/exaudi.org\/#\/schema\/person\/85388ea135d433877a2634f921d5567c"},"headline":"La Parola \u00e8 il volto visibile del silenzio","datePublished":"2026-03-09T15:17:41+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/"},"wordCount":784,"image":{"@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg","keywords":["croce","Gestalt in silenzio","Getsemani","Miracolo dell'Eucaristia","Nazareth","prega in silenzio","Rosa Montenegro","Sguardo amorevole di Cristo","Sguardo rivoluzionario","Sguardo trasformante","silenzio abitato","silenzio di Dio","Silenzio fecondo","Spegni il telefono","Trending","Verbo fatto carne","Volto visibile del silenzio","Vulnerabilit\u00e0 di Dio"],"articleSection":["Voci"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/","url":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/","name":"La Parola \u00e8 il volto visibile del silenzio &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg","datePublished":"2026-03-09T15:17:41+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/85388ea135d433877a2634f921d5567c"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg","width":1170,"height":1613},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/la-parola-e-il-volto-visibile-del-silenzio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"La Parola \u00e8 il volto visibile del silenzio"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/85388ea135d433877a2634f921d5567c","name":"Rosa Montenegro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0fc49e154ba2f960002488bc6c90128a74660ddaabe7e2096076c8659f3d49fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0fc49e154ba2f960002488bc6c90128a74660ddaabe7e2096076c8659f3d49fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fc49e154ba2f960002488bc6c90128a74660ddaabe7e2096076c8659f3d49fa?s=96&d=mm&r=g","caption":"Rosa Montenegro"},"description":"Pedagoga, orientadora familiar (UNAV) y autora del libro \u201cEl yo y sus met\u00e1foras\u201d libro de antropolog\u00eda para gente sencilla. Con una extensa experiencia internacional en asesoramiento, formaci\u00f3n y coaching, acompa\u00f1a procesos de reconstrucci\u00f3n personal y promueve el fortalecimiento de la identidad desde un enfoque humanista y transformador.","sameAs":["https:\/\/metaforasenrosa.com\/","https:\/\/www.facebook.com\/metaforasenrosa\/","https:\/\/www.instagram.com\/metaforasenrosa\/","https:\/\/x.com\/coachingalicia"],"url":"https:\/\/exaudi.org\/it\/author\/rosa-montenegro\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-18.20.00.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-FX4","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/161266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=161266"}],"version-history":[{"count":3,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/161266\/revisions"}],"predecessor-version":[{"id":161269,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/161266\/revisions\/161269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/161017"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=161266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=161266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=161266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}