{"id":154067,"date":"2026-01-16T23:36:31","date_gmt":"2026-01-16T22:36:31","guid":{"rendered":"https:\/\/exaudi.org\/?p=154067"},"modified":"2026-01-16T23:36:31","modified_gmt":"2026-01-16T22:36:31","slug":"addio-ad-angelo-gugel-al-servizio-di-tre-papi","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/","title":{"rendered":"Addio ad Angelo Gugel, al servizio di tre Papi"},"content":{"rendered":"<div class=\"nt_content\">\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Con discrezione e riserbo per mezzo secolo, tra la fine del XX secolo e l&#8217;alba del nuovo millennio, ha servito tre Papi come Camerlengo: Angelo Gugel, scomparso questa notte a Roma all&#8217;et\u00e0 di novant&#8217;anni, circondato dall&#8217;amore dei suoi familiari. Dal breve pontificato del veneto Giovanni Paolo I, che lo chiam\u00f2 tra i suoi collaboratori laici quando era ancora un giovane della sua terra, al lunghissimo pontificato di Giovanni Paolo II, di cui fu testimone silenzioso per quasi ventisette anni, e all&#8217;inizio del pontificato di Benedetto XVI, con il quale, ormai settantenne, concluse il suo servizio.<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nato il 27 aprile 1935 a Miane (Treviso), sposato dal 1964 con Maria Luisa Dall&#8217;Arche e padre di quattro figli \u2014Raffaella, Flaviana, Guido e Carla Luciana Maria\u2014, Gugel \u00e8 stato uno degli ultimi ad aver vissuto da vicino \u2014i Camerlenghi sono parte integrante della Famiglia Pontificia\u2014 la breve parentesi di Luciani sul soglio del Successore degli Apostoli, rendendo testimonianza nel processo che ne ha permesso la beatificazione; quella ben pi\u00f9 lunga con Wojty\u0142a alla guida della Barca di Pietro, al suo fianco anche al momento dell&#8217;attentato del 13 maggio 1981; e il primo periodo in cui al Papa polacco \u00e8 succeduto Ratzinger.<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nato in una famiglia contadina e con due anni di esperienza in seminario, fu reclutato come gendarme in Vaticano nel 1955. Dopo aver contratto la tubercolosi e aver sopportato una lunga convalescenza, fu trasferito al Governatorato, finch\u00e9 Luciani \u2013 il suo ex vescovo a Vittorio Veneto, che conosceva sua madre e sua moglie, avendo ordinato sacerdote il fratello di lei, padre Mario Dall&#8217;Arche \u2013 non lo volle con s\u00e9. Inoltre, aveva gi\u00e0 prestato servizio come autista di Luciani a Roma durante il Concilio Vaticano II e aveva cenato a casa sua.<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Sempre impeccabile nell&#8217;abbigliamento, con quell&#8217;eleganza sobria che non \u00e8 ostentazione, Angelo Gugel mantenne la discrezione che il suo delicato ruolo richiedeva anche dopo il pensionamento. Raramente concesse interviste. Nel centenario della nascita di San Giovanni Paolo II, ne condivise alcuni ricordi con il numero speciale curato da L&#8217;Osservatore Romano per celebrare l&#8217;anniversario. \u00abMi tremavano le gambe quando fui convocato nell&#8217;Appartamento dopo la morte di Giovanni Paolo I\u00bb, scrisse in quell&#8217;occasione, descrivendo la chiamata al Palazzo Apostolico del Papa \u00abvenuto da lontano\u00bb. \u00abMa il clima di fiducia instaurato dal Santo Padre\u00bb e \u00abanche da Monsignor Stanis\u0142aw e dalle suore, mi fece sentire &#8220;a casa&#8221;\u00bb, scrisse, riferendosi al segretario particolare di Wojty\u0142a, ora Cardinale Dziwisz, e alle suore polacche che lo assistevano.<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nel raccontare i 27 anni trascorsi con Giovanni Paolo II, ricchi di attivit\u00e0, incontri e viaggi, ha ricordato viaggi internazionali nei cinque continenti, ma anche momenti pi\u00f9 intimi, come i pochi giorni di vacanza in Cadore o in Valle d&#8217;Aosta, durante i quali persino Gugel rinunciava al suo solito abito scuro e alla cravatta per indossare maglioni e pantaloni da trekking. &#8220;Mantenere la discrezione sul mio lavoro, anche in famiglia, era normale. Quando uscivamo privatamente con il Santo Padre, i miei parenti lo scoprivano dai giornali&#8221;, ha aggiunto. E ha continuato a ricordare ogni momento dell&#8217;attentato del 13 maggio 1981: dal foro di proiettile, al Papa steso a terra all&#8217;ingresso del palazzo dei Servizi Sanitari Vaticani, alla lunga corsa al Policlinico Gemelli.<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">In un&#8217;intervista del 2018 al Corriere della Sera, Gugel raccont\u00f2 due aneddoti: &#8220;Due giorni dopo l&#8217;elezione, il Sostituto per gli Affari Generali della Segreteria di Stato, Giuseppe Caprio, telefon\u00f2 al Governatorato alle 11:30 dicendo: &#8216;Signor Gugel, si presenti nell&#8217;appartamento privato del Papa cos\u00ec come \u00e8 vestito&#8217;. Salii all&#8217;ultimo piano del Palazzo Apostolico. Mi tremavano le gambe. C&#8217;erano solo prelati polacchi; ero l&#8217;unico a parlare italiano&#8221;. Un&#8217;abilit\u00e0 utile per aiutare il nuovo Papa a pronunciare correttamente i suoi primi discorsi. \u201cRimasi sbalordito quando, la mattina del 22 ottobre 1978, prima di recarmi in Piazza San Pietro per la solenne inaugurazione del suo pontificato, il Santo Padre mi chiam\u00f2 nel suo studio e mi lesse l&#8217;omelia che avrebbe pronunciato di l\u00ec a poco: \u2018Non abbiate paura! Aprite, anzi &#8230;<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Nella stessa intervista, ha ricordato quando sua moglie, Maria Luisa, aspettava la loro quarta figlia, che avrebbero chiamato Carla Luciana Maria in onore di Papa Luciani e Papa Giovanni Paolo II. Durante la gravidanza, raccont\u00f2, &#8220;insorsero gravissimi problemi all&#8217;utero. I ginecologi del Policlinico Gemelli \u2013 Bompiani, Forleo e Villani \u2013 esclusero la possibilit\u00e0 che la gravidanza continuasse. Un giorno, Giovanni Paolo II mi disse: &#8216;Oggi ho celebrato la Messa per sua moglie&#8217;. Il 9 aprile, Maria Luisa fu portata in sala operatoria per un taglio cesareo. Uscendo, il dottor Villani osserv\u00f2: &#8216;Qualcuno deve aver pregato molto&#8217;. Sul certificato di nascita, scrisse &#8216;7:15&#8217;, l&#8217;esatto momento in cui il Papa celebrava la Messa mattutina nel Sanctus. A colazione, suor Tobiana Sobotka, superiora delle suore in servizio presso il Palazzo Apostolico, inform\u00f2 il Papa che era nata Carla Luciana Maria. &#8216;Deo gratias&#8217;, esclam\u00f2 Wojty\u0142a. E il 27 aprile, volle essere lui a battezzarla nella cappella privata&#8221;.<\/span><\/span><\/p>\n<p dir=\"auto\"><b><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">L&#8217;Osservatore Romano<\/span><\/span><\/b><\/p>\n<\/div>\n<div class=\"author_bio \"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 stato il cameriere personale di Giovanni Paolo I, Giovanni Paolo II e Benedetto XVI. \u00c8 morto ieri sera a Roma all&#8217;et\u00e0 di 90 anni. Uomo fedele e riservato, era con Papa Giovanni Paolo II il giorno dell&#8217;attentato in Piazza San Pietro, il 13 maggio 1981<\/p>\n","protected":false},"author":17,"featured_media":154001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[71],"tags":[89499,89497,89498,89500,89501,1722,89504,10288,1987,1671,89502,10744,6513,89505,89503,28779,46016,89507,89509,89510,89511,53588,89508,89506,89512,89513,266],"class_list":["post-154067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisi","tag-aiutante-di-campo","tag-angelo-gugel-2","tag-attentato-a-san-pietro-del-1981","tag-battesimo-del-papa","tag-beatificazione-di-giovanni-paolo-i","tag-benedetto-xvi","tag-famiglia-pontificia","tag-gendarmeria-vaticana","tag-giovanni-paolo-i","tag-giovanni-paolo-ii","tag-intervista-al-corriere-della-sera","tag-losservatore-romano-4","tag-luciani","tag-miane","tag-morte-di-angelo-gugel","tag-papa-polacco","tag-policlinico-gemelli-2","tag-pontificato-di-wojtyla","tag-segreto-papale","tag-servizio-papale","tag-stanislaw-dziwisz-2","tag-storia-del-vaticano","tag-suora-polacca","tag-treviso","tag-vacanze-in-cadore","tag-valle-daosta","tag-vaticano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Addio ad Angelo Gugel, al servizio di tre Papi &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Addio ad Angelo Gugel, al servizio di tre Papi &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"\u00c8 stato il cameriere personale di Giovanni Paolo I, Giovanni Paolo II e Benedetto XVI. \u00c8 morto ieri sera a Roma all&#039;et\u00e0 di 90 anni. Uomo fedele e riservato, era con Papa Giovanni Paolo II il giorno dell&#039;attentato in Piazza San Pietro, il 13 maggio 1981\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-16T22:36:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/01\/cq5dam.thumbnail.cropped.750.422-7.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"Addio ad Angelo Gugel, al servizio di tre Papi\",\"datePublished\":\"2026-01-16T22:36:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/\"},\"wordCount\":828,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cq5dam.thumbnail.cropped.750.422-7.jpeg?fit=750%2C422&ssl=1\",\"keywords\":[\"Aiutante di Campo\",\"Angelo Gugel\",\"Attentato a San Pietro del 1981\",\"Battesimo del Papa\",\"Beatificazione di Giovanni Paolo I\",\"Benedetto XVI\",\"Famiglia pontificia\",\"Gendarmeria Vaticana\",\"Giovanni Paolo I\",\"Giovanni Paolo II\",\"Intervista al Corriere della Sera\",\"L'OSSERVATORE ROMANO\",\"Luciani\",\"Miane\",\"Morte di Angelo Gugel\",\"Papa polacco\",\"policlinico Gemelli\",\"Pontificato di Wojty\u0142a\",\"Segreto papale\",\"Servizio papale\",\"Stanis\u0142aw Dziwisz\",\"storia del Vaticano\",\"Suora polacca\",\"Treviso\",\"Vacanze in Cadore\",\"Valle d'Aosta\",\"Vaticano\"],\"articleSection\":[\"Analisi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/\",\"name\":\"Addio ad Angelo Gugel, al servizio di tre Papi &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cq5dam.thumbnail.cropped.750.422-7.jpeg?fit=750%2C422&ssl=1\",\"datePublished\":\"2026-01-16T22:36:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cq5dam.thumbnail.cropped.750.422-7.jpeg?fit=750%2C422&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cq5dam.thumbnail.cropped.750.422-7.jpeg?fit=750%2C422&ssl=1\",\"width\":750,\"height\":422,\"caption\":\"Angelo Gugel (a la izquierda en el papam\u00f3vil) sostiene a Juan Pablo II en sus brazos, despu\u00e9s de que le dispararan en el intento de asesinato del 13 de mayo de 1981 . Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Addio ad Angelo Gugel, al servizio di tre Papi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Addio ad Angelo Gugel, al servizio di tre Papi &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/","og_locale":"it_IT","og_type":"article","og_title":"Addio ad Angelo Gugel, al servizio di tre Papi &#8211; Exaudi","og_description":"\u00c8 stato il cameriere personale di Giovanni Paolo I, Giovanni Paolo II e Benedetto XVI. \u00c8 morto ieri sera a Roma all'et\u00e0 di 90 anni. Uomo fedele e riservato, era con Papa Giovanni Paolo II il giorno dell'attentato in Piazza San Pietro, il 13 maggio 1981","og_url":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2026-01-16T22:36:31+00:00","og_image":[{"width":750,"height":422,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/01\/cq5dam.thumbnail.cropped.750.422-7.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"Addio ad Angelo Gugel, al servizio di tre Papi","datePublished":"2026-01-16T22:36:31+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/"},"wordCount":828,"image":{"@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/01\/cq5dam.thumbnail.cropped.750.422-7.jpeg?fit=750%2C422&ssl=1","keywords":["Aiutante di Campo","Angelo Gugel","Attentato a San Pietro del 1981","Battesimo del Papa","Beatificazione di Giovanni Paolo I","Benedetto XVI","Famiglia pontificia","Gendarmeria Vaticana","Giovanni Paolo I","Giovanni Paolo II","Intervista al Corriere della Sera","L'OSSERVATORE ROMANO","Luciani","Miane","Morte di Angelo Gugel","Papa polacco","policlinico Gemelli","Pontificato di Wojty\u0142a","Segreto papale","Servizio papale","Stanis\u0142aw Dziwisz","storia del Vaticano","Suora polacca","Treviso","Vacanze in Cadore","Valle d'Aosta","Vaticano"],"articleSection":["Analisi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/","url":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/","name":"Addio ad Angelo Gugel, al servizio di tre Papi &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/01\/cq5dam.thumbnail.cropped.750.422-7.jpeg?fit=750%2C422&ssl=1","datePublished":"2026-01-16T22:36:31+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/01\/cq5dam.thumbnail.cropped.750.422-7.jpeg?fit=750%2C422&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/01\/cq5dam.thumbnail.cropped.750.422-7.jpeg?fit=750%2C422&ssl=1","width":750,"height":422,"caption":"Angelo Gugel (a la izquierda en el papam\u00f3vil) sostiene a Juan Pablo II en sus brazos, despu\u00e9s de que le dispararan en el intento de asesinato del 13 de mayo de 1981 . Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/addio-ad-angelo-gugel-al-servizio-di-tre-papi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Addio ad Angelo Gugel, al servizio di tre Papi"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/01\/cq5dam.thumbnail.cropped.750.422-7.jpeg?fit=750%2C422&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-E4X","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/154067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=154067"}],"version-history":[{"count":3,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/154067\/revisions"}],"predecessor-version":[{"id":154070,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/154067\/revisions\/154070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/154001"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=154067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=154067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=154067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}