{"id":152554,"date":"2026-01-05T18:15:20","date_gmt":"2026-01-05T17:15:20","guid":{"rendered":"https:\/\/exaudi.org\/?p=152554"},"modified":"2026-01-05T18:24:49","modified_gmt":"2026-01-05T17:24:49","slug":"cardinale-arizmendi-esame-finale-i-poveri","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/","title":{"rendered":"Cardinale Arizmendi: Esame finale: I poveri"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il cardinale\u00a0 <\/span><\/span><a href=\"https:\/\/exaudi.org\/es\/author\/felipearizmendi\/\" target=\"_blank\" rel=\"noopener\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Felipe Arizmendi<\/span><\/span><\/a><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, vescovo emerito di San Crist\u00f3bal de Las Casas e responsabile della Dottrina della fede presso la\u00a0 <\/span><\/span><a href=\"https:\/\/www.cem.org.mx\/\" target=\"_blank\" rel=\"noopener\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Conferenza episcopale messicana (CEM)<\/span><\/span><\/a><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, offre ai lettori di Exaudi il suo articolo settimanale.<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">FATTI<\/span><\/span><\/strong><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Vale la pena riflettere sugli aspetti positivi e negativi di questi ultimi dodici mesi. Cosa abbiamo fatto bene? Quali cose positive ci sono successe? Cosa ricordiamo con affetto? Al contrario, cosa \u00e8 andato storto? Cosa avremmo voluto che non fosse successo? Cosa dovremmo correggere?<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Sono molti i punti in cui questo esame di vita dovrebbe essere intrapreso, ma desidero sottolineare la necessit\u00e0 di una revisione personale ed ecclesiale di come abbiamo dimostrato il nostro amore per coloro che si trovano in povert\u00e0 a causa delle loro circostanze. Capisco che per alcuni possa essere fastidioso che io ne parli cos\u00ec tanto, ma \u00e8 la guida per sapere se stiamo seguendo la via di Ges\u00f9, ed \u00e8 l&#8217;esame che, secondo San Matteo, ci verr\u00e0 posto alla fine della nostra vita.<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">FULMINE<\/span><\/span><\/strong><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Continuo a condividere con voi alcune affermazioni categoriche di Papa Leone XIV nella sua esortazione\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Dilexi te, sull&#8217;amore<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0per i poveri. Riflettere su di esse ci aiuter\u00e0 a fare un buon esame di coscienza di fine anno.<\/span><\/span><\/p>\n<p><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abLa chiamata del Signore alla misericordia verso i poveri ha trovato la sua espressione pi\u00f9 piena nella grande parabola del Giudizio finale (cfr Mt 25,31-46), che \u00e8 anche una descrizione vivida della beatitudine dei misericordiosi. L\u00ec il Signore ci offre la chiave per raggiungere la nostra pienezza, perch\u00e9 se cerchiamo quella santit\u00e0 che piace a Dio, in questo testo troviamo precisamente un protocollo sul quale saremo giudicati. Le parole forti e chiare del Vangelo vanno vissute senza commenti, senza speculazioni e scuse che ne sminuiscono la forza. Il Signore ci ha fatto capire molto chiaramente che la santit\u00e0 non pu\u00f2 essere compresa n\u00e9 vissuta senza queste sue esigenze\u00bb<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0(28).<\/span><\/span><\/p>\n<p><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abCi\u00f2 che dice la Parola rivelata \u00e8 un messaggio cos\u00ec chiaro, cos\u00ec diretto, cos\u00ec semplice ed eloquente, che nessuna ermeneutica ecclesiale ha il diritto di relativizzarlo. La riflessione della Chiesa su questi testi non deve oscurare o indebolire il loro senso esortativo, ma piuttosto aiutare ad accoglierli con coraggio e fervore. Perch\u00e9 complicare ci\u00f2 che \u00e8 cos\u00ec semplice? Gli schemi concettuali hanno lo scopo di facilitare il contatto con la realt\u00e0 che cercano di spiegare, non di allontanarci da essa\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (31).<\/span><\/span><\/p>\n<p><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abLa Chiesa riconosce nei poveri e nei sofferenti l\u2019immagine del suo Fondatore, povero e paziente, si sforza di porre rimedio alle loro necessit\u00e0 e cerca di servire Cristo in loro. Infatti, essendo stata chiamata a conformarsi agli ultimi, non ci devono essere dubbi in lei, n\u00e9 spiegazioni che indeboliscano questo chiaro messaggio. Bisogna dire con chiarezza che esiste un legame inscindibile tra la nostra fede e i poveri\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (36).<\/span><\/span><\/p>\n<p><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abFin dai primi secoli, i Padri della Chiesa hanno riconosciuto nei poveri un accesso privilegiato a Dio, una via privilegiata per incontrarlo. La carit\u00e0 verso i bisognosi non era intesa come una mera virt\u00f9 morale, ma come espressione concreta della fede nel Verbo incarnato\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (39). <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0\u00abLa Chiesa primitiva non separava la fede dall\u2019azione sociale: la fede che non era accompagnata dalla testimonianza delle opere, come aveva insegnato Giacomo, era considerata morta\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (40). <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0\u00abPertanto, la carit\u00e0 non \u00e8 una via facoltativa, ma il criterio del vero culto\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (42).<\/span><\/span><\/p>\n<p><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abPer sant\u2019Agostino, il povero non \u00e8 solo qualcuno da aiutare, ma la presenza sacramentale del Signore\u00bb<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (44). <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0\u00abIl Vangelo \u00e8 veramente annunciato solo quando tocca la carne degli ultimi, e avvertendo che il rigore dottrinale senza misericordia \u00e8 una parola vuota\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (48). <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0Secondo san Basilio, per essere vicini a Dio bisogna essere vicini ai poveri. L\u2019amore concreto era il criterio della santit\u00e0. Pregare e prendersi cura, contemplare e guarire, scrivere e accogliere: tutte sono espressioni dello stesso amore per Cristo\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (54). <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0\u00abI poveri non sono un problema da risolvere, ma fratelli e sorelle da accogliere\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (56). <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0\u00abPer san Bernardo, la compassione non \u00e8 un optional, ma la via maestra per seguire Cristo\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (58).<\/span><\/span><\/p>\n<p><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abLa carit\u00e0 cristiana, quando si incarna, diventa liberante. E la missione della Chiesa, quando \u00e8 fedele al suo Signore, \u00e8 sempre quella di annunciare la liberazione\u2026 Quando la Chiesa si inginocchia per spezzare le nuove catene che imprigionano i poveri, diventa segno della Pasqua\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (61). <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0\u00abPer la fede cristiana, l\u2019educazione dei poveri non \u00e8 un favore, ma un dovere\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (72). \u00ab <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">I pi\u00f9 poveri tra i poveri \u2013 coloro che non solo mancano di beni materiali, ma anche di voce e riconoscimento della loro dignit\u00e0 \u2013 occupano un posto speciale nel cuore di Dio. Sono gli eletti del Vangelo, gli eredi del Regno. \u00c8 in loro che Cristo continua a soffrire e a risorgere. \u00c8 in loro che la Chiesa riscopre la chiamata a mostrare la sua realt\u00e0 pi\u00f9 autentica\u00bb<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (76).<\/span><\/span><\/p>\n<p><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00abI pi\u00f9 poveri non sono semplici oggetti di compassione, ma maestri del Vangelo. Non si tratta di \u201cportare loro Dio\u201d, ma di trovarlo in mezzo a loro. Servire i poveri non \u00e8 un gesto dall\u2019alto, ma un incontro tra pari, dove Cristo viene rivelato e adorato\u2026 Per questo, quando la Chiesa si china fino a terra per prendersi cura dei poveri, assume la sua posizione pi\u00f9 alta\u00bb\u00a0<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> (79).<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">AZIONI<\/span><\/span><\/strong><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Quando voi e io saremo di fronte al giudizio finale, ci verr\u00e0 chiesto cosa abbiamo fatto per i prigionieri, i migranti, i malati e coloro che sono privi di risorse. Nell&#8217;ultimo anno, cosa abbiamo fatto per loro? Che possiamo essere pi\u00f9 cristiani quest&#8217;anno in questo amore preferenziale.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cosa abbiamo fatto per loro quest&#8217;anno?<\/p>\n","protected":false},"author":24,"featured_media":152405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[129],"tags":[87807,87813,11088,15413,20288,668,64850,34560,13670,64796,87808,87809,87810,15918,51279,87339,81081,2829,87811,472,1128,4696,29566,61020,58164,1043,1109,87814,44899,87815,22549,1896,64787,79341,87812],"class_list":["post-152554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voci","tag-amore-preferenziale-per-i-poveri","tag-carcerati","tag-cardinale-felipe-arizmendi","tag-cardinale-felipe-arizmendi-esquivel","tag-carita-cristiana","tag-chiesa","tag-chiesa-cattolica-it","tag-conferenza-episcopale-messicana","tag-cristiano-2","tag-dottrina-sociale-della-chiesa-it","tag-esame","tag-esame-finale","tag-esortazione-dilexi-te","tag-exaudi-3","tag-fede-e-opere","tag-fine-anno","tag-giudizio-universale","tag-malati","tag-matteo-25","tag-migranti","tag-misericordia","tag-natale","tag-opzione-preferenziale-per-i-poveri","tag-padri-della-chiesa","tag-papa-leone-xiv","tag-poveri","tag-poverta","tag-riflessione-di-fine-anno","tag-san-basilio-2","tag-san-bernardo-2","tag-santagostino","tag-santita","tag-trending-it-236","tag-vangelo-dei-poveri","tag-vescovo-emerito-san-cristobal-de-las-casas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cardinale Arizmendi: Esame finale: I poveri &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cardinale Arizmendi: Esame finale: I poveri &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Cosa abbiamo fatto per loro quest&#039;anno?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-05T17:15:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-05T17:24:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/01\/pexels-rdne-6069351-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cardenal Felipe Arizmendi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cardenal Felipe Arizmendi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/\"},\"author\":{\"name\":\"Cardenal Felipe Arizmendi\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c7d223f87e58f1105d044d8da1439102\"},\"headline\":\"Cardinale Arizmendi: Esame finale: I poveri\",\"datePublished\":\"2026-01-05T17:15:20+00:00\",\"dateModified\":\"2026-01-05T17:24:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/\"},\"wordCount\":888,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/pexels-rdne-6069351-scaled.jpg\",\"keywords\":[\"Amore preferenziale per i poveri\",\"Carcerati\",\"CARDINALE FELIPE ARIZMENDI\",\"CARDINALE FELIPE ARIZMENDI ESQUIVEL\",\"CARIT\u00c0 CRISTIANA\",\"Chiesa\",\"CHIESA CATTOLICA\",\"Conferenza Episcopale Messicana\",\"CRISTIANO\",\"Dottrina sociale della Chiesa\",\"Esame\",\"Esame finale\",\"Esortazione Dilexi te\",\"EXAUDI\",\"fede e opere\",\"Fine anno\",\"Giudizio Universale\",\"malati\",\"Matteo 25\",\"migranti\",\"misericordia\",\"natale\",\"opzione preferenziale per i poveri\",\"Padri della Chiesa\",\"Papa Leone XIV\",\"poveri\",\"povert\u00e0\",\"Riflessione di fine anno\",\"San Basilio\",\"San Bernardo\",\"Sant'Agostino\",\"santit\u00e0\",\"Trending\",\"Vangelo dei poveri\",\"Vescovo emerito San Crist\u00f3bal de las Casas\"],\"articleSection\":[\"Voci\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/\",\"name\":\"Cardinale Arizmendi: Esame finale: I poveri &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/pexels-rdne-6069351-scaled.jpg\",\"datePublished\":\"2026-01-05T17:15:20+00:00\",\"dateModified\":\"2026-01-05T17:24:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c7d223f87e58f1105d044d8da1439102\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/pexels-rdne-6069351-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/pexels-rdne-6069351-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/cardinale-arizmendi-esame-finale-i-poveri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cardinale Arizmendi: Esame finale: I poveri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c7d223f87e58f1105d044d8da1439102\",\"name\":\"Cardenal Felipe Arizmendi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g\",\"caption\":\"Cardenal Felipe Arizmendi\"},\"description\":\"Nacido en Chiltepec el 1 de mayo de 1940. Estudi\u00f3 Humanidades y Filosof\u00eda en el Seminario de Toluca, de 1952 a 1959. Curs\u00f3 la Teolog\u00eda en la Universidad Pontificia de Salamanca, Espa\u00f1a, de 1959 a 1963, obteniendo la licenciatura en Teolog\u00eda Dogm\u00e1tica. Por su cuenta, se especializ\u00f3 en Liturgia. Fue ordenado sacerdote el 25 de agosto de 1963 en Toluca. Sirvi\u00f3 como Vicario Parroquial en tres parroquias por tres a\u00f1os y medio y fue p\u00e1rroco de una comunidad ind\u00edgena otom\u00ed, de 1967 a 1970. Fue Director Espiritual del Seminario de Toluca por diez a\u00f1os, y Rector del mismo de 1981 a 1991. El 7 de marzo de 1991, fue ordenado obispo de la di\u00f3cesis de Tapachula, donde estuvo hasta el 30 de abril del a\u00f1o 2000. El 1 de mayo del 2000, inici\u00f3 su ministerio episcopal como XLVI obispo de la di\u00f3cesis de San Crist\u00f3bal de las Casas, Chiapas, una de las di\u00f3cesis m\u00e1s antiguas de M\u00e9xico, erigida en 1539; all\u00ed sirvi\u00f3 por casi 18 a\u00f1os. Ha ocupado diversos cargos en la Conferencia del Episcopado Mexicano y en el CELAM. El 3 de noviembre de 2017, el Papa Francisco le acept\u00f3, por edad, su renuncia al servicio episcopal en esta di\u00f3cesis, que entreg\u00f3 a su sucesor el 3 de enero de 2018. Desde entonces, reside en la ciudad de Toluca. Desde 1979, escribe art\u00edculos de actualidad en varios medios religiosos y civiles. Es autor de varias publicaciones.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/felipearizmendi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cardinale Arizmendi: Esame finale: I poveri &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/","og_locale":"it_IT","og_type":"article","og_title":"Cardinale Arizmendi: Esame finale: I poveri &#8211; Exaudi","og_description":"Cosa abbiamo fatto per loro quest'anno?","og_url":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2026-01-05T17:15:20+00:00","article_modified_time":"2026-01-05T17:24:49+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/01\/pexels-rdne-6069351-scaled.jpg","type":"image\/jpeg"}],"author":"Cardenal Felipe Arizmendi","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Cardenal Felipe Arizmendi","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/"},"author":{"name":"Cardenal Felipe Arizmendi","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c7d223f87e58f1105d044d8da1439102"},"headline":"Cardinale Arizmendi: Esame finale: I poveri","datePublished":"2026-01-05T17:15:20+00:00","dateModified":"2026-01-05T17:24:49+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/"},"wordCount":888,"image":{"@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/01\/pexels-rdne-6069351-scaled.jpg","keywords":["Amore preferenziale per i poveri","Carcerati","CARDINALE FELIPE ARIZMENDI","CARDINALE FELIPE ARIZMENDI ESQUIVEL","CARIT\u00c0 CRISTIANA","Chiesa","CHIESA CATTOLICA","Conferenza Episcopale Messicana","CRISTIANO","Dottrina sociale della Chiesa","Esame","Esame finale","Esortazione Dilexi te","EXAUDI","fede e opere","Fine anno","Giudizio Universale","malati","Matteo 25","migranti","misericordia","natale","opzione preferenziale per i poveri","Padri della Chiesa","Papa Leone XIV","poveri","povert\u00e0","Riflessione di fine anno","San Basilio","San Bernardo","Sant'Agostino","santit\u00e0","Trending","Vangelo dei poveri","Vescovo emerito San Crist\u00f3bal de las Casas"],"articleSection":["Voci"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/","url":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/","name":"Cardinale Arizmendi: Esame finale: I poveri &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/01\/pexels-rdne-6069351-scaled.jpg","datePublished":"2026-01-05T17:15:20+00:00","dateModified":"2026-01-05T17:24:49+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/c7d223f87e58f1105d044d8da1439102"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/01\/pexels-rdne-6069351-scaled.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/01\/pexels-rdne-6069351-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/cardinale-arizmendi-esame-finale-i-poveri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Cardinale Arizmendi: Esame finale: I poveri"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c7d223f87e58f1105d044d8da1439102","name":"Cardenal Felipe Arizmendi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g","caption":"Cardenal Felipe Arizmendi"},"description":"Nacido en Chiltepec el 1 de mayo de 1940. Estudi\u00f3 Humanidades y Filosof\u00eda en el Seminario de Toluca, de 1952 a 1959. Curs\u00f3 la Teolog\u00eda en la Universidad Pontificia de Salamanca, Espa\u00f1a, de 1959 a 1963, obteniendo la licenciatura en Teolog\u00eda Dogm\u00e1tica. Por su cuenta, se especializ\u00f3 en Liturgia. Fue ordenado sacerdote el 25 de agosto de 1963 en Toluca. Sirvi\u00f3 como Vicario Parroquial en tres parroquias por tres a\u00f1os y medio y fue p\u00e1rroco de una comunidad ind\u00edgena otom\u00ed, de 1967 a 1970. Fue Director Espiritual del Seminario de Toluca por diez a\u00f1os, y Rector del mismo de 1981 a 1991. El 7 de marzo de 1991, fue ordenado obispo de la di\u00f3cesis de Tapachula, donde estuvo hasta el 30 de abril del a\u00f1o 2000. El 1 de mayo del 2000, inici\u00f3 su ministerio episcopal como XLVI obispo de la di\u00f3cesis de San Crist\u00f3bal de las Casas, Chiapas, una de las di\u00f3cesis m\u00e1s antiguas de M\u00e9xico, erigida en 1539; all\u00ed sirvi\u00f3 por casi 18 a\u00f1os. Ha ocupado diversos cargos en la Conferencia del Episcopado Mexicano y en el CELAM. El 3 de noviembre de 2017, el Papa Francisco le acept\u00f3, por edad, su renuncia al servicio episcopal en esta di\u00f3cesis, que entreg\u00f3 a su sucesor el 3 de enero de 2018. Desde entonces, reside en la ciudad de Toluca. Desde 1979, escribe art\u00edculos de actualidad en varios medios religiosos y civiles. Es autor de varias publicaciones.","url":"https:\/\/exaudi.org\/it\/author\/felipearizmendi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/01\/pexels-rdne-6069351-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-DGy","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/152554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=152554"}],"version-history":[{"count":4,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/152554\/revisions"}],"predecessor-version":[{"id":152565,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/152554\/revisions\/152565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/152405"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=152554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=152554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=152554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}