{"id":144741,"date":"2025-11-03T15:53:32","date_gmt":"2025-11-03T14:53:32","guid":{"rendered":"https:\/\/exaudi.org\/?p=144741"},"modified":"2025-11-03T15:53:32","modified_gmt":"2025-11-03T14:53:32","slug":"la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/","title":{"rendered":"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza"},"content":{"rendered":"<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cari fratelli e sorelle in Cristo, il 1\u00b0 novembre abbiamo celebrato la solennit\u00e0 di Tutti i Santi, contemplando la\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Chiesa Trionfante<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, che gi\u00e0 gode della visione beatifica in Cielo. Il giorno seguente, 2 novembre, abbiamo pregato per la\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Chiesa Sofferente<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, quelle anime purificate dall&#8217;amore prima di entrare nella gloria eterna. Ora, in questo Tempo Ordinario che segue, la liturgia ci invita a guardare a noi stessi: siamo la\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Chiesa Militante<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, l&#8217;esercito vivo di Cristo che cammina, combatte e si santifica sulla terra. Che privilegio e che bella chiamata!<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il Catechismo della Chiesa Cattolica ce lo insegna chiaramente: \u00abLa Chiesa sulla terra \u00e8\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Chiesa militante<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0perch\u00e9 lotta contro il peccato, il mondo e il diavolo, sotto la guida di Cristo, suo Capo\u00bb (CCC 954, citando Lumen\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Gentium<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a048-50). Non siamo un circolo sociale o una semplice istituzione: siamo\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">soldati della luce<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, come dice San Paolo: \u00abRivestitevi dell\u2019armatura di Dio, per poter resistere alle insidie del diavolo\u00bb (Ef 6,11). Ma questa lotta non \u00e8 cupa o senza speranza; al contrario, \u00e8\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">una battaglia gioiosa<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, perch\u00e9 Cristo ha gi\u00e0 vinto: \u00abCoraggio, io ho vinto il mondo\u00bb (Gv 16,33).<\/span><\/span><\/p>\n<h3 dir=\"auto\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cosa significa essere un attivista oggi?<\/span><\/span><\/strong><\/h3>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Far parte della Chiesa Militante significa\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">ricercare la santit\u00e0 nel quotidiano<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, con la certezza che ogni piccolo atto d&#8217;amore ci unisce pi\u00f9 strettamente a Cristo e ai santi che ci hanno preceduto. Il Concilio Vaticano II lo esprime splendidamente in\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Lumen Gentium<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a040: &#8220;Tutti i fedeli, di qualsiasi stato o condizione, sono chiamati alla pienezza della vita cristiana e alla perfezione della carit\u00e0&#8221;. Tutti! Il papa, il vescovo, il sacerdote, il padre, la madre che allatta, lo studente, l&#8217;operaio, il malato a letto&#8230; ognuno \u00e8 un\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">combattente per la santit\u00e0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">.<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">San Josemar\u00eda Escriv\u00e1, canonizzato da san Giovanni Paolo II, lo visse con zelo apostolico: \u00abLa santit\u00e0 non consiste in grandi gesta eroiche \u2013 che ordinariamente non accadono \u2013 ma nell\u2019amare\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">profondamente Dio e servirlo nelle cose ordinarie<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00bb (<\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00c8 Ges\u00f9 che passa<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, 2). Che incoraggiamento! Non abbiamo bisogno di miracoli spettacolari; \u00e8 sufficiente offrire un lavoro ben fatto, un sorriso di fronte alle difficolt\u00e0, un perdono pronto e una preghiera fedele.<\/span><\/span><\/p>\n<h3 dir=\"auto\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Armi di lotta: i sacramenti e la preghiera<\/span><\/span><\/strong><\/h3>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La nostra forza non viene da noi stessi, ma da Cristo. Il Catechismo ci ricorda che \u00abl\u2019Eucaristia \u00e8 il\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">centro e il culmine<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0della vita cristiana\u00bb (CCC 1324). Partecipiamo alla Messa quotidiana, se possibile, o almeno a quella domenicale: l\u00ec riceviamo il\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Pane dei forti<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0(cfr Sap 16,20). La confessione ci purifica e ci fortifica: \u00abChi mangia la mia carne e beve il mio sangue ha la vita eterna\u00bb (Gv 6,54).<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La preghiera \u00e8 il nostro\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">scudo<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">. Il\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Compendio del Catechismo<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0(n. 566) insegna che \u00abla preghiera \u00e8 l\u2019elevazione dell\u2019anima a Dio\u00bb. Dedichiamo tempo al Rosario \u2013 arma potente, secondo San Pio V \u2013 alla Lectio Divina e all\u2019Adorazione Eucaristica. San Giovanni Paolo II ci incoraggiava: \u00abNon abbiate paura! Aprite, anzi, spalancate le porte a Cristo!\u00bb (<\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Omelia all\u2019inizio del suo pontificato<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, 1978). Nella preghiera, lo Spirito Santo ci d\u00e0\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">coraggio per la battaglia<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">.<\/span><\/span><\/p>\n<h3 dir=\"auto\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Combattere insieme: la comunione dei santi<\/span><\/span><\/strong><\/h3>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Non siamo soli.\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La Lumen Gentium<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a050 ci dice che \u00abl&#8217;unione dei membri della Chiesa pellegrina con i nostri fratelli addormentati nella pace di Cristo\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">non \u00e8 in alcun modo interrotta<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00bb. I santi ci incoraggiano dal Cielo! Chiediamo la loro intercessione: San Michele Arcangelo contro il male, Santa Teresa d&#8217;Avila nell&#8217;aridit\u00e0 spirituale, San Giuseppe nel nostro lavoro.<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">E aiutiamo le anime del Purgatorio con preghiere per loro: Messe, rosari, indulgenze. Come insegna il Catechismo (CCC 958), &#8220;la nostra preghiera per loro pu\u00f2 non solo aiutarle, ma anche rendere efficace la loro intercessione a nostro favore&#8221;. \u00c8 una catena d&#8217;amore che ci unisce nelle tre Chiese!<\/span><\/span><\/p>\n<h3 dir=\"auto\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Vivere l&#8217;attivismo con gioia<\/span><\/span><\/strong><\/h3>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">San Paolo ci esorta: \u00abCombatti la buona battaglia della fede\u00bb (1 Tm 6,12), ma sempre con gioia: \u00abSiate sempre lieti nel Signore; ve lo ripeto: siate lieti\u00bb (Fil 4,4). Benedetto XVI, nella\u00a0 <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Spe salvi<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a035, ci ha ricordato che \u00abla vita \u00e8 come una\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">campagna<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u00a0che diventa vittoria se \u00e8 vissuta con Cristo\u00bb.<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">In questo mondo secolarizzato, siamo\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">testimoni luminosi<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">. Come diceva il Beato Carlo Acutis: \u00abTutti nascono originali, ma molti muoiono fotocopie\u00bb. Siamo originali di Cristo! Nelle nostre famiglie, al lavoro, sui social media: annunciamo il Vangelo con la vita e le parole.<\/span><\/span><\/p>\n<h3 dir=\"auto\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Avanti, soldati di Cristo!<\/span><\/span><\/strong><\/h3>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cari fratelli e sorelle, la Chiesa militante non \u00e8 un museo di reliquie, ma un\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">esercito in marcia verso la santit\u00e0<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">. Con Maria, Regina dei Martiri e Madre della Chiesa, combattiamo con fiducia. Come insegna il Catechismo (CCC 2015): \u00abLa via della perfezione passa attraverso la croce. Non c&#8217;\u00e8 santit\u00e0 senza rinuncia e combattimento spirituale\u00bb.<\/span><\/span><\/p>\n<p dir=\"auto\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Coraggio! Cristo cammina con noi. Ogni giorno \u00e8 un&#8217;opportunit\u00e0 per crescere nell&#8217;amore. Un giorno \u2013 presto, speriamo \u2013 entreremo a far parte della Chiesa Trionfante. Nel frattempo,\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">combattiamo con gioia<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, sapendo che &#8220;n\u00e9 morte n\u00e9 vita&#8230; potranno separarci dall&#8217;amore di Dio che \u00e8 in Cristo Ges\u00f9&#8221; (Rm 8,38-39).<\/span><\/span><\/p>\n<p dir=\"auto\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Viva Cristo Re! Viva la Chiesa militante! <\/span><\/span><\/strong>\u00a0<em><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">San Michele Arcangelo, difendici nella battaglia.<\/span><\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soldati di Cristo nella battaglia per la santit\u00e0<\/p>\n","protected":false},"author":149,"featured_media":144385,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[71],"tags":[25068,79808,79809,79810,5750,6921,560,1384,37218,25656,79807,24459,12236,79811,26602,1862,2547,10333,3238,20209,67980,64787],"class_list":["post-144741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisi","tag-catechismo-della-chiesa-cattolica","tag-chiesa-militante","tag-chiesa-sofferente","tag-chiesa-trionfante","tag-comunione-dei-santi","tag-concilio-vaticano-ii-2","tag-confessione","tag-eucaristia","tag-gioia-nella-fede","tag-javier-ferrer-garcia-2","tag-lotta-contro-il-peccato","tag-lotta-spirituale","tag-lumen-gentium-2","tag-militanza-cristiana","tag-preghiera-cristiana","tag-rosario","tag-sacramenti","tag-san-giovanni-paolo-ii","tag-san-josemaria-escriva","tag-santi-cattolici","tag-santita-quotidiana","tag-trending-it-236"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Soldati di Cristo nella battaglia per la santit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-03T14:53:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/11\/rafa-disputa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Javier Ferrer Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Ferrer Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/\"},\"author\":{\"name\":\"Javier Ferrer Garc\u00eda\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/0428626ea256fe1d193098fe0ee2b91d\"},\"headline\":\"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza\",\"datePublished\":\"2025-11-03T14:53:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/\"},\"wordCount\":821,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/rafa-disputa.jpg?fit=800%2C600&ssl=1\",\"keywords\":[\"Catechismo della Chiesa Cattolica\",\"Chiesa militante\",\"Chiesa sofferente\",\"Chiesa trionfante\",\"comunione dei santi\",\"Concilio Vaticano II\",\"confessione\",\"Eucaristia\",\"gioia nella fede\",\"Javier Ferrer Garc\u00eda\",\"Lotta contro il peccato\",\"lotta spirituale\",\"LUMEN GENTIUM\",\"Militanza cristiana\",\"Preghiera cristiana\",\"Rosario\",\"sacramenti\",\"SAN GIOVANNI PAOLO II\",\"San Josemaria Escriv\u00e0\",\"SANTI CATTOLICI\",\"santit\u00e0 quotidiana\",\"Trending\"],\"articleSection\":[\"Analisi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/\",\"name\":\"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/rafa-disputa.jpg?fit=800%2C600&ssl=1\",\"datePublished\":\"2025-11-03T14:53:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/0428626ea256fe1d193098fe0ee2b91d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/rafa-disputa.jpg?fit=800%2C600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/rafa-disputa.jpg?fit=800%2C600&ssl=1\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/0428626ea256fe1d193098fe0ee2b91d\",\"name\":\"Javier Ferrer Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7bc1aef05f4433794cef4a55499c99ae6c0d617e2aa24ba4876a5432af93b2d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7bc1aef05f4433794cef4a55499c99ae6c0d617e2aa24ba4876a5432af93b2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7bc1aef05f4433794cef4a55499c99ae6c0d617e2aa24ba4876a5432af93b2d?s=96&d=mm&r=g\",\"caption\":\"Javier Ferrer Garc\u00eda\"},\"description\":\"Soy un apasionado de la vida. Fil\u00f3sofo y economista. Mi carrera profesional se ha enriquecido con el constante deseo de aprender y crecer tanto en el \u00e1mbito acad\u00e9mico como en el personal. Me considero un ferviente lector y amante del cine, lo cual me permite tener una perspectiva amplia y diversa sobre el mundo que nos rodea. Como cat\u00f3lico comprometido, busco integrar mis valores en cada aspecto de mi vida, desde mi carrera profesional hasta mi rol como esposo y padre de familia\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/javier-ferrer-garcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/","og_locale":"it_IT","og_type":"article","og_title":"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza &#8211; Exaudi","og_description":"Soldati di Cristo nella battaglia per la santit\u00e0","og_url":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2025-11-03T14:53:32+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/11\/rafa-disputa.jpg","type":"image\/jpeg"}],"author":"Javier Ferrer Garc\u00eda","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Javier Ferrer Garc\u00eda","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/"},"author":{"name":"Javier Ferrer Garc\u00eda","@id":"https:\/\/exaudi.org\/#\/schema\/person\/0428626ea256fe1d193098fe0ee2b91d"},"headline":"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza","datePublished":"2025-11-03T14:53:32+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/"},"wordCount":821,"image":{"@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/11\/rafa-disputa.jpg?fit=800%2C600&ssl=1","keywords":["Catechismo della Chiesa Cattolica","Chiesa militante","Chiesa sofferente","Chiesa trionfante","comunione dei santi","Concilio Vaticano II","confessione","Eucaristia","gioia nella fede","Javier Ferrer Garc\u00eda","Lotta contro il peccato","lotta spirituale","LUMEN GENTIUM","Militanza cristiana","Preghiera cristiana","Rosario","sacramenti","SAN GIOVANNI PAOLO II","San Josemaria Escriv\u00e0","SANTI CATTOLICI","santit\u00e0 quotidiana","Trending"],"articleSection":["Analisi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/","url":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/","name":"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/11\/rafa-disputa.jpg?fit=800%2C600&ssl=1","datePublished":"2025-11-03T14:53:32+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/0428626ea256fe1d193098fe0ee2b91d"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/11\/rafa-disputa.jpg?fit=800%2C600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/11\/rafa-disputa.jpg?fit=800%2C600&ssl=1","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/la-chiesa-militante-lottare-per-la-santita-con-gioia-e-speranza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"La Chiesa militante: lottare per la santit\u00e0 con gioia e speranza"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/0428626ea256fe1d193098fe0ee2b91d","name":"Javier Ferrer Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7bc1aef05f4433794cef4a55499c99ae6c0d617e2aa24ba4876a5432af93b2d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7bc1aef05f4433794cef4a55499c99ae6c0d617e2aa24ba4876a5432af93b2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7bc1aef05f4433794cef4a55499c99ae6c0d617e2aa24ba4876a5432af93b2d?s=96&d=mm&r=g","caption":"Javier Ferrer Garc\u00eda"},"description":"Soy un apasionado de la vida. Fil\u00f3sofo y economista. Mi carrera profesional se ha enriquecido con el constante deseo de aprender y crecer tanto en el \u00e1mbito acad\u00e9mico como en el personal. Me considero un ferviente lector y amante del cine, lo cual me permite tener una perspectiva amplia y diversa sobre el mundo que nos rodea. Como cat\u00f3lico comprometido, busco integrar mis valores en cada aspecto de mi vida, desde mi carrera profesional hasta mi rol como esposo y padre de familia","url":"https:\/\/exaudi.org\/it\/author\/javier-ferrer-garcia\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-BEx","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/11\/rafa-disputa.jpg?fit=800%2C600&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/144741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/149"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=144741"}],"version-history":[{"count":5,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/144741\/revisions"}],"predecessor-version":[{"id":144746,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/144741\/revisions\/144746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/144385"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=144741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=144741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=144741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}