{"id":136226,"date":"2025-09-24T19:24:06","date_gmt":"2025-09-24T17:24:06","guid":{"rendered":"https:\/\/exaudi.org\/?p=136226"},"modified":"2025-09-24T19:24:06","modified_gmt":"2025-09-24T17:24:06","slug":"loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/","title":{"rendered":"L&#8217;OMS include gli abortivi nella sua lista di farmaci essenziali"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">L&#8217;Organizzazione Mondiale della Sanit\u00e0 (OMS) ha aggiornato il suo elenco di medicinali essenziali nel 2025, includendovi due farmaci utilizzati per indurre l&#8217;aborto.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il documento, intitolato\u00a0 <\/span><\/span><strong><a href=\"https:\/\/iris.who.int\/bitstream\/handle\/10665\/382243\/B09474-eng.pdf\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u201cSelezione e utilizzo dei farmaci essenziali, 2025<\/span><\/span><\/a><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"> \u201d, include mifepristone e misoprostolo nella sezione \u201cFarmaci per l\u2019aborto farmacologico\u201d.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Secondo il documento dell&#8217;OMS, sia il mifepristone che il misoprostolo sono utilizzati in caso di morte fetale e aborto. Il misoprostolo \u00e8 utilizzato anche in caso di aborto incompleto e spontaneo.<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Medicina essenziale?<\/span><\/span><\/strong><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00c8 difficile accettare che i farmaci abortivi siano considerati essenziali. Come\u00a0 <\/span><\/span><strong><a href=\"https:\/\/www.who.int\/es\/news-room\/fact-sheets\/detail\/essential-medicines\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">definito dalla stessa OMS<\/span><\/span><\/a><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, i farmaci essenziali sono quelli che trattano in modo efficace e sicuro i bisogni sanitari prioritari della popolazione. Questi farmaci vengono selezionati in base alla loro rilevanza per la salute pubblica e alle prove disponibili sui loro benefici e rischi, nonch\u00e9 tenendo conto del costo, dell&#8217;accessibilit\u00e0 economica e di altri fattori rilevanti.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">I farmaci abortivi vengono utilizzati per interrompere le gravidanze causando la morte degli embrioni umani. Oltre a non essere terapeutici (non curano nulla), comportano un alto rischio di effetti collaterali per le donne che li assumono, come abbiamo gi\u00e0 segnalato <\/span><strong><a href=\"https:\/\/www.observatoriobioetica.org\/2025\/05\/un-nuevo-estudio-alerta-de-graves-efectos-adversos-tras-el-uso-de-mifepristona\/10004048\"><span dir=\"auto\" style=\"vertical-align: inherit\">in precedenza<\/span><\/a><\/strong><span dir=\"auto\" style=\"vertical-align: inherit\">.<\/span><\/span><strong>\u00a0<\/strong><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Studi recenti, condotti su pi\u00f9 di 800.000 donne che hanno fatto uso di farmaci abortivi, rivelano, secondo i dati delle richieste di rimborso delle assicurazioni sanitarie relative alla pratica degli aborti chimici con <\/span><\/span><a href=\"https:\/\/www.observatoriobioetica.org\/2024\/02\/mifepristona-un-abortivo-controvertido\/10000768\"><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">\u00a0mifepristone<\/span><\/span><\/strong><\/a><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">, un&#8217;elevata prevalenza di gravi eventi avversi come sepsi, infezioni, emorragie e altri nel 10,93% delle donne che ne hanno fatto uso, durante i 45 giorni successivi all&#8217;aborto.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il grave errore di attribuire all&#8217;OMS la classificazione di questi farmaci, che non hanno nulla a che vedere con la salvaguardia della salute della popolazione ma, al contrario, come &#8220;essenziali&#8221;, pu\u00f2 essere compreso solo a partire dal tentativo di considerare l&#8217;aborto un diritto.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Non esiste alcun diritto di uccidere, n\u00e9 i farmaci sono essenziali se la loro indicazione non \u00e8 correlata all&#8217;approccio efficace e sicuro ai bisogni sanitari prioritari della popolazione, come stabilito dall&#8217;OMS.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Stabilire criteri sanitari basati su principi ideologici anzich\u00e9 su prove scientifiche orientate al bene comune costituisce un grave rischio per la salute dei cittadini, che \u00e8 la preoccupazione principale dell&#8217;OMS.<\/span><\/span><\/p>\n<p><em><strong><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Julio Tudela. Ester Bosch \u2013 Osservatorio di Bioetica \u2013 Istituto di Scienze della Vita \u2013 Universit\u00e0 Cattolica di Valencia<\/span><\/span><\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;OMS include mifepristone e misoprostolo nella sua lista di farmaci essenziali del 2025, generando un dibattito su salute e bioetica<\/p>\n","protected":false},"author":87,"featured_media":135969,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[],"tags":[73918,31913,73920,73919,73921,73922,21240,73923,73924,73928,73929,73927,73925,14370,73926,28555,2601,22373,73930,19478,49625,73931,14154,14154],"class_list":["post-136226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-abortivi","tag-aborto-farmacologico-2","tag-aborto-incompleto-2","tag-aborto-spontaneo","tag-aggiornamento-2025","tag-controversia-sullaborto","tag-diritti-riproduttivi","tag-effetti-collaterali","tag-emorragia","tag-farmaci-essenziali","tag-farmaci-prioritari-mifepristone","tag-generando-un-dibattito-su-salute-e-bioetica","tag-infezioni","tag-istituto-di-scienze-della-vita","tag-loms-include-mifepristone-e-misoprostolo-nella-sua-lista-di-farmaci-essenziali-del-2025","tag-misoprostolo","tag-oms","tag-osservatorio-di-bioetica","tag-politiche-sanitarie","tag-rischi-di-aborto","tag-salute-pubblica","tag-sepsi","tag-universita-cattolica-di-valencia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;OMS include gli abortivi nella sua lista di farmaci essenziali &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;OMS include gli abortivi nella sua lista di farmaci essenziali &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"L&#039;OMS include mifepristone e misoprostolo nella sua lista di farmaci essenziali del 2025, generando un dibattito su salute e bioetica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/observatoriodebioetica\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-24T17:24:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/09\/2-2-scaled.png-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"994\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Observatorio de Bio\u00e9tica UCV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@obioetica\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Observatorio de Bio\u00e9tica UCV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/\"},\"author\":{\"name\":\"Observatorio de Bio\u00e9tica UCV\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/05d1c06e56ecb5490e9bff0d27026595\"},\"headline\":\"L&#8217;OMS include gli abortivi nella sua lista di farmaci essenziali\",\"datePublished\":\"2025-09-24T17:24:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/\"},\"wordCount\":379,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/2-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1\",\"keywords\":[\"abortivi\",\"aborto farmacologico\",\"aborto incompleto\",\"aborto spontaneo\",\"aggiornamento 2025\",\"controversia sull'aborto\",\"DIRITTI RIPRODUTTIVI\",\"effetti collaterali\",\"emorragia\",\"farmaci essenziali\",\"farmaci prioritari Mifepristone\",\"generando un dibattito su salute e bioetica\",\"infezioni\",\"ISTITUTO DI SCIENZE DELLA VITA\",\"L'OMS include mifepristone e misoprostolo nella sua lista di farmaci essenziali del 2025\",\"Misoprostolo\",\"Oms\",\"Osservatorio di bioetica\",\"politiche sanitarie\",\"RISCHI DI ABORTO\",\"salute pubblica\",\"sepsi\",\"UNIVERSIT\u00c0 CATTOLICA DI VALENCIA\",\"UNIVERSIT\u00c0 CATTOLICA DI VALENCIA\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/\",\"name\":\"L'OMS include gli abortivi nella sua lista di farmaci essenziali &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/2-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1\",\"datePublished\":\"2025-09-24T17:24:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/05d1c06e56ecb5490e9bff0d27026595\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/2-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/2-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1\",\"width\":2560,\"height\":994},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;OMS include gli abortivi nella sua lista di farmaci essenziali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/05d1c06e56ecb5490e9bff0d27026595\",\"name\":\"Observatorio de Bio\u00e9tica UCV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g\",\"caption\":\"Observatorio de Bio\u00e9tica UCV\"},\"description\":\"El Observatorio de Bio\u00e9tica se encuentra dentro del Instituto Ciencias de la vida de la Universidad Cat\u00f3lica de Valencia \u201cSan Vicente M\u00e1rtir\u201d . En el trasfondo de sus publicaciones, se defiende la vida humana desde la fecundaci\u00f3n a la muerte natural y la dignidad de la persona, teniendo como objetivo aunar esfuerzos para difundir la cultura de la vida como la define la Evangelium Vitae.\",\"sameAs\":[\"https:\\\/\\\/www.observatoriobioetica.org\\\/\",\"https:\\\/\\\/www.facebook.com\\\/observatoriodebioetica\\\/\",\"https:\\\/\\\/x.com\\\/obioetica\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC_Tr4WS5-TXoNo5e1MdQc7w\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/observatoriodebioeticaucv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'OMS include gli abortivi nella sua lista di farmaci essenziali &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/","og_locale":"it_IT","og_type":"article","og_title":"L'OMS include gli abortivi nella sua lista di farmaci essenziali &#8211; Exaudi","og_description":"L'OMS include mifepristone e misoprostolo nella sua lista di farmaci essenziali del 2025, generando un dibattito su salute e bioetica","og_url":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/observatoriodebioetica\/","article_published_time":"2025-09-24T17:24:06+00:00","og_image":[{"width":2560,"height":994,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/09\/2-2-scaled.png-scaled.jpg","type":"image\/jpeg"}],"author":"Observatorio de Bio\u00e9tica UCV","twitter_card":"summary_large_image","twitter_creator":"@obioetica","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Observatorio de Bio\u00e9tica UCV","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/"},"author":{"name":"Observatorio de Bio\u00e9tica UCV","@id":"https:\/\/exaudi.org\/#\/schema\/person\/05d1c06e56ecb5490e9bff0d27026595"},"headline":"L&#8217;OMS include gli abortivi nella sua lista di farmaci essenziali","datePublished":"2025-09-24T17:24:06+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/"},"wordCount":379,"image":{"@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/2-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","keywords":["abortivi","aborto farmacologico","aborto incompleto","aborto spontaneo","aggiornamento 2025","controversia sull'aborto","DIRITTI RIPRODUTTIVI","effetti collaterali","emorragia","farmaci essenziali","farmaci prioritari Mifepristone","generando un dibattito su salute e bioetica","infezioni","ISTITUTO DI SCIENZE DELLA VITA","L'OMS include mifepristone e misoprostolo nella sua lista di farmaci essenziali del 2025","Misoprostolo","Oms","Osservatorio di bioetica","politiche sanitarie","RISCHI DI ABORTO","salute pubblica","sepsi","UNIVERSIT\u00c0 CATTOLICA DI VALENCIA","UNIVERSIT\u00c0 CATTOLICA DI VALENCIA"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/","url":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/","name":"L'OMS include gli abortivi nella sua lista di farmaci essenziali &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/2-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","datePublished":"2025-09-24T17:24:06+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/05d1c06e56ecb5490e9bff0d27026595"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/2-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/2-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","width":2560,"height":994},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/loms-include-gli-abortivi-nella-sua-lista-di-farmaci-essenziali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;OMS include gli abortivi nella sua lista di farmaci essenziali"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/05d1c06e56ecb5490e9bff0d27026595","name":"Observatorio de Bio\u00e9tica UCV","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g","caption":"Observatorio de Bio\u00e9tica UCV"},"description":"El Observatorio de Bio\u00e9tica se encuentra dentro del Instituto Ciencias de la vida de la Universidad Cat\u00f3lica de Valencia \u201cSan Vicente M\u00e1rtir\u201d . En el trasfondo de sus publicaciones, se defiende la vida humana desde la fecundaci\u00f3n a la muerte natural y la dignidad de la persona, teniendo como objetivo aunar esfuerzos para difundir la cultura de la vida como la define la Evangelium Vitae.","sameAs":["https:\/\/www.observatoriobioetica.org\/","https:\/\/www.facebook.com\/observatoriodebioetica\/","https:\/\/x.com\/obioetica","https:\/\/www.youtube.com\/channel\/UC_Tr4WS5-TXoNo5e1MdQc7w"],"url":"https:\/\/exaudi.org\/it\/author\/observatoriodebioeticaucv\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-zrc","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/2-2-scaled.png-scaled.jpg?fit=2560%2C994&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/136226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=136226"}],"version-history":[{"count":3,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/136226\/revisions"}],"predecessor-version":[{"id":136229,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/136226\/revisions\/136229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/135969"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=136226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=136226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=136226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}