{"id":123051,"date":"2025-04-06T18:43:19","date_gmt":"2025-04-06T16:43:19","guid":{"rendered":"https:\/\/exaudi.org\/?p=123051"},"modified":"2025-04-06T18:43:19","modified_gmt":"2025-04-06T16:43:19","slug":"il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/","title":{"rendered":"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole"},"content":{"rendered":"<p>Al termine della Santa Messa per il Giubileo dei Malati e del Mondo della Salute, pubblichiamo di seguito il testo preparato dal Santo Padre Francesco per l&#8217;Angelus di questa V domenica di Quaresima:<\/p>\n<h3><strong>***<\/strong><\/h3>\n<p><b>Testo preparato dal Santo Padre<\/b><\/p>\n<p>Cari fratelli e sorelle,<\/p>\n<p>il Vangelo di questa quinta domenica di Quaresima ci presenta l\u2019episodio della donna colta in adulterio (<i>Gv<\/i>\u00a08,1-11). Mentre gli scribi e i farisei vogliono lapidarla, Ges\u00f9 restituisce a questa donna la bellezza perduta: lei \u00e8 caduta nella polvere; Ges\u00f9 su quella polvere passa il suo dito e scrive per lei una storia nuova: \u00e8 il \u201cdito di Dio\u201d, che salva i suoi figli (cfr\u00a0<i>Es<\/i>\u00a08,15) e li libera dal male (cfr\u00a0<i>Lc<\/i>\u00a011,20).<\/p>\n<p>Carissimi, come durante il ricovero, anche ora nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza premurosa. Nel giorno del\u00a0<a href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/events\/event.dir.html\/content\/vaticanevents\/it\/2025\/4\/6\/giubileo-ammalati.html\">Giubileo degli ammalati e del mondo della sanit\u00e0<\/a>, chiedo al Signore che questo tocco del suo amore raggiunga coloro che soffrono e incoraggi chi si prende cura di loro. E prego per i medici, gli infermieri e gli operatori sanitari, che non sempre sono aiutati a lavorare in condizioni adeguate e, talvolta, sono perfino vittime di aggressioni. La loro missione non \u00e8 facile e va sostenuta e rispettata. Auspico che si investano le risorse necessarie per le cure e per la ricerca, perch\u00e9 i sistemi sanitari siano inclusivi e attenti ai pi\u00f9 fragili e ai pi\u00f9 poveri.<\/p>\n<p>Ringrazio le detenute del carcere femminile di Rebibbia per il biglietto che mi hanno mandato. Prego per loro e per le loro famiglie.<\/p>\n<p>Nella Giornata mondiale dello sport per la pace e lo sviluppo, auspico che lo sport sia segno di speranza per tante persone che hanno bisogno di pace e di inclusione sociale, e ringrazio le associazioni sportive che educano concretamente alla fraternit\u00e0.<\/p>\n<p>Continuiamo a pregare per la pace: nella martoriata Ucraina, colpita da attacchi che provocano molte vittime civili, tra cui tanti bambini. E lo stesso accade a Gaza, dove le persone sono ridotte a vivere in condizioni inimmaginabili, senza tetto, senza cibo, senza acqua pulita. Tacciano le armi e si riprenda il dialogo; siano liberati tutti gli ostaggi e si soccorra la popolazione. Preghiamo per la pace in tutto il Medio Oriente; in Sudan e Sud Sudan; nella Repubblica Democratica del Congo; in Myanmar, duramente provato anche dal terremoto; e ad Haiti, dove infuria la violenza, che alcuni giorni fa ha ucciso due religiose.<\/p>\n<p>La Vergine Maria ci custodisca e interceda per noi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angelus<\/p>\n","protected":false},"author":17,"featured_media":123035,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[69,67],"tags":[52798,4952],"class_list":["post-123051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-angelus-it","category-leone-xiv","tag-angelus-6-febbraio-2025","tag-trending-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Angelus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-06T16:43:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/04\/1743946278130.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole\",\"datePublished\":\"2025-04-06T16:43:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/\"},\"wordCount\":425,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1743946278130.jpg\",\"keywords\":[\"Angelus 6 febbraio 2025\",\"Trending\"],\"articleSection\":[\"Angelus\",\"Leone XIV\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/\",\"name\":\"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1743946278130.jpg\",\"datePublished\":\"2025-04-06T16:43:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1743946278130.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1743946278130.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/","og_locale":"it_IT","og_type":"article","og_title":"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole &#8211; Exaudi","og_description":"Angelus","og_url":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2025-04-06T16:43:19+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/04\/1743946278130.jpg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole","datePublished":"2025-04-06T16:43:19+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/"},"wordCount":425,"image":{"@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/04\/1743946278130.jpg","keywords":["Angelus 6 febbraio 2025","Trending"],"articleSection":["Angelus","Leone XIV"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/","url":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/","name":"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/04\/1743946278130.jpg","datePublished":"2025-04-06T16:43:19+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/04\/1743946278130.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/04\/1743946278130.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/il-papa-nella-convalescenza-sento-il-dito-di-dio-e-sperimento-la-sua-carezza-amorevole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Il Papa: Nella convalescenza sento il \u201cdito di Dio\u201d e sperimento la sua carezza amorevole"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/04\/1743946278130.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-w0H","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/123051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=123051"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/123051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/123035"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=123051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=123051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=123051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}