{"id":119457,"date":"2025-02-17T17:27:48","date_gmt":"2025-02-17T16:27:48","guid":{"rendered":"https:\/\/exaudi.org\/?p=119457"},"modified":"2025-02-17T17:27:48","modified_gmt":"2025-02-17T16:27:48","slug":"la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/","title":{"rendered":"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale"},"content":{"rendered":"<p>Com&#8217;\u00e8 la vita quotidiana delle famiglie con bambini disabili? Il film \u201cI due emisferi di Lucca\u201d mostra questa realt\u00e0 ignorata, basandosi sulla storia di una famiglia con un figlio nato con paralisi cerebrale. Il film della regista messicana Mariana Chenillo \u00e8 una lezione di amore incondizionato, di superamento delle difficolt\u00e0 e di speranza. Tuttavia, questa storia stimolante rivela anche senza mezzi termini gli ostacoli e le sfide che i genitori devono affrontare in una societ\u00e0 che considera la diversit\u00e0 una piaga da sradicare attraverso pratiche eugenetiche.<\/p>\n<p>Barbara e Andres sono una coppia felice perch\u00e9 diventeranno genitori. Ma un problema durante il parto fa s\u00ec che gli eventi si svolgano in modo molto diverso da come avevano immaginato. Lucca nasce con una grave paralisi cerebrale, dovuta a una crisi respiratoria della madre (B\u00e1rbara Mori), che lascia gravi conseguenze sul cervello del bambino. Dieci giorni dopo la nascita, la diagnosi medica conferma l&#8217;entit\u00e0 delle lesioni, che i neurologi considerano irreversibili, escludendo che Lucca (Juli\u00e1n Tello) possa camminare, parlare, relazionarsi con gli altri e persino riconoscere i propri genitori. Questa situazione \u00e8 aggravata dalla crescente frequenza degli attacchi epilettici. Le difficolt\u00e0 nell&#8217;ingestione del cibo rendono inoltre necessario un intervento chirurgico per posizionare un bottone gastrico, per garantire il fabbisogno nutrizionale e facilitare la somministrazione dei farmaci.<\/p>\n<p>Tuttavia, quello che allo spettatore pu\u00f2 sembrare un ostacolo insormontabile, non fa che rafforzare l&#8217;unit\u00e0 di una famiglia che, dopo la nascita di Lucca, cresce con l&#8217;arrivo di Bruno e non perde la speranza che nuove terapie o farmaci possano migliorare le condizioni di vita del membro pi\u00f9 vulnerabile. Barbara e suo marito Andr\u00e9s (Juan Pablo Medina) sanno infatti che non esiste una cura per la paralisi cerebrale del loro figlio, ma confidano che egli possa trarre beneficio dai progressi scientifici e che i trattamenti futuri miglioreranno le sue capacit\u00e0 motorie e la sua capacit\u00e0 di comunicare con le persone che lo circondano. Lucca \u00e8 un dono per tutti, un fermento di amore incondizionato, una fonte di senso e di senso vitale per un ambiente che cresce in generosit\u00e0, dono e gioia di vivere. Un solo sorriso di Lucca scioglie i suoi genitori, fa sparire magicamente ogni capriccio del fratello Bruno e, man mano che il film procede, colpisce il cuore e trasforma la visione della diversit\u00e0 degli spettatori.<\/p>\n<p>L&#8217;avvincente storia della regista messicana Mariana Chenillo, basata su eventi reali e che sta spopolando su Netflix, raggiunge un punto di svolta quando la salute di Lucca peggiora improvvisamente perch\u00e9 le crisi epilettiche diventano sempre pi\u00f9 frequenti e intense e compromettono lo stato neurologico del bambino. Le diagnosi peggiori portano la famiglia ad aspettarsi un esito doloroso quando appare un barlume di speranza. Barbara scopre che un ospedale di Bangalore, una delle capitali pi\u00f9 tecnologicamente avanzate dell&#8217;India, sta portando avanti un trattamento sperimentale che si rivela promettente per i pazienti con lesioni neurologiche. Barbara e Andr\u00e9s non esitano, ipotecano la loro casa e viaggiano dal Messico all&#8217;India per incontrare il dottor Rajah Kumar (Danish Husain), dopo aver appreso dei risultati positivi su pazienti adulti il \u200b\u200bcui trattamento aveva migliorato le connessioni cerebrali e la rigenerazione dei tessuti danneggiati. Dopo aver ottenuto le autorizzazioni necessarie, Lucca \u00e8 il primo bambino a sottoporsi a una terapia non invasiva che gli permetter\u00e0 di sviluppare la parola, migliorare lo strabismo e relazionarsi meglio con l&#8217;ambiente circostante. I suoi rapidi progressi continuano a sorprendere l&#8217;equipe medica dell&#8217;ospedale messicano, che inizialmente aveva sconsigliato il viaggio ed era radicalmente scettico nei confronti di questo nuovo trattamento.<\/p>\n<h3><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-119374 alignleft\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-hemisferios-de-lucca-en-netflix.jpg?resize=300%2C208&#038;ssl=1\" alt=\"\" width=\"300\" height=\"208\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-hemisferios-de-lucca-en-netflix.jpg?resize=300%2C208&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-hemisferios-de-lucca-en-netflix.jpg?resize=1024%2C711&amp;ssl=1 1024w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-hemisferios-de-lucca-en-netflix.jpg?resize=770%2C535&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-hemisferios-de-lucca-en-netflix.jpg?resize=500%2C347&amp;ssl=1 500w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-hemisferios-de-lucca-en-netflix.jpg?resize=293%2C204&amp;ssl=1 293w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-hemisferios-de-lucca-en-netflix.jpg?resize=1400%2C973&amp;ssl=1 1400w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-hemisferios-de-lucca-en-netflix.jpg?resize=390%2C271&amp;ssl=1 390w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-hemisferios-de-lucca-en-netflix.jpg?w=1500&amp;ssl=1 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><strong>Difficolt\u00e0 quotidiane e mancanza di supporto<\/strong><\/h3>\n<p>Il film <em>I due emisferi di Lucca<\/em> porta onestamente alla luce una realt\u00e0 ignorata che riguarda le difficolt\u00e0 quotidiane che devono affrontare le famiglie con bambini con qualche diversit\u00e0 funzionale. Il regista del film mostra anche come molte di queste sofferenze potrebbero essere alleviate, o addirittura eliminate, con pi\u00f9 empatia e sostegno da parte della societ\u00e0 e delle pubbliche amministrazioni.<\/p>\n<p>In effetti, il percorso emotivo e spirituale di Barbara, Andr\u00e9s, Bruno e Lucca non \u00e8 un percorso facile perch\u00e9 nascere e vivere nel mondo con una disabilit\u00e0 significa, ancora oggi, subire un disagio sociale che impedisce la piena inclusione dei pi\u00f9 deboli. In questo senso, il film rivela anche come i genitori finiscano per perdere il lavoro perch\u00e9 le loro aziende ritengono che prendersi cura di un figlio disabile influisca negativamente sullo svolgimento efficiente dei loro obblighi lavorativi. La solitudine li rende facili vittime di persone senza scrupoli e truffatori, ruolo interpretato in questo film dal dottor Jaramillo (Bill Rogers), pi\u00f9 interessato al guadagno finanziario che al benessere dei pazienti. Le compagnie di assicurazione sanitaria non vogliono coprire i costi delle terapie necessarie, che alla fine sono a carico dei genitori. A questo si aggiunge un&#8217;eccessiva burocratizzazione delle amministrazioni pubbliche che cancella il volto di chi ne \u00e8 colpito e di chi convive con la diversit\u00e0 funzionale, applicando politiche basate su criteri utilitaristici ed economicistici.<\/p>\n<p>Niente di quanto detto sopra pu\u00f2 essere separato dalla crescente indifferenza verso la sofferenza altrui o da un&#8217;idea irrazionale che si \u00e8 radicata nella societ\u00e0, secondo cui mettere al mondo una persona disabile \u00e8 un errore perch\u00e9 soffrir\u00e0 la vita invece di viverla, porter\u00e0 solo dolore alla famiglia e costituir\u00e0 un peso per un modello di societ\u00e0 disumanizzato. Questa prospettiva d\u00e0 sfogo a pratiche eugenetiche che non rispettano in alcun modo la dignit\u00e0 intrinseca della persona o il valore della vita umana, indipendentemente dalle condizioni specifiche.<\/p>\n<h3><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-119377 alignleft\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?resize=300%2C208&#038;ssl=1\" alt=\"\" width=\"300\" height=\"208\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?resize=300%2C208&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?resize=1024%2C709&amp;ssl=1 1024w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?resize=770%2C533&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?resize=1536%2C1064&amp;ssl=1 1536w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?resize=500%2C346&amp;ssl=1 500w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?resize=293%2C203&amp;ssl=1 293w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?resize=1400%2C970&amp;ssl=1 1400w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?resize=390%2C270&amp;ssl=1 390w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/los-dos-hemisferios-de-lucca-netflix.webp?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><strong>Dignit\u00e0, diversit\u00e0 e bioetica<\/strong><\/h3>\n<p>Il film invita a una riflessione bioetica in una prospettiva di diversit\u00e0 che non violi il rispetto della dignit\u00e0 che rende tutti uguali, come proposto dal modello bioetico personalista. La realt\u00e0 ci pone di fronte a due strade radicalmente opposte per correggere le drammatiche conseguenze dell\u2019erroneo rapporto tra disabilit\u00e0 e disagio sociale. Una soluzione, che purtroppo sta prendendo piede, \u00e8 l&#8217;eliminazione della diversit\u00e0. Ci\u00f2 conferisce legittimit\u00e0 morale alla negazione dell&#8217;esistenza di coloro che non sono considerati persone. Certamente, se non ci sono persone disabili, l&#8217;idea di flagello o di svantaggio sociale scompare. Ma un&#8217;altra strada, pi\u00f9 incoraggiante e umana, \u00e8 quella di costruire societ\u00e0 capaci di eliminare la visione che associa la disabilit\u00e0 a un valore inferiore della persona e a una vita in condizioni inferiori rispetto alle altre. Questo approccio renderebbe pi\u00f9 facile per chiunque sia interessato da una diversit\u00e0 funzionale sviluppare la propria vita con pari opportunit\u00e0, senza essere escluso o discriminato, ma accolto e beneficiando dell&#8217;assistenza e del sostegno educativo che merita.<\/p>\n<p>Naturalmente, un\u2019interpretazione distorta dell\u2019autonomia o dei diritti individuali non ci prepara adeguatamente ad affrontare problemi come quelli evidenziati in questo film e altri come la <a href=\"https:\/\/www.observatoriobioetica.org\/2024\/01\/china-desarrolla-la-primera-clonacion-exitosa-de-un-ejemplar-de-primate-mono\/44070\">clonazione<\/a>, i \u201c<a href=\"https:\/\/www.observatoriobioetica.org\/2024\/12\/vicente-bellver-tener-hijos-a-la-carta-es-la-clara-expresion-de-la-cultura-capitalista-en-el-ambito-procreativo\/10002970\">bambini su richiesta<\/a>\u201d o l\u2019<a href=\"https:\/\/www.observatoriobioetica.org\/2024\/02\/crispr-cas9-la-revolucion-en-el-tratamiento-de-enfermedades-geneticas\/10000265\">ingegneria genetica<\/a>. Concludo con alcune riflessioni illuminanti del filosofo e bioeticista Michael Sandel che sono essenziali nel nostro panorama morale: umilt\u00e0, responsabilit\u00e0 e solidariet\u00e0. In un mondo sociale che valorizza il dominio e il controllo, la genitoriali \u00e8 una scuola di umilt\u00e0 perch\u00e9 ci invita ad accogliere l&#8217;imprevisto, afferma Sandel. Questo pensatore avverte che la perdita di umanit\u00e0 moltiplica la responsabilit\u00e0 nella misura in cui ci sar\u00e0 meno da attribuire al caso e pi\u00f9 alla scelta. Cosa significa? Questa solidariet\u00e0 consiste nell&#8217;apprezzamento di ci\u00f2 che si \u00e8 ricevuto, perch\u00e9 nessuno \u00e8 pienamente responsabile del suo successo. Se si lasciasse che il caso fosse sostituito dalla scelta, il valore delle conquiste umane e simili perderebbe terreno, cos\u00ec come il nostro apprezzamento per un mondo condiviso. Vale a dire che si tenderebbe a considerare che ogni persona \u00e8 interamente responsabile del proprio successo.<\/p>\n<p>La conseguenza non \u00e8 da poco, perch\u00e9 i soggetti colpiti non sarebbero meritevoli di risarcimento e solidariet\u00e0, ma anzi considerati \u201cinadatti e bisognosi di riparazione eugenetica\u201d. Ecco come il controllo genetico erode la solidariet\u00e0 e ignora il senso dei diritti inalienabili, inviolabili e indisponibili. Sandel sottolinea: \u201cLa rivoluzione genetica \u00e8 arrivata per curare la malattia, ma \u00e8 rimasta per tentarci con la prospettiva di ottimizzare le nostre prestazioni, progettare i nostri figli e perfezionare la nostra natura. Il nostro desiderio di vederci in cima al mondo e di dominare la natura \u00e8 una visione errata della libert\u00e0 che minaccia di sopprimere il nostro apprezzamento della vita come un dono e di non lasciarci nulla da affermare o contemplare oltre alla libert\u00e0 stessa&#8221;.<\/p>\n<p><a href=\"https:\/\/www.observatoriobioetica.org\/?s=Amparo+Aygues&amp;post_type%5B%5D=any&amp;search_limit_to_post_titles=0&amp;fs=1\"><em><strong>Amparo Ayg\u00fces<\/strong><\/em><\/a><em><strong> &#8211; Laurea Magistrale in Bioetica presso l&#8217;Universit\u00e0 Cattolica di Valencia &#8211; Membro dell&#8217;Osservatorio di Bioetica &#8211; Universit\u00e0 Cattolica di Valencia<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cI due emisferi di Lucca\u201d<\/p>\n","protected":false},"author":87,"featured_media":119371,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[129],"tags":[24542,10185,46215,11003,46217,46216,12445,26650,4999,46219,46220,46221,46222,46228,46229,46225,46223,20695,46224,46226,12870,46227,46218,46230,46231,46232,46233,4952],"class_list":["post-119457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voci","tag-amore-incondizionato","tag-amparo-aygues-2","tag-bioetica-e-dignita-umana","tag-cinema","tag-cinema-e-disabilita","tag-cinema-messicano","tag-cinema-per-famiglie","tag-diritti-delle-persone-con-disabilita","tag-disabilita","tag-disabilita-e-societa","tag-diversita-funzionale","tag-etica-ed-eugenetica","tag-famiglia-e-resilienza","tag-film-netflix","tag-film-sulla-paralisi-cerebrale","tag-i-due-emisferi-di-lucca","tag-inclusione-e-rispetto","tag-inclusione-sociale","tag-la-storia-stimolante-di-una-famiglia-con-un-figlio-con-paralisi-cerebrale","tag-mariana-chenillo-2","tag-osservatorio-di-bioetica-delluniversita-cattolica-di-valencia","tag-osservatorio-di-bioetica-ucv","tag-sfide-della-disabilita","tag-solidarieta-e-bioetica","tag-superamento-e-speranza","tag-terapie-innovative","tag-trattamento-sperimentale-india","tag-trending-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"\u201cI due emisferi di Lucca\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/observatoriodebioetica\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-17T16:27:48+00:00\" \/>\n<meta name=\"author\" content=\"Observatorio de Bio\u00e9tica UCV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@obioetica\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Observatorio de Bio\u00e9tica UCV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/\"},\"author\":{\"name\":\"Observatorio de Bio\u00e9tica UCV\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/05d1c06e56ecb5490e9bff0d27026595\"},\"headline\":\"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale\",\"datePublished\":\"2025-02-17T16:27:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/\"},\"wordCount\":1409,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/MMR67N2BZNECVOL5MQ233JTGB4.avif\",\"keywords\":[\"amore incondizionato\",\"Amparo Ayg\u00fces\",\"bioetica e dignit\u00e0 umana\",\"CINEMA\",\"cinema e disabilit\u00e0\",\"cinema messicano\",\"CINEMA PER FAMIGLIE\",\"diritti delle persone con disabilit\u00e0\",\"disabilit\u00e0\",\"disabilit\u00e0 e societ\u00e0\",\"diversit\u00e0 funzionale\",\"etica ed eugenetica\",\"famiglia e resilienza\",\"film Netflix\",\"film sulla paralisi cerebrale\",\"I due emisferi di Lucca\",\"inclusione e rispetto\",\"INCLUSIONE SOCIALE\",\"la storia stimolante di una famiglia con un figlio con paralisi cerebrale\",\"Mariana Chenillo\",\"OSSERVATORIO DI BIOETICA DELL'UNIVERSIT\u00c0 CATTOLICA DI VALENCIA\",\"Osservatorio di bioetica UCV\",\"sfide della disabilit\u00e0\",\"solidariet\u00e0 e bioetica\",\"superamento e speranza\",\"terapie innovative\",\"trattamento sperimentale India\",\"Trending\"],\"articleSection\":[\"Voci\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/\",\"name\":\"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/MMR67N2BZNECVOL5MQ233JTGB4.avif\",\"datePublished\":\"2025-02-17T16:27:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/05d1c06e56ecb5490e9bff0d27026595\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/MMR67N2BZNECVOL5MQ233JTGB4.avif\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/MMR67N2BZNECVOL5MQ233JTGB4.avif\",\"width\":800,\"height\":499},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/05d1c06e56ecb5490e9bff0d27026595\",\"name\":\"Observatorio de Bio\u00e9tica UCV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g\",\"caption\":\"Observatorio de Bio\u00e9tica UCV\"},\"description\":\"El Observatorio de Bio\u00e9tica se encuentra dentro del Instituto Ciencias de la vida de la Universidad Cat\u00f3lica de Valencia \u201cSan Vicente M\u00e1rtir\u201d . En el trasfondo de sus publicaciones, se defiende la vida humana desde la fecundaci\u00f3n a la muerte natural y la dignidad de la persona, teniendo como objetivo aunar esfuerzos para difundir la cultura de la vida como la define la Evangelium Vitae.\",\"sameAs\":[\"https:\\\/\\\/www.observatoriobioetica.org\\\/\",\"https:\\\/\\\/www.facebook.com\\\/observatoriodebioetica\\\/\",\"https:\\\/\\\/x.com\\\/obioetica\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC_Tr4WS5-TXoNo5e1MdQc7w\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/observatoriodebioeticaucv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/","og_locale":"it_IT","og_type":"article","og_title":"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale &#8211; Exaudi","og_description":"\u201cI due emisferi di Lucca\u201d","og_url":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/observatoriodebioetica\/","article_published_time":"2025-02-17T16:27:48+00:00","author":"Observatorio de Bio\u00e9tica UCV","twitter_card":"summary_large_image","twitter_creator":"@obioetica","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Observatorio de Bio\u00e9tica UCV","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/"},"author":{"name":"Observatorio de Bio\u00e9tica UCV","@id":"https:\/\/exaudi.org\/#\/schema\/person\/05d1c06e56ecb5490e9bff0d27026595"},"headline":"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale","datePublished":"2025-02-17T16:27:48+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/"},"wordCount":1409,"image":{"@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/MMR67N2BZNECVOL5MQ233JTGB4.avif","keywords":["amore incondizionato","Amparo Ayg\u00fces","bioetica e dignit\u00e0 umana","CINEMA","cinema e disabilit\u00e0","cinema messicano","CINEMA PER FAMIGLIE","diritti delle persone con disabilit\u00e0","disabilit\u00e0","disabilit\u00e0 e societ\u00e0","diversit\u00e0 funzionale","etica ed eugenetica","famiglia e resilienza","film Netflix","film sulla paralisi cerebrale","I due emisferi di Lucca","inclusione e rispetto","INCLUSIONE SOCIALE","la storia stimolante di una famiglia con un figlio con paralisi cerebrale","Mariana Chenillo","OSSERVATORIO DI BIOETICA DELL'UNIVERSIT\u00c0 CATTOLICA DI VALENCIA","Osservatorio di bioetica UCV","sfide della disabilit\u00e0","solidariet\u00e0 e bioetica","superamento e speranza","terapie innovative","trattamento sperimentale India","Trending"],"articleSection":["Voci"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/","url":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/","name":"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/MMR67N2BZNECVOL5MQ233JTGB4.avif","datePublished":"2025-02-17T16:27:48+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/05d1c06e56ecb5490e9bff0d27026595"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/MMR67N2BZNECVOL5MQ233JTGB4.avif","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/MMR67N2BZNECVOL5MQ233JTGB4.avif","width":800,"height":499},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/la-storia-stimolante-di-una-famiglia-con-un-figlio-affetto-da-paralisi-cerebrale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"La storia stimolante di una famiglia con un figlio affetto da paralisi cerebrale"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/05d1c06e56ecb5490e9bff0d27026595","name":"Observatorio de Bio\u00e9tica UCV","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/086563f59595a89fb0851de25d712a03657b1cdfa8af3c9cd0a1ee122fc5d596?s=96&d=mm&r=g","caption":"Observatorio de Bio\u00e9tica UCV"},"description":"El Observatorio de Bio\u00e9tica se encuentra dentro del Instituto Ciencias de la vida de la Universidad Cat\u00f3lica de Valencia \u201cSan Vicente M\u00e1rtir\u201d . En el trasfondo de sus publicaciones, se defiende la vida humana desde la fecundaci\u00f3n a la muerte natural y la dignidad de la persona, teniendo como objetivo aunar esfuerzos para difundir la cultura de la vida como la define la Evangelium Vitae.","sameAs":["https:\/\/www.observatoriobioetica.org\/","https:\/\/www.facebook.com\/observatoriodebioetica\/","https:\/\/x.com\/obioetica","https:\/\/www.youtube.com\/channel\/UC_Tr4WS5-TXoNo5e1MdQc7w"],"url":"https:\/\/exaudi.org\/it\/author\/observatoriodebioeticaucv\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-v4J","jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/MMR67N2BZNECVOL5MQ233JTGB4.avif","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/119457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=119457"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/119457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/119371"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=119457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=119457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=119457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}