{"id":118682,"date":"2025-02-06T17:56:36","date_gmt":"2025-02-06T16:56:36","guid":{"rendered":"https:\/\/exaudi.org\/?p=118682"},"modified":"2025-02-06T17:56:36","modified_gmt":"2025-02-06T16:56:36","slug":"provvidenza-lassistenza-di-dio-alle-sue-creature","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/","title":{"rendered":"Provvidenza: l&#8217;assistenza di Dio alle sue creature"},"content":{"rendered":"<p>Alla <em>provvidenza<\/em> come &#8220;cura che Dio ha per la creazione e le sue creature&#8221; (RAE), R\u00e9mi Brague ha dedicato il libro <em>A ciascuno secondo i suoi bisogni. Piccolo trattato divino di economia<\/em> (Encuentro, 2025, edizione Kindle). Un libro sintetico, chiaro, suggestivo, che mira a riflettere sull\u2019idea che Dio, \u201cdopo\u201d aver posto nell\u2019essere ci\u00f2 che \u00e8 stato creato, continua a prendersene cura&#8221;. Una visione con le voci dei pensatori classici, antichi e medievali, per far luce sull\u2019idea cristiana di provvidenza: &#8220;Dio d\u00e0 a ogni creatura ci\u00f2 di cui ha bisogno per provvedere a se stessa&#8221; (p. 6).<\/p>\n<p>San Tommaso d&#8217;Aquino, riferendosi alla provvidenza, sottolinea che &#8220;da una parte, ogni creatura riceve da Dio, secondo il suo livello di essere, ci\u00f2 di cui ha bisogno per realizzare il suo bene; D&#8217;altra parte, quanto pi\u00f9 una creatura si trova in alto su questa scala, tanto pi\u00f9 deve agire per se stessa per raggiungere il suo bene\u201d (p. 19). Cio\u00e8 Dio muove le sue creature secondo la loro condizione: le cause naturali portano agli atti naturali; di quelle volontarie, azioni volontarie (cfr. p. 109).<\/p>\n<p>Ogni essere riceve da Dio &#8220;ci\u00f2 di cui ha bisogno per riconoscere il suo bene, desiderarlo e realizzarlo. (\u2026) Dio d\u00e0 sempre i mezzi perch\u00e9 ogni creatura raggiunga il proprio bene&#8221; (p. 19). Il minerale, la pianta, l&#8217;essere umano hanno un principio intimo che li spinge a raggiungere il loro bene. Nella sua opera provvidenziale, Dio tiene conto della partecipazione degli esseri umani, costituendosi collaboratori nel servizio delle creature. Il bambino conta sull&#8217;aiuto dei genitori e, in generale, tutti gli esseri umani, in quanto dipendenti e vulnerabili, necessitano dell&#8217;aiuto degli altri. Siamo pastori delle creature e custodi dei nostri fratelli. Le nostre azioni possono promuovere lo sviluppo delle creature o troncarne la pienezza.<\/p>\n<p>Vale la pena ricordare ci\u00f2 che dovrebbe essere ovvio: &#8220;aspettare che la divina provvidenza agisca al posto nostro per fare ci\u00f2 che potremmo benissimo fare se fossimo disposti a lavorare un po&#8217;, significa dimenticare che le facolt\u00e0 che ci permetterebbero di agire sono esse stesse un effetto della provvidenza&#8221; (p. 112). A questo proposito mi viene in mente il detto popolare: \u201cAiutati e Dio ti aiuter\u00e0\u201d. Sarebbe sbagliato accusare la Provvidenza di non aver fatto ci\u00f2 che avremmo potuto fare benissimo noi stessi. Dio conta sulla nostra libert\u00e0 e intelligenza. Non siamo un granello di polvere lanciato in aria, n\u00e9 uomini-massa determinati dalle leggi della storia, n\u00e9 burattini digitalizzati da un Dio dispotico, seppur benevolo.<\/p>\n<p>Dio affida all&#8217;essere umano ci\u00f2 che \u00e8. Questa idea &#8211; segnala Brague &#8211; si ritrova gi\u00e0 in Epitteto, che d\u00e0 al divino, secondo la scuola stoica, il nome proprio di Zeus: &#8220;Non solo ti ha costituito [in ci\u00f2 che sei], ma ti ha affidato (<em>episteusen<\/em>) e dato in affidamento (<em>parakatheteto<\/em>) a te stesso (p. 91)&#8221;. Abbiamo ricevuto la vita e aggiungiamo vita. Non siamo solo un&#8217;altra creatura nel cosmo. Nel Salmo II, la persona che prega dice: \u201cIl Signore mi ha detto: Tu sei mio figlio. \u201cTi ho generato oggi.\u201d Con tanta alta dignit\u00e0 si comprende che &#8220;Dio non \u00e8 al servizio del nostro comfort, n\u00e9, in generale, del bene come lo immaginiamo. Nel caso dell\u2019uomo, il vero bene (\u2026) \u00e8, soprattutto, se non esclusivamente, il bene morale, la santit\u00e0. Questo bene \u00e8 il bene dell\u2019uomo in quanto egli \u00e8 primariamente persona umana&#8221; (p. 101).<\/p>\n<p>Dio si prende cura delle sue creature, si prende cura dei suoi figli nel Figlio. E si prende cura di noi anche quando la vita ci mette di fronte a delle battute d&#8217;arresto? In tali situazioni, dov&#8217;\u00e8 la sua mano, il suo volto? Forse \u00e8 il momento della notte della fede, la notte nell&#8217;Orto del Getsemani in compagnia del Cristo sofferente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Divina Provvidenza: una chiamata alla collaborazione umana nella cura del creato e del bene morale<\/p>\n","protected":false},"author":109,"featured_media":118579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[129],"tags":[44364,44365,44367,44366,44368,44369,44380,4671,44370,44371,11198,44372,44373,44374,44384,14663,23274,44376,44377,44378,5772,4057,44379,22500,44382,11937,44383,44375,4952,44385,44381],"class_list":["post-118682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voci","tag-a-ciascuno-secondo-i-suoi-bisogni","tag-assistenza-di-dio","tag-bene-morale","tag-bene-umano","tag-brague-2","tag-collaborazione-umana-e-divina","tag-contrattempi-della-vita","tag-cristianesimo","tag-cristo-e-provvidenza","tag-cura-di-dio","tag-dio","tag-dio-e-creazione","tag-economia-divina-2","tag-epitteto-e-provvidenza","tag-essere-umano-e-divinita","tag-francisco-bobadilla-2","tag-getsemani-2","tag-liberta-e-intelligenza-umana","tag-mano-di-dio","tag-notte-della-fede","tag-persona","tag-provvidenza","tag-provvidenza-divina","tag-remi-brague-2","tag-salmo-ii-2","tag-san-tommaso-daquino","tag-santita-e-provvidenza","tag-scala-degli-esseri","tag-trending-it","tag-vita-umana-e-divina","tag-volto-di-dio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Provvidenza: l&#039;assistenza di Dio alle sue creature &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provvidenza: l&#039;assistenza di Dio alle sue creature &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Divina Provvidenza: una chiamata alla collaborazione umana nella cura del creato e del bene morale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-06T16:56:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Bobadilla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Bobadilla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/\"},\"author\":{\"name\":\"Francisco Bobadilla\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f2d4ad1e1e2bb7dad42a623b75b7166b\"},\"headline\":\"Provvidenza: l&#8217;assistenza di Dio alle sue creature\",\"datePublished\":\"2025-02-06T16:56:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/\"},\"wordCount\":620,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg\",\"keywords\":[\"A ciascuno secondo i suoi bisogni\",\"assistenza di Dio\",\"bene morale\",\"bene umano\",\"Brague\",\"collaborazione umana e divina\",\"contrattempi della vita\",\"cristianesimo\",\"Cristo e provvidenza\",\"cura di Dio\",\"DIO\",\"Dio e creazione\",\"economia divina\",\"Epitteto e provvidenza\",\"essere umano e divinit\u00e0\",\"FRANCISCO BOBADILLA\",\"Getsemani\",\"libert\u00e0 e intelligenza umana\",\"mano di Dio\",\"notte della fede\",\"persona\",\"provvidenza\",\"Provvidenza divina\",\"R\u00e9mi Brague\",\"salmo II\",\"SAN TOMMASO D'AQUINO\",\"santit\u00e0 e provvidenza\",\"scala degli esseri\",\"Trending\",\"vita umana e divina\",\"volto di Dio\"],\"articleSection\":[\"Voci\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/\",\"name\":\"Provvidenza: l'assistenza di Dio alle sue creature &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg\",\"datePublished\":\"2025-02-06T16:56:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f2d4ad1e1e2bb7dad42a623b75b7166b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg\",\"width\":800,\"height\":1350,\"caption\":\"Il trionfo della Divina Provvidenza (Palazzo Barberini, opera di Pietro da Cortona)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/provvidenza-lassistenza-di-dio-alle-sue-creature\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provvidenza: l&#8217;assistenza di Dio alle sue creature\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f2d4ad1e1e2bb7dad42a623b75b7166b\",\"name\":\"Francisco Bobadilla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d65d74eeda045f5ef133a25b739fed12768ab871a0ddb2772cf98408d61ee37?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d65d74eeda045f5ef133a25b739fed12768ab871a0ddb2772cf98408d61ee37?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d65d74eeda045f5ef133a25b739fed12768ab871a0ddb2772cf98408d61ee37?s=96&d=mm&r=g\",\"caption\":\"Francisco Bobadilla\"},\"description\":\"Francisco Bobadilla es profesor principal de la Universidad de Piura, donde dicta clases para el pre-grado y posgrado. Interesado en las Humanidades y en la dimensi\u00f3n \u00e9tica de la conducta humana. Lector habitual, de cuyas lecturas se nutre en gran parte este blog. Es autor, entre otros, de los libros \u201cPasi\u00f3n por la Excelencia\u201d, \u201cEmpresas con alma\u201d, \u00abProgreso econ\u00f3mico y desarrollo humano\u00bb, \u00abEl C\u00f3digo da Vinci: de la ficci\u00f3n a la realidad\u00bb; \u00abLa disponibilidad de los derechos de la personalidad\u00bb. Abogado y Master en Derecho Civil por la PUCP, doctor en Derecho por la Universidad de Zaragoza; Licenciado en Ciencias de la Informaci\u00f3n por la Universidad de Piura. Sus temas: pensamiento pol\u00edtico y social, \u00e9tica y cultura, derechos de la persona.\",\"sameAs\":[\"https:\\\/\\\/tertuliaabierta.wordpress.com\\\/\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/francisco-bobadilla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Provvidenza: l'assistenza di Dio alle sue creature &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/","og_locale":"it_IT","og_type":"article","og_title":"Provvidenza: l'assistenza di Dio alle sue creature &#8211; Exaudi","og_description":"Divina Provvidenza: una chiamata alla collaborazione umana nella cura del creato e del bene morale","og_url":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2025-02-06T16:56:36+00:00","og_image":[{"width":800,"height":1350,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg","type":"image\/jpeg"}],"author":"Francisco Bobadilla","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Francisco Bobadilla","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/"},"author":{"name":"Francisco Bobadilla","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f2d4ad1e1e2bb7dad42a623b75b7166b"},"headline":"Provvidenza: l&#8217;assistenza di Dio alle sue creature","datePublished":"2025-02-06T16:56:36+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/"},"wordCount":620,"image":{"@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg","keywords":["A ciascuno secondo i suoi bisogni","assistenza di Dio","bene morale","bene umano","Brague","collaborazione umana e divina","contrattempi della vita","cristianesimo","Cristo e provvidenza","cura di Dio","DIO","Dio e creazione","economia divina","Epitteto e provvidenza","essere umano e divinit\u00e0","FRANCISCO BOBADILLA","Getsemani","libert\u00e0 e intelligenza umana","mano di Dio","notte della fede","persona","provvidenza","Provvidenza divina","R\u00e9mi Brague","salmo II","SAN TOMMASO D'AQUINO","santit\u00e0 e provvidenza","scala degli esseri","Trending","vita umana e divina","volto di Dio"],"articleSection":["Voci"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/","url":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/","name":"Provvidenza: l'assistenza di Dio alle sue creature &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg","datePublished":"2025-02-06T16:56:36+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f2d4ad1e1e2bb7dad42a623b75b7166b"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg","width":800,"height":1350,"caption":"Il trionfo della Divina Provvidenza (Palazzo Barberini, opera di Pietro da Cortona)"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/provvidenza-lassistenza-di-dio-alle-sue-creature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Provvidenza: l&#8217;assistenza di Dio alle sue creature"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f2d4ad1e1e2bb7dad42a623b75b7166b","name":"Francisco Bobadilla","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8d65d74eeda045f5ef133a25b739fed12768ab871a0ddb2772cf98408d61ee37?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d65d74eeda045f5ef133a25b739fed12768ab871a0ddb2772cf98408d61ee37?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d65d74eeda045f5ef133a25b739fed12768ab871a0ddb2772cf98408d61ee37?s=96&d=mm&r=g","caption":"Francisco Bobadilla"},"description":"Francisco Bobadilla es profesor principal de la Universidad de Piura, donde dicta clases para el pre-grado y posgrado. Interesado en las Humanidades y en la dimensi\u00f3n \u00e9tica de la conducta humana. Lector habitual, de cuyas lecturas se nutre en gran parte este blog. Es autor, entre otros, de los libros \u201cPasi\u00f3n por la Excelencia\u201d, \u201cEmpresas con alma\u201d, \u00abProgreso econ\u00f3mico y desarrollo humano\u00bb, \u00abEl C\u00f3digo da Vinci: de la ficci\u00f3n a la realidad\u00bb; \u00abLa disponibilidad de los derechos de la personalidad\u00bb. Abogado y Master en Derecho Civil por la PUCP, doctor en Derecho por la Universidad de Zaragoza; Licenciado en Ciencias de la Informaci\u00f3n por la Universidad de Piura. Sus temas: pensamiento pol\u00edtico y social, \u00e9tica y cultura, derechos de la persona.","sameAs":["https:\/\/tertuliaabierta.wordpress.com\/"],"url":"https:\/\/exaudi.org\/it\/author\/francisco-bobadilla\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Il_trionfo_della_Divina_ProvvidenzaPalazzo_Barberini-e1738748181949.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-uSe","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/118682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=118682"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/118682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/118579"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=118682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=118682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=118682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}