{"id":11837,"date":"2021-04-15T17:35:35","date_gmt":"2021-04-15T15:35:35","guid":{"rendered":"https:\/\/exaudi.org\/?p=11837"},"modified":"2021-04-15T17:35:35","modified_gmt":"2021-04-15T15:35:35","slug":"parolin-rafforzare-il-rispetto-del-diritto-umanitario","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/","title":{"rendered":"Parolin: &#8220;Rafforzare il rispetto del diritto umanitario&#8221;"},"content":{"rendered":"<p>Il segretario di Stato vaticano cardinale Pietro Parolin ha aperto con il suo intervento <a href=\"https:\/\/exaudi.org\/it\/fraternita-multilateralismo-pace-sfide-globali\/\">l&#8217;incontro<\/a> di alto livello on line \u201cFraternit\u00e0, Multilateralismo e Pace\u201d, durante il quale \u00e8 stata presentata alle Nazioni Unite l\u2019Enciclica \u201cFratelli tutti\u201d di Papa Francesco. L&#8217;evento \u00e8 stato promosso dalla Missione Permanente della Santa Sede presso le Nazioni Unite, in collaborazione con Missione dell\u2019Ordine di Malta presso le Nazioni Unite a Ginevra, Commissione Internazionale Cattolica per le Migrazioni, Forum delle Organizzazioni Non Governative Cattoliche, Pontificia Universit\u00e0 Lateranense e Fondazione Caritas in Veritate. Ecco l&#8217;intervento integrale del cardinale Parolin:<\/p>\n<p>Sono particolarmente lieto dell\u2019invito rivoltomi ad intervenire ad un incontro di riflessione sull\u2019Enciclica \u201cFratelli tutti\u201d con la partecipazione di alcuni eminenti Direttori Generali presenti nella Ginevra Internazionale. Il vostro impegno nel multilaterale, come quello degli Eccellentissimi Ambasciatori qui presenti, \u00e8 un modo privilegiato per promuovere il bene comune della famiglia umana e di sviluppare idee originali e strategie innovative, \u201caffinch\u00e9, con una maggiore audacia creativa, si ricerchino soluzioni nuove e sostenibili\u201d.<\/p>\n<h4>Il desiderio del Papa<\/h4>\n<p>Per comprendere in pieno il concetto di fratellanza e la sua declinazione nell\u2019azione diplomatica multilaterale della Santa Sede, pu\u00f2 essere utile tornare all\u2019avvio del Pontificato di Papa Francesco. Si ricorder\u00e0 che la fratellanza \u00e8 il primo tema al quale ha fatto riferimento il Papa nel giorno della sua elezione, pi\u00f9 di otto anni fa, quando ha espresso questo desiderio: \u201cPreghiamo sempre per noi: l\u2019uno per l\u2019altro. Preghiamo per tutto il mondo, perch\u00e9 ci sia una grande fratellanza\u201d. Tutte le azioni ed attivit\u00e0 successive del Pontificato sono state una naturale e coerente conseguenza di un cammino orientato ad essa.<\/p>\n<p>Riflettendo ad un anno dall\u2019inizio della pandemia, vediamo come tale criterio programmatico risulta decisivo se si vuole superare la dicotomia attuale tra \u201cil codice dell\u2019efficienza\u201d e il \u201ccodice della solidariet\u00e0\u201d. Infatti, la fratellanza ci spinge ad un \u201ccodice\u201d ancora pi\u00f9 esigente ed inclusivo: \u201cMentre la solidariet\u00e0 \u00e8 il principio di pianificazione sociale che permette ai diseguali di diventare eguali, la fratellanza \u00e8 quello che consente agli eguali di essere persone diverse. La fratellanza consente a persone che sono eguali nella loro essenza, dignit\u00e0, libert\u00e0, e nei loro diritti fondamentali, di partecipare diversamente al bene comune secondo la loro capacit\u00e0, il loro piano di vita, la loro vocazione, il loro lavoro o il loro carisma di servizio\u201d.<\/p>\n<h4>La fratellanza nell\u2019azione diplomatica<\/h4>\n<p>Nell\u2019azione multilaterale, la fratellanza si traduce nel coraggio e nella generosit\u00e0 per stabilire liberamente determinati obiettivi comuni e per assicurare l\u2019adempimento in tutto il mondo di alcune norme essenziali, in virt\u00f9 della locuzione latina pacta sunt servanda, con la quale si vuole mantenere fede alla volont\u00e0 legittimamente manifestata, per risolvere le controversie mediante i mezzi offerti dalla diplomazia, dal negoziato, dalle Istituzioni multilaterali e dal pi\u00f9 ampio desiderio di realizzare \u201cun bene comune realmente universale e la tutela degli Stati pi\u00f9 deboli\u201d. Sulla base di questa breve premessa sulla fratellanza, vorrei profittare di questa occasione per condividere alcune riflessioni sui temi principali di competenza delle Organizzazioni che Voi rappresentate e le priorit\u00e0 della Santa Sede in materia: accesso alla salute, rifugiati, lavoro, diritto internazionale umanitario e disarmo.<\/p>\n<h4>Salute<\/h4>\n<p>Nell\u2019ambito della salute, quest\u2019ultimo anno la famiglia umana ha sperimentato un indissolubile legame che ha \u201csuscitato per un certo tempo la consapevolezza di essere una comunit\u00e0 mondiale che naviga sulla stessa barca, dove il male di uno va a danno di tutti\u201d. Questo sentimento umano di fronte all\u2019ignoto ha in poco tempo ceduto il passo ad una corsa al vaccino e alle cure a livello nazionale, che ha reso manifesto il gap nell\u2019accesso alle cure fondamentali tra i Paesi sviluppati e il resto del mondo. La Santa Sede di fronte ad un problema sistemico, quale quello delle barriere all\u2019accesso alle cure, acuito dall\u2019emergenza attuale, ha offerto una serie di linee guida per affrontare tale questione, ispirate dalla convinzione dell\u2019importanza della fratellanza.<\/p>\n<h4>Vaccini per tutti<\/h4>\n<p>In ogni momento, dobbiamo concentrarci sul sottostante principio del servizio al bene comune. Tale approccio \u00e8 ben esemplificato da San Giovanni Paolo II e dalla sua insistenza sull&#8217;\u201cipoteca sociale\u201d, la quale insiste sul principio della destinazione universale dei beni. In quest\u2019ottica, la comunit\u00e0 internazionale ha l&#8217;obbligo di garantire che qualsiasi vaccino e trattamento COVID-19 sia sicuro, disponibile, accessibile e conveniente per tutti coloro che ne hanno bisogno.<\/p>\n<h4>I rifugiati<\/h4>\n<p>L\u2019attenzione per i pi\u00f9 bisognosi e coloro che si trovano in situazioni di vulnerabilit\u00e0, in particolare per i rifugiati, i migranti e gli sfollati interni, non \u00e8 solo testimonianza di fratellanza, ma una costatazione di un\u2019attenzione al bisogno reale delle nostre sorelle e dei nostri fratelli. Gli appelli incessanti ai leader e agli Organismi Internazionali per una nuova globalizzazione della solidariet\u00e0 capace di soppiantare quella dell\u2019indifferenza sono una costante del Papa e vengono ripresi sistematicamente anche nell\u2019Enciclica. I rifugiati hanno sempre fatto parte della storia. Purtroppo, ancora oggi il loro numero e le loro sofferenze continuano ad essere una ferita nel tessuto sociale della comunit\u00e0 internazionale.<\/p>\n<p>Nell\u2019anno in cui ricorre il 70\u00b0 anniversario dell\u2019Istituzione dell\u2019Alto Commissariato delle Nazioni Unite per i Rifugiati (UNHCR) continuiamo dolorosamente a constatare che il numero delle persone in cerca di protezione continua a salire inesorabilmente. Ci\u00f2 sottintende problematiche umanitarie e sociali profonde. In tal senso, la Santa Sede accoglie la visione di fondo del Global Compact sui rifugiati, che mira a rafforzare la cooperazione internazionale attraverso una condivisione della responsabilit\u00e0 pi\u00f9 equa e prevedibile, ricordando al contempo che la soluzione duratura ideale e pi\u00f9 completa \u00e8 quella di assicurare i diritti di tutti a vivere e prosperare in dignit\u00e0, pace e sicurezza nei propri Paesi d\u2019origine.<\/p>\n<h4>La pandemia e il lavoro<\/h4>\n<p>Nel corso degli ultimi mesi, le strategie di contenimento della pandemia adottate globalmente hanno avuto un significativo impatto su lavoratori, anche informali, piccoli imprenditori e commercianti, che hanno visto un\u2019erosione dei propri risparmi e hanno dovuto sovente fronteggiare delle barriere sistematiche all\u2019accesso all\u2019assistenza sanitaria di base. Nel mondo di oggi, per il bene dei processi di costruzione della pace, il formato tradizionale del dialogo sociale deve essere ampliato e diventare pi\u00f9 inclusivo. Il coinvolgimento delle organizzazioni dei lavoratori e dei datori di lavoro \u00e8 fondamentale, ma dovrebbe essere integrato da attori che rappresentano l&#8217;economia informale e le preoccupazioni ambientali.<\/p>\n<p>Come la Fratelli tutti ricorda \u201coccorre pensare alla partecipazione sociale, politica ed economica in modalit\u00e0 tali \u2018che includano i movimenti popolari e animino le strutture di governo locali, nazionali e internazionali con quel torrente di energia morale che nasce dal coinvolgimento degli esclusi nella costruzione del destino comune\u2019\u201d.<\/p>\n<h4>Il diritto umanitario<\/h4>\n<p>Forse non \u00e8 noto a molti che il Sig. Henry Dunant (1828 \u2013 1910), fondatore della Croce Rossa, fortemente impressionato dalle violenze perpetrate e dalla disorganizzazione dei soccorsi ai feriti, adott\u00f2 anch\u2019egli il grido \u201cTutti fratelli\u201d, per convincere la popolazione locale e i volontari a prestare soccorso a prescindere dall\u2019appartenenza alle parti in conflitto. Fu proprio da tali drammatiche esperienze che il Sig. Dunant concep\u00ec la Croce Rossa. Oggi, purtroppo, c\u2019\u00e8 un urgente bisogno di rafforzare la diffusione e la promozione del rispetto del diritto umanitario. Esso, infatti, si propone di salvaguardare i principi essenziali di umanit\u00e0 in un contesto, quello della guerra, che \u00e8 in s\u00e9 stesso disumano e disumanizzante, proteggendo la popolazione civile e mettendo al bando armi che infliggono sofferenze tanto atroci quanto inutili.<\/p>\n<p>Si potrebbe anche affermare che l\u2019universalit\u00e0 delle Convenzioni di Ginevra del 1949 rappresenti un riconoscimento implicito di quel legame di fratellanza che unisce i popoli, e almeno della necessit\u00e0 di porre limiti ai conflitti. La Santa Sede, inoltre, cosciente di omissioni ed esitazioni, spera che gli Stati possano giungere ad ulteriori sviluppi del diritto internazionale umanitario, al fine di tenere conto adeguatamente delle caratteristiche dei conflitti armati contemporanei e delle sofferenze fisiche, morali e spirituali che ad essi si accompagnano, con l\u2019obiettivo di eliminare i conflitti del tutto.<\/p>\n<h4>Pace<\/h4>\n<p>Il desiderio di pace, di sicurezza e di stabilit\u00e0, infatti, \u00e8 uno dei desideri pi\u00f9 profondi del cuore umano, poich\u00e9 esso \u00e8 radicato nel Creatore, che fa membri della famiglia umana tutti i popoli. Tale aspirazione non pu\u00f2 mai essere soddisfatta soltanto da mezzi militari e meno che mai dal possesso di armi nucleari ed altre armi di distruzione di massa. I conflitti provocano sempre sofferenze, in chi li subisce, certamente, ma anche chi li combatte. Non \u00e8 retorico affermare che la guerra \u00e8 l\u2019antitesi della fratellanza<\/p>\n<h4>Impegno per il disarmo<\/h4>\n<p>\u00c8 in quest\u2019ottica che la Santa Sede incoraggia con convinzione l\u2019impegno degli Stati nell\u2019ambito del disarmo e del controllo degli armamenti verso accordi duraturi sulla strada della pace e, in modo particolare, sul fronte del disarmo nucleare. Se \u00e8 valida l\u2019affermazione che siamo tutti fratelli e sorelle, come pu\u00f2 la deterrenza nucleare essere alla base di un\u2019etica di fraternit\u00e0 e coesistenza pacifica tra i popoli? Alcuni segnali incoraggianti si notano, come la recente entrata in vigore del Trattato sulla proibizione delle armi nucleari.<\/p>\n<p>Fanno per\u00f2 riflettere le ingenti somme di denaro e le risorse umane destinate agli armamenti. Quella di legare la sicurezza nazionale all&#8217;accumulo di armi \u00e8 una logica controproducente. La sproporzione tra le risorse materiali e i talenti umani dedicati al servizio della morte e le risorse dedicate al servizio della vita \u00e8 motivo di scandalo. Sono ben altre le sfide che affliggono la comunit\u00e0 internazionale e tali dovrebbero essere le priorit\u00e0 per gli Stati.<\/p>\n<h4>Mete imprescindibili<\/h4>\n<p>Eccellenze, Signore e Signori, quelle che ho appena esposto sono solo alcune indicazioni di metodo e sfide che la famiglia umana si trova ad affrontare. Indicazioni e mete che la Santa Sede, sulla scia delle prospettive rinnovate da Papa Francesco con l\u2019Enciclica \u201cFratelli tutti\u201d, ritiene imprescindibili per un\u2019azione che voglia essere adeguata e protagonista rispetto ai processi in atto nella comunit\u00e0 internazionale. Siamo consapevoli che per far fronte allo scenario delineato non basta proclamare l\u2019impegno o limitarsi ad incoraggiare sforzi, richiamare doveri o concorrere all\u2019agire cos\u00ec da rispondere concretamente alle grandi sfide. Di qui la necessit\u00e0 non pi\u00f9 di fronteggiare, ma di preparare un progetto in grado di rispondere a ci\u00f2 che viene dopo.<\/p>\n<h4>Regole efficaci<\/h4>\n<p>In questa prospettiva, l\u2019ordinamento giuridico non ha pi\u00f9 necessit\u00e0 solo di regole comuni, ma che queste siano efficienti ed efficaci rispetto alle situazioni di oggi. L\u2019elemento in pi\u00f9 \u00e8 la responsabilit\u00e0 individuale e la capacit\u00e0 di sentirsi fratelli, cio\u00e8 di far propri i bisogni degli altri attraverso una reciprocit\u00e0 di rapporti che superi l\u2019isolamento e coinvolga gli Stati, i singoli e gli organismi internazionali. L\u2019incitamento di Papa Francesco domanda sempre pi\u00f9 una presenza e una condotta rispondente all\u2019attualit\u00e0 delle relazioni tra gli Stati e tra i popoli, specialmente quando sembrano prevalere atteggiamenti che abbandonano la visione del bene comune. Mi auguro che questo evento rappresenti un passo in avanti per tutti noi nell\u2019intraprendere il cammino tanto ricco quanto esigente della fratellanza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;intervento del Segretario di Stato all&#8217;incontro &#8220;Fraternit\u00e0, Multilateralismo e Pace&#8221;<\/p>\n","protected":false},"author":17,"featured_media":11839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[73,83,297],"tags":[1710,1708,473,1305,1709,688,287,1455,640],"class_list":["post-11837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa-e-mondo","category-eventi-internazionali","category-ultime-notizie","tag-disarmo","tag-fratellanza","tag-fratelli-tutti","tag-lavoro","tag-multilateralismo","tag-pace","tag-pandemia","tag-parolin","tag-rifugiati"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parolin: &quot;Rafforzare il rispetto del diritto umanitario&quot; &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"L&#039;intervento del segretario di Stato vaticano Parolin all&#039;incontro internazionale on line su Fraternit\u00e0, multilateralismo e pace\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parolin: &quot;Rafforzare il rispetto del diritto umanitario&quot; &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"L&#039;intervento del segretario di Stato vaticano Parolin all&#039;incontro internazionale on line su Fraternit\u00e0, multilateralismo e pace\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-15T15:35:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Parolin.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"Parolin: &#8220;Rafforzare il rispetto del diritto umanitario&#8221;\",\"datePublished\":\"2021-04-15T15:35:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/\"},\"wordCount\":1815,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Parolin.jpeg?fit=1500%2C844&ssl=1\",\"keywords\":[\"disarmo\",\"fratellanza\",\"Fratelli Tutti\",\"lavoro\",\"multilateralismo\",\"pace\",\"pandemia\",\"Parolin\",\"rifugiati\"],\"articleSection\":[\"Chiesa e Mondo\",\"Eventi internazionali\",\"Ultime Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/\",\"name\":\"Parolin: \\\"Rafforzare il rispetto del diritto umanitario\\\" &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Parolin.jpeg?fit=1500%2C844&ssl=1\",\"datePublished\":\"2021-04-15T15:35:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"description\":\"L'intervento del segretario di Stato vaticano Parolin all'incontro internazionale on line su Fraternit\u00e0, multilateralismo e pace\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Parolin.jpeg?fit=1500%2C844&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Parolin.jpeg?fit=1500%2C844&ssl=1\",\"width\":1500,\"height\":844,\"caption\":\"Il segretario di Stato Parolin \u00a9 Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parolin: &#8220;Rafforzare il rispetto del diritto umanitario&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parolin: \"Rafforzare il rispetto del diritto umanitario\" &#8211; Exaudi","description":"L'intervento del segretario di Stato vaticano Parolin all'incontro internazionale on line su Fraternit\u00e0, multilateralismo e pace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/","og_locale":"it_IT","og_type":"article","og_title":"Parolin: \"Rafforzare il rispetto del diritto umanitario\" &#8211; Exaudi","og_description":"L'intervento del segretario di Stato vaticano Parolin all'incontro internazionale on line su Fraternit\u00e0, multilateralismo e pace","og_url":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2021-04-15T15:35:35+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Parolin.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"Parolin: &#8220;Rafforzare il rispetto del diritto umanitario&#8221;","datePublished":"2021-04-15T15:35:35+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/"},"wordCount":1815,"image":{"@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Parolin.jpeg?fit=1500%2C844&ssl=1","keywords":["disarmo","fratellanza","Fratelli Tutti","lavoro","multilateralismo","pace","pandemia","Parolin","rifugiati"],"articleSection":["Chiesa e Mondo","Eventi internazionali","Ultime Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/","url":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/","name":"Parolin: \"Rafforzare il rispetto del diritto umanitario\" &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Parolin.jpeg?fit=1500%2C844&ssl=1","datePublished":"2021-04-15T15:35:35+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"description":"L'intervento del segretario di Stato vaticano Parolin all'incontro internazionale on line su Fraternit\u00e0, multilateralismo e pace","breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Parolin.jpeg?fit=1500%2C844&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Parolin.jpeg?fit=1500%2C844&ssl=1","width":1500,"height":844,"caption":"Il segretario di Stato Parolin \u00a9 Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/parolin-rafforzare-il-rispetto-del-diritto-umanitario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Parolin: &#8220;Rafforzare il rispetto del diritto umanitario&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Parolin.jpeg?fit=1500%2C844&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-34V","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/11837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=11837"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/11837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/11839"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=11837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=11837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=11837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}