{"id":113773,"date":"2024-11-27T16:38:14","date_gmt":"2024-11-27T15:38:14","guid":{"rendered":"https:\/\/exaudi.org\/?p=113773"},"modified":"2024-11-27T16:38:14","modified_gmt":"2024-11-27T15:38:14","slug":"perche-la-chiesa-e-cattolica","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/","title":{"rendered":"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d?"},"content":{"rendered":"<p>Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d? <a href=\"https:\/\/exaudi.org\/es\/author\/jyate\/\">Padre Jairo Yate<\/a>, sacerdote e giudice istruttore nella <a href=\"https:\/\/notasamablesalapalabra.blogspot.com\/\">diocesi di Ibagu\u00e9<\/a>, in Colombia, risponde a questa domanda secondo gli insegnamenti della Chiesa stessa.<\/p>\n<h3><strong>Cosa significa la parola \u201ccattolico\u201d?<\/strong><\/h3>\n<p>Significa \u201cuniversale\u201d nel senso di \u201csecondo la totalit\u00e0\u201d o \u201csecondo l\u2019integrit\u00e0\u201d. La Chiesa \u00e8 cattolica in un duplice senso.<\/p>\n<h3><strong>Perch\u00e9 \u00e8 cos\u00ec?<\/strong><\/h3>\n<p>Il <a href=\"https:\/\/www.vatican.va\/archive\/catechism_sp\/index_sp.html\">Catechismo della Chiesa Cattolica<\/a> insegna che: \u201c\u00c8 cattolica perch\u00e9 in essa \u00e8 presente Cristo. \u00abDove \u00e8 Cristo Ges\u00f9, ivi \u00e8 la Chiesa cattolica\u00bb (sant&#8217;Ignazio di Antiochia, Epistula ad Smyrnaeos 8, 2). In Lei sussiste la pienezza del Corpo di Cristo unito al suo Capo (cfr Efesini 1,22-23), il che implica che ella riceve da Lui \u00abla pienezza dei mezzi di salvezza\u00bb (AG 6) che Egli ha voluto: retta e completa confessione di fede, vita sacramentale completa e ministero ordinato nella successione apostolica. La Chiesa, in questo senso fondamentale, era cattolica nel giorno della Pentecoste (cfr Ad Gentes 4) e lo sar\u00e0 sempre fino al giorno della Parusia (fine dei tempi, ndr)\u00bb (830).<\/p>\n<p>\u00ab\u00c8 cattolica perch\u00e9 inviata da Cristo in missione presso tutto il genere umano (cfr Mt 28,19)\u00bb (831).<\/p>\n<h3><strong>Cosa insegna la Chiesa Cattolica?<\/strong><\/h3>\n<p>Contenuti essenziali e fondamentali della dottrina cattolica sia sulla fede che sulla morale, alla luce del Concilio Vaticano II e dell&#8217;intera Tradizione della Chiesa.<\/p>\n<h3><strong>Su cosa basa il suo insegnamento la Chiesa Cattolica?<\/strong><\/h3>\n<p>Le sue fonti principali sono la Sacra Scrittura, i Santi Padri, la Liturgia e il Magistero della Chiesa. Vuole servire \u201ccome punto di riferimento per i catechismi o compendi che si compongono nei vari Paesi\u201d. (Catechismo 11)<\/p>\n<h3><strong>Qual \u00e8 la fede della Chiesa cattolica?<\/strong><\/h3>\n<p>\u201cLa fede cattolica \u00e8: che veneriamo un solo Dio nella Trinit\u00e0 e la Trinit\u00e0 nell&#8217;unit\u00e0, senza confondere le persone, n\u00e9 separando le sostanze; una \u00e8 la persona del Padre, altra quella del Figlio, altra quella dello Spirito Santo; Ma del Padre e del Figlio e dello Spirito Santo la divinit\u00e0 \u00e8 una, la gloria uguale, la maest\u00e0 coeterna\u00bb (Catechismo 266).<\/p>\n<h3><strong>La Chiesa Cattolica crede nella Vergine Maria?<\/strong><\/h3>\n<p>Ci\u00f2 che la fede cattolica crede riguardo a Maria si fonda su ci\u00f2 che crede riguardo a Cristo, ma ci\u00f2 che insegna su Maria, a sua volta, illumina la fede in Cristo. (Catechismo 487).<\/p>\n<h3><strong>Chi governa nella Chiesa cattolica?<\/strong><\/h3>\n<p>\u201cLa Chiesa cattolica, governata dal successore di Pietro e dai vescovi in \u200b\u200bcomunione con lui\u201d (<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19641121_lumen-gentium_sp.html\">Lumen Gentium<\/a><\/em> 8).<\/p>\n<p>Che cos&#8217;\u00e8 una Chiesa particolare?<\/p>\n<p>Per Chiesa particolare si intende innanzitutto la diocesi (o eparchia), cio\u00e8 una comunit\u00e0 di fedeli cristiani in comunione nella fede e nei sacramenti con il proprio Vescovo ordinato nella successione apostolica. Queste Chiese particolari sono \u00abformate a immagine della Chiesa universale. In essi e a partire da essi esiste la Chiesa cattolica, una e unica\u00bb (<em>Lumen Gentium<\/em> 23).<\/p>\n<p>Le Chiese particolari sono pienamente cattoliche grazie alla comunione con una di esse: la Chiesa di Roma \u201cche presiede nella carit\u00e0\u201d (sant&#8217;Ignazio di Antiochia).<\/p>\n<h3><strong>Chi appartiene alla Chiesa cattolica?<\/strong><\/h3>\n<p>\u00abTutti gli uomini, quindi, sono invitati a questa unit\u00e0 cattolica del popolo di Dio&#8230; A questa unit\u00e0 in diversi modi appartengono o sono destinati alla grazia i cattolici, gli altri cristiani e anche tutti gli uomini in generale chiamati alla salvezza da Dio di Dio\u201d (<em>Lumen Gentium<\/em> 13).<\/p>\n<h3><strong>La Chiesa cattolica offre mezzi per la salvezza?<\/strong><\/h3>\n<p>La Chiesa cattolica annuncia la totalit\u00e0 della fede; porta in s\u00e9 e amministra la pienezza dei mezzi di salvezza; Viene inviato a tutte le citt\u00e0; \u00c8 rivolto a tutti gli uomini; copre tutti i tempi; \u00ab\u00e8 per sua natura missionaria\u00bb (<a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_decree_19651207_ad-gentes_sp.html\">Ad Gentes<\/a> 2).<\/p>\n<h3><strong>Come comprendere la presenza delle immagini nella Chiesa cattolica?<\/strong><\/h3>\n<p>\u201cLa bellezza e il colore delle immagini stimolano la mia preghiera. \u00c8 una festa per i miei occhi, cos\u00ec come lo spettacolo della campagna stimola il mio cuore a dare gloria a Dio\u00bb (San Giovanni Damasceno).<\/p>\n<p>\u00abLa contemplazione delle sacre immagini, insieme alla meditazione della Parola di Dio e al canto degli inni liturgici, rientra nell&#8217;armonia dei segni della celebrazione affinch\u00e9 il mistero celebrato sia registrato nella memoria del cuore e sia esprimerlo poi nella vita nuova dei fedeli\u00bb (Catechismo 1162).<\/p>\n<h3><strong>\u00c8 vero che il Battesimo \u00e8 fonte di comunione nella Chiesa cattolica?<\/strong><\/h3>\n<p>\u00abIl Battesimo costituisce il fondamento della comunione tra tutti i cristiani, e anche con coloro che non sono ancora in piena comunione con la Chiesa cattolica: \u00abColoro che credono in Cristo e hanno validamente ricevuto il Battesimo, si trovano in una certa comunione, anche se non perfetta, con i Chiesa cattolica [\u2026]. Giustificati dalla fede nel Battesimo, sono stati incorporati a Cristo, perci\u00f2 sono giustamente onorati del nome di cristiani e giustamente riconosciuti dai figli della Chiesa cattolica Signore (<a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_decree_19641121_unitatis-redintegratio_sp.html\">UR<\/a>\u00a03)\u00bb (Catechismo 1271).<\/p>\n<h3><strong>Cosa sono i sacramentali nella Chiesa cattolica?<\/strong><\/h3>\n<p>\u00abSono stati istituiti dalla Chiesa per santificare alcuni ministeri ecclesiali, alcuni stati di vita, circostanze molto diverse della vita cristiana, nonch\u00e9 l&#8217;uso delle cose utili all&#8217;uomo. Esse comprendono sempre una preghiera, spesso accompagnata da un segno specifico, come l&#8217;imposizione della mano, il segno della croce, l&#8217;aspersione dell&#8217;acqua santa (che ricorda il Battesimo)\u00bb (Catechismo 1668).<\/p>\n<h3><strong>Quali sono i sacramenti della Chiesa cattolica?<\/strong><\/h3>\n<p>Sono Grazia di Dio, vengono da Dio, istituiti da Cristo, per il nostro bene. I sacramenti della Nuova Legge sono stati istituiti da Cristo e sono sette: Battesimo, Cresima, Eucaristia, Penitenza, Unzione degli infermi, Ordini sacerdotali e. Matrimonio.<\/p>\n<h3><strong>Cosa vuole Papa Francesco dalla Chiesa cattolica?<\/strong><\/h3>\n<p>La sua preferenza per la Chiesa che cresce nel silenzio, nel nascosto. \u201cLa Chiesa cresce nella semplicit\u00e0, nel silenzio, nella lode, nel sacrificio eucaristico, nella comunit\u00e0 fraterna, dove tutti si amano e non litigano\u201d. \u201cLa Chiesa si manifesta nell\u2019Eucaristia e nelle opere buone, anche quando apparentemente non sono una novit\u00e0\u201d. \u201cLa sposa di Cristo ha un temperamento silenzioso, produce frutto senza rumore, senza suonare le trombe, come fanno i farisei\u201d. \u00abLa Chiesa cresce attraverso la testimonianza, la preghiera e l\u2019attrazione dello Spirito\u00bb (Omelia 15 novembre 2018).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domande e risposte<\/p>\n","protected":false},"author":75,"featured_media":41217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[71],"tags":[4030,25068,13987,4512,5613,20403,882,2382,1384,15434,17622,34445,34446,34444,34447,12236,34448,34449,21202,251,12159,34450,2547,3987,34451,17482,4952,34452,9837],"class_list":["post-113773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisi","tag-battesimo","tag-catechismo-della-chiesa-cattolica","tag-cattolico","tag-chiesa-cattolica","tag-comunione","tag-comunita-cristiana","tag-cristo","tag-diocesi","tag-eucaristia","tag-fede-cattolica","tag-fede-cristiana","tag-governo-della-chiesa","tag-immagini-nella-chiesa","tag-insegnamento-cattolico","tag-jairo-yate-3","tag-lumen-gentium-2","tag-magisterio-2","tag-mezzi-della-salvezza","tag-missione-della-chiesa","tag-papa-francesco","tag-sacra-scrittura","tag-sacramentali","tag-sacramenti","tag-salvezza","tag-significato-cattolico","tag-tradizione-cattolica","tag-trending-it","tag-universale","tag-vergine-maria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d? &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d? &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Domande e risposte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-27T15:38:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/11\/cathopic_1486130356596435-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jairo Yate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jairo Yate\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/\"},\"author\":{\"name\":\"Jairo Yate\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/0a445e18eeda8a4169db2546dec04b44\"},\"headline\":\"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d?\",\"datePublished\":\"2024-11-27T15:38:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/\"},\"wordCount\":945,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cathopic_1486130356596435-scaled-1.jpg\",\"keywords\":[\"battesimo\",\"Catechismo della Chiesa Cattolica\",\"CATTOLICO\",\"Chiesa cattolica\",\"comunione\",\"COMUNIT\u00c0 CRISTIANA\",\"Cristo\",\"diocesi\",\"Eucaristia\",\"FEDE CATTOLICA\",\"FEDE CRISTIANA\",\"Governo della Chiesa\",\"immagini nella Chiesa\",\"Insegnamento cattolico\",\"Jairo Yate\",\"LUMEN GENTIUM\",\"MAGISTERIO\",\"mezzi della salvezza\",\"MISSIONE DELLA CHIESA\",\"Papa Francesco\",\"SACRA SCRITTURA\",\"sacramentali\",\"sacramenti\",\"salvezza\",\"significato cattolico\",\"TRADIZIONE CATTOLICA\",\"Trending\",\"universale\",\"VERGINE MARIA\"],\"articleSection\":[\"Analisi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/\",\"name\":\"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d? &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cathopic_1486130356596435-scaled-1.jpg\",\"datePublished\":\"2024-11-27T15:38:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/0a445e18eeda8a4169db2546dec04b44\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cathopic_1486130356596435-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cathopic_1486130356596435-scaled-1.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Fonte battesimale \u00a9 Cathopic.Melina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/perche-la-chiesa-e-cattolica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/0a445e18eeda8a4169db2546dec04b44\",\"name\":\"Jairo Yate\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebf148b228fd57b990e025e8ebec5910efc8cda0a662cd217e736dd113fd728f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebf148b228fd57b990e025e8ebec5910efc8cda0a662cd217e736dd113fd728f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebf148b228fd57b990e025e8ebec5910efc8cda0a662cd217e736dd113fd728f?s=96&d=mm&r=g\",\"caption\":\"Jairo Yate\"},\"description\":\"El padre Jairo Yate Ram\u00edrez fue ordenado sacerdote el 23 de Noviembre 1985, incardinado a la arquidi\u00f3cesis de Ibagu\u00e9, Colombia. Licenciado en Teolog\u00eda Moral por Universidad Santa Croce, Roma, Italia. Diplomado en Derecho Can\u00f3nico. Juez Instructor Tribunal Eclesi\u00e1stico y Notario, arquidi\u00f3cesis de Ibagu\u00e9\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/jyate\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d? &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/","og_locale":"it_IT","og_type":"article","og_title":"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d? &#8211; Exaudi","og_description":"Domande e risposte","og_url":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2024-11-27T15:38:14+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/11\/cathopic_1486130356596435-scaled-1.jpg","type":"image\/jpeg"}],"author":"Jairo Yate","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Jairo Yate","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/"},"author":{"name":"Jairo Yate","@id":"https:\/\/exaudi.org\/#\/schema\/person\/0a445e18eeda8a4169db2546dec04b44"},"headline":"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d?","datePublished":"2024-11-27T15:38:14+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/"},"wordCount":945,"commentCount":0,"image":{"@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/11\/cathopic_1486130356596435-scaled-1.jpg","keywords":["battesimo","Catechismo della Chiesa Cattolica","CATTOLICO","Chiesa cattolica","comunione","COMUNIT\u00c0 CRISTIANA","Cristo","diocesi","Eucaristia","FEDE CATTOLICA","FEDE CRISTIANA","Governo della Chiesa","immagini nella Chiesa","Insegnamento cattolico","Jairo Yate","LUMEN GENTIUM","MAGISTERIO","mezzi della salvezza","MISSIONE DELLA CHIESA","Papa Francesco","SACRA SCRITTURA","sacramentali","sacramenti","salvezza","significato cattolico","TRADIZIONE CATTOLICA","Trending","universale","VERGINE MARIA"],"articleSection":["Analisi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/","url":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/","name":"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d? &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/11\/cathopic_1486130356596435-scaled-1.jpg","datePublished":"2024-11-27T15:38:14+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/0a445e18eeda8a4169db2546dec04b44"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/11\/cathopic_1486130356596435-scaled-1.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/11\/cathopic_1486130356596435-scaled-1.jpg","width":2560,"height":1707,"caption":"Fonte battesimale \u00a9 Cathopic.Melina"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/perche-la-chiesa-e-cattolica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Perch\u00e9 la Chiesa \u00e8 \u201ccattolica\u201d?"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/0a445e18eeda8a4169db2546dec04b44","name":"Jairo Yate","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ebf148b228fd57b990e025e8ebec5910efc8cda0a662cd217e736dd113fd728f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ebf148b228fd57b990e025e8ebec5910efc8cda0a662cd217e736dd113fd728f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ebf148b228fd57b990e025e8ebec5910efc8cda0a662cd217e736dd113fd728f?s=96&d=mm&r=g","caption":"Jairo Yate"},"description":"El padre Jairo Yate Ram\u00edrez fue ordenado sacerdote el 23 de Noviembre 1985, incardinado a la arquidi\u00f3cesis de Ibagu\u00e9, Colombia. Licenciado en Teolog\u00eda Moral por Universidad Santa Croce, Roma, Italia. Diplomado en Derecho Can\u00f3nico. Juez Instructor Tribunal Eclesi\u00e1stico y Notario, arquidi\u00f3cesis de Ibagu\u00e9","url":"https:\/\/exaudi.org\/it\/author\/jyate\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/11\/cathopic_1486130356596435-scaled-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-tB3","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/113773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=113773"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/113773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/41217"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=113773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=113773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=113773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}