{"id":112431,"date":"2024-11-07T17:31:07","date_gmt":"2024-11-07T16:31:07","guid":{"rendered":"https:\/\/exaudi.org\/?p=112431"},"modified":"2024-11-07T17:31:07","modified_gmt":"2024-11-07T16:31:07","slug":"come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/","title":{"rendered":"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei?"},"content":{"rendered":"<p>Vi invitiamo a partecipare ai prossimi tre webinar sulla FAMIGLIA organizzati dal Consiglio Cattolico Nazionale per la Pastorale Ispanica (USA) in collaborazione con il Consiglio Episcopale Latinoamericano (CELAM) e il suo Centro Biblico Teologico Pastorale per l&#8217;America Latina e i Caraibi (Cebitepal). Dopo la conclusione dei primi quattro webinar lo scorso maggio, abbiamo raccolto le domande pi\u00f9 rilevanti dei partecipanti e siamo entusiasti di rispondere in questa nuova serie.<\/p>\n<h3><strong>Calendario dei webinar<\/strong><\/h3>\n<p>Mercoled\u00ec 13 e 20 novembre e 4 dicembre 2024 &#8211; 18:00 (Miami\/Colombia)<\/p>\n<h3><strong>1. Come possiamo aiutare i nostri figli a superare la pressione dei coetanei?<\/strong><\/h3>\n<p><strong>Mercoled\u00ec 13 novembre 2024<\/strong><\/p>\n<p>La chiave \u00e8 in noi come genitori. In questo webinar verranno forniti importanti consigli su come favorire l&#8217;indipendenza dei bambini, bilanciando l&#8217;accompagnamento con l&#8217;autonomia.<\/p>\n<h3><strong>2. Come garantire che le reti non inghiottiscano i nostri figli?<\/strong><\/h3>\n<p><strong>Mercoled\u00ec 20 novembre 2024<\/strong><\/p>\n<p>\u00c8 possibile con una buona pedagogia! Questo argomento centrale affronter\u00e0 strategie efficaci per gestire l&#8217;uso dei social network e mantenere l&#8217;armonia familiare.<\/p>\n<h3><strong>3. Come possiamo convincere i nostri figli ad andare a Messa?<\/strong><\/h3>\n<p><strong>Mercoled\u00ec 4 dicembre 2024<\/strong><\/p>\n<p>Non \u00e8 quello che pensi! Verr\u00e0 condivisa un&#8217;alternativa innovativa che va oltre i metodi tradizionali e incoraggia la partecipazione attiva dei bambini alla vita della Chiesa.<\/p>\n<h3><strong>Registrazione e ulteriori informazioni<\/strong><\/h3>\n<ul>\n<li><strong>Iscriviti ai webinar:<\/strong> <a href=\"http:\/\/www.bit.ly\/webinar-pastoral\">www.bit.ly\/webinar-pastoral<\/a><\/li>\n<li><strong>Informazioni aggiornate:<\/strong> <a href=\"http:\/\/ncchm.us\/webinar-sobre-familia\">nccm.us\/webinar-sobre-familia<\/a><\/li>\n<\/ul>\n<p>Un approccio globale per rafforzare la famiglia<\/p>\n<p>Questi tre webinar, che sviluppano la pedagogia dei legami, della fiducia e della libert\u00e0, formano un&#8217;unit\u00e0 completa. Forniranno strumenti chiari per rafforzare i legami familiari e motivare i nostri figli a vivere una vita piena. Da non perdere!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come possiamo aiutare i nostri figli a superare la pressione dei coetanei?<\/p>\n","protected":false},"author":17,"featured_media":112354,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[73],"tags":[30992,13294,1502,30997,31007,30991,30993,30995,30987,31000,30994,30996,31006,31004,31008,30998,30988,31005,30989,31009,30999,31001,30990,31002,31003,31011,31010],"class_list":["post-112431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa-e-mondo","tag-catholic-education-2","tag-cebitepal-3","tag-celam-it","tag-childrens-independence","tag-educational-webinars","tag-family-development-2","tag-family-education-2","tag-family-formation","tag-family-harmony","tag-family-pedagogy","tag-family-strategies-family","tag-family-strengthening","tag-family-ties","tag-family-values-2","tag-family-webinars-2024","tag-hispanic-ministry","tag-latin-american-episcopal-council-2","tag-life-in-fullness","tag-national-catholic-council-for-hispanic-ministry","tag-online-webinars","tag-participation-in-mass","tag-peer-pressure","tag-positive-parenting-2","tag-social-networks-2","tag-tips-for-parents","tag-webinars-about-the-family","tag-webinars-for-parents"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come possiamo aiutare i nostri figli a superare la pressione dei coetanei? &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei? &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-07T16:31:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei?\",\"datePublished\":\"2024-11-07T16:31:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/\"},\"wordCount\":268,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg?fit=2560%2C1237&ssl=1\",\"keywords\":[\"Catholic education\",\"CEBITEPAL\",\"CELAM\",\"children's independence\",\"educational webinars\",\"Family development\",\"Family education\",\"family formation\",\"family harmony\",\"family pedagogy\",\"family strategies. Family\",\"family strengthening\",\"family ties\",\"family values\",\"family webinars 2024\",\"Hispanic ministry\",\"Latin American Episcopal Council\",\"life in fullness\",\"National Catholic Council for Hispanic Ministry\",\"online webinars\",\"participation in mass\",\"peer pressure\",\"positive parenting\",\"Social networks\",\"tips for parents\",\"webinars about the family\",\"webinars for parents\"],\"articleSection\":[\"Chiesa e Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/\",\"name\":\"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei? &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg?fit=2560%2C1237&ssl=1\",\"datePublished\":\"2024-11-07T16:31:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg?fit=2560%2C1237&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg?fit=2560%2C1237&ssl=1\",\"width\":2560,\"height\":1237,\"caption\":\"Foto de Benjamin Manley en Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei? &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/","og_locale":"it_IT","og_type":"article","og_title":"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei? &#8211; Exaudi","og_description":"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei?","og_url":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2024-11-07T16:31:07+00:00","og_image":[{"width":2560,"height":1237,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei?","datePublished":"2024-11-07T16:31:07+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/"},"wordCount":268,"image":{"@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg?fit=2560%2C1237&ssl=1","keywords":["Catholic education","CEBITEPAL","CELAM","children's independence","educational webinars","Family development","Family education","family formation","family harmony","family pedagogy","family strategies. Family","family strengthening","family ties","family values","family webinars 2024","Hispanic ministry","Latin American Episcopal Council","life in fullness","National Catholic Council for Hispanic Ministry","online webinars","participation in mass","peer pressure","positive parenting","Social networks","tips for parents","webinars about the family","webinars for parents"],"articleSection":["Chiesa e Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/","url":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/","name":"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei? &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg?fit=2560%2C1237&ssl=1","datePublished":"2024-11-07T16:31:07+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg?fit=2560%2C1237&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg?fit=2560%2C1237&ssl=1","width":2560,"height":1237,"caption":"Foto de Benjamin Manley en Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/come-possiamo-aiutare-i-nostri-figli-a-superare-la-pressione-dei-coetanei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Come possiamo aiutare i nostri figli a superare la pressione dei coetanei?"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-tfp","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/benjamin-manley-QkflfhJn1KA-unsplash-scaled.jpg?fit=2560%2C1237&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/112431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=112431"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/112431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/112354"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=112431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=112431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=112431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}