{"id":109113,"date":"2024-09-25T18:21:39","date_gmt":"2024-09-25T16:21:39","guid":{"rendered":"https:\/\/exaudi.org\/?p=109113"},"modified":"2024-09-25T18:25:24","modified_gmt":"2024-09-25T16:25:24","slug":"continuiamo-ad-essere-costruttori-di-pace","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/","title":{"rendered":"Continuiamo ad essere costruttori di pace"},"content":{"rendered":"<p>In un emozionante incontro svoltosi nella Cattedrale di Notre-Dame, la Comunit\u00e0 di Sant&#8217;Egidio ha riunito uomini e donne di fede per riflettere sulla pace e sulla fraternit\u00e0. Questo evento, pieno di speranza e di impegno, ha ricordato l&#8217;importanza di continuare a costruire ponti di comprensione e riconciliazione in un mondo segnato dal conflitto.<\/p>\n<h3><strong>Una testimonianza di speranza<\/strong><\/h3>\n<p>Laurent Ulrich, arcivescovo di Parigi, ha aperto la cerimonia ricordando il dolore causato dall&#8217;incendio di Notre-Dame, simbolo della spiritualit\u00e0 che unisce milioni di persone. La cattedrale, che si erge come luogo di preghiera, \u00e8 diventata anche emblema della resilienza umana. &#8220;In questa citt\u00e0, i Giochi Olimpici hanno mostrato le virt\u00f9 della competizione e diffuso una gioia contagiosa&#8221;, ha detto Ulrich, esortando tutti a unirsi sulla via della pace.<\/p>\n<p>Durante l&#8217;evento si sono sentite le voci di coloro che hanno subito le conseguenze della guerra. Gilberte Fournier, sopravvissuta alla seconda guerra mondiale, ha condiviso la sua esperienza: \u201cLa guerra distrugge tutto. Non dobbiamo dimenticare il grande male che \u00e8 la guerra. \u00c8 nostro dovere trasmetterne la memoria alle generazioni pi\u00f9 giovani\u201d. La loro testimonianza ha avuto una forte risonanza, ricordandoci che la pace non dovrebbe essere un ideale lontano, ma piuttosto uno sforzo collettivo.<\/p>\n<h3><strong>Un messaggio di Papa Francesco<\/strong><\/h3>\n<p>Nel suo messaggio, Papa Francesco ha esortato tutti i partecipanti a essere \u201cartigiani di pace\u201d. Ha sottolineato che le religioni devono smettere di essere strumenti di conflitto e diventare motori di dialogo e di amicizia. \u201cLa pace attende i suoi artefici\u201d, ha proclamato il Santo Padre, sottolineando che in tempo di guerra il compito di costruire la pace \u00e8 pi\u00f9 urgente che mai.<\/p>\n<p>Il Papa ha lanciato un appello anche ai leader politici: \u201cFermate la guerra! Stiamo distruggendo il mondo. &#8220;\u00c8 tempo di agire con saggezza e determinazione per promuovere la fratellanza tra le persone&#8221;. Il suo messaggio ha risuonato nel cuore di coloro che cercano un futuro in cui la pace sia una realt\u00e0 e non solo un desiderio.<\/p>\n<h3><strong>La comunit\u00e0 in azione<\/strong><\/h3>\n<p>Marco Impagliazzo, presidente della Comunit\u00e0 di Sant&#8217;Egidio, ha chiuso i lavori con un appello all&#8217;azione. \u201cLa pace \u00e8 la nostra vittoria, non contro gli altri, ma con gli altri\u201d, ha affermato. Ha sottolineato l&#8217;importanza di trasmettere l&#8217;eredit\u00e0 della pace da una generazione all&#8217;altra, esortando tutti a immaginare un futuro senza conflitti.<\/p>\n<p>Lo spirito di unit\u00e0 e di speranza che ha permeato l&#8217;incontro di Notre-Dame \u00e8 una testimonianza dell&#8217;impegno e della buona volont\u00e0 delle comunit\u00e0 religiose nella lotta per la pace. In questo luogo sacro si \u00e8 rinnovato l&#8217;impegno di tutti i presenti: continuare a essere costruttori di pace, instancabili nella loro opera di riconciliazione e di fraternit\u00e0.<\/p>\n<p>L\u2019incontro a Notre-Dame ha ricordato con forza che, anche in tempi di incertezza, il dialogo, l\u2019ascolto e la comprensione sono essenziali per costruire un futuro migliore. Continuiamo a immaginare la pace e a lavorare insieme per renderla realt\u00e0.<\/p>\n<p><a href=\"https:\/\/meetingsforpeace.santegidio.org\/\">Per ulteriori informazioni<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Notre-Dame, Parigi: Un appello alla pace e alla riconciliazione<\/p>\n","protected":false},"author":17,"featured_media":108999,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[],"tags":[25569,6542,3569,25548,1956,25549,25551,1668,25550,25553,10803,688,251,25554,25555,2490,510,25552,25556,4952,20701],"class_list":["post-109113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-cattedrale-di-notre-dame","tag-comunita-di-santegidio","tag-conflitti","tag-costruzione-della-pace","tag-dialogo-it","tag-evento-interreligioso-2","tag-fratellanza-mondiale","tag-fraternita","tag-futuro-senza-guerre","tag-giovani-e-pace","tag-interreligioso","tag-pace","tag-papa-francesco","tag-promozione-della-pace","tag-religioni-e-pace","tag-riconciliazione","tag-solidarieta","tag-storia-di-pace","tag-testimonianze-di-guerra","tag-trending-it","tag-valori-umanitari"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Continuiamo ad essere costruttori di pace &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Continuiamo ad essere costruttori di pace &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Da Notre-Dame, Parigi: Un appello alla pace e alla riconciliazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-25T16:21:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T16:25:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"Continuiamo ad essere costruttori di pace\",\"datePublished\":\"2024-09-25T16:21:39+00:00\",\"dateModified\":\"2024-09-25T16:25:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/\"},\"wordCount\":489,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg?fit=1200%2C675&ssl=1\",\"keywords\":[\"Cattedrale di Notre-Dame\",\"Comunit\u00e0 di Sant'Egidio\",\"conflitti\",\"costruzione della pace\",\"di\u00e1logo\",\"Evento interreligioso\",\"Fratellanza mondiale\",\"fraternit\u00e0\",\"Futuro senza guerre\",\"Giovani e pace\",\"INTERRELIGIOSO\",\"pace\",\"Papa Francesco\",\"Promozione della pace\",\"Religioni e pace\",\"riconciliazione\",\"solidariet\u00e0\",\"Storia di pace\",\"Testimonianze di guerra\",\"Trending\",\"VALORI UMANITARI\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/\",\"name\":\"Continuiamo ad essere costruttori di pace &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg?fit=1200%2C675&ssl=1\",\"datePublished\":\"2024-09-25T16:21:39+00:00\",\"dateModified\":\"2024-09-25T16:25:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg?fit=1200%2C675&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg?fit=1200%2C675&ssl=1\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/continuiamo-ad-essere-costruttori-di-pace\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Continuiamo ad essere costruttori di pace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Continuiamo ad essere costruttori di pace &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/","og_locale":"it_IT","og_type":"article","og_title":"Continuiamo ad essere costruttori di pace &#8211; Exaudi","og_description":"Da Notre-Dame, Parigi: Un appello alla pace e alla riconciliazione","og_url":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2024-09-25T16:21:39+00:00","article_modified_time":"2024-09-25T16:25:24+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"Continuiamo ad essere costruttori di pace","datePublished":"2024-09-25T16:21:39+00:00","dateModified":"2024-09-25T16:25:24+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/"},"wordCount":489,"image":{"@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/09\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg?fit=1200%2C675&ssl=1","keywords":["Cattedrale di Notre-Dame","Comunit\u00e0 di Sant'Egidio","conflitti","costruzione della pace","di\u00e1logo","Evento interreligioso","Fratellanza mondiale","fraternit\u00e0","Futuro senza guerre","Giovani e pace","INTERRELIGIOSO","pace","Papa Francesco","Promozione della pace","Religioni e pace","riconciliazione","solidariet\u00e0","Storia di pace","Testimonianze di guerra","Trending","VALORI UMANITARI"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/","url":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/","name":"Continuiamo ad essere costruttori di pace &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/09\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg?fit=1200%2C675&ssl=1","datePublished":"2024-09-25T16:21:39+00:00","dateModified":"2024-09-25T16:25:24+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/09\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg?fit=1200%2C675&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/09\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg?fit=1200%2C675&ssl=1","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/continuiamo-ad-essere-costruttori-di-pace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Continuiamo ad essere costruttori di pace"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/09\/Cerimonia_finale_dell_Incontro_Internazionale_Imaginer_la_Paix_77.jpg?fit=1200%2C675&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-snT","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/109113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=109113"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/109113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/108999"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=109113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=109113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=109113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}