{"id":102020,"date":"2024-05-31T23:57:00","date_gmt":"2024-05-31T21:57:00","guid":{"rendered":"https:\/\/exaudi.org\/?p=102020"},"modified":"2024-05-31T23:57:00","modified_gmt":"2024-05-31T21:57:00","slug":"festa-della-visitazione-della-vergine","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/","title":{"rendered":"Festa della Visitazione della Vergine"},"content":{"rendered":"<p>Il sacerdote <a href=\"https:\/\/exaudi.org\/es\/author\/joseantiniosenovilla\/\">D. Jos\u00e9 Antonio Senovilla<\/a> propone questo articolo sulla festa della Visitazione della Vergine, celebrata oggi, 31 maggio.<\/p>\n<p>***<\/p>\n<p>Perch\u00e9 la visita di una giovane donna al suo parente, in un minuscolo villaggio, \u00e8 cos\u00ec importante per i cristiani, a tal punto da essere uno dei misteri pi\u00f9 notevoli della vita di Ges\u00f9, che ogni giorno consideriamo nel Rosario ?<\/p>\n<p>Perch\u00e9 in quell&#8217;incontro Dio era presente in modo del tutto speciale e anche qui ci viene donato il canto di gratitudine e di lode pi\u00f9 puro, gioioso e profondo che qualunque creatura abbia mai pronunciato. Il <a href=\"http:\/\/www.vatican.va\/content\/john-paul-ii\/es\/audiences\/1996\/documents\/hf_jp-ii_aud_19961106.html\">Magnificat<\/a> \u00e8 servito da ispirazione per alcune delle opere pi\u00f9 importanti della storia della musica e dell&#8217;arte in generale.<\/p>\n<p>L&#8217;incontro ha avuto luogo in uno dei villaggi pi\u00f9 belli della Palestina. Quando visiti la Terra Santa, rimani colpito dalla bellezza e dalla freschezza del paesaggio di Ain-Karem, il luogo dove vissero Zaccaria ed Elisabetta, a pochi chilometri da Gerusalemme.<\/p>\n<p>Parliamo di due anziani che, con gli anni, hanno imparato ad amarsi ogni giorno di pi\u00f9, a rispettarsi ogni giorno di pi\u00f9, a sorprendersi ogni giorno di pi\u00f9. Quel suo amore, puro, pulito, profondo, sempre giovane, era una manifestazione dell&#8217;amore di Dio. Perch\u00e9 la sua fede in Dio era molto grande. Dio, che avevano sempre voluto servire con tutto il cuore, aveva chiesto loro un grande sacrificio: Isabella era sterile e anche gi\u00e0 vecchia, quindi tutto indicava che sarebbero morte senza vedere il frutto del loro amore. Quante volte avevano chiesto a Dio un miracolo, e sembrava che Dio non volesse ascoltarli, che i suoi piani per loro fossero diversi! Per una donna d&#8217;Israele, non avere figli era segno di punizione, punizione per qualche peccato. E per quanto Zacar\u00edas dimostrasse affetto e tenerezza a sua moglie, lei soffriva per non avergli dato un figlio&#8230;<\/p>\n<p>Ma i piani di Dio erano diversi. Elisabetta, come suo marito Zaccaria, erano pieni di Dio. E il figlio che Dio avrebbe mandato loro sarebbe stato il Precursore stesso del Messia, colui che prepar\u00f2 la strada e indic\u00f2 El Salvador, colui che pot\u00e9 vedere i cieli aperti quando Ges\u00f9 fu battezzato e ascoltare la voce del Padre. : \u201cQuesto \u00e8 il Figlio mio, il prediletto, nel quale mi sono compiaciuto (Matteo 3:17).\u201d<\/p>\n<p>\u00c8 commovente la scena che contempliamo nel mistero della Visitazione: un incontro familiare molto speciale. Maria arriva in aiuto dell&#8217;anziana cugina accogliendo prontamente il suggerimento dell&#8217;angelo durante l&#8217;Annunciazione. E ora, alle porte della casa di Elisabetta e Zaccaria, tutti sono pieni di Spirito Santo. Ges\u00f9, nel grembo di sua Madre; Maria stessa, piena di grazia; Giovanni, nel grembo di Elisabetta: pieno di Spirito, esultava di gioia; e infine Elisabetta e Zaccaria; e Giuseppe, che sicuramente accompagn\u00f2 Maria nel suo lungo e pericoloso viaggio da Nazaret. Tutti pieni di Spirito Santo, ciascuno adempiendo la volont\u00e0 di Dio. Che grande esempio di fedelt\u00e0 per tutti noi!<\/p>\n<p>L\u00e0 i cuori di tutti erano aperti. La gioia degli anziani nel vedere la loro parente Maria, che gi\u00e0 sapevano essere la madre del Messia, \u00e8 stata immensa: bisogna immaginarselo. Il clima di gratitudine verso Dio e verso tutti, pieno. E, all&#8217;improvviso, Maria, quella creatura piena di discrezione e di umilt\u00e0, cominci\u00f2 a cantare le sue lodi a Dio. \u00c8 un grande tesoro che ci viene donato: la gioia straripante di un Cuore come quello di Maria.<\/p>\n<p>San Luca lo riprende nel primo capitolo del suo Vangelo: cos\u00ec la Vergine gli disse:<\/p>\n<p>[46] Maria esclam\u00f2:<\/p>\n<p>\u2014L&#8217;anima mia magnifica il Signore,<\/p>\n<p>[47] E il mio spirito esulta in Dio, mio \u200b\u200bsalvatore:<\/p>\n<p>[48]perch\u00e9 ha alzato gli occhi<\/p>\n<p>nell&#8217;umilt\u00e0 del suo schiavo;<\/p>\n<p>Per questo d&#8217;ora in poi mi chiameranno beata<\/p>\n<p>tutte le generazioni.<\/p>\n<p>[49] Perch\u00e9 ha fatto per me grandi cose<\/p>\n<p>l&#8217;onnipotente,<\/p>\n<p>il cui nome \u00e8 Santo;<\/p>\n<p>[50] La sua misericordia si diffonde di generazione in generazione<\/p>\n<p>nella generazione<\/p>\n<p>su coloro che lo temono.<\/p>\n<p>[51] Mostr\u00f2 la potenza del suo braccio,<\/p>\n<p>Ha disperso i superbi nel cuore.<\/p>\n<p>[52] Ha rovesciato i potenti dai troni<\/p>\n<p>ed ha esaltato gli umili.<\/p>\n<p>[53] Ha ricolmato di beni gli affamati<\/p>\n<p>e rimand\u00f2 i ricchi a mani vuote.<\/p>\n<p>[54] Ha protetto Israele suo servo,<\/p>\n<p>ricordando la sua misericordia,<\/p>\n<p>[55]Come avevo promesso ai nostri padri,<\/p>\n<p>Abramo e i suoi discendenti per sempre.<\/p>\n<p>Ecco quanto \u00e8 grande e buono Dio, che riempie di grazia e di giustizia questo mondo spesso crudele e ingiusto! Ecco quanto \u00e8 buono Dio nostro Padre, che opera meraviglie anche in noi! E quanto pi\u00f9 piccoli ci vedremo, tanto pi\u00f9 grande apparir\u00e0 Lui, il nostro Creatore e Redentore, l&#8217;unico vero Salvatore.<\/p>\n<p>Questo canto \u00e8 cos\u00ec bello che la Liturgia delle Ore ci invita a pregarlo ogni giorno all&#8217;imbrunire. Quanto bene fa all&#8217;anima nostra fare nostre le parole pi\u00f9 belle della Vergine! Se li meditiamo con calma ci diranno sempre qualcosa di nuovo. Perch\u00e9 d&#8217;altronde eravamo presenti l\u00ec. Siamo quelle generazioni che riconoscono la Vergine Maria come benedetta tra tutte le donne. Ella allora ha parlato di noi a Dio, come continua a fare anche adesso in Cielo: gli dice cose belle di noi. E noi rispondiamo venerandola come la beata di Dio, nostra Madre, Maria: \u00abBenedetta tu fra tutte le donne, e benedetto \u00e8 il frutto del tuo seno, Ges\u00f9\u00bb (Preghiera dell&#8217;Ave Maria).<\/p>\n<p>Rinnoviamo l&#8217;intento di ripetere quante pi\u00f9 volte possibile, ogni giorno, questa eco del Magnificat. La Vergine ci sorrider\u00e0 dal Cielo. E un&#8217;altra cosa: se confidiamo in Dio, Lui non ci deluder\u00e0: Lui \u00e8 fedele e mantiene sempre le sue promesse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ripetere l&#8217;eco del &#8216;Magnificat&#8217;<\/p>\n","protected":false},"author":40,"featured_media":102021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[73,95],"tags":[17617,6083,17619,17620,17622,17624,17623,17048,669,17628,17621,17626,17627,17629,17618,17630,17631,17632,17633,17634,1862,960,17625,819,402,9837,17635,17636],"class_list":["post-102020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa-e-mondo","category-spiritualita","tag-ain-karem-2","tag-bioetica-it","tag-d-jose-antonio-senovilla-2","tag-devozione-mariana","tag-fede-cristiana","tag-festa-cristiana","tag-festa-della-visita-della-vergine","tag-festa-religiosa","tag-gesu","tag-giovanni-battista","tag-incontro-familiare","tag-ispirazione-artistica","tag-jose-antonio-senovilla-2","tag-liturgia-delle-ore","tag-lode-a-dio","tag-magnificat-2","tag-mese-di-maggio","tag-misteri-del-rosario","tag-preghiera-del-magnificat","tag-riflessione-spirituale","tag-rosario","tag-spirito-santo","tag-storia-della-musica","tag-terra-santa","tag-tierra-santa-it","tag-vergine-maria","tag-visita-della-vergine","tag-zacaria-ed-elisabetta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festa della Visitazione della Vergine &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festa della Visitazione della Vergine &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Ripetere l&#039;eco del &#039;Magnificat&#039;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-31T21:57:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1155\" \/>\n\t<meta property=\"og:image:height\" content=\"770\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jos\u00e9 Antonio Senovilla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos\u00e9 Antonio Senovilla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/\"},\"author\":{\"name\":\"Jos\u00e9 Antonio Senovilla\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/a73453d91de9e04fe2489c961537fbe8\"},\"headline\":\"Festa della Visitazione della Vergine\",\"datePublished\":\"2024-05-31T21:57:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/\"},\"wordCount\":904,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg\",\"keywords\":[\"AIN-KAREM\",\"Bio\u00e9tica\",\"D. JOS\u00c9 ANTONIO SENOVILLA\",\"DEVOZIONE MARIANA\",\"FEDE CRISTIANA\",\"FESTA CRISTIANA\",\"FESTA DELLA VISITA DELLA VERGINE\",\"festa religiosa\",\"Ges\u00f9\",\"GIOVANNI BATTISTA\",\"INCONTRO FAMILIARE\",\"ISPIRAZIONE ARTISTICA\",\"JOS\u00c9 ANTONIO SENOVILLA\",\"LITURGIA DELLE ORE\",\"LODE A DIO\",\"MAGNIFICAT\",\"MESE DI MAGGIO\",\"MISTERI DEL ROSARIO\",\"PREGHIERA DEL MAGNIFICAT\",\"RIFLESSIONE SPIRITUALE\",\"Rosario\",\"Spirito Santo\",\"STORIA DELLA MUSICA\",\"Terra Santa\",\"Tierra Santa\",\"VERGINE MARIA\",\"VISITA DELLA VERGINE\",\"ZACAR\u00cdA ED ELISABETTA\"],\"articleSection\":[\"Chiesa e Mondo\",\"Spiritualit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/\",\"name\":\"Festa della Visitazione della Vergine &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg\",\"datePublished\":\"2024-05-31T21:57:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/a73453d91de9e04fe2489c961537fbe8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg\",\"width\":1155,\"height\":770},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/festa-della-visitazione-della-vergine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festa della Visitazione della Vergine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/a73453d91de9e04fe2489c961537fbe8\",\"name\":\"Jos\u00e9 Antonio Senovilla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee98463f208ee5720dc372a562e672d4dd2c1c5d7026e2751206af0658fdd6e1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee98463f208ee5720dc372a562e672d4dd2c1c5d7026e2751206af0658fdd6e1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee98463f208ee5720dc372a562e672d4dd2c1c5d7026e2751206af0658fdd6e1?s=96&d=mm&r=g\",\"caption\":\"Jos\u00e9 Antonio Senovilla\"},\"description\":\"Jos\u00e9 Antonio Senovilla Garc\u00eda naci\u00f3 en Ja\u00e9n y es licenciado de Derecho por la Universidad de Granada. Inici\u00f3 su ejercicio profesional en Almer\u00eda, donde trabaj\u00f3 en el \u00e1mbito de la empresa y la formaci\u00f3n de directivos. Volvi\u00f3 a Granada y, despu\u00e9s de unos a\u00f1os dedicados a tareas de formaci\u00f3n y direcci\u00f3n, complet\u00f3 sus estudios de Filosof\u00eda Eclesi\u00e1stica con una tesis doctoral sobre la Filiaci\u00f3n. Recibi\u00f3 en Roma la ordenaci\u00f3n sacerdotal de manos de Monse\u00f1or Javier Echevarr\u00eda y, tras un breve per\u00edodo de pr\u00e1cticas en pastorales en Sevilla, march\u00f3 a Rusia para ayudar all\u00ed en los comienzos de la labor estable del Opus Dei. Viaj\u00f3 tambi\u00e9n con frecuencia a Ucrania. Actualmente, colabora en el impulso de los apostolados de la Prelatura en la parte Oriental de Andaluc\u00eda\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/joseantiniosenovilla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festa della Visitazione della Vergine &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/","og_locale":"it_IT","og_type":"article","og_title":"Festa della Visitazione della Vergine &#8211; Exaudi","og_description":"Ripetere l'eco del 'Magnificat'","og_url":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2024-05-31T21:57:00+00:00","og_image":[{"width":1155,"height":770,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg","type":"image\/jpeg"}],"author":"Jos\u00e9 Antonio Senovilla","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Jos\u00e9 Antonio Senovilla","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/"},"author":{"name":"Jos\u00e9 Antonio Senovilla","@id":"https:\/\/exaudi.org\/#\/schema\/person\/a73453d91de9e04fe2489c961537fbe8"},"headline":"Festa della Visitazione della Vergine","datePublished":"2024-05-31T21:57:00+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/"},"wordCount":904,"commentCount":0,"image":{"@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg","keywords":["AIN-KAREM","Bio\u00e9tica","D. JOS\u00c9 ANTONIO SENOVILLA","DEVOZIONE MARIANA","FEDE CRISTIANA","FESTA CRISTIANA","FESTA DELLA VISITA DELLA VERGINE","festa religiosa","Ges\u00f9","GIOVANNI BATTISTA","INCONTRO FAMILIARE","ISPIRAZIONE ARTISTICA","JOS\u00c9 ANTONIO SENOVILLA","LITURGIA DELLE ORE","LODE A DIO","MAGNIFICAT","MESE DI MAGGIO","MISTERI DEL ROSARIO","PREGHIERA DEL MAGNIFICAT","RIFLESSIONE SPIRITUALE","Rosario","Spirito Santo","STORIA DELLA MUSICA","Terra Santa","Tierra Santa","VERGINE MARIA","VISITA DELLA VERGINE","ZACAR\u00cdA ED ELISABETTA"],"articleSection":["Chiesa e Mondo","Spiritualit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/","url":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/","name":"Festa della Visitazione della Vergine &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg","datePublished":"2024-05-31T21:57:00+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/a73453d91de9e04fe2489c961537fbe8"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg","width":1155,"height":770},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/festa-della-visitazione-della-vergine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"Festa della Visitazione della Vergine"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/a73453d91de9e04fe2489c961537fbe8","name":"Jos\u00e9 Antonio Senovilla","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ee98463f208ee5720dc372a562e672d4dd2c1c5d7026e2751206af0658fdd6e1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ee98463f208ee5720dc372a562e672d4dd2c1c5d7026e2751206af0658fdd6e1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee98463f208ee5720dc372a562e672d4dd2c1c5d7026e2751206af0658fdd6e1?s=96&d=mm&r=g","caption":"Jos\u00e9 Antonio Senovilla"},"description":"Jos\u00e9 Antonio Senovilla Garc\u00eda naci\u00f3 en Ja\u00e9n y es licenciado de Derecho por la Universidad de Granada. Inici\u00f3 su ejercicio profesional en Almer\u00eda, donde trabaj\u00f3 en el \u00e1mbito de la empresa y la formaci\u00f3n de directivos. Volvi\u00f3 a Granada y, despu\u00e9s de unos a\u00f1os dedicados a tareas de formaci\u00f3n y direcci\u00f3n, complet\u00f3 sus estudios de Filosof\u00eda Eclesi\u00e1stica con una tesis doctoral sobre la Filiaci\u00f3n. Recibi\u00f3 en Roma la ordenaci\u00f3n sacerdotal de manos de Monse\u00f1or Javier Echevarr\u00eda y, tras un breve per\u00edodo de pr\u00e1cticas en pastorales en Sevilla, march\u00f3 a Rusia para ayudar all\u00ed en los comienzos de la labor estable del Opus Dei. Viaj\u00f3 tambi\u00e9n con frecuencia a Ucrania. Actualmente, colabora en el impulso de los apostolados de la Prelatura en la parte Oriental de Andaluc\u00eda","url":"https:\/\/exaudi.org\/it\/author\/joseantiniosenovilla\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/Visitacion-de-la-Virgen-a-su-prima-Isabel-Cathopic.-Fiore-Bagatello-1155x770-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-qxu","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/102020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=102020"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/102020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/102021"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=102020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=102020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=102020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}