{"id":100204,"date":"2024-05-10T19:05:37","date_gmt":"2024-05-10T17:05:37","guid":{"rendered":"https:\/\/exaudi.org\/?p=100204"},"modified":"2024-05-11T19:17:14","modified_gmt":"2024-05-11T17:17:14","slug":"lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio","status":"publish","type":"post","link":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/","title":{"rendered":"&#8220;Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio&#8221;"},"content":{"rendered":"<p>Pubblichiamo di seguito il Discorso che il Santo Padre Francesco ha pronunciato Questo venerd\u00ec, 10 maggio, all\u2019Auditorium di Via della Conciliazione, in Roma, nel corso dei lavori della quarta edizione degli Stati Generali della Natalit\u00e0:<\/p>\n<h3><strong>Discorso del Santo Padre<\/strong><\/h3>\n<p><iframe loading=\"lazy\" title=\"10 May 2024 Auditorium Conciliazione &quot;General State of the Birth Rate&quot;- Pope Francis\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/UaFRYoHgQHU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><i>Distinte Autorit\u00e0,<br \/>\nRappresentanti della societ\u00e0 civile,<br \/>\ncari fratelli e sorelle, cari ragazzi e bambini, buongiorno!<\/i><\/p>\n<p>\u00c8 bello fare un applauso quando uno dice \u201cbuongiorno\u201d, perch\u00e9 tante volte non ci salutiamo. \u00c8 bello l\u2019applauso al \u201cbuongiorno\u201d.\u00a0E grazie a Gianluigi e a quanti lavorano per questa iniziativa. Sono contento di essere ancora con voi perch\u00e9, come sapete, il tema della natalit\u00e0 mi sta molto a cuore. Ogni dono di un figlio, infatti, ci ricorda che Dio ha fiducia nell\u2019umanit\u00e0, come sottolinea il motto \u201c<i>Esserci, pi\u00f9 giovani pi\u00f9 futuro<\/i>\u201d. Il nostro \u201cesserci\u201d non \u00e8 frutto del caso: Dio ci ha voluti, ha un progetto grande e unico su ciascuno di noi, nessuno escluso. In questa prospettiva, \u00e8 importante incontrarsi, lavorare insieme per promuovere la natalit\u00e0 con\u00a0<i>realismo<\/i>,\u00a0<i>lungimiranza<\/i>\u00a0e\u00a0<i>coraggio<\/i>. Vorrei riflettere un po\u2019 su queste tre parole-chiave.<\/p>\n<p>Prima:\u00a0<i>\u00a0realismo.<\/i>\u00a0In passato, non sono mancati studi e teorie che mettevano in guardia sul numero degli abitanti della Terra, perch\u00e9 la nascita di troppi bambini avrebbe creato squilibri economici, mancanza di risorse e inquinamento. Mi ha sempre colpito constatare come queste tesi, ormai datate e superate da tempo, parlassero di\u00a0<i>esseri umani<\/i>\u00a0come se si trattasse di\u00a0<i>problemi<\/i>. Ma la vita umana\u00a0<i>non \u00e8 un problema<\/i>, \u00e8\u00a0<i>un dono<\/i>. E alla base dell\u2019inquinamento e della fame nel mondo non ci sono i bambini che nascono, ma le scelte di chi pensa solo a s\u00e9 stesso, il delirio di un materialismo sfrenato, cieco e dilagante, di un consumismo che, come un virus malefico, intacca alla radice l\u2019esistenza delle persone e della societ\u00e0. Il problema non \u00e8\u00a0<i>in quanti siamo al mondo<\/i>, ma\u00a0<i>che mondo stiamo costruendo\u00a0<\/i>&#8211; questo \u00e8 il problema -; non sono i figli, ma l\u2019egoismo, che crea ingiustizie e strutture di peccato, fino a intrecciare malsane interdipendenze tra sistemi sociali, economici e politici.\u00a0<a class=\" cleaner\" href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/speeches\/2024\/may\/documents\/20240510-statigenerali-natalita.html#_ftn1\" name=\"_ftnref1\">[1]<\/a>\u00a0L\u2019egoismo rende sordi alla voce di Dio, che ama per primo e insegna ad amare, e alla voce dei fratelli che ci stanno accanto; anestetizza il cuore, fa vivere di cose, senza pi\u00f9 capire per cosa; induce ad avere tanti beni, senza pi\u00f9 saper fare il bene. E le case si riempiono di oggetti e si svuotano di figli, diventando luoghi molto tristi (cfr\u00a0<a href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/homilies\/2019\/documents\/papa-francesco_20191201_omelia-comunitacattolica-congolese.html\"><i>Omelia della<\/i>\u00a0<i>Messa per la comunit\u00e0 cattolica congolese<\/i><\/a>, 1\u00b0 dicembre 2019). Non mancano i cagnolini, i gatti\u2026, questi non mancano. Mancano i figli. Il problema del nostro mondo non sono i bambini che nascono: sono l\u2019egoismo, il consumismo e l\u2019individualismo, che rendono le persone sazie, sole e infelici.<\/p>\n<p>Il numero delle nascite \u00e8 il primo indicatore della speranza di un popolo. Senza bambini e giovani, un Paese perde il suo desiderio di futuro. In Italia, ad esempio, l\u2019et\u00e0 media attualmente \u00e8 di quarantasette anni \u2013 ma ci sono Paesi del centro Europa che hanno l\u2019et\u00e0 media si ventiquattro anni \u2013 e si continuano a segnare nuovi\u00a0<i>record<\/i>\u00a0negativi. Purtroppo, se dovessimo basarci su questo dato, saremmo costretti a dire che l\u2019Italia sta progressivamente perdendo la sua speranza nel domani, come il resto d\u2019Europa: il\u00a0<i>Vecchio Continente<\/i>\u00a0si trasforma sempre pi\u00f9 in un\u00a0<i>continente vecchio<\/i>, stanco e rassegnato, cos\u00ec impegnato ad esorcizzare le solitudini e le angosce da non saper pi\u00f9 gustare, nella\u00a0<i>civilt\u00e0 del dono<\/i>, la\u00a0<i>vera bellezza della vita<\/i>.\u00a0E c\u2019\u00e8 un dato che mi ha detto uno studioso di demografia. In questo momento gli investimenti che danno pi\u00f9 reddito sono la fabbrica di armi e gli anticoncezionali. Le une distruggono la vita, gli altri impediscono la vita. E questi sono gli investimenti che danno pi\u00f9 reddito. Che futuro ci attende? \u00c8 brutto.<\/p>\n<p>Nonostante tante parole e tanto impegno, non si arriva a invertire la rotta. Come mai? Perch\u00e9 non si riesce a frenare questa emorragia di vita?<\/p>\n<p>La questione \u00e8 complessa, ma questo non pu\u00f2 e non deve diventare un alibi per non affrontarla. Serve\u00a0<i>lungimiranza<\/i>, che \u00e8 la seconda parola-chiave. A livello istituzionale, urgono\u00a0<i>politiche efficaci, scelte coraggiose, concrete e di lungo termine<\/i>, per seminare oggi affinch\u00e9 i figli possano raccogliere domani. C\u2019\u00e8 bisogno di un impegno maggiore da parte di tutti i governi, perch\u00e9 le giovani generazioni vengano messe nelle condizioni di poter realizzare i propri legittimi sogni. Si tratta di attuare\u00a0<i>serie ed efficaci scelte in favore della famiglia<\/i>. Ad esempio, porre una madre nella condizione di non dover scegliere tra lavoro e cura dei figli; oppure liberare tante giovani coppie dalla zavorra della precariet\u00e0 occupazionale e dell\u2019impossibilit\u00e0 di acquistare una casa.<\/p>\n<p>\u00c8 poi importante promuovere, a livello sociale, una\u00a0<i>cultura della generosit\u00e0<\/i>\u00a0e\u00a0<i>della solidariet\u00e0 intergenerazionale<\/i>, per rivedere abitudini e stili di vita, rinunciando a ci\u00f2 che \u00e8 superfluo allo scopo di dare ai pi\u00f9 giovani una speranza per il domani, come avviene in tante famiglie. Non dimentichiamolo: il futuro di figli e nipoti si costruisce anche con le schiene doloranti per anni di fatica e con i sacrifici nascosti di genitori e nonni, nel cui abbraccio c\u2019\u00e8 il dono silenzioso e discreto del lavoro di una vita intera. E d\u2019altra parte, il riconoscimento e la gratitudine verso di loro da parte di chi cresce sono la sana risposta che, come l\u2019acqua unita al cemento, rende solida e forte la societ\u00e0. Questi sono i valori da sostenere, questa \u00e8 la cultura da diffondere, se vogliamo avere un domani.<\/p>\n<p>Terza parola:\u00a0<i>coraggio<\/i>. E qui mi rivolgo particolarmente ai giovani. So che per molti di voi il futuro pu\u00f2 apparire inquietante, e che tra denatalit\u00e0, guerre, pandemie e mutamenti climatici non \u00e8 facile mantenere viva la speranza. Ma non arrendetevi, abbiate fiducia, perch\u00e8 il domani non \u00e8 qualcosa di ineluttabile: lo costruiamo insieme, e in questo \u201cinsieme\u201d prima di tutto troviamo il Signore. \u00c8 Lui che, nel Vangelo, ci insegna quel \u201cma io vi dico\u201d che cambia le cose (cfr\u00a0<i>Mt<\/i>\u00a05,38-48): un \u201cma\u201d che profuma di salvezza, che prepara un \u201cfuori schema\u201d, una rottura. Facciamo nostro questo \u201cma\u201d, tutti, qui e ora. Non rassegniamoci a un copione gi\u00e0 scritto da altri, mettiamoci a remare per invertire la rotta, anche a costo di andare controcorrente! Come fanno le mamme e i pap\u00e0 della\u00a0<i>Fondazione per la Natalit\u00e0<\/i>, che ogni anno organizzano questo evento, questo \u201ccantiere di speranza\u201d che ci aiuta a pensare, e che cresce, coinvolgendo sempre pi\u00f9 il mondo della politica, delle imprese, delle banche, dello sport, dello spettacolo e del giornalismo.<\/p>\n<p>Ma il futuro non si costruisce solo facendo figli. Manca un\u2019altra parte molto importante: i nonni. Oggi c\u2019\u00e8 una cultura che nasconde i nonni, li manda alla casa di riposo. Adesso \u00e8 cambiata un po\u2019 per la pensione \u2013 purtoppo \u00e8 cos\u00ec \u2013, ma la tendenza \u00e8 quella: scartare i nonni. Mi viene in mente una storia interessante. C\u2019era una bella famiglia, dove il nonno viveva con loro. Ma con il tempo in nonno \u00e8 invecchiato, e poi quando mangiava si sporcava\u2026 Allora il pap\u00e0 ha fatto costruire un tavolino, in cucina, perch\u00e9 ci mangiasse il nonno, cos\u00ec loro potevano invitare gente. Un giorno il pap\u00e0 torna a casa e trova uno dei bambini piccoli che lavorava con il legno. \u201cCosa stai facendo?\u201d \u2013 \u201cUn tavolino, pap\u00e0\u201d \u2013 \u201cMa perch\u00e9?\u201d- \u201cPer te, per quando sarai vecchio\u201d. Per favore, non dimenticare i nonni! Quando io, nell\u2019altra diocesi, visitavo tanto le case di riposo, domandavo ai nonni \u2013 penso a un caso \u2013: \u201cQuanti figli ha?\u201d &#8211; \u201cTanti\u201d &#8211; \u201cAh, bene. E vengono a trovarla?\u201d &#8211; \u201cS\u00ec s\u00ec, vengono sempre\u201d. Poi, all\u2019uscita, l\u2019infermiere mi diceva: \u201cNon vengono mai\u201d. I nonni soli. I nonni scartati. Questo \u00e8 un suicidio culturale! Il futuro lo fanno i giovani e i vecchi insieme; il coraggio e la memoria, insieme. Per favore, parlando di natalit\u00e0, che \u00e8 il futuro, parliamo anche dei nonni, che non sono il passato: aiutano il futuro. Per favore, abbiamo figli, tanti, ma abbiamo anche cura dei nonni! \u00c8 molto importante.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-100208 alignleft\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-300x200.jpeg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-770x513.jpeg 770w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-360x240.jpeg?crop=1 360w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-500x333.jpeg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-370x247.jpeg 370w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-293x195.jpeg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-120x80.jpeg 120w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-240x160.jpeg 240w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8-390x260.jpeg 390w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-8.jpeg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Cari amici, vi ringrazio per quello che fate, grazie a tutti voi. Grazie a te per il tuo coraggio. Vi sono vicino e vi accompagno con la mia preghiera. E per favore, vi chiedo di non dimenticarvi di pregare per me. Ma pregate a favore, non contro! Grazie.<\/p>\n<p>Questo \u201ca favore e non contro\u201d lo dico perch\u00e9 una volta, stavo finendo un\u2019udienza e l\u00ec a venti metri c\u2019era una signora, una vecchietta, piccolina, occhi bellissimi. Ha cominciato a dire: \u201cVieni, vieni!\u201d. Simpatica. Mi sono avvicinato: \u201cSignora come si chiama?\u201d \u2013 mi ha detto il nome \u2013 \u201cE quanti anni ha?\u201d \u2013 \u201c87\u201d \u2013 \u201cMa cosa fa, cosa mangia per essere cos\u00ec forte?\u201d \u2013 \u201cMangio i ravioli, li faccio io\u201d. E mi ha dato la ricetta dei ravioli. E poi le ho detto: \u201cSignora, per favore, preghi per me\u201d \u2013 \u201cLo faccio tutti i giorni\u201d. E io per scherzare le dissi: \u201cMa preghi a favore, non contro!\u201d. E la vecchietta, sorridendo, mi disse: \u201cStia attento, Padre! Contro pregano l\u00ec dentro\u201d. Furba! Un po\u2019 anticlericale. E per favore: a favore, non contro, a favore.<\/p>\n<p>____________________________<\/p>\n<p><a class=\" cleaner\" href=\"https:\/\/www.vatican.va\/content\/francesco\/it\/speeches\/2024\/may\/documents\/20240510-statigenerali-natalita.html#_ftnref1\" name=\"_ftn1\">[1]<\/a>\u00a0cfr S. Giovanni Paolo II, Lett. enc.\u00a0\u00a0<i><a href=\"https:\/\/www.vatican.va\/content\/john-paul-ii\/it\/encyclicals\/documents\/hf_jp-ii_enc_30121987_sollicitudo-rei-socialis.html\">Sollicitudo rei socialis<\/a><\/i>\u00a0(1987), 36-37;\u00a0\u00a0<i><a href=\"https:\/\/www.vatican.va\/archive\/catechism_it\/p3s1c1a8_it.htm#V.%20La%20proliferazione%20del%20peccato\">Catechismo della Chiesa Cattolica<\/a><\/i>, n. 1869.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Discorso del Santo Padre Francesco ai partecipanti alla quarta edizione degli Stati Generali della Natalit\u00e0<\/p>\n","protected":false},"author":17,"featured_media":100205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[123,67],"tags":[251,4952,579],"class_list":["post-100204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-discorsi","category-leone-xiv","tag-papa-francesco","tag-trending-it","tag-udienza-generale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio&quot; &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio&quot; &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Discorso del Santo Padre Francesco ai partecipanti alla quarta edizione degli Stati Generali della Natalit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNotizie\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-10T17:05:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-11T17:17:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-1-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_Notizie\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/\"},\"author\":{\"name\":\"Exaudi Redazione\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"headline\":\"&#8220;Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio&#8221;\",\"datePublished\":\"2024-05-10T17:05:37+00:00\",\"dateModified\":\"2024-05-11T17:17:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/\"},\"wordCount\":1525,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cq5dam.web_.800.800-1-2.jpeg\",\"keywords\":[\"Papa Francesco\",\"Trending\",\"udienza generale\"],\"articleSection\":[\"Discorsi\",\"Leone XIV\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/\",\"name\":\"\\\"Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio\\\" &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cq5dam.web_.800.800-1-2.jpeg\",\"datePublished\":\"2024-05-10T17:05:37+00:00\",\"dateModified\":\"2024-05-11T17:17:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cq5dam.web_.800.800-1-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cq5dam.web_.800.800-1-2.jpeg\",\"width\":800,\"height\":533,\"caption\":\"Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/it\\\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/e1ab6ed07c01774724dd96f925f3a5f0\",\"name\":\"Exaudi Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redazione\"},\"description\":\"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\\\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNotizie\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Exaudi_notizie\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_Notizie\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/it\\\/author\\\/dlvedi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio\" &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/","og_locale":"it_IT","og_type":"article","og_title":"\"Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio\" &#8211; Exaudi","og_description":"Discorso del Santo Padre Francesco ai partecipanti alla quarta edizione degli Stati Generali della Natalit\u00e0","og_url":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNotizie\/","article_published_time":"2024-05-10T17:05:37+00:00","article_modified_time":"2024-05-11T17:17:14+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-1-2.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redazione","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_Notizie","twitter_site":"@Exaudi_News","twitter_misc":{"Scritto da":"Exaudi Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/"},"author":{"name":"Exaudi Redazione","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"headline":"&#8220;Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio&#8221;","datePublished":"2024-05-10T17:05:37+00:00","dateModified":"2024-05-11T17:17:14+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/"},"wordCount":1525,"image":{"@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-1-2.jpeg","keywords":["Papa Francesco","Trending","udienza generale"],"articleSection":["Discorsi","Leone XIV"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/","url":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/","name":"\"Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio\" &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-1-2.jpeg","datePublished":"2024-05-10T17:05:37+00:00","dateModified":"2024-05-11T17:17:14+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-1-2.jpeg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-1-2.jpeg","width":800,"height":533,"caption":"Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/it\/lavoriamo-insieme-per-promuovere-la-nascita-con-realismo-lungimiranza-e-coraggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/it\/"},{"@type":"ListItem","position":2,"name":"&#8220;Lavoriamo insieme per promuovere la nascita con realismo, lungimiranza e coraggio&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/e1ab6ed07c01774724dd96f925f3a5f0","name":"Exaudi Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad6774b3ada023bf5b939d64f45c94b3adf91502dd883507d469b4308a943bb3?s=96&d=mm&r=g","caption":"Exaudi Redazione"},"description":"Che cosa \u00e8 Exaudi News? Exaudi News \u00e8 un agenzia cattolica internazionale che informa, istruisce e trasforma quotidianamente in spagnolo, inglese e italiano. Attraverso notizie, articoli di analisi e trasmissioni in diretta degli eventi del Papa, Exaudi cerca di rafforzare l'unit\u00e0 dei cristiani e di contribuire all'evangelizzazione del mondo, sempre guidato dalla dottrina sociale della Chiesa. Lavoriamo per portare la verit\u00e0 e i valori cristiani in ogni angolo del pianeta. Aiutaci a trasformare il mondo con Exaudi! Noi di Exaudi crediamo che l'evangelizzazione e l'informazione di qualit\u00e0 possano cambiare la vita. Per continuare la nostra missione ed espandere la nostra portata, abbiamo bisogno del tuo aiuto. Stiamo anche cercando persone motivate che vogliano unirsi al nostro team. Grazie al vostro sostegno raggiungeremo pi\u00f9 persone, diffonderemo il messaggio di Cristo e rafforzeremo l'unit\u00e0 dei cristiani. Vuoi unirti alla nostra missione? Per maggiori informazioni su come contribuire, visita Exaudi.org\/it o contattaci direttamente: info@exaudi.org Exaudi: informa, forma e trasforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNotizie\/","https:\/\/www.instagram.com\/Exaudi_notizie\/","https:\/\/x.com\/Exaudi_Notizie","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/it\/author\/dlvedi-org\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/05\/cq5dam.web_.800.800-1-2.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-q4c","_links":{"self":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/100204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/comments?post=100204"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/posts\/100204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media\/100205"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/media?parent=100204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/categories?post=100204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/it\/wp-json\/wp\/v2\/tags?post=100204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}