{"id":83773,"date":"2023-09-18T09:08:54","date_gmt":"2023-09-18T07:08:54","guid":{"rendered":"https:\/\/exaudi.org\/?p=83773"},"modified":"2023-09-18T09:35:30","modified_gmt":"2023-09-18T07:35:30","slug":"redescubrir-el-matrimonio","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/","title":{"rendered":"Redescubrir el matrimonio"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-83773-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/ttsmaker-file-2023-9-18-9-4-53.mp3?_=1\" \/><a href=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/ttsmaker-file-2023-9-18-9-4-53.mp3\">https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/ttsmaker-file-2023-9-18-9-4-53.mp3<\/a><\/audio>\n<p>El <a href=\"https:\/\/exaudi.org\/es\/author\/dr-salvador-fabre\/\" target=\"_blank\" rel=\"noopener\">Dr. Salvador Fabre<\/a>, comparte con los lectores de Exaudi su art\u00edculo semanal titulado \u201cRedescubrir el matrimonio\u201d.<\/p>\n<p><strong>***<\/strong><\/p>\n<ul>\n<li>\u201cProfe, para m\u00ed, el matrimonio como lo entiende la Iglesia es una suerte de cadena perpetua.\u201d<\/li>\n<li>\u201cSi equivocarse forma parte de la condici\u00f3n humana y rectificar es una muestra de sabidur\u00eda, \u00bfpor qu\u00e9 no aplica esto para el matrimonio seg\u00fan la Iglesia?\u201d<\/li>\n<li>\u201cS\u00f3lo de pensar que voy a tener que estar <em>toooda<\/em> la vida con una persona me da agobio, me asfixia.\u201d<\/li>\n<\/ul>\n<p>Nuevamente el tema del matrimonio generaba conflicto, especialmente en mis alumnas. Anta\u00f1o lo que era dif\u00edcil de comprender era la opci\u00f3n del celibato por el reino de los cielos, m\u00e1xime cuando ese celibato no iba unido a la ordenaci\u00f3n sacerdotal. Para muchos el celibato laical representaba una especie de \u201ccirculo cuadrado\u201d, es decir, un ox\u00edmoron, un absurdo. Otros muchos cuestionaban el celibato sacerdotal, se\u00f1alando que era causa de desviaciones sexuales graves, como la pedofilia. Pero ahora, el frente de batalla -por decirlo de alguna manera- se ha replegado al matrimonio. Ya no se ve la opci\u00f3n matrimonial y el proyecto de crear una familia como una forma v\u00e1lida de realizaci\u00f3n personal o, por lo menos, no todos lo ven con claridad, sospecho que la mayor\u00eda de los j\u00f3venes no lo ven as\u00ed, y tienen sus propios planes alternativos.<\/p>\n<p>Al escuchar los alegatos de algunas de mis alumnas, resonaban en mi mente las palabras de <em>Mateo<\/em> 19,10: \u201cSi tal es la condici\u00f3n del hombre respecto de su mujer, no viene a cuento casarse.\u201d Sin embargo, tal vers\u00edculo se habr\u00eda modificado, conforme al esp\u00edritu de los tiempos; ahora dir\u00eda: \u201cSi tal es la condici\u00f3n de la mujer respecto al var\u00f3n, no viene a cuento casarse.\u201d La grave crisis que ha sufrido el matrimonio y con \u00e9l la familia, en tiempos recientes, inevitablemente ha pasado factura. El matrimonio y la familia se han desconfigurado como ideales de vida para un n\u00famero consistente de personas. Se trata, si se mira agudamente, de un fracaso antropol\u00f3gico: no se concibe que la persona humana pueda adquirir compromisos para toda la vida; su voluntad no llega a tanto, su libertad no alcanza tal extremo. En el fondo, se trata de un empobrecimiento del amor, pues ya no ser\u00eda de recibo la afirmaci\u00f3n b\u00edblica seg\u00fan la cual \u201cfuerte como la muerte es el amor\u201d (<em>Cantar de los cantares<\/em> 8, 6). Por el contrario, el amor, y con \u00e9l la libertad, no resisten la erosi\u00f3n del tiempo.<\/p>\n<p>M\u00e1s incluso, ahora se considerar\u00eda nocivo para la salud mental intentar mantener el compromiso, la palabra dada, a cualquier precio. Tal actitud encerrar\u00eda vestigios de irracionalidad, fanatismo, cerrilidad. El fr\u00edo realismo de la condici\u00f3n humana muestra, por el contrario, que cuando algo deja de funcionar, lo l\u00f3gico, lo natural, es abandonarlo. As\u00ed, sin ambages ni maquillajes, lo reconoc\u00eda una alumna: \u201cYo pienso estar con una persona mientras las cosas funcionen. Cuando, eventualmente, dejen de funcionar, dejar\u00e9 de estar con ella, pues no soy capaz de violentar la realidad. Tengo que aceptar las cosas como son, no como me gustar\u00eda que fueran.\u201d Una especie de \u201crealismo\u201d se difunde como epidemia, de forma que los ideales se consideran eso: enso\u00f1aciones, fantas\u00edas, buenos deseos vacuos. La cruel experiencia de la condici\u00f3n humana nos muestra que el hombre, en l\u00edneas generales, no est\u00e1 a la altura de sus ideales y, por ello, es mejor dejarlos de lado.<\/p>\n<p>Las m\u00faltiples experiencias de matrimonios altamente conflictivos, ha pasado su factura a las nuevas generaciones. Con frecuencia escucho c\u00f3mo son los hijos los que aconsejan separarse a sus padres, para evitar el triste espect\u00e1culo de las continuas disputas. Digamos que los hijos, ante el fracaso matrimonial de sus padres, se \u201chan curado en salud.\u201d<\/p>\n<p>Por eso el cristianismo, una vez m\u00e1s y en un frente nuevo, debe ir contracorriente. La tentaci\u00f3n de ceder a pesimismos realistas es grande y las estad\u00edsticas no ayudan, pues confirman el debilitamiento de la instituci\u00f3n matrimonial. Ahora, para lanzarse a formar una familia abierta a la vida se necesita ser revolucionario, inconformista, idealista. No se parte de una ingenua confianza en los alcances de nuestra libertad, sino que se cimenta la vida desde la confianza en Dios. Aqu\u00ed la fe juega un papel insustituible. A final de cuentas, \u00bfpor qu\u00e9 pensamos los cat\u00f3licos que el matrimonio cristiano compromete toda nuestra vida? Porque Jes\u00fas mismo lo dijo expresamente (Cfr. <em>Mateo<\/em> 19, 3-6). Confiados en esa Palabra y no en nuestras precarias fuerzas, nos lanzamos a esa aventura, que da fruto, de forma que saca lo mejor de nosotros mismos, y se convierte, hoy m\u00e1s que nunca, en una silenciosa pero elocuente catequesis para la sociedad. Redescubrimos as\u00ed, admirados, c\u00f3mo la libertad y el amor son m\u00e1s fuertes que el tiempo, y tambi\u00e9n c\u00f3mo el ideal cristiano eleva al ser humano.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-83784 aligncenter\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2.jpg\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2.jpg 1080w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2-300x300.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2-1024x1024.jpg 1024w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2-100x100.jpg?crop=1 100w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2-770x770.jpg 770w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2-500x500.jpg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2-293x293.jpg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2-390x390.jpg 390w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2-585x585.jpg 585w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Copia-de-Voces-2-2-900x900.jpg 900w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para lanzarse a formar una familia abierta a la vida se necesita ser revolucionario, inconformista, idealista<\/p>\n","protected":false},"author":116,"featured_media":83781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[130],"tags":[2618,10087,4953],"class_list":["post-83773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-matrimonio-es","tag-salvador-fabre","tag-trending-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Redescubrir el matrimonio &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Redescubrir el matrimonio &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Para lanzarse a formar una familia abierta a la vida se necesita ser revolucionario, inconformista, idealista\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-18T07:08:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-18T07:35:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/pexels-megapixelstock-17834-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salvador Fabre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salvador Fabre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/\"},\"author\":{\"name\":\"Salvador Fabre\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/29b1dbd9f3952eecacfc704ca1a473a8\"},\"headline\":\"Redescubrir el matrimonio\",\"datePublished\":\"2023-09-18T07:08:54+00:00\",\"dateModified\":\"2023-09-18T07:35:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/\"},\"wordCount\":865,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/pexels-megapixelstock-17834-scaled.jpg\",\"keywords\":[\"matrimonio\",\"salvador fabre\",\"Trending\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/\",\"name\":\"Redescubrir el matrimonio &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/pexels-megapixelstock-17834-scaled.jpg\",\"datePublished\":\"2023-09-18T07:08:54+00:00\",\"dateModified\":\"2023-09-18T07:35:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/29b1dbd9f3952eecacfc704ca1a473a8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/pexels-megapixelstock-17834-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/pexels-megapixelstock-17834-scaled.jpg\",\"width\":2560,\"height\":1349},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/redescubrir-el-matrimonio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Redescubrir el matrimonio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/29b1dbd9f3952eecacfc704ca1a473a8\",\"name\":\"Salvador Fabre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1a5a78ba86b9a8255e1c5b454943b9168b1dc31a275487309b73b631a7ac5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1a5a78ba86b9a8255e1c5b454943b9168b1dc31a275487309b73b631a7ac5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1a5a78ba86b9a8255e1c5b454943b9168b1dc31a275487309b73b631a7ac5d?s=96&d=mm&r=g\",\"caption\":\"Salvador Fabre\"},\"description\":\"Doctor en filosof\u00eda - Pensar en Cristiano\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/dr-salvador-fabre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Redescubrir el matrimonio &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/","og_locale":"es_ES","og_type":"article","og_title":"Redescubrir el matrimonio &#8211; Exaudi","og_description":"Para lanzarse a formar una familia abierta a la vida se necesita ser revolucionario, inconformista, idealista","og_url":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2023-09-18T07:08:54+00:00","article_modified_time":"2023-09-18T07:35:30+00:00","og_image":[{"width":2560,"height":1349,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/pexels-megapixelstock-17834-scaled.jpg","type":"image\/jpeg"}],"author":"Salvador Fabre","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Salvador Fabre","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/"},"author":{"name":"Salvador Fabre","@id":"https:\/\/exaudi.org\/#\/schema\/person\/29b1dbd9f3952eecacfc704ca1a473a8"},"headline":"Redescubrir el matrimonio","datePublished":"2023-09-18T07:08:54+00:00","dateModified":"2023-09-18T07:35:30+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/"},"wordCount":865,"image":{"@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/pexels-megapixelstock-17834-scaled.jpg","keywords":["matrimonio","salvador fabre","Trending"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/","url":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/","name":"Redescubrir el matrimonio &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/pexels-megapixelstock-17834-scaled.jpg","datePublished":"2023-09-18T07:08:54+00:00","dateModified":"2023-09-18T07:35:30+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/29b1dbd9f3952eecacfc704ca1a473a8"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/pexels-megapixelstock-17834-scaled.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/pexels-megapixelstock-17834-scaled.jpg","width":2560,"height":1349},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/redescubrir-el-matrimonio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Redescubrir el matrimonio"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/29b1dbd9f3952eecacfc704ca1a473a8","name":"Salvador Fabre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8d1a5a78ba86b9a8255e1c5b454943b9168b1dc31a275487309b73b631a7ac5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d1a5a78ba86b9a8255e1c5b454943b9168b1dc31a275487309b73b631a7ac5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d1a5a78ba86b9a8255e1c5b454943b9168b1dc31a275487309b73b631a7ac5d?s=96&d=mm&r=g","caption":"Salvador Fabre"},"description":"Doctor en filosof\u00eda - Pensar en Cristiano","url":"https:\/\/exaudi.org\/es\/author\/dr-salvador-fabre\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/pexels-megapixelstock-17834-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-lNb","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/83773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/116"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=83773"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/83773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/83781"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=83773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=83773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=83773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}