{"id":83611,"date":"2023-09-15T12:33:25","date_gmt":"2023-09-15T10:33:25","guid":{"rendered":"https:\/\/exaudi.org\/?p=83611"},"modified":"2023-09-15T12:43:55","modified_gmt":"2023-09-15T10:43:55","slug":"el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/","title":{"rendered":"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-83611-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Hakuna.mp3?_=1\" \/><a href=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Hakuna.mp3\">https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/Hakuna.mp3<\/a><\/audio>\n<p>El Papa Francisco mantuvo una audiencia privada el 11 de septiembre con el sacerdote Jos\u00e9 Pedro Manglano, fundador de Hakuna, una iniciativa que se origin\u00f3 en Espa\u00f1a pero que ha trascendido fronteras para llevar a cabo diversas actividades como Horas Santas, escapadas, retiros y formaci\u00f3n en varios pa\u00edses. A trav\u00e9s de su proyecto Hakuna Group Music, esta comunidad dej\u00f3 una huella significativa en la Jornada Mundial de la Juventud en Lisboa, Portugal, con un grupo musical compuesto por j\u00f3venes que utilizan su pasi\u00f3n por la m\u00fasica para compartir una verdad que resuena profundamente en sus corazones y que desean transmitir al mundo.<\/p>\n<p>Durante unos 30 minutos, el <strong>Papa\u00a0Francisco<\/strong>\u00a0pudo conversar en audiencia privada con\u00a0<strong>Jos\u00e9 Pedro Manglano<\/strong>,\u00a0el sacerdote iniciador de Hakuna que acudi\u00f3 este 11 de septiembre a su primera reuni\u00f3n con Francisco en el Vaticano. Durante la charla, pudieron profundizar en los 25 \u201ccompartiriados\u201d, as\u00ed denominan a los proyectos de\u00a0<a href=\"https:\/\/linktr.ee\/BeHakuna\" target=\"_blank\" rel=\"noopener\" data-mrf-link=\"https:\/\/linktr.ee\/BeHakuna\"><strong>Acci\u00f3n Social de Hakuna que realizan por todo el mundo y del d\u00e9cimo aniversario del movimiento.<\/strong><\/a><\/p>\n<p>El Papa Francisco tambi\u00e9n<strong> pudo saludar a los de acompa\u00f1antes y miembros de Hakuna.<\/strong><\/p>\n<h3><strong>No aflojen<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-83615\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640.jpg\" alt=\"\" width=\"540\" height=\"360\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640.jpg 540w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640-300x200.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640-360x240.jpg?crop=1 360w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640-500x333.jpg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640-370x247.jpg 370w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640-293x195.jpg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640-120x80.jpg 120w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640-240x160.jpg 240w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/150088_papa_francisco_manglano_2023_640-390x260.jpg 390w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>No es la primera vez que el Papa felicita \u201cla creatividad del grupo\u201d y pide que \u201cno aflojen\u201d. En este primer encuentro, que coincide con el d\u00e9cimo aniversario de Hakuna, han podido hablar de la presencia del movimiento en m\u00e1s de 30 pa\u00edses por todo el mundo (desde Per\u00fa a Corea del Sur, pasando por Estados Unidos, gran parte de Europa, e incluso El Congo) <strong>as\u00ed como de su labor social.<\/strong> Tal y como expresaron desde la propia realidad a trav\u00e9s de una nota de prensa, \u201cel Santo Padre nos ha animado a seguir cuidando especialmente a los obispos de las\u00a0<a href=\"https:\/\/linktr.ee\/BeHakuna\" target=\"_blank\" rel=\"noopener\" data-mrf-link=\"https:\/\/linktr.ee\/BeHakuna\">di\u00f3cesis en las que est\u00e1 presente Hakuna y ha bendecido la misi\u00f3n que hace por todo el mundo\u201d.<\/a><\/p>\n<p>En el encuentro Manglano, tambi\u00e9n pudo presentar el libro que expone el esp\u00edritu del compartiriado \u201cRedescubriendo la verdad en la pobreza: dej\u00e9monos del buenismo y aprendamos de los pobres\u201d,<strong>\u00a0en el que se detallan los m\u00e1s de 20 proyectos de Acci\u00f3n Social que se realizan en Hakuna, <\/strong>un \u00e1lbum de fotos de los diez a\u00f1os, y un disco en edici\u00f3n especial que recopila canciones de los 5 discos que ha publicado Hakuna Group Music.<\/p>\n<h3><strong>\u201cHAM\u201d, (Hakuna All Meeting)<\/strong><\/h3>\n<p>Tras el encuentro, el grupo pudo hablar con el p\u00e1rroco de San Pedro, Fray Agnelo, de cara a las pr\u00f3ximas\u00a0<a href=\"https:\/\/linktr.ee\/BeHakuna\" target=\"_blank\" rel=\"noopener\" data-mrf-link=\"https:\/\/linktr.ee\/BeHakuna\"><em><strong>\u201cHAM\u201d, (Hakuna All Meeting)<\/strong><\/em><\/a>\u00a0que se celebrar\u00e1n del 11 al 15 de octubre en la capital italiana.\u00a0El pasado a\u00f1o, el lait motiv fue \u201cFratelli Tutti\u201d y este a\u00f1o se centra en el carisma y la m\u00fasica. Contar\u00e1n con la presencia de distintos movimientos, congregaciones y comunidades Poner ejemplos de los invitados (Taize, Camino Neocatecumenal, Renovaci\u00f3n Carism\u00e1tica, Hermanitas del Cordero\u2026) en los que la m\u00fasica tambi\u00e9n forma parte del carisma para compartir experiencias, rezar y disfrutar juntos.<\/p>\n<h3><strong>Hakuna: Cristianos juntos seguimos a Cristo<\/strong><\/h3>\n<p>El Papa Francisco ha descrito a Hakuna como \u00abuna familia eucar\u00edstica que surgi\u00f3 en R\u00edo de Janeiro durante la Jornada Mundial de la Juventud de 2013\u00bb. Esta comunidad de cristianos comparte un estilo de vida que se fundamenta en la adoraci\u00f3n a Cristo en la Eucarist\u00eda, y a partir de esa relaci\u00f3n con \u00c9l, aprenden a vivir con humildad frente a sus semejantes, ante la vida y en el contexto global.<\/p>\n<p>En sus propias palabras, Hakuna explica: \u00ab<em>Creamos espacios donde transmitimos la Vida. Disfrutamos de todo, incluso de lo que el mundo puede despreciar, porque vemos la bondad en todas las cosas, y a trav\u00e9s de esta perspectiva glorificamos a Dios. Nuestro compromiso es colaborar con el Esp\u00edritu Santo para transformar todas las realidades que encontramos. Anhelamos llevar siempre una expresi\u00f3n de alegr\u00eda en nuestros rostros, como aquellos que han resucitado. Nuestra misi\u00f3n es convertir la vida en una fiesta, y los momentos festivos en ocasiones de vida<\/em>\u00ab. Estas son sus palabras, tal como se presentan en su p\u00e1gina web.<\/p>\n<p>Hakuna, por tanto, representa una comunidad de cristianos que, inspirados por su fe y la Eucarist\u00eda, se esfuerzan por vivir una vida plena y alegre mientras comparten su mensaje de amor y esperanza con el mundo.<\/p>\n<blockquote><p><em>\u00abNos expresamos habitualmente con m\u00fasica: vivimos lo que cantamos y cantamos lo que vivimos. Tambi\u00e9n con m\u00fasica queremos recordar al mundo la belleza de la vida, y mostrarles la belleza de Cristo\u00bb.<\/em><\/p><\/blockquote>\n<p>Jur\u00eddicamente, Hakuna es una Asociaci\u00f3n privada de fieles, aprobada por el cardenal arzobispo em\u00e9rito de Madrid,<strong>\u00a0Carlos Osoro<\/strong>. El C\u00f3digo de Derecho Can\u00f3nico contempla las Asociaciones de fieles p\u00fablicas y privadas.<strong>\u00a0Las Asociaciones privadas de fieles son las que promueven los fieles, y las Asociaciones p\u00fablicas de Fieles que son las que promueve y erige la Jerarqu\u00eda Eclesi\u00e1stica.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristianos juntos seguimos a Cristo<\/p>\n","protected":false},"author":15,"featured_media":83612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[74,68,132],"tags":[2065,2067,158,4953],"class_list":["post-83611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iglesia-y-mundo","category-leon-xiv","category-vaticano-es","tag-hakuna","tag-jose-pedro-manglano","tag-papa-francisco","tag-trending-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Cristianos juntos seguimos a Cristo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-15T10:33:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-15T10:43:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/1694513293116.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna\",\"datePublished\":\"2023-09-15T10:33:25+00:00\",\"dateModified\":\"2023-09-15T10:43:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/\"},\"wordCount\":854,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1694513293116.jpg\",\"keywords\":[\"Hakuna\",\"Jos\u00e9 Pedro Manglano\",\"papa francisco\",\"Trending\"],\"articleSection\":[\"Iglesia y Mundo\",\"Le\u00f3n XIV\",\"Vaticano\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/\",\"name\":\"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1694513293116.jpg\",\"datePublished\":\"2023-09-15T10:33:25+00:00\",\"dateModified\":\"2023-09-15T10:43:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1694513293116.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1694513293116.jpg\",\"width\":976,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/","og_locale":"es_ES","og_type":"article","og_title":"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna &#8211; Exaudi","og_description":"Cristianos juntos seguimos a Cristo","og_url":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2023-09-15T10:33:25+00:00","article_modified_time":"2023-09-15T10:43:55+00:00","og_image":[{"width":976,"height":650,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/1694513293116.jpg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna","datePublished":"2023-09-15T10:33:25+00:00","dateModified":"2023-09-15T10:43:55+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/"},"wordCount":854,"image":{"@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/1694513293116.jpg","keywords":["Hakuna","Jos\u00e9 Pedro Manglano","papa francisco","Trending"],"articleSection":["Iglesia y Mundo","Le\u00f3n XIV","Vaticano"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/","url":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/","name":"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/1694513293116.jpg","datePublished":"2023-09-15T10:33:25+00:00","dateModified":"2023-09-15T10:43:55+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/1694513293116.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/1694513293116.jpg","width":976,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/el-papa-francisco-se-reune-con-jose-pedro-manglano-fundador-de-hakuna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"El Papa Francisco se re\u00fane con Jos\u00e9 Pedro Manglano, fundador de Hakuna"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/09\/1694513293116.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-lKz","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/83611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=83611"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/83611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/83612"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=83611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=83611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=83611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}