{"id":81708,"date":"2023-08-07T08:12:10","date_gmt":"2023-08-07T06:12:10","guid":{"rendered":"https:\/\/exaudi.org\/?p=81708"},"modified":"2023-08-08T15:27:42","modified_gmt":"2023-08-08T13:27:42","slug":"el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/","title":{"rendered":"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad"},"content":{"rendered":"<p>El Papa Francisco reitera su \u00abtolerancia cero\u00bb hacia el abuso de menores. Explica los motivos del viaje a Marsella. Repite que la Iglesia est\u00e1 abierta a todos, incluso para aquellos que no pueden recibir ciertos sacramentos. \u00abMi salud est\u00e1 bien\u00bb.<\/p>\n<p>A continuaci\u00f3n la transcripci\u00f3n no oficial de los medios de comunicaci\u00f3n vaticanos:<\/p>\n<p><b>Matteo Bruni:<\/b><\/p>\n<p>Buenas noches Santidad volvemos rejuvenecidos y alegres de esta JMJ en la que hemos podido confrontarnos con las preguntas y las expectativas de los j\u00f3venes, con respecto a la Iglesia, a la fe, y tambi\u00e9n al mundo. Y hemos podido escuchar su respuesta en sus palabras, en su presencia. Ahora hay algunas preguntas de los periodistas, pero antes usted quer\u00eda decir unas palabras:<\/p>\n<p><b>Papa Francisco:<\/b><\/p>\n<p>Buenas noches y muchas gracias por esta experiencia, hoy hay un cumplea\u00f1os: (Bruni: de Rita CRUZ) \u00a1Feliz cumplea\u00f1os! \u00a1Luego viene la tarta!<\/p>\n<p><b>Aura Mar\u00eda Vistas Miguel (R\u00e1dio Renascen\u00e7a):<\/b><\/p>\n<p>Su Santidad, en primer lugar, gracias por su visita a Portugal. Todo el mundo la considera ya un \u00e9xito. Todos est\u00e1n muy contentos. Gracias por haber venido. Encontr\u00e9 a un gran jefe de polic\u00eda que me dijo que nunca hab\u00eda visto una multitud tan obediente y pac\u00edfica. Fue hermoso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-81712\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg 750w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-1-3-300x169.jpeg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-1-3-500x281.jpeg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-1-3-293x165.jpeg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-1-3-390x219.jpeg 390w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>Mi pregunta es sobre F\u00e1tima. Sabemos que usted fue all\u00ed y rez\u00f3 en silencio en la capillita. Pero hab\u00eda una gran expectaci\u00f3n, en el mismo lugar donde Nuestra Se\u00f1ora hab\u00eda hecho una petici\u00f3n para rezar por el fin de la guerra (y estamos en guerra en este momento, por desgracia) para tener una renovaci\u00f3n del Santo Padre, rezando p\u00fablicamente por la paz&#8230; Los ojos del mundo entero estaban fijos en usted ayer por la ma\u00f1ana en F\u00e1tima. \u00bfPor qu\u00e9 no lo hizo?<\/p>\n<p><b>Papa Francisco:<\/b><\/p>\n<p>Rec\u00e9, rec\u00e9. Rec\u00e9 a la Virgen y rec\u00e9 por la paz. No he hecho publicidad. Pero he rezado. Y debemos repetir continuamente esta oraci\u00f3n por la paz. Ella hab\u00eda pedido esto en la Primera Guerra Mundial. Y esta vez (\u00e9sta) se lo he pedido a la Virgen. Y he rezado. No he hecho publicidad.<\/p>\n<p><b>Joa\u0303o Francisco Gonc\u0327alves Gomes (El Observador):<\/b><\/p>\n<p>Muchas gracias, Santo Padre. Yo voy a hablar en espa\u00f1ol, creo que es m\u00e1s f\u00e1cil para m\u00ed y, si puede responder en espa\u00f1ol, mejor, que es m\u00e1s f\u00e1cil para los portugueses, para que lo comprendan. Me gustar\u00eda preguntarle sobre los abusos de ni\u00f1os en la Iglesia, en Portugal. En febrero de este a\u00f1o se ha publicado un informe sobre la realidad de los abusos en Portugal. Casi 5000 ni\u00f1os han sido v\u00edctimas en las \u00faltimas d\u00e9cadas. Le pregunto: \u00bfha le\u00eddo, conoce este informe que ha sido entregado a los obispos? Y tambi\u00e9n, \u00bfqu\u00e9 piensa que debe suceder con los obispos que han sabido de casos de abuso y no los han comunicado a las autoridades?<\/p>\n<p><b>Papa Francisco:<\/b><\/p>\n<p>Como ustedes saben, de manera muy reservada, recib\u00ed a un grupo de personas que fueron abusadas. Como siempre hago en estos casos, dialogamos sobre esta peste, esta tremenda peste, \u00bfno? En la Iglesia, se segu\u00eda m\u00e1s o menos la conducta que se sigue actualmente en las familias y en los barrios: se cubre, \u00bfno? El\u2026 Pensar que el 42% de los abusos, m\u00e1s o menos, se da en las familias o en los barrios. Todav\u00eda hay que madurar y ayudar a que se descubran esas cosas hasta el esc\u00e1ndalo de Boston. Y ah\u00ed la Iglesia tom\u00f3 conciencia de que no se pod\u00eda ir por caminos aleatorios, sino que hab\u00eda que tomar el toro por las astas. Hace dos a\u00f1os y medio tuvimos la reuni\u00f3n de Presidentes de las Conferencias Episcopales, ah\u00ed tambi\u00e9n se dieron estad\u00edsticas oficiales sobre los abusos. Y es grave, la situaci\u00f3n es muy grave. En la Iglesia, hay una frase que la estamos usando continuamente: tolerancia cero, tolerancia cero. Y los pastores que, de alguna manera, no se hicieron cargo tienen que hacerse cargo de esa irresponsabilidad, se ver\u00e1 el modo en cada uno de ellos. Pero es muy duro el mundo de los abusos. Y en eso, yo exhorto a que estemos muy abiertos en todo esto. Sobre lo que me pregunt\u00e1s de c\u00f3mo va el proceso en la Iglesia portuguesa, va bien. Va bien y con serenidad, se busca la seriedad en los casos abusados. Los n\u00fameros, a veces, terminan siendo agrandados, un poco por los comentarios que siempre nos gusta, pero lo que es la realidad, se est\u00e1 llevando bien y eso a m\u00ed me da cierta tranquilidad.<\/p>\n<p>Yo quisiera tocar un punto, y ustedes, como periodistas, les pido que colaboren en esto. Hoy d\u00eda, \u00bftienen telefonino ustedes? Tel\u00e9fono. Bueno, en cualquiera de estos tel\u00e9fonos, pagando algo y con alguna clave, se tiene acceso al abuso sexual con menores. Esto entra en nuestras casas y el abuso sexual con menores se filma en vivo. \u00bfD\u00f3nde se filma? \u00bfQui\u00e9nes son los responsables? Esta es una de las pestes m\u00e1s graves, junto a todo el mundo, pero quiero subrayar esto porque, por ah\u00ed, no se nos ocurre que las cosas son tan radicales. Cuando vos us\u00e1s un nene para hacer un espect\u00e1culo de abuso, llama la atenci\u00f3n. El abuso es como \u201ccomerse\u201d a la v\u00edctima, \u00bfno? O peor, herirla y dejarla viva.\u00a0Hablar con personas abusadas es una experiencia muy dolorosa, que tambi\u00e9n a m\u00ed me hace bien, no porque me guste escuchar, sino me ayuda a hacerme cargo de ese drama. O sea, yo les dir\u00eda, respecto a tu pregunta, lo que dije: el proceso va bien, estoy notificado de c\u00f3mo van las cosas. Por ah\u00ed las noticias lo agrandaron, pero la cosa est\u00e1 andando bien en cuanto a esto. Pero tambi\u00e9n, con esto, les digo, de alguna manera, ayuden, ayuden a que todo tipo de abuso sea solucionado el abuso sexual, pero no es el \u00fanico. Tambi\u00e9n est\u00e1n otros tipos de abusos que claman al Cielo: el abuso del trabajo con ni\u00f1os, el abuso laboral en los ni\u00f1os, y se usa; el abuso en las mujeres, \u00bfno? Todav\u00eda hoy, en muchos pa\u00edses, se tiene como m\u00e9todo la operaci\u00f3n quir\u00fargica de las ni\u00f1as: les quitan el cl\u00edtoris y eso es hoy y se hace con una navaja, y chau\u2026 Crueldad\u2026 Y el abuso laboral, o sea, dentro del abuso sexual, que es grave y todo esto, hay una cultura del abuso que la humanidad tiene que revisar y convertirse.<\/p>\n<div>\n<div class=\"article__embed article__embed--unwrap article__embed--photo\">\n<figure><\/figure>\n<div class=\"photo_embed--Title\">El Papa Francisco durante el vuelo de regreso a Lisboa.<\/div>\n<\/div>\n<\/div>\n<p><b>Jean-Marie Gu\u00e9nois (Le Figaro):<\/b><\/p>\n<p>Santo Padre, \u00bfc\u00f3mo est\u00e1, su salud, c\u00f3mo va su convalecencia? No ha le\u00eddo o s\u00f3lo peque\u00f1as partes de cinco discursos. No hay precedentes en los viajes: \u00bfpor qu\u00e9? \u00bfHa tenido problemas de vista, cansancio? \u00bfTextos demasiado largos? \u00bfC\u00f3mo se siente? Y si me permite una peque\u00f1a pregunta sobre Francia. Usted viene a Marsella, pero nunca visita Francia. El pueblo no lo entiende, \u00bfquiz\u00e1s es demasiado peque\u00f1a o tiene algo en contra de Francia?<\/p>\n<p><b>Papa Francisco:<\/b><\/p>\n<p>Mi salud est\u00e1 bien. Me quitaron los puntos, hago vida normal, llevo un vendaje que tengo que llevar durante dos, tres meses para evitar un eventual \u201ceventraci\u00f3n\u00bb (en lenguaje m\u00e9dico: salida de las v\u00edsceras abdominales, ed.) hasta que los m\u00fasculos est\u00e9n m\u00e1s fuertes. La vista. En esa parroquia cort\u00e9 el discurso porque hab\u00eda una luz delante y no pod\u00eda leer, me daba la luz y por eso lo cort\u00e9. Algunos, a trav\u00e9s de Mateo, preguntaron por qu\u00e9 acort\u00e9 las homil\u00edas que ustedes tienen. Yo cuando hablo, no las homil\u00edas acad\u00e9micas, intento hacerlo los m\u00e1s claro posible. Pero siempre cuando hablo busco la comunicaci\u00f3n. Ustedes han visto que incluso en la homil\u00eda acad\u00e9mica hago algunas bromas, algunas sonrisas las hago para controlar la comunicaci\u00f3n. Con los j\u00f3venes los discursos largos ten\u00edan lo esencial del mensaje y yo lo tomaba de all\u00ed en funci\u00f3n de c\u00f3mo sent\u00eda la comunicaci\u00f3n.<\/p>\n<p>Vieron que yo hac\u00eda alguna pregunta e inmediatamente el eco me dec\u00eda por d\u00f3nde iba la cuesti\u00f3n, si era errado o no. Los j\u00f3venes no tienen mucho tiempo de atenci\u00f3n. Piensen que, si haces un discurso claro, con una idea, una imagen, un afecto, te pueden seguir ocho minutos. Entre par\u00e9ntesis, en la Evangelii Gaudium, la primera exhortaci\u00f3n que hice, hice, escrib\u00ed un largo cap\u00edtulo sobre la homil\u00eda. Porque aqu\u00ed hay un p\u00e1rroco (se refiere a don Benito Giorgetta, p\u00e1rroco de Termoli ed.) que sabe que las homil\u00edas son a veces una tortura, una tortura, que se habla bla, bla, y la gente&#8230; En alg\u00fan pueblo peque\u00f1o, no s\u00e9 si en Termoli, los hombres salen a fumarse un cigarrillo y vuelven. La Iglesia debe convertirse a este aspecto de la homil\u00eda: breve, clara, con un mensaje claro, y afectuosa. Por eso compruebo c\u00f3mo va con los j\u00f3venes y les hago decir. Pero yo acort\u00e9 porque&#8230; me hace falta la idea con los j\u00f3venes.\u00a0 Y pasamos a Francia. Fui a Estrasburgo, ir\u00e9 a Marsella, pero no a Francia. Es un problema que me preocupa, que es el problema Mediterr\u00e1neo. Por eso voy a Francia. La explotaci\u00f3n de los migrantes es criminal. Aqu\u00ed en Europa no, porque va, somos m\u00e1s cultos, pero en los lagers del norte de \u00c1frica&#8230; Yo recomiendo una lectura. Hay un librito, peque\u00f1ito, que escribi\u00f3 un emigrante que tard\u00f3 creo que tres a\u00f1os en venir de Guinea a Espa\u00f1a porque le capturaron, le torturaron, le esclavizaron. Los migrantes en esos lagers del Norte: es terrible. En este momento -la semana pasada- la asociaci\u00f3n Mediterr\u00e1nea Saving Human, estaba haciendo un trabajo de rescate de migrantes que estaban en el desierto entre T\u00fanez y Libia, porque los hab\u00edan dejado all\u00ed a morir. Ese libro se llama \u00abHermanito\u00bb -en italiano tiene el subt\u00edtulo de \u00abFratellino\u00bb-, pero se lee en dos horas, merece la pena. L\u00e9anlo y ver\u00e1n el drama de los migrantes antes de embarcarse. Los obispos del Mediterr\u00e1neo har\u00e1n este encuentro, tambi\u00e9n con algunos pol\u00edticos, para reflexionar seriamente sobre el drama de los migrantes. El Mediterr\u00e1neo es un cementerio, pero no es el mayor cementerio. El mayor cementerio es el norte de \u00c1frica. Esto es terrible, l\u00e9anlo. Voy a Marsella por esto. La semana pasada, el presidente Macron me dijo que es su intenci\u00f3n ir a Marsella y estar\u00e9 un d\u00eda y medio: llegar\u00e9 por la tarde y al d\u00eda siguiente estar\u00e9 todo el d\u00eda.<\/p>\n<p><b>Matteo Bruni:<\/b><\/p>\n<p>No tiene nada contra Francia\u00a0 (repitiendo pregunta).<\/p>\n<p><b>Papa Francisco:<\/b><\/p>\n<p>No. No sobre eso es una pol\u00edtica. Yo visito los pa\u00edses peque\u00f1os de Europa. Los pa\u00edses grandes, Espa\u00f1a, Francia, Inglaterra, los dejo para m\u00e1s adelante, eventualmente.\u00a0 Pero como opci\u00f3n empec\u00e9 con Albania y as\u00ed los peque\u00f1os. No es nada. Francia, dos ciudades, Estrasburgo y Marsella.<\/p>\n<p><b>Anita Hirschbeck\u00a0(KNA):<\/b><\/p>\n<p>El Santo Padre en Lisboa nos dijo que en la Iglesia hay sitio para todos, para todos. La Iglesia est\u00e1 abierta para todos, pero al mismo tiempo no todos tienen los mismos derechos, oportunidades, en el sentido de que por ejemplo las mujeres, los homosexuales no pueden recibir todos los sacramentos. Santo Padre, \u00bfc\u00f3mo explica esta incoherencia entre Iglesia abierta e Iglesia no igual para todos? Gracias.<\/p>\n<p><b>Papa Francisco:<\/b><\/p>\n<p>Usted me hace una pregunta sobre dos puntos de vista diferentes, la Iglesia es abierta para todos, luego hay legislaciones que regulan la vida dentro de la Iglesia. El que est\u00e1 dentro est\u00e1 seg\u00fan la legislaci\u00f3n, lo que dices es una simplificaci\u00f3n: &#8216;no puede hacer los sacramentos&#8217;. Eso no quiere decir que la Iglesia est\u00e9 cerrada, cada uno encuentra a Dios en su camino dentro de la Iglesia, y la Iglesia es madre y gu\u00eda a cada uno en su camino. Por eso no me gusta decir: vienen todos, pero t\u00fa, \u00e9ste, pero el otro&#8230; Cada uno, cada uno en la oraci\u00f3n, en el di\u00e1logo interior, en el di\u00e1logo pastoral, busca el camino a seguir. Por eso haciendo una pregunta: por qu\u00e9 los homosexuales no&#8230; \u00a1Todos! Y el Se\u00f1or es claro: enfermos. Sanos, viejos y j\u00f3venes, feos y guapos&#8230; \u00a1buenos y malos! Hay como una mirada que no entiende esta inserci\u00f3n de la Iglesia como Madre y piensa en ella como una especie de empresa que para entrar hay que hacer esto, hacerlo de esta manera y no de aquella&#8230; Otra cosa es la ministerialidad de la Iglesia, que es la manera de sacar adelante el reba\u00f1o y una de las cosas importantes es la paciencia, en la ministerialidad: acompa\u00f1ar a las personas paso a paso en su camino hacia la madurez. Cada uno de nosotros tiene esta experiencia: que la Iglesia Madre nos ha acompa\u00f1ado y nos acompa\u00f1a en nuestro propio camino de maduraci\u00f3n. No me gusta la reducci\u00f3n, esto no es eclesial, esto es gn\u00f3stico. Es como una herej\u00eda gn\u00f3stica que hoy est\u00e1 un poco de moda. Un cierto gnosticismo que reduce la realidad eclesial y esto no ayuda. La Iglesia es Madre, recibe a todos, y cada uno hace su camino dentro de la Iglesia, sin publicidad, y esto es muy importante. Gracias por el valor de hacer esta pregunta. Gracias.<\/p>\n<p><b>Paolo Ruffini:<\/b><\/p>\n<p>El Papa desea compartir un pensamiento sobre la JMJ.<\/p>\n<p><b>Papa Francisco:<\/b><\/p>\n<p>C\u00f3mo he vivido la JMJ. Esta es la cuarta que vivo. La primera fue en R\u00edo de Janeiro, all\u00e1 brasileira. La segunda fue en Cracovia, la tercera en Panam\u00e1. Esta es la cuarta. Esta es la m\u00e1s numerosa. Seg\u00fan los datos concretos reales, hubo m\u00e1s de un mill\u00f3n de participantes. M\u00e1s. De hecho, en la Vigilia se estim\u00f3 que hab\u00eda un mill\u00f3n cuatrocientos y un mill\u00f3n seiscientos mil.<\/p>\n<p>Impresionante la cantidad. Bien preparada. De las que he visto esta es la mejor preparada. Los j\u00f3venes son una sorpresa. Los j\u00f3venes son j\u00f3venes. Hacen chiquilladas, la vida es as\u00ed. Pero intentan seguir adelante. Y son el futuro. El asunto (el prop\u00f3sito) es acompa\u00f1arlos. El problema es saber acompa\u00f1arlos. Y que no se desprendan de sus ra\u00edces. Por eso insisto tanto en el di\u00e1logo mayores-j\u00f3venes, abuelos con nietos. Este di\u00e1logo es importante, m\u00e1s importante que el di\u00e1logo entre padres e hijos. Los abuelos, las ra\u00edces.<\/p>\n<p>Los j\u00f3venes son religiosos. Buscan la fe, no lo artificial. Buscan el encuentro con Jes\u00fas. Algunos dicen que los j\u00f3venes no siempre viven seg\u00fan la moral. Pero qui\u00e9n de nosotros no ha cometido errores morales en su vida. Todos. Tambi\u00e9n de los mandamientos. Cada uno de nosotros tiene sus propias ca\u00eddas en su historia. La vida es as\u00ed. Pero el Se\u00f1or siempre nos espera porque es misericordioso y padre y la misericordia va m\u00e1s all\u00e1 de todo. Esto es lo que quer\u00eda decir sobre la JMJ.<\/p>\n<p><b>Justin McLellan \u2013 CNS<\/b><\/p>\n<p>Hablando sobre la JMJ, hemos escuchado en estos d\u00edas testimonios de j\u00f3venes que han luchado con la salud mental, con la depresi\u00f3n. \u00bfHa luchado alguna vez por esto? Y si alguien decide suicidarse, \u00bfqu\u00e9 dir\u00eda a los familiares de esa persona que, debido a la ense\u00f1anza cat\u00f3lica sobre el suicidio, sufren pensando que se ha ido al infierno?<\/p>\n<p><b>Papa Francisco:\u00a0<\/b><\/p>\n<p>El suicidio juvenil es importante hoy, el n\u00famero es importante. Existen. Los medios de comunicaci\u00f3n no dicen tanto porque no se informa a trav\u00e9s de los medios de comunicaci\u00f3n. Yo me qued\u00e9 en di\u00e1logo con los j\u00f3venes -no en la Confesi\u00f3n- aprovech\u00e9 para dialogar. Un joven simp\u00e1tico me dijo: \u201c\u00bfPuedo hacerte una pregunta? \u00bfQu\u00e9 piensa del suicidio?\u201d. No hablaba nuestro idioma, pero le entend\u00ed bien y empezamos a hablar del suicidio. Y al final me dijo: \u201cGracias, porque el a\u00f1o pasado estaba indeciso sobre si hacerlo o no\u201d. Tantos j\u00f3venes est\u00e1n ansiosos, deprimidos, pero no solo psicol\u00f3gicamente&#8230; Adem\u00e1s, en algunos pa\u00edses que son muy, muy exigentes en la universidad, los j\u00f3venes que no pueden conseguir un t\u00edtulo o encontrar un trabajo se suicidan, porque sienten una verg\u00fcenza muy grande. No digo que sea algo cotidiano, pero es un problema. Es un problema actual. Es algo que ocurre.<\/p>\n<p><b>Matteo Bruni:<\/b><\/p>\n<p>Gracias, su Santidad, por las respuestas.<\/p>\n<p><b>Papa Francisco:<\/b><\/p>\n<p>Gracias a ustedes por lo que han hecho y mi consejo: no os olvid\u00e9is\u00a0 \u00abHermanito\u00bb, \u00abFratellino\u00bb, el libro del migrante. Gracias.<\/p>\n<p><iframe loading=\"lazy\" title=\"2023 08 06 Papa Francesco conferenza stampa integrale aereo viaggio apostolico in Portogallo\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/vN1IeoG-n40?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el vuelo de regreso de Lisboa, Francisco explica a los periodistas por qu\u00e9 eligi\u00f3 rezar en silencio en el santuario y por qu\u00e9 ante los j\u00f3venes prefiri\u00f3 dejar los discursos preparados y hablarles con m\u00e1s eficacia<\/p>\n","protected":false},"author":15,"featured_media":81729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[154,68],"tags":[997,7351,7352,9529,158,2769,4953],"class_list":["post-81708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jmj","category-leon-xiv","tag-conferencia-de-prensa","tag-jmj","tag-jmj-lisboa-2023","tag-jmjlisboa","tag-papa-francisco","tag-portugal-es","tag-trending-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"En el vuelo de regreso de Lisboa, Francisco explica a los periodistas por qu\u00e9 eligi\u00f3 rezar en silencio en el santuario y por qu\u00e9 ante los j\u00f3venes prefiri\u00f3 dejar los discursos preparados y hablarles con m\u00e1s eficacia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-07T06:12:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-08T13:27:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad\",\"datePublished\":\"2023-08-07T06:12:10+00:00\",\"dateModified\":\"2023-08-08T13:27:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/\"},\"wordCount\":2879,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg\",\"keywords\":[\"Conferencia de prensa\",\"JMJ\",\"JMJ Lisboa 2023\",\"JMJLISBOA\",\"papa francisco\",\"portugal\",\"Trending\"],\"articleSection\":[\"JMJ\",\"Le\u00f3n XIV\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/\",\"name\":\"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg\",\"datePublished\":\"2023-08-07T06:12:10+00:00\",\"dateModified\":\"2023-08-08T13:27:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg\",\"width\":750,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/","og_locale":"es_ES","og_type":"article","og_title":"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad &#8211; Exaudi","og_description":"En el vuelo de regreso de Lisboa, Francisco explica a los periodistas por qu\u00e9 eligi\u00f3 rezar en silencio en el santuario y por qu\u00e9 ante los j\u00f3venes prefiri\u00f3 dejar los discursos preparados y hablarles con m\u00e1s eficacia","og_url":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2023-08-07T06:12:10+00:00","article_modified_time":"2023-08-08T13:27:42+00:00","og_image":[{"width":750,"height":422,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad","datePublished":"2023-08-07T06:12:10+00:00","dateModified":"2023-08-08T13:27:42+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/"},"wordCount":2879,"image":{"@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg","keywords":["Conferencia de prensa","JMJ","JMJ Lisboa 2023","JMJLISBOA","papa francisco","portugal","Trending"],"articleSection":["JMJ","Le\u00f3n XIV"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/","url":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/","name":"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg","datePublished":"2023-08-07T06:12:10+00:00","dateModified":"2023-08-08T13:27:42+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg","width":750,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/el-papa-en-fatima-rece-por-la-paz-sin-hacer-publicidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"El Papa: en F\u00e1tima rec\u00e9 por la paz sin hacer publicidad"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2023\/08\/cq5dam.thumbnail.cropped.750.422-2-2.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-lfS","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/81708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=81708"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/81708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/81729"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=81708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=81708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=81708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}