{"id":7132,"date":"2021-03-22T09:00:43","date_gmt":"2021-03-22T08:00:43","guid":{"rendered":"https:\/\/exaudi.org\/?p=7132"},"modified":"2022-09-30T13:16:37","modified_gmt":"2022-09-30T11:16:37","slug":"teologia-para-millennials-bendicion-parejas-homosexuales-2021","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/","title":{"rendered":"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales"},"content":{"rendered":"<p>Hoy lunes 22 de marzo de 2021, en \u201c<a href=\"https:\/\/teologiaparamillennials.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Teolog\u00eda para Millennials<\/a>\u201d, el sacerdote mexicano\u00a0<a href=\"https:\/\/exaudi.org\/es\/author\/padremarioarroyo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mario Arroyo Mart\u00ednez<\/a>, comparte con los lectores de Exaudi su art\u00edculo \u201cBendici\u00f3n de parejas homosexuales\u201d.<\/p>\n<p>***<\/p>\n<h4><b>Bendici\u00f3n de parejas homosexuales<\/b><\/h4>\n<p><span style=\"font-weight: 400\">Gran incomodidad ha generado, en la comunidad LGTBIQ y en las personas sensibles a sus derechos y al respeto que merecen como personas, el comunicado de la <\/span><a href=\"https:\/\/www.vatican.va\/roman_curia\/congregations\/cfaith\/index_sp.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">Congregaci\u00f3n para la Doctrina de la Fe<\/span><\/a><span style=\"font-weight: 400\">, donde se responde negativamente a la pregunta sobre si pueden bendecirse las uniones homosexuales. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Es comprensible que eso suceda, y que algunos supongan una especie de esquizofrenia en Francisco respecto a este tema, por dar se\u00f1ales contradictorias con la doctrina oficial aprobada por \u00e9l mismo. Obviamente, el documento reclama una explicaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Por un lado, ve\u00edamos en el documental \u201cFrancesco\u201d, c\u00f3mo el Papa anima a una pareja homosexual cat\u00f3lica a llevar a sus hijos al catecismo. Ahora vemos que el mismo Francisco niega la bendici\u00f3n a una pareja homosexual que tiene intenciones de convivir establemente. \u00bfPor qu\u00e9 ese cambio? En realidad, no se trata de ning\u00fan cambio, sino de problemas y realidades diversas, donde es preciso distinguir finamente a qu\u00e9 nos estamos refiriendo. <\/span><\/p>\n<p><span style=\"font-weight: 400\">En el citado documental, uno de los homosexuales, padre de los tres ni\u00f1os, reconoce que el Papa le anim\u00f3 a meter a sus hijos al catecismo, pero no se pronunci\u00f3 nunca respecto a su situaci\u00f3n, es decir, al hecho de estar casado civilmente con otro hombre, y observa qu\u00e9 \u00e9l piensa que el Papa sostiene la doctrina de la Iglesia, es decir, considerar que est\u00e1 mal ese hecho sin juzgar a las personas concretas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Esa consideraci\u00f3n, hecha en el documental \u201cFrancesco\u201d queda reconocida oficialmente en la pregunta a la <\/span><i><span style=\"font-weight: 400\">Congregaci\u00f3n para la Doctrina de la Fe<\/span><\/i><span style=\"font-weight: 400\"> sobre si la Iglesia puede bendecir esas uniones. Junto a la respuesta negativa viene la explicaci\u00f3n, que es a la par l\u00f3gica y respetuosa, aunque dadas las sensibilidades actuales, es tambi\u00e9n imposible que no desagrade a algunas, muchas personas. La Iglesia aqu\u00ed va contra corriente, pues parafraseando a San Pablo, no es a los hombres a los que debemos agradar, sino a Dios.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Es un asunto de coherencia, y lo explica el documento, porque la uni\u00f3n entre dos personas del mismo sexo no es conforme al designio creador de Dios ni a las ense\u00f1anzas de Jesucristo. En efecto, la doctrina claramente expuesta en <\/span><i><span style=\"font-weight: 400\">G\u00e9nesis<\/span><\/i><span style=\"font-weight: 400\"> 2 y <\/span><i><span style=\"font-weight: 400\">Mateo<\/span><\/i><span style=\"font-weight: 400\"> 19, no deja lugar a dudas o equ\u00edvocos, Dios bendice la uni\u00f3n entre un hombre y una mujer abierta a la vida. Otro tipo de uniones no son conformes con el plan de Dios y por lo tanto no son susceptibles de ser bendecidas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">En este terreno es importante hacer hincapi\u00e9, en que no es una restricci\u00f3n exclusiva para las personas homosexuales, sino para todos los que no cumplan con el plan de Dios. No se puede bendecir, en esa l\u00ednea, un matrimonio civil que no quiera acceder al religioso, la uni\u00f3n libre e incluso un matrimonio que excluya consciente y voluntariamente la prole \u2013aunque en la pr\u00e1ctica eso no lo sabe el sacerdote y puede bendecirlo, sin que sea correcto hacerlo. <\/span><\/p>\n<p><span style=\"font-weight: 400\">El punto es que no se trata de una prescripci\u00f3n en contra de las personas homosexuales, y por lo tanto discriminatoria, sino a favor del designio de Dios sobre la sexualidad y la vida.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Que no se trate de un rechazo de la persona homosexual queda claro en el mismo documento, donde insiste que, si bien la uni\u00f3n entre ellas no puede bendecirse, las personas homosexuales por separado, como hijas de Dios que son, \u00a1claro que se pueden bendecir! <\/span><\/p>\n<p><span style=\"font-weight: 400\">El documento insiste de pasada, en recordar que las personas homosexuales tienen cabida en la Iglesia y pueden encontrar en ella su camino hacia Dios. Pueden meditar la Palabra de Dios, hacer obras de misericordia, participar de la santa misa, practicar el rezo del rosario o cualquier otra devoci\u00f3n.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">La Iglesia las llama, al igual que nos llama a todos, a vivir en plenitud la vocaci\u00f3n bautismal, es decir, aspirar a la santidad. En ellas eso supone abrazar el celibato por el reino de los cielos, y la Iglesia se compromete a brindarles su apoyo. Pero si no aspiran a tanto, no se sienten capaces o simplemente no quieren, la Iglesia no las rechaza, como no rechaza a un divorciado vuelto a casar o a cualquier pecador, pues todos somos pecadores. <\/span><\/p>\n<p><span style=\"font-weight: 400\">En ese caso las invita a hacer lo que puedan y participar en la forma en la que vean conveniente en la vida cristiana, confiando en la misericordia de Dios. En conclusi\u00f3n, no se trata de una discriminaci\u00f3n, sino del significado de la bendici\u00f3n.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>An\u00e1lisis tras el comunicado de la Santa Sede<\/p>\n","protected":false},"author":22,"featured_media":7134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[],"tags":[1072,1073,460,459],"class_list":["post-7132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-22-de-marzo-de-2021","tag-homosexuales","tag-padre-mario-arroyo","tag-teologia-para-millennials"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales - Exaudi<\/title>\n<meta name=\"description\" content=\"En Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cBendici\u00f3n de parejas homosexuales\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales - Exaudi\" \/>\n<meta property=\"og:description\" content=\"En Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cBendici\u00f3n de parejas homosexuales\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-22T08:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-30T11:16:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/03\/cathopic_1487631473308490-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mario Arroyo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Arroyo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/\"},\"author\":{\"name\":\"Mario Arroyo\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/2195e6e643f4a07a343345d49e4e6985\"},\"headline\":\"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales\",\"datePublished\":\"2021-03-22T08:00:43+00:00\",\"dateModified\":\"2022-09-30T11:16:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/\"},\"wordCount\":809,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cathopic_1487631473308490-scaled.jpg?fit=2560%2C1707&ssl=1\",\"keywords\":[\"22 de marzo de 2021\",\"Homosexuales\",\"Padre Mario Arroyo\",\"Teolog\u00eda para Millennials\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/\",\"name\":\"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales - Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cathopic_1487631473308490-scaled.jpg?fit=2560%2C1707&ssl=1\",\"datePublished\":\"2021-03-22T08:00:43+00:00\",\"dateModified\":\"2022-09-30T11:16:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/2195e6e643f4a07a343345d49e4e6985\"},\"description\":\"En Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cBendici\u00f3n de parejas homosexuales\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cathopic_1487631473308490-scaled.jpg?fit=2560%2C1707&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cathopic_1487631473308490-scaled.jpg?fit=2560%2C1707&ssl=1\",\"width\":2560,\"height\":1707,\"caption\":\"Momento de la consagraci\u00f3n \u00a9 Cathopic\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/2195e6e643f4a07a343345d49e4e6985\",\"name\":\"Mario Arroyo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g\",\"caption\":\"Mario Arroyo\"},\"description\":\"Licenciado en Filosof\u00eda por la Universidad Panamericana, M\u00e9xico 1996, ostenta el bachiller en Teolog\u00eda por la Pontificia Universidad de la Santa Cruz, Roma 1999. Doctor en Filosof\u00eda por la Pontificia Universidad de la Santa Cruz, Roma 2002. Ordenado sacerdote en Torreciudad, Espa\u00f1a, en 2002. Autor de: Poder, Dinero y Santidad, Lima 2012; Ciencia y Fe. Un equilibrio posible, UCSS, Lima 2015; Ciencia y Fe. Situaci\u00f3n actual, Facultad de Teolog\u00eda Pontificia y Civil de Lima, Lima 2016; La Iglesia y los Homosexuales. Un falso conflicto, Facultad de Teolog\u00eda Pontificia y Civil de Lima, Lima 2017. Coautor de Dios Busca al Hombre, CDSCO, Lima 2013; Neurona mata esp\u00edritu, Amazon, Lima 2018; Teolog\u00eda para Millennials, Amazon, Lima 2018. El padre Mario es columnista de los portales peruanos Cr\u00f3nica Viva, La abeja y Lucidez, as\u00ed como de los peri\u00f3dicos mexicanos Mural, Expreso, del portal mexicano Vox Fides y de ZENIT. Capell\u00e1n de la Universidad de Piura, Campus de Lima durante los cursos 2017 y 2018. Actualmente, profesor de Teolog\u00eda en la Universidad Panamericana, Ciudad de M\u00e9xico.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/padremarioarroyo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales - Exaudi","description":"En Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cBendici\u00f3n de parejas homosexuales\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/","og_locale":"es_ES","og_type":"article","og_title":"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales - Exaudi","og_description":"En Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cBendici\u00f3n de parejas homosexuales\u201d.","og_url":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2021-03-22T08:00:43+00:00","article_modified_time":"2022-09-30T11:16:37+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/03\/cathopic_1487631473308490-scaled.jpg","type":"image\/jpeg"}],"author":"Mario Arroyo","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Mario Arroyo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/"},"author":{"name":"Mario Arroyo","@id":"https:\/\/exaudi.org\/#\/schema\/person\/2195e6e643f4a07a343345d49e4e6985"},"headline":"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales","datePublished":"2021-03-22T08:00:43+00:00","dateModified":"2022-09-30T11:16:37+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/"},"wordCount":809,"image":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/03\/cathopic_1487631473308490-scaled.jpg?fit=2560%2C1707&ssl=1","keywords":["22 de marzo de 2021","Homosexuales","Padre Mario Arroyo","Teolog\u00eda para Millennials"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/","url":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/","name":"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales - Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/03\/cathopic_1487631473308490-scaled.jpg?fit=2560%2C1707&ssl=1","datePublished":"2021-03-22T08:00:43+00:00","dateModified":"2022-09-30T11:16:37+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/2195e6e643f4a07a343345d49e4e6985"},"description":"En Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cBendici\u00f3n de parejas homosexuales\u201d.","breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/03\/cathopic_1487631473308490-scaled.jpg?fit=2560%2C1707&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/03\/cathopic_1487631473308490-scaled.jpg?fit=2560%2C1707&ssl=1","width":2560,"height":1707,"caption":"Momento de la consagraci\u00f3n \u00a9 Cathopic"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-bendicion-parejas-homosexuales-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Teolog\u00eda para Millennials: Bendici\u00f3n de parejas homosexuales"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/2195e6e643f4a07a343345d49e4e6985","name":"Mario Arroyo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g","caption":"Mario Arroyo"},"description":"Licenciado en Filosof\u00eda por la Universidad Panamericana, M\u00e9xico 1996, ostenta el bachiller en Teolog\u00eda por la Pontificia Universidad de la Santa Cruz, Roma 1999. Doctor en Filosof\u00eda por la Pontificia Universidad de la Santa Cruz, Roma 2002. Ordenado sacerdote en Torreciudad, Espa\u00f1a, en 2002. Autor de: Poder, Dinero y Santidad, Lima 2012; Ciencia y Fe. Un equilibrio posible, UCSS, Lima 2015; Ciencia y Fe. Situaci\u00f3n actual, Facultad de Teolog\u00eda Pontificia y Civil de Lima, Lima 2016; La Iglesia y los Homosexuales. Un falso conflicto, Facultad de Teolog\u00eda Pontificia y Civil de Lima, Lima 2017. Coautor de Dios Busca al Hombre, CDSCO, Lima 2013; Neurona mata esp\u00edritu, Amazon, Lima 2018; Teolog\u00eda para Millennials, Amazon, Lima 2018. El padre Mario es columnista de los portales peruanos Cr\u00f3nica Viva, La abeja y Lucidez, as\u00ed como de los peri\u00f3dicos mexicanos Mural, Expreso, del portal mexicano Vox Fides y de ZENIT. Capell\u00e1n de la Universidad de Piura, Campus de Lima durante los cursos 2017 y 2018. Actualmente, profesor de Teolog\u00eda en la Universidad Panamericana, Ciudad de M\u00e9xico.","url":"https:\/\/exaudi.org\/es\/author\/padremarioarroyo\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/03\/cathopic_1487631473308490-scaled.jpg?fit=2560%2C1707&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-1R2","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/7132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=7132"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/7132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/7134"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=7132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=7132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=7132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}