{"id":62907,"date":"2022-09-28T09:58:16","date_gmt":"2022-09-28T07:58:16","guid":{"rendered":"https:\/\/exaudi.org\/?p=62907"},"modified":"2022-09-28T09:58:16","modified_gmt":"2022-09-28T07:58:16","slug":"pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/","title":{"rendered":"Pakist\u00e1n: \u00abHay una bendici\u00f3n para los que tocan la Palabra de Dios\u00bb"},"content":{"rendered":"<p style=\"font-weight: 400\"><em>El 30 de septiembre se celebra la memoria de san Jer\u00f3nimo, padre y doctor de la Iglesia, que tradujo la Biblia al lat\u00edn. La Iglesia dedica el mes de septiembre a la Biblia y recuerda la profunda convicci\u00f3n de san Jer\u00f3nimo de que \u201cquien no conoce la Sagrada Escritura, no conoce a Cristo\u201d.<\/em><em>\u00a0<\/em><\/p>\n<p style=\"font-weight: 400\"><em>La fundaci\u00f3n Aid to the Church in Need (ACN) habl\u00f3 con el padre Emmanuel Asi, secretario ejecutivo de la Comisi\u00f3n B\u00edblica Cat\u00f3lica en Pakist\u00e1n desde su fundaci\u00f3n en 2002, sobre la situaci\u00f3n de los cristianos y el apostolado que realiza en Pakist\u00e1n. El padre Asi, sacerdote de la arquidi\u00f3cesis de Lahore, destac\u00f3 tambi\u00e9n el car\u00e1cter sagrado que tiene la Biblia para sus fieles. <\/em><\/p>\n<figure id=\"attachment_62908\" aria-describedby=\"caption-attachment-62908\" style=\"width: 200px\" class=\"wp-caption alignright\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-62908\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/09\/image001-2.jpg?resize=200%2C147&#038;ssl=1\" alt=\"\u00a9ACN\" width=\"200\" height=\"147\" \/><figcaption id=\"caption-attachment-62908\" class=\"wp-caption-text\">\u00a9ACN<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><strong>\u00bfCu\u00e1l es la situaci\u00f3n de los cristianos en Pakist\u00e1n? <\/strong><\/p>\n<p style=\"font-weight: 400\">Pakist\u00e1n es una rep\u00fablica isl\u00e1mica con 230 millones de habitantes, de los cuales el 97% son musulmanes. El 3% restante son minor\u00edas, entre ellas hind\u00faes, cristianos y sikhs. La mayor\u00eda de los 1,5 millones de cristianos son cat\u00f3licos. Por tanto, para gente de otras religiones distintas al islam, como los cristianos, vivir en Pakist\u00e1n no es f\u00e1cil. No hay libertad religiosa.<\/p>\n<p style=\"font-weight: 400\"><strong>Pero la Constituci\u00f3n reconoce que \u00abtodo ciudadano tendr\u00e1 derecho a profesar, practicar y difundir su religi\u00f3n\u00bb, y que toda confesi\u00f3n religiosa \u00abtiene derecho a fundar, mantener y gestionar sus propias instituciones religiosas\u00bb \u00bfQu\u00e9 es lo que est\u00e1 sucediendo entonces? <\/strong><\/p>\n<p style=\"font-weight: 400\">En el papel se nos permite hacer todo, tenemos derechos; pero en la pr\u00e1ctica, en la pol\u00edtica, en la vida social, en la vida acad\u00e9mica, en la vida laboral, hay mucha discriminaci\u00f3n y dificultades para nuestros j\u00f3venes \u2014los que quieren estudiar en las universidades y los que buscan trabajo. \u00a0En la Iglesia, puedes hacer lo que quieras, tienes el 100% de libertad. Puedes dirigir tus escuelas, puedes dirigir tus institutos, puedes dirigir tus parroquias, tu comunidad, hacer cualquier programa, puedes imprimir Biblias, puedes imprimir tus libros. Pero una vez que sales a la sociedad, a la calle, a la oficina, al trabajo, entonces hay dificultades, hay discriminaci\u00f3n.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfCu\u00e1l cree que es el mayor reto para los cristianos en Pakist\u00e1n? <\/strong><\/p>\n<figure id=\"attachment_62917\" aria-describedby=\"caption-attachment-62917\" style=\"width: 200px\" class=\"wp-caption alignright\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-62917\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/09\/image013.jpg?resize=200%2C133&#038;ssl=1\" alt=\"\u00a9ACN\" width=\"200\" height=\"133\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/09\/image013.jpg?w=200&amp;ssl=1 200w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/09\/image013.jpg?resize=120%2C80&amp;ssl=1 120w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><figcaption id=\"caption-attachment-62917\" class=\"wp-caption-text\">\u00a9ACN<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">El primer reto para ellos es mantenerse fieles y ser valientes en la vida diaria. Tenemos una gran bendici\u00f3n, y es que la mayor\u00eda de nuestra gente es joven. Cuando vas a la iglesia, alrededor del 65 por ciento de la gente tiene menos de 40 a\u00f1os. Por lo tanto, nuestra Iglesia est\u00e1 muy viva. Pero nuestro gran problema, nuestro principal reto es la educaci\u00f3n de nuestra gente, porque la educaci\u00f3n en Pakist\u00e1n es de muy bajo nivel. El analfabetismo es muy alto. Por otro lado, la poblaci\u00f3n cristiana sigue creciendo, este es otro reto: c\u00f3mo llegar a la gente. Los obispos quieren abrir m\u00e1s parroquias. Tenemos suficientes sacerdotes y vocaciones, as\u00ed que tendremos suficientes sacerdotes en el futuro. Esa no es nuestra dificultad, sino poder abrir parroquias, construir casas parroquiales para poder llegar a la gente.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfDe qu\u00e9 manera la Comisi\u00f3n B\u00edblica da a conocer el mensaje del Evangelio en Pakist\u00e1n? <\/strong><\/p>\n<p style=\"font-weight: 400\">En los \u00faltimos 20 a\u00f1os, desde que existe la Comisi\u00f3n B\u00edblica Cat\u00f3lica, hemos hecho muchas cosas para acercar la Palabra de Dios a la gente, y la gente a la Palabra de Dios. Esta es nuestra misi\u00f3n. La gente quiere escuchar, quiere leer la Palabra de Dios. Tenemos varios programas para la gente. Por ejemplo, uno llamado \u2018cien mil amigos de la Biblia\u2019 en el que se inscriben personas de todo Pakist\u00e1n, que tienen su propia Biblia y les gusta leerla al menos cinco minutos al d\u00eda.<\/p>\n<p style=\"font-weight: 400\">El a\u00f1o pasado, en noviembre, pusimos los audios de la Biblia en internet para la gente que no puede leer. As\u00ed, la gente puede escuchar la Palabra de Dios. Adem\u00e1s, tenemos la Biblia para ni\u00f1os y la Biblia YouCat impresa en urdu gracias a la fundaci\u00f3n ACN. Hemos impreso 70.000 Biblias.<\/p>\n<p style=\"font-weight: 400\">Tambi\u00e9n, tenemos en todas las di\u00f3cesis el marat\u00f3n de la Biblia en la que participan unas 2000 personas en todo el pa\u00eds. En 127 horas se lee continuamente, d\u00eda y noche, toda la Biblia. Cada persona lee 15 o 20 vers\u00edculos de la Biblia. La gente se ha entusiasmado y emocionado espiritualmente con este programa.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfPodr\u00eda contarnos una historia sobre c\u00f3mo la Biblia ha cambiado la vida de la gente?<\/strong><\/p>\n<p style=\"font-weight: 400\">Tengo muchos, muchos testimonios. Hab\u00eda una persona analfabeta. No sab\u00eda leer. Cuando habl\u00e9 con \u00e9l, me dijo: \u00abQuiero leer la Biblia, pero no s\u00e9 leer\u00bb. Entonces le dije que en la Biblia hay una bendici\u00f3n especial para los que tocan la Palabra de Dios. As\u00ed que le dije: \u00abcada d\u00eda debes tocar una p\u00e1gina de la Biblia, cada palabra de la Biblia. Ve l\u00ednea por l\u00ednea, da esta bendici\u00f3n a tus dedos, porque est\u00e1 escrito en la Biblia que hay una bendici\u00f3n para los que tocan la Palabra de Dios\u00bb. La idea era que cada d\u00eda abriera la Biblia y tocara algunas l\u00edneas. As\u00ed lo hizo y en dos a\u00f1os y medio vino a verme, \u00a1estaba tan feliz y emocionado! Me dijo: \u00abRecib\u00ed muchas bendiciones, mucha conversi\u00f3n y cambio en mi vida. He tocado toda la Biblia\u00bb. As\u00ed que le di un certificado, porque las personas que leen toda la Biblia reciben un certificado de nuestra parte.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfC\u00f3mo es su trabajo fuera de la Iglesia, especialmente en un pa\u00eds mayoritariamente musulm\u00e1n?<\/strong><\/p>\n<p style=\"font-weight: 400\">En primer lugar, ofrecemos muchos seminarios a los que se invita a muchas personas de otras religiones. Hace poco, tuvimos un seminario sobre espiritualidad en el que participaron personas de seis religiones. En segundo lugar, trabajamos con profesores y estudiantes universitarios en estudios de religi\u00f3n comparada. En tercer lugar, est\u00e1 el di\u00e1logo en directo. D\u00eda y noche estamos conviviendo con otras religiones. Vivimos con ellos, hablamos con ellos, vienen a nuestras casas, nosotros vamos a las suyas.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfLe gustar\u00eda dar un mensaje final a ACN y a los benefactores?<\/strong><\/p>\n<p style=\"font-weight: 400\">Quiero dar las gracias a la gente de todo el mundo, a la gente de ACN, a todos los que nos ayudan econ\u00f3micamente y a los que nos apoyan con sus oraciones. Les pido que sigan ayudando, especialmente a Pakist\u00e1n. Les pido en nombre de nuestro pueblo: Por favor, \u00a1contin\u00faen ayud\u00e1ndonos todo lo que puedan! Sea cual sea la situaci\u00f3n cr\u00edtica, sea cual sea la amarga realidad, debemos tener esperanza en Dios. S\u00f3lo la esperanza puede hacer nacer una nueva vida. En nuestro idioma, cuando una mujer est\u00e1 embarazada, utilizamos esta palabra para decir que ella \u00abest\u00e1 con Umeed (\u0627\u0645\u06cc\u062f)\u00bb, \u00abest\u00e1 con esperanza\u00bb, que dar\u00e1 a luz una nueva vida. La esperanza te hace multiplicar y fructificar.<\/p>\n<p style=\"font-weight: 400\">\n","protected":false},"excerpt":{"rendered":"<p>La Iglesia dedica el mes de septiembre a la Biblia y recuerda que \u201cquien no conoce la Sagrada Escritura, no conoce a Cristo\u201d.\u00a0<\/p>\n","protected":false},"author":89,"featured_media":62911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[],"tags":[325],"class_list":["post-62907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-acn"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pakist\u00e1n: &quot;Hay una bendici\u00f3n para los que tocan la Palabra de Dios&quot; &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pakist\u00e1n: &quot;Hay una bendici\u00f3n para los que tocan la Palabra de Dios&quot; &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"La Iglesia dedica el mes de septiembre a la Biblia y recuerda que \u201cquien no conoce la Sagrada Escritura, no conoce a Cristo\u201d.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ayudaalaiglesianecesitada\/?ref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-28T07:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/image002-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"127\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ayuda a la Iglesia Necesitada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/AyudaIglesNeces\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ayuda a la Iglesia Necesitada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/\"},\"author\":{\"name\":\"Ayuda a la Iglesia Necesitada\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/d4906ab3b6c174ffe37d722c51c73317\"},\"headline\":\"Pakist\u00e1n: \u00abHay una bendici\u00f3n para los que tocan la Palabra de Dios\u00bb\",\"datePublished\":\"2022-09-28T07:58:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/\"},\"wordCount\":1191,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image002-1.jpg?fit=200%2C127&ssl=1\",\"keywords\":[\"ACN\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/\",\"name\":\"Pakist\u00e1n: \\\"Hay una bendici\u00f3n para los que tocan la Palabra de Dios\\\" &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image002-1.jpg?fit=200%2C127&ssl=1\",\"datePublished\":\"2022-09-28T07:58:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/d4906ab3b6c174ffe37d722c51c73317\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image002-1.jpg?fit=200%2C127&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image002-1.jpg?fit=200%2C127&ssl=1\",\"width\":200,\"height\":127,\"caption\":\"\u00a9ACN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pakist\u00e1n: \u00abHay una bendici\u00f3n para los que tocan la Palabra de Dios\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/d4906ab3b6c174ffe37d722c51c73317\",\"name\":\"Ayuda a la Iglesia Necesitada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18b646e6575a46729bc25d1c374d5965acb9854728a2929ada390e85905160db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18b646e6575a46729bc25d1c374d5965acb9854728a2929ada390e85905160db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18b646e6575a46729bc25d1c374d5965acb9854728a2929ada390e85905160db?s=96&d=mm&r=g\",\"caption\":\"Ayuda a la Iglesia Necesitada\"},\"description\":\"Ayuda a la Iglesia Necesitada (ACN) es la Fundaci\u00f3n Pontificia que apoya a la Iglesia cat\u00f3lica en su labor evangelizadora en las comunidades m\u00e1s necesitadas, discriminadas y perseguidas del mundo. Cada a\u00f1o, ACN financia m\u00e1s de 5.000 proyectos pastorales y de emergencia humanitaria en m\u00e1s de 130 pa\u00edses. Cuenta con m\u00e1s de 20 oficinas en el mundo (en Espa\u00f1a desde 1965), dedicadas a informar sobre la realidad de estos cristianos; al fomento de la oraci\u00f3n, y a la recaudaci\u00f3n de fondos para la cobertura de proyectos. El 100% de los proyectos que desarrolla ACN se sostienen gracias a los donativos de personas f\u00edsicas u organizaciones que valoran la labor de la Iglesia en el mundo. La Fundaci\u00f3n no recibe subvenciones de organismos p\u00fablicos.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ayudaalaiglesianecesitada\\\/?ref=ts\",\"https:\\\/\\\/www.instagram.com\\\/ayudaiglesianecesitada\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/AyudaIglesNeces\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AINorg\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/ayudaalaiglesianecesitada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pakist\u00e1n: \"Hay una bendici\u00f3n para los que tocan la Palabra de Dios\" &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/","og_locale":"es_ES","og_type":"article","og_title":"Pakist\u00e1n: \"Hay una bendici\u00f3n para los que tocan la Palabra de Dios\" &#8211; Exaudi","og_description":"La Iglesia dedica el mes de septiembre a la Biblia y recuerda que \u201cquien no conoce la Sagrada Escritura, no conoce a Cristo\u201d.\u00a0","og_url":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ayudaalaiglesianecesitada\/?ref=ts","article_published_time":"2022-09-28T07:58:16+00:00","og_image":[{"width":200,"height":127,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/image002-1.jpg","type":"image\/jpeg"}],"author":"Ayuda a la Iglesia Necesitada","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/AyudaIglesNeces","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Ayuda a la Iglesia Necesitada","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/"},"author":{"name":"Ayuda a la Iglesia Necesitada","@id":"https:\/\/exaudi.org\/#\/schema\/person\/d4906ab3b6c174ffe37d722c51c73317"},"headline":"Pakist\u00e1n: \u00abHay una bendici\u00f3n para los que tocan la Palabra de Dios\u00bb","datePublished":"2022-09-28T07:58:16+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/"},"wordCount":1191,"image":{"@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/09\/image002-1.jpg?fit=200%2C127&ssl=1","keywords":["ACN"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/","url":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/","name":"Pakist\u00e1n: \"Hay una bendici\u00f3n para los que tocan la Palabra de Dios\" &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/09\/image002-1.jpg?fit=200%2C127&ssl=1","datePublished":"2022-09-28T07:58:16+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/d4906ab3b6c174ffe37d722c51c73317"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/09\/image002-1.jpg?fit=200%2C127&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/09\/image002-1.jpg?fit=200%2C127&ssl=1","width":200,"height":127,"caption":"\u00a9ACN"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/pakistan-hay-una-bendicion-para-los-que-tocan-la-palabra-de-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Pakist\u00e1n: \u00abHay una bendici\u00f3n para los que tocan la Palabra de Dios\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/d4906ab3b6c174ffe37d722c51c73317","name":"Ayuda a la Iglesia Necesitada","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/18b646e6575a46729bc25d1c374d5965acb9854728a2929ada390e85905160db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/18b646e6575a46729bc25d1c374d5965acb9854728a2929ada390e85905160db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18b646e6575a46729bc25d1c374d5965acb9854728a2929ada390e85905160db?s=96&d=mm&r=g","caption":"Ayuda a la Iglesia Necesitada"},"description":"Ayuda a la Iglesia Necesitada (ACN) es la Fundaci\u00f3n Pontificia que apoya a la Iglesia cat\u00f3lica en su labor evangelizadora en las comunidades m\u00e1s necesitadas, discriminadas y perseguidas del mundo. Cada a\u00f1o, ACN financia m\u00e1s de 5.000 proyectos pastorales y de emergencia humanitaria en m\u00e1s de 130 pa\u00edses. Cuenta con m\u00e1s de 20 oficinas en el mundo (en Espa\u00f1a desde 1965), dedicadas a informar sobre la realidad de estos cristianos; al fomento de la oraci\u00f3n, y a la recaudaci\u00f3n de fondos para la cobertura de proyectos. El 100% de los proyectos que desarrolla ACN se sostienen gracias a los donativos de personas f\u00edsicas u organizaciones que valoran la labor de la Iglesia en el mundo. La Fundaci\u00f3n no recibe subvenciones de organismos p\u00fablicos.","sameAs":["https:\/\/www.facebook.com\/ayudaalaiglesianecesitada\/?ref=ts","https:\/\/www.instagram.com\/ayudaiglesianecesitada\/","https:\/\/x.com\/https:\/\/x.com\/AyudaIglesNeces","https:\/\/www.youtube.com\/user\/AINorg"],"url":"https:\/\/exaudi.org\/es\/author\/ayudaalaiglesianecesitada\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/09\/image002-1.jpg?fit=200%2C127&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-gmD","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/62907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=62907"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/62907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/62911"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=62907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=62907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=62907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}