{"id":62217,"date":"2022-09-16T14:53:31","date_gmt":"2022-09-16T12:53:31","guid":{"rendered":"https:\/\/exaudi.org\/?p=62217"},"modified":"2022-09-16T15:02:45","modified_gmt":"2022-09-16T13:02:45","slug":"el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/","title":{"rendered":"\u00abEl sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones\u00bb"},"content":{"rendered":"<p>Esta ma\u00f1ana, 16 septiembre de 2022, en la Sala Clementina del Palacio Apost\u00f3lico Vaticano, el Santo Padre Francisco ha recibido en Audiencia a los participantes en el Cap\u00edtulo General de los Cistercienses de la Estricta Observancia (trapenses).<\/p>\n<p>Publicamos a continuaci\u00f3n el discurso que el Papa dirigi\u00f3 a los presentes durante el encuentro:<\/p>\n<p>***<\/p>\n<h3><strong>Discurso del Papa<\/strong><\/h3>\n<p>Queridos hermanos y hermanas, \u00a1buenos d\u00edas y bienvenidos!<\/p>\n<p>Agradezco al Abad General sus palabras de saludo y presentaci\u00f3n. S\u00e9 que est\u00e1is celebrando la segunda parte de vuestro Cap\u00edtulo General, en la Porci\u00fancula de Santa Mar\u00eda de los \u00c1ngeles: un lugar tan rico en gracia que seguramente habr\u00e1 contribuido a inspirar vuestras jornadas.<\/p>\n<p>Me alegro con vosotros por el \u00e9xito de la primera parte del Cap\u00edtulo, celebrado en el mismo lugar, durante el cual se eligi\u00f3 tambi\u00e9n al nuevo Abad General. Usted, Padre, se puso inmediatamente a visitar las doce regiones en las que se encuentran sus monasterios. Me gusta pensar que esta \u00abvisita\u00bb se produjo con el santo cuidado que la Virgen Mar\u00eda nos muestra en el Evangelio. \u00abSe levant\u00f3 y se fue deprisa\u00bb, dice Lucas (1,39), y esta expresi\u00f3n merece siempre ser contemplada, para que podamos imitarla, con la gracia del Esp\u00edritu Santo. Me gusta rezar a la Virgen que tiene \u00abprisa\u00bb: \u00abSe\u00f1ora, tienes prisa, \u00bfverdad?\u00bb. Y ella entiende ese lenguaje.<\/p>\n<p>El padre Abad dice que en este viaje ha \u00abrecogido los sue\u00f1os de los superiores\u00bb. Me llam\u00f3 la atenci\u00f3n esta forma de expresarse, y la comparto plenamente. Tanto porque, como sab\u00e9is, yo tambi\u00e9n entiendo \u00abso\u00f1ar\u00bb en este sentido positivo, no ut\u00f3pico sino proyectual; como porque aqu\u00ed no se trata de los sue\u00f1os de un individuo, aunque sea el general superior, sino de una puesta en com\u00fan, de una \u00abcolecci\u00f3n\u00bb de sue\u00f1os que surgen de las comunidades, y que imagino ser\u00e1n objeto de discernimiento en esta segunda parte del Cap\u00edtulo.<\/p>\n<p>Se resumen as\u00ed: sue\u00f1o de comuni\u00f3n, sue\u00f1o de participaci\u00f3n, sue\u00f1o de misi\u00f3n y sue\u00f1o de formaci\u00f3n. Me gustar\u00eda ofrecer algunas reflexiones sobre estos cuatro \u00abcaminos\u00bb.<\/p>\n<p>En primer lugar, me gustar\u00eda hacer una nota, por as\u00ed decirlo, de m\u00e9todo. Es una indicaci\u00f3n que me viene del enfoque ignaciano, pero que, en el fondo, creo que tengo en com\u00fan con vosotros, hombres llamados a la contemplaci\u00f3n en la escuela de San Benito y San Bernardo. Es decir, se trata de interpretar todos estos \u00absue\u00f1os\u00bb a trav\u00e9s de Cristo, identific\u00e1ndonos con \u00c9l a trav\u00e9s del Evangelio e imaginando -en un sentido objetivo y contemplativo- c\u00f3mo so\u00f1\u00f3 Jes\u00fas estas realidades: comuni\u00f3n, participaci\u00f3n, misi\u00f3n y formaci\u00f3n. En efecto, estos sue\u00f1os nos construyen como personas y como comunidad en la medida en que no son nuestros, sino suyos, y los asimilamos en el Esp\u00edritu Santo. Sus sue\u00f1os.<\/p>\n<p>Y aqu\u00ed se abre el espacio para una hermosa y gratificante b\u00fasqueda espiritual: la b\u00fasqueda de los \u00absue\u00f1os de Jes\u00fas\u00bb, es decir, de sus mayores deseos, que el Padre suscit\u00f3 en su coraz\u00f3n divino-humano. Aqu\u00ed, en esta clave de contemplaci\u00f3n evang\u00e9lica, me gustar\u00eda \u00abresonar\u00bb con sus cuatro grandes sue\u00f1os.<\/p>\n<p>El Evangelio de Juan nos ofrece esta oraci\u00f3n de Jes\u00fas al Padre: \u00abLa gloria que me has dado, yo se la he dado a ellos, para que sean uno como nosotros. Yo en ellos y t\u00fa en m\u00ed, para que sean perfectos en la unidad y para que el mundo sepa que t\u00fa me has enviado y que los has amado como a m\u00ed\u00bb (17,22-23). Esta santa Palabra nos permite so\u00f1ar con Jes\u00fas en la comuni\u00f3n de sus disc\u00edpulos, nuestra comuni\u00f3n como \u00absuya\u00bb (cf. Exhortaci\u00f3n apost\u00f3lica <em>Gaudete et exsultate,<\/em> 146). Esta comuni\u00f3n -es importante dejarlo claro- no consiste en nuestra uniformidad, homogeneidad, compatibilidad, m\u00e1s o menos espont\u00e1nea o forzada, no; consiste en nuestra com\u00fan relaci\u00f3n con Cristo, y en \u00c9l con el Padre en el Esp\u00edritu. Jes\u00fas no tuvo miedo de la diversidad que exist\u00eda entre los Doce, y por lo tanto nosotros tampoco debemos temer la diversidad, porque al Esp\u00edritu Santo le encanta avivar las diferencias y hacer de ellas una armon\u00eda. En cambio, nuestros particularismos, nuestros exclusivismos, esos s\u00ed, debemos temerlos, porque causan divisiones (cf. Exhortaci\u00f3n Apost\u00f3lica <em>Evangelii gaudium,<\/em> 131). Por lo tanto, el sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones, ambas cosas malas.<\/p>\n<p>Otra palabra que tomamos del Evangelio de Mateo. En la controversia con los escribas y fariseos, Jes\u00fas dice a sus disc\u00edpulos: \u00abNo os llam\u00e9is &#8216;rabino&#8217;, porque uno es vuestro Maestro, y todos vosotros sois hermanos. Y no llam\u00e9is \u00abpadre\u00bb a ninguno de vosotros en la tierra, porque uno es vuestro Padre, el celestial. Y no os llam\u00e9is \u00abgu\u00edas\u00bb, porque uno es vuestro Gu\u00eda, el Cristo\u00bb (23:8-10). Aqu\u00ed podemos contemplar el sue\u00f1o de Jes\u00fas de una comunidad fraterna, en la que todos participan sobre la base de una relaci\u00f3n filial com\u00fan con el Padre y como disc\u00edpulos de Jes\u00fas. En particular, una comunidad de vida consagrada puede ser un signo del Reino de Dios al testimoniar un estilo de fraternidad participativa entre personas reales y concretas que, con sus limitaciones, eligen cada d\u00eda, confiando en la gracia de Cristo, vivir juntos. Tambi\u00e9n los instrumentos de comunicaci\u00f3n actuales pueden y deben estar al servicio de la participaci\u00f3n real -no s\u00f3lo virtual- en la vida concreta de la comunidad (cf. <em>Evangelii gaudium,<\/em> 87).<\/p>\n<p>El Evangelio nos entrega tambi\u00e9n el sue\u00f1o de Jes\u00fas de una Iglesia totalmente misionera: \u00abId y haced disc\u00edpulos a todas las naciones, bautiz\u00e1ndolas en el nombre del Padre y del Hijo y del Esp\u00edritu Santo, ense\u00f1\u00e1ndoles a cumplir todo lo que os he mandado\u00bb (<em>Mt<\/em> 28,19-20). Este mandato concierne a todos en la Iglesia. No hay carismas que sean misioneros y otros que no lo sean. Todos los carismas, en la medida en que son dados a la Iglesia, son para la evangelizaci\u00f3n de los pueblos, es decir, misioneros; por supuesto, de maneras diferentes, muy diferentes, seg\u00fan la \u00abimaginaci\u00f3n\u00bb de Dios. Un monje que reza en su monasterio desempe\u00f1a su papel para llevar el Evangelio a esa tierra, para ense\u00f1ar a la gente que vive all\u00ed que tenemos un Padre que nos ama y que en este mundo estamos en camino hacia el Cielo. Entonces, la pregunta es: \u00bfc\u00f3mo se puede ser cisterciense estricto y formar parte de \u00abuna Iglesia en salida\u00bb (Evangelii gaudium, 20)? En el camino, pero es una salida. \u00bfC\u00f3mo experimentas la \u00abdulce y reconfortante alegr\u00eda de evangelizar\u00bb (San Pablo VI, Exhortaci\u00f3n Apost\u00f3lica <em>Evangelii Nuntiandi<\/em>, 75)? Ser\u00eda bueno escucharlo de ustedes, contemplativos. Por ahora, nos basta con recordar que \u00aben cualquier forma de evangelizaci\u00f3n la primac\u00eda es siempre de Dios\u00bb y que \u00aben toda la vida de la Iglesia debe quedar siempre claro que la iniciativa es de Dios, que &#8216;es \u00e9l quien nos ha amado&#8217; (1 Jn 4,10)\u00bb (<em>Evangelii gaudium,<\/em> 12).<\/p>\n<p>Finalmente, los Evangelios nos muestran a Jes\u00fas cuidando de sus disc\u00edpulos, educ\u00e1ndolos con paciencia, explic\u00e1ndoles, al margen, el sentido de ciertas par\u00e1bolas; e iluminando con palabras el testimonio de su forma de vida, de sus gestos. Por ejemplo, cuando Jes\u00fas, despu\u00e9s de haber lavado los pies a los disc\u00edpulos, les dice: \u00abOs he dado ejemplo para que tambi\u00e9n vosotros hag\u00e1is lo que yo he hecho con vosotros\u00bb (<em>Jn<\/em> 13,15), el Maestro sue\u00f1a con la formaci\u00f3n de sus amigos seg\u00fan el camino de Dios, que es la humildad y el servicio. Y cuando, un poco m\u00e1s tarde, dice: \u00abMuchas cosas tengo que deciros todav\u00eda, pero por el momento no pod\u00e9is soportar su carga\u00bb (Jn 16,12), Jes\u00fas deja claro que los disc\u00edpulos tienen un camino que recorrer, una formaci\u00f3n que recibir; y promete que el Formador ser\u00e1 el Esp\u00edritu Santo: \u00abCuando venga el Esp\u00edritu de la verdad, os guiar\u00e1 a toda la verdad\u00bb (v. 13). Y podr\u00eda haber muchas referencias evang\u00e9licas que atestiguan el sue\u00f1o de la formaci\u00f3n en el coraz\u00f3n del Se\u00f1or. Me gusta resumirlos como un sue\u00f1o de santidad, renovando esta invitaci\u00f3n: \u00abQue la gracia de tu Bautismo fructifique en un camino de santidad\u00bb. Que todo est\u00e9 abierto a Dios y para ello el\u00edjalo, elija a Dios una y otra vez. No os desanim\u00e9is, porque ten\u00e9is la fuerza del Esp\u00edritu Santo para hacerlo posible, y la santidad, al fin y al cabo, es el fruto del Esp\u00edritu Santo en vuestra vida (cf. Gal 5,22-23)\u00bb (Exhortaci\u00f3n apost\u00f3lica <em>Gaudete et exsultate<\/em>, 15).<\/p>\n<p>Queridos hermanos y hermanas, les agradezco su presencia y les deseo lo mejor en la conclusi\u00f3n de su Cap\u00edtulo. Que la Virgen te acompa\u00f1e. De coraz\u00f3n te bendigo a ti y a todos tus cohermanos del mundo. Y les pido que por favor recen por m\u00ed.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cap\u00edtulo General de los Cistercienses de la Estricta Observancia (trapenses).<\/p>\n","protected":false},"author":15,"featured_media":62218,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[124,68],"tags":[4636,6987,648,158,6988,4953],"class_list":["post-62217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-discursos","category-leon-xiv","tag-capitulo-general","tag-cisterciences","tag-discurso","tag-papa-francisco","tag-trapenses","tag-trending-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;El sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones&quot; &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;El sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones&quot; &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Cap\u00edtulo General de los Cistercienses de la Estricta Observancia (trapenses).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-16T12:53:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-16T13:02:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Trapenses-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"\u00abEl sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones\u00bb\",\"datePublished\":\"2022-09-16T12:53:31+00:00\",\"dateModified\":\"2022-09-16T13:02:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/\"},\"wordCount\":1580,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Trapenses-scaled.jpg\",\"keywords\":[\"Capitulo General\",\"Cisterciences\",\"Discurso\",\"papa francisco\",\"Trapenses\",\"Trending\"],\"articleSection\":[\"Discursos\",\"Le\u00f3n XIV\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/\",\"name\":\"\\\"El sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones\\\" &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Trapenses-scaled.jpg\",\"datePublished\":\"2022-09-16T12:53:31+00:00\",\"dateModified\":\"2022-09-16T13:02:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Trapenses-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Trapenses-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Trapenses \u00a9 Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abEl sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"El sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones\" &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/","og_locale":"es_ES","og_type":"article","og_title":"\"El sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones\" &#8211; Exaudi","og_description":"Cap\u00edtulo General de los Cistercienses de la Estricta Observancia (trapenses).","og_url":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2022-09-16T12:53:31+00:00","article_modified_time":"2022-09-16T13:02:45+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Trapenses-scaled.jpg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"\u00abEl sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones\u00bb","datePublished":"2022-09-16T12:53:31+00:00","dateModified":"2022-09-16T13:02:45+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/"},"wordCount":1580,"image":{"@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Trapenses-scaled.jpg","keywords":["Capitulo General","Cisterciences","Discurso","papa francisco","Trapenses","Trending"],"articleSection":["Discursos","Le\u00f3n XIV"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/","url":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/","name":"\"El sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones\" &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Trapenses-scaled.jpg","datePublished":"2022-09-16T12:53:31+00:00","dateModified":"2022-09-16T13:02:45+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Trapenses-scaled.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Trapenses-scaled.jpg","width":2560,"height":1707,"caption":"Trapenses \u00a9 Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/el-sueno-de-comunion-de-jesus-nos-libera-de-la-uniformidad-y-de-las-divisiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abEl sue\u00f1o de comuni\u00f3n de Jes\u00fas nos libera de la uniformidad y de las divisiones\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/09\/Trapenses-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-gbv","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/62217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=62217"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/62217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/62218"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=62217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=62217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=62217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}