{"id":60476,"date":"2022-08-08T09:09:40","date_gmt":"2022-08-08T07:09:40","guid":{"rendered":"https:\/\/exaudi.org\/?p=60476"},"modified":"2022-08-08T09:09:40","modified_gmt":"2022-08-08T07:09:40","slug":"terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/","title":{"rendered":"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo"},"content":{"rendered":"<p>Cuando una persona joven muere de un ataque al coraz\u00f3n, con frecuencia es debido a que hered\u00f3 una mutaci\u00f3n en el ADN que produce la enfermedad del m\u00fasculo card\u00edaco. Seg\u00fan refiere la revista Science ( <a href=\"https:\/\/www.science.org\/content\/article\/u-k-charity-gives-36-million-boost-gene-editing-inherited-heart-diseases\">https:\/\/www.science.org\/content\/article\/u-k-charity-gives-36-million-boost-gene-editing-inherited-heart-diseases<\/a> ), la Fundaci\u00f3n Brit\u00e1nica del Coraz\u00f3n anunci\u00f3 recientemente una concesi\u00f3n de 30 millones de libras esterlinas (36 millones de d\u00f3lares) durante 5 a\u00f1os a un equipo internacional para el desarrollo de terapias de edici\u00f3n gen\u00e9tica para estas mortales dolencias. El proyecto, que ha sido llamado CureHeart, fue elegido al competir con otras propuestas que pugnaban por lograr el financiamiento de un trabajo de investigaci\u00f3n en patolog\u00edas card\u00edacas.<\/p>\n<p>Los m\u00e9todos de edici\u00f3n gen\u00e9tica han progresado bastante, especialmente mediante el sistema CRISPR. \u00abRealmente brindan oportunidades para combatir&#8230; las enfermedades cardiovasculares de manera diferente\u00bb, dijo la directora ejecutiva de la Fundaci\u00f3n Brit\u00e1nica del Coraz\u00f3n, Charmaine Griffiths, en una conferencia de prensa.<\/p>\n<p>El premio se otorga para el estudio de las cardiomiopat\u00edas gen\u00e9ticas. Estas patolog\u00edas afectan a una de cada 250 personas. El riesgo de ataques e insuficiencia card\u00edacos se da en ellos y en sus parientes. \u201cLas miocardiopat\u00edas realmente persiguen a las familias\u201d, a menudo durante generaciones, dice Hugh Watkins, cardi\u00f3logo de la Universidad de Oxford y l\u00edder de CureHeart.<\/p>\n<p>Como se conoce una gran cantidad de mutaciones que provocan estas patolog\u00edas, se podr\u00eda considerar que la terapia g\u00e9nica puede aliviarlas, sin embargo, los investigadores deben afrontar grandes retos pues algunos genes defectuosos son muy grandes, por lo que no se pueden trasladar mediante virus. Por otro lado, los cient\u00edficos podr\u00edan tener necesidad de corregir una sola hebra de ADN, lo que lleva a eliminar la herramienta CRISPR cl\u00e1sica que efect\u00faa la edici\u00f3n cortando ambas hebras de ADN. Para esquivar estas dificultades el proyecto CureHeart implementar\u00e1 sistemas que reparen peque\u00f1os errores de una sola base en una sola copia de un gen, as\u00ed como f\u00f3rmulas que alteran el ADN regulador que controla el gen. \u00abEl silenciamiento ser\u00e1 m\u00e1s f\u00e1cil\u00bb, dice la codirectora Christine Seidman, investigadora de gen\u00e9tica cardiovascular en el Hospital Brigham and Women&#8217;s y la Escuela de Medicina de Harvard.\u00a0Sin embargo, impulsar la producci\u00f3n de una prote\u00edna grande \u00abrequerir\u00e1 muchos m\u00e1s trucos moleculares\u00bb. Los cient\u00edficos son optimistas gracias al reciente logro en la reparaci\u00f3n de c\u00e9lulas card\u00edacas y de otros tejidos en ratones que sufren de progeria, una patolog\u00eda que produce envejecimiento prematuro.<\/p>\n<p>La revista Nature informa de los llamados tratamientos de edici\u00f3n de bases con los primeros ensayos cl\u00ednicos para tratar la enfermedad de c\u00e9lulas falciformes o regular el colesterol (<a href=\"https:\/\/www.nature.com\/articles\/d41586-022-01951-1\">https:\/\/www.nature.com\/articles\/d41586-022-01951-1<\/a> ) Estas pruebas deben informar de sus resultados en 2023. \u201cEs muy emocionante que comiencen los primeros ensayos cl\u00ednicos, con CRISPR-Cas9 y ahora tambi\u00e9n con la edici\u00f3n b\u00e1sica\u201d, dice Gerald Schwank, quien estudia el uso de la edici\u00f3n del genoma para tratar enfermedades en la Universidad de Z\u00farich, Suiza.\u00a0\u00abTenemos mucho que aprender.\u00bb<\/p>\n<p>Mediante CRISPR-Cas9, la enzima Cas9 rompe ambas cadenas de ADN en el lugar en que se editar\u00e1 el genoma. La c\u00e9lula repara el ADN uniendo las hebras, pero en ocasiones se producen errores, lo que conlleva una serie de cambios en la secuencia gen\u00e9tica por cada proceso de edici\u00f3n. En cambio, la llamada edici\u00f3n de bases ensambla una prote\u00edna Cas9, que corta solamente una de las hebras del ADN, con otra enzima que transforma una base del genoma en otra. Cas9 se encarga de llevar a la enzima que edita al lugar correcto y \u00e9sta interviene dando lugar a una sola edici\u00f3n. Este grado de precisi\u00f3n induce a pensar que se logren t\u00e9cnicas m\u00e1s fiables y seguras para las terapias g\u00e9nicas.<\/p>\n<p>La propuesta consiste en producir sistemas que eliminen en lo posible el riesgo y se dirijan a un tipo determinado de mutaci\u00f3n, para que se puedan realizar ensayos cl\u00ednicos con algunas pocas terapias posibles, que est\u00e9n terminadas para las primeras pruebas luego de 5 a\u00f1os.<\/p>\n<p>Adem\u00e1s de la British Heart Foundation, en el Reino Unido tambi\u00e9n hay otras instituciones como el Cancer Research UK que tambi\u00e9n financia equipos para afrontar otros retos en el campo de la investigaci\u00f3n.<\/p>\n<p>El trabajo de investigaci\u00f3n es un deber \u00e9tico porque, aunque no siempre beneficia a los sujetos de investigaci\u00f3n participantes en un determinado protocolo, permite adquirir conocimiento generalizable que servir\u00e1, entre otras cosas, para la curaci\u00f3n o el alivio de diferentes enfermedades. La bio\u00e9tica en investigaci\u00f3n nos lleva a respetar y cuidar a los sujetos (personas humanas) que colaboran para el descubrimiento de nuevos f\u00e1rmacos o terapias, tomando en consideraci\u00f3n el balance entre los riesgos y los posibles beneficios del trabajo experimental. Como la terapia g\u00e9nica ha presentado anteriormente problemas graves en su aplicaci\u00f3n, es l\u00f3gico que se priorice la seguridad de los procedimientos que se van a ensayar, de ah\u00ed la demora en las pruebas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Importancia de la bio\u00e9tica en investigaci\u00f3n<\/p>\n","protected":false},"author":61,"featured_media":60477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[130],"tags":[728,6716],"class_list":["post-60476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-bioetica","tag-terapia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Importancia de la bio\u00e9tica en investigaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-08T07:09:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/08\/pexels-miguel-a-padrinan-2120614-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1702\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaime Mill\u00e1s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaime Mill\u00e1s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/\"},\"author\":{\"name\":\"Jaime Mill\u00e1s\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/9289b86f583b467de6211ee83d38bd64\"},\"headline\":\"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo\",\"datePublished\":\"2022-08-08T07:09:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/\"},\"wordCount\":892,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-miguel-a-padrinan-2120614-scaled.jpg\",\"keywords\":[\"Bio\u00e9tica\",\"terapia\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/\",\"name\":\"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-miguel-a-padrinan-2120614-scaled.jpg\",\"datePublished\":\"2022-08-08T07:09:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/9289b86f583b467de6211ee83d38bd64\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-miguel-a-padrinan-2120614-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-miguel-a-padrinan-2120614-scaled.jpg\",\"width\":2560,\"height\":1702,\"caption\":\"Copyright Pexels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/9289b86f583b467de6211ee83d38bd64\",\"name\":\"Jaime Mill\u00e1s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5411e954b925aec35e6fee798049038437d70fbb0331a1e1ab0973b05285a7a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5411e954b925aec35e6fee798049038437d70fbb0331a1e1ab0973b05285a7a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5411e954b925aec35e6fee798049038437d70fbb0331a1e1ab0973b05285a7a5?s=96&d=mm&r=g\",\"caption\":\"Jaime Mill\u00e1s\"},\"description\":\"Licenciado en Ciencias Biol\u00f3gicas, por la Universidad de Valencia (Espa\u00f1a), ciudad donde naci\u00f3 en 1953, es licenciado en Ciencias de la Educaci\u00f3n por la Universidad de Piura (Per\u00fa) y M\u00e1ster en Direcci\u00f3n de Instituciones Educativas por el Centro Universitario Villanueva, adscrito a la Universidad Complutense de Madrid. Tambi\u00e9n es M\u00e1ster en Bio\u00e9tica por la Universidad de Murcia (Espa\u00f1a) y Doctor en Bio\u00e9tica por la Universidad Cat\u00f3lica de Valencia (Espa\u00f1a) con una tesis sobre \u201cReflexi\u00f3n bio\u00e9tica sobre la opini\u00f3n de los m\u00e9dicos peruanos acerca de la aplicaci\u00f3n de la terapia con c\u00e9lulas madre en cl\u00ednicas de Latinoam\u00e9rica\u201d (Sobresaliente Cum Laude). En Valencia fue subdirector del Colegio Mayor \u201cAlbalat\u201d y, tras fijar su residencia en el Per\u00fa, en 1977, director de varios Centros Culturales de Lima y del Colegio Alpamayo desde 1988 hasta 2004. Ha sido vicepresidente del Centro de Orientaci\u00f3n Familiar (COFAM) y trabaj\u00f3 en la oficina de proyectos de la Asociaci\u00f3n para el Desarrollo de la Ense\u00f1anza Universitaria (ADEU), entidad promotora de la Universidad de Piura. Asimismo ha sido secretario de la Asociaci\u00f3n Civil \u201cPiura 450\u201d, promotora de colegios en Chiclayo y Piura. Tambi\u00e9n ha sido director del Colegio \u201cTuricar\u00e1\u201d de Piura entre los a\u00f1os 2005 y 2012. Actualmente se desempe\u00f1a como presidente del Comit\u00e9 Institucional de \u00c9tica en Investigaci\u00f3n de la Universidad de Piura. Director del Departamento de Ciencias B\u00e1sicas y Bio\u00e9tica, y director de Estudios de la Facultad de Medicina de la Universidad de Piura. Coautor del libro \u201cBio\u00e9tica en Investigaci\u00f3n. Fundamentos, principios, aplicaciones\u201d. Y autor de otros libros de Bio\u00e9tica y educaci\u00f3n, as\u00ed como art\u00edculos de Bio\u00e9tica en revistas indexadas.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/jaimemillas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/","og_locale":"es_ES","og_type":"article","og_title":"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo &#8211; Exaudi","og_description":"Importancia de la bio\u00e9tica en investigaci\u00f3n","og_url":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2022-08-08T07:09:40+00:00","og_image":[{"width":2560,"height":1702,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/08\/pexels-miguel-a-padrinan-2120614-scaled.jpg","type":"image\/jpeg"}],"author":"Jaime Mill\u00e1s","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Jaime Mill\u00e1s","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/"},"author":{"name":"Jaime Mill\u00e1s","@id":"https:\/\/exaudi.org\/#\/schema\/person\/9289b86f583b467de6211ee83d38bd64"},"headline":"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo","datePublished":"2022-08-08T07:09:40+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/"},"wordCount":892,"image":{"@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/08\/pexels-miguel-a-padrinan-2120614-scaled.jpg","keywords":["Bio\u00e9tica","terapia"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/","url":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/","name":"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/08\/pexels-miguel-a-padrinan-2120614-scaled.jpg","datePublished":"2022-08-08T07:09:40+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/9289b86f583b467de6211ee83d38bd64"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/08\/pexels-miguel-a-padrinan-2120614-scaled.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/08\/pexels-miguel-a-padrinan-2120614-scaled.jpg","width":2560,"height":1702,"caption":"Copyright Pexels"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/terapia-de-edicion-genetica-para-enfermedades-cardiacas-hereditarias-minimizar-el-riesgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Terapia de edici\u00f3n gen\u00e9tica para enfermedades card\u00edacas hereditarias: minimizar el riesgo"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/9289b86f583b467de6211ee83d38bd64","name":"Jaime Mill\u00e1s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5411e954b925aec35e6fee798049038437d70fbb0331a1e1ab0973b05285a7a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5411e954b925aec35e6fee798049038437d70fbb0331a1e1ab0973b05285a7a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5411e954b925aec35e6fee798049038437d70fbb0331a1e1ab0973b05285a7a5?s=96&d=mm&r=g","caption":"Jaime Mill\u00e1s"},"description":"Licenciado en Ciencias Biol\u00f3gicas, por la Universidad de Valencia (Espa\u00f1a), ciudad donde naci\u00f3 en 1953, es licenciado en Ciencias de la Educaci\u00f3n por la Universidad de Piura (Per\u00fa) y M\u00e1ster en Direcci\u00f3n de Instituciones Educativas por el Centro Universitario Villanueva, adscrito a la Universidad Complutense de Madrid. Tambi\u00e9n es M\u00e1ster en Bio\u00e9tica por la Universidad de Murcia (Espa\u00f1a) y Doctor en Bio\u00e9tica por la Universidad Cat\u00f3lica de Valencia (Espa\u00f1a) con una tesis sobre \u201cReflexi\u00f3n bio\u00e9tica sobre la opini\u00f3n de los m\u00e9dicos peruanos acerca de la aplicaci\u00f3n de la terapia con c\u00e9lulas madre en cl\u00ednicas de Latinoam\u00e9rica\u201d (Sobresaliente Cum Laude). En Valencia fue subdirector del Colegio Mayor \u201cAlbalat\u201d y, tras fijar su residencia en el Per\u00fa, en 1977, director de varios Centros Culturales de Lima y del Colegio Alpamayo desde 1988 hasta 2004. Ha sido vicepresidente del Centro de Orientaci\u00f3n Familiar (COFAM) y trabaj\u00f3 en la oficina de proyectos de la Asociaci\u00f3n para el Desarrollo de la Ense\u00f1anza Universitaria (ADEU), entidad promotora de la Universidad de Piura. Asimismo ha sido secretario de la Asociaci\u00f3n Civil \u201cPiura 450\u201d, promotora de colegios en Chiclayo y Piura. Tambi\u00e9n ha sido director del Colegio \u201cTuricar\u00e1\u201d de Piura entre los a\u00f1os 2005 y 2012. Actualmente se desempe\u00f1a como presidente del Comit\u00e9 Institucional de \u00c9tica en Investigaci\u00f3n de la Universidad de Piura. Director del Departamento de Ciencias B\u00e1sicas y Bio\u00e9tica, y director de Estudios de la Facultad de Medicina de la Universidad de Piura. Coautor del libro \u201cBio\u00e9tica en Investigaci\u00f3n. Fundamentos, principios, aplicaciones\u201d. Y autor de otros libros de Bio\u00e9tica y educaci\u00f3n, as\u00ed como art\u00edculos de Bio\u00e9tica en revistas indexadas.","url":"https:\/\/exaudi.org\/es\/author\/jaimemillas\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/08\/pexels-miguel-a-padrinan-2120614-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-fJq","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/60476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=60476"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/60476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/60477"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=60476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=60476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=60476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}