{"id":58798,"date":"2022-06-29T22:11:17","date_gmt":"2022-06-29T20:11:17","guid":{"rendered":"https:\/\/exaudi.org\/?p=58798"},"modified":"2022-07-01T12:00:03","modified_gmt":"2022-07-01T10:00:03","slug":"cara-papa-desidero-desideravi-poderosa-belleza-liturgia","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/","title":{"rendered":"Carta del Papa &#8216;Desiderio desideravi&#8217;: La poderosa belleza de la liturgia"},"content":{"rendered":"<p>El 29 de junio de 2022, el Papa Francisco ha publicado <em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html\">Desiderio desideravi<\/a><\/em>, una Carta Apost\u00f3lica al Pueblo de Dios sobre la liturgia, para recordar el sentido profundo de la celebraci\u00f3n eucar\u00edstica surgida del Concilio Vaticano II e invitar a la formaci\u00f3n lit\u00fargica.<\/p>\n<p>En sus 65 puntos, la carta desarrolla los resultados de la plenaria de febrero de 2019 del Dicasterio del Culto Divino y sigue el <em>motu proprio<\/em>\u00a0<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/motu_proprio\/documents\/20210716-motu-proprio-traditionis-custodes.html\" target=\"_blank\" rel=\"noopener\">Traditionis custodes<\/a><\/em>, reafirmando la importancia de la comuni\u00f3n eclesial en torno al rito surgido de la reforma lit\u00fargica postconciliar.<\/p>\n<p>Este nuevo documento papal no constituye un libro de instrucciones o una enumeraci\u00f3n de normas, sino una meditaci\u00f3n que pretender transmitir la belleza de la celebraci\u00f3n lit\u00fargica y su papel en la evangelizaci\u00f3n.<\/p>\n<p>\u201cHe querido ofrecer simplemente algunas reflexiones que ciertamente no agotan el inmenso tesoro de la celebraci\u00f3n de los santos misterios. Pido a todos los obispos, presb\u00edteros y di\u00e1conos, a los formadores de los seminarios, a los profesores de las facultades teol\u00f3gicas y de las escuelas de teolog\u00eda, y a todos los catequistas, que ayuden al pueblo santo de Dios a beber de la que siempre ha sido la fuente principal de la espiritualidad cristiana\u201d, expone el Sucesor de Pedro.<\/p>\n<p>\u201cEstamos continuamente llamados a redescubrir la riqueza de los principios generales expuestos en los primeros n\u00fameros de la\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\" target=\"_blank\" rel=\"noopener\">Sacrosanctum Concilium<\/a><\/em>, comprendiendo el \u00edntimo v\u00ednculo entre la primera Constituci\u00f3n conciliar y todas las dem\u00e1s. Por eso, no podemos volver a esa forma ritual que los Padres Conciliares,\u00a0<em>cum Petro y sub Petro<\/em>, sintieron la necesidad de reformar, aprobando, bajo la gu\u00eda del Esp\u00edritu y seg\u00fan su conciencia de pastores, los principios de los que naci\u00f3 la reforma\u201d, clarifica.<\/p>\n<p>Y prosigue: \u201clos santos Pont\u00edfices Pablo VI y Juan Pablo II, al aprobar los libros lit\u00fargicos reformados\u00a0<em>ex decreto Sacrosancti \u0152cumenici Concilii Vaticani II<\/em>, garantizaron la fidelidad de la reforma al Concilio\u201d. Por eso, clarifica, \u201cescrib\u00ed\u00a0<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/motu_proprio\/documents\/20210716-motu-proprio-traditionis-custodes.html\" target=\"_blank\" rel=\"noopener\">Traditionis custodes<\/a><\/em>, para que la Iglesia pueda elevar, en la variedad de lenguas, una \u00fanica e id\u00e9ntica oraci\u00f3n capaz de expresar su unidad\u00a0<a name=\"_ftnref23\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn23\">[23]<\/a>. Esta unidad que, como ya he escrito, pretendo ver restablecida en toda la Iglesia de Rito Romano\u201d (61).<\/p>\n<p>En el punto 16, Francisco indica que \u201ccon esta carta quisiera simplemente invitar a toda la Iglesia a redescubrir, custodiar y vivir la verdad y la fuerza de la celebraci\u00f3n cristiana. Quisiera que la belleza de la celebraci\u00f3n cristiana y de sus necesarias consecuencias en la vida de la Iglesia no se vieran desfiguradas por una comprensi\u00f3n superficial y reductiva de su valor o, peor a\u00fan, por su instrumentalizaci\u00f3n al servicio de alguna visi\u00f3n ideol\u00f3gica, sea cual sea\u201d<\/p>\n<p>A continuaci\u00f3n, el Pont\u00edfice recuerda c\u00f3mo en varias ocasiones ha advertido \u201csobre una tentaci\u00f3n peligrosa para la vida de la Iglesia que es la \u201cmundanidad espiritual\u201d: he hablado de ella ampliamente en la Exhortaci\u00f3n\u00a0<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_exhortations\/documents\/papa-francesco_esortazione-ap_20131124_evangelii-gaudium.html#No_a_la_mundanidad_espiritual\" target=\"_blank\" rel=\"noopener\">Evangelii gaudium<\/a><\/em>\u00a0(nn. 93-97), identificando el gnosticismo y el neopelagianismo como los dos modos vinculados entre s\u00ed, que la alimentan\u201d.<\/p>\n<p>El primero, explica \u201creduce la fe cristiana a un subjetivismo que encierra al individuo \u201cen la inmanencia de su propia raz\u00f3n o de sus sentimientos\u201d (<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_exhortations\/documents\/papa-francesco_esortazione-ap_20131124_evangelii-gaudium.html#No_a_la_mundanidad_espiritual\">Evangelii gaudium<\/a><\/em>, n. 94)\u201d.<\/p>\n<p>El segundo, \u201canula el valor de la gracia para confiar s\u00f3lo en las propias fuerzas, dando lugar a \u2018un elitismo narcisista y autoritario, donde en lugar de evangelizar lo que se hace es analizar y clasificar a los dem\u00e1s, y en lugar de facilitar el acceso a la gracia se gastan las energ\u00edas en controlar\u2019 (<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_exhortations\/documents\/papa-francesco_esortazione-ap_20131124_evangelii-gaudium.html#No_a_la_mundanidad_espiritual\" target=\"_blank\" rel=\"noopener\">Evangelii gaudium<\/a><\/em>, n. 94)\u201d.<\/p>\n<p>Estas \u201cformas distorsionadas del cristianismo pueden tener consecuencias desastrosas para la vida de la Iglesia\u201d.<\/p>\n<p>Para el Obispo de Roma, la liturgia constituye \u201cel ant\u00eddoto m\u00e1s eficaz contra estos venenos. Evidentemente, hablo de la Liturgia en su sentido teol\u00f3gico y \u2013 ya lo afirmaba P\u00edo XII \u2013 no como un\u00a0<em>ceremonial decorativo\u2026 o un mero conjunto de leyes y de preceptos\u2026<\/em>\u00a0que ordena el cumplimiento de los ritos\u00a0<a name=\"_ftnref6\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn6\" target=\"_blank\" rel=\"noopener\">[6]<\/a>\u201c (18) .<\/p>\n<p>Por otro lado, el Papa matiza que \u201cparticipar en el sacrificio eucar\u00edstico no es una conquista nuestra, como si pudi\u00e9ramos presumir de ello ante Dios y ante nuestros hermanos\u201d. De este modo, \u201cel inicio de cada celebraci\u00f3n me recuerda qui\u00e9n soy, pidi\u00e9ndome que confiese mi pecado e invit\u00e1ndome a rogar a la bienaventurada siempre Virgen Mar\u00eda, a los \u00e1ngeles, a los santos y a todos los hermanos y hermanas, que intercedan por m\u00ed ante el Se\u00f1or: ciertamente no somos dignos de entrar en su casa, necesitamos una palabra suya para salvarnos (cfr.\u00a0<em>Mt<\/em>\u00a08,8).<\/p>\n<p>La Liturgia, contin\u00faa \u201cno tiene nada que ver con un moralismo asc\u00e9tico: es el don de la Pascua del Se\u00f1or que, aceptado con docilidad, hace nueva nuestra vida. No se entra en el cen\u00e1culo sino por la fuerza de atracci\u00f3n de su deseo de comer la Pascua con nosotros:\u00a0<em>Desiderio desideravi hoc Pascha manducare vobiscum, antequam patiar<\/em>\u00a0(<em>Lc<\/em>\u00a022,15)\u201d (20).<\/p>\n<p>El Papa Francisco remarca tambi\u00e9n que \u201cel redescubrimiento continuo de la belleza de la Liturgia no es la b\u00fasqueda de un esteticismo ritual, que se complace s\u00f3lo en el cuidado de la formalidad exterior de un rito, o se satisface con una escrupulosa observancia de las r\u00fabricas\u201d. Al mismo tiempo que aclarar que \u201cesta afirmaci\u00f3n no pretende avalar, de ning\u00fan modo, la actitud contraria que confunde lo sencillo con una dejadez banal, lo esencial con la superficialidad ignorante, lo concreto de la acci\u00f3n ritual con un funcionalismo pr\u00e1ctico exagerado\u201d (22).<\/p>\n<p>Al mismo tiempo el Santo Padre aclara que \u201chay que cuidar todos los aspectos de la celebraci\u00f3n (espacio, tiempo, gestos, palabras, objetos, vestiduras, cantos, m\u00fasica, &#8230;) y observar todas las r\u00fabricas: esta atenci\u00f3n ser\u00eda suficiente para no robar a la asamblea lo que le corresponde, es decir, el misterio pascual celebrado en el modo ritual que la Iglesia establece\u201d. Pero, a\u00f1ade, \u201cincluso, si la calidad y la norma de la acci\u00f3n celebrativa estuvieran garantizadas, esto no ser\u00eda suficiente para que nuestra participaci\u00f3n fuera plena\u201d (23).<\/p>\n<p>En este sentido, resalta que el \u201casombro ante el misterio pascual\u201d como parte esencial de la acci\u00f3n lit\u00fargica: \u201cSi faltara el asombro por el misterio pascual que se hace presente en la concreci\u00f3n de los signos sacramentales, podr\u00edamos correr el riesgo de ser realmente impermeables al oc\u00e9ano de gracia que inunda cada celebraci\u00f3n\u201d (24).<\/p>\n<p>Y expone que \u201ccuando digo asombro ante el misterio pascual, no me refiero en absoluto a lo que, me parece, se quiere expresar con la vaga expresi\u00f3n \u2018sentido del misterio\u2019: a veces, entre las supuestas acusaciones contra la reforma lit\u00fargica est\u00e1 la de haberlo \u2013 se dice \u2013 eliminado de la celebraci\u00f3n\u201d. El asombro al que se refiere \u201cno es una especie de desorientaci\u00f3n ante una realidad oscura o un rito enigm\u00e1tico, sino que es, por el contrario, admiraci\u00f3n ante el hecho de que el plan salv\u00edfico de Dios nos haya sido revelado en la Pascua de Jes\u00fas (cfr.\u00a0<em>Ef<\/em>\u00a01,3-14), cuya eficacia sigue lleg\u00e1ndonos en la celebraci\u00f3n de los \u2018misterios\u2019, es decir, de los sacramentos\u201d (25).<\/p>\n<p>Por otro lado, Su Santidad apunta que \u201cSi la Liturgia es \u2018la cumbre a la cual tiende la acci\u00f3n de la Iglesia y, al mismo tiempo, la fuente de donde mana toda su fuerza\u2019 (<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, n. 10), comprendemos bien lo que est\u00e1 en juego en la cuesti\u00f3n lit\u00fargica\u201d. As\u00ed, \u201cser\u00eda banal leer las tensiones, desgraciadamente presentes en torno a la celebraci\u00f3n, como una simple divergencia entre diferentes sensibilidades sobre una forma ritual\u201d, matizando que \u201cla problem\u00e1tica es, ante todo, eclesiol\u00f3gica\u201d. En este sentido, el Papa no ve \u201cc\u00f3mo se puede decir que se reconoce la validez del Concilio \u2013 aunque me sorprende un poco que un cat\u00f3lico pueda presumir de no hacerlo \u2013 y no aceptar la reforma lit\u00fargica nacida de la\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, que expresa la realidad de la Liturgia en \u00edntima conexi\u00f3n con la visi\u00f3n de la Iglesia descrita admirablemente por la\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19641121_lumen-gentium_sp.html\">Lumen Gentium<\/a><\/em>\u201c.<\/p>\n<p>Por ello, agrega \u201ccomo expliqu\u00e9 en la carta enviada a todos los Obispos \u2013 me sent\u00ed en el deber de afirmar que \u00a1los libros lit\u00fargicos promulgados por los Santos Pont\u00edfices Pablo VI y Juan Pablo II, en conformidad con los decretos del Concilio Vaticano II, como \u00fanica expresi\u00f3n de la\u00a0<em>lex orandi<\/em>\u00a0del Rito Romano\u2019 (Motu Proprio\u00a0<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/motu_proprio\/documents\/20210716-motu-proprio-traditionis-custodes.html\">Traditionis custodes<\/a><\/em>, art. 1).<\/p>\n<p>La no aceptaci\u00f3n de la reforma, as\u00ed como una comprensi\u00f3n superficial de la misma, \u201cnos distrae de la tarea de encontrar las respuestas a la pregunta que repito: \u00bfc\u00f3mo podemos crecer en la capacidad de vivir plenamente la acci\u00f3n lit\u00fargica? \u00bfC\u00f3mo podemos seguir asombr\u00e1ndonos de lo que ocurre ante nuestros ojos en la celebraci\u00f3n? Necesitamos una formaci\u00f3n lit\u00fargica seria y vital\u201d (31).<\/p>\n<p>En este sentido, remite al te\u00f3logo Romano Guardini, resaltando que sin formaci\u00f3n lit\u00fargica, \u201clas reformas en el rito y en el texto no sirven de mucho\u201d (34).<\/p>\n<p>Asimismo, describe que \u201cuna celebraci\u00f3n que no evangeliza, no es aut\u00e9ntica, como no lo es un anuncio que no lleva al encuentro con el Resucitado en la celebraci\u00f3n: ambos, pues, sin el testimonio de la caridad, son como un metal que resuena o un c\u00edmbalo que aturde\u201d (37<\/p>\n<p>El Pont\u00edfice indica, por otro lado que,\u00a0\u201dUn modo para custodiar y para crecer en la comprensi\u00f3n vital de los s\u00edmbolos de la Liturgia es, ciertamente, cuidar el arte de celebrar\u201d. Esta expresi\u00f3n, prosigue, \u201ctambi\u00e9n es objeto de diferentes interpretaciones. Se entiende m\u00e1s claramente teniendo en cuenta el sentido teol\u00f3gico de la Liturgia descrito en el n\u00famero 7 de\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, al cual nos hemos referido varias veces\u201d.<\/p>\n<p>El\u00a0<em>ars celebrandi<\/em>, se\u00f1ala, \u201cno puede reducirse a la mera observancia de un aparato de r\u00fabricas, ni tampoco puede pensarse en una fantasiosa \u2013 a veces salvaje \u2013 creatividad sin reglas. El rito es en s\u00ed mismo una norma, y la norma nunca es un fin en s\u00ed misma, sino que siempre est\u00e1 al servicio de la realidad superior que quiere custodiar\u201d (48).<\/p>\n<p>Para el Sucesor de Pedro, \u201cel arte de celebrar no se puede improvisar\u201d, pues, \u201ccomo cualquier arte, requiere una aplicaci\u00f3n asidua\u201d. \u201cUno no aprende el arte de celebrar porque asista a un curso de oratoria o de t\u00e9cnicas de comunicaci\u00f3n persuasiva (no juzgo las intenciones, veo los efectos). Toda herramienta puede ser \u00fatil, pero siempre debe estar sujeta a la naturaleza de la Liturgia y a la acci\u00f3n del Esp\u00edritu. Es necesaria una dedicaci\u00f3n diligente a la celebraci\u00f3n, dejando que la propia celebraci\u00f3n nos transmita su arte\u201d (50).<\/p>\n<p>Despu\u00e9s, se refiere a que \u201cson muchas las formas en que la asamblea,\u00a0<em>como un solo hombre\u00a0<\/em>(<em>Neh<\/em>\u00a08,1), participa en la celebraci\u00f3n\u201d y sobre c\u00f3mo \u201crealizar todos juntos el mismo gesto, hablar todos a la vez, transmite a los individuos la fuerza de toda la asamblea\u201d. Habla de \u201cuna uniformidad que no s\u00f3lo no mortifica, sino que, por el contrario, educa a cada fiel a descubrir la aut\u00e9ntica singularidad de su personalidad, no con actitudes individualistas, sino siendo conscientes de ser un solo cuerpo\u201d.<\/p>\n<p>\u201cNo se trata de tener que seguir un protocolo lit\u00fargico: se trata m\u00e1s bien de una \u2018disciplina\u2019 \u2013 en el sentido utilizado por Guardini \u2013 que, si se observa con autenticidad, nos forma: son gestos y palabras que ponen orden en nuestro mundo interior, haci\u00e9ndonos experimentar sentimientos, actitudes, comportamientos. No son el enunciado de un ideal en el que inspirarnos, sino una acci\u00f3n que implica al cuerpo en su totalidad, es decir, ser unidad de alma y cuerpo\u201d (51).<\/p>\n<p>Entre los gestos rituales que pertenecen a toda la asamblea, el Papa Francisco afirma que \u201cel silencio ocupa un lugar de absoluta importancia\u201d, que \u201cmueve al arrepentimiento y al deseo de conversi\u00f3n; suscita la escucha de la Palabra y la oraci\u00f3n; dispone a la adoraci\u00f3n del Cuerpo y la Sangre de Cristo\u201d (52).<\/p>\n<p>Adem\u00e1s, el Santo Padre resalta c\u00f3mo en las comunidades cristianas la forma de vivir la celebraci\u00f3n \u201cest\u00e1 condicionada -para bien y, por desgracia, tambi\u00e9n para mal- por el modo en que su pastor preside la asamblea\u201d. En esta l\u00ednea, enumera varios \u201cmodelos\u201d de presidencia inadecuada: \u201crigidez austera o creatividad exasperada; misticismo espiritualizante o funcionalismo pr\u00e1ctico; prisa precipitada o lentitud acentuada; descuido desali\u00f1ado o refinamiento excesivo; afabilidad sobreabundante o impasibilidad hier\u00e1tica\u201d.<\/p>\n<p>Estos modelos, aunque distintos entre s\u00ed, presentan una ra\u00edz com\u00fan: \u201cUn exagerado personalismo en el estilo celebrativo que, en ocasiones, expresa una mal disimulada man\u00eda de protagonismo. Esto suele ser m\u00e1s evidente cuando nuestras celebraciones se difunden en red\u201d, mientras que \u201cpresidir la Eucarist\u00eda es sumergirse en el horno del amor de Dios\u201d (57).<\/p>\n<p>\u201cAbandonemos las pol\u00e9micas para escuchar juntos lo que el Esp\u00edritu dice a la Iglesia, mantengamos la comuni\u00f3n, sigamos asombr\u00e1ndonos por la belleza de la Liturgia\u201d, concluye la carta del Papa.<\/p>\n<p>A continuaci\u00f3n sigue el texto completo de la Carta Apost\u00f3lica del Santo Padre.<\/p>\n<p>***<\/p>\n<p style=\"text-align: center\">CARTA APOST\u00d3LICA<\/p>\n<p style=\"text-align: center\"><strong><em>DESIDERIO DESIDERAVI<\/em><\/strong><\/p>\n<p style=\"text-align: center\">DEL SANTO PADRE<br \/>\n<strong>FRANCISCO<\/strong><\/p>\n<p style=\"text-align: center\">A LOS OBISPOS, A LOS PRESB\u00cdTEROS<br \/>\nY A LOS DI\u00c1CONOS,<br \/>\nA LAS PERSONAS CONSAGRADAS<br \/>\nY A TODOS LOS FIELES LAICOS<\/p>\n<p style=\"text-align: center\">SOBRE LA FORMACI\u00d3N LIT\u00daRGICA<br \/>\nDEL PUEBLO DE DIOS<\/p>\n<p><em>Desiderio desideravi<br \/>\nhoc Pascha manducare vobiscum,<br \/>\nantequam patiar\u00a0<\/em>(Lc 22, 15)<\/p>\n<ol>\n<li>Queridos hermanos y hermanas:<\/li>\n<\/ol>\n<p>con esta carta deseo llegar a todos \u2013despu\u00e9s de haber escrito a los obispos tras la publicaci\u00f3n del Motu Proprio\u00a0<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/motu_proprio\/documents\/20210716-motu-proprio-traditionis-custodes.html\">Traditionis custodes<\/a><\/em>\u2013 para compartir con vosotros algunas reflexiones sobre la Liturgia, dimensi\u00f3n fundamental para la vida de la Iglesia. El tema es muy extenso y merece una atenta consideraci\u00f3n en todos sus aspectos: sin embargo, con este escrito no pretendo tratar la cuesti\u00f3n de forma exhaustiva. Quiero ofrecer simplemente algunos elementos de reflexi\u00f3n para contemplar la belleza y la verdad de la celebraci\u00f3n cristiana.<\/p>\n<p><em>La Liturgia: el \u201choy\u201d de la historia de la salvaci\u00f3n<\/em><\/p>\n<ol start=\"2\">\n<li><em>\u201cArdientemente he deseado comer esta Pascua con vosotros, antes de padecer\u201d<\/em>(<em>Lc<\/em>\u00a022,15) Las palabras de Jes\u00fas con las cuales inicia el relato de la \u00faltima Cena son el medio por el que se nos da la asombrosa posibilidad de vislumbrar la profundidad del amor de las Personas de la Sant\u00edsima Trinidad hacia nosotros.<\/li>\n<li>Pedro y Juan hab\u00edan sido enviados a preparar lo necesario para poder comer la Pascua, pero, mir\u00e1ndolo bien, toda la creaci\u00f3n, toda la historia \u2013que finalmente estaba a punto de revelarse como historia de salvaci\u00f3n\u2013 es una gran preparaci\u00f3n de aquella Cena. Pedro y los dem\u00e1s est\u00e1n en esa mesa, inconscientes y, sin embargo, necesarios: todo don, para ser tal, debe tener alguien dispuesto a recibirlo. En este caso, la desproporci\u00f3n entre la inmensidad del don y la peque\u00f1ez de quien lo recibe es infinita y no puede dejar de sorprendernos. Sin embargo \u2013 por la misericordia del Se\u00f1or \u2013 el don se conf\u00eda a los Ap\u00f3stoles para que sea llevado a todos los hombres.<\/li>\n<li>Nadie se gan\u00f3 el puesto en esa Cena, todos fueron invitados, o, mejor dicho, atra\u00eddos por el deseo ardiente que Jes\u00fas tiene de comer esa Pascua con ellos: \u00c9l sabe que es el Cordero de esa Pascua, sabe que es la Pascua. Esta es la novedad absoluta de esa Cena, la \u00fanica y verdadera novedad de la historia, que hace que esa Cena sea \u00fanica y, por eso, \u201c\u00faltima\u201d, irrepetible. Sin embargo, su infinito deseo de restablecer esa comuni\u00f3n con nosotros, que era y sigue siendo su proyecto original, no se podr\u00e1 saciar hasta que todo hombre,\u00a0<em>de toda tribu, lengua, pueblo y naci\u00f3n<\/em>(<em>Ap<\/em>\u00a05,9) haya comido su Cuerpo y bebido su Sangre: por eso, esa misma Cena se har\u00e1 presente en la celebraci\u00f3n de la Eucarist\u00eda hasta su vuelta.<\/li>\n<li>El mundo todav\u00eda no lo sabe, pero todos est\u00e1n\u00a0<em>invitados al banquete de bodas del Cordero<\/em>(<em>Ap<\/em>\u00a019,9). Lo \u00fanico que se necesita para acceder es el vestido nupcial de la fe que viene por medio de la escucha de su Palabra (cfr.\u00a0<em>Rom<\/em>\u00a010,17): la Iglesia lo confecciona a medida, con la blancura de una vestidura\u00a0<em>lavada en la Sangre del Cordero<\/em>\u00a0(cfr.\u00a0<em>Ap<\/em>\u00a07,14). No debemos tener ni un momento de descanso, sabiendo que no todos han recibido a\u00fan la invitaci\u00f3n a la Cena, o que otros la han olvidado o perdido en los tortuosos caminos de la vida de los hombres. Por eso, he dicho que \u201csue\u00f1o con una opci\u00f3n misionera capaz de transformarlo todo, para que las costumbres, los estilos, los horarios, el lenguaje y toda estructura eclesial se convierta en un cauce adecuado para la evangelizaci\u00f3n del mundo actual m\u00e1s que para la autopreservaci\u00f3n\u201d (<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_exhortations\/documents\/papa-francesco_esortazione-ap_20131124_evangelii-gaudium.html#Una_impostergable_renovaci%C3%B3n_eclesial\">Evangelii gaudium<\/a><\/em>, n. 27): para que todos puedan sentarse a la Cena del sacrificio del Cordero y vivir de \u00c9l.<\/li>\n<li>Antes de nuestra respuesta a su invitaci\u00f3n \u2013 mucho antes \u2013 est\u00e1 su deseo de nosotros: puede que ni siquiera seamos conscientes de ello, pero cada vez que vamos a Misa, el motivo principal es porque nos atrae el deseo que \u00c9l tiene de nosotros. Por nuestra parte, la respuesta posible, la ascesis m\u00e1s exigente es, como siempre, la de entregarnos a su amor, la de dejarnos atraer por \u00c9l. Ciertamente, nuestra comuni\u00f3n con el Cuerpo y la Sangre de Cristo ha sido deseada por \u00c9l en la \u00faltima Cena.<\/li>\n<li>El contenido del Pan partido es la cruz de Jes\u00fas, su sacrificio en obediencia amorosa al Padre. Si no hubi\u00e9ramos tenido la \u00faltima Cena, es decir, la anticipaci\u00f3n ritual de su muerte, no habr\u00edamos podido comprender c\u00f3mo la ejecuci\u00f3n de su sentencia de muerte pudiera ser el acto de culto perfecto y agradable al Padre, el \u00fanico y verdadero acto de culto. Unas horas m\u00e1s tarde, los Ap\u00f3stoles habr\u00edan podido ver en la cruz de Jes\u00fas, si hubieran soportado su peso, lo que significaba \u201ccuerpo entregado\u201d, \u201csangre derramada\u201d: y es de lo que hacemos memoria en cada Eucarist\u00eda. Cuando regresa, resucitado de entre los muertos, para partir el pan a los disc\u00edpulos de Ema\u00fas y a los suyos, que hab\u00edan vuelto a pescar peces y no hombres, en el lago de Galilea, ese gesto les abre sus ojos, los cura de la ceguera provocada por el horror de la cruz, haci\u00e9ndolos capaces de \u201cver\u201d al Resucitado, de creer en la Resurrecci\u00f3n.<\/li>\n<li>Si hubi\u00e9semos llegado a Jerusal\u00e9n despu\u00e9s de Pentecost\u00e9s y hubi\u00e9ramos sentido el deseo no s\u00f3lo de tener noticias sobre Jes\u00fas de Nazaret, sino de volver a encontrarnos con \u00c9l, no habr\u00edamos tenido otra posibilidad que buscar a los suyos para escuchar sus palabras y ver sus gestos, m\u00e1s vivos que nunca. No habr\u00edamos tenido otra posibilidad de un verdadero encuentro con \u00c9l sino en la comunidad que celebra. Por eso, la Iglesia siempre ha custodiado, como su tesoro m\u00e1s precioso, el mandato del Se\u00f1or: \u201chaced esto en memoria m\u00eda\u201d.<\/li>\n<li>Desde los inicios, la Iglesia ha sido consciente que no se trataba de una representaci\u00f3n, ni siquiera sagrada, de la Cena del Se\u00f1or: no habr\u00eda tenido ning\u00fan sentido y a nadie se le habr\u00eda ocurrido \u201cescenificar\u201d \u2013 m\u00e1s a\u00fan bajo la mirada de Mar\u00eda, la Madre del Se\u00f1or \u2013 ese excelso momento de la vida del Maestro. Desde los inicios, la Iglesia ha comprendido, iluminada por el Esp\u00edritu Santo, que aquello que era visible de Jes\u00fas, lo que se pod\u00eda ver con los ojos y tocar con las manos, sus palabras y sus gestos, lo concreto del Verbo encarnado, ha pasado a la celebraci\u00f3n de los sacramentos\u00a0<a name=\"_ftnref1\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn1\">[1]<\/a>.<\/li>\n<\/ol>\n<p><em>La Liturgia: lugar del encuentro con Cristo<\/em><\/p>\n<ol start=\"10\">\n<li>Aqu\u00ed est\u00e1 toda la poderosa belleza de la Liturgia. Si la Resurrecci\u00f3n fuera para nosotros un concepto, una idea, un pensamiento; si el Resucitado fuera para nosotros el recuerdo del recuerdo de otros, tan autorizados como los Ap\u00f3stoles, si no se nos diera tambi\u00e9n la posibilidad de un verdadero encuentro con \u00c9l, ser\u00eda como declarar concluida la novedad del Verbo hecho carne. En cambio, la Encarnaci\u00f3n, adem\u00e1s de ser el \u00fanico y novedoso acontecimiento que la historia conozca, es tambi\u00e9n el m\u00e9todo que la Sant\u00edsima Trinidad ha elegido para abrirnos el camino de la comuni\u00f3n. La fe cristiana, o es un encuentro vivo con \u00c9l, o no es.<\/li>\n<li>La Liturgia nos garantiza la posibilidad de tal encuentro. No nos sirve un vago recuerdo de la \u00faltima Cena, necesitamos estar presentes en aquella Cena, poder escuchar su voz, comer su Cuerpo y beber su Sangre: le necesitamos a \u00c9l. En la Eucarist\u00eda y en todos los Sacramentos se nos garantiza la posibilidad de encontrarnos con el Se\u00f1or Jes\u00fas y de ser alcanzados por el poder de su Pascua. El poder salv\u00edfico del sacrificio de Jes\u00fas, de cada una de sus palabras, de cada uno de sus gestos, mirada, sentimiento, nos alcanza en la celebraci\u00f3n de los Sacramentos. Yo soy Nicodemo y la Samaritana, el endemoniado de Cafarna\u00fan y el paral\u00edtico en casa de Pedro, la pecadora perdonada y la hemorroisa, la hija de Jairo y el ciego de Jeric\u00f3, Zaqueo y L\u00e1zaro; el ladr\u00f3n y Pedro, perdonados. El Se\u00f1or Jes\u00fas que\u00a0<em>inmolado, ya no vuelve a morir; y sacrificado, vive para siempre<\/em><a name=\"_ftnref2\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn2\">[2]<\/a>, contin\u00faa perdon\u00e1ndonos, cur\u00e1ndonos y salv\u00e1ndonos con el poder de los Sacramentos. A trav\u00e9s de la encarnaci\u00f3n, es el modo concreto por el que nos ama; es el modo con el que sacia esa sed de nosotros que ha declarado en la cruz(\u00a0<em>Jn<\/em>\u00a019,28).<\/li>\n<li>Nuestro primer encuentro con su Pascua es el acontecimiento que marca la vida de todos nosotros, los creyentes en Cristo: nuestro bautismo. No es una adhesi\u00f3n mental a su pensamiento o la sumisi\u00f3n a un c\u00f3digo de comportamiento impuesto por \u00c9l: es la inmersi\u00f3n en su pasi\u00f3n, muerte, resurrecci\u00f3n y ascensi\u00f3n. No es un gesto m\u00e1gico: la magia es lo contrario a la l\u00f3gica de los Sacramentos porque pretende tener poder sobre Dios y, por esa raz\u00f3n, viene del tentador. En perfecta continuidad con la Encarnaci\u00f3n, se nos da la posibilidad, en virtud de la presencia y la acci\u00f3n del Esp\u00edritu, de morir y resucitar en Cristo.<\/li>\n<li>El modo en que acontece es conmovedor. La plegaria de bendici\u00f3n del agua bautismal\u00a0<a name=\"_ftnref3\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn3\">[3]<\/a>nos revela que Dios cre\u00f3 el agua precisamente en vista del bautismo. Quiere decir que mientras Dios creaba el agua pensaba en el bautismo de cada uno de nosotros, y este pensamiento le ha acompa\u00f1ado en su actuar a lo largo de la historia de la salvaci\u00f3n cada vez que, con un designio concreto, ha querido servirse del agua. Es como si, despu\u00e9s de crearla, hubiera querido perfeccionarla para llegar a ser el agua del bautismo. Y por eso la ha querido colmar del movimiento de su Esp\u00edritu que se cern\u00eda sobre ella (cfr.\u00a0<em>G\u00e9n<\/em>\u00a01,2) para que contuviera en germen el poder de santificar; la ha utilizado para regenerar a la humanidad en el diluvio (cfr.\u00a0<em>G\u00e9n<\/em>\u00a06,1-9,29); la ha dominado separ\u00e1ndola para abrir una v\u00eda de liberaci\u00f3n en el Mar Rojo (cfr.\u00a0<em>Ex<\/em>\u00a014); la ha consagrado en el Jord\u00e1n sumergiendo la carne del Verbo, impregnada del Esp\u00edritu (cfr.\u00a0<em>Mt<\/em>\u00a03,13-17; Mc 1,9-11;\u00a0<em>Lc<\/em>\u00a03,21-22). Finalmente, la ha mezclado con la sangre de su Hijo, don del Esp\u00edritu inseparablemente unido al don de la vida y la muerte del Cordero inmolado por nosotros, y desde el costado traspasado la ha derramado sobre nosotros (\u00a0<em>Jn<\/em>\u00a019,34). En esta agua fuimos sumergidos para que, por su poder, pudi\u00e9ramos ser injertados en el Cuerpo de Cristo y, con \u00c9l, resucitar a la vida inmortal (cfr.\u00a0<em>Rom<\/em>\u00a06,1-11).<\/li>\n<\/ol>\n<p><em>La Iglesia: sacramento del Cuerpo de Cristo<\/em><\/p>\n<ol start=\"14\">\n<li>Como nos ha recordado el Concilio Vaticano II (cfr.\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, n. 5) citando la Escritura, los Padres y la Liturgia \u2013columnas de la verdadera Tradici\u00f3n\u2013\u00a0<em>del costado de Cristo dormido en la cruz brot\u00f3 el admirable sacramento de toda la Iglesia<\/em><a name=\"_ftnref4\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn4\">[4]<\/a>. El paralelismo entre el primer y el nuevo Ad\u00e1n es sorprendente: as\u00ed como del costado del primer Ad\u00e1n, tras haber dejado caer un letargo sobre \u00e9l, Dios form\u00f3 a Eva, as\u00ed del costado del nuevo Ad\u00e1n, dormido en el sue\u00f1o de la muerte, nace la nueva Eva, la Iglesia. El estupor est\u00e1 en las palabras que, podr\u00edamos imaginar, el nuevo Ad\u00e1n hace suyas mirando a la Iglesia: \u201cEsta s\u00ed que es hueso de mis huesos y carne de mi carne\u201d (\u00a0<em>G\u00e9n<\/em>\u00a02,23). Por haber cre\u00eddo en la Palabra y haber descendido en el agua del bautismo, nos hemos convertido en hueso de sus huesos, en carne de su carne.<\/li>\n<li>Sin esta incorporaci\u00f3n, no hay posibilidad de experimentar la plenitud del culto a Dios. De hecho, uno s\u00f3lo es el acto de culto perfecto y agradable al Padre, la obediencia del Hijo cuya medida es su muerte en cruz. La \u00fanica posibilidad de participar en su ofrenda es ser hijos en el Hijo. Este es el don que hemos recibido. El sujeto que act\u00faa en la Liturgia es siempre y solo Cristo-Iglesia, el Cuerpo M\u00edstico de Cristo.<\/li>\n<\/ol>\n<p><em>El sentido teol\u00f3gico de la Liturgia<\/em><\/p>\n<ol start=\"16\">\n<li>Debemos al Concilio \u2013 y al movimiento lit\u00fargico que lo ha precedido \u2013 el redescubrimiento de la comprensi\u00f3n teol\u00f3gica de la Liturgia y de su importancia en la vida de la Iglesia: los principios generales enunciados por la\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, as\u00ed como fueron fundamentales para la reforma, contin\u00faan si\u00e9ndolo para la promoci\u00f3n de la participaci\u00f3n plena, consciente, activa y fructuosa en la celebraci\u00f3n (cfr.\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, nn. 11.14), \u201cfuente primaria y necesaria de donde han de beber los fieles el esp\u00edritu verdaderamente cristiano\u201d (\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, n. 14). Con esta carta quisiera simplemente invitar a toda la Iglesia a redescubrir, custodiar y vivir la verdad y la fuerza de la celebraci\u00f3n cristiana. Quisiera que la belleza de la celebraci\u00f3n cristiana y de sus necesarias consecuencias en la vida de la Iglesia no se vieran desfiguradas por una comprensi\u00f3n superficial y reductiva de su valor o, peor a\u00fan, por su instrumentalizaci\u00f3n al servicio de alguna visi\u00f3n ideol\u00f3gica, sea cual sea. La oraci\u00f3n sacerdotal de Jes\u00fas en la \u00faltima cena para que todos sean uno (\u00a0<em>Jn<\/em>17,21), juzga todas nuestras divisiones en torno al Pan partido,\u00a0<em>sacramento de piedad, signo de unidad, v\u00ednculo de caridad<\/em>\u00a0<a name=\"_ftnref5\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn5\">[5]<\/a>.<\/li>\n<li>He advertido en varias ocasiones sobre una tentaci\u00f3n peligrosa para la vida de la Iglesia que es la \u201cmundanidad espiritual\u201d: he hablado de ella ampliamente en la Exhortaci\u00f3n\u00a0<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_exhortations\/documents\/papa-francesco_esortazione-ap_20131124_evangelii-gaudium.html#No_a_la_mundanidad_espiritual\">Evangelii gaudium<\/a><\/em>(nn. 93-97), identificando el gnosticismo y el neopelagianismo como los dos modos vinculados entre s\u00ed, que la alimentan.<\/li>\n<\/ol>\n<p>El primero reduce la fe cristiana a un subjetivismo que encierra al individuo \u201cen la inmanencia de su propia raz\u00f3n o de sus sentimientos\u201d (<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_exhortations\/documents\/papa-francesco_esortazione-ap_20131124_evangelii-gaudium.html#No_a_la_mundanidad_espiritual\">Evangelii gaudium<\/a><\/em>, n. 94).<\/p>\n<p>El segundo anula el valor de la gracia para confiar s\u00f3lo en las propias fuerzas, dando lugar a \u201cun elitismo narcisista y autoritario, donde en lugar de evangelizar lo que se hace es analizar y clasificar a los dem\u00e1s, y en lugar de facilitar el acceso a la gracia se gastan las energ\u00edas en controlar\u201d (<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_exhortations\/documents\/papa-francesco_esortazione-ap_20131124_evangelii-gaudium.html#No_a_la_mundanidad_espiritual\">Evangelii gaudium<\/a><\/em>, n. 94).<\/p>\n<p>Estas formas distorsionadas del cristianismo pueden tener consecuencias desastrosas para la vida de la Iglesia.<\/p>\n<ol start=\"18\">\n<li>Resulta evidente, en todo lo que he querido recordar anteriormente, que la Liturgia es, por su propia naturaleza, el ant\u00eddoto m\u00e1s eficaz contra estos venenos. Evidentemente, hablo de la Liturgia en su sentido teol\u00f3gico y \u2013 ya lo afirmaba P\u00edo XII \u2013 no como un\u00a0<em>ceremonial decorativo\u2026 o un mero conjunto de leyes y de preceptos\u2026<\/em>que ordena el cumplimiento de los ritos\u00a0<a name=\"_ftnref6\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn6\">[6]<\/a>.<\/li>\n<li>Si el gnosticismo nos intoxica con el veneno del subjetivismo, la celebraci\u00f3n lit\u00fargica nos libera de la prisi\u00f3n de una autorreferencialidad alimentada por la propia raz\u00f3n o sentimiento: la acci\u00f3n celebrativa no pertenece al individuo sino a Cristo-Iglesia, a la totalidad de los fieles unidos en Cristo. La Liturgia no dice \u201cyo\u201d sino \u201cnosotros\u201d, y cualquier limitaci\u00f3n a la amplitud de este \u201cnosotros\u201d es siempre demon\u00edaca. La Liturgia no nos deja solos en la b\u00fasqueda de un presunto conocimiento individual del misterio de Dios, sino que nos lleva de la mano, juntos, como asamblea, para conducirnos al misterio que la Palabra y los signos sacramentales nos revelan. Y lo hace, en coherencia con la acci\u00f3n de Dios, siguiendo el camino de la Encarnaci\u00f3n, a trav\u00e9s del lenguaje simb\u00f3lico del cuerpo, que se extiende a las cosas, al espacio y al tiempo.<\/li>\n<\/ol>\n<p><em>Redescubrir cada d\u00eda la belleza de la verdad de la celebraci\u00f3n cristiana<\/em><\/p>\n<ol start=\"20\">\n<li>Si el neopelagianismo nos intoxica con la presunci\u00f3n de una salvaci\u00f3n ganada con nuestras fuerzas, la celebraci\u00f3n lit\u00fargica nos purifica proclamando la gratuidad del don de la salvaci\u00f3n recibida en la fe. Participar en el sacrificio eucar\u00edstico no es una conquista nuestra, como si pudi\u00e9ramos presumir de ello ante Dios y ante nuestros hermanos. El inicio de cada celebraci\u00f3n me recuerda qui\u00e9n soy, pidi\u00e9ndome que confiese mi pecado e invit\u00e1ndome a rogar a la bienaventurada siempre Virgen Mar\u00eda, a los \u00e1ngeles, a los santos y a todos los hermanos y hermanas, que intercedan por m\u00ed ante el Se\u00f1or: ciertamente no somos dignos de entrar en su casa, necesitamos una palabra suya para salvarnos (cfr.\u00a0<em>Mt<\/em>8,8). No tenemos otra gloria que la cruz de nuestro Se\u00f1or Jesucristo (cfr.\u00a0<em>G\u00e1l<\/em>\u00a06,14). La Liturgia no tiene nada que ver con un moralismo asc\u00e9tico: es el don de la Pascua del Se\u00f1or que, aceptado con docilidad, hace nueva nuestra vida. No se entra en el cen\u00e1culo sino por la fuerza de atracci\u00f3n de su deseo de comer la Pascua con nosotros:\u00a0<em>Desiderio desideravi hoc Pascha manducare vobiscum, antequam patiar<\/em>\u00a0(<em>Lc<\/em>\u00a022,15).<\/li>\n<li>Sin embargo, tenemos que tener cuidado: para que el ant\u00eddoto de la Liturgia sea eficaz, se nos pide redescubrir cada d\u00eda la belleza de la verdad de la celebraci\u00f3n cristiana. Me refiero, una vez m\u00e1s, a su significado teol\u00f3gico, como ha descrito admirablemente el n. 7 de la\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>: la Liturgia es el sacerdocio de Cristo revelado y entregado a nosotros en su Pascua, presente y activo hoy a trav\u00e9s de los signos sensibles (agua, aceite, pan, vino, gestos, palabras) para que el Esp\u00edritu, sumergi\u00e9ndonos en el misterio pascual, transforme toda nuestra vida, conform\u00e1ndonos cada vez m\u00e1s con Cristo.<\/li>\n<li>El redescubrimiento continuo de la belleza de la Liturgia no es la b\u00fasqueda de un esteticismo ritual, que se complace s\u00f3lo en el cuidado de la formalidad exterior de un rito, o se satisface con una escrupulosa observancia de las r\u00fabricas. Evidentemente, esta afirmaci\u00f3n no pretende avalar, de ning\u00fan modo, la actitud contraria que confunde lo sencillo con una dejadez banal, lo esencial con la superficialidad ignorante, lo concreto de la acci\u00f3n ritual con un funcionalismo pr\u00e1ctico exagerado.<\/li>\n<li>Seamos claros: hay que cuidar todos los aspectos de la celebraci\u00f3n (espacio, tiempo, gestos, palabras, objetos, vestiduras, cantos, m\u00fasica, &#8230;) y observar todas las r\u00fabricas: esta atenci\u00f3n ser\u00eda suficiente para no robar a la asamblea lo que le corresponde, es decir, el misterio pascual celebrado en el modo ritual que la Iglesia establece. Pero, incluso, si la calidad y la norma de la acci\u00f3n celebrativa estuvieran garantizadas, esto no ser\u00eda suficiente para que nuestra participaci\u00f3n fuera plena.<\/li>\n<\/ol>\n<p><em>Asombro ante el misterio pascual, parte esencial de la acci\u00f3n lit\u00fargica<\/em><\/p>\n<ol start=\"24\">\n<li>Si faltara el asombro por el misterio pascual que se hace presente en la concreci\u00f3n de los signos sacramentales, podr\u00edamos correr el riesgo de ser realmente impermeables al oc\u00e9ano de gracia que inunda cada celebraci\u00f3n. No bastan los esfuerzos, aunque loables, para una mejor calidad de la celebraci\u00f3n, ni una llamada a la interioridad: incluso \u00e9sta corre el riesgo de quedar reducida a una subjetividad vac\u00eda si no acoge la revelaci\u00f3n del misterio cristiano. El encuentro con Dios no es fruto de una individual b\u00fasqueda interior, sino que es un acontecimiento regalado: podemos encontrar a Dios por el hecho novedoso de la Encarnaci\u00f3n que, en la \u00faltima cena, llega al extremo de querer ser comido por nosotros. \u00bfC\u00f3mo se nos puede escapar lamentablemente la fascinaci\u00f3n por la belleza de este don?<\/li>\n<li>Cuando digo asombro ante el misterio pascual, no me refiero en absoluto a lo que, me parece, se quiere expresar con la vaga expresi\u00f3n \u201csentido del misterio\u201d: a veces, entre las supuestas acusaciones contra la reforma lit\u00fargica est\u00e1 la de haberlo \u2013 se dice \u2013 eliminado de la celebraci\u00f3n. El asombro del que hablo no es una especie de desorientaci\u00f3n ante una realidad oscura o un rito enigm\u00e1tico, sino que es, por el contrario, admiraci\u00f3n ante el hecho de que el plan salv\u00edfico de Dios nos haya sido revelado en la Pascua de Jes\u00fas (cfr.\u00a0<em>Ef<\/em>1,3-14), cuya eficacia sigue lleg\u00e1ndonos en la celebraci\u00f3n de los \u201cmisterios\u201d, es decir, de los sacramentos. Sin embargo, sigue siendo cierto que la plenitud de la revelaci\u00f3n tiene, en comparaci\u00f3n con nuestra finitud humana, un exceso que nos trasciende y que tendr\u00e1 su cumplimiento al final de los tiempos, cuando vuelva el Se\u00f1or. Si el asombro es verdadero, no hay ning\u00fan riesgo de que no se perciba la alteridad de la presencia de Dios, incluso en la cercan\u00eda que la Encarnaci\u00f3n ha querido. Si la reforma hubiera eliminado ese \u201csentido del misterio\u201d, m\u00e1s que una acusaci\u00f3n ser\u00eda un m\u00e9rito. La belleza, como la verdad, siempre genera asombro y, cuando se refiere al misterio de Dios, conduce a la adoraci\u00f3n.<\/li>\n<li>El asombro es parte esencial de la acci\u00f3n lit\u00fargica porque es la actitud de quien sabe que est\u00e1 ante la peculiaridad de los gestos simb\u00f3licos; es la maravilla de quien experimenta la fuerza del s\u00edmbolo, que no consiste en referirse a un concepto abstracto, sino en contener y expresar, en su concreci\u00f3n, lo que significa.<\/li>\n<\/ol>\n<p><em>La necesidad de una seria y vital formaci\u00f3n lit\u00fargica<\/em><\/p>\n<ol start=\"27\">\n<li>Es \u00e9sta, pues, la cuesti\u00f3n fundamental: \u00bfc\u00f3mo recuperar la capacidad de vivir plenamente la acci\u00f3n lit\u00fargica? La reforma del Concilio tiene este objetivo. El reto es muy exigente, porque el hombre moderno \u2013 no en todas las culturas del mismo modo \u2013 ha perdido la capacidad de confrontarse con la acci\u00f3n simb\u00f3lica, que es una caracter\u00edstica esencial del acto lit\u00fargico.<\/li>\n<li>La posmodernidad \u2013 en la que el hombre se siente a\u00fan m\u00e1s perdido, sin referencias de ning\u00fan tipo, desprovisto de valores, porque se han vuelto indiferentes, hu\u00e9rfano de todo, en una fragmentaci\u00f3n en la que parece imposible un horizonte de sentido \u2013 sigue cargando con la pesada herencia que nos dej\u00f3 la \u00e9poca anterior, hecha de individualismo y subjetivismo (que recuerdan, una vez m\u00e1s, al pelagianismo y al gnosticismo), as\u00ed como por un espiritualismo abstracto que contradice la naturaleza misma del hombre, esp\u00edritu encarnado y, por tanto, en s\u00ed mismo capaz de acci\u00f3n y comprensi\u00f3n simb\u00f3lica.<\/li>\n<li>La Iglesia reunida en el Concilio ha querido confrontarse con la realidad de la modernidad, reafirmando su conciencia de ser sacramento de Cristo, luz de las gentes (<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19641121_lumen-gentium_sp.html\">Lumen Gentium<\/a><\/em>), poni\u00e9ndose a la escucha atenta de la palabra de Dios (<em>Dei Verbum<\/em>) y reconociendo como propios\u00a0<em>los gozos y las esperanzas<\/em>(<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19651207_gaudium-et-spes_sp.html\">Gaudium et spes<\/a><\/em>) de los hombres de hoy. Las grandes Constituciones conciliares son inseparables, y no es casualidad que esta \u00fanica gran reflexi\u00f3n del Concilio Ecum\u00e9nico \u2013 la m\u00e1s alta expresi\u00f3n de la sinodalidad de la Iglesia, de cuya riqueza estoy llamado a ser, con todos vosotros, custodio \u2013 haya partido de la Liturgia (<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>).<\/li>\n<li>Concluyendo la\u00a0<a href=\"https:\/\/www.vatican.va\/content\/paul-vi\/es\/speeches\/1963\/documents\/hf_p-vi_spe_19631204_chiusura-concilio.html\">segunda sesi\u00f3n del Concilio<\/a>(4 de diciembre de 1963) san Pablo VI se expresaba as\u00ed\u00a0<a name=\"_ftnref7\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn7\">[7]<\/a>:<\/li>\n<\/ol>\n<p>\u00abPor lo dem\u00e1s, no ha quedado sin fruto la ardua e intrincada discusi\u00f3n, puestos que uno de los temas, el primero que fue examinado, y en un cierto sentido el primero tambi\u00e9n por la excelencia intr\u00ednseca y por su importancia para la vida de la Iglesia, el de la sagrada Liturgia, ha sido terminado y es hoy promulgado por Nos solemnemente. Nuestro esp\u00edritu exulta de gozo ante este resultado. Nos rendimos en esto el homenaje conforme a la escala de valores y deberes: Dios en el primer puesto; la oraci\u00f3n, nuestra primera obligaci\u00f3n; la Liturgia, la primera fuente de la vida divina que se nos comunica, la primera escuela de nuestra vida espiritual, el primer don que podemos hacer al pueblo cristiano, que con nosotros que cree y ora, y la primera invitaci\u00f3n al mundo para que desate en oraci\u00f3n dichosa y veraz su lengua muda y sienta el inefable poder regenerador de cantar con nosotros las alabanzas divinas y las esperanzas humanas, por Cristo Se\u00f1or en el Esp\u00edritu Santo\u00bb.<\/p>\n<ol start=\"31\">\n<li>En esta carta no puedo detenerme en la riqueza de cada una de las expresiones, que dejo a vuestra meditaci\u00f3n. Si la Liturgia es \u201cla cumbre a la cual tiende la acci\u00f3n de la Iglesia y, al mismo tiempo, la fuente de donde mana toda su fuerza\u201d (<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, n. 10), comprendemos bien lo que est\u00e1 en juego en la cuesti\u00f3n lit\u00fargica. Ser\u00eda banal leer las tensiones, desgraciadamente presentes en torno a la celebraci\u00f3n, como una simple divergencia entre diferentes sensibilidades sobre una forma ritual. La problem\u00e1tica es, ante todo, eclesiol\u00f3gica. No veo c\u00f3mo se puede decir que se reconoce la validez del Concilio \u2013 aunque me sorprende un poco que un cat\u00f3lico pueda presumir de no hacerlo \u2013 y no aceptar la reforma lit\u00fargica nacida de la\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, que expresa la realidad de la Liturgia en \u00edntima conexi\u00f3n con la visi\u00f3n de la Iglesia descrita admirablemente por la\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19641121_lumen-gentium_sp.html\">Lumen Gentium<\/a><\/em>. Por ello \u2013 como expliqu\u00e9 en la carta enviada a todos los Obispos \u2013 me sent\u00ed en el deber de afirmar que \u201clos libros lit\u00fargicos promulgados por los Santos Pont\u00edfices Pablo VI y Juan Pablo II, en conformidad con los decretos del Concilio Vaticano II, como \u00fanica expresi\u00f3n de la\u00a0<em>lex orandi<\/em>del Rito Romano\u201d (Motu Proprio\u00a0<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/motu_proprio\/documents\/20210716-motu-proprio-traditionis-custodes.html\">Traditionis custodes<\/a><\/em>, art. 1).<\/li>\n<\/ol>\n<p>La no aceptaci\u00f3n de la reforma, as\u00ed como una comprensi\u00f3n superficial de la misma, nos distrae de la tarea de encontrar las respuestas a la pregunta que repito: \u00bfc\u00f3mo podemos crecer en la capacidad de vivir plenamente la acci\u00f3n lit\u00fargica? \u00bfC\u00f3mo podemos seguir asombr\u00e1ndonos de lo que ocurre ante nuestros ojos en la celebraci\u00f3n? Necesitamos una formaci\u00f3n lit\u00fargica seria y vital.<\/p>\n<ol start=\"32\">\n<li>Volvamos de nuevo al Cen\u00e1culo de Jerusal\u00e9n: en la ma\u00f1ana de Pentecost\u00e9s naci\u00f3 la Iglesia, c\u00e9lula inicial de la nueva humanidad. S\u00f3lo la comunidad de hombres y mujeres reconciliados, porque han sido perdonados; vivos, porque \u00c9l est\u00e1 vivo; verdaderos, porque est\u00e1n habitados por el Esp\u00edritu de la verdad, puede abrir el angosto espacio del individualismo espiritual.<\/li>\n<li>Es la comunidad de Pentecost\u00e9s la que puede partir el Pan con la certeza de que el Se\u00f1or est\u00e1 vivo, resucitado de entre los muertos, presente con su palabra, con sus gestos, con la ofrenda de su Cuerpo y de su Sangre. Desde aquel momento, la celebraci\u00f3n se convierte en el lugar privilegiado, no el \u00fanico, del encuentro con \u00c9l. Sabemos que, s\u00f3lo gracias a este encuentro, el hombre llega a ser plenamente hombre. S\u00f3lo la Iglesia de Pentecost\u00e9s puede concebir al hombre como persona, abierto a una relaci\u00f3n plena con Dios, con la creaci\u00f3n y con los hermanos.<\/li>\n<li>Aqu\u00ed se plantea la cuesti\u00f3n decisiva de la formaci\u00f3n lit\u00fargica. Dice Guardini: \u201cAs\u00ed se perfila tambi\u00e9n la primera tarea pr\u00e1ctica: sostenidos por esta transformaci\u00f3n interior de nuestro tiempo, debemos aprender nuevamente a situarnos ante la relaci\u00f3n religiosa como hombres en sentido pleno\u00a0<a name=\"_ftnref8\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn8\">[8]<\/a>. Esto es lo que hace posible la Liturgia, en esto es en lo que nos debemos formar. El propio Guardini no duda en afirmar que, sin formaci\u00f3n lit\u00fargica, \u201clas reformas en el rito y en el texto no sirven de mucho\u201d\u00a0<a name=\"_ftnref9\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn9\">[9]<\/a>. No pretendo ahora tratar exhaustivamente el riqu\u00edsimo tema de la formaci\u00f3n lit\u00fargica: s\u00f3lo quiero ofrecer algunos puntos de reflexi\u00f3n. Creo que podemos distinguir dos aspectos: la formaci\u00f3n para la Liturgia y la formaci\u00f3n desde la Liturgia. El primero est\u00e1 en funci\u00f3n del segundo, que es esencial.<\/li>\n<li>Es necesario encontrar cauces para una formaci\u00f3n como estudio de la Liturgia: a partir del movimiento lit\u00fargico, se ha hecho mucho en este sentido, con valiosas aportaciones de muchos estudiosos e instituciones acad\u00e9micas. Sin embargo, es necesario difundir este conocimiento fuera del \u00e1mbito acad\u00e9mico, de forma accesible, para que todo creyente crezca en el conocimiento del sentido teol\u00f3gico de la Liturgia \u2013\u00e9sta es la cuesti\u00f3n decisiva y fundante de todo conocimiento y de toda pr\u00e1ctica lit\u00fargica\u2013, as\u00ed como en el desarrollo de la celebraci\u00f3n cristiana, adquiriendo la capacidad de comprender los textos eucol\u00f3gicos, los dinamismos rituales y su valor antropol\u00f3gico.<\/li>\n<li>Pienso en la normalidad de nuestras asambleas que se re\u00fanen para celebrar la Eucarist\u00eda el d\u00eda del Se\u00f1or, domingo tras domingo, Pascua tras Pascua, en momentos concretos de la vida de las personas y de las comunidades, en diferentes edades de la vida: los ministros ordenados realizan una acci\u00f3n pastoral de primera importancia cuando llevan de la mano a los fieles bautizados para conducirlos a la repetida experiencia de la Pascua. Recordemos siempre que es la Iglesia, Cuerpo de Cristo, el sujeto celebrante, no s\u00f3lo el sacerdote. El conocimiento que proviene del estudio es s\u00f3lo el primer paso para poder entrar en el misterio celebrado. Es evidente que, para poder guiar a los hermanos y a las hermanas, los ministros que presiden la asamblea deben conocer el camino, tanto por haberlo estudiado en el mapa de la ciencia teol\u00f3gica, como por haberlo frecuentado en la pr\u00e1ctica de una experiencia de fe viva, alimentada por la oraci\u00f3n, ciertamente no s\u00f3lo como un compromiso que cumplir. En el d\u00eda de la ordenaci\u00f3n, todo presb\u00edtero siente decir a su obispo: \u00abConsidera lo que realizas e imita lo que conmemoras, y conforma tu vida con el misterio de la cruz del Se\u00f1or\u00bb\u00a0<a name=\"_ftnref10\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn10\">[10]<\/a>.<\/li>\n<li>La configuraci\u00f3n del estudio de la Liturgia en los seminarios debe tener en cuenta tambi\u00e9n la extraordinaria capacidad que la celebraci\u00f3n tiene en s\u00ed misma para ofrecer una visi\u00f3n org\u00e1nica del conocimiento teol\u00f3gico. Cada disciplina de la teolog\u00eda, desde su propia perspectiva, debe mostrar su \u00edntima conexi\u00f3n con la Liturgia, en virtud de la cual se revela y realiza la unidad de la formaci\u00f3n sacerdotal (cfr.\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, n. 16). Una configuraci\u00f3n lit\u00fargico-sapiencial de la formaci\u00f3n teol\u00f3gica en los seminarios tendr\u00eda ciertamente efectos positivos, tambi\u00e9n en la acci\u00f3n pastoral. No hay ning\u00fan aspecto de la vida eclesial que no encuentre su culmen y su fuente en ella. La pastoral de conjunto, org\u00e1nica, integrada, m\u00e1s que ser el resultado de la elaboraci\u00f3n de complicados programas, es la consecuencia de situar la celebraci\u00f3n eucar\u00edstica dominical, fundamento de la comuni\u00f3n, en el centro de la vida de la comunidad. La comprensi\u00f3n teol\u00f3gica de la Liturgia no permite, de ninguna manera, entender estas palabras como si todo se redujera al aspecto cultual. Una celebraci\u00f3n que no evangeliza, no es aut\u00e9ntica, como no lo es un anuncio que no lleva al encuentro con el Resucitado en la celebraci\u00f3n: ambos, pues, sin el testimonio de la caridad, son como un metal que resuena o un c\u00edmbalo que aturde (cfr. 1<em>Cor<\/em>13,1).<\/li>\n<li>Para los ministros y para todos los bautizados, la formaci\u00f3n lit\u00fargica, en su primera acepci\u00f3n, no es algo que se pueda conquistar de una vez para siempre: puesto que el don del misterio celebrado supera nuestra capacidad de conocimiento, este compromiso deber\u00e1 ciertamente acompa\u00f1ar la formaci\u00f3n permanente de cada uno, con la humildad de los peque\u00f1os, actitud que abre al asombro.<\/li>\n<li>Una \u00faltima observaci\u00f3n sobre los seminarios: adem\u00e1s del estudio, deben ofrecer tambi\u00e9n la oportunidad de experimentar una celebraci\u00f3n, no s\u00f3lo ejemplar desde el punto de vista ritual, sino aut\u00e9ntica, vital, que permita vivir esa verdadera comuni\u00f3n con Dios, a la cual debe tender tambi\u00e9n el conocimiento teol\u00f3gico. S\u00f3lo la acci\u00f3n del Esp\u00edritu puede perfeccionar nuestro conocimiento del misterio de Dios, que no es cuesti\u00f3n de comprensi\u00f3n mental, sino de una relaci\u00f3n que toca la vida. Esta experiencia es fundamental para que, una vez sean ministros ordenados, puedan acompa\u00f1ar a las comunidades en el mismo camino de conocimiento del misterio de Dios, que es misterio de amor.<\/li>\n<li>Esta \u00faltima consideraci\u00f3n nos lleva a reflexionar sobre el segundo significado con el que podemos entender la expresi\u00f3n \u201cformaci\u00f3n lit\u00fargica\u201d. Me refiero al ser formados, cada uno seg\u00fan su vocaci\u00f3n, por la participaci\u00f3n en la celebraci\u00f3n lit\u00fargica. Incluso el conocimiento del estudio que acabo de mencionar, para que no se convierta en racionalismo, debe estar en funci\u00f3n de la puesta en pr\u00e1ctica de la acci\u00f3n formativa de la Liturgia en cada creyente en Cristo.<\/li>\n<li>De cuanto hemos dicho sobre la naturaleza de la Liturgia, resulta evidente que el conocimiento del misterio de Cristo, cuesti\u00f3n decisiva para nuestra vida, no consiste en una asimilaci\u00f3n mental de una idea, sino en una real implicaci\u00f3n existencial con su persona. En este sentido, la Liturgia no tiene que ver con el \u201cconocimiento\u201d, y su finalidad no es primordialmente pedag\u00f3gica (aunque tiene un gran valor pedag\u00f3gico: cfr.\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a>,<\/em>n. 33) sino que es la alabanza, la acci\u00f3n de gracias por la Pascua del Hijo, cuya fuerza salvadora llega a nuestra vida. La celebraci\u00f3n tiene que ver con la realidad de nuestro ser d\u00f3ciles a la acci\u00f3n del Esp\u00edritu, que act\u00faa en ella, hasta que Cristo se forme en nosotros (cfr.\u00a0<em>G\u00e1l<\/em>\u00a04,19). La plenitud de nuestra formaci\u00f3n es la conformaci\u00f3n con Cristo. Repito: no se trata de un proceso mental y abstracto, sino de llegar a ser \u00c9l. Esta es la finalidad para la cual se ha dado el Esp\u00edritu, cuya acci\u00f3n es siempre y \u00fanicamente confeccionar el Cuerpo de Cristo. Es as\u00ed con el pan eucar\u00edstico, es as\u00ed para todo bautizado llamado a ser, cada vez m\u00e1s, lo que recibi\u00f3 como don en el bautismo, es decir, ser miembro del Cuerpo de Cristo. Le\u00f3n Magno escribe: \u00abNuestra participaci\u00f3n en el Cuerpo y la Sangre de Cristo no tiende a otra cosa sino a convertirnos en lo que comemos\u00bb\u00a0<a name=\"_ftnref11\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn11\">[11]<\/a>.<\/li>\n<li>Esta implicaci\u00f3n existencial tiene lugar \u2013 en continuidad y coherencia con el m\u00e9todo de la Encarnaci\u00f3n \u2013 por v\u00eda sacramental. La Liturgia est\u00e1 hecha de cosas que son exactamente lo contrario de abstracciones espirituales: pan, vino, aceite, agua, perfume, fuego, ceniza, piedra, tela, colores, cuerpo, palabras, sonidos, silencios, gestos, espacio, movimiento, acci\u00f3n, orden, tiempo, luz. Toda la creaci\u00f3n es manifestaci\u00f3n del amor de Dios: desde que ese mismo amor se ha manifestado en plenitud en la cruz de Jes\u00fas, toda la creaci\u00f3n es atra\u00edda por \u00c9l. Es toda la creaci\u00f3n la que es asumida para ser puesta al servicio del encuentro con el Verbo encarnado, crucificado, muerto, resucitado, ascendido al Padre. As\u00ed como canta la plegaria sobre el agua para la fuente bautismal, al igual que la del aceite para el sagrado crisma y las palabras de la presentaci\u00f3n del pan y el vino, frutos de la tierra y del trabajo del hombre.<\/li>\n<li>La Liturgia da gloria a Dios no porque podamos a\u00f1adir algo a la belleza de la luz inaccesible en la que \u00c9l habita (cfr. 1\u00a0<em>Tim<\/em>6,16) o a la perfecci\u00f3n del canto ang\u00e9lico, que resuena eternamente en las moradas celestiales. La Liturgia da gloria a Dios porque nos permite, aqu\u00ed en la tierra, ver a Dios en la celebraci\u00f3n de los misterios y, al verlo, revivir por su Pascua: nosotros, que est\u00e1bamos muertos por los pecados, hemos revivido por la gracia con Cristo (cfr.\u00a0<em>Ef<\/em>\u00a02,5), somos la gloria de Dios. Ireneo,\u00a0<em>doctor unitatis<\/em>, nos lo recuerda: \u00abLa gloria de Dios es el hombre vivo, y la vida del hombre consiste en la visi\u00f3n de Dios: si ya la revelaci\u00f3n de Dios a trav\u00e9s de la creaci\u00f3n da vida a todos los seres que viven en la tierra, \u00a1cu\u00e1nto m\u00e1s la manifestaci\u00f3n del Padre a trav\u00e9s del Verbo es causa de vida para los que ven a Dios!\u00bb\u00a0<a name=\"_ftnref12\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn12\">[12]<\/a>.<\/li>\n<li>Guardini escribe: \u00abCon esto se delinea la primera tarea del trabajo de la formaci\u00f3n lit\u00fargica: el hombre ha de volver a ser capaz de s\u00edmbolos\u00bb\u00a0<a name=\"_ftnref13\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn13\">[13]<\/a>. Esta tarea concierne a todos, ministros ordenados y fieles. La tarea no es f\u00e1cil, porque el hombre moderno es analfabeto, ya no sabe leer los s\u00edmbolos, apenas conoce de su existencia. Esto tambi\u00e9n ocurre con el s\u00edmbolo de nuestro cuerpo. Es un s\u00edmbolo porque es la uni\u00f3n \u00edntima del alma y el cuerpo, visibilidad del alma espiritual en el orden de lo corp\u00f3reo, y en ello consiste la unicidad humana, la especificidad de la persona irreductible a cualquier otra forma de ser vivo. Nuestra apertura a lo trascendente, a Dios, es constitutiva: no reconocerla nos lleva inevitablemente a un no conocimiento, no s\u00f3lo de Dios, sino tambi\u00e9n de nosotros mismos. No hay m\u00e1s que ver la forma parad\u00f3jica en que se trata al cuerpo, o bien tratado casi obsesivamente en pos del mito de la eterna juventud, o bien reducido a una materialidad a la cual se le niega toda dignidad. El hecho es que no se puede dar valor al cuerpo s\u00f3lo desde el cuerpo. Todo s\u00edmbolo es a la vez poderoso y fr\u00e1gil: si no se respeta, si no se trata como lo que es, se rompe, pierde su fuerza, se vuelve insignificante.<\/li>\n<\/ol>\n<p>Ya no tenemos la mirada de San Francisco, que miraba al sol \u2013al que llamaba hermano porque as\u00ed lo sent\u00eda \u2013, lo ve\u00eda\u00a0<em>bellu e radiante cum grande splendore<\/em>\u00a0y, lleno de asombro, cantaba:\u00a0<em>de te Altissimu, porta significatione<\/em>.\u00a0<a name=\"_ftnref14\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn14\">[14]<\/a>\u00a0Haber perdido la capacidad de comprender el valor simb\u00f3lico del cuerpo y de toda criatura hace que el lenguaje simb\u00f3lico de la Liturgia sea casi inaccesible para el hombre moderno. No se trata, sin embargo, de renunciar a ese lenguaje: no se puede renunciar a \u00e9l porque es el que la Sant\u00edsima Trinidad ha elegido para llegar a nosotros en la carne del Verbo. Se trata m\u00e1s bien de recuperar la capacidad de plantear y comprender los s\u00edmbolos de la Liturgia. No hay que desesperar, porque en el hombre esta dimensi\u00f3n, como acabo de decir, es constitutiva y, a pesar de los males del materialismo y del espiritualismo \u2013 ambos negaci\u00f3n de la unidad cuerpo y alma \u2013, est\u00e1 siempre dispuesta a reaparecer, como toda verdad.<\/p>\n<ol start=\"45\">\n<li>Entonces, la pregunta que nos hacemos es \u00bfc\u00f3mo volver a ser capaces de s\u00edmbolos? \u00bfC\u00f3mo volver a saber leerlos para vivirlos? Sabemos muy bien que la celebraci\u00f3n de los sacramentos es \u2013 por la gracia de Dios \u2013 eficaz en s\u00ed misma (<em>ex opere operato<\/em>), pero esto no garantiza una plena implicaci\u00f3n de las personas sin un modo adecuado de situarse frente al lenguaje de la celebraci\u00f3n. La lectura simb\u00f3lica no es una cuesti\u00f3n de conocimiento mental, de adquisici\u00f3n de conceptos, sino una experiencia vital.<\/li>\n<li>Ante todo, debemos recuperar la confianza en la creaci\u00f3n. Con esto quiero decir que las cosas \u2013 con las cuales \u201cse hacen\u201d los sacramentos \u2013 vienen de Dios, est\u00e1n orientadas a \u00c9l y han sido asumidas por \u00c9l, especialmente con la encarnaci\u00f3n, para que pudieran convertirse en instrumentos de salvaci\u00f3n, veh\u00edculos del Esp\u00edritu, canales de gracia. Aqu\u00ed se advierte la distancia, tanto de la visi\u00f3n materialista, como espiritualista. Si las cosas creadas son parte irrenunciable de la acci\u00f3n sacramental que lleva a cabo nuestra salvaci\u00f3n, debemos situarnos ante ellas con una mirada nueva, no superficial, respetuosa, agradecida. Desde el principio, contienen la semilla de la gracia santificante de los sacramentos.<\/li>\n<li>Otra cuesti\u00f3n decisiva \u2013 reflexionando de nuevo sobre c\u00f3mo nos forma la Liturgia \u2013 es la educaci\u00f3n necesaria para adquirir la actitud interior, que nos permita situar y comprender los s\u00edmbolos lit\u00fargicos. Lo expreso de forma sencilla. Pienso en los padres y, m\u00e1s a\u00fan, en los abuelos, pero tambi\u00e9n en nuestros p\u00e1rrocos y catequistas. Muchos de nosotros aprendimos de ellos el poder de los gestos lit\u00fargicos, como la se\u00f1al de la cruz, el arrodillarse o las f\u00f3rmulas de nuestra fe. Quiz\u00e1s puede que no tengamos un vivo recuerdo de ello, pero podemos imaginar f\u00e1cilmente el gesto de una mano m\u00e1s grande que toma la peque\u00f1a mano de un ni\u00f1o y acompa\u00f1\u00e1ndola lentamente mientras traza, por primera vez, la se\u00f1al de nuestra salvaci\u00f3n. El movimiento va acompa\u00f1ado de las palabras, tambi\u00e9n lentas, como para apropiarse de cada instante de ese gesto, de todo el cuerpo: \u00abEn el nombre del Padre&#8230; y del Hijo&#8230; y del Esp\u00edritu Santo&#8230; Am\u00e9n\u00bb. Para despu\u00e9s soltar la mano del ni\u00f1o y, dispuesto a acudir en su ayuda, ver c\u00f3mo repite \u00e9l solo ese gesto ya entregado, como si fuera un h\u00e1bito que crecer\u00e1 con \u00e9l, visti\u00e9ndolo de la manera que s\u00f3lo el Esp\u00edritu conoce. A partir de ese momento, ese gesto, su fuerza simb\u00f3lica, nos pertenece o, mejor dicho, pertenecemos a ese gesto, nos da forma, somos formados por \u00e9l. No es necesario hablar demasiado, no es necesario haber entendido todo sobre ese gesto: es necesario ser peque\u00f1o, tanto al entregarlo, como al recibirlo. El resto es obra del Esp\u00edritu. As\u00ed hemos sido iniciados en el lenguaje simb\u00f3lico. No podemos permitir que nos roben esta riqueza. A medida que crecemos, podemos tener m\u00e1s medios para comprender, pero siempre con la condici\u00f3n de seguir siendo peque\u00f1os.<\/li>\n<\/ol>\n<p><em>Ars celebrandi<\/em><\/p>\n<ol start=\"48\">\n<li>Un modo para custodiar y para crecer en la comprensi\u00f3n vital de los s\u00edmbolos de la Liturgia es, ciertamente, cuidar el arte de celebrar. Esta expresi\u00f3n tambi\u00e9n es objeto de diferentes interpretaciones. Se entiende m\u00e1s claramente teniendo en cuenta el sentido teol\u00f3gico de la Liturgia descrito en el n\u00famero 7 de\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, al cual nos hemos referido varias veces. El\u00a0<em>ars celebrandi<\/em>no puede reducirse a la mera observancia de un aparato de r\u00fabricas, ni tampoco puede pensarse en una fantasiosa \u2013 a veces salvaje \u2013 creatividad sin reglas. El rito es en s\u00ed mismo una norma, y la norma nunca es un fin en s\u00ed misma, sino que siempre est\u00e1 al servicio de la realidad superior que quiere custodiar.<\/li>\n<li>Como cualquier arte, requiere diferentes conocimientos.<\/li>\n<\/ol>\n<p>En primer lugar, la comprensi\u00f3n del dinamismo que describe la Liturgia. El momento de la acci\u00f3n celebrativa es el lugar donde, a trav\u00e9s del memorial, se hace presente el misterio pascual para que los bautizados, en virtud de su participaci\u00f3n, puedan experimentarlo en su vida: sin esta comprensi\u00f3n, se cae f\u00e1cilmente en el \u201cexteriorismo\u201d (m\u00e1s o menos refinado) y en el rubricismo (m\u00e1s o menos r\u00edgido).<\/p>\n<p>Es necesario, pues, conocer c\u00f3mo act\u00faa el Esp\u00edritu Santo en cada celebraci\u00f3n: el arte de celebrar debe estar en sinton\u00eda con la acci\u00f3n del Esp\u00edritu. S\u00f3lo as\u00ed se librar\u00e1 de los subjetivismos, que son el resultado de la prevalencia de las sensibilidades individuales, y de los culturalismos, que son incorporaciones sin criterio de elementos culturales, que nada tienen que ver con un correcto proceso de inculturaci\u00f3n.<\/p>\n<p>Por \u00faltimo, es necesario conocer la din\u00e1mica del lenguaje simb\u00f3lico, su peculiaridad, su eficacia.<\/p>\n<ol start=\"50\">\n<li>De estas breves observaciones se desprende que el arte de celebrar no se puede improvisar. Como cualquier arte, requiere una aplicaci\u00f3n asidua. Un artesano s\u00f3lo necesita la t\u00e9cnica; un artista, adem\u00e1s de los conocimientos t\u00e9cnicos, no puede carecer de inspiraci\u00f3n, que es una forma positiva de posesi\u00f3n: el verdadero artista no posee un arte, ni es pose\u00eddo por \u00e9l. Uno no aprende el arte de celebrar porque asista a un curso de oratoria o de t\u00e9cnicas de comunicaci\u00f3n persuasiva (no juzgo las intenciones, veo los efectos). Toda herramienta puede ser \u00fatil, pero siempre debe estar sujeta a la naturaleza de la Liturgia y a la acci\u00f3n del Esp\u00edritu. Es necesaria una dedicaci\u00f3n diligente a la celebraci\u00f3n, dejando que la propia celebraci\u00f3n nos transmita su arte. Guardini escribe: \u00abDebemos darnos cuenta de lo profundamente arraigados que estamos todav\u00eda en el individualismo y el subjetivismo, de lo poco acostumbrados que estamos a la llamada de las cosas grandes y de lo peque\u00f1a que es la medida de nuestra vida religiosa. Hay que despertar el sentido de la grandeza de la oraci\u00f3n, la voluntad de implicar tambi\u00e9n nuestra existencia en ella. Pero el camino hacia estas metas es la disciplina, la renuncia a un sentimentalismo blando; un trabajo serio, realizado en obediencia a la Iglesia, en relaci\u00f3n con nuestro ser y nuestro comportamiento religioso\u00bb\u00a0<a name=\"_ftnref15\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn15\">[15]<\/a>. As\u00ed es como se aprende el arte de la celebraci\u00f3n.<\/li>\n<li>Al hablar de este tema, podemos pensar que s\u00f3lo concierne a los ministros ordenados que ejercen el servicio de la presidencia. En realidad, es una actitud a la que est\u00e1n llamados a vivir todos los bautizados. Pienso en todos los gestos y palabras que pertenecen a la asamblea: reunirse, caminar en procesi\u00f3n, sentarse, estar de pie, arrodillarse, cantar, estar en silencio, aclamar, mirar, escuchar. Son muchas las formas en que la asamblea,\u00a0<em>como un solo hombre\u00a0<\/em>(<em>Neh<\/em>8,1), participa en la celebraci\u00f3n. Realizar todos juntos el mismo gesto, hablar todos a la vez, transmite a los individuos la fuerza de toda la asamblea. Es una uniformidad que no s\u00f3lo no mortifica, sino que, por el contrario, educa a cada fiel a descubrir la aut\u00e9ntica singularidad de su personalidad, no con actitudes individualistas, sino siendo conscientes de ser un solo cuerpo. No se trata de tener que seguir un protocolo lit\u00fargico: se trata m\u00e1s bien de una \u201cdisciplina\u201d \u2013 en el sentido utilizado por Guardini \u2013 que, si se observa con autenticidad, nos forma: son gestos y palabras que ponen orden en nuestro mundo interior, haci\u00e9ndonos experimentar sentimientos, actitudes, comportamientos. No son el enunciado de un ideal en el que inspirarnos, sino una acci\u00f3n que implica al cuerpo en su totalidad, es decir, ser unidad de alma y cuerpo.<\/li>\n<li>Entre los gestos rituales que pertenecen a toda la asamblea, el silencio ocupa un lugar de absoluta importancia. Varias veces se prescribe expresamente en las r\u00fabricas: toda la celebraci\u00f3n eucar\u00edstica est\u00e1 inmersa en el silencio que precede a su inicio y marca cada momento de su desarrollo ritual. En efecto, est\u00e1 presente en el acto penitencial; despu\u00e9s de la invitaci\u00f3n a la oraci\u00f3n; en la Liturgia de la Palabra (antes de las lecturas, entre las lecturas y despu\u00e9s de la homil\u00eda); en la plegaria eucar\u00edstica; despu\u00e9s de la comuni\u00f3n\u00a0<a name=\"_ftnref16\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn16\">[16]<\/a>. No es un refugio para esconderse en un aislamiento intimista, padeciendo la ritualidad como si fuera una distracci\u00f3n: tal silencio estar\u00eda en contradicci\u00f3n con la esencia misma de la celebraci\u00f3n. El silencio lit\u00fargico es mucho m\u00e1s: es el s\u00edmbolo de la presencia y la acci\u00f3n del Esp\u00edritu Santo que anima toda la acci\u00f3n celebrativa, por lo que, a menudo, constituye la culminaci\u00f3n de una secuencia ritual. Precisamente porque es un s\u00edmbolo del Esp\u00edritu, tiene el poder de expresar su acci\u00f3n multiforme. As\u00ed, retomando los momentos que he recordado anteriormente, el silencio mueve al arrepentimiento y al deseo de conversi\u00f3n; suscita la escucha de la Palabra y la oraci\u00f3n; dispone a la adoraci\u00f3n del Cuerpo y la Sangre de Cristo; sugiere a cada uno, en la intimidad de la comuni\u00f3n, lo que el Esp\u00edritu quiere obrar en nuestra vida para conformarnos con el Pan partido. Por eso, estamos llamados a realizar con extremo cuidado el gesto simb\u00f3lico del silencio: en \u00e9l nos da forma el Esp\u00edritu.<\/li>\n<li>Cada gesto y cada palabra contienen una acci\u00f3n precisa que es siempre nueva, porque encuentra un momento siempre nuevo en nuestra vida. Permitidme explicarlo con un sencillo ejemplo. Nos arrodillamos para pedir perd\u00f3n; para doblegar nuestro orgullo; para entregar nuestras l\u00e1grimas a Dios; para suplicar su intervenci\u00f3n; para agradecerle un don recibido: es siempre el mismo gesto, que expresa esencialmente nuestra peque\u00f1ez ante Dios. Sin embargo, realizado en diferentes momentos de nuestra vida, modela nuestra profunda interioridad y posteriormente se manifiesta externamente en nuestra relaci\u00f3n con Dios y con nuestros hermanos. Arrodillarse debe hacerse tambi\u00e9n con arte, es decir, con plena conciencia de su significado simb\u00f3lico y de la necesidad que tenemos de expresar, mediante este gesto, nuestro modo de estar en presencia del Se\u00f1or. Si todo esto es cierto para este simple gesto, \u00bfcu\u00e1nto m\u00e1s para la celebraci\u00f3n de la Palabra? \u00bfQu\u00e9 arte estamos llamados a aprender al proclamar la Palabra, al escucharla, al hacerla inspiraci\u00f3n de nuestra oraci\u00f3n, al hacer que se haga vida? Todo ello merece el m\u00e1ximo cuidado, no formal, exterior, sino vital, interior, porque cada gesto y cada palabra de la celebraci\u00f3n expresada con \u201carte\u201d forma la personalidad cristiana del individuo y de la comunidad.<\/li>\n<li>Si bien es cierto que el\u00a0<em>ars celebrandi<\/em>concierne a toda la asamblea que celebra, no es menos cierto que los ministros ordenados deben cuidarlo especialmente. Visitando comunidades cristianas he comprobado, a menudo, que su forma de vivir la celebraci\u00f3n est\u00e1 condicionada \u2013 para bien, y desgraciadamente tambi\u00e9n para mal \u2013 por la forma en que su p\u00e1rroco preside la asamblea. Podr\u00edamos decir que existen diferentes \u201cmodelos\u201d de presidencia. He aqu\u00ed una posible lista de actitudes que, aunque opuestas, caracterizan a la presidencia de forma ciertamente inadecuada: rigidez austera o creatividad exagerada; misticismo espiritualizador o funcionalismo pr\u00e1ctico; prisa precipitada o lentitud acentuada; descuido desali\u00f1ado o refinamiento excesivo; afabilidad sobreabundante o impasibilidad hier\u00e1tica. A pesar de la amplitud de este abanico, creo que la inadecuaci\u00f3n de estos modelos tiene una ra\u00edz com\u00fan: un exagerado personalismo en el estilo celebrativo que, en ocasiones, expresa una mal disimulada man\u00eda de protagonismo. Esto suele ser m\u00e1s evidente cuando nuestras celebraciones se difunden en red, cosa que no siempre es oportuno y sobre la que deber\u00edamos reflexionar. Eso s\u00ed, no son estas las actitudes m\u00e1s extendidas, pero las asambleas son objeto de ese \u201cmaltrato\u201d frecuentemente.<\/li>\n<li>Se podr\u00eda decir mucho sobre la importancia y el cuidado de la presidencia. En varias ocasiones me he detenido en la exigente tarea de la homil\u00eda\u00a0<a name=\"_ftnref17\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn17\">[17]<\/a>. Me limitar\u00e9 ahora a algunas consideraciones m\u00e1s amplias, queriendo, de nuevo, reflexionar con vosotros sobre c\u00f3mo somos formados por la Liturgia. Pienso en la normalidad de las Misas dominicales en nuestras comunidades: me refiero, pues, a los presb\u00edteros, pero impl\u00edcitamente a todos los ministros ordenados.<\/li>\n<li>El presb\u00edtero vive su participaci\u00f3n propia durante la celebraci\u00f3n en virtud del don recibido en el sacramento del Orden: esta tipolog\u00eda se expresa precisamente en la presidencia. Como todos los oficios que est\u00e1 llamado a desempe\u00f1ar, \u00e9ste no es, primariamente, una tarea asignada por la comunidad, sino la consecuencia de la efusi\u00f3n del Esp\u00edritu Santo recibida en la ordenaci\u00f3n, que le capacita para esta tarea. El presb\u00edtero tambi\u00e9n es formado al presidir la asamblea que celebra.<\/li>\n<li>Para que este servicio se haga bien \u2013 con arte \u2013 es de fundamental importancia que el presb\u00edtero tenga, ante todo, la viva conciencia de ser, por misericordia, una presencia particular del Resucitado. El ministro ordenado es en s\u00ed mismo uno de los modos de presencia del Se\u00f1or que hacen que la asamblea cristiana sea \u00fanica, diferente de cualquier otra (cfr.\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a>,<\/em>n. 7). Este hecho da profundidad \u201csacramental\u201d \u2013en sentido amplio\u2013 a todos los gestos y palabras de quien preside. La asamblea tiene derecho a poder sentir en esos gestos y palabras el deseo que tiene el Se\u00f1or, hoy como en la \u00faltima cena, de seguir comiendo la Pascua con nosotros. Por tanto, el Resucitado es el protagonista, y no nuestra inmadurez, que busca asumir un papel, una actitud y un modo de presentarse, que no le corresponde. El propio presb\u00edtero se ve sobrecogido por este deseo de comuni\u00f3n que el Se\u00f1or tiene con cada uno: es como si estuviera colocado entre el coraz\u00f3n ardiente de amor de Jes\u00fas y el coraz\u00f3n de cada creyente, objeto de su amor. Presidir la Eucarist\u00eda es sumergirse en el horno del amor de Dios. Cuando se comprende o, incluso, se intuye esta realidad, ciertamente ya no necesitamos un\u00a0<em>directorio<\/em>\u00a0que nos dicte el adecuado comportamiento. Si lo necesitamos, es\u00a0<em>por la dureza de nuestro coraz\u00f3n<\/em>. La norma m\u00e1s excelsa y, por tanto, m\u00e1s exigente, es la realidad de la propia celebraci\u00f3n eucar\u00edstica, que selecciona las palabras, los gestos, los sentimientos, haci\u00e9ndonos comprender si son o no adecuados a la tarea que han de desempe\u00f1ar. Evidentemente, esto tampoco se puede improvisar: es un arte, requiere la aplicaci\u00f3n del sacerdote, es decir, la frecuencia asidua del fuego del amor que el Se\u00f1or vino a traer a la tierra (cfr.\u00a0<em>Lc<\/em>\u00a012,49).<\/li>\n<li>Cuando la primera comunidad parte el pan en obediencia al mandato del Se\u00f1or, lo hace bajo la mirada de Mar\u00eda, que acompa\u00f1a los primeros pasos de la Iglesia: \u201cperseveraban un\u00e1nimes en la oraci\u00f3n, junto con algunas mujeres y Mar\u00eda, la madre de Jes\u00fas\u201d (<em>Hch<\/em>1,14). La Virgen Madre \u201csupervisa\u201d los gestos de su Hijo encomendados a los Ap\u00f3stoles. Como ha conservado en su seno al Verbo hecho carne, despu\u00e9s de acoger las palabras del \u00e1ngel Gabriel, la Virgen conserva tambi\u00e9n ahora en el seno de la Iglesia aquellos gestos que conforman el cuerpo de su Hijo. El presb\u00edtero, que en virtud del don recibido por el sacramento del Orden repite esos gestos, es custodiado en las entra\u00f1as de la Virgen. \u00bfNecesitamos una norma que nos diga c\u00f3mo comportarnos?<\/li>\n<li>Convertidos en instrumentos para que arda en la tierra el fuego de su amor, custodiados en las entra\u00f1as de Mar\u00eda, Virgen hecha Iglesia (como cantaba san Francisco), los presb\u00edteros se dejan modelar por el Esp\u00edritu que quiere llevar a t\u00e9rmino la obra que comenz\u00f3 en su ordenaci\u00f3n. La acci\u00f3n del Esp\u00edritu les ofrece la posibilidad de ejercer la presidencia de la asamblea eucar\u00edstica con el temor de Pedro, consciente de su condici\u00f3n de pecador (cfr.\u00a0<em>Lc<\/em>5,1-11), con la humildad fuerte del siervo sufriente (cfr.\u00a0<em>Is<\/em>\u00a042 ss), con el deseo de \u201cser comido\u201d\u201dpor el pueblo que se les conf\u00eda en el ejercicio diario de su ministerio.<\/li>\n<li>La propia celebraci\u00f3n educa a esta cualidad de la presidencia; repetimos, no es una adhesi\u00f3n mental, aunque toda nuestra mente, as\u00ed como nuestra sensibilidad, est\u00e9n implicadas en ella. El presb\u00edtero est\u00e1, por tanto, formado para presidir mediante las palabras y los gestos que la Liturgia pone en sus labios y en sus manos.<\/li>\n<\/ol>\n<p>No se sienta en un trono\u00a0<a name=\"_ftnref18\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn18\">[18]<\/a>, porque el Se\u00f1or reina con la humildad de quien sirve.<\/p>\n<p>No roba la centralidad del altar,\u00a0<em>signo de Cristo, de cuyo lado, traspasado en la cruz, brot\u00f3 sangre y agua, inicio de los sacramentos de la Iglesia y centro de nuestra alabanza y acci\u00f3n de gracias<\/em>\u00a0<a name=\"_ftnref19\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn19\">[19]<\/a>.<\/p>\n<p>Al acercarse al altar para la ofrenda, se ense\u00f1a al presb\u00edtero la humildad y el arrepentimiento con las palabras: \u00abAcepta, Se\u00f1or, nuestro coraz\u00f3n contrito y nuestro esp\u00edritu humilde; que este sea hoy nuestro sacrificio y que sea agradable en tu presencia, Se\u00f1or, Dios nuestro\u00bb\u00a0<a name=\"_ftnref20\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn20\">[20]<\/a>.<\/p>\n<p>No puede presumir de s\u00ed mismo por el ministerio que se le ha confiado, porque la Liturgia le invita a pedir ser purificado, con el signo del agua: \u00abLava del todo mi delito, Se\u00f1or, y limpia mi pecado\u00bb\u00a0<a name=\"_ftnref21\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn21\">[21]<\/a>.<\/p>\n<p>Las palabras que la Liturgia pone en sus labios tienen distintos significados, que requieren tonalidades espec\u00edficas: por la importancia de estas palabras, se pide al presb\u00edtero un verdadero\u00a0<em>ars dicendi<\/em>. \u00c9stas dan forma a sus sentimientos interiores, ya sea en la s\u00faplica al Padre en nombre de la asamblea, como en la exhortaci\u00f3n dirigida a la asamblea, as\u00ed como en las aclamaciones junto con toda la asamblea.<\/p>\n<p>Con la plegaria eucar\u00edstica \u2013en la que participan tambi\u00e9n todos los bautizados escuchando\u00a0<em>con reverencia y silencio<\/em>\u00a0e interviniendo con\u00a0<em>aclamaciones<\/em>\u00a0<a name=\"_ftnref22\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn22\">[22]<\/a>\u2013 el que preside tiene la fuerza, en nombre de todo el pueblo santo, de recordar al Padre la ofrenda de su Hijo en la \u00faltima cena, para que ese inmenso don se haga de nuevo presente en el altar. Participa en esa ofrenda con la ofrenda de s\u00ed mismo. El presb\u00edtero no puede hablar al Padre de la \u00faltima cena sin participar en ella. No puede decir: \u00abTomad y comed todos de \u00e9l, porque esto es mi Cuerpo, que ser\u00e1 entregado por vosotros\u00bb, y no vivir el mismo deseo de ofrecer su propio cuerpo, su propia vida por el pueblo a \u00e9l confiado. Esto es lo que ocurre en el ejercicio de su ministerio.<\/p>\n<p>El presb\u00edtero es formado continuamente en la acci\u00f3n celebrativa por todo esto y mucho m\u00e1s.<\/p>\n<p>&nbsp;<\/p>\n<p>* * *<\/p>\n<ol start=\"61\">\n<li>He querido ofrecer simplemente algunas reflexiones que ciertamente no agotan el inmenso tesoro de la celebraci\u00f3n de los santos misterios. Pido a todos los obispos, presb\u00edteros y di\u00e1conos, a los formadores de los seminarios, a los profesores de las facultades teol\u00f3gicas y de las escuelas de teolog\u00eda, y a todos los catequistas, que ayuden al pueblo santo de Dios a beber de la que siempre ha sido la fuente principal de la espiritualidad cristiana. Estamos continuamente llamados a redescubrir la riqueza de los principios generales expuestos en los primeros n\u00fameros de la\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, comprendiendo el \u00edntimo v\u00ednculo entre la primera Constituci\u00f3n conciliar y todas las dem\u00e1s. Por eso, no podemos volver a esa forma ritual que los Padres Conciliares,\u00a0<em>cum Petro y sub Petro<\/em>, sintieron la necesidad de reformar, aprobando, bajo la gu\u00eda del Esp\u00edritu y seg\u00fan su conciencia de pastores, los principios de los que naci\u00f3 la reforma. Los santos Pont\u00edfices Pablo VI y Juan Pablo II, al aprobar los libros lit\u00fargicos reformados\u00a0<em>ex decreto Sacrosancti \u0152cumenici Concilii Vaticani II<\/em>, garantizaron la fidelidad de la reforma al Concilio. Por eso, escrib\u00ed\u00a0<em><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/motu_proprio\/documents\/20210716-motu-proprio-traditionis-custodes.html\">Traditionis custodes<\/a><\/em>, para que la Iglesia pueda elevar, en la variedad de lenguas, una \u00fanica e id\u00e9ntica oraci\u00f3n capaz de expresar su unidad\u00a0<a name=\"_ftnref23\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn23\">[23]<\/a>. Esta unidad que, como ya he escrito, pretendo ver restablecida en toda la Iglesia de Rito Romano.<\/li>\n<li>Quisiera que esta carta nos ayudara a reavivar el asombro por la belleza de la verdad de la celebraci\u00f3n cristiana, a recordar la necesidad de una aut\u00e9ntica formaci\u00f3n lit\u00fargica y a reconocer la importancia de un arte de la celebraci\u00f3n, que est\u00e9 al servicio de la verdad del misterio pascual y de la participaci\u00f3n de todos los bautizados, cada uno con la especificidad de su vocaci\u00f3n.<\/li>\n<\/ol>\n<p>Toda esta riqueza no est\u00e1 lejos de nosotros: est\u00e1 en nuestras iglesias, en nuestras fiestas cristianas, en la centralidad del domingo, en la fuerza de los sacramentos que celebramos. La vida cristiana es un continuo camino de crecimiento: estamos llamados a dejarnos formar con alegr\u00eda y en comuni\u00f3n.<\/p>\n<ol start=\"63\">\n<li>Por eso, me gustar\u00eda dejaros una indicaci\u00f3n m\u00e1s para proseguir en nuestro camino. Os invito a redescubrir el sentido del\u00a0<em>a\u00f1o lit\u00fargico<\/em>y del\u00a0<em>d\u00eda del Se\u00f1or<\/em>: tambi\u00e9n esto es una consigna del Concilio (cfr.\u00a0<em><a href=\"https:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19631204_sacrosanctum-concilium_sp.html\">Sacrosanctum Concilium<\/a><\/em>, nn. 102-111).<\/li>\n<li>A la luz de lo que hemos recordado anteriormente, entendemos que el a\u00f1o lit\u00fargico es la posibilidad de crecer en el conocimiento del misterio de Cristo, sumergiendo nuestra vida en el misterio de su Pascua, mientras esperamos su vuelta. Se trata de una verdadera formaci\u00f3n continua. Nuestra vida no es una sucesi\u00f3n casual y ca\u00f3tica de acontecimientos, sino un camino que, de Pascua en Pascua, nos conforma a \u00c9l\u00a0<em>mientras esperamos la gloriosa venida de nuestro Salvador Jesucristo<\/em><a name=\"_ftnref24\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftn24\">[24]<\/a>.<\/li>\n<li>En el correr del tiempo, renovado por la Pascua, cada ocho d\u00edas la Iglesia celebra, en el domingo, el acontecimiento de la salvaci\u00f3n. El domingo, antes de ser un precepto, es un regalo que Dios hace a su pueblo (por eso, la Iglesia lo protege con un precepto). La celebraci\u00f3n dominical ofrece a la comunidad cristiana la posibilidad de formarse por medio de la Eucarist\u00eda. De domingo a domingo, la Palabra del Resucitado ilumina nuestra existencia queriendo realizar en nosotros aquello para lo que ha sido enviada (cfr.\u00a0<em>Is<\/em>55,10-11). De domingo a domingo, la comuni\u00f3n en el Cuerpo y la Sangre de Cristo quiere hacer tambi\u00e9n de nuestra vida un sacrificio agradable al Padre, en la comuni\u00f3n fraterna que se transforma en compartir, acoger, servir. De domingo a domingo, la fuerza del Pan partido nos sostiene en el anuncio del Evangelio en el que se manifiesta la autenticidad de nuestra celebraci\u00f3n.<\/li>\n<\/ol>\n<p>Abandonemos las pol\u00e9micas para escuchar juntos lo que el Esp\u00edritu dice a la Iglesia, mantengamos la comuni\u00f3n, sigamos asombr\u00e1ndonos por la belleza de la Liturgia. Se nos ha dado la Pascua, conservemos el deseo continuo que el Se\u00f1or sigue teniendo de poder comerla con nosotros. Bajo la mirada de Mar\u00eda, Madre de la Iglesia.<\/p>\n<p><em>Dado en Roma, en San Juan de Letr\u00e1n, a 29 de junio, solemnidad de los Santos Pedro y Pablo, Ap\u00f3stoles, del a\u00f1o 2022, d\u00e9cimo de mi pontificado.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>FRANCISCO<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Tiemble el hombre todo entero, estrem\u00e9zcase el mundo todo<br \/>\ny exulte el cielo cuando Cristo, el Hijo de Dios vivo,<br \/>\nse encuentra sobre el altar en manos del sacerdote!<br \/>\n\u00a1Oh celsitud admirable y condescendencia asombrosa!<br \/>\n\u00a1Oh sublime humildad, oh humilde sublimidad:<br \/>\nque el Se\u00f1or del mundo universo, Dios e Hijo de Dios,<br \/>\nse humilla hasta el punto de esconderse,<br \/>\npara nuestra salvaci\u00f3n, bajo una peque\u00f1a forma de pan!<br \/>\nMirad, hermanos, la humildad de Dios<br \/>\ny derramad ante \u00c9l vuestros corazones;<br \/>\nhumillaos tambi\u00e9n vosotros, para ser enaltecidos por \u00c9l.<br \/>\nEn conclusi\u00f3n:<br \/>\nnada de vosotros reteng\u00e1is para vosotros mismos<br \/>\na fin de enteros os reciba el que todo entero se os entrega.<\/p>\n<p><em>San Francisco de As\u00eds, Carta a toda la Orden\u00a0<\/em>II, 26-29<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a name=\"_ftn1\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref1\">[1]<\/a>\u00a0Cfr. Leo Magnus,\u00a0<em>Sermo LXXIV<\/em>:\u00a0<em>De ascensione Domini II,<\/em>\u00a01: \u201cquod [\u2026] Redemptoris nostri conspicuum fuit, in sacramenta transivit\u201d.<\/p>\n<p><a name=\"_ftn2\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref2\">[2]<\/a>\u00a0<em>Pr\u00e6fatio paschalis<\/em>\u00a0<em>III<\/em>,\u00a0<em>Missale Romanum<\/em>\u00a0(2008) p.367: \u201cQui immol\u00e1tus iam non m\u00f3ritur, sed semper vivit occ\u00edsus\u201d.<\/p>\n<p><a name=\"_ftn3\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref3\">[3]<\/a>\u00a0Cfr.\u00a0<em>Missale Romanum\u00a0<\/em>(2008) p. 532.<\/p>\n<p><a name=\"_ftn4\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref4\">[4]<\/a>\u00a0Cfr. Augustinus,\u00a0<em>Enarrationes in psalmos. Ps. 138,2<\/em>;\u00a0<em>Oratio post septimam lectionem<\/em>,\u00a0<em>Vigilia Paschalis<\/em>,\u00a0<em>Missale Romanum\u00a0<\/em>(2008) p. 359;\u00a0<em>Super oblata<\/em>,\u00a0<em>Pro Ecclesia<\/em>\u00a0(B),\u00a0<em>Missale Romanum<\/em>\u00a0(2008) p. 1076.<\/p>\n<p><a name=\"_ftn5\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref5\">[5]<\/a>\u00a0Cfr. Augustinus,\u00a0<em>In Ioannis Evangelium tractatus XXVI<\/em>,13.<\/p>\n<p><a name=\"_ftn6\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref6\">[6]<\/a>\u00a0Litter\u00e6 encyclic\u00e6\u00a0<em>Mediator Dei\u00a0<\/em>(20 Novembris 1947) en\u00a0<em>AAS<\/em>\u00a039 (1947) 532.<\/p>\n<p><a name=\"_ftn7\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref7\">[7]<\/a>\u00a0<em>AAS<\/em>\u00a056 (1964) 34.<\/p>\n<p><a name=\"_ftn8\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref8\">[8]<\/a>\u00a0R. Guardini,\u00a0<em>Liturgische Bildung<\/em>\u00a0(1923) en\u00a0<em>Liturgie und liturgische Bildung<\/em>\u00a0(Mainz 1992) p. 43.<\/p>\n<p><a name=\"_ftn9\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref9\">[9]<\/a>\u00a0R. Guardini,\u00a0<em>Der Kultakt und die gegenw\u00e4rtige Aufgabe der Liturgischen Bildung<\/em>\u00a0(1964) en\u00a0<em>Liturgie und liturgische Bildung<\/em>\u00a0(Mainz 1992) p. 14.<\/p>\n<p><a name=\"_ftn10\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref10\">[10]<\/a>\u00a0<em>De Ordinatione Episcopi, Presbyterorum et Diaconorum<\/em>\u00a0(1990) p. 95: \u00abAgnosce quod ages, imitare quod tractabis, et vitam tuam mysterio dominic\u00e6 crucis conforma\u00bb.<\/p>\n<p><a name=\"_ftn11\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref11\">[11]<\/a>\u00a0Leo Magnus,\u00a0<em>Sermo XII<\/em>:\u00a0<em>De Passione III<\/em>, 7.<\/p>\n<p><a name=\"_ftn12\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref12\">[12]<\/a>\u00a0Iren\u00e6us Lugdunensis,\u00a0<em>Adversus h\u00e6reses IV<\/em>, 20, 7.<\/p>\n<p><a name=\"_ftn13\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref13\">[13]<\/a>\u00a0R. Guardini,\u00a0<em>Liturgische Bildung<\/em>\u00a0(1923) en\u00a0<em>Liturgie und liturgische Bildung<\/em>\u00a0(Mainz 1992) p. 36.<\/p>\n<p><a name=\"_ftn14\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref14\">[14]<\/a>\u00a0<em>Cantico delle Creature<\/em>, Fonti Francescane, n. 263.<\/p>\n<p><a name=\"_ftn15\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref15\">[15]<\/a>\u00a0R. Guardini,\u00a0<em>Liturgische Bildung<\/em>\u00a0(1923) en\u00a0<em>Liturgie und liturgische Bildung<\/em>\u00a0(Mainz 1992) p. 99.<\/p>\n<p><a name=\"_ftn16\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref16\">[16]<\/a>\u00a0Cfr.\u00a0<em>Institutio Generalis Missalis Romani<\/em>, nn. 45; 51; 54-56; 66; 71; 78; 84; 88; 271.<\/p>\n<p><a name=\"_ftn17\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref17\">[17]<\/a>\u00a0Ver Exhortaci\u00f3n apost\u00f3lica\u00a0<em>Evangelii gaudium<\/em>\u00a0(24 Noviembre 2013), nn. 135-144.<\/p>\n<p><a name=\"_ftn18\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref18\">[18]<\/a>\u00a0Cfr.\u00a0<em>Institutio Generalis Missalis Romani<\/em>, n. 310.<\/p>\n<p><a name=\"_ftn19\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref19\">[19]<\/a>\u00a0<em>Prex dedicationis\u00a0<\/em>en\u00a0<em>Ordo dedicationis ecclesi\u00e6 et altaris<\/em>\u00a0(1977) p. 102.<\/p>\n<p><a name=\"_ftn20\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref20\">[20]<\/a>\u00a0<em>Missale Romanum<\/em>\u00a0(2008) p. 515: \u201cIn spiritu humilitatis et in animo contrito suscipiamur a te, Domine; et sic fiat sacrificium nostrum in conspectu tuo hodie, ut placeat tibi, Domine Deus\u201d.<\/p>\n<p><a name=\"_ftn21\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref21\">[21]<\/a>\u00a0<em>Missale Romanum<\/em>\u00a0(2008) p. 515: \u201cLava me, Domine, ab iniquitate mea, et a peccato meo munda me\u201d.<\/p>\n<p><a name=\"_ftn22\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref22\">[22]<\/a>\u00a0Cfr.\u00a0<em>Institutio Generalis Missalis Romani<\/em>, nn. 78-79.<\/p>\n<p><a name=\"_ftn23\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref23\">[23]<\/a>\u00a0Cfr. Paulus VI, Constitutio apostolica\u00a0<em>Missale Romanum<\/em>\u00a0(3 Aprilis 1969) en\u00a0<em>AAS<\/em>\u00a061 (1969) 222.<\/p>\n<p><a name=\"_ftn24\"><\/a><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/apost_letters\/documents\/20220629-lettera-ap-desiderio-desideravi.html#_ftnref24\">[24]<\/a>\u00a0<em>Missale Romanum<\/em>\u00a0(2008) p. 598: \u201c\u2026 exspectantes beatam spem et adventum Salvatoris nostri Iesu Christi\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recordar el sentido profundo de la celebraci\u00f3n eucar\u00edstica surgida del Concilio Vaticano II e invitar a la formaci\u00f3n lit\u00fargica<\/p>\n","protected":false},"author":15,"featured_media":6161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[68],"tags":[6467,158,4953],"class_list":["post-58798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leon-xiv","tag-formacion-liturgica","tag-papa-francisco","tag-trending-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta del Papa &#039;Desiderio desideravi&#039;: La poderosa belleza de la liturgia &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta del Papa &#039;Desiderio desideravi&#039;: La poderosa belleza de la liturgia &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Recordar el sentido profundo de la celebraci\u00f3n eucar\u00edstica surgida del Concilio Vaticano II e invitar a la formaci\u00f3n lit\u00fargica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T20:11:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-01T10:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/03\/vm140321112114_00483.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2020\" \/>\n\t<meta property=\"og:image:height\" content=\"1347\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"47 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"Carta del Papa &#8216;Desiderio desideravi&#8217;: La poderosa belleza de la liturgia\",\"datePublished\":\"2022-06-29T20:11:17+00:00\",\"dateModified\":\"2022-07-01T10:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/\"},\"wordCount\":13109,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/vm140321112114_00483.jpg\",\"keywords\":[\"Formaci\u00f3n lit\u00fargica\",\"papa francisco\",\"Trending\"],\"articleSection\":[\"Le\u00f3n XIV\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/\",\"name\":\"Carta del Papa 'Desiderio desideravi': La poderosa belleza de la liturgia &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/vm140321112114_00483.jpg\",\"datePublished\":\"2022-06-29T20:11:17+00:00\",\"dateModified\":\"2022-07-01T10:00:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/vm140321112114_00483.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/vm140321112114_00483.jpg\",\"width\":2020,\"height\":1347,\"caption\":\"Misa del 500 aniversario de la evangelizaci\u00f3n de Filipinas \u00a9 Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta del Papa &#8216;Desiderio desideravi&#8217;: La poderosa belleza de la liturgia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta del Papa 'Desiderio desideravi': La poderosa belleza de la liturgia &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/","og_locale":"es_ES","og_type":"article","og_title":"Carta del Papa 'Desiderio desideravi': La poderosa belleza de la liturgia &#8211; Exaudi","og_description":"Recordar el sentido profundo de la celebraci\u00f3n eucar\u00edstica surgida del Concilio Vaticano II e invitar a la formaci\u00f3n lit\u00fargica","og_url":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2022-06-29T20:11:17+00:00","article_modified_time":"2022-07-01T10:00:03+00:00","og_image":[{"width":2020,"height":1347,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/03\/vm140321112114_00483.jpg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"47 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"Carta del Papa &#8216;Desiderio desideravi&#8217;: La poderosa belleza de la liturgia","datePublished":"2022-06-29T20:11:17+00:00","dateModified":"2022-07-01T10:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/"},"wordCount":13109,"image":{"@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/03\/vm140321112114_00483.jpg","keywords":["Formaci\u00f3n lit\u00fargica","papa francisco","Trending"],"articleSection":["Le\u00f3n XIV"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/","url":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/","name":"Carta del Papa 'Desiderio desideravi': La poderosa belleza de la liturgia &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/03\/vm140321112114_00483.jpg","datePublished":"2022-06-29T20:11:17+00:00","dateModified":"2022-07-01T10:00:03+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/03\/vm140321112114_00483.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/03\/vm140321112114_00483.jpg","width":2020,"height":1347,"caption":"Misa del 500 aniversario de la evangelizaci\u00f3n de Filipinas \u00a9 Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/cara-papa-desidero-desideravi-poderosa-belleza-liturgia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Carta del Papa &#8216;Desiderio desideravi&#8217;: La poderosa belleza de la liturgia"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/03\/vm140321112114_00483.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-fim","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/58798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=58798"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/58798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/6161"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=58798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=58798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=58798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}