{"id":58623,"date":"2022-06-25T18:52:54","date_gmt":"2022-06-25T16:52:54","guid":{"rendered":"https:\/\/exaudi.org\/?p=58623"},"modified":"2022-06-27T15:31:19","modified_gmt":"2022-06-27T13:31:19","slug":"amor-familiar-vocacion-y-camino-de-santidad","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/","title":{"rendered":"\u00abAmor familiar: vocaci\u00f3n y camino de santidad\u00bb"},"content":{"rendered":"<p style=\"text-align: left\">A las 18.30 horas de esta tarde, s\u00e1bado, 25 de junio de 2022, en la Plaza de San Pedro, tiene lugar -en presencia del Santo Padre Francisco- la Santa Misa con motivo del X Encuentro Mundial de las Familias, que tendr\u00e1 lugar en Roma del 22 al 26 de junio de 2022, sobre el tema: \u00abAmor familiar: vocaci\u00f3n y camino de santidad\u00bb.<\/p>\n<p>Durante la celebraci\u00f3n eucar\u00edstica, tras la proclamaci\u00f3n del Santo Evangelio, el Papa pronuncia la homil\u00eda que publicamos a continuaci\u00f3n:<\/p>\n<p>***<\/p>\n<p><strong>Homil\u00eda del Santo Padre<\/strong><\/p>\n<p>En el \u00e1mbito del X Encuentro Mundial de las Familias, este es el momento de la <em>acci\u00f3n de gracias<\/em>. Hoy presentamos ante Dios con gratitud \u2014como en un gran ofertorio\u2014 todo lo que el Esp\u00edritu Santo ha sembrado en vosotras, queridas familias. Algunas de vosotras hab\u00e9is participado en los momentos de reflexi\u00f3n e intercambio aqu\u00ed en el Vaticano; otras los hab\u00e9is animado y vivido en vuestras respectivas di\u00f3cesis, en una especie de inmensa constelaci\u00f3n. Imagino la riqueza de experiencias, de prop\u00f3sitos, de sue\u00f1os, y tampoco habr\u00e1n faltado las preocupaciones y las incertidumbres. Ahora presentamos todo al Se\u00f1or, y le pedimos a \u00c9l que os sostenga con su fuerza y con su amor. Sois pap\u00e1s, mam\u00e1s, hijos, abuelos, t\u00edos; sois adultos, ni\u00f1os, j\u00f3venes, ancianos; cada uno con una experiencia diferente de familia, pero todos con la misma esperanza hecha oraci\u00f3n. Que Dios bendiga y proteja a vuestras familias y a todas las familias del mundo.<\/p>\n<p>En la segunda lectura, san Pablo nos ha hablado de<em> libertad<\/em>. La libertad es uno de los bienes m\u00e1s valorados y buscados por el hombre moderno y contempor\u00e1neo. Todos desean ser libres, no tener condicionamientos, no estar limitados, y por eso aspiran a liberarse de todo tipo de \u201cprisi\u00f3n\u201d: cultural, social, econ\u00f3mica. Sin embargo, cu\u00e1ntas personas carecen de la libertad m\u00e1s grande, la interior. El Ap\u00f3stol nos recuerda a nosotros cristianos que esta libertad es sobre todo un don, cuando exclama: \u00abPara la libertad nos ha liberado Cristo\u00bb (<em>Ga<\/em> 5,1). La libertad nos ha sido dada. Todos nosotros nacemos con muchos condicionamientos, interiores y exteriores, y sobre todo con la tendencia al<br \/>\nego\u00edsmo, es decir, a ponernos nosotros mismos en el centro y a buscar nuestros propios intereses. Pero Cristo nos ha liberado de esta esclavitud. Para evitar malentendidos, san Pablo nos advierte que la libertad que nos da Dios no es la falsa y vac\u00eda libertad del mundo, que en realidad es \u00abun pretexto para satisfacer los deseos carnales\u00bb (<em>Ga<\/em> 5,13). No, la libertad que Cristo nos ha adquirido al precio de su sangre est\u00e1 orientada totalmente al amor, para que \u2014como dec\u00eda y nos dice hoy el Ap\u00f3stol\u2014 \u00abse hagan m\u00e1s bien esclavos unos de los otros, por medio del amor\u00bb (<em>ib\u00edd<\/em>.).<\/p>\n<p>Todos vosotros c\u00f3nyuges, formando vuestra familia, con la gracia de Cristo hab\u00e9is hecho esta elecci\u00f3n valiente: <em>no usar vuestra libertad para vosotros mismos, sino para amar a las personas que Dios ha puesto a vuestro lado<\/em>. En vez de vivir como \u201cislas\u201d, os hab\u00e9is puesto \u201cal servicio los unos de los otros\u201d. De este modo se vive la libertad en familia. No hay \u201cplanetas\u201d o \u201csat\u00e9lites\u201d que viajan cada uno en su propia \u00f3rbita. La familia es el lugar del encuentro, del compartir, del salir de s\u00ed mismos para acoger a los otros y estar cerca de ellos. <em>Es el primer lugar donde se aprende a amar.<\/em><\/p>\n<p>Hermanos y hermanas, mientras reafirmamos esto con gran convicci\u00f3n, sabemos bien que en los hechos no siempre es as\u00ed, por muchos motivos y muchas situaciones diversas. Y as\u00ed, precisamente mientras <em>afirmamos la belleza de la familia<\/em>, sentimos m\u00e1s que nunca que <em>debemos defenderla<\/em>. No dejemos que se contamine con los venenos del ego\u00edsmo, del individualismo, de la cultura de la indiferencia y del descarte, y pierda as\u00ed su \u201cADN\u201d que es la acogida y el esp\u00edritu de servicio.<\/p>\n<p>La relaci\u00f3n entre los profetas El\u00edas y Eliseo, presentada en la primera lectura, nos hace pensar en la <em>relaci\u00f3n entre las generaciones<\/em>, en el \u201cpaso del testigo\u201d de padres a hijos. Esta relaci\u00f3n en el mundo de hoy no es sencilla y a menudo es motivo de preocupaciones. Los padres temen que los hijos no sean capaces de orientarse en la complejidad y en la confusi\u00f3n de nuestras sociedades, donde todo parece ca\u00f3tico y precario, y que al final pierdan su camino. Este miedo hace a algunos padres ansiosos, a otros sobreprotectores, y a veces termina incluso por impedir el deseo de traer nuevas vidas al mundo.<\/p>\n<figure id=\"attachment_58630\" aria-describedby=\"caption-attachment-58630\" style=\"width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-58630\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-300x200.jpeg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-770x513.jpeg 770w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-360x240.jpeg?crop=1 360w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-500x333.jpeg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-370x247.jpeg 370w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-293x195.jpeg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-120x80.jpeg 120w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-240x160.jpeg 240w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-390x260.jpeg 390w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1.jpeg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-58630\" class=\"wp-caption-text\">Misa, 25 junio 2022 &#8211; \u00a9 Vatican Media<\/figcaption><\/figure>\n<p>Nos hace bien reflexionar sobre la relaci\u00f3n entre El\u00edas y Eliseo. El\u00edas, en un momento de crisis y de miedo por el futuro, recibe de Dios la orden de ungir a Eliseo como su sucesor. Dios le hace entender a El\u00edas que el mundo no termina con \u00e9l y le manda que transmita a otro su misi\u00f3n. Este es el sentido del gesto descrito en el texto: El\u00edas puso su manto en los hombros de Eliseo, y desde ese momento el disc\u00edpulo toma el lugar del maestro para continuar el ministerio prof\u00e9tico en Israel. Dios muestra de este modo que t<em>iene confianza en el joven Eliseo<\/em>.<\/p>\n<p>\u00a1Qu\u00e9 importante es para los padres contemplar el modo de actuar de Dios! Dios ama a los j\u00f3venes, pero no por eso los preserva de todos los peligros, desaf\u00edos y sufrimientos. No es ansioso ni sobreprotector; al contrario, <em>conf\u00eda en ellos y llama a cada uno al alto sentido de la vida y de la misi\u00f3n<\/em>. Pensemos en el ni\u00f1o Samuel, en el adolescente David, en el joven Jerem\u00edas; pensemos sobre todo en la Virgen Mar\u00eda. Queridos padres, la Palabra de Dios nos muestra el camino: no preservar a los hijos de cualquier malestar y sufrimiento, sino tratar de transmitirles la pasi\u00f3n por la vida, de encender en ellos el deseo de que encuentren su vocaci\u00f3n y que abracen la gran misi\u00f3n que Dios ha pensado para ellos. Este descubrimiento es justamente el que hace a Eliseo valiente, determinado, y lo convierte en un adulto. El alejamiento de los progenitores y la inmolaci\u00f3n de los bueyes son precisamente el signo por el que Eliseo comprendi\u00f3 que ahora \u201cle tocaba a \u00e9l\u201d, que era el momento de acoger la llamada de Dios y de llevar adelante cuanto hab\u00eda visto hacer a su maestro. Y lo har\u00e1 con valent\u00eda hasta el final de su vida. Queridos padres, si ayud\u00e1is a vuestros hijos a que descubran y acojan su vocaci\u00f3n, ver\u00e9is que ellos estar\u00e1n \u201caferrados\u201d a esta misi\u00f3n y tendr\u00e1n la fuerza de afrontar y superar las dificultades de la vida.<\/p>\n<p>Quisiera agregar tambi\u00e9n que, para un educador, el mejor modo de ayudar a otro a seguir su vocaci\u00f3n es el de <em>abrazar la propia vocaci\u00f3n con amor fiel<\/em>. Fue lo que los disc\u00edpulos vieron hacer a Jes\u00fas, y el Evangelio de hoy nos muestra un momento emblem\u00e1tico, cuando Jes\u00fas \u00abse encamin\u00f3 decididamente hacia Jerusal\u00e9n\u00bb (<em>Lc<\/em> 9,51), sabiendo bien que all\u00ed ser\u00eda condenado y morir\u00eda. Y en el camino hacia Jerusal\u00e9n, Jes\u00fas sufri\u00f3 el rechazo de los habitantes de Samar\u00eda, un rechazo que suscit\u00f3 la reacci\u00f3n indignada de Santiago y Juan, pero que \u00c9l acept\u00f3 porque formaba parte de su vocaci\u00f3n. Al principio fue rechazado en Nazaret, ahora en Samar\u00eda, y al final ser\u00e1 rechazado en Jerusal\u00e9n. Jes\u00fas acepta todo esto porque ha venido para cargar sobre s\u00ed nuestros pecados. Del mismo modo, no hay nada m\u00e1s estimulante para los hijos que ver a los propios padres vivir el matrimonio y la familia como una misi\u00f3n, con fidelidad y paciencia, a pesar de las dificultades, los momentos tristes y las pruebas. Y esto que le sucedi\u00f3 a Jes\u00fas en Samar\u00eda acontece en toda vocaci\u00f3n cristiana, tambi\u00e9n en la familiar. Llegan momentos en los que es necesario cargar sobre s\u00ed las resistencias, las cerrazones, las incomprensiones que provienen del coraz\u00f3n humano y, con la gracia de Cristo, transformarlas en acogida del otro, en amor gratuito.<\/p>\n<p>Inmediatamente despu\u00e9s de este episodio, que nos describe en cierto sentido la \u201cvocaci\u00f3n de Jes\u00fas\u201d, el Evangelio nos presenta otras tres llamadas, tres vocaciones de otros aspirantes a disc\u00edpulos de Jes\u00fas. El primero es invitado a no buscar una morada estable, un lugar seguro siguiendo al Maestro. De hecho, \u00c9l \u00abno tiene d\u00f3nde reclinar la cabeza\u00bb (<em>Lc<\/em> 9,58). Seguir a Jes\u00fas significa ponerse en movimiento y permanecer siempre en movimiento, \u201cen camino\u201d con \u00c9l a trav\u00e9s de las vicisitudes de la vida. \u00a1Qu\u00e9 verdadero es esto para vosotros casados! Tambi\u00e9n vosotros, acogiendo la llamada al matrimonio y a la familia, hab\u00e9is dejado vuestro \u201cnido\u201d y hab\u00e9is iniciado un viaje, del que no pod\u00edais conocer anticipadamente todas las etapas, y que os mantiene en constante movimiento, con situaciones siempre nuevas, acontecimientos inesperados, sorpresas. As\u00ed es el camino con el Se\u00f1or. Es din\u00e1mico, es impredecible, y es siempre un descubrimiento maravilloso. Recordemos que el descanso de todo disc\u00edpulo de Jes\u00fas est\u00e1 precisamente en hacer cada d\u00eda la voluntad de Dios, sea cual fuere.<\/p>\n<p>El segundo disc\u00edpulo es invitado a \u201cno volver a enterrar a sus muertos\u201d (cf. vv. 59-60). No se trata de faltar al cuarto mandamiento, que permanece siempre v\u00e1lido; sino que es una invitaci\u00f3n a obedecer<\/p>\n<figure id=\"attachment_58633\" aria-describedby=\"caption-attachment-58633\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-58633\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-300x200.jpeg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-770x513.jpeg 770w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-360x240.jpeg?crop=1 360w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-500x333.jpeg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-370x247.jpeg 370w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-293x195.jpeg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-120x80.jpeg 120w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-240x160.jpeg 240w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1-390x260.jpeg 390w, https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/cq5dam.web_.800.800-1-1.jpeg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-58633\" class=\"wp-caption-text\">Misa, 25 junio 2022 &#8211; \u00a9 Vatican Media<\/figcaption><\/figure>\n<p>sobre todo al primer mandamiento: amar a Dios sobre todas las cosas. As\u00ed le sucedi\u00f3 tambi\u00e9n al tercer disc\u00edpulo, llamado a seguir a Cristo decididamente y con todo el coraz\u00f3n, sin \u201cvolverse atr\u00e1s\u201d, ni siquiera para despedirse de sus familiares (cf. vv. 61-62).<\/p>\n<p>Queridas familias, tambi\u00e9n vosotras est\u00e1is invitadas a no tener otras prioridades, a \u201cno volveros atr\u00e1s\u201d, es decir, a no echar de menos la vida de antes, la libertad de antes, con sus ilusiones enga\u00f1osas. Cuando no se acoge la novedad de la llamada de Dios la vida se fosiliza, a\u00f1orando el pasado. Cuando Jes\u00fas llama, tambi\u00e9n al matrimonio y a la familia, pide que miremos hacia adelante y siempre nos precede en el camino, <em>siempre nos precede<\/em> en el amor y en el servicio. Quien lo sigue no queda defraudado.<\/p>\n<p>Queridos hermanos y hermanas, las lecturas que la liturgia nos ha propuesto hoy, todas, providencialmente, hablan de vocaci\u00f3n, que es justamente el tema de este d\u00e9cimo Encuentro Mundial de las Familias: <em>\u201cEl amor familiar: vocaci\u00f3n y camino de santidad<\/em>\u201d. Con la fuerza de esta Palabra de vida, os animo a retomar con decisi\u00f3n el camino del amor familiar, compartiendo con todos los miembros de la familia la alegr\u00eda de esta llamada. Que el amor que viv\u00eds entre vosotros sea siempre abierto, extrovertido, capaz de \u201calcanzar\u201d a los m\u00e1s d\u00e9biles y a los heridos que encontr\u00e1is a lo largo del camino; fr\u00e1giles en el cuerpo y fr\u00e1giles en el alma. El amor, en efecto, tambi\u00e9n el familiar, se purifica y se refuerza cuando se da.<\/p>\n<p>La Iglesia est\u00e1 con vosotros, es m\u00e1s, la Iglesia est\u00e1 en vosotros. De hecho, la Iglesia naci\u00f3 de una Familia, la de Nazaret, y est\u00e1 formada principalmente por familias. Que el Se\u00f1or os ayude cada d\u00eda a permanecer en la unidad, en la paz y en la alegr\u00eda, mostrando a todos que Dios es amor y comuni\u00f3n de vida.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Papa Francisco: Santa Misa X Encuentro Mundial de las Familias<\/p>\n","protected":false},"author":15,"featured_media":58651,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[114,68],"tags":[158,704,4953],"class_list":["post-58623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homilias","category-leon-xiv","tag-papa-francisco","tag-santa-misa","tag-trending-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Amor familiar: vocaci\u00f3n y camino de santidad&quot; &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Amor familiar: vocaci\u00f3n y camino de santidad&quot; &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Papa Francisco: Santa Misa X Encuentro Mundial de las Familias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-25T16:52:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-27T13:31:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/XencuentroIII.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"\u00abAmor familiar: vocaci\u00f3n y camino de santidad\u00bb\",\"datePublished\":\"2022-06-25T16:52:54+00:00\",\"dateModified\":\"2022-06-27T13:31:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/\"},\"wordCount\":2012,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/XencuentroIII.jpeg\",\"keywords\":[\"papa francisco\",\"Santa Misa\",\"Trending\"],\"articleSection\":[\"Homilias\",\"Le\u00f3n XIV\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/\",\"name\":\"\\\"Amor familiar: vocaci\u00f3n y camino de santidad\\\" &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/XencuentroIII.jpeg\",\"datePublished\":\"2022-06-25T16:52:54+00:00\",\"dateModified\":\"2022-06-27T13:31:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/XencuentroIII.jpeg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/XencuentroIII.jpeg\",\"width\":800,\"height\":533,\"caption\":\"X Encuentro Mundial de las Familias - \u00a9 Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/amor-familiar-vocacion-y-camino-de-santidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abAmor familiar: vocaci\u00f3n y camino de santidad\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Amor familiar: vocaci\u00f3n y camino de santidad\" &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/","og_locale":"es_ES","og_type":"article","og_title":"\"Amor familiar: vocaci\u00f3n y camino de santidad\" &#8211; Exaudi","og_description":"Papa Francisco: Santa Misa X Encuentro Mundial de las Familias","og_url":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2022-06-25T16:52:54+00:00","article_modified_time":"2022-06-27T13:31:19+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/XencuentroIII.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"\u00abAmor familiar: vocaci\u00f3n y camino de santidad\u00bb","datePublished":"2022-06-25T16:52:54+00:00","dateModified":"2022-06-27T13:31:19+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/"},"wordCount":2012,"image":{"@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/XencuentroIII.jpeg","keywords":["papa francisco","Santa Misa","Trending"],"articleSection":["Homilias","Le\u00f3n XIV"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/","url":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/","name":"\"Amor familiar: vocaci\u00f3n y camino de santidad\" &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/XencuentroIII.jpeg","datePublished":"2022-06-25T16:52:54+00:00","dateModified":"2022-06-27T13:31:19+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/XencuentroIII.jpeg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/XencuentroIII.jpeg","width":800,"height":533,"caption":"X Encuentro Mundial de las Familias - \u00a9 Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/amor-familiar-vocacion-y-camino-de-santidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abAmor familiar: vocaci\u00f3n y camino de santidad\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/XencuentroIII.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-ffx","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/58623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=58623"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/58623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/58651"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=58623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=58623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=58623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}