{"id":58552,"date":"2022-06-24T09:00:42","date_gmt":"2022-06-24T07:00:42","guid":{"rendered":"https:\/\/exaudi.org\/?p=58552"},"modified":"2022-06-23T19:58:02","modified_gmt":"2022-06-23T17:58:02","slug":"no-hace-falta","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/no-hace-falta\/","title":{"rendered":"No hace falta"},"content":{"rendered":"<p>El Padre Antonio Mar\u00eda Domenech ofrece este art\u00edculo en el que reflexiona sobre la amistad y la sociedad actual.<\/p>\n<p>***<\/p>\n<p>Se me han ocurrido varias maneras de empezar estas letras. He elegido esta frase de mi sobrina de cuatro a\u00f1os, que puede estar jugando contigo o charlando, como si fuera la persona m\u00e1s cercana del mundo y cuando tienes que marchar le dices: \u00bfMe das un beso? Y suele contestar as\u00ed:\u00a0<em>No hace falta.<\/em><\/p>\n<p>En fin, si nos ponemos as\u00ed, hacen falta tan pocas cosas. Sin embargo, est\u00e1 claro que alg\u00fan gesto, alg\u00fan sacrificio por la otra persona, renunciar a lo que nos gusta por los dem\u00e1s, s\u00ed que hace falta, al menos de vez en cuando. Hoy quer\u00eda hablar de la AMISTAD. El motivo es que ayer, despu\u00e9s de comer, me son\u00f3 el tel\u00e9fono:\u00a0<em>\u00a1Antonio Mar\u00eda, toca las campanas que hay fuego!\u00a0<\/em>Me dijeron donde era, y pude enviar un mensaje al grupo de whatsapp de la Parroquia con el aviso, adem\u00e1s de poner en marcha todas las campanas tocando a rebato. No tardaron m\u00e1s de treinta personas en llegar al lugar. Mucho despu\u00e9s llegaron los bomberos y a\u00fan pudieron refrescar algunas paredes y apagar algunos almacenes de le\u00f1a que empezaban a humear. No en vano se dice que el incendio m\u00e1s grande, si se coge a tiempo, se puede apagar con un vaso de agua.<\/p>\n<p>La gente llev\u00f3 sus tractores con los arados, la cuba de agua, estaba tambi\u00e9n la Guardia Civil que se encontraba muy cerca en ese momento. Es verdad que corri\u00f3 muy r\u00e1pido, que las llamas eran altas, porque la cebada estaba sin cosechar, que se acerc\u00f3 mucho a alguna casa, pero no tuvimos que lamentar da\u00f1os mayores. Bien seguro que las campanas hicieron su funci\u00f3n porque, adem\u00e1s, llevaba toda la ma\u00f1ana fallando la cobertura de algunos tel\u00e9fonos.<\/p>\n<p>Es hermoso ver al pueblo ayudando cuando pasa una desgracia, aportando todo lo que tiene. En estos diez a\u00f1os de p\u00e1rroco, he tenido la ocasi\u00f3n de verlo muchas veces y por muchos motivos diferentes. Con Filomena, cuando muri\u00f3 L\u00edder, despu\u00e9s del hurac\u00e1n, ayer con el fuego y tantas y tantas otras que, quiz\u00e1s, ni me he enterado. Seguro que sucede en todos los pueblos. Tambi\u00e9n ocurri\u00f3 en el atentado de Atocha, el 11 de marzo. Pero yo me pregunto. \u00bfNo podr\u00edamos dar lo mejor de nosotros mismos a los dem\u00e1s, siempre? No s\u00f3lo si explota una bomba. \u00bfQu\u00e9 te parece? Entiendo que nos falte confianza, a veces. Entiendo que la gente como est\u00e1 mejor es en su casa, pero creo, hablando en general, que por alg\u00fan motivo que no conozco, quiz\u00e1s porque somos cada vez m\u00e1s ego\u00edstas, estamos perdiendo la AMISTAD.<\/p>\n<p>T\u00fa me dir\u00e1s que tienes amigos. Pero, \u00bfest\u00e1s dispuesto a sacrificar algo tuyo por alguno de ellos? \u00bfEn alguna ocasi\u00f3n, has tenido que advertir a alguno de algo, y te lo ha agradecido? \u00bfO se ha enfadado? Es cierto que he perdido amistades por decirles la verdad, por hablarles claro. Algunos me dicen que si eso ha ocurrido no eran amigos. Quiz\u00e1s es complicado encontrar un amigo, porque eso incluye unas caracter\u00edsticas poco comunes como la lealtad, la franqueza, la sinceridad, la confianza.<\/p>\n<p>\u00a1Qu\u00e9 dif\u00edcil es, hoy, encontrar a alguien que se f\u00ede de alguien! \u00a1Qu\u00e9 dif\u00edcil es encontrar un AMIGO de verdad! Ya lo dice la Biblia,\u00a0<em>un amigo fiel es un refugio seguro,<\/em>\u00a0<em>el que lo encuentra, ha encontrado un tesoro<\/em>\u00a0(Eclo. 6, 14).<\/p>\n<p>Ayer tambi\u00e9n, en el Oficio de Lectura, tambi\u00e9n llamado Maitines, le\u00edamos unas letras del Beato Elredo, un abad ingl\u00e9s del siglo XII, que defin\u00eda la amistad con estas palabras:\u00a0<em><strong>\u00c9sta es la verdadera, la perfecta, la estable y la constante amistad: la que no se deja corromper por la envidia, la que no se enfr\u00eda por sospechas, la que no se disuelve por la ambici\u00f3n, la que, puesta a prueba de esta manera, no cede; la que, a pesar de tantos golpes, no cae, la que batida por tantas injurias, se muestra inflexible; la que provocada por tanto ultraje, permanece inm\u00f3vil. Anda, pues, haz t\u00fa lo mismo.<\/strong><\/em>\u00a0\u00bfCrees que hace falta un incendio, o que ocurra cualquier desgracia para dar los mejor de nosotros mismos a los dem\u00e1s? Creo, como dice mi sobrina, que no hace falta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un amigo fiel es un refugio seguro,\u00a0el que lo encuentra, ha encontrado un tesoro<\/p>\n","protected":false},"author":14,"featured_media":58553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[130],"tags":[5844,1008,6446],"class_list":["post-58552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-amistad","tag-espana","tag-se-llenaron-de-inmensa-alegria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No hace falta &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/no-hace-falta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No hace falta &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Un amigo fiel es un refugio seguro,\u00a0el que lo encuentra, ha encontrado un tesoro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/no-hace-falta\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-24T07:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/pexels-arnav-kainthola-6352761-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1155\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/\"},\"author\":{\"name\":\"Exaudi Staff\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f8d6bbcd3b747b47feaa29603390ae1d\"},\"headline\":\"No hace falta\",\"datePublished\":\"2022-06-24T07:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/\"},\"wordCount\":762,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/pexels-arnav-kainthola-6352761-scaled.jpg?fit=2560%2C1155&ssl=1\",\"keywords\":[\"Amistad\",\"Espa\u00f1a\",\"Se llenaron de inmensa alegr\u00eda\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/\",\"name\":\"No hace falta &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/pexels-arnav-kainthola-6352761-scaled.jpg?fit=2560%2C1155&ssl=1\",\"datePublished\":\"2022-06-24T07:00:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f8d6bbcd3b747b47feaa29603390ae1d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/pexels-arnav-kainthola-6352761-scaled.jpg?fit=2560%2C1155&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/pexels-arnav-kainthola-6352761-scaled.jpg?fit=2560%2C1155&ssl=1\",\"width\":2560,\"height\":1155,\"caption\":\"Arnav Kainthola\u00a9Pexels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-hace-falta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No hace falta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f8d6bbcd3b747b47feaa29603390ae1d\",\"name\":\"Exaudi Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fd0540d43941e8f0345d5213d0fbbce6078ed0d3ffdabf3d36ae6f6b299dbff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fd0540d43941e8f0345d5213d0fbbce6078ed0d3ffdabf3d36ae6f6b299dbff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fd0540d43941e8f0345d5213d0fbbce6078ed0d3ffdabf3d36ae6f6b299dbff?s=96&d=mm&r=g\",\"caption\":\"Exaudi Staff\"},\"description\":\"What is Exaudi News? Exaudi News is an international Catholic media outlet that informs, shapes, and transforms daily in Spanish, English, and Italian. Through news, analytical articles, and live broadcasts of the Pope's events, Exaudi seeks to strengthen Christian unity and contribute to the evangelization of the world, always guided by the Church's social doctrine. We work to bring Christian truth and values \u200b\u200bto every corner of the planet. Help us transform the world with Exaudi! At Exaudi, we believe that evangelization and quality information can change lives. To continue our mission and expand our reach, we need your help. In addition, we are looking for committed people to join our team. With your support, we will reach more people, spread the message of Christ, and strengthen Christian unity. Will you join our mission? For more information on how to collaborate, visit Exaudi.org or contact us directly: info@exaudi.org Exaudi: Informs, educates, and transforms.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNews\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_news\",\"https:\\\/\\\/x.com\\\/Exaudi_News\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/dfe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No hace falta &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/no-hace-falta\/","og_locale":"es_ES","og_type":"article","og_title":"No hace falta &#8211; Exaudi","og_description":"Un amigo fiel es un refugio seguro,\u00a0el que lo encuentra, ha encontrado un tesoro","og_url":"https:\/\/exaudi.org\/es\/no-hace-falta\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2022-06-24T07:00:42+00:00","og_image":[{"width":2560,"height":1155,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/06\/pexels-arnav-kainthola-6352761-scaled.jpg","type":"image\/jpeg"}],"author":"Exaudi Staff","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Staff","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/"},"author":{"name":"Exaudi Staff","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f8d6bbcd3b747b47feaa29603390ae1d"},"headline":"No hace falta","datePublished":"2022-06-24T07:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/"},"wordCount":762,"image":{"@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/06\/pexels-arnav-kainthola-6352761-scaled.jpg?fit=2560%2C1155&ssl=1","keywords":["Amistad","Espa\u00f1a","Se llenaron de inmensa alegr\u00eda"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/","url":"https:\/\/exaudi.org\/es\/no-hace-falta\/","name":"No hace falta &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/06\/pexels-arnav-kainthola-6352761-scaled.jpg?fit=2560%2C1155&ssl=1","datePublished":"2022-06-24T07:00:42+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f8d6bbcd3b747b47feaa29603390ae1d"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/no-hace-falta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/06\/pexels-arnav-kainthola-6352761-scaled.jpg?fit=2560%2C1155&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/06\/pexels-arnav-kainthola-6352761-scaled.jpg?fit=2560%2C1155&ssl=1","width":2560,"height":1155,"caption":"Arnav Kainthola\u00a9Pexels"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/no-hace-falta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"No hace falta"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f8d6bbcd3b747b47feaa29603390ae1d","name":"Exaudi Staff","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5fd0540d43941e8f0345d5213d0fbbce6078ed0d3ffdabf3d36ae6f6b299dbff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fd0540d43941e8f0345d5213d0fbbce6078ed0d3ffdabf3d36ae6f6b299dbff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fd0540d43941e8f0345d5213d0fbbce6078ed0d3ffdabf3d36ae6f6b299dbff?s=96&d=mm&r=g","caption":"Exaudi Staff"},"description":"What is Exaudi News? Exaudi News is an international Catholic media outlet that informs, shapes, and transforms daily in Spanish, English, and Italian. Through news, analytical articles, and live broadcasts of the Pope's events, Exaudi seeks to strengthen Christian unity and contribute to the evangelization of the world, always guided by the Church's social doctrine. We work to bring Christian truth and values \u200b\u200bto every corner of the planet. Help us transform the world with Exaudi! At Exaudi, we believe that evangelization and quality information can change lives. To continue our mission and expand our reach, we need your help. In addition, we are looking for committed people to join our team. With your support, we will reach more people, spread the message of Christ, and strengthen Christian unity. Will you join our mission? For more information on how to collaborate, visit Exaudi.org or contact us directly: info@exaudi.org Exaudi: Informs, educates, and transforms.","sameAs":["https:\/\/www.facebook.com\/ExaudiNews","https:\/\/www.instagram.com\/exaudi_news","https:\/\/x.com\/Exaudi_News","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/dfe\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/06\/pexels-arnav-kainthola-6352761-scaled.jpg?fit=2560%2C1155&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-feo","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/58552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=58552"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/58552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/58553"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=58552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=58552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=58552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}