{"id":57118,"date":"2022-05-20T20:22:48","date_gmt":"2022-05-20T18:22:48","guid":{"rendered":"https:\/\/exaudi.org\/?p=57118"},"modified":"2022-05-20T20:22:48","modified_gmt":"2022-05-20T18:22:48","slug":"la-semana-laudato-si-crear-una-masa-social-critica-y-proteger-nuestra-casa-comun","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/la-semana-laudato-si-crear-una-masa-social-critica-y-proteger-nuestra-casa-comun\/","title":{"rendered":"La Semana Laudato si&#8217;: Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/laudatosiweek.org\/es\/home-es\/\">La Semana Laudato si<\/a><\/span>&#8216;<\/span><span style=\"font-weight: 400;\">, el evento de una semana de duraci\u00f3n que marca el s\u00e9ptimo aniversario de la enc\u00edclica del Papa Francisco sobre el cuidado de la creaci\u00f3n<\/span><span style=\"font-weight: 400;\"> contar\u00e1 con una serie de<\/span> <span style=\"font-weight: 400;\">celebraciones globales y conversaciones din\u00e1micas, incluida una centrada en elevar las voces ind\u00edgenas<\/span> <span style=\"font-weight: 400;\">que contar\u00e1 con la presencia de la Hna. Alessandra Smerilli, FMA, Secretaria del Dicasterio para el<\/span> <span style=\"font-weight: 400;\">Servicio del Desarrollo Humano Integral.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cientos de miles de cat\u00f3licos se unir\u00e1n del 22 al 29 de mayo para celebrar los progresos realizados para<\/span> <span style=\"font-weight: 400;\">llevar Laudato Si&#8217; a la vida e intensificar sus esfuerzos a trav\u00e9s de la <\/span><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/plataformadeaccionlaudatosi.org\/\"><span style=\"font-weight: 400;\">Plataforma de Acci\u00f3n Laudato si&#8217;<\/span><\/a><\/span> <span style=\"font-weight: 400;\">promovida por el Dicasterio para el Servicio del Desarrollo Humano Integral del Vaticano. Esta nueva<\/span> <span style=\"font-weight: 400;\">herramienta est\u00e1 capacitando a las instituciones, comunidades y familias cat\u00f3licas para implementar<\/span> <span style=\"font-weight: 400;\">Laudato Si&#8217; en su totalidad.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada d\u00eda de la <\/span><span style=\"font-weight: 400; color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/laudatosiweek.org\/es\/home-es\/\">Semana Laudato si&#8217;<\/a> <\/span><span style=\"font-weight: 400;\">presentar\u00e1 eventos globales, regionales y locales vinculados a uno de los siete Objetivos Laudato si&#8217; y a los siete sectores de la Plataforma de Acci\u00f3n Laudato si\u2019, los cuales sustentan el concepto de ecolog\u00eda integral. A las 17:00 CET del mi\u00e9rcoles 18 de mayo, ya se hab\u00edan registrado 107 eventos en LaudatoSiWeek.org, y se esperan cientos m\u00e1s en los pr\u00f3ximos d\u00edas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre los temas cruciales que se explorar\u00e1n durante la Semana Laudato Si&#8217;: c\u00f3mo los cat\u00f3licos pueden combatir el colapso de la biodiversidad; el papel de los combustibles f\u00f3siles en los conflictos y la crisis clim\u00e1tica; y c\u00f3mo todos podemos abrazar a los pobres en nuestra vida cotidiana.\u00a0<\/span><\/p>\n<p><b>Programa de la Semana Laudato si&#8217;<\/b><b>\u00a0<\/b><\/p>\n<p><b>Lunes 23 de mayo: <\/b><span style=\"font-weight: 400;\">Respuesta al clamor de la Tierra\u00a0<\/span><\/p>\n<p><b><i>10:00 CEST No m\u00e1s colapso de la biodiversidad: Reequilibrar los sistemas sociales con la naturaleza\u00a0<\/i><\/b><\/p>\n<p><span style=\"font-weight: 400;\">Retransmitido en directo desde la Universidad Cat\u00f3lica Australiana de Roma, el padre Joshtrom Kureethadam, del Vaticano, dirigir\u00e1 una din\u00e1mica conversaci\u00f3n centrada en elevar las voces ind\u00edgenas de cara a la conferencia de las Naciones Unidas sobre la biodiversidad que tendr\u00e1 lugar este a\u00f1o.\u00a0<\/span><\/p>\n<p><b>Ponentes destacados:\u00a0<\/b><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> Sor Alessandra Smerill, FMA, Secretaria del Dicasterio para el Servicio del Desarrollo Humano Integral del Vaticano\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Theresa Ardler, investigadora de enlace ind\u00edgena en la Universidad Cat\u00f3lica de Australia, directora y propietaria de Gweagal Cultural Connections<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Vandana Shiva, fundadora de la Fundaci\u00f3n de Investigaci\u00f3n Navdanya para la Ciencia, la Tecnolog\u00eda y la Ecolog\u00eda en la India y Presidenta de Navdanya International\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Padre Joshtrom Isaac Kureethadam, Jefe de la Oficina de Ecolog\u00eda y Creaci\u00f3n del Vaticano,<\/span> <span style=\"font-weight: 400;\">Dicasterio para el Servicio del Desarrollo Humano Integral<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Angela Manno, artista premiada<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Greg Asner, Director del Centro ASU de Descubrimiento Global y Ciencia de la Conservaci\u00f3n<\/span><\/li>\n<\/ul>\n<p><b>Martes, 24 de mayo: <\/b><span style=\"font-weight: 400;\">Respuesta al clamor de los pobres (7mo aniversario de LS) <\/span><b><i>9:00 CEST<\/i><\/b><b><i> Empoderamiento de la ECO-munidad: Abrazando a los pobres\u00a0<\/i><\/b><\/p>\n<p><b>Mi\u00e9rcoles, 25 de mayo: <\/b><span style=\"font-weight: 400;\">Econom\u00eda Ecol\u00f3gica\u00a0<\/span><\/p>\n<p><b><i>15:00 CEST Combustibles f\u00f3siles, violencia y crisis clim\u00e1tica\u00a0<\/i><\/b><\/p>\n<p><b><i>Con <\/i><\/b><b><i>Jeffrey D. Sachs<\/i><\/b><b><i>\u00a0<\/i><\/b><\/p>\n<p><b>Jueves, 26 de mayo: <\/b><span style=\"font-weight: 400;\">Adopci\u00f3n de estilos de vida sostenibles (Fiesta de la Ascensi\u00f3n) <\/span><b><i>15:30 CEST Invertir en Laudato Si&#8217;\u00a0<\/i><\/b><\/p>\n<p><b>Viernes, 27 de mayo: <\/b><span style=\"font-weight: 400;\">Educaci\u00f3n Ecol\u00f3gica\u00a0<\/span><\/p>\n<p><b><i>14:00 CEST Avance: Largometraje documental sobre Laudato si&#8217;<\/i><\/b><b><i>\u00a0<\/i><\/b><\/p>\n<p><b>S\u00e1bado, 28 de mayo: <\/b><span style=\"font-weight: 400;\">Espiritualidad Ecol\u00f3gica\u00a0<\/span><\/p>\n<p><b><i>19:00-21:00 CEST Festival Laudato si\u2019\u00a0<\/i><\/b><\/p>\n<p><b><i>Con Migueli Marin y Marco Mammoli\u00a0<\/i><\/b><\/p>\n<p><b>Domingo, 29 de mayo: <\/b><span style=\"font-weight: 400;\">Resiliencia y empoderamiento de la comunidad como parte de nuestro Viaje Sinodal\u00a0<\/span><\/p>\n<p><b><i>15:00 CEST<\/i><\/b><b><i> Encuentro de oraci\u00f3n de clausura de la Semana Laudato si&#8217;: La resiliencia y el empoderamiento de las comunidades como parte de nuestro viaje sinodal\u00a0<\/i><\/b><\/p>\n<p><span style=\"font-weight: 400;\">El programa completo y final de la Semana Laudato si&#8217;, que incluye los eventos mundiales en Uganda, Italia, Irlanda, Brasil y Filipinas, puede encontrarse <\/span><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/laudatosiweek.org\/es\/events-es\/\"><span style=\"font-weight: 400;\">aqu\u00ed <\/span><\/a><\/span><span style=\"font-weight: 400;\">. El Dicasterio espera que todos se sientan llamados a participar en la Semana Laudato Si&#8217; y a emprender con esp\u00edritu sinodal el \u00abitinerario\u00bb de siete a\u00f1os propuesto por la Plataforma de Acci\u00f3n Laudato Si&#8217;.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">M\u00e1s informaci\u00f3n en <\/span><a href=\"http:\/\/www.laudatosiweek.org\/es\"><span style=\"font-weight: 400;\">LaudatoSiWeek.org\/es<\/span><\/a><span style=\"font-weight: 400;\">. Todos los eventos globales, excluyendo el avance de la pel\u00edcula el 27 de mayo, ser\u00e1n transmitidos en los canales de <\/span><span style=\"font-weight: 400;\">Youtube <\/span><span style=\"font-weight: 400;\">y <\/span><span style=\"font-weight: 400;\">Facebook <\/span><span style=\"font-weight: 400;\">del Movimiento Laudato Si&#8217;.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>7 d\u00edas y cientos de eventos globales, regionales y locales para intensificar los esfuerzos en la lucha contra el cambio clim\u00e1tico <\/p>\n","protected":false},"author":15,"featured_media":57119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[128,59,126],"tags":[3491,4953],"class_list":["post-57118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-especiales","category-featured-news","category-viajes-papales","tag-movimiento-laudato-si","tag-trending-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Semana Laudato si&#039;: Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Semana Laudato si&#039;: Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"7 d\u00edas y cientos de eventos globales, regionales y locales para intensificar los esfuerzos en la lucha contra el cambio clim\u00e1tico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-20T18:22:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/05\/Pope-Francis-Laudato-Si-Esp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1059\" \/>\n\t<meta property=\"og:image:height\" content=\"653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"La Semana Laudato si&#8217;: Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan\",\"datePublished\":\"2022-05-20T18:22:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/\"},\"wordCount\":712,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Pope-Francis-Laudato-Si-Esp.jpg?fit=1059%2C653&ssl=1\",\"keywords\":[\"Movimiento Laudato Si'\",\"Trending\"],\"articleSection\":[\"Eventos especiales\",\"Featured News\",\"Viajes Papales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/\",\"name\":\"La Semana Laudato si': Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Pope-Francis-Laudato-Si-Esp.jpg?fit=1059%2C653&ssl=1\",\"datePublished\":\"2022-05-20T18:22:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Pope-Francis-Laudato-Si-Esp.jpg?fit=1059%2C653&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Pope-Francis-Laudato-Si-Esp.jpg?fit=1059%2C653&ssl=1\",\"width\":1059,\"height\":653},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Semana Laudato si&#8217;: Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Semana Laudato si': Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/","og_locale":"es_ES","og_type":"article","og_title":"La Semana Laudato si': Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan &#8211; Exaudi","og_description":"7 d\u00edas y cientos de eventos globales, regionales y locales para intensificar los esfuerzos en la lucha contra el cambio clim\u00e1tico","og_url":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2022-05-20T18:22:48+00:00","og_image":[{"width":1059,"height":653,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/05\/Pope-Francis-Laudato-Si-Esp.jpg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"La Semana Laudato si&#8217;: Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan","datePublished":"2022-05-20T18:22:48+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/"},"wordCount":712,"image":{"@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/05\/Pope-Francis-Laudato-Si-Esp.jpg?fit=1059%2C653&ssl=1","keywords":["Movimiento Laudato Si'","Trending"],"articleSection":["Eventos especiales","Featured News","Viajes Papales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/","url":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/","name":"La Semana Laudato si': Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/05\/Pope-Francis-Laudato-Si-Esp.jpg?fit=1059%2C653&ssl=1","datePublished":"2022-05-20T18:22:48+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/05\/Pope-Francis-Laudato-Si-Esp.jpg?fit=1059%2C653&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/05\/Pope-Francis-Laudato-Si-Esp.jpg?fit=1059%2C653&ssl=1","width":1059,"height":653},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/laudato-si-week-create-a-critical-social-mass-and-protect-our-common-home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"La Semana Laudato si&#8217;: Crear una masa social cr\u00edtica y proteger nuestra casa com\u00fan"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-eRg","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2022\/05\/Pope-Francis-Laudato-Si-Esp.jpg?fit=1059%2C653&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/57118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=57118"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/57118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/57119"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=57118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=57118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=57118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}