{"id":54880,"date":"2022-03-23T13:28:46","date_gmt":"2022-03-23T12:28:46","guid":{"rendered":"https:\/\/exaudi.org\/?p=54880"},"modified":"2022-03-24T16:09:19","modified_gmt":"2022-03-24T15:09:19","slug":"fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/","title":{"rendered":"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial"},"content":{"rendered":"<p>\u201cLa fe se transmite siempre en dialecto, en ese dialecto familiar y vivencial aprendido a lo largo de los a\u00f1os. Por eso es muy importante el di\u00e1logo en una familia, el di\u00e1logo de los ni\u00f1os con los abuelos que son aquellos que tienen la sabidur\u00eda de la fe\u201d, se\u00f1al\u00f3 el Papa Francisco.<\/p>\n<p>Durante la audiencia general de este mi\u00e9rcoles, 23 de marzo de 2022, el Santo Padre ha proseguido con el ciclo de catequesis sobre la importancia de la vejez, reflexionando sobre el tema: \u201cLa despedida y la herencia: memoria y testimonio\u201d.<\/p>\n<h2><strong>El ejemplo de Mois\u00e9s<\/strong><\/h2>\n<p>En este sentido, Francisco propone el ejemplo de Mois\u00e9s: En la Biblia, el pasaje de la muerte del viejo Mois\u00e9s est\u00e1 precedido por su testamento espiritual, llamado \u201cC\u00e1ntico de Mois\u00e9s\u201d. Este C\u00e1ntico es en primer lugar una bell\u00edsima confesi\u00f3n de fe (\u2026). Pero, contin\u00faa \u201ctambi\u00e9n es memoria de la historia vivida con Dios, de las aventuras del pueblo que se ha formado a partir de la fe en el Dios de Abraham, Isaac y Jacob. Y por tanto Mois\u00e9s recuerda tambi\u00e9n las amarguras y las desilusiones del mismo Dios: Su fidelidad puesta continuamente a prueba por la infidelidad de su pueblo. El Dios fiel y la respuesta del pueblo infiel: como si el pueblo quisiera poner a prueba la fidelidad de Dios. Y \u00c9l permanece siempre fiel, cerca de su pueblo. Este es precisamente el n\u00facleo del C\u00e1ntico de Mois\u00e9s: la fidelidad de Dios que nos acompa\u00f1a durante toda la vida\u201d.<\/p>\n<p>El Papa resalta tambi\u00e9n que cuando Mois\u00e9s pronuncia esta confesi\u00f3n de fe \u201cest\u00e1 en el umbral de la tierra prometida, y tambi\u00e9n de su despedida de la vida. Ten\u00eda ciento veinte a\u00f1os, se\u00f1ala la narraci\u00f3n, pero \u2018no se hab\u00eda apagado su ojo\u2019 (<em>Dt<\/em>\u00a034,7). Esa capacidad de ver, ver realmente y tambi\u00e9n ver simb\u00f3licamente, como tienen los ancianos, que saben ver las cosas, el significado m\u00e1s profundo de las cosas. La vitalidad de su mirada es un don valioso: le consiente\u00a0<em>transmitir la herencia<\/em>\u00a0de su larga experiencia de vida y de fe, con la lucidez necesaria. Mois\u00e9s ve la historia y transmite la historia; los ancianos ven la historia y transmiten la historia\u201d, a\u00f1ade.<\/p>\n<p>Para el Pont\u00edfice, la narraci\u00f3n de la historia de fe \u201cdeber\u00eda ser como el C\u00e1ntico de Mois\u00e9s, como el testimonio de los Evangelios y de los Hechos de los Ap\u00f3stoles. Es decir, una historia capaz de recordar con emoci\u00f3n la bendici\u00f3n de Dios y con lealtad nuestras faltas\u201d.<\/p>\n<h2><strong>La fe transmitida en dialecto, tesoro grande<\/strong><\/h2>\n<p>Por ello, prosigue, \u201cser\u00eda bonito que en los itinerarios de catequesis existiera desde el principio tambi\u00e9n la costumbre de escuchar, de la experiencia vivida de los ancianos, la l\u00facida confesi\u00f3n de las bendiciones recibidas por Dios, que debemos custodiar, y el leal testimonio de nuestras faltas de fidelidad, que debemos reparar y corregir\u201d.<\/p>\n<p>\u201cLos ancianos entran en la tierra prometida, que Dios desea para toda generaci\u00f3n, cuando ofrecen a los j\u00f3venes la bella iniciaci\u00f3n de su testimonio y transmiten la historia de la fe, la fe en dialecto, ese dialecto familiar, ese dialecto que pasa de los ancianos a los j\u00f3venes. Entonces, guiados por el Se\u00f1or Jes\u00fas, ancianos y j\u00f3venes entran juntos en su Reino de vida y de amor.\u00a0 Pero todos juntos. Todos en familia, con este tesoro grande que es la fe transmitida en dialecto\u201d, apunta.<\/p>\n<p>A continuaci\u00f3n, sigue la catequesis competa del Santo Padre.<\/p>\n<p>***<\/p>\n<h2><strong>Catequesis sobre la vejez 4.<em>\u00a0La despedida y la herencia: memoria y testimonio<\/em><\/strong><\/h2>\n<p>Queridos hermanos y hermanas, \u00a1buenos d\u00edas!<\/p>\n<p>En la Biblia, el pasaje de la muerte del viejo Mois\u00e9s est\u00e1 precedido por su testamento espiritual, llamado \u201cC\u00e1ntico de Mois\u00e9s\u201d. Este C\u00e1ntico es en primer lugar una bell\u00edsima confesi\u00f3n de fe, y dice as\u00ed: \u201cPorque voy a aclamar el nombre de Yahveh; \u00a1ensalzad a nuestro Dios! \u00c9l es la Roca, su obra es consumada, pues todos sus caminos son justicia. Es Dios de lealtad, no de perfidia, es justo y recto\u201d (<em>Dt<\/em>\u00a032,3-4). \u00a0Pero tambi\u00e9n es memoria de la historia vivida con Dios, de las aventuras del pueblo que se ha formado a partir de la fe en el Dios de Abraham, Isaac y Jacob. Y por tanto Mois\u00e9s recuerda tambi\u00e9n las amarguras y las desilusiones del mismo Dios: Su fidelidad puesta continuamente a prueba por la infidelidad de su pueblo. El Dios fiel y la respuesta del pueblo infiel: como si el pueblo quisiera poner a prueba la fidelidad de Dios. Y \u00c9l permanece siempre fiel, cerca de su pueblo. Este es precisamente el n\u00facleo del C\u00e1ntico de Mois\u00e9s: la fidelidad de Dios que nos acompa\u00f1a durante toda la vida.<\/p>\n<p>Cuando Mois\u00e9s pronuncia esta confesi\u00f3n de fe est\u00e1 en el umbral de la tierra prometida, y tambi\u00e9n de su despedida de la vida. Ten\u00eda ciento veinte a\u00f1os, se\u00f1ala la narraci\u00f3n, pero \u201cno se hab\u00eda apagado su ojo\u201d (<em>Dt<\/em>\u00a034,7). Esa capacidad de ver, ver realmente y tambi\u00e9n ver simb\u00f3licamente, como tienen los ancianos, que saben ver las cosas, el significado m\u00e1s profundo de las cosas. La vitalidad de su mirada es un don valioso: le consiente\u00a0<em>transmitir la herencia<\/em>\u00a0de su larga experiencia de vida y de fe, con la lucidez necesaria. Mois\u00e9s ve la historia y transmite la historia; los ancianos ven la historia y transmiten la historia.<\/p>\n<p>Una vejez a la cual le es concedida esta lucidez es un don valioso para la pr\u00f3xima generaci\u00f3n. La escucha personal y directa del pasaje de la historia de fe vivida, con todos sus altibajos, es insustituible. Leerla en los libros, verla en las pel\u00edculas, consultarla en internet, aunque sea \u00fatil, nunca ser\u00e1 lo mismo. Esta transmisi\u00f3n \u2014\u00a1que es la aut\u00e9ntica\u00a0<em>tradici\u00f3n<\/em>, la transmisi\u00f3n concreta del anciano al joven! \u2014, esta transmisi\u00f3n le falta mucho hoy, y cada vez m\u00e1s, a las nuevas generaciones. \u00bfPor qu\u00e9? Porque esta civilizaci\u00f3n nueva tiene la idea de que los ancianos son material de descarte, los ancianos deben ser descartados. \u00a1Esto es una brutalidad! No, no es as\u00ed. La narraci\u00f3n directa, de persona a persona, tiene tonos y modos de comunicaci\u00f3n que ning\u00fan otro medio puede sustituir. Un anciano que ha vivido mucho, y obtiene el don de un\u00a0<em>l\u00facido y apasionado testimonio<\/em>\u00a0de su historia, es una bendici\u00f3n insustituible. \u00bfSomos capaces de reconocer y de honrar este don de los ancianos? \u00bfLa transmisi\u00f3n de la fe \u2014y del sentido de la vida\u2014 sigue hoy este camino de escucha de los ancianos?\u00a0 Yo puedo dar un testimonio personal. El odio y la rabia contra la guerra yo lo aprend\u00ed de mi abuelo que combati\u00f3 en el Piave, en 1914: \u00e9l me transmiti\u00f3 esta rabia a la guerra. Porque me cont\u00f3 los sufrimientos de una guerra. Y esto no se aprende ni en los libros ni de otra manera, se aprende as\u00ed, transmiti\u00e9ndola de abuelos a nietos. Y esto es insustituible. La transmisi\u00f3n de la experiencia de vida de los abuelos a los nietos. Lamentablemente hoy esto no es as\u00ed y se piensa que los abuelos sean material de descarte: \u00a1no! Son la memoria viva de un pueblo y los j\u00f3venes y los ni\u00f1os deben escuchar a los abuelos.<\/p>\n<p>En nuestra cultura, tan \u201cpol\u00edticamente correcta\u201d, este camino resulta obstaculizado de varias formas: en la familia, en la sociedad, en la misma comunidad cristiana. Hay quien propone incluso abolir la ense\u00f1anza de la historia, como una informaci\u00f3n superflua sobre mundos que ya no son actuales, que quita recursos al conocimiento del presente. \u00a1C\u00f3mo si nosotros hubi\u00e9ramos nacido ayer!<\/p>\n<p>A la transmisi\u00f3n de la fe, por otro lado, le falta a menudo la pasi\u00f3n propia de una \u201chistoria vivida\u201d. Transmitir la fe no es decir las cosas \u201cbla-bla-bla\u201d. Es contar la experiencia de fe. \u00bfY entonces dif\u00edcilmente puede atraer a elegir el amor para siempre, la fidelidad a la palabra dada, la perseverancia en la entrega, la compasi\u00f3n por los rostros heridos y abatidos? Ciertamente, las historias de la vida deben ser transformadas en testimonio, y el testimonio debe ser leal. No es ciertamente leal la ideolog\u00eda que doblega la historia a los propios esquemas; no es leal la propaganda, que adapta la historia a la promoci\u00f3n del propio grupo; no es leal hacer de la historia un tribunal en el que se condena todo el pasado y se desalienta todo futuro. Ser leal es contar la historia como es, y solamente la puede contar bien quien la ha vivido. Por esto es muy importante escuchar a los ancianos, escuchar a los abuelos, es importante que los ni\u00f1os hablen con ellos.<\/p>\n<p>Los mismos Evangelios cuentan honestamente la historia bendita de Jes\u00fas sin esconder los errores, las incomprensiones e incluso las traiciones de sus disc\u00edpulos. Esta es la historia, es la verdad, esto es testimonio. Este es el don de la memoria que los \u201cancianos\u201d de la Iglesia transmiten, desde el inicio, pas\u00e1ndolo \u201cde mano en mano\u201d a la pr\u00f3xima generaci\u00f3n. Nos har\u00e1 bien preguntarnos: \u00bfcu\u00e1nto valoramos esta forma de transmitir la fe, de pasar el testigo entre los ancianos de la comunidad y los j\u00f3venes que se abren al futuro? Y aqu\u00ed me viene a la mente algo que he dicho muchas veces, pero quisiera repetirlo. \u00bfC\u00f3mo se transmite la fe? \u201cAh, aqu\u00ed hay un libro, est\u00fadialo\u201d: no. As\u00ed no se puede transmitir la fe. La fe se transmite en dialecto, es decir en el habla familiar, entre abuelos y nietos, entre padres y nietos. La fe se transmite siempre en dialecto, en ese dialecto familiar y vivencial aprendido a lo largo de los a\u00f1os. Por eso es muy importante el di\u00e1logo en una familia, el di\u00e1logo de los ni\u00f1os con los abuelos que son aquellos que tienen la sabidur\u00eda de la fe.<\/p>\n<p>A veces reflexiono sobre esta extra\u00f1a anomal\u00eda. El catecismo de la iniciaci\u00f3n cristiana bebe hoy generosamente en la Palabra de Dios y transmite informaci\u00f3n precisa sobre los dogmas, sobre la moral de la fe y los sacramentos. A menudo falta, sin embargo, un conocimiento de la Iglesia que nazca de la escucha y del testimonio de la historia real de la fe y de la vida de la comunidad eclesial, desde el inicio hasta nuestros d\u00edas. De ni\u00f1os se aprende la Palabra de Dios en las aulas del catecismo; pero la Iglesia se \u201caprende\u201d, de j\u00f3venes, en las aulas escolares y en los medios de comunicaci\u00f3n de la informaci\u00f3n global.<\/p>\n<p>La narraci\u00f3n de la historia de fe deber\u00eda ser como el C\u00e1ntico de Mois\u00e9s, como el testimonio de los Evangelios y de los Hechos de los Ap\u00f3stoles. Es decir, una historia capaz de recordar con emoci\u00f3n la bendici\u00f3n de Dios y con lealtad nuestras faltas. Ser\u00eda bonito que en los itinerarios de catequesis existiera desde el principio tambi\u00e9n la costumbre de escuchar, de la experiencia vivida de los ancianos, la l\u00facida confesi\u00f3n de las bendiciones recibidas por Dios, que debemos custodiar, y el leal testimonio de nuestras faltas de fidelidad, que debemos reparar y corregir. Los ancianos entran en la tierra prometida, que Dios desea para toda generaci\u00f3n, cuando ofrecen a los j\u00f3venes la bella iniciaci\u00f3n de su testimonio y transmiten la historia de la fe, la fe en dialecto, ese dialecto familiar, ese dialecto que pasa de los ancianos a los j\u00f3venes. Entonces, guiados por el Se\u00f1or Jes\u00fas, ancianos y j\u00f3venes entran juntos en su Reino de vida y de amor.\u00a0 Pero todos juntos. Todos en familia, con este tesoro grande que es la fe transmitida en dialecto.<\/p>\n<p><strong>\u00a9 Librer\u00eda Editora Vaticana<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Catequesis completa del Santo Padre<\/p>\n","protected":false},"author":15,"featured_media":54881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[112,68],"tags":[179,158],"class_list":["post-54880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audiencia-general","category-leon-xiv","tag-audiencia-general","tag-papa-francisco"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"\u201cLa fe se transmite siempre en dialecto, en ese dialecto familiar y vivencial aprendido a lo largo de los a\u00f1os\u201d, se\u00f1al\u00f3 el Papa Francisco.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"\u201cLa fe se transmite siempre en dialecto, en ese dialecto familiar y vivencial aprendido a lo largo de los a\u00f1os\u201d, se\u00f1al\u00f3 el Papa Francisco.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-23T12:28:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-24T15:09:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/03\/DSC8135-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial\",\"datePublished\":\"2022-03-23T12:28:46+00:00\",\"dateModified\":\"2022-03-24T15:09:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/\"},\"wordCount\":2051,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DSC8135-scaled.jpg\",\"keywords\":[\"audiencia general\",\"papa francisco\"],\"articleSection\":[\"Audiencia General\",\"Le\u00f3n XIV\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/\",\"name\":\"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DSC8135-scaled.jpg\",\"datePublished\":\"2022-03-23T12:28:46+00:00\",\"dateModified\":\"2022-03-24T15:09:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"description\":\"\u201cLa fe se transmite siempre en dialecto, en ese dialecto familiar y vivencial aprendido a lo largo de los a\u00f1os\u201d, se\u00f1al\u00f3 el Papa Francisco.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DSC8135-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DSC8135-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Audiencia general, 23 marzo 2022 \u00a9 Vatican Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial &#8211; Exaudi","description":"\u201cLa fe se transmite siempre en dialecto, en ese dialecto familiar y vivencial aprendido a lo largo de los a\u00f1os\u201d, se\u00f1al\u00f3 el Papa Francisco.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial &#8211; Exaudi","og_description":"\u201cLa fe se transmite siempre en dialecto, en ese dialecto familiar y vivencial aprendido a lo largo de los a\u00f1os\u201d, se\u00f1al\u00f3 el Papa Francisco.","og_url":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2022-03-23T12:28:46+00:00","article_modified_time":"2022-03-24T15:09:19+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/03\/DSC8135-scaled.jpg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial","datePublished":"2022-03-23T12:28:46+00:00","dateModified":"2022-03-24T15:09:19+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/"},"wordCount":2051,"image":{"@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/03\/DSC8135-scaled.jpg","keywords":["audiencia general","papa francisco"],"articleSection":["Audiencia General","Le\u00f3n XIV"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/","url":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/","name":"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/03\/DSC8135-scaled.jpg","datePublished":"2022-03-23T12:28:46+00:00","dateModified":"2022-03-24T15:09:19+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"description":"\u201cLa fe se transmite siempre en dialecto, en ese dialecto familiar y vivencial aprendido a lo largo de los a\u00f1os\u201d, se\u00f1al\u00f3 el Papa Francisco.","breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/03\/DSC8135-scaled.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/03\/DSC8135-scaled.jpg","width":2560,"height":1707,"caption":"Audiencia general, 23 marzo 2022 \u00a9 Vatican Media"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/fe-se-transmite-siempre-en-dialecto-familiar-y-vivencial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u201cLa fe se transmite siempre en dialecto\u201d, familiar y vivencial"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2022\/03\/DSC8135-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-eha","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/54880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=54880"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/54880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/54881"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=54880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=54880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=54880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}