{"id":43410,"date":"2021-12-01T11:06:16","date_gmt":"2021-12-01T10:06:16","guid":{"rendered":"https:\/\/exaudi.org\/?p=43410"},"modified":"2021-12-01T13:50:34","modified_gmt":"2021-12-01T12:50:34","slug":"honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/","title":{"rendered":"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio"},"content":{"rendered":"<p>Una de las \u00e1reas de trabajo que ha desarrollado la <a href=\"https:\/\/redfranciscana.org\/\">Red Franciscana para Migrantes<\/a> es capacitar a sus miembros en temas de inter\u00e9s que les permitan prestar un mejor servicio a las personas migrantes. La defensa de los derechos humanos es uno de los objetivos. Por este motivo, junto a\u00a0<a href=\"https:\/\/franciscansinternational.org\/home\/\" target=\"_blank\" rel=\"noopener\">Franciscans International,<\/a> la ONG de la Familia Franciscana ante Naciones Unidas, se prepar\u00f3 el contenido de la capacitaci\u00f3n titulada\u00a0\u201cDerechos Humanos y Migraci\u00f3n\u201d. Esta actividad tuvo lugar el pa\u00eds de <a href=\"https:\/\/exaudi.org\/es\/honduras-obispos-votar-responsabildiad\/\" target=\"_blank\" rel=\"noopener\">Honduras<\/a> en la regi\u00f3n centroamericana.<\/p>\n<h2><strong>Una formaci\u00f3n entre lo virtual y lo presencial<\/strong><\/h2>\n<p>\u201cLa\u00a0<a href=\"https:\/\/redfranciscana.org\/finaliza-capacitacion-virtual-migracion-y-derechos-humanos-2021\/\">primera parte fue virtual sincr\u00f3nica<\/a>\u00a0y se realiz\u00f3 en 6 m\u00f3dulos durante tres meses. La segunda parte fue un desaf\u00edo y una gran alegr\u00eda haber podido realizarla de forma presencial en las cercan\u00edas de Tegucigalpa, Honduras. Un total de 18 personas, provenientes de M\u00e9xico (Tenosique, Salto de Agua, Cholula), Colombia (Medell\u00edn, Bogot\u00e1, Barrancabermeja), El Salvador (San Salvador), Guatemala (C. de Guatemala), Suiza (Ginebra), Italia (Roma) y Honduras (Tegucigalpa, La Mosquitia)\u201d expres\u00f3 Fray Jaime Campos de la oficina de Justicia, Paz e Integridad de la Creaci\u00f3n.<\/p>\n<p>Durante este encuentro las delegaciones participantes intercambiaron experiencia con familias de migrantes, lo que les permiti\u00f3 reconocer el contexto de uno de los pa\u00edses centroamericanos que m\u00e1s migrantes expulsa de su territorio anualmente.<\/p>\n<p>Fray Jaime comparti\u00f3 que \u201cAl mismo tiempo, pudimos constatar los esfuerzos que se hacen para mantener viva la esperanza y ofrecer, sobre todo a los j\u00f3venes, oportunidades que les permitan superar la falta de empleo y la amenaza constante de la violencia del crimen organizado presente en gran parte del territorio nacional\u201d.<\/p>\n<p>La Red Franciscana para Migrantes surgi\u00f3 en abril de 2018 durante el Curso anual de JPIC, realizado en Guadalajara, M\u00e9xico, cuyo tema central fue \u201cMigraci\u00f3n: causas, muros y perspectivas franciscanas\u201d. El trabajo de La 72, un Hogar-refugio para personas migrantes en la frontera sur de M\u00e9xico, inspir\u00f3 el di\u00e1logo entre los frailes sobre c\u00f3mo compartir informaci\u00f3n y ofrecer apoyo y protecci\u00f3n a las personas que han sido desplazadas por la fuerza debido a situaciones de extrema pobreza, violencia institucional, el crimen organizado y los carteles de la droga; particularmente a las personas del tri\u00e1ngulo norte de Am\u00e9rica Central: Honduras, El Salvador y Guatemala.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La defensa de los derechos humanos, uno de los objetivos<\/p>\n","protected":false},"author":29,"featured_media":43416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[86],"tags":[1495],"class_list":["post-43410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iglesia-local","tag-honduras"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"Red Franciscana para Migrantes reflexiona para brindar mejor servicio a las personas migrantes y para la defensa de los derechos humanos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Red Franciscana para Migrantes reflexiona para brindar mejor servicio a las personas migrantes y para la defensa de los derechos humanos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T10:06:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-01T12:50:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/12\/32.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Cristhian Alvarenga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristhian Alvarenga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/\"},\"author\":{\"name\":\"Cristhian Alvarenga\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/cc0c4abb8e41070fb467c5272d6726d1\"},\"headline\":\"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio\",\"datePublished\":\"2021-12-01T10:06:16+00:00\",\"dateModified\":\"2021-12-01T12:50:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/\"},\"wordCount\":399,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/32.png?fit=1350%2C900&ssl=1\",\"keywords\":[\"Honduras\"],\"articleSection\":[\"Iglesia Local\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/\",\"name\":\"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/32.png?fit=1350%2C900&ssl=1\",\"datePublished\":\"2021-12-01T10:06:16+00:00\",\"dateModified\":\"2021-12-01T12:50:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/cc0c4abb8e41070fb467c5272d6726d1\"},\"description\":\"Red Franciscana para Migrantes reflexiona para brindar mejor servicio a las personas migrantes y para la defensa de los derechos humanos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/32.png?fit=1350%2C900&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/32.png?fit=1350%2C900&ssl=1\",\"width\":1350,\"height\":900,\"caption\":\"Red Franciscana para Migrantes en Honduras \u00a9 Red Franciscana para Migrantes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/cc0c4abb8e41070fb467c5272d6726d1\",\"name\":\"Cristhian Alvarenga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d1e961ad75d3388e09e7a712fdb4ee1c94d947afa0d5dbfdcbd86a5c99bcb40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d1e961ad75d3388e09e7a712fdb4ee1c94d947afa0d5dbfdcbd86a5c99bcb40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d1e961ad75d3388e09e7a712fdb4ee1c94d947afa0d5dbfdcbd86a5c99bcb40?s=96&d=mm&r=g\",\"caption\":\"Cristhian Alvarenga\"},\"description\":\"Periodista de profesi\u00f3n. Del 2015 al 2020 coordin\u00e9 el \u00e1rea de prensa en la di\u00f3cesis de Le\u00f3n, Nicaragua y fui parte de la comisi\u00f3n de comunicaci\u00f3n diocesana, soy el autor del blog Iglesia en Salida, (https:\\\/\\\/www.facebook.com\\\/IglesiaEnSalidaOrg), un espacio de informaci\u00f3n y comunicaci\u00f3n, orientado a generar reflexi\u00f3n, investigaci\u00f3n e informaci\u00f3n sobre el quehacer pastoral de la Iglesia Cat\u00f3lica en Nicaragua, as\u00ed como promover devociones para fomentar nuestra fe. Me gusta producir podcast y escribir poes\u00eda. La defensa del medio ambiente y de los Derechos Humanos debe de ser siempre un compromiso para aportar a un mundo m\u00e1s humano y justo.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/cristhianalvarenga\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio &#8211; Exaudi","description":"Red Franciscana para Migrantes reflexiona para brindar mejor servicio a las personas migrantes y para la defensa de los derechos humanos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/","og_locale":"es_ES","og_type":"article","og_title":"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio &#8211; Exaudi","og_description":"Red Franciscana para Migrantes reflexiona para brindar mejor servicio a las personas migrantes y para la defensa de los derechos humanos.","og_url":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2021-12-01T10:06:16+00:00","article_modified_time":"2021-12-01T12:50:34+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/12\/32.png","type":"image\/png"}],"author":"Cristhian Alvarenga","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Cristhian Alvarenga","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/"},"author":{"name":"Cristhian Alvarenga","@id":"https:\/\/exaudi.org\/#\/schema\/person\/cc0c4abb8e41070fb467c5272d6726d1"},"headline":"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio","datePublished":"2021-12-01T10:06:16+00:00","dateModified":"2021-12-01T12:50:34+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/"},"wordCount":399,"commentCount":0,"image":{"@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/12\/32.png?fit=1350%2C900&ssl=1","keywords":["Honduras"],"articleSection":["Iglesia Local"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/","url":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/","name":"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/12\/32.png?fit=1350%2C900&ssl=1","datePublished":"2021-12-01T10:06:16+00:00","dateModified":"2021-12-01T12:50:34+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/cc0c4abb8e41070fb467c5272d6726d1"},"description":"Red Franciscana para Migrantes reflexiona para brindar mejor servicio a las personas migrantes y para la defensa de los derechos humanos.","breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/12\/32.png?fit=1350%2C900&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/12\/32.png?fit=1350%2C900&ssl=1","width":1350,"height":900,"caption":"Red Franciscana para Migrantes en Honduras \u00a9 Red Franciscana para Migrantes"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/honduras-red-franciscana-para-migrantes-reflexiona-para-brindar-mejor-servicio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Honduras: Red Franciscana para Migrantes reflexiona para brindar mejor servicio"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/cc0c4abb8e41070fb467c5272d6726d1","name":"Cristhian Alvarenga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d1e961ad75d3388e09e7a712fdb4ee1c94d947afa0d5dbfdcbd86a5c99bcb40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d1e961ad75d3388e09e7a712fdb4ee1c94d947afa0d5dbfdcbd86a5c99bcb40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d1e961ad75d3388e09e7a712fdb4ee1c94d947afa0d5dbfdcbd86a5c99bcb40?s=96&d=mm&r=g","caption":"Cristhian Alvarenga"},"description":"Periodista de profesi\u00f3n. Del 2015 al 2020 coordin\u00e9 el \u00e1rea de prensa en la di\u00f3cesis de Le\u00f3n, Nicaragua y fui parte de la comisi\u00f3n de comunicaci\u00f3n diocesana, soy el autor del blog Iglesia en Salida, (https:\/\/www.facebook.com\/IglesiaEnSalidaOrg), un espacio de informaci\u00f3n y comunicaci\u00f3n, orientado a generar reflexi\u00f3n, investigaci\u00f3n e informaci\u00f3n sobre el quehacer pastoral de la Iglesia Cat\u00f3lica en Nicaragua, as\u00ed como promover devociones para fomentar nuestra fe. Me gusta producir podcast y escribir poes\u00eda. La defensa del medio ambiente y de los Derechos Humanos debe de ser siempre un compromiso para aportar a un mundo m\u00e1s humano y justo.","url":"https:\/\/exaudi.org\/es\/author\/cristhianalvarenga\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-bia","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/12\/32.png?fit=1350%2C900&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/43410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=43410"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/43410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/43416"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=43410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=43410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=43410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}