{"id":22886,"date":"2026-06-17T07:30:54","date_gmt":"2026-06-17T05:30:54","guid":{"rendered":"https:\/\/exaudi.org\/?p=22886"},"modified":"2026-05-26T10:53:54","modified_gmt":"2026-05-26T08:53:54","slug":"beato-jose-maria-cassant-17-junio","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/","title":{"rendered":"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio"},"content":{"rendered":"<p>\u00a1Cu\u00e1ntas vocaciones se han salvado de un casi seguro naufragio debido a la fe de hombres y mujeres de Dios que no vieron lastre alguno en las dificultades o carencias de quienes tuvieron delante! A este beato le ayudaron a sostener el tim\u00f3n de su barca. Sin esa dedicaci\u00f3n, tal vez habr\u00eda zozobrado. Aunque no fuese su caso, hay quien no es capaz de remontar sus deficiencias personales. Afronta las jornadas portando la frustraci\u00f3n por todo equipaje, y la tristeza con la que va revestida, sin haber gustado el amor de Dios, ignorando c\u00f3mo puede darle cumplida respuesta. Qui\u00e9n sabe si \u00e9l se hubiera privado de la gloria que alcanz\u00f3 de no contar con la certera visi\u00f3n y el \u00edmpetu del ap\u00f3stol que lo trat\u00f3 viendo en \u00e9l a un santo. El acompa\u00f1amiento es crucial. Por algo ensalz\u00f3 Cristo la v\u00eda comunitaria para seguirle.<\/p>\n<p><iframe title=\"Spotify Embed: Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/6krb1hYinTsttjMVxts3gY?si=1a7d2f0a4ac345db&amp;utm_source=oembed\"><\/iframe><\/p>\n<p>Pedro Jos\u00e9 naci\u00f3 el 6 de marzo de 1878 en Casseneuil-sur-Lot, Francia. Era el segundo v\u00e1stago de una familia de agricultores bien avenidos. La naturaleza no fue pr\u00f3diga con \u00e9l y quiz\u00e1 por eso pasaba desapercibido en todos los \u00f3rdenes. Tanto en el aspecto f\u00edsico como en el intelectual y social no se pod\u00edan atisbar en su persona esos dones que resultan atractivos a los dem\u00e1s, y que pueden convertirse tambi\u00e9n en instrumento apost\u00f3lico: simpat\u00eda, don de gentes, inteligencia, etc. Pero lo que la vida le hurt\u00f3 estaba compensado espiritualmente por su gran sensibilidad. Y la atracci\u00f3n que experimentaba hacia todo elemento religioso hizo de \u00e9l un excelso modelo en su forma de perseguir la perfecci\u00f3n. Ten\u00eda mucho camino recorrido para ello: bohonom\u00eda, humildad, abnegaci\u00f3n, amabilidad\u2026<\/p>\n<p>Una de sus dificultades era la falta de memoria. Adem\u00e1s, se apreciaban en \u00e9l inseguridades personales, dudas y tendencia al des\u00e1nimo. Lidi\u00f3 con ellas, lo hizo con fuerza. Curs\u00f3 estudios con los Hermanos de la Salle en su localidad natal y poco a poco se afianz\u00f3 su llamada al sacerdocio, esa que estuvo presente en sus juegos infantiles cuando ensayaba c\u00f3mo decir misa en los altares que constru\u00eda. Hubo dos personas fundamentalmente que le ayudaron y le sostuvieron en su peregrinar. Una de ellas fue el p\u00e1rroco padre Filhol quien, al igual que los salesianos, se hab\u00eda percatado de que era propenso a la oraci\u00f3n, de su tendencia al silencio, su fervor por la Eucarist\u00eda y el amor a Mar\u00eda y a la liturgia, entre otros signos de piedad que le caracterizaron.<\/p>\n<p>Consciente de las dificultades que su escasa retentiva le creaba, a pesar del esfuerzo que el beato puso por avanzar en los estudios, el sacerdote le prest\u00f3 asistencia a trav\u00e9s de un vicario. Pero era insuficiente para que las puertas del seminario se le abrieran al muchacho. Por eso le habl\u00f3 de la Trapa; estaba seguro de que era id\u00f3nea para alguien de su peculiaridad. Con 16 a\u00f1os, acompa\u00f1ado por \u00e9l, Pedro Jos\u00e9 ingres\u00f3 en la abad\u00eda cisterciense de Santa Mar\u00eda del Desierto, de Toulouse. El maestro de novicios padre Andr\u00e9 Mallet percibi\u00f3 ese mismo d\u00eda que se hallaba ante una persona especial, limpia, sincera e inocente, que verdaderamente buscaba a Dios. Trazando la se\u00f1al de la cruz sobre su frente, le dijo: \u00ab\u00a1Conf\u00eda! Yo te ayudar\u00e9 a amar a Jes\u00fas\u00bb.<\/p>\n<p>En 1895 tom\u00f3 el h\u00e1bito y el nombre de Jos\u00e9 Mar\u00eda. Y en 1900 emiti\u00f3 los votos perpetuos. Humilde, gozoso en su nueva vida, se esforzaba por cumplir la regla con esp\u00edritu de mansedumbre, y encomiable obediencia. La formaci\u00f3n segu\u00eda constituyendo para \u00e9l una dolorosa espina. Junto a ella completaban espeso ramillete otros \u00edntimos dardos cargados con mal\u00e9vola insidia para desestabilizar su vida espiritual. T\u00edmido y sinti\u00e9ndose incapaz, ve\u00eda la supremac\u00eda intelectual de sus hermanos, constataba sus virtudes y se sent\u00eda corro\u00eddo por la envidia y los celos. Esos complejos, que hab\u00edan hecho de \u00e9l una persona muy susceptible, le produc\u00edan grandes sufrimientos por cuestiones a veces nimias surgidas en lo cotidiano a las que daba enorme relevancia. Otros lastres insalvables como su mal o\u00eddo y su atiplada voz, que le imped\u00edan entonar debidamente los c\u00e1nticos, acentuaban su baja autoestima.<\/p>\n<p>Le costaba gran esfuerzo sostener un silencio interior: \u00abCuando no tengo libro si mantengo los ojos abiertos me distraigo, si los cierro me duermo\u00bb. Se sent\u00eda perturbado mentalmente en aspectos relativos a la castidad y luchaba dici\u00e9ndose: \u00abSustituir los malos pensamientos por el amor de Jes\u00fas\u00bb, repitiendo una y otra vez en medio de su lucha esta jaculatoria: \u00abTodo por Jes\u00fas, todo por Mar\u00eda\u00bb. El padre Mallet le ayud\u00f3 a combatir sus escr\u00fapulos, le acompa\u00f1\u00f3 y le anim\u00f3, ense\u00f1\u00e1ndole a liberarse por amor a Cristo de tantas ataduras que brotaban de lo m\u00e1s \u00edntimo de su ser. Con su confianza, superando el prejuicio del profesor de teolog\u00eda, y por encima de sus problemas de salud, logr\u00f3 concluir los estudios y fue ordenado sacerdote en 1902. Pero ya no vivir\u00eda mucho tiempo.<\/p>\n<p>Siempre fue fr\u00e1gil, y sus dolores de pecho, de los que nada dijo llevado de su humildad, ese mismo a\u00f1o revelaron su origen: la tuberculosis. Quedaba claro por qu\u00e9 no hab\u00eda podido inclinarse por completo ante el Sant\u00edsimo, hecho por el que fue corregido repetidamente. No se justific\u00f3 ante el superior; sab\u00eda que excusarse es impropio de la vida santa. Si alguien debi\u00f3 haber estado al tanto de su salud, no lo hizo por las razones que fuesen, con lo cual no pudo ser atendido convenientemente. Oficiada la primera misa, fue enviado con su familia; pensaron en su recuperaci\u00f3n. Pero los cercanos dos meses que estuvo junto a ella no sirvieron de nada. Regres\u00f3 con sus hermanos religiosos y se prepar\u00f3 para su entrada en el cielo. \u00abCuando ya no pueda celebrar la Santa Misa \u2013confi\u00f3 al padre Mallet\u2013, el Coraz\u00f3n de Jes\u00fas podr\u00e1 retirarme de este mundo, pues ya no tendr\u00e9 apego por la tierra\u00bb. Uni\u00f3 a la Pasi\u00f3n redentora de Cristo los intensos sufrimientos causados por su enfermedad en la \u00faltima etapa de su vida. Muri\u00f3 el 17 de junio de 1903 mientras el padre Mallet oficiaba la misa pidiendo por \u00e9l. Juan Pablo II lo beatific\u00f3 el 3 de octubre de 2004.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-103142 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=1080%2C1080&#038;ssl=1\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=770%2C770&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=500%2C500&amp;ssl=1 500w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=293%2C293&amp;ssl=1 293w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=390%2C390&amp;ssl=1 390w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=585%2C585&amp;ssl=1 585w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/06\/Santoral-9.jpg?resize=900%2C900&amp;ssl=1 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-2208\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/02\/santoral-scaled-1.jpg?resize=262%2C370&#038;ssl=1\" alt=\"santoral Isabel Orellana\" width=\"262\" height=\"370\" \/><\/p>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h6><em>\u00a9 <a href=\"https:\/\/exaudi.org\/es\/author\/isabelorellana\/\" target=\"_blank\" rel=\"noopener noreferrer\">Isabel Orellana Vilches<\/a>, 2024<\/em><br \/>\n<em>Autora vinculada a<\/em><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-41949\" src=\"https:\/\/i0.wp.com\/www.idente.org\/wp-content\/uploads\/logo-cedro-v01-843x295-1-e1603384654546.png?resize=80%2C28&#038;ssl=1\" alt=\"\" width=\"80\" height=\"28\" \/><br \/>\nObra protegida por derechos de autor.<br \/>\nInscrita en el Registro de la Propiedad Intelectual el 24 de noviembre de 2014.<br \/>\n________________<br \/>\nDerechos de edici\u00f3n reservados:<br \/>\nFundaci\u00f3n <a href=\"https:\/\/rielo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fernando Rielo<\/a><br \/>\nGoya 20, 4.\u00ba izq. int. 28001 Madrid<br \/>\nTlf.: (34) 91 575 40 91<br \/>\nCorreo electr\u00f3nico: fundacion@rielo.com<\/h6>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h6>Dep\u00f3sito legal: M-18664-2020<br \/>\nISBN: 978-84-946646-6-3<\/h6>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Devoto del coraz\u00f3n de Jes\u00fas<\/p>\n","protected":false},"author":23,"featured_media":22888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[74,2772],"tags":[2908,388,387,58880],"class_list":["post-22886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iglesia-y-mundo","category-santoral","tag-beato-jose-maria-cassant","tag-isabel-orellana-vilches","tag-santoral","tag-trending-es-151"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio - Exaudi Catholic News<\/title>\n<meta name=\"description\" content=\"Santoral del 17 de junio de 2022 sobre el beato Jos\u00e9 Mar\u00eda Cassant, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio - Exaudi Catholic News\" \/>\n<meta property=\"og:description\" content=\"Santoral del 17 de junio de 2022 sobre el beato Jos\u00e9 Mar\u00eda Cassant, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-17T05:30:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"702\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Isabel Orellana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabel Orellana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/\"},\"author\":{\"name\":\"Isabel Orellana\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/64e18b96fd6118559a9217b5b3375fdc\"},\"headline\":\"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio\",\"datePublished\":\"2026-06-17T05:30:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/\"},\"wordCount\":1154,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1\",\"keywords\":[\"Beato Jos\u00e9 Mar\u00eda Cassant\",\"Isabel Orellana Vilches\",\"Santoral\",\"Trending\"],\"articleSection\":[\"Iglesia y Mundo\",\"Santoral\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/\",\"name\":\"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio - Exaudi Catholic News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1\",\"datePublished\":\"2026-06-17T05:30:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/64e18b96fd6118559a9217b5b3375fdc\"},\"description\":\"Santoral del 17 de junio de 2022 sobre el beato Jos\u00e9 Mar\u00eda Cassant, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1\",\"width\":702,\"height\":576,\"caption\":\"Beato Jos\u00e9 Mar\u00eda Cassant \u00a9 Iglesia del Salvador de Toledo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-jose-maria-cassant-17-junio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/64e18b96fd6118559a9217b5b3375fdc\",\"name\":\"Isabel Orellana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g\",\"caption\":\"Isabel Orellana\"},\"description\":\"Isabel Orellana Vilches Misionera idente. Doctora en Filosof\u00eda por la Universidad Aut\u00f3noma de Barcelona con la tesis Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana. Ha cursado estudios de teolog\u00eda en la Universidad Pontificia de Salamanca. Con amplia actividad docente desde 1986, ha publicado libros como: Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana, Universitat Aut\u00f2noma de Barcelona, 1993; El evangelio habla a los j\u00f3venes, Atenas, Madrid, 1997; Qu\u00e9 es... LA TOLERANCIA, Paulinas, Madrid, 1999; Pedagog\u00eda del dolor. Ensayo antropol\u00f3gico, Palabra, Madrid, 1999; En colaboraci\u00f3n con Enrique Rivera de Ventosa (\u2020) OFM. Cap. San Francisco de As\u00eds y Fernando Rielo: Convergencias. Respuestas desde la fe a los interrogantes del hombre de hoy, Universidad Pontificia, Salamanca, 2001; La \\\"mirada\\\" del cine. Recursos did\u00e1cticos del s\u00e9ptimo arte. Librer\u00eda Cervantes, Salamanca, 2001; Paradojas de la convivencia, San Pablo, Madrid, 2002; En la Universidad T\u00e9cnica Particular de Loja, Ecuador, ha publicado: La confianza. El arte de amar, 2002; Educar para la responsabilidad, 2003; Apuntes de \u00e9tica en Karl R. Popper, 2003; De soledades y comunicaci\u00f3n, 2005; Yo educo; t\u00fa respondes, 2008; Humanismo y fe en un crisol de culturas, 2008; Repensar lo cotidiano, 2008; Convivir: un constante desaf\u00edo, 2009; La l\u00f3gica del amor, 2010; El dolor del amor. Apuntes sobre la enfermedad y el dolor en relaci\u00f3n con la virtud heroica, el martirio y la vida santa. Seminario Diocesano de M\u00e1laga, 2006 y Universidad T\u00e9cnica Particular de Loja, Ecuador (2007). Cuenta con numerosas colaboraciones en obras colectivas, as\u00ed como relatos, cuentos, f\u00e1bula y novela juvenil, adem\u00e1s de art\u00edculos de tem\u00e1tica cient\u00edfica, pedag\u00f3gica y espiritual, que viene publicando en distintas revistas nacionales e internacionales. En 2012 culmin\u00f3 el santoral Llamados a ser santos y poco m\u00e1s tarde Epopeyas de amor prologado por mons. Fernando Sebasti\u00e1n. Es la bi\u00f3grafa oficial del fundador de su familia espiritual, autora de Fernando Rielo Pardal. Fundador de los Misioneros Identes, Descl\u00e9e de Brouwer, Bilbao, 2009. Culmina la biograf\u00eda completa. Encargada del santoral de ZENIT desde 2012 a 2020 y ahora en Exaudi\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/isabelorellana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio - Exaudi Catholic News","description":"Santoral del 17 de junio de 2022 sobre el beato Jos\u00e9 Mar\u00eda Cassant, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/","og_locale":"es_ES","og_type":"article","og_title":"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio - Exaudi Catholic News","og_description":"Santoral del 17 de junio de 2022 sobre el beato Jos\u00e9 Mar\u00eda Cassant, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.","og_url":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2026-06-17T05:30:54+00:00","og_image":[{"width":702,"height":576,"url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1","type":"image\/jpeg"}],"author":"Isabel Orellana","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Isabel Orellana","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/"},"author":{"name":"Isabel Orellana","@id":"https:\/\/exaudi.org\/#\/schema\/person\/64e18b96fd6118559a9217b5b3375fdc"},"headline":"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio","datePublished":"2026-06-17T05:30:54+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/"},"wordCount":1154,"image":{"@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1","keywords":["Beato Jos\u00e9 Mar\u00eda Cassant","Isabel Orellana Vilches","Santoral","Trending"],"articleSection":["Iglesia y Mundo","Santoral"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/","url":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/","name":"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio - Exaudi Catholic News","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1","datePublished":"2026-06-17T05:30:54+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/64e18b96fd6118559a9217b5b3375fdc"},"description":"Santoral del 17 de junio de 2022 sobre el beato Jos\u00e9 Mar\u00eda Cassant, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.","breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1","width":702,"height":576,"caption":"Beato Jos\u00e9 Mar\u00eda Cassant \u00a9 Iglesia del Salvador de Toledo"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/beato-jose-maria-cassant-17-junio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Beato Jos\u00e9 Mar\u00eda Cassant, 17 de junio"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/64e18b96fd6118559a9217b5b3375fdc","name":"Isabel Orellana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g","caption":"Isabel Orellana"},"description":"Isabel Orellana Vilches Misionera idente. Doctora en Filosof\u00eda por la Universidad Aut\u00f3noma de Barcelona con la tesis Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana. Ha cursado estudios de teolog\u00eda en la Universidad Pontificia de Salamanca. Con amplia actividad docente desde 1986, ha publicado libros como: Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana, Universitat Aut\u00f2noma de Barcelona, 1993; El evangelio habla a los j\u00f3venes, Atenas, Madrid, 1997; Qu\u00e9 es... LA TOLERANCIA, Paulinas, Madrid, 1999; Pedagog\u00eda del dolor. Ensayo antropol\u00f3gico, Palabra, Madrid, 1999; En colaboraci\u00f3n con Enrique Rivera de Ventosa (\u2020) OFM. Cap. San Francisco de As\u00eds y Fernando Rielo: Convergencias. Respuestas desde la fe a los interrogantes del hombre de hoy, Universidad Pontificia, Salamanca, 2001; La \"mirada\" del cine. Recursos did\u00e1cticos del s\u00e9ptimo arte. Librer\u00eda Cervantes, Salamanca, 2001; Paradojas de la convivencia, San Pablo, Madrid, 2002; En la Universidad T\u00e9cnica Particular de Loja, Ecuador, ha publicado: La confianza. El arte de amar, 2002; Educar para la responsabilidad, 2003; Apuntes de \u00e9tica en Karl R. Popper, 2003; De soledades y comunicaci\u00f3n, 2005; Yo educo; t\u00fa respondes, 2008; Humanismo y fe en un crisol de culturas, 2008; Repensar lo cotidiano, 2008; Convivir: un constante desaf\u00edo, 2009; La l\u00f3gica del amor, 2010; El dolor del amor. Apuntes sobre la enfermedad y el dolor en relaci\u00f3n con la virtud heroica, el martirio y la vida santa. Seminario Diocesano de M\u00e1laga, 2006 y Universidad T\u00e9cnica Particular de Loja, Ecuador (2007). Cuenta con numerosas colaboraciones en obras colectivas, as\u00ed como relatos, cuentos, f\u00e1bula y novela juvenil, adem\u00e1s de art\u00edculos de tem\u00e1tica cient\u00edfica, pedag\u00f3gica y espiritual, que viene publicando en distintas revistas nacionales e internacionales. En 2012 culmin\u00f3 el santoral Llamados a ser santos y poco m\u00e1s tarde Epopeyas de amor prologado por mons. Fernando Sebasti\u00e1n. Es la bi\u00f3grafa oficial del fundador de su familia espiritual, autora de Fernando Rielo Pardal. Fundador de los Misioneros Identes, Descl\u00e9e de Brouwer, Bilbao, 2009. Culmina la biograf\u00eda completa. Encargada del santoral de ZENIT desde 2012 a 2020 y ahora en Exaudi","url":"https:\/\/exaudi.org\/es\/author\/isabelorellana\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/06\/89.0-e1623854149570.jpg?fit=702%2C576&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-5X8","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/22886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=22886"}],"version-history":[{"count":2,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/22886\/revisions"}],"predecessor-version":[{"id":172408,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/22886\/revisions\/172408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/22888"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=22886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=22886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=22886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}