{"id":18544,"date":"2021-05-24T09:38:27","date_gmt":"2021-05-24T07:38:27","guid":{"rendered":"https:\/\/exaudi.org\/?p=18544"},"modified":"2021-05-24T17:32:45","modified_gmt":"2021-05-24T15:32:45","slug":"teologia-para-millennials-descanso-2021","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/","title":{"rendered":"Teolog\u00eda para Millennials: Descanso"},"content":{"rendered":"<p>Hoy lunes 24 de mayo de 2021, en \u201c<a href=\"https:\/\/teologiaparamillennials.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Teolog\u00eda para Millennials<\/a>\u201d, el sacerdote mexicano\u00a0<a href=\"https:\/\/exaudi.org\/es\/author\/padremarioarroyo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mario Arroyo Mart\u00ednez<\/a>, comparte con los lectores de Exaudi su art\u00edculo \u201cDescanso\u201d, sobre el peligro de vivir una vida de efectividad, producci\u00f3n y sin reposo integral.<\/p>\n<p>***<\/p>\n<p><span style=\"font-weight: 400\">La actividad febril de nuestra vida puede dificultarnos descansar. El prurito de hacer, producir, el culto a la eficacia, la necesidad de generar resultados\u2026 A ello se a\u00f1ade el hecho de que no es f\u00e1cil descansar o, por lo menos, no podemos dar por descontado que sabemos hacerlo. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Mucha gente no sabe descansar, o plantea sus planes de descanso en forma tal, que finalmente resultan agotadores por intensos, d\u00e1ndose la paradoja de que frecuentemente nos encontramos en la tesitura de necesitar descansar de nuestro \u201cdescanso.\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400\">Desde una perspectiva judeocristiana, el descanso es querido por Dios. Es un mandamiento \u2013santificar las fiestas-; le agrada a Dios que descansemos. De hecho, con frecuencia, en el evangelio se repite la escena de que Jes\u00fas lleva a sus disc\u00edpulos a un lugar apartado para descansar despu\u00e9s de su extenuante actividad apost\u00f3lica. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Jes\u00fas mismo se retira en ocasiones a un lugar apartado para estar a solas con su Padre Dios. Seg\u00fan el evangelio, no siempre fue posible ese descanso, pues a veces las multitudes los segu\u00edan y \u00c9l se conmov\u00eda porque las ve\u00eda \u201ccomo ovejas que no tienen pastor\u201d, y comenzaba a ense\u00f1arles muchas cosas. Pero lo intentaba.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La perfecci\u00f3n de lo humano es lo cristiano, debido a que Jes\u00fas es perfecto hombre y perfecto Dios, modelo acabado de toda perfecci\u00f3n humana. A \u00c9l debemos mirar si queremos alcanzar la aut\u00e9ntica plenitud humana y no conformarnos con suced\u00e1neos superficiales de moda. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Y Jes\u00fas descans\u00f3, y puso los medios para que sus disc\u00edpulos lo hicieran; podemos, en consecuencia, poner los medios e intentar imitarlo: aprender a descansar. La plenitud humana requiere del descanso. Tambi\u00e9n as\u00ed cultivamos una virtud fundamental: la humildad; el reconocimiento llano y sincero de que no somos superhombres, ni somos m\u00e1quinas; somos humanos fr\u00e1giles que necesitan rehacerse peri\u00f3dicamente.<\/span><\/p>\n<p><span style=\"font-weight: 400\">El descanso del esp\u00edritu est\u00e1 muy unido a la contemplaci\u00f3n. La capacidad de maravillarse con la vida, la naturaleza, los detalles. Hay una contemplaci\u00f3n humana que es preludio de la sobrenatural; el Papa lo acaba de se\u00f1alar en sus catequesis de los mi\u00e9rcoles. Es necesario cultivar la primera, patrimonio com\u00fan de todos los hombres, independientemente de su religi\u00f3n o ausencia de ella, para poder dar paso a la segunda, la cual requiere siempre el don de la fe.<\/span><\/p>\n<p><span style=\"font-weight: 400\"> Muchas veces esa contemplaci\u00f3n natural se vuelve pre\u00e1mbulo de la fe para hombres con una sincera apertura espiritual; con actitud abierta hacia la verdad, se encuentre donde se encuentre. Pero esa primera contemplaci\u00f3n tiene como requisito el recogimiento de los sentidos, externos e internos \u2013imaginaci\u00f3n, memoria-, la paz del alma. Solo as\u00ed se tiene la mirada serena, la actitud conveniente, para poder maravillarse con la vida y el mundo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La oraci\u00f3n mental habitual es un buen medio para conseguir la paz del alma, la serenidad de esp\u00edritu, condiciones para acceder a una contemplaci\u00f3n, que a trav\u00e9s de escalones nos lleve del mundo hacia Dios. En Dios encontramos el descanso de nuestro esp\u00edritu, la serenidad de nuestras angustias, lo que se llama \u201cel santo abandono\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\"> El ponerlo todo en manos de Dios, dejar nuestras angustias e inquietudes en Sus Manos, sabiendo que son las mejores Manos. \u201cSe\u00f1or, Dios m\u00edo, en tus manos abandono lo pasado, lo presente, lo futuro, lo peque\u00f1o y lo grande, lo poco y lo mucho, lo temporal y lo eterno\u201d (San Josemar\u00eda). El descanso profundo tiene algo de don del Esp\u00edritu, pues es la paz del alma, el sosiego interior que Dios quiere concedernos para que nos rehagamos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Hay distintos tipos de contemplaci\u00f3n. Una, la habitual, compatible con el fragor de la calle, con la intensidad de actividades. Hacerlo todo metidos en Dios, con Dios en el alma mientras externamente lo damos todo. Pero para que esa contemplaci\u00f3n sea posible, se requieren espacios de silencio, de soledad acompa\u00f1ada, de un saber distanciarse prudentemente de las actividades habituales para repesar las cosas; verlas desde una cierta distancia, con perspectiva. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Para recuperar la capacidad de maravillarnos con lo peque\u00f1o: con una flor, un atardecer, un paisaje, una sonrisa o nuestra propia vida. Esto \u00faltimo requiere descanso, no solo del cuerpo, sino tambi\u00e9n del alma. No implica \u201chacer cosas\u201d, sino saber estar, darse cuenta y contemplar. D\u00e9monos la oportunidad de descansar; luchemos para que todos puedan darse este espacio vital.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peligro de no reposar<\/p>\n","protected":false},"author":22,"featured_media":18546,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[],"tags":[2470],"class_list":["post-18544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-descanso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teolog\u00eda para Millennials: Descanso &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"Hoy, 24 de mayo de 2021, en Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cDescanso\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teolog\u00eda para Millennials: Descanso &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Hoy, 24 de mayo de 2021, en Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cDescanso\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-24T07:38:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-24T15:32:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/05\/34c-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mario Arroyo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Arroyo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/\"},\"author\":{\"name\":\"Mario Arroyo\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/2195e6e643f4a07a343345d49e4e6985\"},\"headline\":\"Teolog\u00eda para Millennials: Descanso\",\"datePublished\":\"2021-05-24T07:38:27+00:00\",\"dateModified\":\"2021-05-24T15:32:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/\"},\"wordCount\":801,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/34c-scaled.jpg?fit=2560%2C1854&ssl=1\",\"keywords\":[\"Descanso\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/\",\"name\":\"Teolog\u00eda para Millennials: Descanso &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/34c-scaled.jpg?fit=2560%2C1854&ssl=1\",\"datePublished\":\"2021-05-24T07:38:27+00:00\",\"dateModified\":\"2021-05-24T15:32:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/2195e6e643f4a07a343345d49e4e6985\"},\"description\":\"Hoy, 24 de mayo de 2021, en Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cDescanso\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/34c-scaled.jpg?fit=2560%2C1854&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/34c-scaled.jpg?fit=2560%2C1854&ssl=1\",\"width\":2560,\"height\":1854,\"caption\":\"Crucifijo clavado en un tronco en el bosque \u00a9 Cathopic\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/teologia-para-millennials-descanso-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teolog\u00eda para Millennials: Descanso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/2195e6e643f4a07a343345d49e4e6985\",\"name\":\"Mario Arroyo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g\",\"caption\":\"Mario Arroyo\"},\"description\":\"Licenciado en Filosof\u00eda por la Universidad Panamericana, M\u00e9xico 1996, ostenta el bachiller en Teolog\u00eda por la Pontificia Universidad de la Santa Cruz, Roma 1999. Doctor en Filosof\u00eda por la Pontificia Universidad de la Santa Cruz, Roma 2002. Ordenado sacerdote en Torreciudad, Espa\u00f1a, en 2002. Autor de: Poder, Dinero y Santidad, Lima 2012; Ciencia y Fe. Un equilibrio posible, UCSS, Lima 2015; Ciencia y Fe. Situaci\u00f3n actual, Facultad de Teolog\u00eda Pontificia y Civil de Lima, Lima 2016; La Iglesia y los Homosexuales. Un falso conflicto, Facultad de Teolog\u00eda Pontificia y Civil de Lima, Lima 2017. Coautor de Dios Busca al Hombre, CDSCO, Lima 2013; Neurona mata esp\u00edritu, Amazon, Lima 2018; Teolog\u00eda para Millennials, Amazon, Lima 2018. El padre Mario es columnista de los portales peruanos Cr\u00f3nica Viva, La abeja y Lucidez, as\u00ed como de los peri\u00f3dicos mexicanos Mural, Expreso, del portal mexicano Vox Fides y de ZENIT. Capell\u00e1n de la Universidad de Piura, Campus de Lima durante los cursos 2017 y 2018. Actualmente, profesor de Teolog\u00eda en la Universidad Panamericana, Ciudad de M\u00e9xico.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/padremarioarroyo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teolog\u00eda para Millennials: Descanso &#8211; Exaudi","description":"Hoy, 24 de mayo de 2021, en Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cDescanso\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/","og_locale":"es_ES","og_type":"article","og_title":"Teolog\u00eda para Millennials: Descanso &#8211; Exaudi","og_description":"Hoy, 24 de mayo de 2021, en Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cDescanso\u201d.","og_url":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2021-05-24T07:38:27+00:00","article_modified_time":"2021-05-24T15:32:45+00:00","og_image":[{"width":2560,"height":1854,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/05\/34c-scaled.jpg","type":"image\/jpeg"}],"author":"Mario Arroyo","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Mario Arroyo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/"},"author":{"name":"Mario Arroyo","@id":"https:\/\/exaudi.org\/#\/schema\/person\/2195e6e643f4a07a343345d49e4e6985"},"headline":"Teolog\u00eda para Millennials: Descanso","datePublished":"2021-05-24T07:38:27+00:00","dateModified":"2021-05-24T15:32:45+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/"},"wordCount":801,"image":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/34c-scaled.jpg?fit=2560%2C1854&ssl=1","keywords":["Descanso"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/","url":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/","name":"Teolog\u00eda para Millennials: Descanso &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/34c-scaled.jpg?fit=2560%2C1854&ssl=1","datePublished":"2021-05-24T07:38:27+00:00","dateModified":"2021-05-24T15:32:45+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/2195e6e643f4a07a343345d49e4e6985"},"description":"Hoy, 24 de mayo de 2021, en Teolog\u00eda para Millennials, el padre Mario Arroyo comparte con los lectores de Exaudi su art\u00edculo \u201cDescanso\u201d.","breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/34c-scaled.jpg?fit=2560%2C1854&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/34c-scaled.jpg?fit=2560%2C1854&ssl=1","width":2560,"height":1854,"caption":"Crucifijo clavado en un tronco en el bosque \u00a9 Cathopic"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/teologia-para-millennials-descanso-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Teolog\u00eda para Millennials: Descanso"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/2195e6e643f4a07a343345d49e4e6985","name":"Mario Arroyo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e2dddc1d3bf207409f5b4d542cef9a9955ad497448376a1621fcb1df592d137?s=96&d=mm&r=g","caption":"Mario Arroyo"},"description":"Licenciado en Filosof\u00eda por la Universidad Panamericana, M\u00e9xico 1996, ostenta el bachiller en Teolog\u00eda por la Pontificia Universidad de la Santa Cruz, Roma 1999. Doctor en Filosof\u00eda por la Pontificia Universidad de la Santa Cruz, Roma 2002. Ordenado sacerdote en Torreciudad, Espa\u00f1a, en 2002. Autor de: Poder, Dinero y Santidad, Lima 2012; Ciencia y Fe. Un equilibrio posible, UCSS, Lima 2015; Ciencia y Fe. Situaci\u00f3n actual, Facultad de Teolog\u00eda Pontificia y Civil de Lima, Lima 2016; La Iglesia y los Homosexuales. Un falso conflicto, Facultad de Teolog\u00eda Pontificia y Civil de Lima, Lima 2017. Coautor de Dios Busca al Hombre, CDSCO, Lima 2013; Neurona mata esp\u00edritu, Amazon, Lima 2018; Teolog\u00eda para Millennials, Amazon, Lima 2018. El padre Mario es columnista de los portales peruanos Cr\u00f3nica Viva, La abeja y Lucidez, as\u00ed como de los peri\u00f3dicos mexicanos Mural, Expreso, del portal mexicano Vox Fides y de ZENIT. Capell\u00e1n de la Universidad de Piura, Campus de Lima durante los cursos 2017 y 2018. Actualmente, profesor de Teolog\u00eda en la Universidad Panamericana, Ciudad de M\u00e9xico.","url":"https:\/\/exaudi.org\/es\/author\/padremarioarroyo\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/34c-scaled.jpg?fit=2560%2C1854&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-4P6","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/18544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=18544"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/18544\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/18546"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=18544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=18544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=18544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}