{"id":177366,"date":"2026-06-30T11:00:03","date_gmt":"2026-06-30T09:00:03","guid":{"rendered":"https:\/\/exaudi.org\/?p=177366"},"modified":"2026-06-30T10:14:34","modified_gmt":"2026-06-30T08:14:34","slug":"la-humanizacion-de-la-atencion-medica-para-los-pobres","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/","title":{"rendered":"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres"},"content":{"rendered":"<p>Medicaid ha estado en el centro de la atenci\u00f3n durante el \u00faltimo a\u00f1o, sometido a acusaciones de mala gesti\u00f3n y despilfarro. Sin embargo, una iniciativa \u00fanica en curso en el Estado de Nueva York promete una reforma radical que reducir\u00e1 dr\u00e1sticamente el gasto en Medicaid, haciendo innecesarios los recortes presupuestarios, incluso mientras mejora notablemente la calidad de la atenci\u00f3n para los pobres.<\/p>\n<p><iframe title=\"Spotify Embed: La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/5ffR9Ja5pGSi19xCq4gx7J?si=7ab1be863c9944b1&amp;utm_source=oembed\"><\/iframe><\/p>\n<p>La iniciativa est\u00e1 impulsada por la convicci\u00f3n de que los tratamientos m\u00e9dicos tradicionales tambi\u00e9n deben abordar las necesidades <em>sociales <\/em>de los pacientes que pueden causar o exacerbar afecciones m\u00e9dicas y conductuales. Estas necesidades se conocen como \u2018Necesidades Sociales Relacionadas con la Salud\u2019 (<em>Health-Related Social Needs<\/em>).<\/p>\n<p>El objetivo general es integrar a las Organizaciones Comunitarias (CBO, por sus siglas en ingl\u00e9s) y su experiencia social en el sistema actual de atenci\u00f3n primaria y de salud conductual. Las investigaciones han demostrado que la salud f\u00edsica solo representa alrededor del 20 por ciento de la salud y el bienestar general. Las organizaciones comunitarias y su experiencia son necesarias para complementar las formas tradicionales de atenci\u00f3n m\u00e9dica.<\/p>\n<p>En el coraz\u00f3n de la atenci\u00f3n social est\u00e1 el reconocimiento de que los pobres, al igual que quienes est\u00e1n en mejor situaci\u00f3n, son personas complejas con muchas necesidades, sociales y de otro tipo. El respeto por su dignidad exige una disciplina rigurosa en su atenci\u00f3n para que ya no sean personas sin rostro que se mueven mec\u00e1nicamente a trav\u00e9s del sistema. La Atenci\u00f3n Social asegura que los pacientes sean mejor conocidos por personas clave de la comunidad: m\u00e9dicos, trabajadores comunitarios de la salud, pacientes y voluntarios.<\/p>\n<p>As\u00ed, la humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica va de la mano de la atenci\u00f3n preventiva, con pacientes que asumen la responsabilidad tanto de su atenci\u00f3n social como de la tradicional. Sentirse conocido y cuidado hace maravillas para la moral. Los pacientes de Medicaid en el Estado de Nueva York ya no ser\u00e1n consumidores pasivos, casi an\u00f3nimos, de atenci\u00f3n m\u00e9dica. En cambio, se emancipar\u00e1n y obtendr\u00e1n un asiento en la mesa cuando su m\u00e9dico y la organizaci\u00f3n comunitaria discutan su caso. Las personas sanas se mantienen alejadas de la sala de emergencias y de las costosas camas de hospital: un beneficio para los contribuyentes. La comunicaci\u00f3n y la colaboraci\u00f3n son los llamados a la acci\u00f3n.<\/p>\n<p>Nueve Redes de Atenci\u00f3n Social (SCN, por sus siglas en ingl\u00e9s) regionales han sido financiadas con un presupuesto de $500 millones, provenientes de un total de $66 mil millones destinados a mejorar la atenci\u00f3n general para los beneficiarios de Medicaid m\u00e1s vulnerables en el Estado de Nueva York. Estas redes ayudar\u00e1n a los m\u00e9dicos y otras partes interesadas a identificar y, posteriormente, involucrar a agencias comunitarias que adopten la misi\u00f3n de la Iglesia local: brindar atenci\u00f3n a los miembros m\u00e1s vulnerables de la comunidad. Las organizaciones comunitarias que realizan un trabajo superlativo son reconocidas por la red de atenci\u00f3n social regional mediante personal adicional o mejoras en sus instalaciones.<\/p>\n<p>Las organizaciones comunitarias tienen la experiencia social que los pacientes en el Estado de Nueva York necesitan. Hoy, la mayor parte de las Necesidades Sociales Relacionadas con la Salud que se est\u00e1n abordando tienen que ver con la nutrici\u00f3n, la vivienda y el transporte. A la espera de investigaciones y de la identificaci\u00f3n de los proveedores de atenci\u00f3n social adecuados, surgir\u00e1n m\u00e1s \u00e1reas de enfoque. Tanto la educaci\u00f3n como el empleo prometen convertirse en importantes \u00e1reas de enfoque para la extensi\u00f3n.<\/p>\n<p>Los miembros de Medicaid que necesiten asistencia con sus necesidades sociales relacionadas con la salud no satisfechas ser\u00e1n conectados con los recursos existentes, incluidos los m\u00e9dicos locales que conf\u00edan en el personal de las organizaciones comunitarias para obtener informaci\u00f3n sobre las organizaciones locales. Ahora comienza el proceso cr\u00edtico de mapear cuidadosamente las necesidades m\u00e9dicas y sociales de la poblaci\u00f3n local. Los voluntarios, que a menudo son expacientes, pueden desempe\u00f1ar un papel importante informando sobre las organizaciones comunitarias de las cuales han recibido servicios. Es una colaboraci\u00f3n con el prop\u00f3sito de hacer coincidir las necesidades de los pacientes con los recursos disponibles y una parte clave del gasto inteligente. Ya se est\u00e1n realizando preparativos para una conferencia que reunir\u00e1 a organizaciones comunitarias de todo Nueva York, lo que cambiar\u00e1 la econom\u00eda de la atenci\u00f3n m\u00e9dica del estado y elevar\u00e1 el perfil de la atenci\u00f3n social.<\/p>\n<p>Hay que destacar la labor del Dr. Ram\u00f3n Tallaj, fundador y presidente de SOMOS Community Care, una red de m\u00e1s de 2.500 proveedores de atenci\u00f3n primaria independientes. Al fundarse en 2014, SOMOS se uni\u00f3 a una iniciativa de Medicaid del Estado de Nueva York dise\u00f1ada para mejorar la atenci\u00f3n m\u00e9dica de los beneficiarios de Medicaid m\u00e1s pobres. Esa misi\u00f3n ha permanecido en el centro de SOMOS, con una visi\u00f3n temprana de la atenci\u00f3n social.<\/p>\n<p>Desde el principio, los m\u00e9dicos de SOMOS confiaron en los trabajadores comunitarios de la salud para que visitaran los hogares de los pacientes y proporcionaran informaci\u00f3n sobre sus necesidades sociales. SOMOS se enorgullece de ver sus inicios en el \u00e1mbito de la atenci\u00f3n social reflejados en el gran escenario de la iniciativa de Medicaid del Estado de Nueva York. Asimismo, SOMOS agradece la operaci\u00f3n de la Red de Atenci\u00f3n Social en el territorio del Bronx.<\/p>\n<p>Existe la esperanza de que los funcionarios federales de atenci\u00f3n m\u00e9dica adopten el impulso de Nueva York para la Atenci\u00f3n Social de Medicaid y lo implementen en todo Estados Unidos. Los \u00e9xitos tempranos han demostrado el potencial del programa para reducir costos y mostrar el poder del gobierno para lograr una transformaci\u00f3n radical de la atenci\u00f3n m\u00e9dica para los pobres.<\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-177373 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Voces-12.jpg?resize=1080%2C1080&#038;ssl=1\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Voces-12.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Voces-12.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Voces-12.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Voces-12.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Voces-12.jpg?resize=770%2C770&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Voces-12.jpg?resize=500%2C500&amp;ssl=1 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La revoluci\u00f3n de la atenci\u00f3n social: C\u00f3mo Nueva York est\u00e1 transformando la salud de los m\u00e1s vulnerables<\/p>\n","protected":false},"author":114,"featured_media":177370,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[130],"tags":[117538,15888,25146,62725,7881,100611,62727,78634,62716,117537,117539,17807,7882,58880,58880,58880,58880],"class_list":["post-177366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-atencion-medica-humanizada","tag-atencion-primaria","tag-bienestar-social","tag-equidad-en-salud","tag-mario-j-paredes","tag-necesidades-sociales-relacionadas-con-la-salud","tag-organizaciones-comunitarias","tag-ramon-tallaj","tag-redes-de-atencion-social","tag-reforma-medicaid-nueva-york","tag-salud-preventiva","tag-sistema-de-salud","tag-somos-community-care","tag-trending-es-151"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"La revoluci\u00f3n de la atenci\u00f3n social: C\u00f3mo Nueva York est\u00e1 transformando la salud de los m\u00e1s vulnerables\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SOMOSCommunityCare\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-30T09:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1229\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mario J. Paredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SOMOSCare\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario J. Paredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/\"},\"author\":{\"name\":\"Mario J. Paredes\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f4babf785ff6e9ecd6850d1802095c1d\"},\"headline\":\"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres\",\"datePublished\":\"2026-06-30T09:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/\"},\"wordCount\":1034,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1\",\"keywords\":[\"atenci\u00f3n m\u00e9dica humanizada\",\"atenci\u00f3n primaria\",\"bienestar social\",\"equidad en salud\",\"Mario J Paredes\",\"necesidades sociales relacionadas con la salud\",\"organizaciones comunitarias\",\"ram\u00f3n tallaj\",\"redes de atenci\u00f3n social\",\"reforma Medicaid Nueva York\",\"salud preventiva\",\"Sistema de Salud\",\"SOMOS Community Care\",\"Trending\",\"Trending\",\"Trending\",\"Trending\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/\",\"name\":\"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1\",\"datePublished\":\"2026-06-30T09:00:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f4babf785ff6e9ecd6850d1802095c1d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1\",\"width\":1229,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-humanizacion-de-la-atencion-medica-para-los-pobres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f4babf785ff6e9ecd6850d1802095c1d\",\"name\":\"Mario J. Paredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g\",\"caption\":\"Mario J. Paredes\"},\"description\":\"Presidente ejecutivo de SOMOS Community Care, una red de 2,600 m\u00e9dicos independientes -en su mayor\u00eda de atenci\u00f3n primaria- que atienden a cerca de un mill\u00f3n de los pacientes m\u00e1s vulnerables del Medicaid de la Ciudad de Nueva York\",\"sameAs\":[\"http:\\\/\\\/somosnyhealth.org\",\"https:\\\/\\\/www.facebook.com\\\/SOMOSCommunityCare\\\/\",\"https:\\\/\\\/www.instagram.com\\\/somoscare\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/somoscommunitycare\\\/\",\"https:\\\/\\\/x.com\\\/SOMOSCare\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUrnRjEHj5UrNvxU0jHSzQQ\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/mario-j-paredes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/","og_locale":"es_ES","og_type":"article","og_title":"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres &#8211; Exaudi","og_description":"La revoluci\u00f3n de la atenci\u00f3n social: C\u00f3mo Nueva York est\u00e1 transformando la salud de los m\u00e1s vulnerables","og_url":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/SOMOSCommunityCare\/","article_published_time":"2026-06-30T09:00:03+00:00","og_image":[{"width":1229,"height":768,"url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1","type":"image\/jpeg"}],"author":"Mario J. Paredes","twitter_card":"summary_large_image","twitter_creator":"@SOMOSCare","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Mario J. Paredes","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/"},"author":{"name":"Mario J. Paredes","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f4babf785ff6e9ecd6850d1802095c1d"},"headline":"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres","datePublished":"2026-06-30T09:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/"},"wordCount":1034,"image":{"@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1","keywords":["atenci\u00f3n m\u00e9dica humanizada","atenci\u00f3n primaria","bienestar social","equidad en salud","Mario J Paredes","necesidades sociales relacionadas con la salud","organizaciones comunitarias","ram\u00f3n tallaj","redes de atenci\u00f3n social","reforma Medicaid Nueva York","salud preventiva","Sistema de Salud","SOMOS Community Care","Trending","Trending","Trending","Trending"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/","url":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/","name":"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1","datePublished":"2026-06-30T09:00:03+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f4babf785ff6e9ecd6850d1802095c1d"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1","width":1229,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/la-humanizacion-de-la-atencion-medica-para-los-pobres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"La humanizaci\u00f3n de la atenci\u00f3n m\u00e9dica para los pobres"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f4babf785ff6e9ecd6850d1802095c1d","name":"Mario J. Paredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g","caption":"Mario J. Paredes"},"description":"Presidente ejecutivo de SOMOS Community Care, una red de 2,600 m\u00e9dicos independientes -en su mayor\u00eda de atenci\u00f3n primaria- que atienden a cerca de un mill\u00f3n de los pacientes m\u00e1s vulnerables del Medicaid de la Ciudad de Nueva York","sameAs":["http:\/\/somosnyhealth.org","https:\/\/www.facebook.com\/SOMOSCommunityCare\/","https:\/\/www.instagram.com\/somoscare\/","https:\/\/www.linkedin.com\/company\/somoscommunitycare\/","https:\/\/x.com\/SOMOSCare","https:\/\/www.youtube.com\/channel\/UCUrnRjEHj5UrNvxU0jHSzQQ"],"url":"https:\/\/exaudi.org\/es\/author\/mario-j-paredes\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-K8K","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/Mario-Paredes-1.jpg?fit=1229%2C768&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/177366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=177366"}],"version-history":[{"count":5,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/177366\/revisions"}],"predecessor-version":[{"id":177377,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/177366\/revisions\/177377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/177370"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=177366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=177366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=177366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}