{"id":175446,"date":"2026-06-16T08:00:48","date_gmt":"2026-06-16T06:00:48","guid":{"rendered":"https:\/\/exaudi.org\/?p=175446"},"modified":"2026-06-16T09:13:23","modified_gmt":"2026-06-16T07:13:23","slug":"el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/","title":{"rendered":"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad"},"content":{"rendered":"<p>Marinera, balada y pop son algunos de los g\u00e9neros musicales m\u00e1s utilizados por los participantes del concurso nacional de composici\u00f3n musical, presentado en Lima, capital del Per\u00fa, en el marco del primer aniversario de su pontificado.<\/p>\n<p>Y es que son diversas las historias de fe, que se entretejen a lo largo del norte peruano, donde el entonces, padre Prevost, desarroll\u00f3 su labor pastoral. Tambi\u00e9n como misionero agustino, conoci\u00f3 de cerca la realidad de las comunidades rurales, en Chulucanas, Piura.<\/p>\n<h3><strong>Un pont\u00edfice con coraz\u00f3n peruano<\/strong><\/h3>\n<p>Tras un a\u00f1o del saludo que envi\u00f3 desde el balc\u00f3n del vaticano al mundo, los pobladores de Chongoyape, Pimentel, y Morrop\u00f3n, celebran agradecidos, la elecci\u00f3n de un ap\u00f3stol misionero de coraz\u00f3n agustino.<\/p>\n<p>En la d\u00e9cada de los ochenta \u201cEl papa del Norte\u201d, se dedic\u00f3 a la formaci\u00f3n de nuevos sacerdotes, en la provincia de Trujillo, capital del departamento de la Libertad. Convivi\u00f3 con los m\u00e1s vulnerables, tanto como administrador apost\u00f3lico, en 2014, y luego al ser consagrado obispo de la di\u00f3cesis de Chiclayo en 2015.<\/p>\n<p>\u00a1Un Le\u00f3n, se ha forjado en el norte del Per\u00fa! resuena la letra de un tondero con guitarra y con caj\u00f3n, en homenaje al peregrino, que cruz\u00f3 de Chiclayo al Vaticano. Entre otros temas musicales que surgieron en homenaje al nuevo sucesor de Pedro, destacan tambi\u00e9n; <strong>\u201cLa Cumbia del papa\u201d,<\/strong> interpretada por <strong>Donnie Yaip\u00e9n<\/strong>, o la <strong>\u201cMarinera del papa\u201d<\/strong> de Charlie Andre, y el tondero <strong>\u201cDe Chiclayo al Vaticano\u201d<\/strong> de Coco Llaque.<\/p>\n<figure id=\"attachment_175451\" aria-describedby=\"caption-attachment-175451\" style=\"width: 1600px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-175451 size-full\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.57.jpeg?resize=1600%2C900&#038;ssl=1\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.57.jpeg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.57.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.57.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.57.jpeg?resize=770%2C433&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.57.jpeg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.57.jpeg?resize=500%2C281&amp;ssl=1 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-175451\" class=\"wp-caption-text\">De derecha a izquierda Jorge Ch\u00e1vez, director de radio Nacional del Per\u00fa, Esther D\u00e1vila, Gustavo Ratto y Rully Rendo miembros del jurado del concurso \u00abLe\u00f3n de la Esperanza\u00bb<\/figcaption><\/figure>\n<h3><strong>\u201cLe\u00f3n de la Esperanza\u201d<\/strong><\/h3>\n<p>Como un signo del profundo afecto, y del cari\u00f1o que el pueblo peruano le tiene al santo Padre, se organiz\u00f3 la convocatoria al certamen musical denominado <em>\u201cLe\u00f3n de la Esperanza\u201d<\/em> que busca una voz o voces para cantarle al papa Le\u00f3n XIV, as\u00ed lo explic\u00f3 el consejero de la nunciatura apost\u00f3lica monse\u00f1or <strong>Giuseppe<\/strong>\u00a0<strong>Quirighetti<\/strong>, durante el lanzamiento de este concurso, el pasado 11 de mayo.<\/p>\n<p>En representaci\u00f3n del presidente de la Conferencia Episcopal Peruana, monse\u00f1or Carlos Garc\u00eda Camader, el secretario interino, monse\u00f1or Guillermo Inca Pereda, sostuvo que esta iniciativa liderada por el <strong>Instituto Nacional de Radio y Televisi\u00f3n del Per\u00fa que <\/strong>se lleva adelante en coordinaci\u00f3n con el <strong>Arzobispado de Lima y la Conferencia Episcopal Peruana <\/strong>es, adem\u00e1s, de una expresi\u00f3n art\u00edstica, una oportunidad para que el Per\u00fa manifieste a trav\u00e9s de la m\u00fasica, la fe y el anhelo de Paz, y reconciliaci\u00f3n de los peruanos.<\/p>\n<p>En una entrevista exclusiva para Exaudi el directo de radio nacional del Per\u00fa, Jorge Ch\u00e1vez, dio a conocer que la fecha de cierre para la inscripci\u00f3n a esta actividad se ampli\u00f3 hasta el 21 de junio. Por otro lado, indic\u00f3 que el tema musical que se escoja ser\u00e1 identificado como el himno oficial de la visita del papa Le\u00f3n XIV al Per\u00fa programada para el mes de noviembre.<\/p>\n<p>Para acceder a las bases del concurso puedes ingresar a este link:<\/p>\n<p><a href=\"https:\/\/digital.tvperu.gob.pe\/leon-de-la-esperanza\">https:\/\/digital.tvperu.gob.pe\/leon-de-la-esperanza<\/a><\/p>\n<p>Y en redes:<\/p>\n<p>@Periodismo consentido<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/reel\/1646638266592154\">https:\/\/www.facebook.com\/reel\/1646638266592154<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los peruanos se alistan para cantarle al papa \u201cLe\u00f3n XIV\u201d. Por calles y plazas del pa\u00eds andino, m\u00fasicos ensayan diversos ritmos, con letras inspiradas en la misi\u00f3n pastoral de Robert Francis Prevost Mart\u00ednez, realizada en tierras peruanas, por m\u00e1s de 40 a\u00f1os<\/p>\n","protected":false},"author":39,"featured_media":175447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[74],"tags":[116185,116200,116197,59406,116190,116189,116198,19256,3588,116188,116196,75006,3164,116199,116201,116195,449,116194,116202,116182,116184,116192,116183,58111,625,945,116191,18332,116186,116203,116181,116187,58880,116193,2783,272,20486],"class_list":["post-175446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iglesia-y-mundo","tag-balada","tag-carlos-garcia-camader","tag-charlie-andre","tag-chiclayo-3","tag-chongoyape","tag-chulucanas","tag-coco-llaque","tag-concurso-musical","tag-conferencia-episcopal-peruana","tag-cumbia","tag-donnie-yaipen","tag-esther-nunez","tag-fe-es","tag-giuseppe-quirighetti","tag-guillermo-inca-pereda","tag-himno-oficial","tag-iglesia-catolica","tag-instituto-nacional-de-radio-y-television-del-peru","tag-jorge-chavez","tag-leon-de-la-esperanza","tag-marinera","tag-morropon","tag-musica-peruana","tag-papa-leon-xiv","tag-paz","tag-peru","tag-pimentel","tag-piura","tag-pop","tag-radio-nacional-del-peru","tag-robert-francis-prevost-martinez","tag-tondero","tag-trending-es-151","tag-trujillo-3","tag-unidad","tag-vaticano-es","tag-visita-papal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Per\u00fa le canta a la Esperanza, la Paz y a la unidad &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Los peruanos se alistan para cantarle al papa \u201cLe\u00f3n XIV\u201d. Por calles y plazas del pa\u00eds andino, m\u00fasicos ensayan diversos ritmos, con letras inspiradas en la misi\u00f3n pastoral de Robert Francis Prevost Mart\u00ednez, realizada en tierras peruanas, por m\u00e1s de 40 a\u00f1os\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-16T06:00:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T07:13:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Esther N\u00fa\u00f1ez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Esther N\u00fa\u00f1ez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/\"},\"author\":{\"name\":\"Esther N\u00fa\u00f1ez\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/7105d7735b2bf8c31e7cf8784351ebbc\"},\"headline\":\"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad\",\"datePublished\":\"2026-06-16T06:00:48+00:00\",\"dateModified\":\"2026-06-16T07:13:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/\"},\"wordCount\":576,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg?fit=1200%2C1066&ssl=1\",\"keywords\":[\"balada\",\"Carlos Garc\u00eda Camader\",\"Charlie Andre\",\"Chiclayo\",\"Chongoyape\",\"Chulucanas\",\"Coco Llaque\",\"Concurso Musical\",\"Conferencia Episcopal Peruana\",\"cumbia\",\"Donnie Yaip\u00e9n\",\"Esther N\u00fa\u00f1ez\",\"fe\",\"Giuseppe Quirighetti\",\"Guillermo Inca Pereda\",\"himno oficial\",\"Iglesia cat\u00f3lica\",\"Instituto Nacional de Radio y Televisi\u00f3n del Per\u00fa\",\"Jorge Ch\u00e1vez\",\"Le\u00f3n de la Esperanza\",\"marinera\",\"Morrop\u00f3n\",\"m\u00fasica peruana\",\"papa le\u00f3n xiv\",\"Paz\",\"Per\u00fa\",\"Pimentel\",\"Piura\",\"pop\",\"Radio Nacional del Per\u00fa\",\"Robert Francis Prevost Mart\u00ednez\",\"tondero\",\"Trending\",\"Trujillo\",\"Unidad\",\"Vaticano\",\"visita papal\"],\"articleSection\":[\"Iglesia y Mundo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/\",\"name\":\"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg?fit=1200%2C1066&ssl=1\",\"datePublished\":\"2026-06-16T06:00:48+00:00\",\"dateModified\":\"2026-06-16T07:13:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/7105d7735b2bf8c31e7cf8784351ebbc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg?fit=1200%2C1066&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg?fit=1200%2C1066&ssl=1\",\"width\":1200,\"height\":1066,\"caption\":\"De derecha a izquierda monse\u00f1or Giuseppe Quirighetti, consejero de la Nunciatura Apost\u00f3lica en el Per\u00fa, Ana Cano Bobadilla, gerente del IRTP, monse\u00f1or Guillermo El\u00edas, obispo auxiliar de Lima, el secretario interino de la Conferencia Episcopal Peruana monse\u00f1or Guillermo Inca Pereda. Gustavo Ratto y Rully Rendo miembros del jurado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/7105d7735b2bf8c31e7cf8784351ebbc\",\"name\":\"Esther N\u00fa\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/856566533d218d9d7b852b03a545bc963463ade36cec448d0cba38a2d59be800?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/856566533d218d9d7b852b03a545bc963463ade36cec448d0cba38a2d59be800?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/856566533d218d9d7b852b03a545bc963463ade36cec448d0cba38a2d59be800?s=96&d=mm&r=g\",\"caption\":\"Esther N\u00fa\u00f1ez\"},\"description\":\"Lima, Per\u00fa Periodista colegiada con ejercicio de la profesi\u00f3n desde 2001. Licenciada en periodismo por la Universidad Jaime Bausate y Meza, de Lima. Estudios complementarios en Teolog\u00eda, Filosof\u00eda, Comunicaci\u00f3n Digital; as\u00ed como en Conducci\u00f3n de noticieros y producci\u00f3n audiovisual. Con preparaci\u00f3n adicional en doctrina social de la Iglesia, comunicaci\u00f3n institucional en el sector p\u00fablico y eclesial. Ha ejercido tareas como imagen institucional en la Oficina de Educaci\u00f3n de la Conferencia Episcopal Peruana. Asimismo, Jefa de prensa de un canal y editora de dos revistas impresas. Experiencia en la realizaci\u00f3n de talleres de redacci\u00f3n, as\u00ed como en corresponsal\u00edas de agencias y portales web, direcci\u00f3n, producci\u00f3n y conducci\u00f3n de programas de radio y televisi\u00f3n. Desde 2020 colabora como periodista en el Instituto de Radio y Televisi\u00f3n del Per\u00fa.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/esthernunez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/","og_locale":"es_ES","og_type":"article","og_title":"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad &#8211; Exaudi","og_description":"Los peruanos se alistan para cantarle al papa \u201cLe\u00f3n XIV\u201d. Por calles y plazas del pa\u00eds andino, m\u00fasicos ensayan diversos ritmos, con letras inspiradas en la misi\u00f3n pastoral de Robert Francis Prevost Mart\u00ednez, realizada en tierras peruanas, por m\u00e1s de 40 a\u00f1os","og_url":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2026-06-16T06:00:48+00:00","article_modified_time":"2026-06-16T07:13:23+00:00","og_image":[{"width":1200,"height":1066,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg","type":"image\/jpeg"}],"author":"Esther N\u00fa\u00f1ez","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Esther N\u00fa\u00f1ez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/"},"author":{"name":"Esther N\u00fa\u00f1ez","@id":"https:\/\/exaudi.org\/#\/schema\/person\/7105d7735b2bf8c31e7cf8784351ebbc"},"headline":"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad","datePublished":"2026-06-16T06:00:48+00:00","dateModified":"2026-06-16T07:13:23+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/"},"wordCount":576,"image":{"@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg?fit=1200%2C1066&ssl=1","keywords":["balada","Carlos Garc\u00eda Camader","Charlie Andre","Chiclayo","Chongoyape","Chulucanas","Coco Llaque","Concurso Musical","Conferencia Episcopal Peruana","cumbia","Donnie Yaip\u00e9n","Esther N\u00fa\u00f1ez","fe","Giuseppe Quirighetti","Guillermo Inca Pereda","himno oficial","Iglesia cat\u00f3lica","Instituto Nacional de Radio y Televisi\u00f3n del Per\u00fa","Jorge Ch\u00e1vez","Le\u00f3n de la Esperanza","marinera","Morrop\u00f3n","m\u00fasica peruana","papa le\u00f3n xiv","Paz","Per\u00fa","Pimentel","Piura","pop","Radio Nacional del Per\u00fa","Robert Francis Prevost Mart\u00ednez","tondero","Trending","Trujillo","Unidad","Vaticano","visita papal"],"articleSection":["Iglesia y Mundo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/","url":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/","name":"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg?fit=1200%2C1066&ssl=1","datePublished":"2026-06-16T06:00:48+00:00","dateModified":"2026-06-16T07:13:23+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/7105d7735b2bf8c31e7cf8784351ebbc"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg?fit=1200%2C1066&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg?fit=1200%2C1066&ssl=1","width":1200,"height":1066,"caption":"De derecha a izquierda monse\u00f1or Giuseppe Quirighetti, consejero de la Nunciatura Apost\u00f3lica en el Per\u00fa, Ana Cano Bobadilla, gerente del IRTP, monse\u00f1or Guillermo El\u00edas, obispo auxiliar de Lima, el secretario interino de la Conferencia Episcopal Peruana monse\u00f1or Guillermo Inca Pereda. Gustavo Ratto y Rully Rendo miembros del jurado"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/el-peru-le-canta-a-la-esperanza-la-paz-y-a-la-unidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"El Per\u00fa le canta a la Esperanza, la Paz y a la unidad"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/7105d7735b2bf8c31e7cf8784351ebbc","name":"Esther N\u00fa\u00f1ez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/856566533d218d9d7b852b03a545bc963463ade36cec448d0cba38a2d59be800?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/856566533d218d9d7b852b03a545bc963463ade36cec448d0cba38a2d59be800?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/856566533d218d9d7b852b03a545bc963463ade36cec448d0cba38a2d59be800?s=96&d=mm&r=g","caption":"Esther N\u00fa\u00f1ez"},"description":"Lima, Per\u00fa Periodista colegiada con ejercicio de la profesi\u00f3n desde 2001. Licenciada en periodismo por la Universidad Jaime Bausate y Meza, de Lima. Estudios complementarios en Teolog\u00eda, Filosof\u00eda, Comunicaci\u00f3n Digital; as\u00ed como en Conducci\u00f3n de noticieros y producci\u00f3n audiovisual. Con preparaci\u00f3n adicional en doctrina social de la Iglesia, comunicaci\u00f3n institucional en el sector p\u00fablico y eclesial. Ha ejercido tareas como imagen institucional en la Oficina de Educaci\u00f3n de la Conferencia Episcopal Peruana. Asimismo, Jefa de prensa de un canal y editora de dos revistas impresas. Experiencia en la realizaci\u00f3n de talleres de redacci\u00f3n, as\u00ed como en corresponsal\u00edas de agencias y portales web, direcci\u00f3n, producci\u00f3n y conducci\u00f3n de programas de radio y televisi\u00f3n. Desde 2020 colabora como periodista en el Instituto de Radio y Televisi\u00f3n del Per\u00fa.","url":"https:\/\/exaudi.org\/es\/author\/esthernunez\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-JDM","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-15-at-13.34.32.jpeg?fit=1200%2C1066&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/175446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=175446"}],"version-history":[{"count":3,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/175446\/revisions"}],"predecessor-version":[{"id":175602,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/175446\/revisions\/175602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/175447"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=175446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=175446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=175446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}