{"id":172947,"date":"2026-05-29T14:06:52","date_gmt":"2026-05-29T12:06:52","guid":{"rendered":"https:\/\/exaudi.org\/?p=172947"},"modified":"2026-06-03T12:51:27","modified_gmt":"2026-06-03T10:51:27","slug":"arte-fe-y-belleza-en-la-obra-de-gaudi","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/","title":{"rendered":"Arte, fe y belleza en la obra de Gaud\u00ed"},"content":{"rendered":"<p data-path-to-node=\"2\">El jueves 21 de mayo se celebr\u00f3 en la Pontificia Universidad de la Santa Cruz el acto \u00abArte, fe y belleza en la obra de Gaud\u00ed\u00bb, organizado por la Delegaci\u00f3n del Gobierno de Catalu\u00f1a en Italia con motivo del \u00abA\u00f1o Gaud\u00ed\u00bb. Hace cien a\u00f1os, el 10 de junio de 1926, fallec\u00eda el genial arquitecto catal\u00e1n y en los \u00faltimos meses se ha completado la Torre de Jes\u00fas de la Sagrada Fam\u00edlia, que alcanza los 172,5 metros de altura, convirti\u00e9ndola as\u00ed en la bas\u00edlica m\u00e1s alta del mundo. Precisamente el pr\u00f3ximo 10 junio, el Santo Padre Le\u00f3n XIV, durante su viaje a Espa\u00f1a, celebrar\u00e1 all\u00ed la Misa y bendecir\u00e1 la torre. \u00abHemos querido ofrecer una mirada amplia y articulada sobre el arquitecto catal\u00e1n, destacando no solo su genio creativo sino tambi\u00e9n la dimensi\u00f3n humana y espiritual en la base de su obra\u00bb, afirm\u00f3 el delegado del Gobierno catal\u00e1n, Luca Bellizzi.<\/p>\n<p data-path-to-node=\"3\">En su saludo, la profesora Reyes, vicerrectora de la Universidad, subray\u00f3 la doble coincidencia hist\u00f3rica: el centenario de la muerte de Gaud\u00ed y la v\u00edspera de la hist\u00f3rica visita del Papa Le\u00f3n XIV: \u00abEste encuentro es, por tanto, una bienvenida ideal y anticipada al Santo Padre a la ciudad y a la casa del genio catal\u00e1n, que toca las fibras m\u00e1s \u00edntimas del alma\u00bb y, como dijo Benedicto XVI, fue un \u00abarquitecto genial y cristiano coherente\u00bb.<\/p>\n<p data-path-to-node=\"4\">A continuaci\u00f3n se proyect\u00f3 el documental de Jordi Roig\u00e9 \u00abLa biblia en pedra\u00bb (<i data-path-to-node=\"4\" data-index-in-node=\"78\">La biblia de piedra<\/i>), una perspectiva excepcional de la Sagrada Fam\u00edlia gracias a las filmaciones realizadas con drones. \u00abEl verdadero milagro de Gaud\u00ed es que se haya completado la Torre de Jes\u00fas, con todo lo que esto representa\u00bb, dijo el director, subrayando que ahora el nuevo desaf\u00edo, tras haber superado guerras, pandemias, crisis econ\u00f3micas e incluso intentos de demolici\u00f3n, es \u00abevitar transformarse en un simple parque tem\u00e1tico. No debe perder su esencia m\u00e1s profunda: la de ser un templo, una \u00abBiblia de piedra\u00bb, un lugar capaz de acercar a Dios a las personas que la contemplan\u00bb.<\/p>\n<p data-path-to-node=\"5\">Moderados por el periodista de L&#8217;Osservatore Romano Federico Piana, dialogaron despu\u00e9s la profesora Maria Antonietta Crippa y el fil\u00f3sofo Llu\u00eds Clavell.<\/p>\n<p data-path-to-node=\"5\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-172949 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Il-delegato-Bellizzi-scaled.jpg?resize=2560%2C1920&#038;ssl=1\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Il-delegato-Bellizzi-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Il-delegato-Bellizzi-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Il-delegato-Bellizzi-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Il-delegato-Bellizzi-scaled.jpg?resize=770%2C578&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Il-delegato-Bellizzi-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Il-delegato-Bellizzi-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Il-delegato-Bellizzi-scaled.jpg?resize=500%2C375&amp;ssl=1 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p data-path-to-node=\"6\">Crippa abord\u00f3 algunos aspectos de la construcci\u00f3n de la Sagrada Fam\u00edlia, empezando por la idea del arquitecto de querer superar el g\u00f3tico: Gaud\u00ed ya no utiliza arbotantes ni contrafuertes, sino un nuevo sistema constructivo con sistemas innovadores, entre ellos el uso de los arcos catenarios. \u00abEs un gran santo pero tambi\u00e9n un gran constructor. Las dos cosas van juntas y no hay que olvidarlo\u00bb, subray\u00f3. Tambi\u00e9n record\u00f3 la importancia de la luz en el interior, que \u00abrecuerda a un bosque acogedor y luminoso, una construcci\u00f3n que alude a algo natural\u00bb, as\u00ed como la importancia de la liturgia en la obra de Gaud\u00ed. \u00abUna obra maestra que conmueve\u00bb, a\u00f1adi\u00f3. Luego explic\u00f3 el significado de las tres fachadas de la bas\u00edlica, remarcando que la fachada de la Gloria, la \u00faltima que queda por realizar, \u00abdeber\u00e1 representar cu\u00e1l es el fin de nuestra vida, participar en la gloria de Dios\u00bb.<\/p>\n<p data-path-to-node=\"7\">Monse\u00f1or Clavell destac\u00f3 el origen del templo expiatorio promovido por \u00abJosep Bocabella, un humilde librero nacido en Sant Cugat del Vall\u00e8s: P\u00edo IX le aconseja ir a Loreto. Pocos lo saben, pero el proyecto nace all\u00ed\u00bb. Luego subray\u00f3 la relaci\u00f3n de Gaud\u00ed con la Eucarist\u00eda, que \u00abexplica mucho de su camino y se alimenta de la renovaci\u00f3n lit\u00fargica\u00bb. Por \u00faltimo, citando a Benedicto XVI, Clavell explic\u00f3 que Gaud\u00ed \u00abtransmite a trav\u00e9s de la belleza compartida una gran unidad. Es tambi\u00e9n el deseo de unidad y paz del Papa Le\u00f3n que se realiza en la contemplaci\u00f3n y en la oraci\u00f3n que es la Sagrada Fam\u00edlia. Gaud\u00ed san\u00f3 la fractura entre conciencia humana y conciencia cristiana a trav\u00e9s de la belleza compartida\u00bb, concluy\u00f3.<\/p>\n<p data-path-to-node=\"8\">El panel de clausura tuvo como protagonista a la arquitecta Chiara Curti, autora, entre otras, de diversas obras sobre Gaud\u00ed, entre las cuales se encuentran \u00abMi Gaud\u00ed. La biograf\u00eda escrita por sus amigos\u00bb y \u00abGaud\u00ed vivo\u00bb, de pr\u00f3xima publicaci\u00f3n por Ediciones Ares. En su intervenci\u00f3n, esboz\u00f3 cuatro aspectos de Gaud\u00ed: su infancia, c\u00f3mo trabajaba, su visi\u00f3n del arte y qu\u00e9 significado tiene el viaje del Papa Le\u00f3n XIV a Barcelona. Particularmente interesantes resultaron los aspectos relacionados con el joven arquitecto: un conocimiento de su vida desde los inicios, gracias a tantos testimonios, \u00abhace que cualquiera que se acerque a Gaud\u00ed no lo perciba como una figura genial retirada de las relaciones y de la vida, sino como un ser querido, alguien cercano\u00bb. En cuanto al pr\u00f3ximo viaje del Papa, Curti record\u00f3 que no ir\u00e1 a dar \u00absu imprim\u00e1tur a una obra terminada. Todav\u00eda no sabemos cu\u00e1ndo terminar\u00e1, pero tampoco c\u00f3mo. El Papa Le\u00f3n pone el acento en el camino. En el hecho de que nosotros formamos parte de la Historia de la Salvaci\u00f3n y de que la vida de la Iglesia es hoy. Que la Iglesia es peregrina en el mundo, atra\u00edda hacia Dios, al igual que la propia Sagrada Fam\u00edlia\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pontificia Universidad de la Santa Cruz<\/p>\n","protected":false},"author":18,"featured_media":172952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[74],"tags":[114572,12378,114573,53792,8033,4250,4806,10891,114579,114575,3164,10853,114581,516,114577,114580,114576,90049,114578,58111,114571,1533,5310,114574,106254],"class_list":["post-172947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iglesia-y-mundo","tag-ano-gaudi","tag-antoni-gaudi","tag-arquitectura","tag-arquitectura-religiosa","tag-arte-2","tag-barcelona","tag-belleza","tag-cataluna","tag-chiara-curti","tag-delegacion-de-cataluna","tag-fe-es","tag-gaudi-2","tag-historia-de-la-arquitectura","tag-italia","tag-jordi-roige","tag-jornada-de-estudios","tag-la-biblia-en-pedra","tag-lluis-clavell","tag-maria-antonietta-crippa","tag-papa-leon-xiv","tag-pontificia-universita-santa-croce","tag-roma-es","tag-sagrada-familia","tag-torre-de-jesus","tag-viaje-apostolico-espana-2026"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arte, fe y belleza en la obra de Gaud\u00ed &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arte, fe y belleza en la obra de Gaud\u00ed &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Pontificia Universidad de la Santa Cruz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T12:06:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T10:51:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/05\/Curti-e-Bellizzi-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Acali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Acali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/\"},\"author\":{\"name\":\"Andrea Acali\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/127735be832481a6d3c410c5837bb61a\"},\"headline\":\"Arte, fe y belleza en la obra de Gaud\u00ed\",\"datePublished\":\"2026-05-29T12:06:52+00:00\",\"dateModified\":\"2026-06-03T10:51:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/\"},\"wordCount\":903,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Curti-e-Bellizzi-scaled.jpg?fit=2560%2C1920&ssl=1\",\"keywords\":[\"a\u00f1o gaudi\",\"Antoni Gaud\u00ed\",\"arquitectura\",\"arquitectura religiosa\",\"Arte\",\"Barcelona\",\"belleza\",\"Catalu\u00f1a\",\"chiara curti\",\"delegacion de catalu\u00f1a\",\"fe\",\"Gaud\u00ed\",\"historia de la arquitectura\",\"Italia\",\"jordi roige\",\"jornada de estudios\",\"la biblia en pedra\",\"Lluis Clavell\",\"maria antonietta crippa\",\"papa le\u00f3n xiv\",\"pontificia universita santa croce\",\"Roma\",\"Sagrada Familia\",\"torre de jesus\",\"viaje apost\u00f3lico espa\u00f1a 2026\"],\"articleSection\":[\"Iglesia y Mundo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/\",\"name\":\"Arte, fe y belleza en la obra de Gaud\u00ed &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Curti-e-Bellizzi-scaled.jpg?fit=2560%2C1920&ssl=1\",\"datePublished\":\"2026-05-29T12:06:52+00:00\",\"dateModified\":\"2026-06-03T10:51:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/127735be832481a6d3c410c5837bb61a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Curti-e-Bellizzi-scaled.jpg?fit=2560%2C1920&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Curti-e-Bellizzi-scaled.jpg?fit=2560%2C1920&ssl=1\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/arte-fe-y-belleza-en-la-obra-de-gaudi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arte, fe y belleza en la obra de Gaud\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/127735be832481a6d3c410c5837bb61a\",\"name\":\"Andrea Acali\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g\",\"caption\":\"Andrea Acali\"},\"description\":\"Andrea Acali es un periodista y comunicador italiano con una larga trayectoria en el \u00e1mbito de la informaci\u00f3n religiosa, social y deportiva. Durante casi treinta a\u00f1os trabaj\u00f3 en el diario Il Tempo como vaticanista y jefe de secci\u00f3n, especializ\u00e1ndose en la cobertura de la actualidad del Vaticano y de la Iglesia cat\u00f3lica. Desde 2016 colabora como periodista web en RomaSette y tambi\u00e9n escribe para el peri\u00f3dico Avvenire. Desde 2019 ejerce como comunicador en la Delegazione della Generalitat de Catalunya in Italia, con sede en Roma, donde combina su experiencia period\u00edstica con la comunicaci\u00f3n institucional\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/andrea-acali-505567125\\\/?originalSubdomain=it\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/aacaliexaudi-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arte, fe y belleza en la obra de Gaud\u00ed &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/","og_locale":"es_ES","og_type":"article","og_title":"Arte, fe y belleza en la obra de Gaud\u00ed &#8211; Exaudi","og_description":"Pontificia Universidad de la Santa Cruz","og_url":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2026-05-29T12:06:52+00:00","article_modified_time":"2026-06-03T10:51:27+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/05\/Curti-e-Bellizzi-scaled.jpg","type":"image\/jpeg"}],"author":"Andrea Acali","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Andrea Acali","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/"},"author":{"name":"Andrea Acali","@id":"https:\/\/exaudi.org\/#\/schema\/person\/127735be832481a6d3c410c5837bb61a"},"headline":"Arte, fe y belleza en la obra de Gaud\u00ed","datePublished":"2026-05-29T12:06:52+00:00","dateModified":"2026-06-03T10:51:27+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/"},"wordCount":903,"image":{"@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Curti-e-Bellizzi-scaled.jpg?fit=2560%2C1920&ssl=1","keywords":["a\u00f1o gaudi","Antoni Gaud\u00ed","arquitectura","arquitectura religiosa","Arte","Barcelona","belleza","Catalu\u00f1a","chiara curti","delegacion de catalu\u00f1a","fe","Gaud\u00ed","historia de la arquitectura","Italia","jordi roige","jornada de estudios","la biblia en pedra","Lluis Clavell","maria antonietta crippa","papa le\u00f3n xiv","pontificia universita santa croce","Roma","Sagrada Familia","torre de jesus","viaje apost\u00f3lico espa\u00f1a 2026"],"articleSection":["Iglesia y Mundo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/","url":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/","name":"Arte, fe y belleza en la obra de Gaud\u00ed &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Curti-e-Bellizzi-scaled.jpg?fit=2560%2C1920&ssl=1","datePublished":"2026-05-29T12:06:52+00:00","dateModified":"2026-06-03T10:51:27+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/127735be832481a6d3c410c5837bb61a"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Curti-e-Bellizzi-scaled.jpg?fit=2560%2C1920&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Curti-e-Bellizzi-scaled.jpg?fit=2560%2C1920&ssl=1","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/arte-fe-y-belleza-en-la-obra-de-gaudi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Arte, fe y belleza en la obra de Gaud\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/127735be832481a6d3c410c5837bb61a","name":"Andrea Acali","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2abf8e528c4f8c571ab456e5ef9ac66b04b987863e3ab3fd9546150699bb9259?s=96&d=mm&r=g","caption":"Andrea Acali"},"description":"Andrea Acali es un periodista y comunicador italiano con una larga trayectoria en el \u00e1mbito de la informaci\u00f3n religiosa, social y deportiva. Durante casi treinta a\u00f1os trabaj\u00f3 en el diario Il Tempo como vaticanista y jefe de secci\u00f3n, especializ\u00e1ndose en la cobertura de la actualidad del Vaticano y de la Iglesia cat\u00f3lica. Desde 2016 colabora como periodista web en RomaSette y tambi\u00e9n escribe para el peri\u00f3dico Avvenire. Desde 2019 ejerce como comunicador en la Delegazione della Generalitat de Catalunya in Italia, con sede en Roma, donde combina su experiencia period\u00edstica con la comunicaci\u00f3n institucional","sameAs":["https:\/\/www.linkedin.com\/in\/andrea-acali-505567125\/?originalSubdomain=it"],"url":"https:\/\/exaudi.org\/es\/author\/aacaliexaudi-org\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-IZt","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/05\/Curti-e-Bellizzi-scaled.jpg?fit=2560%2C1920&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/172947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=172947"}],"version-history":[{"count":5,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/172947\/revisions"}],"predecessor-version":[{"id":172976,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/172947\/revisions\/172976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/172952"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=172947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=172947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=172947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}