{"id":166184,"date":"2026-04-17T08:00:07","date_gmt":"2026-04-17T06:00:07","guid":{"rendered":"https:\/\/exaudi.org\/?p=166184"},"modified":"2026-04-21T11:58:40","modified_gmt":"2026-04-21T09:58:40","slug":"el-dicasterio-para-el-servicio-del-desarrollo-humano-integral","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/","title":{"rendered":"Dicasterio para el Servicio del Desarrollo Humano Integral"},"content":{"rendered":"<p data-path-to-node=\"5\">El Dicasterio para el Servicio del Desarrollo Humano Integral, como establece la Constituci\u00f3n Apost\u00f3lica <i data-path-to-node=\"5\" data-index-in-node=\"105\">Praedicate Evangelium<\/i>, \u00abtiene la tarea de promover la persona humana y su dignidad, los derechos humanos, la salud, la justicia y la paz. Se interesa principalmente por las cuestiones relativas a la econom\u00eda y al trabajo, al cuidado de la creaci\u00f3n y de la tierra como \u00abcasa com\u00fan\u00bb, a las migraciones y a las emergencias humanitarias. Profundiza y difunde la doctrina social de la Iglesia sobre el desarrollo humano integral y reconoce e interpreta a la luz del Evangelio las necesidades y las preocupaciones del g\u00e9nero humano de su tiempo y del futuro\u00bb. El prefecto es el <b data-path-to-node=\"5\" data-index-in-node=\"677\">cardenal Michael Czerny, S.J.<\/b>, mientras que la secretaria es la <b data-path-to-node=\"5\" data-index-in-node=\"741\">sor Alessandra Smerilli, F.M.A.<\/b><\/p>\n<p><iframe title=\"Spotify Embed: El Dicasterio para el Servicio del Desarrollo Humano Integral\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/73tIlQZDgwpMBnlavVqhhw?si=7bafe48a989346b4&amp;utm_source=oembed\"><\/iframe><\/p>\n<figure id=\"attachment_166190\" aria-describedby=\"caption-attachment-166190\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-166190\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-7.jpeg?resize=750%2C422&#038;ssl=1\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-7.jpeg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-7.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-7.jpeg?resize=500%2C281&amp;ssl=1 500w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-166190\" class=\"wp-caption-text\">Los superiores del Dicasterio. (El primero desde la izquierda es el cardenal Czerny; la segunda desde la derecha, sor Smerilli)<\/figcaption><\/figure>\n<h3 data-path-to-node=\"7\">Apuntes hist\u00f3ricos<\/h3>\n<p data-path-to-node=\"8\">El Dicasterio para el Servicio del Desarrollo Humano Integral fue instituido por el <b data-path-to-node=\"8\" data-index-in-node=\"84\">Papa Francisco el 17 de agosto de 2016<\/b>, con el Motu Proprio <i data-path-to-node=\"8\" data-index-in-node=\"144\">Humanam Progressionem<\/i>. En el Dicasterio confluyeron las competencias de cuatro Pontificios Consejos: el Pontificio Consejo para la Justicia y la Paz, el Pontificio Consejo Cor Unum, el Pontificio Consejo para la Pastoral de los Migrantes e Itinerantes, y el Pontificio Consejo para los Operadores Sanitarios.<\/p>\n<p data-path-to-node=\"9\">Durante los primeros seis a\u00f1os desde el nacimiento del Dicasterio, las cuestiones relativas a migrantes, refugiados y v\u00edctimas de la trata fueron confiadas a una Secci\u00f3n espec\u00edfica, la <b data-path-to-node=\"9\" data-index-in-node=\"185\">Secci\u00f3n de Migrantes y Refugiados<\/b>, situada <i data-path-to-node=\"9\" data-index-in-node=\"228\">ad tempus<\/i> bajo la gu\u00eda directa del Papa Francisco, asistido por dos subsecretarios. Desde el 1 de enero de 2023, la Secci\u00f3n se integr\u00f3 a todos los efectos dentro del Dicasterio, que ha heredado sus tareas y responsabilidades.<\/p>\n<p data-path-to-node=\"10\">A petici\u00f3n de Francisco, en marzo de 2020, con la llegada del Covid-19, el Dicasterio \u2014en colaboraci\u00f3n con otros Dicasterios de la Curia Romana y otras organizaciones\u2014 dio vida a la <b data-path-to-node=\"10\" data-index-in-node=\"182\">Comisi\u00f3n Vaticana Covid-19<\/b>, con la tarea de afrontar los numerosos desaf\u00edos causados por la pandemia y aliviar el sufrimiento de personas y comunidades, orientando \u201ccon la ciencia y la imaginaci\u00f3n\u201d hacia un futuro equitativo y justo, con la conciencia de que \u201ctodo est\u00e1 interconectado\u201d.<\/p>\n<p data-path-to-node=\"11\">Con su trabajo, el Dicasterio promueve el desarrollo integral de la persona a la luz del Evangelio y de la Doctrina Social de la Iglesia. Expresa la solicitud y la atenci\u00f3n del Papa hacia la humanidad sufriente y hacia las Iglesias locales, poni\u00e9ndose al servicio de las Conferencias Episcopales, las Iglesias particulares y todas las diversas realidades que colaboran con ellas.<\/p>\n<h3 data-path-to-node=\"12\">Organizaci\u00f3n<\/h3>\n<p data-path-to-node=\"13\">Diariamente se otorga un gran espacio a la <b data-path-to-node=\"13\" data-index-in-node=\"43\">escucha y al di\u00e1logo directo con las Iglesias Locales<\/b>, prestando atenci\u00f3n a sus preocupaciones y a las peticiones espec\u00edficas que reflejan los desaf\u00edos, en continuo cambio, de las comunidades individuales. Escuchando, dialogando y reflexionando de modo sinodal, se proponen orientaciones pastorales y respuestas adecuadas para apoyar y servir a la Iglesia.<\/p>\n<p data-path-to-node=\"14\">Se ofrecen indicaciones concretas para que las Iglesias locales puedan acompa\u00f1ar de forma evang\u00e9lica a su pueblo al enfrentar preocupaciones y situaciones urgentes, incluso mediante el intercambio de buenas pr\u00e1cticas eficaces, de modo que las comunidades puedan aprender unas de otras. En particular, se da especial atenci\u00f3n a \u00e1mbitos que entran en las competencias del Dicasterio, entre ellos:<\/p>\n<ul>\n<li data-path-to-node=\"15,0,0\">Derechos humanos y salud.<\/li>\n<li data-path-to-node=\"15,1,0\">Justicia, paz y desarme.<\/li>\n<li data-path-to-node=\"15,2,0\">Econom\u00eda y trabajo.<\/li>\n<li data-path-to-node=\"15,3,0\">Medio ambiente.<\/li>\n<li data-path-to-node=\"15,4,0\">Migrantes, refugiados y emergencias humanitarias.<\/li>\n<li data-path-to-node=\"15,5,0\">Formas contempor\u00e1neas de esclavitud y cualquier campo donde se niegue o ponga en riesgo la dignidad humana.<\/li>\n<\/ul>\n<p data-path-to-node=\"16\">El Dicasterio promueve sus actividades a trav\u00e9s de una <b data-path-to-node=\"16\" data-index-in-node=\"55\">red de relaciones<\/b> que involucra a Conferencias Episcopales, Iglesias locales, organismos de la Curia Romana, organizaciones internacionales, ONG, asociaciones y agencias humanitarias (cat\u00f3licas y no cat\u00f3licas).<\/p>\n<p data-path-to-node=\"17\">La Constituci\u00f3n Apost\u00f3lica <i data-path-to-node=\"17\" data-index-in-node=\"27\">Praedicate Evangelium<\/i> destaca la colaboraci\u00f3n del Dicasterio con la Secretar\u00eda de Estado y la estrecha relaci\u00f3n con la <b data-path-to-node=\"17\" data-index-in-node=\"146\">Pontificia Academia de las Ciencias Sociales<\/b>. Adem\u00e1s, se confirma la competencia del Dicasterio respecto a <i data-path-to-node=\"17\" data-index-in-node=\"253\">Caritas Internationalis<\/i> y la Fundaci\u00f3n Juan Pablo II para el Sahel. Tambi\u00e9n pertenece al Dicasterio la nueva <b data-path-to-node=\"17\" data-index-in-node=\"362\">Fundaci\u00f3n Van Thu\u00e2n<\/b>, a la que se ha transferido el patrimonio de las anteriores fundaciones Justicia y Paz y Buen Samaritano. El Dicasterio aborda toda la variedad y riqueza de la vida de los pueblos bajo la perspectiva de un crecimiento y bienestar que sea para todos y para que nadie se quede atr\u00e1s.<\/p>\n<p><iframe loading=\"lazy\" title=\"Presentazione Dicastero per il Servizio dello Sviluppo Umano Integrale\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/gdW3kOfOL2M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p dir=\"auto\">(Traducci\u00f3n realizada manteniendo la fidelidad al texto original publicado en\u00a0<a href=\"https:\/\/www.vaticannews.va\/it\/vaticano\/news\/2025-06\/dicastero-servizio-carita-vaticano.html\" target=\"_blank\" rel=\"noopener\">Vatican News<\/a>\u00a0)<\/p>\n<ol>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/secretaria-de-estado\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Secretar\u00eda de Estado<\/strong><\/em><\/a><\/li>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/dicasterio-para-la-doctrina-de-la-fe\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Dicasterio para la Doctrina de la Fe<\/strong><\/em><\/a><\/li>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/dicasterio-para-los-obispos\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Dicasterio para los Obispos<\/strong><\/em><\/a><\/li>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/dicasterio-para-el-clero\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Dicasterio para el Clero<\/strong><\/em><\/a><\/li>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/dicasterio-para-el-servicio-de-la-caridad\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Dicasterio para el Servicio de la Caridad<\/strong><\/em><\/a><\/li>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/dicasterio-para-la-vida-consagrada-y-las-sociedades-de-vida-apostolica\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Dicasterio para la Vida Consagrada y las Sociedades de Vida Apost\u00f3lica<\/strong><\/em><\/a><\/li>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/el-dicasterio-para-las-causas-de-los-santos\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Dicasterio para las Causas de los Santos<\/strong><\/em><\/a><\/li>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/el-dicasterio-para-la-promocion-de-la-unidad-de-los-cristianos\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Dicasterio para la Promoci\u00f3n de la Unidad de los Cristianos<\/strong><\/em><\/a><\/li>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/dicasterio-para-el-dialogo-interreligioso\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Dicasterio para el Di\u00e1logo Interreligioso<\/strong><\/em><\/a><\/li>\n<li dir=\"auto\"><a href=\"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Dicasterio para el Servicio del Desarrollo Humano Integral<\/strong><\/em><\/a><\/li>\n<\/ol>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-166228 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Voces-1.jpg?resize=940%2C788&#038;ssl=1\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Voces-1.jpg?w=940&amp;ssl=1 940w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Voces-1.jpg?resize=300%2C251&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Voces-1.jpg?resize=770%2C645&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Voces-1.jpg?resize=500%2C419&amp;ssl=1 500w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Dicasterio tiene la tarea de promover el desarrollo humano integral de cada hombre y de todo el hombre, garantizando que se respeten, de modo particular, la dignidad, los derechos humanos, el derecho a la salud, la justicia y la paz. Se ocupa de cuestiones relativas a la econom\u00eda y al trabajo, al cuidado de la creaci\u00f3n y de la tierra como \u201ccasa com\u00fan\u201d, a las migraciones y a las emergencias humanitarias. Profundiza y difunde la doctrina social de la Iglesia<\/p>\n","protected":false},"author":15,"featured_media":166187,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[132],"tags":[3836,3718,9469,108128,5598,91752,802,108127,12167,2523,16166,3135,12691,26877,158,158,158,2315,49476,726,16162,58880,272,272],"class_list":["post-166184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vaticano-es","tag-alessandra-smerilli","tag-ayuda-humanitaria","tag-casa-comun","tag-comision-covid-19","tag-curia-romana-es","tag-dentro-del-vaticano","tag-derechos-humanos","tag-dicasterio-servicio-desarrollo-humano-integral","tag-dignidad-humana","tag-doctrina-social-de-la-iglesia","tag-ecologia-integral","tag-economia-social","tag-michael-czerny-2","tag-migraciones","tag-papa-francisco","tag-refugiados","tag-salud-publica","tag-solidaridad","tag-trabajo-digno","tag-trending-es-151","tag-vaticano-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dicasterio para el Servicio del Desarrollo Humano Integral &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dicasterio para el Servicio del Desarrollo Humano Integral &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"El Dicasterio tiene la tarea de promover el desarrollo humano integral de cada hombre y de todo el hombre, garantizando que se respeten, de modo particular, la dignidad, los derechos humanos, el derecho a la salud, la justicia y la paz. Se ocupa de cuestiones relativas a la econom\u00eda y al trabajo, al cuidado de la creaci\u00f3n y de la tierra como \u201ccasa com\u00fan\u201d, a las migraciones y a las emergencias humanitarias. Profundiza y difunde la doctrina social de la Iglesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T06:00:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T09:58:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"Dicasterio para el Servicio del Desarrollo Humano Integral\",\"datePublished\":\"2026-04-17T06:00:07+00:00\",\"dateModified\":\"2026-04-21T09:58:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/\"},\"wordCount\":881,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg?fit=750%2C422&ssl=1\",\"keywords\":[\"Alessandra Smerilli\",\"Ayuda humanitaria\",\"Casa com\u00fan\",\"comisi\u00f3n covid-19\",\"curia romana\",\"Dentro del Vaticano\",\"Derechos Humanos\",\"dicasterio servicio desarrollo humano integral\",\"Dignidad humana\",\"Doctrina Social de la Iglesia\",\"ecolog\u00eda integral\",\"Econom\u00eda social\",\"MICHAEL CZERNY\",\"migraciones\",\"papa francisco\",\"papa francisco\",\"papa francisco\",\"Refugiados\",\"salud p\u00fablica\",\"solidaridad\",\"trabajo digno\",\"Trending\",\"Vaticano\",\"Vaticano\"],\"articleSection\":[\"Vaticano\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/\",\"name\":\"Dicasterio para el Servicio del Desarrollo Humano Integral &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg?fit=750%2C422&ssl=1\",\"datePublished\":\"2026-04-17T06:00:07+00:00\",\"dateModified\":\"2026-04-21T09:58:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg?fit=750%2C422&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg?fit=750%2C422&ssl=1\",\"width\":750,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dicasterio para el Servicio del Desarrollo Humano Integral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dicasterio para el Servicio del Desarrollo Humano Integral &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/","og_locale":"es_ES","og_type":"article","og_title":"Dicasterio para el Servicio del Desarrollo Humano Integral &#8211; Exaudi","og_description":"El Dicasterio tiene la tarea de promover el desarrollo humano integral de cada hombre y de todo el hombre, garantizando que se respeten, de modo particular, la dignidad, los derechos humanos, el derecho a la salud, la justicia y la paz. Se ocupa de cuestiones relativas a la econom\u00eda y al trabajo, al cuidado de la creaci\u00f3n y de la tierra como \u201ccasa com\u00fan\u201d, a las migraciones y a las emergencias humanitarias. Profundiza y difunde la doctrina social de la Iglesia","og_url":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2026-04-17T06:00:07+00:00","article_modified_time":"2026-04-21T09:58:40+00:00","og_image":[{"width":750,"height":422,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"Dicasterio para el Servicio del Desarrollo Humano Integral","datePublished":"2026-04-17T06:00:07+00:00","dateModified":"2026-04-21T09:58:40+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/"},"wordCount":881,"image":{"@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg?fit=750%2C422&ssl=1","keywords":["Alessandra Smerilli","Ayuda humanitaria","Casa com\u00fan","comisi\u00f3n covid-19","curia romana","Dentro del Vaticano","Derechos Humanos","dicasterio servicio desarrollo humano integral","Dignidad humana","Doctrina Social de la Iglesia","ecolog\u00eda integral","Econom\u00eda social","MICHAEL CZERNY","migraciones","papa francisco","papa francisco","papa francisco","Refugiados","salud p\u00fablica","solidaridad","trabajo digno","Trending","Vaticano","Vaticano"],"articleSection":["Vaticano"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/","url":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/","name":"Dicasterio para el Servicio del Desarrollo Humano Integral &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg?fit=750%2C422&ssl=1","datePublished":"2026-04-17T06:00:07+00:00","dateModified":"2026-04-21T09:58:40+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg?fit=750%2C422&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg?fit=750%2C422&ssl=1","width":750,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/el-dicasterio-para-el-servicio-del-desarrollo-humano-integral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Dicasterio para el Servicio del Desarrollo Humano Integral"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/cq5dam.thumbnail.cropped.750.422-1-3.jpeg?fit=750%2C422&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-Heo","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/166184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=166184"}],"version-history":[{"count":8,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/166184\/revisions"}],"predecessor-version":[{"id":167401,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/166184\/revisions\/167401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/166187"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=166184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=166184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=166184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}