{"id":16550,"date":"2026-05-14T07:30:19","date_gmt":"2026-05-14T05:30:19","guid":{"rendered":"https:\/\/exaudi.org\/?p=16550"},"modified":"2026-04-21T11:33:14","modified_gmt":"2026-04-21T09:33:14","slug":"san-miguel-garicoits-14-mayo","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/","title":{"rendered":"San Miguel Garico\u00efts, 14 de mayo"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">En el devenir de Miguel tuvo un peso decisivo el ejemplo de los suyos: abuelos y padres Arnaud y Gratianne. Ahora bien, el detonante de la inspirada elecci\u00f3n que hizo para su vida fue la autoridad moral de la madre, estricta con \u00e9l. Reconoci\u00f3 que sin ella pudo haberse convertido en un malvado. Es otra prueba del alcance que toda familia tiene en el acontecer de los hijos, inigualable ante cualquier otra v\u00eda formativa.\u00a0<\/span><\/p>\n<p><iframe title=\"Spotify Embed: San Miguel Garico\u00efts, 14 de mayo\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/1U9WYa7F4bgWzZPRZsAhcc?si=e48f9f556a1e4441&amp;utm_source=oembed\"><\/iframe><\/p>\n<p><span style=\"font-weight: 400;\">Naci\u00f3 en Ibarra, Bayona, regi\u00f3n fronteriza entre Francia y Espa\u00f1a, el 15 de abril de 1797. Algunos lo consideran el primer vasco canonizado. Era el mayor de seis hijos. Desafiando los rigores de la Revoluci\u00f3n francesa, sus padres, que no ten\u00edan medios econ\u00f3micos, acog\u00edan a los sacerdotes fugitivos en su casa, hasta que Arnaud pod\u00eda conducirlos en secreto a Espa\u00f1a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Miguel era robusto, de gran fuerza f\u00edsica, y un temperamento impetuoso, violento y combativo que mostraba a la primera de cambio. En medio de su rudeza perviv\u00eda un torrente de sensibilidad que, en su momento, llevado por su gran ardor m\u00edstico le har\u00eda verter muchas l\u00e1grimas. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esa \u00e9poca Gratianne le enderezaba con buenos consejos que \u00e9l siempre recordar\u00eda. Con una pedagog\u00eda clara, sencilla, plagada de ejemplos, su madre le ense\u00f1aba a discernir el bien del mal. As\u00ed aprendi\u00f3 la gravedad del pecado y se propuso conquistar el cielo porque ella le hab\u00eda dicho: \u201cEl cielo es la casa de Dios\u201d. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En su ingenuidad crey\u00f3 que subiendo a la cima de una colina con su reba\u00f1o podr\u00eda alcanzarlo. Un d\u00eda, al ver que no pod\u00eda llegar al firmamento, encamin\u00f3 sus pasos hacia otra y luego hacia una m\u00e1s alejada hasta que anocheci\u00f3 y tuvo que dormir al raso con las ovejas. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando regres\u00f3 al d\u00eda siguiente, nadie le recrimin\u00f3,\u00a0 pero ese deseo de ir al cielo lo mantuvo vivo en lo m\u00e1s hondo de su ser. En la escuela donde ingres\u00f3 en 1806, destac\u00f3 entre todos los alumnos. Dos a\u00f1os m\u00e1s tarde abandon\u00f3 los estudios para ayudar a su familia. Era pastor en Oneix en la granja propiedad de la familia Anghel\u00fa. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Siempre llevaba consigo un libro. En 1811 recibi\u00f3 la Primera Comuni\u00f3n. Una de las caracter\u00edsticas de su vida fue su amor a la Eucarist\u00eda. En 1813 comunic\u00f3 a sus padres que quer\u00eda ser sacerdote. La falta de recursos econ\u00f3micos pes\u00f3 en su juicio negativo, hasta que los convenci\u00f3 la abuela que le ense\u00f1\u00f3 a decir a Dios: \u201c\u00a1Heme aqu\u00ed!\u201d. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ella recorri\u00f3 10 km. para hablar con el p\u00e1rroco de Saint-Palais y logr\u00f3 que acogiese en su casa a Miguel y le preparase a cambio de algunas tareas. No fue f\u00e1cil para \u00e9l combinar labores dom\u00e9sticas y estudios, pero cosech\u00f3 el fruto de su tes\u00f3n. Su mal temperamento a\u00fan le proporcionaba malas pasadas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Y fue transform\u00e1ndolo a costa de esfuerzo, extrayendo lecciones ejemplares: \u201cEn el obispado, ten\u00eda que soportar a menudo el mal humor de la cocinera, y yo me vengaba limpiando alegremente las ollas y las cazuelas; ella acab\u00f3 ocupando su tiempo libre en coser mis pa\u00f1uelos y en lavarme la ropa\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Complet\u00f3 estudios eclesi\u00e1sticos en varios seminarios. Los formadores al ver su aprovechamiento le destinaron al seminario de Saint-Sulpice, donde iban los m\u00e1s destacados. Pero el obispo, temiendo perderlo, le retuvo en el seminario de Dax. Su piedad hizo que fuese comparado con san Lu\u00eds Gonzaga.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En 1821 imparti\u00f3 clases en el seminario menor de Larressore mientras segu\u00eda los estudios de teolog\u00eda. Se orden\u00f3 en 1823 y parti\u00f3 a Cambo como vicario de un anciano sacerdote que estaba paral\u00edtico. Y r\u00e1pidamente fue conocido por su caridad, la profundidad de sus sermones, la labor catequ\u00e9tica y su dedicaci\u00f3n en el confesionario, en el que tantas veces permanec\u00eda qued\u00e1ndose sin comer. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Padre celestial fue una de sus pasiones. Dec\u00eda: \u201c\u00a1Padre, aqu\u00ed estoy!\u201d. \u201cDios es Padre; hay que entregarse por completo a su amor, hay que contestarle: \u2018\u00a1Aqu\u00ed estoy!\u2019\u201d. Su fortaleza f\u00edsica le permit\u00eda realizar numerosas penitencias. Y el domingo compart\u00eda con los feligreses el juego de la pelota vasca.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Despu\u00e9s oraba ante el Sant\u00edsimo. Su lema era <\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">\u201cFiat Voluntas Dei\u201d.<\/span> <span style=\"font-weight: 400;\">El obispo de Bayona lo nombr\u00f3 profesor de filosof\u00eda y administrador del seminario mayor de la di\u00f3cesis, establecido en Betharram, junto a un santuario mariano enclavado al pie de una colina, del que fue su capell\u00e1n. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fue confesor de Isabel Bichier des Ages. Y al tratar con ella y con la fundaci\u00f3n instituida junto a san Andr\u00e9s Fournet, las Hijas de la Cruz, se sinti\u00f3 atra\u00eddo por la vida religiosa. Adem\u00e1s, como responsable del seminario hab\u00eda visto los resultados de un inadecuado enfoque anterior en su gesti\u00f3n. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entonces se dijo: \u201cformar\u00e9 sacerdotes que, por su obediencia, consolar\u00e1n el coraz\u00f3n de sus obispos\u201d. En 1832 hizo un retiro de un mes de duraci\u00f3n con los jesuitas de Toulouse, pero no parec\u00eda que fuese su lugar. El P. Le Blanc, director espiritual de la comunidad, lo tuvo claro: \u201cDios quiere que sea m\u00e1s que un jesuita; siga su primera inspiraci\u00f3n, que creo que le viene del cielo, y ser\u00e1 el padre de una familia que ser\u00e1 hermana de la nuestra&#8230;\u201d. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seis a\u00f1os m\u00e1s tarde, junto a otros cinco sacerdotes que lo eligieron como superior, contando con la aprobaci\u00f3n del obispo de Bayona, Miguel puso los pilares de los \u201cSacerdotes del Sagrado Coraz\u00f3n de Jes\u00fas de Betharram\u201d, nombre que recibieron en 1841. No fue f\u00e1cil. Surgieron graves disensiones entre los integrantes de la fundaci\u00f3n, y \u00e9l tuvo que sufrir mucho en un proceso que se alarg\u00f3 hasta el final. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un d\u00eda confi\u00f3 al prelado Lacroix: \u201c\u00a1Cu\u00e1n laborioso resulta el alumbramiento de una congregaci\u00f3n!\u201d. En 1853 perdi\u00f3 la salud que hab\u00eda disfrutado siempre al sufrir un ataque de par\u00e1lisis que se repiti\u00f3 en 1859. \u201cNo tengan miedo, dec\u00eda a los cercanos, seguiremos todo el tiempo\u00a0 que Dios permita\u201d. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se recuper\u00f3, pero en 1863 sufri\u00f3 otra crisis, que fue definitiva, y muri\u00f3 el 14 de mayo de ese a\u00f1o. En 1870 la nueva congregaci\u00f3n fundada por \u00e9l sali\u00f3 adelante con las directrices que concibi\u00f3 para ella. P\u00edo XI lo beatific\u00f3 el 10 de mayo de 1923. Y P\u00edo XII lo canoniz\u00f3 el 6 de julio de 1947 junto a Isabel Bichier des Ages.<\/span><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-100400 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=1080%2C1080&#038;ssl=1\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=770%2C770&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=500%2C500&amp;ssl=1 500w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=293%2C293&amp;ssl=1 293w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=390%2C390&amp;ssl=1 390w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=585%2C585&amp;ssl=1 585w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/05\/Santoral-2.jpg?resize=900%2C900&amp;ssl=1 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-2208\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/02\/santoral-scaled-1.jpg?resize=262%2C370&#038;ssl=1\" alt=\"santoral Isabel Orellana\" width=\"262\" height=\"370\" \/><\/p>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h6><em>\u00a9 <a href=\"https:\/\/exaudi.org\/es\/author\/isabelorellana\/\" target=\"_blank\" rel=\"noopener noreferrer\">Isabel Orellana Vilches<\/a>, 2018<\/em><br \/>\n<em>Autora vinculada a<\/em><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-41949\" src=\"https:\/\/i0.wp.com\/www.idente.org\/wp-content\/uploads\/logo-cedro-v01-843x295-1-e1603384654546.png?resize=80%2C28&#038;ssl=1\" alt=\"\" width=\"80\" height=\"28\" \/><br \/>\nObra protegida por derechos de autor.<br \/>\nInscrita en el Registro de la Propiedad Intelectual el 24 de noviembre de 2014.<br \/>\n________________<br \/>\nDerechos de edici\u00f3n reservados:<br \/>\nFundaci\u00f3n <a href=\"https:\/\/rielo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fernando Rielo<\/a><br \/>\nGoya 20, 4.\u00ba izq. int. 28001 Madrid<br \/>\nTlf.: (34) 91 575 40 91<br \/>\nCorreo electr\u00f3nico: fundacion@rielo.com<\/h6>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h6>Dep\u00f3sito legal: M-18664-2020<br \/>\nISBN: 978-84-946646-6-3<\/h6>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sacerdote y Fundador<\/p>\n","protected":false},"author":23,"featured_media":16555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2772],"tags":[2285],"class_list":["post-16550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-santoral","tag-san-miguel-garicoits"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Miguel Garico\u00efts, 14 de mayo &#8211; Exaudi<\/title>\n<meta name=\"description\" content=\"Santoral del 14 de mayo de 2021 sobre san Miguel Garico\u00efts, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Miguel Garico\u00efts, 14 de mayo &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Santoral del 14 de mayo de 2021 sobre san Miguel Garico\u00efts, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-14T05:30:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/05\/2323-e1620830998493.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Isabel Orellana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabel Orellana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/\"},\"author\":{\"name\":\"Isabel Orellana\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/64e18b96fd6118559a9217b5b3375fdc\"},\"headline\":\"San Miguel Garico\u00efts, 14 de mayo\",\"datePublished\":\"2026-05-14T05:30:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/\"},\"wordCount\":1170,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/2323-e1620830998493.jpg?fit=2500%2C1325&ssl=1\",\"keywords\":[\"San Miguel Garico\u00efts\"],\"articleSection\":[\"Santoral\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/\",\"name\":\"San Miguel Garico\u00efts, 14 de mayo &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/2323-e1620830998493.jpg?fit=2500%2C1325&ssl=1\",\"datePublished\":\"2026-05-14T05:30:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/64e18b96fd6118559a9217b5b3375fdc\"},\"description\":\"Santoral del 14 de mayo de 2021 sobre san Miguel Garico\u00efts, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/2323-e1620830998493.jpg?fit=2500%2C1325&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/2323-e1620830998493.jpg?fit=2500%2C1325&ssl=1\",\"width\":2500,\"height\":1325,\"caption\":\"San Miguel Garico\u00efts \u00a9 Congregaci\u00f3n De Betharram\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/san-miguel-garicoits-14-mayo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Miguel Garico\u00efts, 14 de mayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/64e18b96fd6118559a9217b5b3375fdc\",\"name\":\"Isabel Orellana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g\",\"caption\":\"Isabel Orellana\"},\"description\":\"Isabel Orellana Vilches Misionera idente. Doctora en Filosof\u00eda por la Universidad Aut\u00f3noma de Barcelona con la tesis Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana. Ha cursado estudios de teolog\u00eda en la Universidad Pontificia de Salamanca. Con amplia actividad docente desde 1986, ha publicado libros como: Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana, Universitat Aut\u00f2noma de Barcelona, 1993; El evangelio habla a los j\u00f3venes, Atenas, Madrid, 1997; Qu\u00e9 es... LA TOLERANCIA, Paulinas, Madrid, 1999; Pedagog\u00eda del dolor. Ensayo antropol\u00f3gico, Palabra, Madrid, 1999; En colaboraci\u00f3n con Enrique Rivera de Ventosa (\u2020) OFM. Cap. San Francisco de As\u00eds y Fernando Rielo: Convergencias. Respuestas desde la fe a los interrogantes del hombre de hoy, Universidad Pontificia, Salamanca, 2001; La \\\"mirada\\\" del cine. Recursos did\u00e1cticos del s\u00e9ptimo arte. Librer\u00eda Cervantes, Salamanca, 2001; Paradojas de la convivencia, San Pablo, Madrid, 2002; En la Universidad T\u00e9cnica Particular de Loja, Ecuador, ha publicado: La confianza. El arte de amar, 2002; Educar para la responsabilidad, 2003; Apuntes de \u00e9tica en Karl R. Popper, 2003; De soledades y comunicaci\u00f3n, 2005; Yo educo; t\u00fa respondes, 2008; Humanismo y fe en un crisol de culturas, 2008; Repensar lo cotidiano, 2008; Convivir: un constante desaf\u00edo, 2009; La l\u00f3gica del amor, 2010; El dolor del amor. Apuntes sobre la enfermedad y el dolor en relaci\u00f3n con la virtud heroica, el martirio y la vida santa. Seminario Diocesano de M\u00e1laga, 2006 y Universidad T\u00e9cnica Particular de Loja, Ecuador (2007). Cuenta con numerosas colaboraciones en obras colectivas, as\u00ed como relatos, cuentos, f\u00e1bula y novela juvenil, adem\u00e1s de art\u00edculos de tem\u00e1tica cient\u00edfica, pedag\u00f3gica y espiritual, que viene publicando en distintas revistas nacionales e internacionales. En 2012 culmin\u00f3 el santoral Llamados a ser santos y poco m\u00e1s tarde Epopeyas de amor prologado por mons. Fernando Sebasti\u00e1n. Es la bi\u00f3grafa oficial del fundador de su familia espiritual, autora de Fernando Rielo Pardal. Fundador de los Misioneros Identes, Descl\u00e9e de Brouwer, Bilbao, 2009. Culmina la biograf\u00eda completa. Encargada del santoral de ZENIT desde 2012 a 2020 y ahora en Exaudi\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/isabelorellana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Miguel Garico\u00efts, 14 de mayo &#8211; Exaudi","description":"Santoral del 14 de mayo de 2021 sobre san Miguel Garico\u00efts, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/","og_locale":"es_ES","og_type":"article","og_title":"San Miguel Garico\u00efts, 14 de mayo &#8211; Exaudi","og_description":"Santoral del 14 de mayo de 2021 sobre san Miguel Garico\u00efts, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.","og_url":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2026-05-14T05:30:19+00:00","og_image":[{"width":2500,"height":1325,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/05\/2323-e1620830998493.jpg","type":"image\/jpeg"}],"author":"Isabel Orellana","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Isabel Orellana","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/"},"author":{"name":"Isabel Orellana","@id":"https:\/\/exaudi.org\/#\/schema\/person\/64e18b96fd6118559a9217b5b3375fdc"},"headline":"San Miguel Garico\u00efts, 14 de mayo","datePublished":"2026-05-14T05:30:19+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/"},"wordCount":1170,"image":{"@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/2323-e1620830998493.jpg?fit=2500%2C1325&ssl=1","keywords":["San Miguel Garico\u00efts"],"articleSection":["Santoral"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/","url":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/","name":"San Miguel Garico\u00efts, 14 de mayo &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/2323-e1620830998493.jpg?fit=2500%2C1325&ssl=1","datePublished":"2026-05-14T05:30:19+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/64e18b96fd6118559a9217b5b3375fdc"},"description":"Santoral del 14 de mayo de 2021 sobre san Miguel Garico\u00efts, por Isabel Orellana Vilches y Fundaci\u00f3n Fernando Rielo.","breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/2323-e1620830998493.jpg?fit=2500%2C1325&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/2323-e1620830998493.jpg?fit=2500%2C1325&ssl=1","width":2500,"height":1325,"caption":"San Miguel Garico\u00efts \u00a9 Congregaci\u00f3n De Betharram"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/san-miguel-garicoits-14-mayo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"San Miguel Garico\u00efts, 14 de mayo"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/64e18b96fd6118559a9217b5b3375fdc","name":"Isabel Orellana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g","caption":"Isabel Orellana"},"description":"Isabel Orellana Vilches Misionera idente. Doctora en Filosof\u00eda por la Universidad Aut\u00f3noma de Barcelona con la tesis Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana. Ha cursado estudios de teolog\u00eda en la Universidad Pontificia de Salamanca. Con amplia actividad docente desde 1986, ha publicado libros como: Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana, Universitat Aut\u00f2noma de Barcelona, 1993; El evangelio habla a los j\u00f3venes, Atenas, Madrid, 1997; Qu\u00e9 es... LA TOLERANCIA, Paulinas, Madrid, 1999; Pedagog\u00eda del dolor. Ensayo antropol\u00f3gico, Palabra, Madrid, 1999; En colaboraci\u00f3n con Enrique Rivera de Ventosa (\u2020) OFM. Cap. San Francisco de As\u00eds y Fernando Rielo: Convergencias. Respuestas desde la fe a los interrogantes del hombre de hoy, Universidad Pontificia, Salamanca, 2001; La \"mirada\" del cine. Recursos did\u00e1cticos del s\u00e9ptimo arte. Librer\u00eda Cervantes, Salamanca, 2001; Paradojas de la convivencia, San Pablo, Madrid, 2002; En la Universidad T\u00e9cnica Particular de Loja, Ecuador, ha publicado: La confianza. El arte de amar, 2002; Educar para la responsabilidad, 2003; Apuntes de \u00e9tica en Karl R. Popper, 2003; De soledades y comunicaci\u00f3n, 2005; Yo educo; t\u00fa respondes, 2008; Humanismo y fe en un crisol de culturas, 2008; Repensar lo cotidiano, 2008; Convivir: un constante desaf\u00edo, 2009; La l\u00f3gica del amor, 2010; El dolor del amor. Apuntes sobre la enfermedad y el dolor en relaci\u00f3n con la virtud heroica, el martirio y la vida santa. Seminario Diocesano de M\u00e1laga, 2006 y Universidad T\u00e9cnica Particular de Loja, Ecuador (2007). Cuenta con numerosas colaboraciones en obras colectivas, as\u00ed como relatos, cuentos, f\u00e1bula y novela juvenil, adem\u00e1s de art\u00edculos de tem\u00e1tica cient\u00edfica, pedag\u00f3gica y espiritual, que viene publicando en distintas revistas nacionales e internacionales. En 2012 culmin\u00f3 el santoral Llamados a ser santos y poco m\u00e1s tarde Epopeyas de amor prologado por mons. Fernando Sebasti\u00e1n. Es la bi\u00f3grafa oficial del fundador de su familia espiritual, autora de Fernando Rielo Pardal. Fundador de los Misioneros Identes, Descl\u00e9e de Brouwer, Bilbao, 2009. Culmina la biograf\u00eda completa. Encargada del santoral de ZENIT desde 2012 a 2020 y ahora en Exaudi","url":"https:\/\/exaudi.org\/es\/author\/isabelorellana\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/05\/2323-e1620830998493.jpg?fit=2500%2C1325&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-4iW","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/16550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=16550"}],"version-history":[{"count":1,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/16550\/revisions"}],"predecessor-version":[{"id":167358,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/16550\/revisions\/167358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/16555"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=16550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=16550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=16550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}