{"id":148743,"date":"2025-12-02T09:39:43","date_gmt":"2025-12-02T08:39:43","guid":{"rendered":"https:\/\/exaudi.org\/?p=148743"},"modified":"2025-12-03T09:22:49","modified_gmt":"2025-12-03T08:22:49","slug":"leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/","title":{"rendered":"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento"},"content":{"rendered":"<p>En un emotivo cierre de su primer viaje apost\u00f3lico al extranjero, que incluy\u00f3 etapas en Turqu\u00eda y L\u00edbano, el Papa Le\u00f3n XIV inici\u00f3 este martes su tercera y \u00faltima jornada en Beirut con una visita al Hospital de la Cruz, en Jal Ed Dib. Este centro, uno de los m\u00e1s grandes del Medio Oriente para personas con discapacidades mentales, se convirti\u00f3 en el escenario de un mensaje profundo de compasi\u00f3n y solidaridad. Fundado en 1919 por el beato Padre Jacques Haddad \u2013conocido como Padre Yaacoub, un incansable ap\u00f3stol de la caridad\u2013, el hospital fue transformado en 1951 en un refugio para los m\u00e1s fr\u00e1giles, y hoy atiende a cientos de pacientes a trav\u00e9s de sus cinco grandes pabellones.<\/p>\n<p>La llegada del Pont\u00edfice fue recibida con una mezcla de emoci\u00f3n y cari\u00f1o por pacientes, m\u00e9dicos, religiosas franciscanas de la Cruz y personal sanitario. Multitudes se alinearon en las calles para saludarlo, en un gesto que subraya el impacto de su presencia en una naci\u00f3n marcada por conflictos, pobreza y vulnerabilidad. Le\u00f3n XIV, visiblemente conmovido, expres\u00f3 su alegr\u00eda por estar all\u00ed: \u201cQuer\u00eda venir porque Jes\u00fas habita en este lugar: en vosotros que est\u00e1is enfermos, y en vosotros que cuid\u00e1is a los enfermos \u2013las hermanas, los m\u00e9dicos, todos los trabajadores sanitarios y el personal\u201d. Asegur\u00f3 a todos que est\u00e1n en sus oraciones y agradeci\u00f3 el himno de esperanza interpretado por un coro local, un detalle que simboliz\u00f3 el esp\u00edritu de la visita.<\/p>\n<p>El Papa dedic\u00f3 palabras especiales al legado del beato Padre Jacques, recordando su santidad manifestada en el amor por los pobres y sufrientes. \u201cEs recordado por la santidad de vida que mostr\u00f3 especialmente a trav\u00e9s de su amor por los m\u00e1s pobres y los que sufren\u201d, afirm\u00f3. Las Hermanas Franciscanas de la Cruz, que contin\u00faan su obra con dedicaci\u00f3n y alegr\u00eda, fueron elogiadas como un \u201csigno tangible del amor misericordioso de Cristo\u201d. Le\u00f3n XIV las compar\u00f3 con el Buen Samaritano del Evangelio, que se detiene ante el herido para levantarlo y sanarlo, y reconoci\u00f3 los desaf\u00edos que enfrentan: el cansancio, el des\u00e1nimo y las condiciones adversas en un contexto regional tan inestable.<\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-148748 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281.jpeg?resize=500%2C281&#038;ssl=1\" alt=\"\" width=\"500\" height=\"281\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281.jpeg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281.jpeg?resize=300%2C169&amp;ssl=1 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>\u201cA veces puede sobrevenir el cansancio o el des\u00e1nimo, sobre todo por las condiciones no siempre favorables en las que trabajan. Los animo a no perder la alegr\u00eda de esta misi\u00f3n y, a pesar de algunas dificultades, los invito a tener siempre presente el bien que pueden realizar. Es una gran obra a los ojos de Dios\u201d, exhort\u00f3 el Santo Padre. Entre los regalos recibidos, destac\u00f3 una imagen del fundador, que simboliza la continuidad de esa misi\u00f3n humanitaria en un hospital que, desde su conversi\u00f3n en 1937 de centro psiqui\u00e1trico a hogar para discapacitados mentales, ha sido faro de esperanza.<\/p>\n<p>Pero el mensaje de Le\u00f3n XIV trascendi\u00f3 las paredes del hospital. Dirigi\u00e9ndose a la sociedad libanesa y al mundo entero, el Papa lanz\u00f3 un llamado urgente a no ignorar a los m\u00e1s fr\u00e1giles. \u201cNo podemos olvidar a los m\u00e1s vulnerables. No podemos avanzar como sociedad aferr\u00e1ndonos a falsos mitos de bienestar mientras ignoramos la realidad de la pobreza y la fragilidad\u201d, advirti\u00f3. En particular, inst\u00f3 a los cristianos \u2013como Iglesia de Jes\u00fas\u2013 a cuidar de los pobres, recordando que \u201cel Evangelio mismo nos lo pide y nos interpela el grito de los pobres, que atraviesa tambi\u00e9n la Escritura\u201d. Cit\u00f3 su propia exhortaci\u00f3n apost\u00f3lica *Dilexi te* (9): \u201cEn el rostro herido de los pobres encontramos impreso el sufrimiento de los inocentes y, por tanto, el mismo sufrimiento de Cristo\u201d.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-148751 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-2.jpeg?resize=500%2C281&#038;ssl=1\" alt=\"\" width=\"500\" height=\"281\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-2.jpeg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-2.jpeg?resize=300%2C169&amp;ssl=1 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>El cl\u00edmax emocional lleg\u00f3 en su saludo directo a los enfermos: \u201cDios os tiene en la palma de su mano; os acompa\u00f1a con amor y os ofrece su ternura a trav\u00e9s de las manos y las sonrisas de quienes os cuidan\u201d. Con voz cargada de afecto, concluy\u00f3: \u201c\u00a1Te amo, eres mi hijo! \u00a1Nunca lo olvides!\u201d. La visita, que dur\u00f3 cerca de una hora, incluy\u00f3 momentos de bendici\u00f3n y oraci\u00f3n, dejando un eco de esperanza en un L\u00edbano que lucha por reconstruirse tras a\u00f1os de crisis.<\/p>\n<p><iframe title=\"Viaje Apost\u00f3lico . 02 de diciembre de 2025\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/kBSynk1cCpM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Papa visita el Hospital de la Cruz y llama a no olvidar a los m\u00e1s vulnerables<\/p>\n","protected":false},"author":15,"featured_media":148745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[68,120],"tags":[83982,3587,83985,76265,83979,83989,83987,83983,83980,62565,58067,408,83984,49125,83981,83978,58111,58880,83986,83147,83977],"class_list":["post-148743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leon-xiv","category-viajes","tag-beato-yaacoub","tag-beirut-es","tag-cuidado-vulnerables","tag-dilexi-te","tag-discapacidad-mental","tag-esperanza-cristianos-libano","tag-evangelio-y-fragilidad","tag-hermanas-franciscanas-de-la-cruz","tag-hospital-jal-ed-dib","tag-iglesia-y-pobres","tag-leon-xiv","tag-libano","tag-mensaje-compasion","tag-misericordia-papal","tag-padre-jacques-haddad","tag-papa-en-libano-2025","tag-papa-leon-xiv","tag-trending-es-151","tag-viaje-apostolico-leon-xiv","tag-viaje-apostolico-turquia-y-libano","tag-visita-hospital-de-la-cruz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"El Papa visita el Hospital de la Cruz y llama a no olvidar a los m\u00e1s vulnerables\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-02T08:39:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T08:22:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento\",\"datePublished\":\"2025-12-02T08:39:43+00:00\",\"dateModified\":\"2025-12-03T08:22:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/\"},\"wordCount\":733,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cq5dam.thumbnail.cropped.500.281-4.jpeg?fit=500%2C281&ssl=1\",\"keywords\":[\"beato Yaacoub\",\"beirut\",\"cuidado vulnerables\",\"Dilexi te\",\"discapacidad mental\",\"esperanza cristianos L\u00edbano\",\"Evangelio y fragilidad\",\"Hermanas Franciscanas de la Cruz\",\"Hospital Jal Ed Dib\",\"Iglesia y pobres\",\"Le\u00f3n XIV\",\"L\u00edbano\",\"mensaje compasi\u00f3n\",\"misericordia papal\",\"Padre Jacques Haddad\",\"Papa en L\u00edbano 2025\",\"papa le\u00f3n xiv\",\"Trending\",\"viaje apost\u00f3lico Le\u00f3n XIV\",\"Viaje Apost\u00f3lico Turqu\u00eda y L\u00edbano\",\"visita Hospital de la Cruz\"],\"articleSection\":[\"Le\u00f3n XIV\",\"Viajes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/\",\"name\":\"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cq5dam.thumbnail.cropped.500.281-4.jpeg?fit=500%2C281&ssl=1\",\"datePublished\":\"2025-12-02T08:39:43+00:00\",\"dateModified\":\"2025-12-03T08:22:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cq5dam.thumbnail.cropped.500.281-4.jpeg?fit=500%2C281&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cq5dam.thumbnail.cropped.500.281-4.jpeg?fit=500%2C281&ssl=1\",\"width\":500,\"height\":281},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento &#8211; Exaudi","og_description":"El Papa visita el Hospital de la Cruz y llama a no olvidar a los m\u00e1s vulnerables","og_url":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2025-12-02T08:39:43+00:00","article_modified_time":"2025-12-03T08:22:49+00:00","og_image":[{"width":500,"height":281,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-4.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento","datePublished":"2025-12-02T08:39:43+00:00","dateModified":"2025-12-03T08:22:49+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/"},"wordCount":733,"image":{"@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-4.jpeg?fit=500%2C281&ssl=1","keywords":["beato Yaacoub","beirut","cuidado vulnerables","Dilexi te","discapacidad mental","esperanza cristianos L\u00edbano","Evangelio y fragilidad","Hermanas Franciscanas de la Cruz","Hospital Jal Ed Dib","Iglesia y pobres","Le\u00f3n XIV","L\u00edbano","mensaje compasi\u00f3n","misericordia papal","Padre Jacques Haddad","Papa en L\u00edbano 2025","papa le\u00f3n xiv","Trending","viaje apost\u00f3lico Le\u00f3n XIV","Viaje Apost\u00f3lico Turqu\u00eda y L\u00edbano","visita Hospital de la Cruz"],"articleSection":["Le\u00f3n XIV","Viajes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/","url":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/","name":"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-4.jpeg?fit=500%2C281&ssl=1","datePublished":"2025-12-02T08:39:43+00:00","dateModified":"2025-12-03T08:22:49+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-4.jpeg?fit=500%2C281&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-4.jpeg?fit=500%2C281&ssl=1","width":500,"height":281},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/leon-xiv-en-beirut-un-gesto-de-esperanza-en-medio-del-sufrimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Le\u00f3n XIV en Beirut: Un Gesto de Esperanza en Medio del Sufrimiento"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-CH5","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/12\/cq5dam.thumbnail.cropped.500.281-4.jpeg?fit=500%2C281&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/148743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=148743"}],"version-history":[{"count":4,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/148743\/revisions"}],"predecessor-version":[{"id":148939,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/148743\/revisions\/148939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/148745"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=148743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=148743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=148743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}